﻿


{"id":196953,"date":"2022-02-13T07:30:03","date_gmt":"2022-02-13T06:30:03","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=196953"},"modified":"2022-02-11T15:17:17","modified_gmt":"2022-02-11T14:17:17","slug":"fame-di-mamma-un-autoritratto-fotografico-per-scoprire-che-esiste-un-futuro-nonostante-tutto","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-un-autoritratto-fotografico-per-scoprire-che-esiste-un-futuro-nonostante-tutto\/","title":{"rendered":"Fame di mamma. Un autoritratto fotografico per scoprire che esiste un futuro, nonostante tutto"},"content":{"rendered":"<h2><strong>Il lavoro di accoglienza nelle comunit\u00e0 mamma-bambino di AIBC, si concretizza in aspetti molteplici e, a volte, totalmente innovativi: ecco il significato di un&#8217; &#8220;esperienza fotografica&#8221; vissuta dalla nostre mamme.<\/strong><\/h2>\n<p style=\"font-weight: 400;\"><em>Conosci te stesso\u201d (\u201cGn\u014dthi seaut\u00f3n\u201d)\u00a0<\/em><\/p>\n<p style=\"font-weight: 400;\">Questa \u00e8 la scritta che campeggiava sul tempio del Dio Apollo a Delfi e che per secoli ha influenzato i pi\u00f9 importanti pensatori della cultura occidentale: da Socrate a Platone, da Kant a Nietzsche.\u00a0<strong>Quante volte guardandoci allo specchio ci chiediamo: io chi sono veramente?<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong>Questo fine settimana in una delle nostre comunit\u00e0 per il supporto e il sostegno alle famiglie fragili, \u00e8 stato offerto un\u00a0<strong>servizio fotografico \u2018speciale\u2019 alle nostre mamme e ai loro bambini\u00a0<\/strong>grazie ad un progetto curato dalla fotografa\u00a0<strong>Eleonora Rettori<\/strong>.<\/p>\n<p style=\"font-weight: 400;\">Eleonora, come facilitatrice SPEX (Self Portrait EXperience), ha voluto far provare alle nostre mamme e ai loro bambini questa esperienza fotografica, intensa soprattutto per gli\u00a0<strong>aspetti emotivi e narrativi di s\u00e9 che ogni scatto ha ritratto.<\/strong><\/p>\n<p style=\"font-weight: 400;\">Un\u2019esperienza che ha permesso alle donne e ai bambini di vedersi e parlare di s\u00e9 come ne parlerebbe una terza persona.<\/p>\n<h3 style=\"font-weight: 400;\"><strong>Un\u00a0set\u00a0fotografico diverso dal solito\u2026<\/strong><\/h3>\n<p style=\"font-weight: 400;\">Il setting fotografico, infatti, era un po\u2019 diverso dal solito, in quanto\u00a0<strong>a scattare non \u00e8 stata Eleonora ma le mamme e in alcuni casi anche i loro bambini.\u00a0<\/strong>Eleonora ha preparato il setting e ha spiegato alle mamme il senso e la modalit\u00e0 in cui si sarebbe svolto questo momento non solo\u00a0<strong>ludico ma anche molto introspettivo<\/strong>.<\/p>\n<p style=\"font-weight: 400;\">Ogni mamma avrebbe usato il telecomando collegato alla camera per scattarsi delle foto,\u00a0<strong>come se si guardassero con altri occhi<\/strong>, in terza persona.<\/p>\n<p style=\"font-weight: 400;\">Ogni scatto o opera, perch\u00e9 questo sono stati gli scatti realizzati insieme ad ogni nucleo, mostrava un\u2019emozione o un aspetto di s\u00e9. \u00a0Successivamente con ogni mamma e con ogni bambino protagonista di questi momenti, la fotografa ha avuto un momento individuale ed intimo di confronto per\u00a0<strong>scegliere l\u2019immagine pi\u00f9 perturbante<\/strong>, quella che piaceva di meno.<\/p>\n<p style=\"font-weight: 400;\">Ci si \u00e8 preso del tempo per capire cosa piacesse e cosa piacesse di meno, e si \u00e8 parlato delle persone ritratte come se non fossero loro. Si sono osservati i volti, le loro emozioni e le loro sensazioni, partendo dal lato sinistro del volto (la\u00a0pi\u00f9 emotiva e vulnerabile) e poi successivamente la destra (quella della creativit\u00e0, degli obbiettivi).<\/p>\n<h3 style=\"font-weight: 400;\"><strong>Tutte le mamme e i loro bambini si sono lasciati coinvolgere\u2026<\/strong><\/h3>\n<p style=\"font-weight: 400;\">Tutte le mamme e i loro minori si sono lasciati coinvolgere e si sono messi in gioco, raccontando parti di se stesse che\u00a0<strong>spesso fanno fatica a riconoscere quando si guardano semplicemente allo specchio<\/strong>\u00a0o in una foto.<\/p>\n<p style=\"font-weight: 400;\">Hanno parlato di giudizi che ancora sentono verso se stesse, o di difficolt\u00e0 a sentirsi forti abbastanza. Hanno anche intercettato la loro parte combattiva, quella che le porta tutti i giorni ad aprirsi a nuove possibilit\u00e0 per se stesse e per i loro figli, a darsi una possibilit\u00e0 per farsi conoscere e per fidarsi e affidarsi (loro che spesso sono state tradite da chi doveva proteggerle).<\/p>\n<p style=\"font-weight: 400;\"><strong>Anche i bimbi pi\u00f9 grandicelli hanno voluto sperimentarsi nello scatto<\/strong>. Si sono presi quello spazio per essere visti, per sentirsi ascoltati, cosa che non sempre hanno trovato negli adulti che avevano accanto.<\/p>\n<p style=\"font-weight: 400;\"><strong>L\u2019esperienza \u00e8 stata molto intensa anche per Eleonora<\/strong>, che si \u00e8 resa disponibile non solo per fare degli scatti professionali per le prossime ricorrenze natalizie ai nostri bambini e alle loro mamme e per i loro familiari, ma anche per dare un seguito a questo percorso di scoperta e narrazione di s\u00e9, che, come diceva Socrate, dobbiamo continuare per tutta la nostra vita.<\/p>\n<h3 style=\"font-weight: 400;\"><strong>Fame di mamma. Adotta anche tu una famiglia in Italia!<\/strong><\/h3>\n<p style=\"font-weight: 400;\">\u00a0Per aiutare le mamme rese fragili da vicende, condizioni e situazioni, che hanno incontrato e vissuto nel corso della propria vita, a costruire un rapporto pi\u00f9 saldo con il proprio bambino, Ai.Bi. in Italia ha dato vita a\u00a0<strong>Fame di Mamma<\/strong>, Campagna di Ai.Bi. e della Cooperativa AIBC per dire basta all\u2019abbandono.<\/p>\n<p style=\"font-weight: 400;\">I figli per crescere non hanno bisogno solo di nutrimento fisico, ma anche interiore ed affettivo.<\/p>\n<p style=\"font-weight: 400;\">Aderendo alla\u00a0<strong>Campagna Fame di Mamma<\/strong>, con una donazione di\u00a0<strong>10 euro<\/strong>\u00a0al mese, potrai adottare una famiglia\u00a0<strong>in Italia<\/strong>, contribuendo a sostenere\u00a0<strong>le comunit\u00e0 e gli<\/strong>\u00a0<strong>alloggi mamma \u2013 bambino di Ai.Bi.<\/strong>\u00a0(per vedere di cosa si tratta\u00a0<strong><a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/sostegno-a-distanza-in-italia\/\">QUI<\/a><\/strong>).<\/p>\n<p style=\"font-weight: 400;\">\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/dona.aibi.it\/adozione-a-distanza\/\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn btnsx-btn-embossed\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Adotta una Famiglia in Italia<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n","protected":false},"excerpt":{"rendered":"<p>Il lavoro di accoglienza nelle comunit&agrave; mamma-bambino di AIBC, si concretizza in aspetti molteplici e, a volte, totalmente innovativi: ecco il significato di un&rsquo; &ldquo;esperienza fotografica&rdquo; vissuta dalla nostre mamme. Conosci te stesso&rdquo; (&ldquo;Gn&#333;thi seaut&oacute;n&rdquo;)&nbsp; Questa &egrave; la scritta che campeggiava sul tempio del Dio Apollo a Delfi e che [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":196954,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[764],"tags":[608],"class_list":["post-196953","post","type-post","status-publish","format-standard","has-post-thumbnail","category-progetti-in-italia","tag-fame-di-mamma"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fame di mamma. Un autoritratto fotografico per scoprire che esiste un futuro, nonostante tutto - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Il lavoro di accoglienza nelle comunit\u00e0 mamma-bambino di AIBC, si concretizza in aspetti molteplici e, a volte, totalmente innovativi: ecco il significato di un&#039; &quot;esperienza fotografica&quot; vissuta dalla nostre mamme.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/fame-di-mamma-un-autoritratto-fotografico-per-scoprire-che-esiste-un-futuro-nonostante-tutto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fame di mamma. Un autoritratto fotografico per scoprire che esiste un futuro, nonostante tutto\" \/>\n<meta property=\"og:description\" content=\"Il lavoro di accoglienza nelle comunit\u00e0 mamma-bambino di AIBC, si concretizza in aspetti molteplici e, a volte, totalmente innovativi: ecco il significato di un&#039; &quot;esperienza fotografica&quot; vissuta dalla nostre mamme.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/fame-di-mamma-un-autoritratto-fotografico-per-scoprire-che-esiste-un-futuro-nonostante-tutto\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-13T06:30:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/fame-di-mamma.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-un-autoritratto-fotografico-per-scoprire-che-esiste-un-futuro-nonostante-tutto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-un-autoritratto-fotografico-per-scoprire-che-esiste-un-futuro-nonostante-tutto\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"Fame di mamma. Un autoritratto fotografico per scoprire che esiste un futuro, nonostante tutto\",\"datePublished\":\"2022-02-13T06:30:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-un-autoritratto-fotografico-per-scoprire-che-esiste-un-futuro-nonostante-tutto\\\/\"},\"wordCount\":741,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-un-autoritratto-fotografico-per-scoprire-che-esiste-un-futuro-nonostante-tutto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/02\\\/fame-di-mamma.jpg\",\"keywords\":[\"Fame di mamma\"],\"articleSection\":[\"Progetti in Italia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-un-autoritratto-fotografico-per-scoprire-che-esiste-un-futuro-nonostante-tutto\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-un-autoritratto-fotografico-per-scoprire-che-esiste-un-futuro-nonostante-tutto\\\/\",\"name\":\"Fame di mamma. Un autoritratto fotografico per scoprire che esiste un futuro, nonostante tutto - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-un-autoritratto-fotografico-per-scoprire-che-esiste-un-futuro-nonostante-tutto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-un-autoritratto-fotografico-per-scoprire-che-esiste-un-futuro-nonostante-tutto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/02\\\/fame-di-mamma.jpg\",\"datePublished\":\"2022-02-13T06:30:03+00:00\",\"description\":\"Il lavoro di accoglienza nelle comunit\u00e0 mamma-bambino di AIBC, si concretizza in aspetti molteplici e, a volte, totalmente innovativi: ecco il significato di un' \\\"esperienza fotografica\\\" vissuta dalla nostre mamme.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-un-autoritratto-fotografico-per-scoprire-che-esiste-un-futuro-nonostante-tutto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-un-autoritratto-fotografico-per-scoprire-che-esiste-un-futuro-nonostante-tutto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-un-autoritratto-fotografico-per-scoprire-che-esiste-un-futuro-nonostante-tutto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/02\\\/fame-di-mamma.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/02\\\/fame-di-mamma.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-un-autoritratto-fotografico-per-scoprire-che-esiste-un-futuro-nonostante-tutto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti in Italia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/progetti-in-italia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fame di mamma. Un autoritratto fotografico per scoprire che esiste un futuro, nonostante tutto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fame di mamma. Un autoritratto fotografico per scoprire che esiste un futuro, nonostante tutto - Ai.Bi. Amici dei Bambini","description":"Il lavoro di accoglienza nelle comunit\u00e0 mamma-bambino di AIBC, si concretizza in aspetti molteplici e, a volte, totalmente innovativi: ecco il significato di un' \"esperienza fotografica\" vissuta dalla nostre mamme.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-un-autoritratto-fotografico-per-scoprire-che-esiste-un-futuro-nonostante-tutto\/","og_locale":"it_IT","og_type":"article","og_title":"Fame di mamma. Un autoritratto fotografico per scoprire che esiste un futuro, nonostante tutto","og_description":"Il lavoro di accoglienza nelle comunit\u00e0 mamma-bambino di AIBC, si concretizza in aspetti molteplici e, a volte, totalmente innovativi: ecco il significato di un' \"esperienza fotografica\" vissuta dalla nostre mamme.","og_url":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-un-autoritratto-fotografico-per-scoprire-che-esiste-un-futuro-nonostante-tutto\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2022-02-13T06:30:03+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/fame-di-mamma.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-un-autoritratto-fotografico-per-scoprire-che-esiste-un-futuro-nonostante-tutto\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-un-autoritratto-fotografico-per-scoprire-che-esiste-un-futuro-nonostante-tutto\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"Fame di mamma. Un autoritratto fotografico per scoprire che esiste un futuro, nonostante tutto","datePublished":"2022-02-13T06:30:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-un-autoritratto-fotografico-per-scoprire-che-esiste-un-futuro-nonostante-tutto\/"},"wordCount":741,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-un-autoritratto-fotografico-per-scoprire-che-esiste-un-futuro-nonostante-tutto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/fame-di-mamma.jpg","keywords":["Fame di mamma"],"articleSection":["Progetti in Italia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-un-autoritratto-fotografico-per-scoprire-che-esiste-un-futuro-nonostante-tutto\/","url":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-un-autoritratto-fotografico-per-scoprire-che-esiste-un-futuro-nonostante-tutto\/","name":"Fame di mamma. Un autoritratto fotografico per scoprire che esiste un futuro, nonostante tutto - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-un-autoritratto-fotografico-per-scoprire-che-esiste-un-futuro-nonostante-tutto\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-un-autoritratto-fotografico-per-scoprire-che-esiste-un-futuro-nonostante-tutto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/fame-di-mamma.jpg","datePublished":"2022-02-13T06:30:03+00:00","description":"Il lavoro di accoglienza nelle comunit\u00e0 mamma-bambino di AIBC, si concretizza in aspetti molteplici e, a volte, totalmente innovativi: ecco il significato di un' \"esperienza fotografica\" vissuta dalla nostre mamme.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-un-autoritratto-fotografico-per-scoprire-che-esiste-un-futuro-nonostante-tutto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/fame-di-mamma-un-autoritratto-fotografico-per-scoprire-che-esiste-un-futuro-nonostante-tutto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-un-autoritratto-fotografico-per-scoprire-che-esiste-un-futuro-nonostante-tutto\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/fame-di-mamma.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/fame-di-mamma.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-un-autoritratto-fotografico-per-scoprire-che-esiste-un-futuro-nonostante-tutto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Progetti in Italia","item":"https:\/\/www.aibi.it\/ita\/category\/progetti-in-italia\/"},{"@type":"ListItem","position":3,"name":"Fame di mamma. Un autoritratto fotografico per scoprire che esiste un futuro, nonostante tutto"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 12:58:37","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/196953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=196953"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/196953\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/196954"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=196953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=196953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=196953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}