﻿


{"id":196973,"date":"2022-02-11T19:42:56","date_gmt":"2022-02-11T18:42:56","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=196973"},"modified":"2022-07-25T10:17:48","modified_gmt":"2022-07-25T08:17:48","slug":"bolivia-alfonso-storie-di-ordinario-abbandono-e-di-rinascita","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/bolivia-alfonso-storie-di-ordinario-abbandono-e-di-rinascita\/","title":{"rendered":"Bolivia. Alfonso: storie di \u201cordinario\u201d abbandono e di rinascita\u2026"},"content":{"rendered":"<h2 style=\"font-weight: 400;\"><strong>Alfonso presto torner\u00e0 a casa insieme ai suoi genitori, nel frattempo noi di Ai.Bi., grazie all\u2019Adozione a Distanza ci prendiamo cura di lui e di tutti i bimbi del\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/?scelta=25&amp;progetto=Bolivia\">Gota de Leche.<\/a><\/strong><\/h2>\n<p style=\"font-weight: 400;\"><strong>Alfonso \u00e8 un piccolino di 8 mesi<\/strong>. \u00c8 stato soccorso il\u00a030 novembre 2021, a seguito di una denuncia, che segnalava all\u2019autorit\u00e0 la presenza di persone che bevevano\u00a0<strong>alcolici per strada<\/strong>. Con loro vi era Alfonso, che piangeva disperato. Il bambino era totalmente trascurato,\u00a0<strong>senza vestiti e sporco<\/strong>.\u00a0Per questo motivo, il piccolo, \u00e8 stato accolto\u00a0all\u2019orfanotrofio &#8220;Gota de Leche&#8221;, partner di Ai.Bi. in Bolivia.<\/p>\n<p style=\"font-weight: 400;\">I genitori, rattristati per quanto accaduto, hanno promesso che non consumeranno pi\u00f9 bevande alcoliche e\u00a0il 1\u00b0 dicembre, la mamma ha fatto richiesta al SEDEGES e al Tribunale per l&#8217;infanzia e l&#8217;adolescenza, di poter\u00a0<strong>alimentare con il latte materno il suo bambino<\/strong>. Cos\u00ec dal\u00a03 dicembre 2021, la mamma del piccolo, due volte al giorno si reca all\u2019orfanotrofio Gota de Leche, per allattare Alfonso e rafforzare, allo stesso tempo, il\u00a0legame affettivo con il piccolo.<\/p>\n<p style=\"font-weight: 400;\"><strong>Alfonso si sente felice quando vede sua madre<\/strong>, comincia a sorridere e a fare rumori. Presto torneranno a casa insieme. I genitori vogliono l&#8217;affidamento del loro bambino. Hanno chiesto l&#8217;autorizzazione al Tribunale per l&#8217;infanzia e l&#8217;adolescenza ai fini del\u00a0<strong>reinserimento familiare<\/strong>. Si sono impegnati ad assumersi le proprie responsabilit\u00e0 e a rispettare tutte le raccomandazioni date per il benessere del piccolo.<\/p>\n<h3 style=\"font-weight: 400;\"><strong><a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/\">Un\u2019Adozione a Distanza<\/a>\u00a0per i piccoli ospiti di Gota de Leche!<\/strong><\/h3>\n<p style=\"font-weight: 400;\">L\u2019orfanotrofio Gota de Leche \u00e8 posizionato nel centro della cittadina di\u00a0<strong>Oruro<\/strong>, una delle localit\u00e0 pi\u00f9 piccole della Bolivia.<\/p>\n<p style=\"font-weight: 400;\">L\u2019orfanotrofio \u00e8 molto grande e per le sue dimensioni potrebbe ospitare fino a 90 bambini, ma per fornire un\u2019attenzione personalizzata \u00e8 stato concordato di\u00a0<strong>non accoglierne oltre 35, nella fascia di et\u00e0 da zero a sei anni,\u00a0<\/strong>ma c\u2019\u00e8 anche qualche bambino pi\u00f9 grandicello,\u00a0<strong>si tratta di fratelli maggiori,<\/strong>\u00a0che continuano a stare qui per non separarli dai fratellini pi\u00f9 piccoli.<\/p>\n<p style=\"font-weight: 400;\">I piccoli ospiti della struttura, proprio come Alfonso, arrivano da storie difficili: abbandono, maltrattamento, smarrimento.<\/p>\n<p style=\"font-weight: 400;\">Noi di Ai.Bi., grazie al prezioso sostegno\u00a0<strong>dell\u2019Adozione a Distanza,<\/strong>\u00a0ci impegniamo ogni giorno per garantire a questi bambini un\u2019infanzia serena, fino a quando, speriamo il pi\u00f9 presto possibile, non torneranno a crescere nella loro famiglia o avranno l&#8217;opportunit\u00e0 di rinascere nuovamente figli, ma, per farlo al meglio abbiamo bisogno anche del tuo aiuto.<\/p>\n<p style=\"font-weight: 400;\">Attiva\u00a0<strong>un\u2019Adozione a Distanza per i bambini dell\u2019orfanotrofio Gota de Leche!<\/strong>\u00a0<strong>Bastano 25 euro al mese<\/strong>, meno di un caff\u00e8 al giorno.<\/p>\n<p style=\"font-weight: 400;\">\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/dona.aibi.it\/adozione-a-distanza\/\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn btnsx-btn-embossed\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Adotta a Distanza ORA<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n<p style=\"font-weight: 400;\"><strong> \n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn btnsx-btn-embossed\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Scopri di pi\u00f9<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alfonso presto torner&agrave; a casa insieme ai suoi genitori, nel frattempo noi di Ai.Bi., grazie all&rsquo;Adozione a Distanza ci prendiamo cura di lui e di tutti i bimbi del&nbsp;Gota de Leche. Alfonso &egrave; un piccolino di 8 mesi. &Egrave; stato soccorso il&nbsp;30 novembre 2021, a seguito di una denuncia, che [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":196974,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209],"tags":[882],"class_list":["post-196973","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-a-distanza","tag-gota-de-leche"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bolivia. Alfonso: storie di \u201cordinario\u201d abbandono e di rinascita\u2026 - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Bolivia. Alfonso presto torner\u00e0 a casa insieme ai suoi genitori, nel frattempo noi di Ai.Bi., grazie all\u2019Adozione a Distanza ci prendiamo cura di lui e di tutti i bimbi del\u00a0Gota de Leche.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/bolivia-alfonso-storie-di-ordinario-abbandono-e-di-rinascita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bolivia. Alfonso: storie di \u201cordinario\u201d abbandono e di rinascita\u2026\" \/>\n<meta property=\"og:description\" content=\"Bolivia. Alfonso presto torner\u00e0 a casa insieme ai suoi genitori, nel frattempo noi di Ai.Bi., grazie all\u2019Adozione a Distanza ci prendiamo cura di lui e di tutti i bimbi del\u00a0Gota de Leche.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/bolivia-alfonso-storie-di-ordinario-abbandono-e-di-rinascita\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-11T18:42:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-25T08:17:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/bolivia-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-alfonso-storie-di-ordinario-abbandono-e-di-rinascita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-alfonso-storie-di-ordinario-abbandono-e-di-rinascita\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"Bolivia. Alfonso: storie di \u201cordinario\u201d abbandono e di rinascita\u2026\",\"datePublished\":\"2022-02-11T18:42:56+00:00\",\"dateModified\":\"2022-07-25T08:17:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-alfonso-storie-di-ordinario-abbandono-e-di-rinascita\\\/\"},\"wordCount\":463,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-alfonso-storie-di-ordinario-abbandono-e-di-rinascita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/02\\\/bolivia-1.jpg\",\"keywords\":[\"Gota de Leche\"],\"articleSection\":[\"Adozione a Distanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-alfonso-storie-di-ordinario-abbandono-e-di-rinascita\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-alfonso-storie-di-ordinario-abbandono-e-di-rinascita\\\/\",\"name\":\"Bolivia. Alfonso: storie di \u201cordinario\u201d abbandono e di rinascita\u2026 - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-alfonso-storie-di-ordinario-abbandono-e-di-rinascita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-alfonso-storie-di-ordinario-abbandono-e-di-rinascita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/02\\\/bolivia-1.jpg\",\"datePublished\":\"2022-02-11T18:42:56+00:00\",\"dateModified\":\"2022-07-25T08:17:48+00:00\",\"description\":\"Bolivia. Alfonso presto torner\u00e0 a casa insieme ai suoi genitori, nel frattempo noi di Ai.Bi., grazie all\u2019Adozione a Distanza ci prendiamo cura di lui e di tutti i bimbi del\u00a0Gota de Leche.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-alfonso-storie-di-ordinario-abbandono-e-di-rinascita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-alfonso-storie-di-ordinario-abbandono-e-di-rinascita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-alfonso-storie-di-ordinario-abbandono-e-di-rinascita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/02\\\/bolivia-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/02\\\/bolivia-1.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-alfonso-storie-di-ordinario-abbandono-e-di-rinascita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione a Distanza\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-a-distanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bolivia. Alfonso: storie di \u201cordinario\u201d abbandono e di rinascita\u2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bolivia. Alfonso: storie di \u201cordinario\u201d abbandono e di rinascita\u2026 - Ai.Bi. Amici dei Bambini","description":"Bolivia. Alfonso presto torner\u00e0 a casa insieme ai suoi genitori, nel frattempo noi di Ai.Bi., grazie all\u2019Adozione a Distanza ci prendiamo cura di lui e di tutti i bimbi del\u00a0Gota de Leche.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/bolivia-alfonso-storie-di-ordinario-abbandono-e-di-rinascita\/","og_locale":"it_IT","og_type":"article","og_title":"Bolivia. Alfonso: storie di \u201cordinario\u201d abbandono e di rinascita\u2026","og_description":"Bolivia. Alfonso presto torner\u00e0 a casa insieme ai suoi genitori, nel frattempo noi di Ai.Bi., grazie all\u2019Adozione a Distanza ci prendiamo cura di lui e di tutti i bimbi del\u00a0Gota de Leche.","og_url":"https:\/\/www.aibi.it\/ita\/bolivia-alfonso-storie-di-ordinario-abbandono-e-di-rinascita\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2022-02-11T18:42:56+00:00","article_modified_time":"2022-07-25T08:17:48+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/bolivia-1.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/bolivia-alfonso-storie-di-ordinario-abbandono-e-di-rinascita\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-alfonso-storie-di-ordinario-abbandono-e-di-rinascita\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"Bolivia. Alfonso: storie di \u201cordinario\u201d abbandono e di rinascita\u2026","datePublished":"2022-02-11T18:42:56+00:00","dateModified":"2022-07-25T08:17:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-alfonso-storie-di-ordinario-abbandono-e-di-rinascita\/"},"wordCount":463,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-alfonso-storie-di-ordinario-abbandono-e-di-rinascita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/bolivia-1.jpg","keywords":["Gota de Leche"],"articleSection":["Adozione a Distanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/bolivia-alfonso-storie-di-ordinario-abbandono-e-di-rinascita\/","url":"https:\/\/www.aibi.it\/ita\/bolivia-alfonso-storie-di-ordinario-abbandono-e-di-rinascita\/","name":"Bolivia. Alfonso: storie di \u201cordinario\u201d abbandono e di rinascita\u2026 - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-alfonso-storie-di-ordinario-abbandono-e-di-rinascita\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-alfonso-storie-di-ordinario-abbandono-e-di-rinascita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/bolivia-1.jpg","datePublished":"2022-02-11T18:42:56+00:00","dateModified":"2022-07-25T08:17:48+00:00","description":"Bolivia. Alfonso presto torner\u00e0 a casa insieme ai suoi genitori, nel frattempo noi di Ai.Bi., grazie all\u2019Adozione a Distanza ci prendiamo cura di lui e di tutti i bimbi del\u00a0Gota de Leche.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-alfonso-storie-di-ordinario-abbandono-e-di-rinascita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/bolivia-alfonso-storie-di-ordinario-abbandono-e-di-rinascita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/bolivia-alfonso-storie-di-ordinario-abbandono-e-di-rinascita\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/bolivia-1.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/bolivia-1.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/bolivia-alfonso-storie-di-ordinario-abbandono-e-di-rinascita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione a Distanza","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-a-distanza\/"},{"@type":"ListItem","position":3,"name":"Bolivia. Alfonso: storie di \u201cordinario\u201d abbandono e di rinascita\u2026"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:56:27","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/196973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=196973"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/196973\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/196974"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=196973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=196973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=196973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}