﻿


{"id":197124,"date":"2022-02-17T07:29:17","date_gmt":"2022-02-17T06:29:17","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=197124"},"modified":"2022-02-17T15:33:17","modified_gmt":"2022-02-17T14:33:17","slug":"pan-di-zucchero-bolzano-consulenza-mamma","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/pan-di-zucchero-bolzano-consulenza-mamma\/","title":{"rendered":"Pan di Zucchero di Bolzano: un ascolto a misura di famiglia, come se fossimo &#8220;a casa tua&#8221;"},"content":{"rendered":"<h2>Con il nuovo servizio dello sportello con la psicologa, i servizi dei Pan di Zucchero si ampliano, offrendo a mamme e famiglie un aiuto concreto nei momenti di difficolt\u00e0<\/h2>\n<p><!--more--><\/p>\n<p>Da qualche settimana i Pan di Zucchero (Centri Servizi alla Famiglia di Ai.Bi.) di Bolzano e di Cagliari hanno <a href=\"https:\/\/www.aibi.it\/ita\/i-pan-di-zucchero-ai-bi-di-cagliari-e-bolzano-aprono-uno-sportello-gratuito-per-le-famiglie-adottive-e-affidatarie\/\">aperto due sportelli<\/a> di ascolto dedicati alle famiglie (grazie ai contributi della Provincia Autonoma di Bolzano e della Regione Sardegna). Totalmente gratuiti, consentono a chiunque viva un momento di difficolt\u00e0 o di bisogno di poter parlare con <strong>psicologhe e psicoterapeute esperte<\/strong> (Marcella Griva, per quanto riguarda la sede di Cagliari, ed Elisa Sciommarello per la sede di Bolzano) cos\u00ec da ricevere un consiglio, avere un confronto\u2026 e trovare nuove armi per affrontare il futuro. Si tratta di un servizio che da subito ha riscontrato un notevole successo e che completa a 360 gradi i <strong>servizi offerti dai Pan di Zucchero<\/strong>.<\/p>\n<h3>Consulenza per la mamma e giochi per il figlio al Pan di Zucchero di Bolzano<\/h3>\n<p>Ne abbiamo avuto un esempio a Bolzano poco tempo fa, quando, complice un periodo di vacanza, \u00e8 stato chiesto alle famiglie di <strong>sfruttare al massimo tutti i servizi<\/strong> offerti dal centro e di farvi visita con i propri bambini. Un caff\u00e8, due chiacchiere con le altre mamme e con la psicologa, tanti giochi\u2026 Il tempo passa veloce e, arrivato il momento di tornare a casa, \u00e8 capitato che un bambino gi\u00e0 programmasse con entusiasmo le cose che avrebbe potuto dare la volta successiva: \u201cFacciamo anche i disegno dei teschi; porto la carta da origami\u2026\u201d.<br \/>\nLe parole della mamma, invece, suonavano pi\u00f9 pacate ma, soprattutto, pi\u00f9 <strong>liberatorie<\/strong>: \u201cAdesso (dopo aver parlato con la psicologo n.d.r.) posso affrontare con maggiore serenit\u00e0 l\u2019incontro con gli insegnanti di mio figlio\u201d &#8211; ha detto.<\/p>\n<h3>Un servizio si ascolto e di aiuto per tutte le mamme<\/h3>\n<p>\u00c8 stato un bel riconoscimento per lo sportello, nato proprio per dare <strong>una risposta e un aiuto<\/strong> alle persone famiglie che stanno vivendo un momento di stress, che sia nei confronti dei figli, della societ\u00e0, della coppia\u2026<br \/>\nPerch\u00e9 per andare dallo psicologo non bisogna essere \u201cmalati\u201d. Non bisogna vergognarsi, anzi, bisogna approfittare delle opportunit\u00e0 che si hanno, proprio come quella che lo sportello del Pan di Zucchero vuole essere.<br \/>\nTutte le iniziative dei Pan di Zucchero, attivi su tutto il territorio nazionale, possono essere supportate attivando <u><a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/sostegno-a-distanza-in-italia\/\"><strong>un\u2019Adozione a Distanza<\/strong><\/a><\/u> per una famiglia italiana. Con soli <strong>10 euro al mese<\/strong> si possono dare speranza e dignit\u00e0 a tante donne e tanti bambini che aspettano solo di avere un\u2019occasione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con il nuovo servizio dello sportello con la psicologa, i servizi dei Pan di Zucchero si ampliano, offrendo a mamme e famiglie un aiuto concreto nei momenti di difficolt&agrave;<\/p>\n","protected":false},"author":102,"featured_media":197127,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[764],"tags":[449,673],"class_list":["post-197124","post","type-post","status-publish","format-standard","has-post-thumbnail","category-progetti-in-italia","tag-bolzano","tag-pan-di-zucchero"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pan di Zucchero di Bolzano: consulenza alla mamma<\/title>\n<meta name=\"description\" content=\"Con il nuovo servizio dello sportello con la psicologa, i servizi dei Pan di Zucchero si ampliano, offrendo alle famiglie un aiuto concreto nelle difficolt\u00e0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/pan-di-zucchero-bolzano-consulenza-mamma\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pan di Zucchero di Bolzano: un ascolto a misura di famiglia, come se fossimo &quot;a casa tua&quot;\" \/>\n<meta property=\"og:description\" content=\"Con il nuovo servizio dello sportello con la psicologa, i servizi dei Pan di Zucchero si ampliano, offrendo alle famiglie un aiuto concreto nelle difficolt\u00e0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/pan-di-zucchero-bolzano-consulenza-mamma\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-17T06:29:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-17T14:33:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/Bolzano_Pan_di_Zucchero_consulenza_mamme.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/pan-di-zucchero-bolzano-consulenza-mamma\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/pan-di-zucchero-bolzano-consulenza-mamma\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Pan di Zucchero di Bolzano: un ascolto a misura di famiglia, come se fossimo &#8220;a casa tua&#8221;\",\"datePublished\":\"2022-02-17T06:29:17+00:00\",\"dateModified\":\"2022-02-17T14:33:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/pan-di-zucchero-bolzano-consulenza-mamma\\\/\"},\"wordCount\":438,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/pan-di-zucchero-bolzano-consulenza-mamma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/02\\\/Bolzano_Pan_di_Zucchero_consulenza_mamme.jpg\",\"keywords\":[\"Bolzano\",\"Pan di Zucchero\"],\"articleSection\":[\"Progetti in Italia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/pan-di-zucchero-bolzano-consulenza-mamma\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/pan-di-zucchero-bolzano-consulenza-mamma\\\/\",\"name\":\"Pan di Zucchero di Bolzano: consulenza alla mamma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/pan-di-zucchero-bolzano-consulenza-mamma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/pan-di-zucchero-bolzano-consulenza-mamma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/02\\\/Bolzano_Pan_di_Zucchero_consulenza_mamme.jpg\",\"datePublished\":\"2022-02-17T06:29:17+00:00\",\"dateModified\":\"2022-02-17T14:33:17+00:00\",\"description\":\"Con il nuovo servizio dello sportello con la psicologa, i servizi dei Pan di Zucchero si ampliano, offrendo alle famiglie un aiuto concreto nelle difficolt\u00e0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/pan-di-zucchero-bolzano-consulenza-mamma\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/pan-di-zucchero-bolzano-consulenza-mamma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/pan-di-zucchero-bolzano-consulenza-mamma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/02\\\/Bolzano_Pan_di_Zucchero_consulenza_mamme.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/02\\\/Bolzano_Pan_di_Zucchero_consulenza_mamme.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/pan-di-zucchero-bolzano-consulenza-mamma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti in Italia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/progetti-in-italia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pan di Zucchero di Bolzano: un ascolto a misura di famiglia, come se fossimo &#8220;a casa tua&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pan di Zucchero di Bolzano: consulenza alla mamma","description":"Con il nuovo servizio dello sportello con la psicologa, i servizi dei Pan di Zucchero si ampliano, offrendo alle famiglie un aiuto concreto nelle difficolt\u00e0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/pan-di-zucchero-bolzano-consulenza-mamma\/","og_locale":"it_IT","og_type":"article","og_title":"Pan di Zucchero di Bolzano: un ascolto a misura di famiglia, come se fossimo \"a casa tua\"","og_description":"Con il nuovo servizio dello sportello con la psicologa, i servizi dei Pan di Zucchero si ampliano, offrendo alle famiglie un aiuto concreto nelle difficolt\u00e0","og_url":"https:\/\/www.aibi.it\/ita\/pan-di-zucchero-bolzano-consulenza-mamma\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2022-02-17T06:29:17+00:00","article_modified_time":"2022-02-17T14:33:17+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/Bolzano_Pan_di_Zucchero_consulenza_mamme.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/pan-di-zucchero-bolzano-consulenza-mamma\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/pan-di-zucchero-bolzano-consulenza-mamma\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Pan di Zucchero di Bolzano: un ascolto a misura di famiglia, come se fossimo &#8220;a casa tua&#8221;","datePublished":"2022-02-17T06:29:17+00:00","dateModified":"2022-02-17T14:33:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/pan-di-zucchero-bolzano-consulenza-mamma\/"},"wordCount":438,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/pan-di-zucchero-bolzano-consulenza-mamma\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/Bolzano_Pan_di_Zucchero_consulenza_mamme.jpg","keywords":["Bolzano","Pan di Zucchero"],"articleSection":["Progetti in Italia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/pan-di-zucchero-bolzano-consulenza-mamma\/","url":"https:\/\/www.aibi.it\/ita\/pan-di-zucchero-bolzano-consulenza-mamma\/","name":"Pan di Zucchero di Bolzano: consulenza alla mamma","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/pan-di-zucchero-bolzano-consulenza-mamma\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/pan-di-zucchero-bolzano-consulenza-mamma\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/Bolzano_Pan_di_Zucchero_consulenza_mamme.jpg","datePublished":"2022-02-17T06:29:17+00:00","dateModified":"2022-02-17T14:33:17+00:00","description":"Con il nuovo servizio dello sportello con la psicologa, i servizi dei Pan di Zucchero si ampliano, offrendo alle famiglie un aiuto concreto nelle difficolt\u00e0","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/pan-di-zucchero-bolzano-consulenza-mamma\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/pan-di-zucchero-bolzano-consulenza-mamma\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/pan-di-zucchero-bolzano-consulenza-mamma\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/Bolzano_Pan_di_Zucchero_consulenza_mamme.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/Bolzano_Pan_di_Zucchero_consulenza_mamme.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/pan-di-zucchero-bolzano-consulenza-mamma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Progetti in Italia","item":"https:\/\/www.aibi.it\/ita\/category\/progetti-in-italia\/"},{"@type":"ListItem","position":3,"name":"Pan di Zucchero di Bolzano: un ascolto a misura di famiglia, come se fossimo &#8220;a casa tua&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:04:04","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/197124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=197124"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/197124\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/197127"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=197124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=197124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=197124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}