﻿


{"id":197352,"date":"2022-12-12T11:00:58","date_gmt":"2022-12-12T10:00:58","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=197352"},"modified":"2023-10-25T14:50:59","modified_gmt":"2023-10-25T12:50:59","slug":"guerra-in-ucraina-tutti-gli-aggiornamenti","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-tutti-gli-aggiornamenti\/","title":{"rendered":"EMERGENZA UCRAINA. Zelensky apre alla pace. Vaticano: \u201cDisponibili come spazio in cui le parti possano avviare un dialogo\u201d"},"content":{"rendered":"<h2>EMERGENZA UCRAINA. Al termine di un colloquio con il Presidente USA Biden, il presidente ucraino Zelensky si dice soddisfatto che \u201cla nostra formula di pace\u201d sia stata percepita positivamente. Disponibilit\u00e0 della Santa Sede a essere terreno comune per un incontro. Ma sul campo la guerra non si ferma<\/h2>\n<h2><!--more--><\/h2>\n<h3>12\/12 \u2013 16.00 <strong>Zelensky apre alla pace. Vaticano: \u201cdisponibili come spazio in cui le parti possano avviare un dialogo\u201d<\/strong><\/h3>\n<p>Data la situazione, ogni volta che viene nominata la parola \u201cpace\u201d da parte dei principali contendenti della guerra in Ucraina vale la pena sottolinearlo e soffermarsi sui possibili spiragli che si possono aprire in tal senso. Questa volta, a nominare la pace \u00e8 stato <strong>Volodymyr Zelensky<\/strong> riportando del suo ultimo colloquio con il Presidente degli Stati Uniti <strong>Biden<\/strong>. \u201cMi ha fatto piacere sentire nella conversazione che <strong>la nostra formula di pace \u00e8 stata percepita positivamente<\/strong> &#8211; si legge sul profilo Telegram del presidente ucraino. E questo <strong>aggiunge ottimismo<\/strong>\u201d.<br \/>\nNon che si tratti di una vera apertura a un negoziato, perch\u00e9 la posizione dell\u2019Ucraina \u00e8 quella gi\u00e0 espressa nell\u2019intervento durante il G20, con i 10 punti imprescindibili per poter pensare a una possibile pace, ma il fatto che sia stata ribadita l\u2019apertura per \u201csedersi al tavolo\u201d, a fronte di determinate condizioni, \u00e8 sicuramente positiva.<br \/>\nNon \u00e8 un caso che, a distanza di poche ore, il Segretario di Stato Vaticano, cardinale <strong>Pietro Parolin<\/strong>, abbia ribadito la disponibilit\u00e0 della Santa Sede a farsi <strong>mediatrice di un possibile dialogo<\/strong>: \u201cSiamo disponibili \u2013 ha risposto il Cardinale a margine di una presentazione al Senato \u2013 e credo che il Vaticano sia il terreno adatto. Abbiamo cercato di offrire <strong>possibilit\u00e0 di incontro con tutti e di mantenere un equilibrio<\/strong>. Offriamo uno spazio in cui le parti possano incontrarsi e avviare un dialogo. Sta a loro individuare la metodologia di lavoro e i contenuti&#8221;.<br \/>\nSegnali importanti e significativi, anche se nessuno si illude che le cose a breve possano cambiare drasticamente. Nel frattempo, infatti, sul campo sono <strong>proseguiti i bombardamenti<\/strong> russi su Kiev e altre citt\u00e0, mentre il Consiglio Ue ha raggiunto l\u2019accordo per aumentare a 2 miliardi il massimale finanziario per la fornitura di armi all\u2019Ucraina nel corso del prossimo anno. Con la speranza che possa presto non essercene pi\u00f9 bisogno.<\/p>\n<h3>07\/12 \u2013 12.00 <strong>Il freddo non ferma le attivit\u00e0 del progetto #BAMBINIxLAPACE<\/strong><\/h3>\n<p>Continuano senza sosta gli attacchi russi in territorio ucraino. Nella notte, come riportato da <em>Rainews,<\/em> il distretto di Zaporizhzhia \u00e8 stato colpito dall\u2019esercito russo.<br \/>\nLa guerra sembra non trovare soluzione di pace. Il portavoce del Cremlino Peskov ha affermato, come indicato da <em>Ansa<\/em>, che Mosca non vede: \u201c<em>prospettive per i colloqui di pace in Ucraina; la Russia deve raggiungere gli obiettivi dell&#8217;operazione militare speciale e questo sar\u00e0 fatto\u201d.<br \/>\n<\/em>Intanto a <strong>Kharkiv,<\/strong> una delle citt\u00e0 ucraine maggiormente colpite dagli attacchi, il freddo invernale, che si aggiunge a guerra e povert\u00e0, aggrava ancora di pi\u00f9 la situazione della popolazione ucraina.<br \/>\nLa cattedrale di San Nicola, in costruzione nella periferia della citt\u00e0, accoglie ogni giorno migliaia di persone in attesa di trovare generi di conforto. A raccontarlo \u00e8 <em>Avvenire<\/em>. Il vescovo Vasyl Tuchapets, che ha voluto che la chiesa greco- cattolica in costruzione divenisse un grande sportello di aiuti spiega: \u201c<em>Il Vangelo<\/em> <em>ci chiede di essere accanto alla gente che soffre<\/em>\u00bb. In citt\u00e0 manca tutto. <strong>\u201c<em>I bisogni<\/em> \u2013 continua il vescovo- <em>stanno esplodendo con l\u2019inverno<\/em>. <\/strong><em>La strategia di Putin di danneggiare le infrastrutture energetiche sta lasciando tutta la regione senza elettricit\u00e0, acqua corrente e riscaldamento, com\u2019\u00e8 accaduto in queste ore<\/em>\u201d.<br \/>\n<strong>Nella giornata del 6 dicembre, si celebra la festa di San Nicola, il &#8216;Babbo Natale&#8217; dell&#8217;est e del nord Europa. <\/strong>La guerra non ha fermato in Ucraina, il \u201csuo\u201d carico di doni e speranza per i bambini. Come infatti riporta <em>Ansa, <\/em>per celebrarlo \u00e8 partito all\u2019alba dalla Polonia un camion della Croce Rossa pieno di 700 doni: giocattoli, dolci, frutta (come da tradizione) e matite. Destinazione, Zovka, cittadina nell&#8217;oblast di <strong>Leopoli<\/strong>, dove nel convento delle suore domenicane \u00e8 stato festeggiato il Santo.<\/p>\n<p><strong>\u201cIl Bello che Fa Bene\u201d per il progetto #BAMBINIxLAPACE<\/strong><\/p>\n<p>Il freddo invernale non ferma di certo le attivit\u00e0 del progetto #BAMBINIxLAPACE. Fino a che la pace non torner\u00e0 ad abitare anche i luoghi oggi martoriati dalla guerra, Ai.Bi. sar\u00e0 presente per cercare di portare il suo aiuto e il suo supporto. Per questo, al progetto #BAMBINIxLAPACE saranno devolute tutte le donazioni raccolte durante il periodo natalizio, a partire dal grande evento \u201c<a href=\"https:\/\/www.aibi.it\/ita\/natale-2022-bambini-poveri\/\"><strong>Il Bello che Fa Bene<\/strong><\/a>\u201d, che torna in presenza dal 16 al 20 dicembre, a Milano, in via Tortona, 30, con un Temporary Shop e una mostra fotografica proprio sui progetti di Ai.Bi. in Ucraina, Moldova e Italia.<br \/>\nTutte le informazioni,\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/bello-che-fa-bene-natale-solidale-aibi\/\"><strong>QUI<\/strong><\/a><\/p>\n<h3>28\/11 \u2013 11.00 \u201cGeneratori di speranza\u201d: la campagna dell\u2019Europa per fornire corrente elettrica all\u2019Ucraina<\/h3>\n<p>Nel giorno in cui un articolo del <em>New York Times<\/em> sottolinea come l\u2019invio di armi da parte dei Paesi Nato all\u2019Ucraina inizi a essere in difficolt\u00e0 a causa dei costi altissimi, della quantit\u00e0 di colpi sparati quotidianamente e del prolungarsi del conflitto, l\u2019Europa \u00e8 pronta a mobilitarsi per fornire un altro tipo di \u201carmi\u201d alla popolazione stremata: <strong>generatori di emergenza \u201cPer alimentare le case e illuminare la notte\u201d.<\/strong> Cos\u00ec recita un tweet della Presidente del Parlamento Eueopeo Roberta Metsola all\u2019indomani del lancio della campagna \u201c<strong>Generatori di speranza<\/strong>\u201d, presentata al insieme al co-iniziatore della campagna Daniele Nardella, sindaco di Firenze e Presidente di Eurocities.<br \/>\n\u201cInsieme \u2013 prosegue il messaggio della Metsola \u2013 <strong>attraverseremo l\u2019oscurit\u00e0 causata dalle bombe del Cremlino<\/strong>\u201d.<br \/>\n\u00c8 senza dubbio un bel messaggio, non solo per la promessa di un aiuto concreto verso quelli che sono gi\u00e0 i principali problemi per la popolazione dell\u2019Ucraina: il gelo dell\u2019inverno e la difficolt\u00e0 di approvvigionamento energetico, ma anche per l\u2019immagine in cui, per una volta, viene <strong>contrapposta al \u201cbuio\u201d delle armi la \u201cluce\u201d della speranza<\/strong>. Una luce che non arriva da altre armi o altri missili sparati come riposta, ma da \u201c<strong>generatori<\/strong>\u201d di corrente elettrica, con tutto il significato che una parola come questa si porta dietro.<br \/>\nPerch\u00e9 una guerra si combatte anche cercando di tenere alto il morale delle persone, fornendo loro dei motivi di speranza cui aggrapparsi per resistere ai momenti terribili in cui tutto sembra destinato alla distruzione. Si possono leggere in tal senso anche il moltiplicarsi delle \u201c<strong>Stazioni di invincibilit\u00e0<\/strong>\u201d: grosse tende aperte a tutta la popolazione in cui viene garantita la presenza di corrente elettrica (con cavi e stazioni per ricaricare i propri telefonini e i computer), riscaldamento, snack e acqua.<br \/>\nUna sorta di versione statale, ingigantita, di ci\u00f2 che i <strong><a href=\"https:\/\/www.aibi.it\/ita\/bambinixlapace-ucraina-i-punti-ai-bi-luoghi-protetti-dove-i-bambini-sono-liberi-di-esprimere-le-proprie-emozioni\/\">Punti Ai.Bi.<\/a><\/strong>, nel loro piccolo cercano di fare gi\u00e0 da diverse settimane: garantire ai bambini e le famiglie un luogo sicuro, in cui ritrovare un pezzetto di quella normalit\u00e0 che le bombe stanno provando a portare via.<\/p>\n<h3>23\/11 \u2013 15.30 Manca l\u2019acqua in tutta Kiev. Blackout anche in Moldova<\/h3>\n<p>Non c\u2019\u00e8 un attimo di tregua, oggi, in tutta l\u2019Ucraina. Dopo i bombardamenti di questa notte, nel corso della giornata si sono intensificati gli attacchi in tutte le regioni del Paese, compresa la capitale <strong>Kiev<\/strong>. Cos\u00ec, mentre si apprende che a Kheroson \u00e8 <strong>morto anche un ragazzino di 13 anni<\/strong> per le conseguenze del bombardamento, il sindaco di Kiev Vitaly Klitschko avvisa tramite <em>Telegram<\/em> che in tutta la citt\u00e0 \u00e8 sospesa l\u2019erogazione dell\u2019acqua. I tecnici sono al lavoro, ma il sindaco chiede \u201cdi fare scorta di acqua per ogni evenienza&#8221;.<br \/>\nA <strong>Leopoli<\/strong>, invece, manca la corrente elettrica e la citt\u00e0 \u00e8 senza luce. Ma anche in questo caso il sindaco ha avvertito della possibilit\u00e0 che ci possano essere anche interruzioni nell\u2019erogazione dell\u2019acqua.<br \/>\nLe conseguenze dei pesantissimi bombardamenti si sentono anche nella confinante <strong>Moldova<\/strong>, dove si sono verificati blackout in diverse parti del Paese, compresa la capitale Chisinau.<br \/>\nTatiana, una delle cooperanti di Ai.Bi. che in Moldova porta avanti le attivit\u00e0 del progetto <strong>#BAMBINIxLAPACE<\/strong>, racconta cos\u00ec la situazione attuale: \u201cLa luce \u00e8 tornata da circa un&#8217;ora. Purtroppo non abbiamo l&#8217;acqua. In alcuni settori della citt\u00e0, invece, manca la luce, ma c\u2019\u00e8 l\u2019acqua. I messaggi che arrivano dalle autorit\u00e0 sono positivi, ma il panico fra i civili sta crescendo\u201d.<\/p>\n<h3>23\/11 \u2013 12.00 Bombe sul reparto maternit\u00e0 di un ospedale. Muore neonato<\/h3>\n<p>Altra notte di terrore in Ucraina, altra notte di bombe indiscriminate e di morti terribili. I missili russi sono tornati a colpire le citt\u00e0 del Paese, concentrandosi ancora una volta nella zona intorno a Zaporizhzhia. Tra gli edifici pi\u00f9 colpiti c\u2019\u00e8 anche <strong>l\u2019ospedale di Vilnianska<\/strong>, dove, secondo quanto riportato dal <em>Kyiv Indipendent<\/em> riferendo di un messaggio Telegram del governatore della regione Oleksandr Starukh, sarebbe rimasto ucciso anche un neonato.<br \/>\nNel corso della mattinata, i soccorritori hanno estratto viva dalla macerie la mamma del piccolo, portata in salvo insieme a un medico della struttura.<br \/>\nGli attacchi sono stati molto intensi anche nella <strong>regione di Kharkiv<\/strong>: anche qui \u00e8 stato colpito un ospedale, quello di Kupyansk, e alcuni condomini di civili. Le autorit\u00e0 riportano di due cittadini morti: una donna di 55 anni e un uomo di 68.<br \/>\nIl Presidente ucraino Zelensky su Telegram ha accusato la Russia di riccorrere al \u201cterrore e all\u2019omicidio\u201d, e davvero, se gi\u00e0 nella guerra trovare un senso \u00e8 difficile, davanti alle bombe che colpiscono i reparti maternit\u00e0 degli ospedali \u00e8 assolutamente impossibile.<\/p>\n<p>In questo contesto difficile, non si fermano le attivit\u00e0 di Ai.Bi. del progetto <strong>#BAMBINIxLAPACE<\/strong> che proprio in Ucraina continuano a portare aiuti e conforto ai bambini e le famiglie pi\u00f9 in difficolt\u00e0, cos\u00ec come lo fanno con chi a causa del conflitto \u00e8 sfollato in Moldova e in italia. \u00c8 proprio a queste attivit\u00e0 che verranno destinati i fondi raccolti durante la <strong>campagna di Natale Solidale<\/strong> di quest\u2019anno, le cui proposte, dal Panettone per la Pace\u00a9 ai biglietti di auguri con la grafica firmata Alan Zeni fino alla <a href=\"https:\/\/www.aibi.it\/natale\/adozione-a-distanza\/\">possibilit\u00e0 di un\u2019Adozione a Distanza<\/a>, si possono trovare alla <a href=\"https:\/\/www.aibi.it\/natale\/solidale\/\">pagina dedicata<\/a> del sito.<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*207043-start*\/\n#btnsx-207043{margin-top:0px;margin-bottom:0px;margin-left:0px;margin-right:0px;padding-top:10px;padding-bottom:10px;padding-left:40px;padding-right:40px;}\n#btnsx-207043 .btnsx-text-primary{font-size:33px;line-height:33px;font-style:normal;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-207043:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-207043{background-color:#dd3333!important;}\n#btnsx-207043:hover{background-color:#dd3333!important;}\n#btnsx-207043{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px;}\n#btnsx-207043:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px;}\n#btnsx-207043{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-207043:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*207043-end*\/\n<\/style>\n<a href=\"https:\/\/www.aibi.it\/natale\/solidale\" id=\"btnsx-207043\" target=\"_self\" class=\"btnsx-btn btnsx-btn-block\" >\n\t<span class=\"btnsx-text-primary \">Natale Solidale<\/span><\/a>\n\n<!-- Buttons X - End -->\n\n<h3>16\/11 \u2013 16.00 Bombardamento a Kiev: la testimonianza del cooperante di Ai.Bi. Eugenio<\/h3>\n<p>Nuove immagini e notizie arrivano direttamente da Kiev dal nostro cooperante Eugenio, che si trova nella capitale dell\u2019Ucraina per portare avanti i progetti nell\u2019ambito della campagna <strong>BAMBINIxLAPACE<\/strong>. In seguito ai bombardamenti di marted\u00ec 15, diverse case sono state colpite dai frammenti di razzi abbattuti dalla contraerea. Secondo l\u2019addetto stampa del Servizio statale di emergenza di Kiev, Oleksandr Makushenko, due palazzi residenziali sono stati danneggiati nel quartiere Pechersk, mentre altri frammenti sono caduti nel distretto di Obolonsky colpendo edifici abbandonati.<br \/>\n\u00c8 arrivata anche la conferma che una persona \u00e8 rimasta uccisa e tre sono state ferite in seguito al bombardamento, mentre le forze dell\u2019ordine e i soccorritori continuano a lavorare sul luogo della tragedia.<br \/>\nCome ha riferito il sindaco della capitale Vitaliy Klitschko: &#8220;L&#8217;ingresso di uno degli edifici di cinque piani \u00e8 stato danneggiato in modo significativo. Le persone sono state evacuate e re-insediate. Alcune hanno preferito, invece, andare a stare per il momento da parenti e amici\u201d.<\/p>\n<div id='gallery-1' class='gallery galleryid-197352 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/bombe-kiev-guerra-ucraina-15-novembre\/'><img loading=\"lazy\" decoding=\"async\" width=\"571\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/11\/bombe-kiev-guerra-ucraina-15-novembre-571x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/11\/bombe-kiev-guerra-ucraina-15-novembre-571x300.jpg 571w, https:\/\/www.aibi.it\/ita\/images\/2022\/11\/bombe-kiev-guerra-ucraina-15-novembre-150x79.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/11\/bombe-kiev-guerra-ucraina-15-novembre-768x403.jpg 768w, https:\/\/www.aibi.it\/ita\/images\/2022\/11\/bombe-kiev-guerra-ucraina-15-novembre.jpg 1200w\" sizes=\"auto, (max-width: 571px) 100vw, 571px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/bombe-kiev-guerra-ucraina-15-novembre-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"571\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/11\/bombe-kiev-guerra-ucraina-15-novembre-3-571x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/11\/bombe-kiev-guerra-ucraina-15-novembre-3-571x300.jpg 571w, https:\/\/www.aibi.it\/ita\/images\/2022\/11\/bombe-kiev-guerra-ucraina-15-novembre-3-150x79.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/11\/bombe-kiev-guerra-ucraina-15-novembre-3-768x403.jpg 768w, https:\/\/www.aibi.it\/ita\/images\/2022\/11\/bombe-kiev-guerra-ucraina-15-novembre-3.jpg 1200w\" sizes=\"auto, (max-width: 571px) 100vw, 571px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/bombe-kiev-guerra-ucraina-15-novembre-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"571\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/11\/bombe-kiev-guerra-ucraina-15-novembre-2-571x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/11\/bombe-kiev-guerra-ucraina-15-novembre-2-571x300.jpg 571w, https:\/\/www.aibi.it\/ita\/images\/2022\/11\/bombe-kiev-guerra-ucraina-15-novembre-2-150x79.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/11\/bombe-kiev-guerra-ucraina-15-novembre-2-768x403.jpg 768w, https:\/\/www.aibi.it\/ita\/images\/2022\/11\/bombe-kiev-guerra-ucraina-15-novembre-2.jpg 1200w\" sizes=\"auto, (max-width: 571px) 100vw, 571px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<h3>16\/11 &#8211; 11.30 Missili in Polonia: cautela della Nato. \u201cImprobabile siano partiti dalla Russia\u201d<\/h3>\n<p>Nella giornata di marted\u00ec 15 novembre, poche ore dopo il discorso di Zelensky al G20 che aveva fatto sperare in possibili, anche se molto tenuti, spiragli di pace, la risposta della Russia non si \u00e8 fatta attendere. Ed \u00e8 stata una risposta di <strong>assoluta violenza<\/strong>, con uno dei peggiori bombardamenti effettuato su Kiev e altre citt\u00e0 dell\u2019Ucraina negli ultimi mesi. Quasi un centinaio di missili si sono abbattuti su strutture civili e centrali energetiche, proseguendo la strategia ormai evidente di colpire obiettivi che non hanno nulla di militare e che servono soltanto a <strong>terrorizzare la popolazione<\/strong> e a rendere sempre pi\u00f9 difficile l\u2019approvvigionamento energetico e, quindi, il riscaldamento delle case, in vista del rigido inverno ormai alle porte.<br \/>\nMa il fatto che pi\u00f9 di tutti ha catalizzato l\u2019attenzione del mondo \u00e8 stata l\u2019esplosione avvenuta a Przewod\u00f3w, piccolo Paese vicino al confine con l\u2019Ucraina ma situato in Polonia. La Polonia, infatti, non solo \u00e8 un Paese della Comunit\u00e0 Europea, ma \u00e8 anche <strong>membro della NATO<\/strong>, l\u2019Alleanza Atlantica che prevede l\u2019intervento degli alleati in caso di attacco verso un Paese membro.<br \/>\nSubito dopo l\u2019esplosione, che ha ucciso due persone, la Polonia ha convocato il comitato per la Sicurezza nazionale e gli Affari della Difesa, mentre i leader dei Paesi Nato presenti al G20 di Bali si sono a loro volta incontrati.<br \/>\nTanto dalla Polonia quanto da NATO e Stati Uniti, per fortuna sono arrivati presti <strong>messaggi di grande cautela<\/strong>, fino alla dichiarazione del Presidente Biden di come sia \u201cimprobabile\u201d che i missili siano stati deliberatamente lanciati dalla Russia. L\u2019ipotesi che al momento sembrerebbe pi\u00f9 accreditata \u00e8 quella che riconduce l\u2019esplosione alla contraerea ucraina: i resti trovati, secondo le prime foto circolate (non verificate) sarebbero di missili s\u00ec di fabbricazione russa, ma in dotazione anche all\u2019esercito ucraino proprio per difendersi da attacchi missilistici.<br \/>\nDel tutto improbabile, dunque, al momento, che l\u2019episodio possa innescare la richiesta di applicazione del famoso \u201c<strong>Articolo 5<\/strong>\u201d della NATO (quello, appunto, che obbliga gli alleati a intervenire in caso di attacco verso un Paese membro), ma quanto accaduto dimostra <strong>l\u2019ingovernabilit\u00e0 di un fenomeno come la guerra<\/strong>, dove un errore o un episodio \u201ccasuale\u201d diventa comunque irreversibile e pu\u00f2 provocare delle conseguenze che nessuno dei contendenti desiderava o si auspicava.<\/p>\n<p><strong>Sostieni anche tu la campagna di Ai.Bi. BAMBINIXLAPACE<\/strong><\/p>\n<p>In un momento cos\u00ec delicato, diventa ancor pi\u00f9 indispensabile l\u2019attivit\u00e0 che Amici dei Bambini conduce in Ucraina all\u2019interno dei \u201cPunti Ai.Bi.\u201d nel contesto del progetto <a href=\"https:\/\/www.aibi.it\/ita\/bambinixlapace\"><strong>BAMBINIxLAPACE<\/strong><\/a>, a cui chiunque pu\u00f2 dare il proprio contributo con una <a href=\"https:\/\/www.aibi.it\/ita\/emergenza-ucraina\/?scelta=Una%20tantum\"><strong>donazione libera<\/strong><\/a> oppure attivando <strong>un\u2019<a href=\"https:\/\/www.aibi.it\/ita\/emergenza-ucraina\/?scelta=Adozione%20a%20Distanza\">Adozione a Distanza per i minori dell\u2019Ucraina<\/a><\/strong><\/p>\n<h3>\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*197331-start*\/\n#btnsx-197331{margin-top:0px;margin-bottom:25px;margin-left:0px;margin-right:0px;padding-top:16px;padding-bottom:15px;padding-left:43px;padding-right:44px;}\n#btnsx-197331 .btnsx-text-primary{text-transform:uppercase;font-size:20px;line-height:20px;font-weight:800;font-family:Raleway;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-197331:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-197331{background-color:#dd3333!important;}\n#btnsx-197331:hover{background-color:#d13030!important;}\n#btnsx-197331{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px;}\n#btnsx-197331:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:solid;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px;}\n#btnsx-197331{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-197331:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*197331-end*\/\n<\/style>\n<a href=\"https:\/\/dona.aibi.it\/emergenza-ucraina\/?act=cplt&amp;origine=web-button-in-post\" id=\"btnsx-197331\" class=\"btnsx-btn btnsx-btn-block\"  data-font-primary=\"Raleway\">\n\t<span class=\"btnsx-text-primary \">EMERGENZA UCRAINA<\/span><\/a>\n\n<!-- Buttons X - End -->\n<\/h3>\n<h3>31\/10 \u2013 19.00 Nuovo bombardamento sull\u2019Ucraina: a Kiev l\u201980% degli abitanti snz\u2019acqua<\/h3>\n<p>Ancora bombe su Kiev e sull\u2019Ucraina. Anche alle prime luci dell\u2019alba del 31 ottobre, nel cielo della capitale, come in quello di altre citt\u00e0 del Paese, sono risuonate le sirene e, poco dopo, sono comparse le bombe che hanno iniziato a colpire, ancora una volta, diverse <strong>infrastrutture critiche<\/strong>. Il piano di Mosca \u00e8 ormai pi\u00f9 che chiaro: colpire gli snodi vitali per la distribuzione di acqua e di energia cos\u00ec da terrorizzare la popolazione e costringere gli ucraini ad affrontare un inverno che si annuncia difficilissimo. Secondo il sindaco di Kiev, a oggi l\u2019<strong>80% degli abitanti della citt\u00e0 \u00e8 senz\u2019acqua<\/strong>, mentre circa <strong>350mila case sono senza elettricit\u00e0<\/strong>. Tra le altre citt\u00e0 colpite ci sono anche Zaporizhzhia, Vinnitsa e Kharkiv, oltre ad altri centri sparsi in almeno 10 regioni. Dappertutto l\u2019approvvigionamento dell\u2019energia \u00e8 molto difficoltoso.<br \/>\nI sistemi di difesa sono riusciti a intercettare diversi missili, uno dei quali \u00e8 finito per <strong>cadere sul territorio della Moldova<\/strong>, provocando alcuni danni ma, per fortuna, senza che si siano registrate delle vittime.<br \/>\nCattive notizie arrivano anche dal fronte <strong>dell\u2019accordo sul grano<\/strong>, dal quale la Russia si \u00e8 ritirata in seguito agli attacchi ucraini verso alcune navi al largo della Crimea. La Turchia si \u00e8 subito attivata per vie diplomatiche cercando con determinazione \u2013 come annunciato dal Presidente Erdogan \u2013 \u201cDi mantenere in vita l\u2019accordo sul grano\u201d, anche senza la Russia. Ipotesi, per\u00f2, che renderebbe tutto estremamente pi\u00f9 complicato e insicuro.<\/p>\n<h3>24\/10 \u2013 10.30 \u2013 \u00a0Finlandia. Troppi\u00a0 cittadini russi si rifugiano nel Paese: il Governo pensa a una barriera sul confine con la Russia<\/h3>\n<p>La Finlandia condivide con la Russia un confine di ben <strong>1.340 chilometri<\/strong>: una misura decisamente notevole per pensare di poterla controllare strettamente in tutta la sua lunghezza, tanto che gran parte della frontiera non \u00e8 segnata che da palizzate di legno utili pi\u00f9 che altro per non far andare gli animali nel Paese \u201csbagliato\u201d. Con lo scoppio della guerra in Ucraina, per\u00f2, la questione del confine tra Finlandia e Russia si \u00e8 fatta via via pi\u00f9 spinosa, tanto da portare la Guardia di frontiera del Paese scandinavo a chiedere, circa un mese fa, l\u2019installazione di un <strong>sistema pi\u00f9 strutturato e solido di barriere. <\/strong>I motivi sono principalmente due: da un lato c\u2019\u00e8 la volont\u00e0 di contenere il numero di migranti che dalla Russia si spostano in Finlandia per fuggire alla mobilitazione che costringe diversi cittadini ad arruolarsi per andare a combattere; dall\u2019altro c\u2019\u00e8 l\u2019obiettivo di impedire alla stessa Russia di spingere migliaia di profughi in direzione di quel confine con l\u2019intento (gi\u00e0 visto in passato nei confronti di Polonia e Lituania) di <strong>mettere il Paese in difficolt\u00e0<\/strong> davanti a una quantit\u00e0 di richiedenti asilo difficile da gestire, specie per un Paese che conta solamente, all\u2019incirca, 5,5 milioni di abitanti.<br \/>\nOggi la prima ministra <strong>Sanna Marin<\/strong> \u00e8 tornata sull\u2019argomento, annunciando che la proposta gode di un sostegno sempre maggiore all\u2019interno del governo e non \u00e8 escluso possa trovare il consenso anche di parte dell\u2019opposizione. Naturalmente sarebbe impensabile costruire una barriera di oltre 1300 km, per questo il progetto prevede di erigerne tra i 130 e i 260 km, concentrandosi nei punti strategicamente pi\u00f9 sensibili. Se dovesse arrivare subito il via libera del Parlamento, un primo tratto di 3 chilometri potrebbe essere realizzato gi\u00e0 nei prossimi mesi.<\/p>\n<h3>19\/10 \u2013 12:20 Colpite le infrastrutture energetiche: oltre 1000 citt\u00e0 senza elettricit\u00e0, acqua e riscaldamento<\/h3>\n<p>Dopo l\u2019ennesima notte di bombardamenti, \u00e8 ormai chiara quale sia l\u2019attuale strategia intrapresa dalla Russia nella guerra in Ucraina: <strong>colpire le infrastrutture energetiche<\/strong>. Il ch\u00e9, inevitabilmente, significa colpire <strong>obiettivi civili<\/strong> e far ricadere prima di tutto sui civili le conseguenze della guerra. D\u2019altra parte, la strategia non \u00e8 molto differente da quella gi\u00e0 vista in Siria, dove la popolazione civile non \u00e8 stata certo risparmiata. L\u2019obiettivo \u00e8 soprattutto quello di <strong>terrorizzare la popolazione<\/strong>, lasciando le citt\u00e0 senza elettricit\u00e0, acqua e riscaldamento mentre il rigido inverno \u00e8 sempre pi\u00f9 vicino.<br \/>\nSecondo quanto dichiarato dal presidente ucraino Volodymyr Zelensky, i bombardamenti degli ultimi giorni hanno <strong>distrutto il 30% delle centrali elettriche ucraine<\/strong>. Le citt\u00e0 senza elettricit\u00e0 sono <strong>1.162<\/strong>, ma sarebbero potute essere molte di pi\u00f9 senza il grande lavoro del personale addetto che ha consentito di ripristinare la corrente in molte zone del Paese. Principali protagonisti di questi bombardamenti sono i droni di fabbricazione iraniana Shahed-136: secondo l\u2019Aeronautica Militare delle Forze Armate Ucraine, negli ultimi 36 giorni ne sarebbero stato lanciati <strong>223<\/strong>.<br \/>\nLa vicinanza delle strutture energetiche a citt\u00e0 e case ha portato nell\u2019ultima settimana ad almeno <strong>70 morti tra i civili<\/strong>, tanto da portare la presidente della Commissione Europea Ursula von der Leyen a parlare apertamente di \u201c<strong>crimini di guerra<\/strong>\u201d.<br \/>\nIntanto, nelle aree dell\u2019Ucraina attualmente occupate, lo Stato Maggiore dell\u2019esercito ucraino ha denunciato il <strong>saccheggio dei musei<\/strong> da parte dei soldati russi, che starebbero anche bruciando i libri in lingua ucraina.<\/p>\n<h3><strong>17\/10 \u2013 17.00 \u2013 Attacco con droni kamikaze. L\u2019ambasciata italiana: \u201clasciare l\u2019Ucraina\u201d<br \/>\n<\/strong><\/h3>\n<p>A confronto di chi dalle bombe si deve difendere, la difficolt\u00e0 di chi deve trovare ogni volta delle parole diverse per quello che succede in Ucraina \u00e8 ben poca cosa, ma \u00e8 senza dubbio indicativa della <strong>tragedia senza fine<\/strong> che sta accadendo.<br \/>\nAncora una volta, infatti, le sirene sono tornate a suonare nei cieli di Kiev, dove si sono verificati una serie di attacchi condotti attraverso droni kamikaze. Secondo le autorit\u00e0, sono stati <strong>almeno 43<\/strong> i droni lanciati su tutta l\u2019Ucraina, molti dei quali abbattuti. Quelli andati a bersaglio, per\u00f2, hanno provocato almeno tre morti e diversi danni, specie alle infrastrutture elettriche. Secondo una comunicazione iniziale del primo ministro ucraino, sono \u201ccentinaia\u201d le localit\u00e0 rimaste senza elettricit\u00e0, anche se il gestore delle rete si \u00e8 subito messo al lavoro per cercare di ripristinare le linee.<br \/>\nOltre a Kiev, diverse esplosioni si sono verificate anche nelle regioni di Odessa e Kharkov, nella citt\u00e0 di Nikolayev, a Sumy e a Zaporizhzhia. Qui, in particolare, una volta ancora sono stati danneggiati i sistemi di approvvigionamento elettrico fondamentali per la sicurezza della centrale nucleare. Sono stati attivati i generatori diesel di emergenza.<br \/>\nIn seguito ai nuovi bombardamenti, l\u2019ambasciata italiana in Ucraina ha invitato tutti i cittadini italiani a <strong>lasciare il Paese<\/strong> e ha sconsigliato di mettersi in viaggio per l\u2019Ucraina per qualsiasi motivo.<\/p>\n<h3><strong>12\/10 \u2013 14.30 Bombe su un mercato nella zona di Donetsk: almeno 7 i morti<\/strong><\/h3>\n<p>Non si fermano le bombe e purtroppo, ancora una volta, cadono su obiettivi che di militare hanno ben poco. In mattinata, infatti, a essere colpito \u00e8 stato il mercato della citt\u00e0 di Avdiivka, nel distretto di Donetsk. Secondo il governatore locale, l\u2019attacco ha provocato almeno <strong>7 morti e 8 feriti<\/strong>. Intanto, nelle zone liberate sempre nell\u2019Oblast di Donetsk, i militari ucraini continuano a rinvenire fosse comuni e siti di sepolture. Secondo la polizia regionale, sono 35 quelli scoperti nelle zone appena liberate, da cui sono stati riesumati, per ora, circa 120 corpi.<\/p>\n<p><strong>12\/10 \u2013 La lunga notte tra paura e preghiere<\/strong><\/p>\n<p>Non \u00e8 nulla in confronto al bombardamento di luned\u00ec mattina, ma anche durante questa notte le bombe non hanno taciuto sull\u2019Ucraina. In particolare, \u00e8 stata presa di mira ancora un volta la citt\u00e0 di <strong>Zaporizhzhia<\/strong>, dove si trova la ormai famosa centrale nucleare che, per la seconda volta negli ultimi 5 giorni, ha visto interrompersi la fornitura di corrente elettrica ed \u00e8 stata costretta a fare affidamento sui motori di emergenza diesel.<br \/>\nVerso mattina, secondo quanto riportano i media ucraini, le sirene di allarme sono suonate anche <strong>in 8 altre regioni del Paese<\/strong>, e alcune esplosioni sono state avvertite nella regione di Nikolayev e sulla citt\u00e0 di Melitopol. Al momento non si hanno notizie di vittime o di feriti. I problemi pi\u00f9 grossi, al momento, sembrano essere quelli del sistema di distribuzione dell\u2019energia: secondo quanto riferito alla CNN dal ministro ucraino Herman Halushchenko, i continui bombardamenti hanno <strong>colpito circa il 30% delle infrastrutture energetiche<\/strong> del Paese.<br \/>\nSul fronte delle operazioni sul terreno, continua, seppur rallentata, l\u2019avanzata dell\u2019esercito ucriano a sud, dove \u00e8 stata annunciata la riconquista di altre 5 citt\u00e0 nella zona di Kherson. E come capita dall\u2019inizio della liberazione dei territori occupati dai russi, ovunque vengono alla luce orrori e segni di violenze terribili. L\u2019ultimo in ordine di tempo arriva da Lyman, dove in una fossa del cimitero \u00e8 stata <strong>trovato il corpo di una bambina di un anno<\/strong> con evidenti segni di ferite da proiettili.<\/p>\n<h3>11\/10 \u2013 13.00 \u2013 Anche in Moldova sale l\u2019allerta<\/h3>\n<p>Che la situazione in Ucraina sia molto preoccupante, lo si percepisce anche\u2026 guardandola da fuori. In questo senso, la <strong>Moldova<\/strong> \u00e8 fin dall\u2019inizio della guerra il Paese che forse pi\u00f9 di tutti ha sub\u00ecto le ripercussioni del conflitto, mostrando una generosit\u00e0 e una prontezza di accoglienza straordinari. Non a caso, qui si sono concentrati molti dei progetti di Ai.Bi., come la <a href=\"https:\/\/www.aibi.it\/ita\/tenda-aibi-dogana-palanca-isola-speranza\/\">tenda sul confine di Palanca<\/a> per garantire una prima assistenza, o come il <a href=\"https:\/\/www.aibi.it\/ita\/ludobus-della-pace-progetto-aibi-moldova\/\">Ludobus della Pace<\/a> che gira il Paese portando conforto, sostegno e svago ai bambini moldavi e gli ucraini sfollati.<br \/>\n\u00c8 interessante, dunque, capire come hanno vissuto anche in Moldova l\u2019ultimo, terribile, bombardamento, e quale sia la situazione, oggi. Lo abbiamo chiesto a <strong>Tatiana<\/strong>, la donna che si occupa della comunicazione relativa ai progetti di Ai.Bi. nel Paese e che segue da vicino tutte le attivit\u00e0: \u201cAlcuni punti doganali sono stati <strong>chiusi per misure di sicurezza<\/strong> \u2013 racconta. Ma la preoccupazione maggiore \u00e8 stata per i 3 missili che ieri sono stati osservati attraversare lo spazio aereo della Moldova\u201d. Un fatto, questo, riportato da tutti i giornali e che ha visto, naturalmente, una richiesta di spiegazioni a livello istituzionale. Pi\u00f9 dei grossi avvenimenti, per\u00f2, a volte sono i dettagli che raccontano meglio di tutto la situazione che si vive sul territorio e, in questo, Tatiana ne racconta uno a suo modo molto significativo: \u201cIo abito vicino ad una caserma: oggi i soldati non cantano come gli altri giorni. <strong>Per ora c&#8217;\u00e8 solo silenzio<\/strong>\u201d<\/p>\n<h3>11\/10 \u2013 9.00 \u2013 A scuola sotto le bombe<\/h3>\n<p>Il colore dei banchi e dei tappeti morbidi circondati dai pouf sembrano assolutamente <strong>fuori posto<\/strong> in contrasto con il bianco freddo delle pareti e le innaturali luci al neon. Ai muri non ci sono finestre e che gli spazi siano <strong>angusti e limitati<\/strong> lo si capisce anche utilizzando il pi\u00f9 estremo dei grandangoli. Sono le foto di <strong>una scuola<\/strong> arrivate da Kiev. Una scuola che, come tutte le altre, sta cercando di attrezzarsi velocemente per poter continuare a fare lezione e tenere i bambini pi\u00f9 piccoli in sicurezza. Per farlo, non ci sono altri modi che <strong>rifugiarsi sottoterra<\/strong>, dove le bombe si spera non possano arrivare. Sopra la testa passano i tubi dell\u2019acqua e il pavimento \u00e8 rovinato come quello di qualsiasi cantina. I tappeti colorati lo nascondono a malapena e se, con uno sforzo di fantasia, si riesce per un attimo a pensare di essere in una \u201cnormale\u201d aula d\u2019asilo, basta alzare lo sguardo sul banco messo in un angolo, pieno di boccioni di acqua, per capire che il tutto, <strong>normale proprio non \u00e8<\/strong>.<\/p>\n<div id='gallery-2' class='gallery galleryid-197352 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/bombardamento-kiev-scuola4\/'><img loading=\"lazy\" decoding=\"async\" width=\"158\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola4-158x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola4-158x300.jpeg 158w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola4-538x1024.jpeg 538w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola4-79x150.jpeg 79w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola4.jpeg 630w\" sizes=\"auto, (max-width: 158px) 100vw, 158px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/bombardamento-kiev-scuola7\/'><img loading=\"lazy\" decoding=\"async\" width=\"158\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola7-158x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola7-158x300.jpeg 158w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola7-538x1024.jpeg 538w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola7-79x150.jpeg 79w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola7.jpeg 630w\" sizes=\"auto, (max-width: 158px) 100vw, 158px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/bombardamento-kiev-scuola5\/'><img loading=\"lazy\" decoding=\"async\" width=\"158\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola5-158x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola5-158x300.jpeg 158w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola5-538x1024.jpeg 538w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola5-79x150.jpeg 79w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola5.jpeg 630w\" sizes=\"auto, (max-width: 158px) 100vw, 158px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>Eppure, anche qui, risuoneranno le voci dei bambini. Impaurite, inizialmente, ma sempre pi\u00f9 forti via via che lo stare insieme, e l\u2019<strong>infinito, paziente, eroico sforzo delle maestre<\/strong>, far\u00e0 tornare in loro le sensazioni dimenticate di un giorno di scuola come i tanti altri vissuti in un recente passato che appare ormai lontanissimo.<br \/>\nSono anche queste le vittime della guerra: allo stesso modo dei feriti, dei buchi nelle strade, dei ponti crollati e delle corsie svuotate dei supermercati. \u00c8 la follia di una violenza che non guarda in faccia a nulla e a nessuno, che <strong>non tiene in considerazione la vita dei pi\u00f9 piccoli<\/strong> allo stesso modo di quella dei soldati chiamati a combattere un nemico che non hanno cercato e che forse, fino a ieri, non avrebbero faticato a chiamare \u201cfratello\u201d. I bambini, siamo sicuri, sarebbero pronti a farlo anche domani!<\/p>\n<div id='gallery-3' class='gallery galleryid-197352 gallery-columns-2 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/bombardamento-kiev-scuola3\/'><img loading=\"lazy\" decoding=\"async\" width=\"572\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola3-572x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola3-572x300.jpeg 572w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola3-150x79.jpeg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola3-768x403.jpeg 768w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola3.jpeg 1200w\" sizes=\"auto, (max-width: 572px) 100vw, 572px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/bombardamento-kiev-scuola2\/'><img loading=\"lazy\" decoding=\"async\" width=\"571\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola2-571x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola2-571x300.jpeg 571w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola2-150x79.jpeg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola2-768x403.jpeg 768w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola2.jpeg 1200w\" sizes=\"auto, (max-width: 571px) 100vw, 571px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/bombardamento-kiev-scuola\/'><img loading=\"lazy\" decoding=\"async\" width=\"572\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola-572x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola-572x300.jpeg 572w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola-150x79.jpeg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola-768x403.jpeg 768w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola.jpeg 1200w\" sizes=\"auto, (max-width: 572px) 100vw, 572px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/bombardamento-kiev-scuola8\/'><img loading=\"lazy\" decoding=\"async\" width=\"571\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola8-571x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola8-571x300.jpeg 571w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola8-150x79.jpeg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola8-768x403.jpeg 768w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-Scuola8.jpeg 1200w\" sizes=\"auto, (max-width: 571px) 100vw, 571px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n<p><strong>10\/10 \u2013 16.40 \u2013 \u201cKiev . L\u2019assalto ai supermercati: &#8220;Ci asppettano giorni duri &#8220;<\/strong><\/p>\n<p>5 parole ,arrivate via <em>WhatsApp<\/em> da Elena, una delle cooperanti di Ai.Bi. in Ucraina, certificano quella che, da stamattina, era una sensazione diffusa: il massiccio attacco missilistico di oggi in tutta l\u2019Ucraina potrebbe ripetersi ancora in tempi brevi.<br \/>\nTimorosi, abbiamo posto la stessa domanda a Elena, che ha risposto cos\u00ec: \u201cPi\u00f9 che la sensazione, <strong>c\u2019\u00e8 la certezza che stanno arrivando altri attacchi<\/strong>\u201d.<br \/>\nDifficile, da qui, comprendere la situazione. Forse, pi\u00f9 che le foto dei crateri nelle strade, dei feriti e degli incendi (che colpiscono, certo, ma corrono il rischio di far percepire i fatti quasi come un film, troppo distanti dalla nostra realt\u00e0 per essere immediatamente comprensibili), sono significative le <strong>foto scattate all\u2019interno di un supermercato<\/strong>, preso d\u2019assalto, una volta cessato l\u2019allarme pi\u00f9 immediato delle bombe, dalle famiglie impaurite: si fa scorta di quello che pu\u00f2 servire per sopravvivere, con la certezza che nei prossimi giorni sar\u00e0 complicato anche solo poter uscire di casa, o dai rifugi, e poter trovare con facilit\u00e0 nei negozi e nei supermercati i beni di prima necessit\u00e0. Perch\u00e9 la guerra sono i morti e i bambini rimasti orfani, certo, ma sono anche le code al supermercato di <strong>mamme disperate<\/strong> di non poter provvedere alla famiglia e ai propri figli per la follia di una guerra che nessuna di loro ha mai voluto!<\/p>\n<div id='gallery-4' class='gallery galleryid-197352 gallery-columns-2 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/bombardamento-kiev-supermercato5\/'><img loading=\"lazy\" decoding=\"async\" width=\"571\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-supermercato5-571x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-supermercato5-571x300.jpeg 571w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-supermercato5-150x79.jpeg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-supermercato5-768x403.jpeg 768w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-supermercato5.jpeg 1200w\" sizes=\"auto, (max-width: 571px) 100vw, 571px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/bombardamento-kiev-supermercato4\/'><img loading=\"lazy\" decoding=\"async\" width=\"571\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-supermercato4-571x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-supermercato4-571x300.jpeg 571w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-supermercato4-150x79.jpeg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-supermercato4-768x403.jpeg 768w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-supermercato4.jpeg 1200w\" sizes=\"auto, (max-width: 571px) 100vw, 571px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/bombardamento-kiev-supermercato3\/'><img loading=\"lazy\" decoding=\"async\" width=\"571\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-supermercato3-571x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-supermercato3-571x300.jpeg 571w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-supermercato3-150x79.jpeg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-supermercato3-768x403.jpeg 768w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-supermercato3.jpeg 1200w\" sizes=\"auto, (max-width: 571px) 100vw, 571px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/bombardamento-kiev-supermercato\/'><img loading=\"lazy\" decoding=\"async\" width=\"572\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-supermercato-572x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-supermercato-572x300.jpeg 572w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-supermercato-150x79.jpeg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-supermercato-768x403.jpeg 768w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombardamento-Kiev-supermercato.jpeg 1200w\" sizes=\"auto, (max-width: 572px) 100vw, 572px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p><strong>10\/10 \u2013 13.20 \u2013 Lanciati 83 missili sull\u2019Ucraina<\/strong><\/p>\n<p>Dopo qualche difficolt\u00e0 nel riuscire ad avere notizie, Ai.Bi. ha potuto mettersi in contatto anche con <strong>Masha<\/strong>, la cooperante che da anni porta avanti i progetti dell\u2019Associazione in Ucraina e che, allo scoppio della guerra, \u00e8 stata per qualche mese in Italia prima di tornare, appena ha potuto, nella sua Kiev. Anche Mash \u00e8 stata colta di sorpresa dall\u2019ultimo attacco missilistico: \u201cEro in ufficio a un paio di kilometri da dove sono arrivate alcune bombe \u2013 racconta. Prima ancora ero in un parco vicino per allenarmi un po\u2019\u2026 Dopo l\u2019ennesima esplosione, che si sentivano sempre pi\u00f9 vicine, e dopo che lo sbalzo di corrente mi ha fatto spegnere il computer, sono andata via\u201d.<br \/>\nAnche Masha ha confermato i numeri che si leggono nelle ultime notizie: \u201cIn tutto sono stati lanciati sull\u2019Ucraina <strong>83 missili<\/strong>, di cui la met\u00e0 \u00e8 stata intercettata dai sistemi di difesa. A Kyiv di sicuro ne sono caduti almeno una decina\u201d.<\/p>\n<h5>(foto dal profilo Facebook di Alla Nosenko)<\/h5>\n<div id='gallery-5' class='gallery galleryid-197352 gallery-columns-2 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/bombe-kiev-ottobre-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombe-Kiev-ottobre-2-450x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombe-Kiev-ottobre-2-450x300.jpg 450w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombe-Kiev-ottobre-2-150x100.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombe-Kiev-ottobre-2-768x512.jpg 768w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombe-Kiev-ottobre-2-165x109.jpg 165w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombe-Kiev-ottobre-2.jpg 1080w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/bombe-kiev-ottobre\/'><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombe-Kiev-ottobre-450x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombe-Kiev-ottobre-450x300.jpg 450w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombe-Kiev-ottobre-150x100.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombe-Kiev-ottobre-768x512.jpg 768w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombe-Kiev-ottobre-165x109.jpg 165w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/bombe-Kiev-ottobre.jpg 1080w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p><strong>10\/10 &#8211; 10.30<\/strong> &#8211; <strong>Bombardata Kiev. Alemo 8 morti<br \/>\n<\/strong><\/p>\n<p>Dopo qualche mese in cui avevamo abbandonato l&#8217;aggiornamento costante della situazione in Ucraina, non perch\u00e9 la guerra non ci fosse, ma perch\u00e9 abbiamo preferito dare spazio a notizie pi\u00f9 approfondite sui progetti e le storie legate alla speranza di una ripresa della vita e di una resistenza <strong>che giuardasse al futuro<\/strong>, gli ultimi avvenimenti, purtroppo, hanno fatto tornare la cruda cronaca della guerra al centro della scena. Nella mattinata de luned\u00ec 10 ottobre, infatti, le bombe sono tornate a cadere, numerose, su diverse citt\u00e0 dell&#8217;Ucraina in cui da tempo non si vedevano. <strong>Colpita pesantemente anche la capitale Kiev<\/strong>, dove, al momento, si contano almeno 8 morti e 24 feriti. Le esplosioni si sono verificate in una zona non lontana dal centro, vicino al parco Taras Shevchenko, dove si trova anche una sede dell&#8217;Universit\u00e0. Visto l&#8217;orario (mattina presto) le strade erano gi\u00e0 piuttosto trafficate e molta gente si stava recando al lavoro.<br \/>\nSecondo le prime analisi, il bombardamento potrebbe essere una rappresaglia per l&#8217;attacco che, sabato, ha colpito il ponte che collega la Russia alla Crimea.<br \/>\nElena, la cooperante di Ai.Bi. che da pochissimo \u00e8 arrivata a Kiev per seguire i progetti avviati nella capitale ucraina, racconta di &#8220;Tanta confusione e paura in giro. Negozi chiusi, e tanta gente nelle vicinanze della metro&#8221;.<\/p>\n<h5>(foto in apertura Twitter <span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">@MattiMaasikas, capo della delegazione dell&#8217;Unione europea in Ucraina)<\/span><\/h5>\n<p><strong>03\/06 &#8211; 8.15<\/strong> &#8211; <strong>Ogni giorno la guerra in Ucraina uccide oltre 2 bambini. Da 100 giorni<br \/>\n<\/strong><\/p>\n<p>100 giorni di guerra. \u00c8 un triste traguardo quello raggiunto il 3 giugno: 100 giorni di bombe, di morti, di fughe e distruzione. <strong>100 giorni<\/strong> in cui la vita quotidiana delle famiglie ucraine \u00e8 stata stravolta e cambiata per sempre. 100 giorni in cui, come sempre in guerra, i bambini hanno subito le conseguenze pi\u00f9 dure da accettare. Perch\u00e9 \u00e8 vero che i dati finora verificati (e molto sottostimati) dicono che i morti civili sono <strong>oltre 4000<\/strong>, ma leggere che <strong>243<\/strong> di questi sono bambini lascia sgomenti e fa ancora pi\u00f9 male. Si tratta di oltre <strong>2 bambini al giorno<\/strong>, come riportato da un documento di Unicef: 2 bambini strappati alla vita da attacchi con armi esplosive avvenuti in aree densamente abitate, a conferma di come la guerra non si limiti certo agli obiettivi e i contesti militari. Ai morti, infatti, si aggiungono anche <strong>446 feriti<\/strong>, e anche in questo caso si tratta di conteggi difficili da portare a termine e sicuramente inferiori alla realt\u00e0 dei fatti.<br \/>\nMa il dramma dei bambini non finisce qui, perch\u00e9 <strong>10 volte pi\u00f9 dei morti<\/strong> sono i minori che le autorit\u00e0 ucraine denunciano siano stati deportati in Russia, la quale, da parte sua, ammanta questa azione di toni patriottici: \u201cLa Russia far\u00e0 di tutto per sostenere i bambini orfani del Donbass\u201d.<br \/>\nSecondo la viceministra dell&#8217;Interno di Kiev Kateryna Pavlichenko, i bambini deportati dall\u2019inizio della guerra sarebbero <strong>234 mila<\/strong>, e il decreto amanato dal Cremlino per facilitare l\u2019adozione degli orfani del Donbass da parte delle famiglie russe non fa che confermare il vero disegno dietro alla deportazione.<br \/>\nMa il dramma dei bambini si estende anche a chi \u00e8 rimasto in Ucraina, dove, sempre secondo Unicef, ci sono <strong>3 milioni di minori sfollati<\/strong> all\u2019interno del Paese e <strong>2,2 milioni scappati<\/strong> e, ora, profughi in altri Paesi. <strong>Due bambini su tre hanno perso la loro casa<\/strong> e la quotidianit\u00e0 degli affetti e all\u2019orizzonte non appaiono notizie che possano portare a un miglioramento della situazione in tempi brevi.<br \/>\nQualcuno riassume tutto questo con l\u2019espressione \u201cla guerra dei bambini\u201d. Ma, in realt\u00e0, in questa come in tutte le guerre i bambini hanno un solo e unico ruolo: quello delle <strong>vittime innocenti<\/strong>!<\/p>\n<h3>Sostieni l\u2019impegno di Ai.Bi. per i bambini dell\u2019Ucraina<\/h3>\n<p>Dall\u2019inizio della guerra, Ai.Bi. \u00e8 impegnata in molteplici attivit\u00e0 lanciate all\u2019interno del progetto\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/bambinixlapace\/\"><strong>#BAMBINIxLAPACE<\/strong><\/a>, attivo in Ucraina, Moldova e Italia a favore dei bambini ucraini e delle loro famiglie. Chiunque pu\u00f2 sostenerli con una donazione una tantum o con l\u2019Adozione a Distanza. E se sei cliente Fineco, la banca\u00a0<a href=\"https:\/\/finecobank.com\/it\/online\/charity\/emergenza-ucraina\/\"><strong>raddoppia la tua donazione<\/strong><\/a>\u00a0fino al 30 giugno. Ricordati che tutte le donazioni ad Ai.Bi. godono delle seguenti\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/images\/AGEVOLAZIONI_FISCALI.pdf\"><strong>agevolazioni fiscali.<\/strong><\/a><\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*197331-start*\/\n#btnsx-197331{margin-top:0px;margin-bottom:25px;margin-left:0px;margin-right:0px;padding-top:16px;padding-bottom:15px;padding-left:43px;padding-right:44px;}\n#btnsx-197331 .btnsx-text-primary{text-transform:uppercase;font-size:20px;line-height:20px;font-weight:800;font-family:Raleway;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-197331:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-197331{background-color:#dd3333!important;}\n#btnsx-197331:hover{background-color:#d13030!important;}\n#btnsx-197331{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px;}\n#btnsx-197331:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:solid;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px;}\n#btnsx-197331{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-197331:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*197331-end*\/\n<\/style>\n<a href=\"https:\/\/dona.aibi.it\/emergenza-ucraina\/?act=cplt&amp;origine=web-button-in-post\" id=\"btnsx-197331\" class=\"btnsx-btn btnsx-btn-block\"  data-font-primary=\"Raleway\">\n\t<span class=\"btnsx-text-primary \">EMERGENZA UCRAINA<\/span><\/a>\n\n<!-- Buttons X - End -->\n\n<p><strong>26\/05 &#8211; 8.15<\/strong> &#8211;<strong>Sono pi\u00f9 di mille le scuole bombardate dall\u2019inizio della guerra<br \/>\n<\/strong>Avevano scritto la parola &#8220;bambini&#8221; in cirillico, a caratteri cubitali, sulle finestre, ma non \u00e8 stato sufficiente per risparmiarle dai bombardamenti dei soldati russi.<br \/>\nLa tremenda guerra che si sta combattendo ormai da pi\u00f9 di 3 mesi in Ucraina sta tragicamente impattando non solo sulla vita dei pi\u00f9 piccoli, sui loro affetti, sulla loro quotidianit\u00e0, ma anche sulla loro istruzione e sul loro futuro. Il governo ucraino dall\u2019inizio del conflitto ha contato pi\u00f9 di\u00a0mille scuole e strutture educative colpite da bombardamenti. Novantacinque di queste sarebbero state completamente distrutte. Non si ricorda, in altri terribili conflitti, come nell&#8217;ex Jugoslavia o in Siria, un numero cos\u00ec alto di scuole colpite in maniera cos\u00ec larga e sistematica. Colpire una scuola vuol dire colpire il futuro.<br \/>\n&#8220;<em><span style=\"font-weight: 400;\">\u00c8 doloroso rendersi conto di quanti amici sono morti<\/span><\/em>\u2013 racconta una professoressa di Chernihiv come riporta Associated press &#8211; <em>e di quanti bambini sono rimasti soli senza genitori, traumatizzati. Lo ricorderanno per tutta la vita e trasmetteranno le loro storie alla generazione successiva&#8221;.<br \/>\n<\/em>Colpire una scuola, commenta\u00a0<em>Associated Press:<\/em> &#8220;<em>\u00c8 un attacco alla possibilit\u00e0 di una Nazione di ripartire alla fine di una guerra, una ferita inferta per molti anni a venire<\/em>&#8220;.<br \/>\nEcco perch\u00e9 ricostruire le scuole dovrebbe essere una delle prime azioni concrete da fare alla fine della guerra, uno degli obiettivi che si pone il progetto #BAMBINIxLAPACE, al quale anche tu puoi contribuire.<\/p>\n<p><strong>23\/05 &#8211; 13.10 &#8211; Londra: armi alla Moldova affinch\u00e9 sia pronta per un\u2019eventuale attacco russo<br \/>\n<\/strong>MentreNegli ultimi giorni, la guerra in Ucraina, sul campo, non ha registrato novit\u00e0 particolari. Lo scenario delle battaglie \u00e8 sempre pi\u00f9 concentrato nel sud del Paese, dove, come ormai assodato, la Russia concentrer\u00e0 i suoi sforzi per cercare di conquistare quanto pi\u00f9 terreno possibile. E proprio questo \u201cquanto pi\u00f9 terreno possibile\u201d \u00e8 ci\u00f2 che spaventa non solo l\u2019Ucraina ma anche la confinante Moldova, che al suo interno conta gi\u00e0 la presenza di una porzione di territorio separatista e filorusso: la Transnistria. Da Mosca sono gi\u00e0 arrivate alcune dichiarazioni che hanno ribadito anche per quanto riguarda questa zona gli argomenti utilizzati per giustificare l\u2019intervento in Ucraina, di conseguenza l\u2019allerta a Chisinau \u00e8 massima. Ormai da settimane il governo ha ufficialmente chiesto di poter entrare nell\u2019Unione Europea, ma sappiamo bene come la procedura richieda tempi molto lunghi e come, quindi, la mossa sia pi\u00f9 che altro simbolica, per ora. Molto pi\u00f9 immediata e concreta potrebbe essere, invece, la promessa arrivata proprio in questi giorni da Londra, che ha dichiarato di voler fornire armi alla Moldova affinch\u00e9 possa essere pronta in caso di attacco della Russia.<br \/>\nPer il momento, il piccolo Stato che conta il maggior numero di profughi ucraini pro capite e che ha dimostrato una straordinaria organizzazione per accogliere gli sfollati, prosegue con le sue attivit\u00e0 \u201cdi prima linea\u201d nell\u2019emergenza, cercando di tenere a bada la paura che la guerra possa anch\u2019essa varcare presto i confini.<\/p>\n<p><strong>19\/05 &#8211; 18.00 -La piccola Moldova dall\u2019inizio della guerra ha accolto pi\u00f9 di 400 mila rifugiati.<br \/>\n<\/strong>Mentre la guerra in Ucraina continua, al confine, la piccola Moldova, il Paese pi\u00f9 povero dell\u2019Europa, ma dal cuore davvero grande, continua la sua opera di accoglienza ed assistenza alla popolazione in fuga dalla guerra: \u201cAbbiamo accolto \u2013 ha spiegato Natalia Gavrilita, premier della Moldova,\u00a0in un\u2019intervista sul Corriere della Sera- pi\u00f9 di 400 mila rifugiati. Circa 100 mila sono rimasti in Moldavia e quasi la met\u00e0 sono bambini. Tutto questo \u00e8 stato possibile grazie a uno sforzo enorme e alla solidariet\u00e0 della societ\u00e0, ma ha anche significato togliere risorse finanziarie ad altri progetti in corso\u201d.<\/p>\n<p style=\"font-weight: 400;\">In Moldova \u00e8 davvero difficile rimanere tranquilli con ai suoi confini una regione separatista come la Transnistria, nella quale da fine\u00a0aprile\u00a0alcune esplosioni hanno alzato il livello di allarme. Ma la premier della Moldova continua ad invitare alla pace e alla calma.<\/p>\n<p style=\"font-weight: 400;\">Alla domanda su chi, secondo lei, sia il mandante di quelle esplosioni,\u00a0<span style=\"font-weight: 400;\">Natalia Gavrilita\u00a0<\/span>ha spiegato: \u201cUna cosa mi \u00e8 chiara: questi incidenti sono causati da parti interessate che cercano di destabilizzarci e trascinarci in una guerra indesiderata. Sono attacchi mascherati per creare panico e insicurezza\u201d.<\/p>\n<p style=\"font-weight: 400;\">\u201cDall\u2019inizio del conflitto il livello d\u2019ansia \u00e8 molto aumentato. Tanti cittadini sentono le bombe che cadono su Odessa, Vinnytsia o Zhmerynka. Siamo determinati a fare il possibile per mantenere la calma e non permettere a terzi di rompere il nostro equilibrio\u201d.<\/p>\n<p style=\"font-weight: 400;\">[\u2026] \u201cCi auguriamo di poter procedere nel processo di integrazione e trovare una soluzione pacifica a questa situazione\u201d.<\/p>\n<p><strong>17\/05 &#8211; 21.55 &#8211; Sono 4 mila i minori stranieri non accompagnati giunti in Italia dall\u2019Ucraina<br \/>\n<\/strong>L\u2019ultimo dato noto indicava in quasi <strong>4 mila<\/strong> i minori stranieri non accompagnati provenienti dall\u2019Ucraina presenti in Italia, su un totale, aggiornato al 16 maggio, di <strong>39.458 minori<\/strong> (116.499 il totale delle persone arrivate in Italia). Sostanzialmente, dunque, si pu\u00f2 dire che un minore su dieci di quelli che arrivano dall\u2019Ucraina \u00e8 non accompagnato. Serve ricordare che tale definizione comprende tutti i minori che arrivano con un adulto che non sia un proprio genitore e non sia un tutore ufficialmente riconosciuto dalla legge italiana. Questo con le conseguenze e le incomprensioni che ci possono essere per quanto riguarda i bambini delle case \u2013 famiglia, come gi\u00e0 ampiamente raccontato sul sito di Ai.Bi.<br \/>\nLe ultime disposizioni hanno stanziato per l\u2019accoglienza di questi minori un fondo di 58 milioni di euro, che verranno distribuiti ai Comuni che, a loro volta, rimborseranno le strutture di accoglienza in cui i minori verranno accolti. Il rimborso pensato dal Governo ammonta a 100 euro al giorno per minore.<br \/>\nL\u2019ondata di MISNA arrivata in seguito allo scoppio della guerra ha portato l\u2019Ucraina a essere il terzo Paese di provenienza dei minori non accompagnati in Italia; un balzo notevole, se si considera che nel report precedente, relativo al mese di febbraio, il Paese non era nemmeno presente.<br \/>\nCome sottolinea Vita nella sua analisi, \u201cGli arrivi dall\u2019Ucraina hanno cambiato anche il profilo dei MSNA: la <strong>presenza femminile<\/strong> in un mese \u00e8 salita dal 2,8% all\u20198,4% mentre l\u2019et\u00e0 media si \u00e8 abbassata\u201d. Crescono in particolare le fasce d\u2019et\u00e0 al di sotto dei 6 anni (da 0,3% a 1,1%) e quella tra 7 e 14 anni (da 5% al 10,9%). Calano gli adolescenti, scesi dal 64,3% al 59,3%.<br \/>\nPer tutti coloro che fossero interessati ad aprirsi all&#8217;accoglienza dei minori e delle famiglie ucraine, Faris &#8211; Family Relationship International School organizza dei webinar gratuiti nell&#8217;ambito della campagna <strong>#BAMBINIXLAPACE.\u00a0<\/strong> Il prossimo appuntamento in programma \u00e8 per il 25 maggio alle ore 18:00. Tutte le informazioni <a href=\"https:\/\/www.fondazioneaibi.it\/faris\/prodotto\/10394\/\">QUI<\/a><\/p>\n<p><strong>12\/05 &#8211; 15.35 &#8211; La sfida degli sfollati interni<br \/>\n<\/strong>Se i profughi che hanno lasciato l&#8217;Ucraina sono quasi 6 milioni, quelli che hanno lasciato la loro casa per fermarsi in altre aree del Paese (i cosiddetti &#8220;sfollati interni&#8221;) sono circa 7 milioni. Un numero impressionante, che corrisponde quasi a un sesto della popolazione totale dell&#8217;Ucraina, che chiama politici locali, popolazione, volontari e associazioni a uno sforzo enorme. Perch\u00e9 a queste persone non va solo garantita l&#8217;accoglienza e una risposta di prima emergenza, ma va data loro anche una prospettiva di futuro: un lavoro per gli adulti, una scuola per i pi\u00f9 piccoli, una casa dove abitare, forse, per anni&#8230; Si tratta di un impegno collettivo a cui tanti si stanno gi\u00e0 dedicando e che chiamer\u00e0 a raccolta sempre pi\u00f9 forze nel corso dei prossimi mesi. Anche Ai.Bi. sta gi\u00e0 pensando a questo futuro ed \u00e8 pronta ad attivare i &#8220;punti Ai.Bi.&#8221; in diverse parti dell&#8217;Ucraina: luoghi sicuri, colorati, con personale dedicato, dove i bambini possono giocare, socializzare e, apprunto, trovare una nuova spinta verso il futuro. D&#8217;altra parte \u00e8 proprio questo il senso dell&#8217;Adozione a Distanza che Ai.Bi. ha prmosso gi\u00e0 da tempo per l&#8217;Ucraina: dare un contributo che non si limiti all&#8217;emergenza del momento, ma guardi gi\u00e0 al tempo che verr\u00e0 e alle grandi sfide cui, insieme bisogner\u00e0 rispondere.<\/p>\n<p><strong>10\/05 &#8211; 17.50 &#8211; Ancora bombe su Odessa<br \/>\n<\/strong>Gli esperti dell&#8217;intelligence dicono che la guerra in Ucraina \u00e8 in stallo, ma in diverse zone del Paese le bombe continuano a cadere, specie vero Odessa. Ieri, per sicurezza, anche in vista della ricorrenza del 9 maggio, Giorno della Vittoria festeggiato dai russi, la dogana di Palanca \u00e8 stata chiusa e anche <a href=\"https:\/\/www.aibi.it\/ita\/bambinixlapace-ai-bi-moldova-accoglie-una-nuova-collega-jana\/\">Jana<\/a>, la collaboratrice di Ai.Bi. Moldova, che era andata in Ucraina per trovare il pap\u00e0 in occasione del suo compleanno, \u00e8 rimasta bloccata nel Paese. Le foto e i video che ha mandato, purtroppo, non sono molto rassicuranti, con le bombe sul lungomare della citt\u00e0 e le trincee scavate nelle campagne circostanti a difesa del territorio.<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/s6o4kBgYIiM\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><strong>10\/05 &#8211; 13.40 &#8211; Quasi 23 mila gli studenti ucraini accolti in Italia<br \/>\n<\/strong>Un report del Ministero dell&#8217;Istruzione riportato dal Corriere della Sera rende noto che dall&#8217;inizio della guerra in Ucraina gli studenti accolti in italia sono 22.788. La regione dove se ne trova il maggior numero \u00e8 la Lombardia, seguida da Emilia &#8211; Romagna e Campania. La fascia d&#8217;et\u00e0 pi\u00f9 rappresentata \u00e8 quella delle scuole elementari, con 10.399 studenti. Seguono scuola media (5.226), asilo (5.060) e superiori (2.103).<\/p>\n<p><strong>10\/05 &#8211; 10.50 &#8211; Missili ipersonici su Odessa<br \/>\n<\/strong>La Russia continua a colpire in diverse zone dell&#8217;Ucraina. In particolare, la citt\u00e0 di Odessa \u00e8 stata bombardata anche con quelli che secondo il portavoce militare della regione di Odessa, Sergey Bratchuk, sarebbero tre missili ipersonici. Tra le strutture colpite anche un hotel e un centro commerciale.<br \/>\nA Mariupol, invece, nonostante quanto annunciato nei giorni scorsi dallo stesso Zelensky, le autorit\u00e0 ucraine hanno segnalato la presenza nell&#8217;acciaieria ancora di un centinaio di civili.<\/p>\n<p><strong>9\/05 &#8211; 16.00 &#8211; Morti 226 bambini dall&#8217;inizioa della guerra<br \/>\n<\/strong>Le autorit\u00e0 di Kiev, in un messaggio su Telegram, hanno aggiornato il numero dei bambini morti dall&#8217;inizio della guerra in Ucraina. AL momento, i decessi confermati sono 226, a cui si aggiungono 415 feriti. Purtroppo, per\u00f2, si tratta di cifre non definitive, in quanto sono in corso diverse verifiche in luoghi pi\u00f9 difficili da raggiungere e nei territori occupati. La regione che ha subito pi\u00f9 perdite \u00e8 quella di Donetsk, dove si contano 139 morti e feriti. 116 le vittime nella regione di Kiev.<br \/>\nLe autorit\u00e0 sottolineano anche che 1.635 strutture educative hanno sub\u00ecto danni ingenti e 126 di queste sono state \u201ccompletamente distrutte\u201d.<\/p>\n<p><strong>9\/05 &#8211; 12.00 &#8211; Il discorso di Putin per il Giorno della Vittoria<br \/>\n<\/strong>Si \u00e8 tenuto sulla Piazza Rossa di Mosca l&#8217;atteso discorso di Vladimir Putin per celebrare il Giorno della Vittoria. Dopo la parata militare, senza gli aerei che avrebbero dovuto disegnare una &#8220;Z&#8221; in volo (non si sono alzati causa maltempo), il discorso del Presidente ha esaltato, come ci si aspettava, i temi pi\u00f9 nazionalistici e anti-occidentali, specie contro gli Stati Uniti, ma non ha annunciato quella escalation che alcuni temevano. Putin ha giustificato l&#8217;azione militare (che \u00e8 rimasta nel discorso una &#8220;operazione speciale&#8221;) come una &#8220;decisione corretta e tempestiva da prendere&#8221; per anticipare le intenzioni della NATO di un attacco nel Donbass.<br \/>\nLa parte pi\u00f9 dura del discorso \u00e8 stata quello rivolta agli USA, tornati a essere il nemico numero uno come ai tempi della guerra fredda. Ma &#8211; ha ribadito Putin . la Russia non si piega a questo &#8220;degrado morale&#8221; dell&#8217;Occidente e ribadisce la sua tradizione, la sua indipendenza e i suoi valori.<br \/>\nInsomma, si pu\u00f2 dire che il discorso ha ribadito quanto pi\u00f9 volte gi\u00e0 si \u00e8 sentito, esaltando la retorica nazionalista. Il fatto, per\u00f2, che non ci sia stato l&#8217;annuncio di un inasprimento del conflitto, n\u00e9 tantomeno una ufficiale dichiarazione di guerra, \u00e8 stato visto da tutti gli osservatori come un segnale positivo.<\/p>\n<p><strong>7\/05 &#8211; 13.15 &#8211; Riprese le avacuazioni dall&#8217;acciaieria di Mariupol<br \/>\n<\/strong>Ieri sono stati messi in salvo altre 50 persone, tra cui 11 bambini, ma anche oggi dovrebbe proseguire l&#8217;evacuazione dall&#8217;acciaieria Azovstal di Mariupol, con il Presidente dell&#8217;Ucraina Zelensky che ha dichiarato di stare lavorando a &#8220;Opzione diplomatiche&#8221; per poter mettere in salvo anche i militari.<br \/>\nSu altri fronti, da segnare che questa mattina presto ci sono state delle esplosioni in Transnistria, vicino al villaggio di Varancau, come ha reso noto il Ministero dell\u2019Interno della regione separatista della Moldova.<\/p>\n<p><strong>7\/05 &#8211; 10.20 &#8211; Un sito per rintracciare le persone scomparse<br \/>\n<\/strong>Proseguono gli scontri e, con essi, le dichiarazioni e le smentite reciproche di Russia e Ucraina su obiettivi colpiti e territori conquistati. Al momento, la strategia di Mosca pare quella di voler danneggiare il pi\u00f9 possibile le infrastrutture di tutto il Paese, cos\u00ec da complicare la consegna e il trasporto delle armi promesse dai Paesi dell&#8217;Occidente. Intanto, nei territori pi\u00f9 vicini a Kiev, da giorni ormai liberati dall&#8217;occupazione russa, continuano a emergere storie terribili di torture, stupri e molte deportazioni: i politici dei vari villaggi stanno cercando di rendicontare le persone che mancano all&#8217;appello e che in molti casi sono state deportate in Russia per essere utilizzate come &#8220;scambio&#8221; con altri prigionieri. \u00c8\u00a0stato creato anche <a href=\"https:\/\/mrpl.life\/\" target=\"_blank\" rel=\"noopener\">un sito<\/a> in cui si trovano le foto delle persone scomparse per facilitarne il ritrovamento.<\/p>\n<p><strong>6\/05 &#8211; 17.10 &#8211;\u00a0 109.325 i profughi arrivati in Italia dall&#8217;Ucraina<br \/>\n<\/strong>Consueto aggiornamento del Viminale sui profughi arrivati in Italia dall&#8217;Ucraina dall&#8217;inizio del conflitto. Secondo il dato aggiornato a venerd\u00ec 6 maggio alle ore 10.57, il totale degli sfollati che hanno raggiunto il nostro Paese \u00e8 di <strong>109.325<\/strong>. Di questi, le donne sono 56.817, gli uomini 14.576 e i minori 37.932.<br \/>\nL&#8217;incremento nelle ultime 24 ore \u00e8 stato di 928 ingressi.<br \/>\n(Immagine in apertura Ministero degli Interni)<\/p>\n<p><strong>6\/05 &#8211; 16.30 &#8211;\u00a0 Pace possibile anche con la Crimea in mano ai russi<br \/>\n<\/strong>Da tempo, ormai, la speranza che si arrivi a un cessate il fuoco attraverso la diplomazia pare molto remota. Ma il Presidente ucraino Zelensky, oggi, in un intervenento alla Chatham House, think tank britannico con sede a Londra, ha esplicitato un&#8217;apertura importante: ovvero che &#8211; come riporta il <em>Corriere della Sera<\/em> &#8211; l\u2019Ucraina sarebbe disposta a un accordo di pace che prevedesse un ritorno alle &#8220;posizioni del 23 febbraio&#8221;, ovvero il giorno prima dell&#8217;inizio delle ostilit\u00e0. Ci\u00f2 significherebbe non avanzare pretese nei confronti della Crimea e, in un certo modo, anche essere disponibili a trattare sui territori di Doneck e Lugansk, che in quella data erano s\u00ec territorio ucraino ma, di fatto, controlati dai filorussi.<\/p>\n<p><strong>6\/05 &#8211; 11.20 &#8211;\u00a0 Dall&#8217;inizio della guerra almeno 3238 civili hanno perso la vita. Ma i numeri reali<br \/>\n<\/strong>&#8220;L&#8217;acciaieria di Mariupol \u00e8 l&#8217;inferno!&#8221;. Cos\u00ec il Presidente ucraino Zelensky nel suo messaggio odierno, dove ha sottolineato come all&#8217;interno di Azovstal siano presenti ancora bambini e circa 200 civili.<br \/>\nMa questo non ferma i combattimenti, che, anzi, si intensificano con l&#8217;obiettivo di piegare l&#8217;ultima sacca di resistenza ucraina in citt\u00e0.<br \/>\nIntanto, il portavoce del segretario generale delle Nazioni Unite, Stephane Dujarric, a un programma radiofonico della BBC ha raccontato le condizioni di chi \u00e8 riuscito a lasciare l&#8217;acciaieria: &#8220;Le\u00a0mie persone sul terreno, sui bus con loro, mi dicono che queste persone hanno traumi profondi, profonde cicatrici psicologiche&#8221;. Conseguenze inevitabili di settimane vissute sotto le bombe, con poca acqua, poco sibo e nell&#8217;oscurit\u00e0.<\/p>\n<p><strong>5\/05 &#8211; 11.21 &#8211;\u00a0 Dall&#8217;inizio della guerra almeno 3238 civili hanno perso la vita. Ma i numeri reali potrebbero essere pi\u00f9 alti<br \/>\n<\/strong>Dall&#8217;inizio della guerra, secondo i dati riportati dall\u2019Ufficio dell\u2019Alto Commissario delle Nazioni Unite per i diritti umani, sarebbero 3.238 i civili ad aver perso la vita. Numeri impressionanti che potrebbero essere nella realt\u00e0 ancora pi\u00f9 alti. Secondo i dati confermati dalle Nazioni Unite, e riportati dal Corriere della Sera, dal 24 febbraio, data dell&#8217;invasione russa in Ucraina: \u201csono stati uccisi circa 1.162 uomini, circa 738 donne, 84 ragazzi e 71 ragazze. Mentre il genere di 72 bambini e 1.111 adulti non \u00e8 ancora stato determinato. Tra i 3.397 feriti ci sono 82 ragazzi e 71 ragazze, oltre a 169 bambini il cui sesso non \u00e8 ancora stato confermato&#8221;.<\/p>\n<p><strong>4\/05 &#8211; 19.15 &#8211; Nessun accordo per il Papa a Mosca<br \/>\n<\/strong>Dopo l&#8217;intervista di ieri a Papa Francesco apparsa sul Corriere della Sera, in cui il Pontefice si era detto &#8220;pronto&#8221; ad andare a Mosca a incontrare Putin, il Cremlino ha fatto sapere che, al momento, non \u00e8 stato raggiunto alcun accordo per una possibile visita. Una precisazione che, seppur dosando le parole per non opporre un &#8220;no&#8221; secco, chiarisce ancora una volta quanto siano lontane le posizioni e, soprattutti, quanto poco sia disposta Mosca a qualsiasi dialogo in ottica di una possibile pace.<\/p>\n<p><strong>4\/05 &#8211; 16.15 &#8211; Il sacrificio di un ragazzo di 14 anni<br \/>\n<\/strong>Nelle pieghe della guerra si nascondono sempre anche fatti (tristemente) eroici. Come quello raccontato dall&#8217;Arcivescovo di Kiev e riportato dal Corriere della Sera, che ha scritto come nel bombardamento del 2 maggio a Odessa, al suono delle sirene un ragazzo di 14 anni si sia precipitato dai vicini anziani per avvisarli e aiutarli a metterli in salvo. L&#8217;operazione \u00e8 riuscita, ma il ragazzo, purtroppo, \u00e8 rimasto ucciso. &#8220;L&#8217;atto eroico di questo adolescente &#8211; si legge sul Corriere &#8211; &#8216;che sacrifica la sua vita per salvare i suoi anziani vicini dai missili russi nella citt\u00e0 ucraina di Odessa, apre una nuova pagina dell&#8217;eroica testimonianza che il popolo ucraino d\u00e0 oggi al mondo intero&#8217;.&#8221;<\/p>\n<p><strong>4\/05 &#8211; 12.20 &#8211; Colpita la Transcarpazia<br \/>\n<\/strong>Non si fermano gli attacchi russi su tutto il territorio dell&#8217;Ucraina. Mariupol, ormai, &#8220;non fa notizia&#8221;, visto che viene ininterrottamente colpita da settimane. Le bombe ormai colpiscono con continuit\u00e0 anche Odessa e, per la prima volta, sono arrivate anche in\u00a0Transcarpazia, regione al confine con l&#8217;Ungheria finora non toccata dallle bombe. Obiettivo dell&#8217;attacco pare essere stato un collegamento ferroviario vicino alla stazione di Vollovets. Non ci sono ancora notizie di morti o feriti.<\/p>\n<p><strong>3\/05 &#8211; 17.10 &#8211; Oltre 106 mila profughi in Italia<br \/>\n<\/strong>Nuovo aggiornamento del numero dei profughi arrivati in Italia dall&#8217;Ucraina dall&#8217;inizio della guerra: alle 13:56 di marted\u00ec 3 maggio il Ministero dell&#8217;Interno conta un totale di 106.597 persone. Di queste, 55.261 sono donne, seguite da 37.428 minori e 13.908 uomini.<br \/>\nLa crescita nelle ultime 24 ore \u00e8 stata di 638 unit\u00e0.<\/p>\n<p><strong>3\/05 &#8211; 16.15 &#8211; Evacuati 101 civili da Mariupol<br \/>\n<\/strong>Osnat Lubrani, coordinatore umanitario dell&#8217;ONU per l&#8217;Ucraina, ha annunciato l&#8217;arrivo a Zaporizhzhia di 101 civili evacuati dall&#8217;acciaieria Azovstal di Mariupol. Il corridoio umanitario ha finalmente retto e, al convoglio partito da Mariupol, si sono via via unite altre persone dalle zone incrociate lungo il percorso. Nessuna notizia, invece, al momento, degli altri 11 pullman che il sindaco di Mariupol ha riferito essere partiti dalla citt\u00e0, oggi, e di cui ha denunciato si siano perse le tracce.<\/p>\n<p><strong>3\/05 &#8211; 10.00 &#8211; Papa Francesco pronto a incontrare Putin<br \/>\n<\/strong>Oggi il <em>Corriere della Sera<\/em> pubblica una lunga intervista del direttore Luciano Fontana a Papa Francesco nella quale il Pontefice si dice &#8220;pronto&#8221; a incontrare Putin: &#8220;Ho chiesto al cardinale Parolin&#8221; &#8211; si legge nell&#8217;intervista &#8211; di far &#8220;arrivare a Putin il messaggio che io ero disposto ad andare a Mosca&#8221;. Un&#8217;apertura che \u00e8 ancora in attesa di una risposta e per la quale &#8211; dice il Papa: &#8220;Stiamo ancora insistendo&#8221;. Lo stesso Begoglio, per\u00f2, lascia trasparire un certo pessimismo, perch\u00e9, per poter davvero organizzare l&#8217;incontro, sarebbe necessario che Putin conceda &#8220;qualche finestrina&#8221;, cosa che finora non \u00e8 mai avvenuta. Da qui la conclusione disincantata: &#8220;Temo che Putin non possa e voglia fare questo incontro in questo momento&#8221;.<br \/>\nNella stessa intervista Papa Francesco ribadisce che, per il momento, non ha intenzione di andare a Kiev, dove ha inviato i cardinali Michael Czerny e Konrad Krajewski: &#8220;Io sento che non devo andare. Io prima devo andare a Mosca, prima devo incontrare Putin. Ma anche io sono un prete, che cosa posso fare? Faccio quello che posso. Se Putin aprisse la porta&#8230;&#8221;.<\/p>\n<p><strong>2\/05 &#8211; 18.20 &#8211; Bombardata Odessa<br \/>\n<\/strong>Mentre l&#8217;Europa discute delle prossime sanzioni che dovrebbero comprendere l&#8217;embrago del petrolio russo, in Ucraina proseguono i bombardamenti. In particolare \u00e8 stata colpita la citt\u00e0 di Odessa, con i russi che rivendicano di aver colpito la pista di un aeroporto militare e un hangar in cui ci sarebbero state armi e munizioni.<\/p>\n<p><strong>2\/05 &#8211; 15.10 &#8211; Oltre 105 mila i profughi arrivati in Italia<br \/>\n<\/strong>Il Ministero degli Interni ha nuovamente aggiornato il numero dei profughi arrivati in Italia dall&#8217;Ucraina dall&#8217;inizio della guerra: sono <strong>105.959<\/strong> in totale. Nel dettaglio: 54.909 donne, 13.738 uomini e 37.312 minori.<br \/>\nGli ingressi avvenuti nelle ultime 24 ore sono stati\u00a0542.<\/p>\n<p><strong>2\/05 &#8211; 11.45 &#8211; 219 i bambini morti dall&#8217;inizio della guerra<br \/>\n<\/strong>Dopo l&#8217;evacuazione di ieri, l&#8217;Ucraina ha fatto sapere che ci sarebbero ancora 200 persone all\u2019interno dell\u2019acciaieria Azovstal a Mariupol. Nella notte sono proseguiti gli scontri.<br \/>\nIntanto, il procuratore generale di Kiev ha aggiornato il numero dei bambini rimasti uccisi dall&#8217;inizio della guerra: sono 219, cui si aggiungono 405 feriti. Il conto pi\u00f9 salato lo paga la regione di Donetsk, dove le vittime tra i minori sono state 139.<br \/>\nAggiornamento anche sul fronte profughi, con l&#8217;UNHCR che stima in 5,5 milioni il numero dei profughi che hanno lasciato l&#8217;Ucraina dall&#8217;inizio della guerra.<\/p>\n<p><strong>1\/05 &#8211; 8.27 &#8211; Missili russi su Odessa. Acciaieria Azovstal a Mariupol: evacuati 25 civili<br \/>\n<\/strong>Nel tardo pomeriggio di sabato missili russi hanno colpito la citt\u00e0 ucraina di Odessa. Nell&#8217;attacco, riferisce il governatore della citt\u00e0 Maksym Marchenko su Telegram, come riportato da AdnKronos, \u00e8 stata distrutta la pista dell&#8217;aeroporto locale, senza causare vittime o feriti. Le autorit\u00e0 cittadine hanno gi\u00e0 proclamato il coprifuoco dalle 22 di oggi, domenica 1\u00b0 maggio alle 17 del 3.<br \/>\nA Mariupol, secondo quanto riporta l&#8217;agenzia stampa russa Tass, 25 civili tra cui 6 minori di 14 anni, sono usciti dall&#8217;acciaieria Azovstal, ma, riferisce l&#8217;Ansa, i piani per la completa evacuazione faticano a partire. Nell&#8217;acciaieria rimarrebbero ancora centinaia di civili ed alcuni militari ucraini.<\/p>\n<p><strong>30\/04 &#8211; 17.20 Sale a 104.577 il numero dei profughi ucraini giunti a oggi in Italia<br \/>\n<\/strong>Sale a 104.577 il numero dei profughi ucraini giunti fino ad oggi in Italia. Secondo i dati segnalati dal Viminale, 54.111 sono donne, 13.426 uomini e 37.039 minori. Le citt\u00e0 di destinazione dichiarate all&#8217;ingresso in Italia sono ancora Milano, Roma, Napoli e Bologna. L&#8217;incremento, rispetto a ieri, \u00e8 di 623 ingressi nel territorio nazionale.<br \/>\n(Immagine Ministero degli Interni)<\/p>\n<p><strong>30\/04 &#8211; 9.53-\u00a0 \u00c8 online la piattaforma della Protezione Civile, per richiedere il contributo di sostegno economico<br \/>\n<\/strong>\u00c8 online la piattaforma del Dipartimento della Protezione Civile che permette ai profughi ucraini giunti in Italia, che abbiano presentato domanda di permesso di soggiorno per protezione temporanea, di richiedere il contributo di sostentamento per s\u00e9, per i propri figli e per i minori di cui abbiano tutela legale.<br \/>\nIl contributo, che ha l\u2019obiettivo di offrire un primo sostegno economico in Italia, \u00e8 destinato, come si legge sulla piattaforma, a chi ha trovato una sistemazione autonoma, anche presso parenti, amici o famiglie ospitanti e viene riconosciuto per un massimo di tre mesi dalla data riportata sulla ricevuta di presentazione della domanda di permesso di soggiorno per protezione temporanea.<br \/>\nPer maggiori informazioni \u00e8 possibile consultare il sito della Protezione Civile <a href=\"https:\/\/contributo-emergenzaucraina.protezionecivile.gov.it\/#\/\">QUI<\/a><\/p>\n<p><strong>29\/04 &#8211; 17.00 &#8211; Coprifuoco a Odessa<br \/>\n<\/strong>LE autorit\u00e0 di Odessa hanno proclamato un coprifuoco dalle ore 22 del primo maggio alle 5 del mattino del 3 maggio. La situazione nella zona \u00e8 sempre pi\u00f9 tesa, con il carburante che sta ormai scarseggiando e il razionamento di un massimo di 10 litri ad autovettura.<\/p>\n<p><strong>29\/04 &#8211; 14.30 &#8211; Mattarella: &#8220;Il traguardo \u00e8 la pace&#8221;<br \/>\n<\/strong>Il Presidente della Repubblica Sergio Mattarella ha visitato l\u2019Istituto Salesiano &#8220;G.Bearzi&#8221; di Udine, la scuola di Lorenzo Parelli, il ragazzo che il 21 gennaio scorso perse la vita in un incidente mentre svolgeva l\u2019ultimo giorno di tirocinio in una fabbrica di Lauzacco. Nel discorso tenuto agli studenti, i docenti e le autorit\u00e0 nella palestra della scuola, Mattarella ha fatto un richiamo anche alla situazione in Ucraina, sottolineando il dovere di sostenere la resistenza del popolo ucraino, ma ribadendo che &#8220;Il traguardo di umanit\u00e0 a cui \u00e8 necessario tendere resta la pace. Ben lo sanno i giovani, ai quali la Repubblica, in questi 76 anni, ha saputo assicurare la pace. La pace, che \u00e8 inscindibilmente connessa alla libert\u00e0, al diritto, alla giustizia, allo sviluppo nel benessere dei nostri Paesi e delle nostre citt\u00e0&#8221;.<br \/>\n<a href=\"https:\/\/www.quirinale.it\/elementi\/67122\" target=\"_blank\" rel=\"noopener\">QUI<\/a> il discorso completo di Sergio Mattarella<\/p>\n<p><strong>29\/04 &#8211; 09.50 &#8211; Bombe su Kiev durante la visita del Segretario Generale dell&#8217;ONU<br \/>\n<\/strong>Non \u00e8 stato il bombardamento pi\u00f9 violento n\u00e9, per fortuna, il pi\u00f9 sanguinoso, ma probabilmente \u00e8 stato il pi\u00f9 significativo e preoccupante quello avvenuto ieri poemriggio: 5 missili lanciati dai russi si un edificio residenziale di Kiev proprio mentre era presente in citt\u00e0 il segretario generale dell&#8217;Onu Antonio Guterres. Un vero e proprio &#8220;schiaffo&#8221; agli sforzi della diplomazia di trovare una soluzione al conflitto. Lo stesso Guterres si \u00e8 definito &#8220;scioccato&#8221;, mentre l&#8217;alto rappresentante per la politica estera UE Josep Borrell ha rincarato la dose in un tweet scritto durante la notte: &#8220;Scioccato e sconvolto per l&#8217;attacco missilistico russo su Kiev e altre citt\u00e0 ucraine. La Russia dimostra ancora il suo sfacciato disprezzo per il diritto internazionale bombardando una citt\u00e0 mentre il segretario generale delle Nazioni Uniti Antonio Guterres \u00e8 presente, nello stesso momento del primo ministro bulgaro Kiril Petkov&#8221;.<\/p>\n<p><strong>28\/04 &#8211; 15.15 &#8211; 5,4 milioni di rifugiati<br \/>\n<\/strong>Anche l&#8217;UNHCR (Alto commissariato delle Nazioni Unite per i rifugiati) ha aggiornato il suo conteggio sui profughi che hanno lasciato l&#8217;Ucraina dall&#8217;inizio del conflitto: sono 5.372.854. 55 mila lo hanno fatto nelle ultime 24 ore.<\/p>\n<p><strong>28\/04 &#8211; 12.40 &#8211; Oltre 102 mila profughi in Italia<br \/>\n<\/strong>Nuovo aggiornamento sui numeri dei profughi arrivati finora in Italia dall&#8217;Ucraina. Secondo quanto riportato dal Viminale, alle 10:53 di Gioved\u00ec 28 aprile le persone entrate in Italia in fuga dalla guerra sono 102.654. Di queste,\u00a053.132 sono donne, 12.958 uomini e 36.564 minori.<br \/>\nL&#8217;incremento nelle ultime 24 ore \u00e8 di 882 nuovi ingressi<\/p>\n<p><strong>28\/04 &#8211; 12.25 &#8211; Cresce la tensione<br \/>\n<\/strong>Purtroppo la giornata odierna registra un aumento della tensione e del tono delle dichiarazioni, da una parte e dall&#8217;altra. La Nato, per bocca del segretario generale Jens Stoltenberg ha detto di essere pronta ad accogliere &#8220;a braccia aperte&#8221; Svezia e Finlandia all&#8217;interno dell&#8217;alleanza. La Russia, da parte sua, continua a interpretare queste aperture come provocazioni e ribadisce di essere pronta a rispondere con mezzi &#8220;fionra mai utilizzati&#8221;.<br \/>\nSul campo, intanto, proseguono i bombardamenti, sia verso Mariupol (dove oggi l&#8217;ONU ta provando a organizzare un nuovo corridoio umanitario) sia su depositi di armi e altre citt\u00e0 dell&#8217;est del Paese.<\/p>\n<p><strong>27\/04 &#8211; 18.15 &#8211; Oltre 101mila profughi arrivati in Italia dall&#8217;Ucraina<br \/>\n<\/strong>Nuovo aggiornamento sul numero di profughi arrivati finora in Italia dall&#8217;Ucraina. Secondo i dati del Viminale sono 101.772, di cui\u00a052.623 donne, 12.747 uomini e 36.402 minori. L&#8217;incremento nelle ultime 24 ore \u00e8 di &#8220;soli&#8221; 568 ingressi.<br \/>\n(foto in apertura &#8211; Avvenire &#8211; L&#8217;ego Hub)<\/p>\n<p><strong>27\/04 &#8211; 14.35 &#8211; Sale la paura in Transnistria<br \/>\n<\/strong>Anche oggi non sono mancate le esplosioni e gli attacchi di natura &#8220;misteriosa&#8221; in Transnistira, (territorio separatista filorusso della Moldova), e anche oggi non sono mancate le reciproche accuse, con Mosca che parla di provocazioni di milizie locali e l&#8217;Ucraina che sospetta degli attacchi pretestuosi effettuati dagli stessi russi per avere il pretesto per una prossima operazione militare sul territorio. Avvenire, pubblica un lungo artiolo in cui riporta anche le parole del parroco di una chiesa di Tiraspol, la capitale, minacciato dai ervizi segreti dopo le sue parole sulla pace. D&#8217;altra parte il territorio \u00e8 da tempo conteso e nelle ultime settimane ha visto aumentare la presenza di militari russi (che a Mosca chiamano &#8220;forze di pace&#8221;) cos\u00ec come di persone ucraine scappate dal proprio Paese, che si sono fermate qui nonostante si sappia che il governo locale autoproclmato \u00e8 legato a duppio filo a Putin. Il governo moldavo predica la calma, ma la paura che la guerra arrivi anche l\u00ec \u00e8 una minaccia con cui ormai bisogna fare i conti.<\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-199471 size-full\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/04\/AVVTransnis-1.png\" alt=\"\" width=\"920\" height=\"540\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/04\/AVVTransnis-1.png 920w, https:\/\/www.aibi.it\/ita\/images\/2022\/04\/AVVTransnis-1-511x300.png 511w, https:\/\/www.aibi.it\/ita\/images\/2022\/04\/AVVTransnis-1-150x88.png 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/04\/AVVTransnis-1-768x451.png 768w\" sizes=\"auto, (max-width: 920px) 100vw, 920px\" \/><br \/>\n27\/04 &#8211; 12.55 &#8211; Movimenti alle frontiere con la Moldova<br \/>\n<\/strong>Con l&#8217;intensificarsi delle azioni militari nel sud dell&#8217;Ucriana proseguono e si intensificano i movimenti alla frontiera con la Moldova. Nelle ultime 24 ore tra 26 e 27 aprile sono entrati in Moldova dall&#8217;Ucraina 4.444 persone, di cui 1.877 minori. In totale, per\u00f2, i movimenti lungo il confino con l&#8217;Ucraina sono stati 10.795, segno di come siano pi\u00f9 le persone andate verso questo Paese che non quelle in uscita.<br \/>\nDalla frontiera di Palanca, la pi\u00f9 vicina rispetto a Odessa, dove Ai.Bi. \u00e8 <a href=\"https:\/\/www.aibi.it\/ita\/tenda-aibi-dogana-palanca-isola-speranza\/\">attiva con una propria tenda<\/a> per dare assistenza ai profughi, sono transitate 2.695 persone (tra ingresso e sucita dalla Moldova).<\/p>\n<p><strong>27\/04 &#8211; 11.10 &#8211; Nuovo appello di Papa Francesco: &#8220;Tacciano le armi&#8221;<br \/>\n<\/strong>&#8220;Vi chiedo di perseverare nella preghiera incessante per la pace. Tacciano le armi, affinch\u00e9 quelli che hanno il potere di fermare la guerra sentano il grido di pace dell\u2019intera umanit\u00e0! Dio vi benedica!&#8221;. Sono le parole pronunciate da Papa Francesco durante l&#8217;udienza generale: un nuovo invito del Pontefice alla pace, in riferimento alla situazione in Ucraina.<br \/>\nSul campo, intanto, proseguono i combattimenti: in mattinata i russi hanno rivendicato la distruzione di un deposito di armi a Zaporizhzhia, citt\u00e0 verso la quale si sono intensificati i bombardamenti.<br \/>\nAl momento, per\u00f2, la notizia pi\u00f9 rilevante arriva dal fronte del fronte delle decisioni politiche, con Putin che ha chiuso la fornitura del gas a Polonia e Bulgaria. Immediato il commento del presidente della Commissione Europea Ursula von der Leyen che ha definito &#8220;ingiustificato e inaccettabile&#8221; il fatto di utilizzare la fornitura di gas come strumento di ricatto.<\/p>\n<p><strong>26\/04 &#8211; 15.50 &#8211; Esplosioni in Transnistria<br \/>\n<\/strong>Dopo le parole di venerd\u00ec del generale russo Rustam Minnekayev, che aveva esplicitamente detto che il &#8220;completo controllo del sud dell&#8217;Ucraina&#8221; avrebbe permesso anche l&#8217;accesso alla Transnistria (territorio separatista filorusso della Moldova), oggi, proprio in Transnistria, si sono registrate alcune esplosioni. Immediatamente, il governo locale ha parlato di &#8220;attacchi terroristici&#8221;, versione riportata anche dai media di Mosca. Il Ministro della Difesa dell&#8217;Ucraina, invece, ha imputato l&#8217;attacco alle stesse forze russe, in un tentativo di destabilizzare la situazione e creare il pretesto per poter invadere anche quel territorio. D&#8217;altra parte lo schema messo in atto \u00e8 qualcosa di gi\u00e0 ampiamente visto in passato, non ultimo proprio per giustificare l&#8217;ingresso nel Donbass. Da tempo molti analisti indicano la Transnistria e la Moldova come i prossimi obiettivi della Russia per aumentare il suo controllo su tutta la zona.<\/p>\n<p><strong>25\/04 &#8211; 19.00 &#8211; &#8220;Cessate il fuoco&#8221; a Mariupol. La vice premier ucraina: &#8220;Nessun accordo \u00e8 stato raggiunto&#8221;<br \/>\n<\/strong>La vice premier ucraina Irina Vereschuk ha dichiarato che nessun accordo \u00e8 stato raggiunto per l&#8217;apertura di un corridoio umanitario, oggi, nella citt\u00e0 di Mariupol.<br \/>\nIn Italia continua l\u2019esodo dei profughi ucraini in fuga dalla guerra. Secondo i dati del Ministero dell\u2019Interno ad oggi sono\u00a0100.754\u00a0di cui 36.134 minori.<\/p>\n<p><strong>25\/04 &#8211; 14.00 Forze russe annunciano il &#8220;cessate il fuoco&#8221; per evacuare i civili rimasti nell&#8217;acciaieria di Mariupol<br \/>\n<\/strong>Fonti della difesa russa hanno annunciato a partire dalle 14.00 di oggi, luned\u00ec 25 aprile (ora di Mosca), l&#8217;interruzione delle ostilit\u00e0 a Mariupol, per permettere l&#8217;evacuazione dei civili (lavoratori, donne e bambini) presenti nell&#8217;acciaieria Azovstal. A riportarlo \u00e8 Adnkrons.<br \/>\nSempre l&#8217;agenzia di stampa riporta che il direttore delle Ferrovie ucraine, Olexandr Kamishin, ha reso noto come 5 stazioni ferroviarie nel centro e nell&#8217;ovest dell&#8217;Ucraina siano state colpite da missili russi e come questi attacchi abbiano procurato delle vittime.<\/p>\n<p><strong>24\/04 &#8211; 17.15<\/strong>\u00a0<strong>&#8211; Messa di Pasqua a Bucha<br \/>\n<\/strong>Nel giorno che celebra la Pasqua ortodossa, \u00e8 stata celebrata la messa anche nella chiesa di Sant&#8217;Andrea a Bucha, quella vicino alla quale sono state trovate le fosse comuni. Alla cerimonia non c&#8217;erano molte persone, ma \u00e8 stato comunque un bel segnale e un messaggio di speranza.<br \/>\nIntanto sono stati aggiornati i numeri dei profughi: secondo l&#8217;UNHCR sono 5,2 milioni le persone che hanno lasciato l&#8217;Ucraina dall&#8217;inizio della guerra, mentre 7,7 milioni sono gli sfollati interni.<br \/>\nIn Italia superata quota 100 mila: l&#8217;aggiornamento del Ministero degli Interni riporta un totale di 100.306 profughi, di cui\u00a051.880 donne, 12.426 uomini e 36.000 minori<\/p>\n<p><strong>24\/04 &#8211; 9.15<\/strong>\u00a0<strong>&#8211; Si aggrava il bilancio del bombardamento su Odessa<br \/>\n<\/strong>Sale a 8 il numero delle persone rimaste uccise nel bombardamento di Odessa. Confermato, purtroppo, che tra le vittime ci sono anche una mamma e la figlia di 3 mesi (nel tweet, sotto, le foto postate dal pap\u00e0 della piccola e marito della donna). Nel suo discorso quotidiano, il presidente ucraino Zelensky ha detto che i missili che hanno colpito l&#8217;edificio residenziale e un altro obiettivo militare sono stati in tutto sette.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Valeria was a new mother, her baby daughter Kira was just three month old. Russia took away their lives today when its rocket hit a residential building in Odesa.<br \/>\nValeria\u2019s husband and Kira\u2019s father Yuri posted these pictures of them. <a href=\"https:\/\/t.co\/pendbL6bi2\">pic.twitter.com\/pendbL6bi2<\/a><\/p>\n<p>\u2014 Myroslava Petsa (@myroslavapetsa) <a href=\"https:\/\/twitter.com\/myroslavapetsa\/status\/1517990210017050627?ref_src=twsrc%5Etfw\">April 23, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<strong>23\/04 &#8211; 16.40<\/strong>\u00a0<strong>&#8211; Bombe su Odessa<br \/>\n<\/strong>Le prime notizie sono iniziate ad arrivare verso le 14. Dopo un paio d&#8217;ore, le prime immagini sembrano avere confermato un attacco missilistico russo sulla citt\u00e0 di Odessa: secondo quanto riporta l&#8217;ufficio della presidenza ucraina, nell&#8217;attacco, che ha colpito anche due strutture residenziali, potrebbero essere rimaste uccise almeno 5 persone, tra loro, scrive il <em>Corriere della Sera<\/em>, anche un bambino di 3 mesi. 18 i feriti<\/p>\n<p><strong>23\/04 &#8211; 15.20<\/strong>\u00a0<strong>&#8211; 208 bambini uccisi<br \/>\n<\/strong>In guerra, purtroppo, anche una notizia del genere pu\u00f2 diventare una &#8220;buona notizia&#8221;, ovvero quella che negli ulltimi due giorni il numero dei bambini morti durante il conflitto non sia aumentato. Secondo quanti riportano del stime del procuratore generale di Kiev, infatti, i bambini che hanno perso la vita finora dall&#8217;inizio della guerra sono 208. Cresce, per\u00e0, li numero dei feriti, arrivato a 595.<br \/>\nIn totale, secondo l&#8217;ONU, le vittime civili della guerra in Ucraina sono 2.435 morti. 2.946 i feriti. Numeri di per s\u00e9 gi\u00e0 notevoli, ma che sicuramente sono sottostimati rispetto alla realt\u00e0, al momento ancora impossibile da certificare.<\/p>\n<p><strong>23\/04 &#8211; 11.45<\/strong>\u00a0<strong>&#8211; Quasi 100mila profughi arrivati in Italia<br \/>\n<\/strong>Il nuovo arriognamento del Ministero degli Interni conta 99.393 persone entrate in Italia dall&#8217;Ucraina dall&#8217;inizio della guerra. Di queste, 51.391 sono donne, 12.191 uomini e 35.811 minori.<br \/>\nNumero notevoli, ma che impallidiscono di fronte a quelli riferiti dalla guardia di frontiera polacca, secondo cui dal 24 febbraio sono entrati nel Paese 2,9 milioni di rifugiati. Tenendo conto che prima del conflitto la popolazione ucraina contava 44 miliani di unit\u00e0, significa che un ucraino su 15 ha trovato momentaneamente riparo in Polonia.<\/p>\n<p><strong>23\/04 &#8211; 10.00<\/strong>\u00a0<strong>&#8211; La strage possibile a Mariupol<br \/>\n<\/strong>Secondo il consueto rapporto dell&#8217;intelligence britannica, l&#8217;esercito russo non \u00e8 avanzato in maniera sensibile durante l&#8217;ultima giornata di guerra: i contrattacchi ucraini, compresi quelli sempre in corso all&#8217;acciaieria Azovstal di Mariupol, starebbero rallentando le operazioni.<br \/>\nDa Mariupol, intanto, emergono altre immagini satellitari che fanno pensare alla presenza di almeno due grandi fosse comuni, che potrebbero contenere migliaia di corpi. Il primo ministro ucraino Denys Shmyhal\u00a0 si \u00e8 spinto a dire che l&#8217;assedio di Mariupol ha portato alla morte di 20 mila ucraini, ponendosi come una delle pi\u00f9 grandi catastrofi umanitarie di questo secolo.<\/p>\n<p><strong>22\/04 &#8211; 13.40<\/strong>\u00a0<strong>&#8211; La Russia vuole il controllo di tutto il sud dell&#8217;Ucraina<br \/>\n<\/strong>Sono parole davvero preoccupanti quelle rilasciate dall&#8217;importante generale russo Rustam Minnekayev. Secondo quanto riportato dalle agenzie di stampa <i>TASS<\/i>\u00a0e\u00a0<i>Interfax <\/i>il vice comandante delle forze del distretto militare della Russia centrale ha dichiarato che l&#8217;obiettivo della seconda fase dell&#8217; &#8220;operazione speciale&#8221; \u00e8 il completo controllo del Donbass e di tutto il sud dell&#8217;Ucraina. Questo permetterebbe anche l&#8217;accesso alla Transnistria, territorio separatista filorusso della Moldova, dove, sempre secondo le parole del generale: &#8220;Sono stati osservati casi di oppressione della popolazione di lingua russa&#8221;. Dichiarazioni che sono da prendere con cautela, naturalmente, ma che per la prima volta esplicitano i reali obiettivi russi che gli analisti da settimane ipotizzano e, soprattutto, apre alla possibilit\u00e0 che il conflitto si sposti anche nella vicina Moldova.<\/p>\n<p><strong>22\/04 &#8211; 11.45<\/strong>\u00a0<strong>&#8211; Niente tregua per la Pasqua ortodossa<br \/>\n<\/strong>L&#8217;aveva provata a chiedere ufficialmente l&#8217;ONU, d\u2019accordo con il capo della Chiesa Greco-Cattolica Ucraina, Sua Beatitudine Sviatoslav Shevchuk. All&#8217;invito si era unito anche Papa Francesco, che in un comunicato, in cui si legge che &#8220;Nulla \u00e8 impossibile a Dio\u201d, ha affermato l&#8217;unione della Santa Sede all&#8217;appello per una tregua delle ostilit\u00e0 in Ucraina in vista della Pasqua ortodossa, che si celebra il 24 aprile. Ma, a quanto riferito dal Presidente ucraino Zelensky, la Russia ha respinto la proposta di stabilire una tregua per la Pasqua&#8221;.<br \/>\nNella giornata odierna, inoltre, al momento pare non saranno organizzati tentativi di evacuazione e corridoi umanitari<\/p>\n<p><strong>21\/04 &#8211; 18.30<\/strong>\u00a0<strong>&#8211; Nuovi aiuti USA all&#8217;Ucraina<br \/>\n<\/strong>Il Presidente degli Stati Uniti Biden ha annunciato di aver stanziato un altro pacchetto di aiuti militari per l&#8217;Ucraina, per un totale di\u00a0800 milioni di dollari. Nella stessa giornata, i parlamenti di Estonia e Lettonia hanno definitio ufficialmente un &#8220;genocidio\u201d quello che la Russia sta compiendo in Ucraina.<\/p>\n<p><strong>21\/04 &#8211; 10.45<\/strong>\u00a0<strong>&#8211; Basta assalti all&#8217;acciaieria Azovstal: per i russi, Mariupol \u00e8 ormai conquistata<br \/>\n<\/strong>\u00c8 sempre Mariupol, al momento, il luogo su cui si concentrano le attenzioni delle operazioni militari in Ucraina: ieri la vice prima ministra Iryna Vereshchuk aveva denunciato il fallimento dell&#8217;evacuazione programmata. Oggi, per\u00f2, ha fatto sapere su Talegram che almeno 4 autobus sono riusciti a portare qualche civile in salvo dalla citt\u00e0 assediata ormai da quasi due mesi. Oggi verranno effettuati altri tentativi, ma le condizioni di sicurezza sono quantomai precarie. Vero \u00e8 che Putin, in una intervista televisiva, ha dichiarato di sospendere l&#8217;assalto all&#8217;acciaieria Azovstal, ultima roccaforte in cui i soldati ucraini e, pare, diversi civili, sono asserragliati. L&#8217;esercito russo dovrebbe limitarsi a circondarla e garantisce di &#8220;trattare con umanit\u00e0&#8221; chiunque decider\u00e0 di arrendersi. Rimane da vedere, ora che, di fatto, il Presidente russo ha dichiarato Mariupol citt\u00e0 ormai nelle mani della Russia, cosa si far\u00e0 per la popolazione civile ancora presente.<\/p>\n<p><strong>20\/04 &#8211; 14.30<\/strong> <strong>&#8211; La visita a Kiev del Presidente del Consiglio Europeo Charles Michel<br \/>\n<\/strong>Senza che fosse stato annunciato in precedenza, nella mattina di mercoled\u00ec 20 aprile \u00e8 arrivato a Kiev il presidente del Consiglio Europeo Charles Michel. Quella dell&#8217;ex primo ministro del Belgio \u00e8 la seconda visita di un rappresentante di alto livello dell&#8217;Unione Europea in Ucraina, dopo quella della Presidente della Commissione Ursula von der Leyen. Michel, una volta arrivato, ha resa nota la sua presenza a Kiev con un significativo tweet, in cui ha detto di trovarsi nel &#8220;cuore di un&#8217;Europa libera e democratica&#8221;.<\/p>\n<p><strong>20\/04 &#8211; 11.30<\/strong> <strong>&#8211; 205 i bambini morti in Ucraina dall&#8217;inzio della guerra<br \/>\n<\/strong>L\u2019Ufficio del Procuratore generale di Kiev ha fatto sapare che, al 20 aprile, il numero dei bambini morti in Ucraina dall&#8217;inizio del conflitto \u00e8 rimasto stabile a 205. Salgono, per\u00f2, i feriti, arrivati a 373.<br \/>\nIntanto, sul fronte delle operazioni militari, il vice primo ministro dell\u2019Ucraina Iryna Vereshchuk ha confermato che in giornata dovrebbe essere aperto un corridoio umanitario per evacuare da Mariupol 6 mila cittadini.<\/p>\n<p><strong>19\/04 &#8211; 17.10<\/strong> <strong>&#8211; Bomba sull&#8217;ospedale di Mariupol<\/strong><\/p>\n<p>Mentre il Presidente degli Stati Uniti si \u00e8 sentito telefonicamente con i leader dei principali paesi europei, presumibilmente per concordare i prossimi passi in risposta alla guerra in Ucraina, secondo quanto riferito da un Tweet di un parlamentare ucraino, i russi hanno bombardato l&#8217;ospedale di Mariupol. Nell&#8217;edificio, uno dei pochi che era rimasto pi\u00f9 o meno integro dopo settimane di bombardamenti, potrebbero trovarsi fino a 300 persone. Naturalmente si tratta di notizie al momento molto difficili da confermare, ma in linea con quanto accade da tempo nella martoriata citt\u00e0 del sud dell&#8217;Ucraina.<\/p>\n<p><strong>19\/04 &#8211; 12.10<\/strong> <strong>&#8211; Si intensifica l&#8217;offensiva nel Donbass<br \/>\n<\/strong>Ormai l&#8217;offensiva russa nel Donbass si \u00e8 intensificata: non solo si continua a combattere a Mariupol, dove pare che sia stato dato un nuovo ultimatum ai soldati ucraini che ancora stanno difendendosi all&#8217;interno dell&#8217;acciaieria Azovstal, ma le operazioni militari occupano ormai un fronte ben pi\u00f9 ampio, secondo la <em>BBC<\/em> di 480 km.<br \/>\nOggi non sono dunque previsti corridoi umanitari dalle zone pi\u00f9 in difficolt\u00e0, mentre le autorit\u00e0 ucraine continuano a invitare la popolazione a lasciare comunque l&#8217;est del Paese.<br \/>\nSul fronte della diplomazia la situazione pare decisamente in stallo, con il presidente francese Macron che, dopo essere stato tra i leader che hanno pi\u00f9 spesso parlato con Putin dall&#8217;inizio della guerra, ha affermato che dopo i fatti di Bucha &#8220;la situazione \u00e8 cambiata&#8221; e le comunicazioni con il Presidente russo si sono interrotte&#8221;.<\/p>\n<p><strong>18\/04 &#8211; 19.50<\/strong> <strong>&#8211; Ad oggi, sono 96.512 i profughi ucraini giunti in Italia<br \/>\n<\/strong>Secondo l&#8217;ultimo aggiornamento del Ministero dell&#8217;Interno sono 96.512 le persone in fuga dalla guerra in Ucraina arrivate ad oggi, in Italia. 49.900 sono donne e 35.133 minori. L&#8217;incremento, rispetto alla giornata di ieri \u00e8 di 560 ingressi nel territorio nazionale.<br \/>\n(immagine di copertina credit Ministero Interno)<\/p>\n<p><strong>18\/04 &#8211; 8.40 &#8211; 150 bambini portati via con la forza a Mariupol<br \/>\n<\/strong>Circa 150 bambini sarebbero stati portati via con la forza da Mariupol, dai <span id=\"U102640948396ApC\">militari russi. A renderlo noto \u00e8 il Crimean Human Rights Group. Molti di loro, <\/span><span id=\"U102640948396ApC\">erano ricoverati negli ospedali e non erano orfani. S<\/span>econdo Petro Andriushchenko, consigliere del sindaco di Mariupol, molti dei minori sono stati portati via senza i loro genitori. A riportarlo sono le agenzie di stampa Ansa e Adnkronos.<\/p>\n<p><strong>17\/04 &#8211; 10.10 &#8211; I colori della Pasqua al MoldExpo<br \/>\n<\/strong>Nella notte sono stati effettuati altri bombardamenti a Kiev, ma \u00e8 sempe a Mariupol la zone dove il conflitto \u00e8 pi\u00f9 intenso. Secondo fonti russe la citt\u00e0 \u00e8 ormai completamente nelle sue mani ed \u00e8 stato dato un ultimatum per arrendersi agli ultimi soldati ucraini che ancora stavano combattendo in situazione disperata. Intanto ha riaperto l&#8217;ambasciata italiana a Kiev, come annunciato in un video dello stesso ambasciatore Pier Francesco Zazo sull&#8217;account della Farnesina<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"it\" dir=\"ltr\">L\u2019Ambasciatore Pier Francesco <a href=\"https:\/\/twitter.com\/hashtag\/Zazo?src=hash&amp;ref_src=twsrc%5Etfw\">#Zazo<\/a> riapre Ambasciata a Kiev. <br \/>\u201cUn momento emozionante e di speranza ad oltre 50 giorni dall\u2019inizio del conflitto in \ud83c\uddfa\ud83c\udde6\u201c.<br \/>Guarda il videomessaggio \ud83d\udc47 <a href=\"https:\/\/t.co\/CUbqUkWKDH\">pic.twitter.com\/CUbqUkWKDH<\/a><\/p>\n<p>&mdash; Farnesina \ud83c\uddee\ud83c\uddf9 (@ItalyMFA) <a href=\"https:\/\/twitter.com\/ItalyMFA\/status\/1515352170786344970?ref_src=twsrc%5Etfw\">April 16, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><strong>16\/04 &#8211; 11.00 &#8211; I colori della Pasqua al MoldExpo<br \/>\n<\/strong>Intanto, in Moldova, non si fermano le attivit\u00e0 di animazione e di accoglienza dei profughi nei campi allestiti nel Paese. Al MoldExpo di Chisinau, dove Ai.Bi. \u00e8 presente e attiva fin dai primissimi giorni dopo lo scoppio del conflitto, le animatrici hanno allestito e colorato lo spazio dedicato ai bambini con i colori della Pasqua. Con la speranza che, davvero, sia una Pasqua di rinascita e di rinnovata speranza nel futuro per tutti.<\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-199225 size-full\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/04\/colori-pasqua-moldexpo.jpeg\" alt=\"\" width=\"1200\" height=\"629\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/04\/colori-pasqua-moldexpo.jpeg 1200w, https:\/\/www.aibi.it\/ita\/images\/2022\/04\/colori-pasqua-moldexpo-572x300.jpeg 572w, https:\/\/www.aibi.it\/ita\/images\/2022\/04\/colori-pasqua-moldexpo-150x79.jpeg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/04\/colori-pasqua-moldexpo-768x403.jpeg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>16\/04 &#8211; 10.30 &#8211; 30mila persone al giorno rientrano a Kiev<br \/>\n<\/strong>Nella notte alcune zone della citt\u00e0 di Kiev sono state colpite dalle bombe. Proprio per questo, il sindaco Vitali Klitschko ha invitato la popolazione a non tornare in citt\u00e0, visto che ancora la sicurezza non pu\u00f2 essere garantita. Nonostante questo, per\u00f2, negli ultimi giorni le autorit\u00e0 di frontiera e le Nazioni Unite hanno confermato un costante flusso di persone che rientrano a Kiev: si parle di circa 30 mila persone al giorno, 870mila dalla fine di febbraio.<strong><br \/>\n<\/strong><\/p>\n<p><strong>15\/04 &#8211; 17.30 &#8211; Allarme adozione illegale di minori ucraini<br \/>\n<\/strong>Il ministero degli esteri ucraino lancia l\u2019allarme sulla minaccia di possibili adozioni illegali di bambini ucraini da parte di cittadini russi. Desta preoccupazione per il ministero ucraino anche l&#8217;intenzione di Mosca di firmare accordi con l&#8217;Ordlo (i territori temporaneamente occupati delle regioni di Donetsk e Luhansk), che consentirebbero, come spiega il Messaggero, il trasferimento degli orfani deportati illegalmente dall&#8217;Ucraina a famiglie russe. Azioni qualificate da Kiev come sequestro di persona.<\/p>\n<p><strong>15\/04 &#8211; ore 9.40 &#8211; 198 minori hanno perso la vita dall&#8217;inizio della guerra<br \/>\n<\/strong>Secondo i dati dell\u2019ufficio del procuratore generale ucraino, riportati da AdnKronos, dall\u2019inizio della guerra ad oggi almeno 198 minori hanno perso la vita e pi\u00f9 di 355 bambini sono rimasti feriti a causa dei combattimenti. Le cifre, precisa l&#8217;ufficio del procuratore, non sono definitive. La maggior parte delle vittime si registrerebbe nella regione di Donetsk, di Kiev e di Kharkiv.<\/p>\n<p><strong>14\/04 &#8211; ore 16.40 &#8211; Danneggiato &#8220;seriamente&#8221; l&#8217;incrociatore russo Mosca<br \/>\n<\/strong>Sul campo di battaglia, la notizia pi\u00f9 rilevante della giornata \u00e8 il danneggiamento dell&#8217;incrociatore russo Mosca. Secondo fonti ucraine, la nave \u00e8 stata colpita da due missili. I russi sostengono, invece, che a creare i problemi sia stata l&#8217;esplosione di diverse munizioni a causa di un incendio. Ancora non ci sono conferme indipendenti, ma sicuramente per la Russia si tratta di una perdita importante dal punti di vista militare e &#8220;simbolico&#8221;, per l&#8217;importanza dell&#8217;ammiraglia.<br \/>\n(immagine in apertura Dnipro Today)<\/p>\n<p><strong>14\/04 &#8211; ore 11.15 &#8211; Oltre 92 mila profughi arrivati in Italia<br \/>\n<\/strong>L&#8217;ultimo aggiornamento del Ministero dell&#8217;Interno, arrivato questa mattina, porta a 92.716 il numero delle persone arrivate in Italia dall&#8217;Ucraina dall&#8217;inizio del conflittto. Di queste, la maggioranza sono donne (47.927), seguite dai minori (34.223) e gli uomini (10.566).<br \/>\nRiguardo i minori, in particolare, il Commissario delegato per il coordinamento delle misure e delle procedure finalizzate alle attivit\u00e0 di assistenza nei confronti dei minori non accompagnati provenienti dall\u2019Ucraina,\u00a0<strong>Francesca Ferrandino<\/strong>, ha aggiornato il piano adottato il 25 marzo scorso. Come riporta il sito del Ministero: &#8220;Sono state specificate con maggiore dettaglio le<strong>\u00a0modalit\u00e0 di implementazione del Sistema informativo minori<\/strong>, al fine di agevolare il censimento realizzato attraverso quel sistema&#8221;.<br \/>\nLa ulteriori misure specificano che &#8220;sin dai primi contatti tra Istituzioni ucraine e associazioni promotrici dei trasferimenti, devono essere informati il dipartimento della Protezione civile, il dipartimento Libert\u00e0 Civili e Immigrazione e il dipartimento della Pubblica sicurezza&#8221;. Inoltre &#8220;almeno dieci giorni prima del trasferimento effettivo l\u2019associazione promotrice deve fornire alle autorit\u00e0 competenti, anche a livello locale, ogni informazione utile, compresa la presenza di eventuali ulteriori motivi di vulnerabilit\u00e0 e bisogni speciali, la presenza di accompagnatori, gli eventuali provvedimenti di tutela e rappresentanza legale adottati dalle autorit\u00e0 ucraine oltre alle misure di accoglienza predisposte&#8221;.<br \/>\nInfine, una volta ricevuta la comunicazione dell\u2019associazione promotrice, la prefettura \u00e8 tenuta a attivare, d\u2019intesa con il Commissario delegato, un <strong>Tavolo di coordinamento con le Istituzioni coinvolte<\/strong> anche per programmare risposte adeguate sotto il profilo educativo e sanitario.<br \/>\n<a href=\"https:\/\/www.interno.gov.it\/it\/notizie\/emergenza-profughi-ucraini-aggiornato-piano-minori-stranieri-non-accompagnati\" target=\"_blank\" rel=\"noopener\">QUI<\/a> la nota completa del Ministero<br \/>\nfoto in paertura: Imagoeconomica. Da sito https:\/\/www.interno.gov.it\/)<\/p>\n<p><strong>13\/04 &#8211; ore 15.40 &#8211; Quasi 2000 civili morti dall&#8217;inizio della guerra<br \/>\n<\/strong>La guerra in Ucraina sta vivendo fasi che si possono definire interlocutorie, con le truppe russe che si stanno riposizionando verso la zona del Donbass dove tutti gli analisti si aspettano, a breve, la prossima, massiccia, offensiva. Nel frattempo, nelle zone del nord lasciate dall&#8217;esercito russo, si contano i morti: finora, secondo il vice procuratore della regione di Kiev, nella citt\u00e0 tornate sotto il controllo ucraino sono stati contati 765 civili, ma si tratta di un conteggio ancora del tutto provvisorio.<br \/>\nAltro aggiornamento sui morti \u00e8 stato fatto dall&#8217;Alto Commissario dell&#8217;ONU, che ha riferito come dall&#8217;inizio del conflitto siano rimasti uccisi 1892 vicili e altri 2558 siano rimasti feriti. Anche in queto caso, per\u00f2, il conteggio \u00e8 destinato a crescere.<\/p>\n<p><strong>13\/04 &#8211; ore 11.40 &#8211; Papa Francesco: &#8220;La guerra \u00e8 un oltraggio a Dio&#8221;<br \/>\n<\/strong>Papa Francesco torna a parlare della guerra in Ucraina durante l&#8217;udienza generale, e lo fa con nuove parole di forte condanna: &#8220;Ogni guerra\u00a0 &#8211; ha affermato &#8211; rappresenta un oltraggio a Dio, un tradimento blasfemo del Signore della Pasqua, un preferire al suo volto mite quello del falso dio di questo mondo.&#8221; Da qui il richiamo alla pace di Ges\u00f9, che &#8220;non \u00e8 la pace che segue le strategie del mondo, il quale crede di ottenerla attraverso la forza, con le conquiste e con varie forme di imposizione. Questa pace, in realt\u00e0, \u00e8 solo un intervallo tra le guerre: lo sappiamo bene. La pace del Signore segue la via della mitezza e della croce: \u00e8 farsi carico degli altri. Cristo, infatti, ha preso su di s\u00e9 il nostro male, il nostro peccato e la nostra morte. Ha preso su di s\u00e9 tutto questo. Cos\u00ec ci ha liberati. Lui ha pagato per noi. La sua pace non \u00e8 frutto di qualche compromesso, ma nasce dal dono di s\u00e9&#8221;.<\/p>\n<p><strong>12\/04 &#8211; ore 15.20 &#8211; Bombardata la Caritas di Mariupol: 7 vittime<br \/>\n<\/strong>Le bombe non risparmiano niente e nessuno, a Mariupol. Stamattina \u00e8 stata colpita da un carro armato la sede della Caritas della citt\u00e0: a riportarlo \u00e8 la presidente della Caritas Ucraina, che ha precisato come nell&#8217;attacco siano rimaste uccise sette persone, di cui 2 dello staff.<\/p>\n<p><strong>12\/04 &#8211; ore 11.20 &#8211; Ucraina: scappati i due terzi dei bambini<br \/>\n<\/strong>Se la guerra \u00e8 un punto di domanda sul futuro di un popolo, quella che si sta combattendo in Ucraina appare pi\u00f9 come un &#8220;macigno&#8221;: secondo gli ultimi dati dell&#8217;Unicef, infatti, i due terzi dei bambini residenti in Ucraina hanno abbandonato il Paese in meno di 50 giorni di conflitto. Si parla di 4,8 milioni di bambini su un totale, di prima della guerra, di 7,5 milioni. Un esodo che il direttore dei programmi di emergenza dell&#8217;UNICEF Manuel Fontaine ha detto di &#8220;non aver mai visto&#8221; in 31 anni di lavoro.<\/p>\n<p><strong>11\/04 &#8211; ore 15.20 &#8211; Si intensifica l&#8217;arrivo di porfughi in Moldova<br \/>\n<\/strong>Dopo qualche giorno in cui il flusso di profughi verso la Moldova si era un po&#8217; arrestato, l&#8217;annuncio della nuova strategia russa e l&#8217;invito delle autorit\u00e0 ucraine a lasciare le zone sud-orientali del Paese ha ridato impulso alla fuga della popolazione. Proprio oggi, nel portare i consueti aiuti alla frontiera di Palanca, l&#8217;equipe di Ai.Bi. ha potuto constatare personalmente l&#8217;aumento degli arrivi di profughi, in particolare dalle citt\u00e0 di Mykola\u00efv, Cherson e Odessa.<\/p>\n<p><strong>11\/04 &#8211; ore 14.40 &#8211; Il cancelliere austriaco Nehammer in visita a Mosca<br \/>\n<\/strong>Se sul fronte delle operazioni militari la situazione \u00e8 ancora piuttosto stazionaria, sul piano degli incontri e delle trattative l&#8217;evento pi\u00f9 rilevante \u00e8 la visita a Mosca del cancelliere austriaco Karl Nehammer, il primo leader di un Paese europeo a incontrare personalmente Vladimir Putin dall&#8217;inizio della guerra. Secondo quanto riportato anche dall&#8217;agenzia russa Tass, al centro dei colloqui ci sar\u00e0 la questione del gas.<\/p>\n<p><strong>11\/04 &#8211; ore 11.00 &#8211; Si prepara una nuova offensiva nel Donbass<br \/>\n<\/strong>Secondo diverse analisi la Russia \u00e8 pronta a sferrare una nuova offensiva militare nel Donbass e, pi\u00f9 in generale, nella parte sud-orientale dell&#8217;Ucraina. Dopo il ritiro da Kiev e le zone pi\u00f9 a nord, le truppe si stanno spostando e riposizionando per aumentare la pressione nella parte del Paese gi\u00e0 da settimane sotto assedio. Le autorit\u00e0 ucraine continuano a invitare la popolazione a lasciare quelle zone e nello stesso tempo chiedono ulteriori armi all&#8217;Occidente per contrastare il nemico.<br \/>\nIntanto, nei territori liberati, continuano a emergere testimonianze terribili: l&#8217;ultima a Buzova, dove \u00e8 stata scoperta una nuova fossa comune con corpi bruciati e con le mani legate. Inoltre, mancano all&#8217;appello circa 60 persone di cui si sono perse le tracce.<\/p>\n<p><strong>10\/04 &#8211; ore 13.00 &#8211; Papa Francesco: si inizi una tregua pasquale<br \/>\n<\/strong>Nell&#8217;omelia della Santa Messa della Domenica delle Palme, il Papa \u00e8 tornato a parlare della guerra in Ucraina. E lo ha fatto con parole molto forti, sottolineando come, oggi, nella guerra, si torni a crocifiggere Crito. &#8220;Cristo \u00e8 ancora una volta inchiodato alla croce nelle madri che piangono la morte ingiusta dei mariti e dei figli &#8211; ha detto il Santo Padre-. \u00c8 crocifisso nei profughi che fuggono dalle bombe con i bambini in braccio. \u00c8 crocifisso negli anziani lasciati soli a morire, nei giovani privati di futuro, nei soldati mandati a uccidere i loro fratelli. Cristo \u00e8 crocifisso l\u00ec, oggi.&#8221;<br \/>\nDurante l&#8217;Angleus, poi, il Papa ha invocato la pace: &#8220;Si depongano le armi! Si inizi una tregua pasquale; ma non per ricaricare le armi e riprendere a combattere, no! Una tregua per arrivare alla pace, attraverso un vero negoziato, disposti anche a qualche sacrificio per il bene della gente. Infatti, che vittoria sar\u00e0 quella che pianter\u00e0 una bandiera su un cumulo di macerie?&#8221;<\/p>\n<p><strong>10\/04 &#8211; ore 9.00 &#8211; In Italia, ad oggi 33.077 minori ucraini hanno trovato rifugio<br \/>\n<\/strong>\u00c8 salito a 88.593 il numero delle persone in fuga dal conflitto in Ucraina giunte nel nostro Paese. Secondo i dati del Viminale sono 1.368 in pi\u00f9 rispetto al precedente monitoraggio. 33.077 di loro sono minori. Le citt\u00e0 di destinazione dichiarate all&#8217;ingresso in Italia sono Milano, Roma, Napoli e Bologna.<\/p>\n<p><strong>9\/04 &#8211; ore 16.00 &#8211; 121 mila bambini sono stati trasferiti con la forza in Russia<br \/>\n<\/strong>Pi\u00f9 di 600mila ucraini, tra cui circa 121mila bambini sono stati trasferiti con la forza in Russia. Ad affermarlo in un post su facebook \u00e8 la responsabile dei diritti umani del Parlamento ucraino, Lyudmila Denisova, che sottolinea come\u00a0i residenti della citt\u00e0 temporaneamente occupata di Izyum, nella regione di Kharkiv, sono stati trasferiti con la forza in Russia.<\/p>\n<p><strong>09\/04 &#8211; ore 10.00 Dall&#8217;inizio del conflitto almeno 869 scuole sono state danneggiate<br \/>\n<\/strong>Tra gli edifici distrutti dalle bombe dall\u2019inizio del conflitto in Ucraina, vi sono anche moltissime scuole. Secondo il Ministero dell\u2019istruzione e della Scienza Ucraino, dall\u2019inizio del conflitto sono state almeno 869 le strutture scolastiche danneggiate e 83 quelli completamente distrutte. Save The Children denuncia che in media, dal 24 febbraio, ogni giorno sono state 22 le scuole attaccate e 5,5 milioni di bambini, ancora nel Paese, sono rimasti senza istruzione. Orizzonte Scuola rende noto come siano stati 10.064 gli alunni ucraini accolti nelle scuole italiane dall\u2019inizio del conflitto.<\/p>\n<p><b>08\/04 &#8211; ore 16.30 Bambini con il numero di telefono scritto sul corpo<br \/>\n<\/b>Da un paio di giorni \u00e8 diventata virale la foto di Vira, la bambina ucraina di 2 anni a cui madre ha scritto sulla schiena nome, indirizzo e numero di telefono. Uno stratagemma per rendere possibile in fretta un&#8217;eventuale identificazione in caso la guerra le separasse. Purtroppo non si tratta di un caso isolato o di un foto &#8220;a effetto&#8221;, perch\u00e9 anche ieri, tra i 234 minori non accompagnati accolti in Veneto, i volontari della protezione civile e le autorit\u00e0 ne hanno trovati diversi con il numero di telefono scritto su un braccio, sulla mano o in qualche altra parte del corpo. Un segno terribile della disperazione di un genitore che, per salvare il figlio, \u00e8 pronto a farlo partire verso qualche altro Paese, con solo un numero di telefono scritto sul suo corpo come legame con chi rimane. E aspetta.<\/p>\n<p><b>08\/04 &#8211; ore 13.30 Il bombardamento della stazione di Kramatorsk<br \/>\n<\/b>Pochi giorni fa, con il ritiro dal nord dell&#8217;Ucraina e dalle citt\u00e0 vicino a Kiev, la Russia ha esplicitamente indicato come il prossimo obiettivo sia il controllo del Donbass. Proprio per questo, le autorit\u00e0 ucraine hanno lanciato appelli alla popolazione delle citt\u00e0 nell&#8217;est e nel sud del Paese affinch\u00e9 sfollassero e si mettessero in salvo, prima del previsto intensificarsi degli attacchi. Per questo, in mattinata, la stazione di Kramatorsk, nella regione di Donetsk, era particolarmente affollata quando c&#8217;\u00e8 stato un violento bombardamento. Al momento le autorit\u00e0 riferiscono di 39 morti e 87 feriti, ma la paura \u00e8 che i numeri possano salirte ancora.<br \/>\nNelle ore successive all&#8217;attacco, sui social ha iniziato a circolare la foto di un missile con la scritta &#8220;per i bambini&#8221;. Impossibile, al momento, stabilire chi abbia scritto tale frase di cui non \u00e8 chiaro anche il significato. C&#8217;\u00e8 chi sostiene, infatti, che quel &#8220;per&#8221; non sia da interpretare come un &#8220;destinato a&#8230;&#8221;, ma come &#8220;per vendicare i&#8230;&#8221; Possibilit\u00e0 di interpretazioni a cui aggrapparsi per non arrendersi davanti a un&#8217;azione che andrebbe al di l\u00e0 di qualsiasi logica umana.<br \/>\n(foto in apertura del Ministero della Difesa ucraino)<\/p>\n<p><b>08\/04 &#8211; ore 11.10 Oltre 86 mila i profughi arrivati in Italia<br \/>\n<\/b>Aggiornamento dei numeri di profughi arrivati in Italia da parte del Ministero degli Interni: a gioved\u00ec 8 aprile sono 86.066 le persone in fuga dal conflitto arrivate nel nostro Paese. Di queste, 44.422 sono donne, 9.173 uomini e 32.471 minori.<br \/>\nSul fronte dei MISNA, invece, l&#8217;Autorit\u00e0 garante per l\u2019infanzia e l\u2019adolescenza Carla Garlatti ha reso noto che i minori stranieri non accompagnati arrivati finora in Italia sono 1099.<\/p>\n<p><b>07\/04 &#8211; ore 16.00 2 mila bambini scomparsi<br \/>\n<\/b>Si faticano a trovare nuove parole davanti alle notizie che si susseguono dall&#8217;Ucraina, specie pensando ai bambini, i soggetti pi\u00f9 indifesi e nei confronti dei quali l&#8217;orrore della guerra si amplifica. Secondo gli ultimi dati, dall&#8217;inizio del conflitto sono 7 milioni e mezzo i bambini sfollati, di cui 2 milioni e mezzo sono usciti dall&#8217;Ucraina. Di 2000, invece, non si ha pi\u00f9 alcuna traccia: in Europa, lo spettro della deportazione e della tratta non \u00e8 mai stato cos\u00ec vicino dalla Seconda Guerra Mondiale.<\/p>\n<p><b>07\/04 &#8211; ore 16.00 Le auto in file per tornare a Bucha<br \/>\n<\/b>Mentra continuano ad arrivare notizie terribili dai territori lasciati dai russi dopo l&#8217;occupazione (ora \u00e8 Borodyanka la citt\u00e0 dalla quale i giornalisti raccontano scene raccapriccianti), l&#8217;inviato del Corriere della Sera Lorenzo Cremonesi ha documentato le file chilometriche di auto che si dirigono verso Bucha: sono gli abitanti che tornano nella loro citt\u00e0 dopo essere sfollati all&#8217;arrivo dei russi. Immagini che, nella devastazione, sanno di resilienza caparbiet\u00e0 e, speriamo, rinascita!<\/p>\n<p><b>07\/04 &#8211; ore 10.00 Ieri ritrovato il cadavere del piccolo Sasha<br \/>\n<\/b>Tra i tanti appelli e segnalazioni che si susseguono, qualche giorno fa era circolato molto sui social quello relativo a Sasha, un bambino di 4 anni di cui i genitori non avevano pi\u00f9 notizie da quando era stato visto scappare da Kiev con la nonna, rimasta uccisa. Ieri la mamma di Sasha\u00a0 ha dato la notizia che anche il corpo di suo figlio \u00e8 stato ritrovato, colpito anche lui, come la nonna, mentre cercava una via verso la salvezza. &#8220;Sasha, il nostro piccolo angelo \u00e8 gi\u00e0 in paradiso! Oggi la sua anima ha trovato pace&#8221;; queste le parole della mamma di Sasha riportate dall&#8217;agenzia Dire.<\/p>\n<p><b>07\/04 &#8211; ore 9.45 Ora la guerra si concentra nel Donbass<br \/>\n<\/b>Secondo quanto riferiscono le intelligence occidentali, l&#8217;esercito russo ha ormai lasciato quasi del tutto le zone intorno a Kiev e il nord dell&#8217;Ucraina. Al momento, le truppe che fino a pochi giorni fa erano l\u00ec faranno tappa in Russia e Bielorussia per riequipaggiarsi prima di riposizionarsi, veresimilmente, nel sud-est del Paese. L&#8217;obiettivo chiaro della guerra, infatti, \u00e8 ormai diventato il Donbass e, probabilmente, la pi\u00f9 estesa area meridionale fino a Odessa, cos\u00ec da creare una continuit\u00e0 di territorio con la Crimea e la Russia e togliere l&#8217;acesso al Mar D&#8217;Azov all&#8217;Ucraina.<\/p>\n<p><b>06\/04 &#8211; ore 16.15 400 civili dispersi a Hostomel<br \/>\n<\/b>Continuano ad arrivare notizie di abusi, omicidi e tragedie dai territori dell&#8217;Ucraina fino a pochi giorni fa occupati dai russi. Uno degli ultimi allarmi arriva dal sobborgo di Hostomel, nei pressi di Kiev, dove secondo le autorit\u00e0 locali risultano dispersi circa 400 civili: Taras Dumenko, la persona che fa le veci del sindaco, ucciso durante gli scontri, ha dichiarato all&#8217;<em>Ansa<\/em> che di queste 400 persone, con le quali &#8220;non riusciamo a stabilire alcun contatto&#8221;, una quindicina sono bambini.<\/p>\n<p><b>06\/04 &#8211; ore 12.40 Papa Francesco: &#8220;Assistiamo all&#8217;impotenza dell&#8217;ONU&#8221;<br \/>\n<\/b>Papa Francesco, durante l&#8217;Udienza Generale incentrata sul suo recente viaggio apostolico a Malta, si \u00e8 soffermato ancora una volta su quanto sta accadendo in Ucraina, In particolare, il Pontefice ha sottolineato l&#8217;impotenza dell&#8217;ONU. &#8220;Si parla spesso di geopolitica &#8211; ha detto il Papa &#8211; ma purtroppo la logica dominante \u00e8 quella delle strategie degli Stati pi\u00f9 potenti per affermare i propri interessi estendendo l\u2019area di influenza economica, o influenza ideologica o influenza militare: lo stiamo vedendo con la guerra&#8221;.<br \/>\n&#8220;Dopo la seconda guerra mondiale &#8211; ha proseguito Bergoglio &#8211; si \u00e8 tentato di porre le basi di una nuova storia di pace, ma purtroppo &#8211; non impariamo &#8211; \u00e8 andata avanti la vecchia storia di grandi potenze concorrenti. E, nell\u2019attuale guerra in Ucraina, assistiamo all\u2019impotenza della Organizzazione delle Nazioni Unite.<\/p>\n<p><b>06\/04 &#8211; ore 11.00 Borodyanka come Bucha: un nuovo scenario dell&#8217;orrore<br \/>\n<\/b>Non hanno ancora smessi di arrivare immagini e racconti dell&#8217;orrore da Bucha, che gi\u00e0 si profila una situaione analoga nella citt\u00e0 di Borodyanka, altra citt\u00e0 nei sobborghi di Kiev occupata per settimane dai russi, oggi ritiratisi.<br \/>\nNel frattempo, gli USA hanno annunciato un inasprimento delle sanzioni, mentre sul versante degli scontri, proseguono le operazioni nella zona orientale del Paese, in particolare nella citt\u00e0 di Sloviansk.<\/p>\n<p><b>05\/04 &#8211; ore 17.00 La Commissione Europea propone nuove sanzioni<br \/>\n<\/b>Come ventilato dopo la diffusione delle terribili immagini di Bucha, la Commissione Europea ha proposto un nuovo pacchetto di sanzioni contro la Russia. La principale misura dovrebbe essere lo stop all&#8217;importazione di carbone, mentre per quanto riguarda il gas naturale non dovrebbero esserci deciioni.<br \/>\nLe misure dovranno eesere approvate dai Paesi membri dell&#8217;Unione per diventare effettive.<\/p>\n<p><b>05\/04 &#8211; ore 10.00 Non si fermano gli orrori che arrivano da Bucha<br \/>\n<\/b>\u00c8 ancora la strage di Bucha a occupare le prime pagine di siti e giornali, con sempre maggiori foto e maggiori dettagli delle atrocit\u00e0 compiute. La Russia continua a negare ogni responsabilit\u00e0 e rivolge a sua volta accuse all&#8217;Occidente, ma sempre pi\u00f9 prove arrivano da giornali e fonti indipendenti che confermano la responsabilit\u00e0 dei soldati di Mosca per quanto successo. Il Presidente ucraino Zelensky, in nottata, ha parlato di almeno 300 persone &#8220;torturate e uccise&#8221;, ma facilmente il numero verr\u00e0 superato. Oltre al fatto che altre citt\u00e0 abbandonate dai russi potrebbero rivelare scenari analoghi.<br \/>\nSe nel nord del Paese si contano i morti, nel sud proseguono i bombardamenti, ora particolarmente intensi attorno alla citt\u00e0 di Mykolaiv, strategica per poter poi puntare su Odessa, obiettivo che permetterebbe ai russi di chiudere l&#8217;accesso al Mar d&#8217;Azov all&#8217;Ucraina e creare una continuit\u00e0 con la Crimea e la Russia.<\/p>\n<p><b>04\/04 &#8211; ore 18.10<br \/>\n<\/b>Anche oggi a Mariupol non sono riuscite le evacuazioni. Un altro giorno in cui i 160 mila abitanti che si stima siano ancora in citt\u00e0 non hanno potuto raggiungere la salvezza. Da giorni i pensieri di tutti vanno alla citt\u00e0 ucraina pi\u00f9 martoriata dal conflitto che, ora, trova l&#8217;ideale sostegno anche di tanti russi. Su Telegram, infatti, si moltiplicano le foto dei memoriali creati in molte citt\u00e0 russe. Piccoli croci di legno, accompagnate da un fiore, un lumino, un disegno, un messaggio&#8230; per dimostrare la propria vicinanza e gridare al mondo, per quanto si riesce, che anche in Russia c&#8217;\u00e8 chi si schiera contro l&#8217;assurdo massacro in corso in Ucraina<\/p>\n<p><b>04\/04 &#8211; ore 12.15\u00a0 83.100 i profughi arrivati in Italia dall&#8217;inizio del conflitto<br \/>\n<\/b>Nuovo aggiornamento da parte del Ministero dell&#8217;Interno sul numero di profughi arrivati nel nostro Paese dall&#8217;inizio della guerra in Ucraina. Alle ore 11:00 di luned\u00ec 4 aprile si contano complessivamente <strong>83.100<\/strong> profughi, dei quali 42.879 donne, 8.551 uomini e 31.670 minori.<\/p>\n<p><b>04\/04 &#8211; ore 10.10\u00a0 Lutto nazionale in Moldova per le vittime dell&#8217;Ucraina<br \/>\n<\/b>Oggi, luned\u00ec 4 aprile, la Moldova osserva una <strong>giornata di lutto nazionale<\/strong> per le vittime del conflitto in Ucraina. Sconvolti, come tutti, dalla immagini agghiaccianti che arrivano da Bucha dei cadaveri per la strada di donne, bambini e anziani massacrati&#8230; le autorit\u00e0 del piccolo Paese che condivide un lungo confine con l&#8217;Ucraina hanno deciso di dichiarare il lutto nazionale.<br \/>\nD&#8217;altra parte la <strong>condanna \u00e8 unanime<\/strong> da parte di tutti i leader europei, mentra da Mosca \u00e8 arrivato il commento della portavoce del Ministero degli Esteri che in un&#8217;intervista ha detto di ritenere le foto dei civili uccisi parte di un &#8220;complotto contro la Russia&#8221;.<br \/>\nPurtroppo, anche davanti ad atrocit\u00e0 cos\u00ec evidenti, serve ricordare che le immagini di Bucha non arrivano solo da fonti ucraine, ma da un numero sempre maggiore di fonti indipendenti: giornalisti che, una volta che i russi si sono ritirati, sono potuti arrivare sul territorio per documentare tutto quello che in queste ore viene rilanciato su siti e giornali di (quasi) tutto il mondo.<\/p>\n<p><b>03\/04 &#8211; ore 17.10\u00a0 Bombardata Odessa. Orrore esecuzione civili a Bucha.<br \/>\n<\/b>Questa mattina, come confermato dallo stesso ministero della difesa di Mosca, c&#8217;\u00e8 stato un intenso bombardamento su Odessa. La citt\u00e0 portuale ucraina, una di quelle strategicamente pi\u00f9 importanti, era stata finora risparmiata dagli attacchi pi\u00f9 intensi dei russi. Il bombardamento di oggi potrebbe essere una conferma della &#8220;nuova strategia&#8221; della guerra da parte di Putin che, ritiratosi dal nord del Paese, concentrer\u00e0 i suoi sforzi nel Donbass e nella parte meridionale dell&#8217;Ucraina.<br \/>\nIntanto, le truppo che si ritirano dal nord dell&#8217;Ucraina lasciano dietro di s\u00e8 immagini agghiaccianti: decine e decine di corpi di civili uccisi e lasciati lungo le strade, spesso con le mani legate dietro la schiena. Non si capisce se in segno di &#8220;avvertimento&#8221; per dimostrare ci\u00f2 che capita a opporsi all&#8217;esercito russo o per quale altro motivo.<\/p>\n<p><b>03\/04 &#8211; ore 9.00\u00a0 Sono almeno 158 i minori uccisi in Ucraina dall&#8217;inizio del conflitto<br \/>\n<\/b>Sono <strong>158 i minori uccisi<\/strong> dall&#8217;inizio della guerra in Ucraina. Ha dichiararlo \u00e8 l&#8217;Ufficio del Procuratore Generale di Kiev, che segnala anche come siano <strong>254 i bambini<\/strong> rimasti feriti nel corso del conflitto, ma i numeri potrebbero essere pi\u00f9 alti. Le vittime si contano in particolare nella citt\u00e0 di\u00a0<strong>Mariupol<\/strong> e nelle regioni di Kiev, Chernihiv e Luhansk.<\/p>\n<p><strong>02\/04 &#8211; ore 16.00<br \/>\n<\/strong>Nuovo, consueto, aggiornamento da parte del Ministero dell&#8217;Interno sui profughi arrivati in Italia dall&#8217;Ucraina dall&#8217;inizio del conflitto. Secondo il Viminale, alla data di sabato 2 aprile, ore 10:48, sono arrivate nel nostro Paese <strong>80.622 persone<\/strong>, di cui 41.614 donne, 8.111 uomini e 30.897 minori.<\/p>\n<p><strong>02\/04 &#8211; ore 12.00<br \/>\n<\/strong>Papa Francesco \u00e8 a Malta per il suo 36\u00b0 viaggio apostolico, ma naturalmente non dimentica l&#8217;Ucraina. Anzi, secondo quando riferiscono i giornalisti che accopmagnano il Santo Padre, sull&#8217;aereo, a specifica domanda di uno di loro se fosse o meno possibile prendere in considerazione una sua visita a Kiev, Bergoglio ha rispoto che, effettivamente, l&#8217;ipotesi &#8220;\u00e8 sul tavolo&#8221;.<\/p>\n<p><strong>02\/04 &#8211; ore 10.40<br \/>\n<\/strong>Nonostante le oltre 2 mila persone evacuate da Mariupol nella giornata di ieri, l&#8217;evacuazione non \u00e8 andata come le autorit\u00e0 ucraine speravano e la stessa Croce Rossa ha ammesso di essere stata costretta a fermare le operazioni perch\u00e9 non c&#8217;erano le condizioni di sicurezza. Oggi si proceder\u00e0 a un nuovo tentativo: in citt\u00e0, infatti, rimangono ancora circa 160 mila persone che da settimane vivono senza avere cibo, acqua corrente, riscaldamento e connessione internet.<\/p>\n<p><strong>01\/04 &#8211; ore 18.20<br \/>\n<\/strong>Finalmente da Mariupol sono riusciti a evacuare circa 2 mila civili. Sono queste le notizie che circolano dal primo pomeriggio, insieme ad alcune immagini che mostrano i mezzi della Croce Rossa scortare bus e auto private verso Zaporizhzhia. Non ci sono state ancora dichiarazioni ufficiali da parte delle autorit\u00e0 ucraine, ma finalmente, dopo settimane drammatiche, per una parte almeno della popolazione ancora intrappolata a Mariupol si \u00e8 aperta la strada verso una possibile salvezza.<\/p>\n<p><strong>01\/04 &#8211; ore 13.15<br \/>\n<\/strong>Nuovo aggiornamento del Ministero dell&#8217;interno sui profughi arrivati in Italia dall&#8217;Ucraina: a venerd\u00ec 1 aprile si tratta di <strong>79.047<\/strong>\u00a0<strong>persone<\/strong>, di cui 40.780 donne, 7.800 uomini e <strong>30.467 minori<\/strong>.<\/p>\n<p><strong>01\/04 &#8211; ore 12.20<br \/>\n<\/strong>Per la prima volta dallo scoppio della guerra, oggi \u00e8 a Kiev una dei pi\u00f9 importanti leader dell&#8217;Unione Europea: si tratta della Presidente del Parlamento europeo Roberta Metsola, in carica da qualche mese dopo la morte di David Sassoli. La stessa Metsola ha confermato il viaggio in mattinata con un semplice tweet in inglese e ucraino: &#8220;On my way to Kyiv&#8221;<\/p>\n<p><strong>01\/04 &#8211; ore 09.40<br \/>\n<\/strong>Potrebbe essere oggi il giorno dei corridoi umanitari da e per Mariupol: nel corso della mattina sono arrivate alcune rassicurazioni da parte della Russia, ma naturalmente \u00e8 tutto molto in bilico, visti i precedenti. Gli autobus sono pronti da ieri a partire da Berdyansk, una piccola citt\u00e0 che dista circa 80 km da Mariupol, ma, al momento, la Croce Rossa, che dovrebbe coordinare gli aiuti umanitari, ha fatto sapere che non ci sono le condizioni di sicurezza per procedere. La speranza \u00e8 che nel corso della giornata si possa finalmente riuscire a portare aiuti alal citt\u00e0 che ormai da tre settimane vive sotto il fuoco dell&#8217;esercito russo, senza acqua, elettricit\u00e0, riscaldamento e connessione internet.<\/p>\n<p><strong>31\/03 &#8211; ore 18.10<br \/>\n<\/strong>Purtroppo la notizia non coglie del tutto impreparati, perch\u00e9 gi\u00e0 altre volte nel corso delle ostilit\u00e0 le &#8220;promesse&#8221; russe della vigilia sono state poi disattese dai fatti. Cos\u00ec \u00e8, al momento, anche per i corridoi umanitari previsti per oggi da Mariupol: secondo il governo ucraino, che ha parlato per voce della vice prima ministra Iryna Vereshchuk, i russi hanno continuato a bombardare la citt\u00e0 rendendo di fatto impossibile tanto l&#8217;arrivo dei bus con gli aiuti umanitari quanto l&#8217;evacuazione delle persone ancora rimaste in citt\u00e0. Tuttavia, per una considerazione definitiva, si aspetta di vedere se verso sera qualcosa cambier\u00e0.<\/p>\n<p><strong>31\/03 &#8211; ore 15.00<br \/>\n<\/strong>Come noto, nel corso delle telefonate che ci sono state dall&#8217;inizio della guerra tra il Presidente dell&#8217;Ucraina Zelensky e Papa Francesco, il primo aveva esplicitamente invitato il secondo ad andare a Kiev. Una proposta suggestiva e sicuramente di grande significato, ma che \u00e8 sembrata da subito irrealizzabile per motivi di sicurezza, come ribadito anche dal nunzio apostolico in Ucraina monsignor Kulbokas, che, come riporta <em>Famiglia Cristiana<\/em>, ha affermato come &#8220;Senza un minimo di tregua sarebbe rischioso per il Pontefice e per i fedeli. Non \u00e8 immaginabile un viaggio di Francesco segreto o clandestino&#8221;.<br \/>\nQuesto, per\u00f2, succedeva due giorni fa, prima che gli ultimi negoziati in Turchia facessero intravedere qualche possibile spiraglio di un allentamenteo delle tensioni. Ecco, dunque, che alla luce di quella che, pi\u00f9 che altro, al momento rimane ancora una speranza, torna d&#8217;attualit\u00e0 la domanda se, davvero, davanti a un nuovo scenario di tregua pi\u00f9 duratura, il Papa possa andare in Ucraina, a porare, con la sua persona, il pi\u00f9 potente mnessaggio di pace che potrebbe esserci.<\/p>\n<p><strong>31\/03 &#8211; ore 09.20<br \/>\n<\/strong>La notizia \u00e8 da prendere con le molle, visto quante volte ci\u00f2 che la Russia ha annunciato a parole non \u00e8 stato poi rispettato nei fatti, per\u00f2, stando, appunto, alle parole, dalle 10 di questa mattina dovrebbe esserci un &#8220;cessate il fuoco&#8221; a Mariupol, la citt\u00e0 assediata ormai da settimane e in cui la guerra sta mostrando il suo lato pi\u00f9 disumano. Secondo l&#8217;agenzia di stampa <em>AFP<\/em>, che riporta la notizia, i russi avrebbero acconsentito a creare un corridoio umanitario per i civili verso la vicina citt\u00e0 di Zaporizhzhia, dove anche nei giorni scorsi si sono diretti i pochi che sono riusciti a lasciare Mariupol.<br \/>\nLa conferma della notizia \u00e8 arrivata anche dalla vice prima ministra Iryna Vereshcuk, che in un messaggio su Telegram ha annunciato l\u2019arrivo a Mariupol di 45 autobous per conesgnare aiuti umanitari ed evacuare i civili. Ora non resta che attendere, con speranza, che tutto ci\u00f2 avvenga davvero e non sia l&#8217;ennesima speranza messa a tacere dalla bombe russe.<\/p>\n<p><strong>30\/03 &#8211; ore 18.00<br \/>\n<\/strong>\u00c8 in corso di pubblicazione in Gazzetta Ufficiale l\u2019ordinanza della <strong>Protezione civile<\/strong> <a href=\"https:\/\/www.protezionecivile.gov.it\/it\/normativa\/ocdpc-n-881-del-29-marzo-2022-0\" target=\"_blank\" rel=\"noopener\">QUI<\/a> volta ad introdurre \u201culteriori disposizioni urgenti per assicurare, sul territorio nazionale, l\u2019accoglienza, il soccorso e l\u2019assistenza alla popolazione\u201d ucraina. L\u2019ordinanza prevede l\u2019erogazione di <strong>300 euro al mese per gli adulti e 150 per i bambini<\/strong>, destinati <strong>direttamente<\/strong> ai rifugiati che abbiano provveduto autonomamente a trovarsi una sistemazione in Italia, tra i propri conoscenti. Gli altri, entreranno a far parte del sistema <strong>di accoglienza diffusa,<\/strong> gestita dalle associazioni del <strong>Terzo settore<\/strong> o dagli enti religiosi, presso piccole strutture o famiglie italiane, ricevendo non solo un alloggio, ma anche sostentamento ed ulteriori servizi come quello di assistenza e di mediazione linguistica. Le famiglie interessate ad <strong>aprire la propria casa all&#8217;accoglienza<\/strong> dovranno quindi rivolgersi ad un&#8217;associazione ed essere inseriti nella loro rete.<\/p>\n<p><strong>30\/03 &#8211; ore 10.30<br \/>\n<\/strong><strong>Sono 75.115\u00a0 i profughi ucraini arrivati in Italia dallo scoppio della guerra.<\/strong> Tra loro 38.373 donne, 7.158 uomini e 29.222 minori. Si inizia ad intravedere un rallentamento degli arrivi a livello europeo. A riferirlo \u00e8 il ministro dell\u2019Interno Luciana Lamorgese, in audizione al Comitato Schengen. Intanto in Ucraina, nella notte, sono continuati i bombardamenti delle forze russe. Nella mattinata di oggi, riporta Adnkronos, le sirene sono suonate anche a Zhytomyr, Kharkiv, Dnipro e Poltava.<\/p>\n<p><strong>29\/03 &#8211; ore 18.00<br \/>\n<\/strong>A distanza di poche ore dall&#8217;arrivo delle prime notizie sulla &#8220;drastica riduzione&#8221; delle operazioni militari verso Kiev e Chernigov, il capo della delegazione di Mosca Vladimir Medinsky ha sottolineato che de-escalation non significa un cessate il fuoco. Parole che sembrano confermare la reazione degli USA che, per bocca del segretario di Stato Antony Blinken avevano frenato l&#8217;entusiasmo generato dalla prime dichiarazioni russe.<br \/>\nMedinsky ha comunque ribadito che sono stati fatti &#8220;passi da gigante verso la pace&#8221;, almeno secondo quanto riporta l&#8217;agenzia Tass che, ricordiamo, \u00e8 molto vicina alle posizioni del Cremlino.<\/p>\n<p><strong>29\/03 &#8211; ore 15.00<br \/>\n<\/strong>Filtrano per la prima volta degli spiragli di fiducia dai colloqui tra Ucraina e Russia: al termine dell&#8217;incontro avvenuto in Turchia, il Ministro della Difesa russo ha confermato la decisione di &#8220;diminuire drasticamente l&#8217;attivit\u00e0 militare in direzione di Kiev e Chernigov&#8221;. Un segnale per &#8220;rafforzare le fiducia reciproca&#8221; in vista di ulteriori colloqui. Colloqui che, secondo un delegato ucraino, potrebbero coinvolgere anche i Paesi garanti, in vista di un possibile incontro tra i due presidenti. \u00c8 la prima volta che anche da parte russa arrivano dei segnali di conferma in tal senso.<br \/>\nAlla base del principio di accordo, secondo gli analisti, ci sarebbe la disponibilit\u00e0 dell&#8217;Ucraina ad accettare lo stato di neutralit\u00e0 e rinunciare all&#8217;ingresso nella Nato e al nucelare. Rimarrebbe sul tavolo, invece, la richiesta di adesione all&#8217;Unione Europea.<\/p>\n<div id=\"advBottom1All\" class=\"rcsAdvOut\">\n<div class=\"adv--Bottom1 banner-margin-top-40\"><strong>29\/03 &#8211; ore 11.50<br \/>\n<\/strong>Secondo diverse fonti ai negoziati in corso in Turchia starebbe partecipando (o, comunque, sarebbe presente) anche Roman Abramovich. Sono ricolate alcune foto e video in cui lo si vede vicino al Presidente della Torchia Erdogan. La notizia \u00e8 rilevante in quanto proprio ieri erano il Wall Street Journal aveva parlato di un presunto avvelenamento nei suoi confronti avvenuto durante i primi negoziati risalenti a quasi un mese fa.<strong><br \/>\n<\/strong><\/div>\n<\/div>\n<p><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\"><strong>29\/03 &#8211; ore 10.05<\/strong><br \/>\nLe ultime notizie dal campo parlano di qualche contrattacco da parte dell&#8217;esercito ucraino che pare avere riconquistato un po&#8217; di terreno nei dintorni di Kiev. Nonostante questo, comunque, le bombe russe continuano a colpire e l&#8217;assedio non si ferma, specie nella parte sud-orientale del Paese.<br \/>\nIn questo scenario, \u00e8 iniziato, in Turchia, un nuovo incontro di negoziati, introdotti direttamente dal presidente turco Erdo\u011fan che ha espresso l&#8217;auspicio di &#8220;arrivare alla pace e al cessate il fuoco il prima possibile&#8221;.\u00a0<\/span><\/p>\n<p><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\"><strong>28\/03 &#8211; ore 17.40<\/strong><br \/>\nSecondo il Wall Street Journal, tre negoziatori ucraini e l&#8217;oligarca russo Roman Abramovich, che aveva partecipato in qualit\u00e0 di mediatore, hanno riscontrato sintomi di sospetto avvelenamento dopo un incontro dei negoziati avvenuto ormai un mese fa. Le loro condizioni sarebbero comunque sotto controllo e non sarebbero in pericolo di vita.<\/span><\/p>\n<p><strong>28\/03 &#8211; ore 17.00<\/strong><br \/>\nContatto telefonico, nel pomeriggio, tra il Presidente del Consiglio italiano Mario Draghi e Presidente dell\u2019Ucraina Volodymyr Zelensky. Come riporta una nota di Palazzo Chigi: &#8220;Zelensky ha lamentato il blocco da parte russa dei corridoi umanitari e la prosecuzione dell\u2019assedio e dei bombardamenti delle citt\u00e0, comprese le scuole, con conseguenti perdite civili, tra cui anche bambini. Il Presidente Draghi ha ribadito il fermo sostegno del Governo italiano alle autorit\u00e0 e al popolo ucraini e la piena disponibilit\u00e0 dell\u2019Italia a contribuire all\u2019azione internazionale per porre fine alla guerra e promuovere una soluzione durevole della crisi in Ucraina&#8221;.<\/p>\n<p><strong>28\/03 &#8211; ore 14.00<\/strong><br \/>\nLa situazione a Kiev e in tutta l&#8217;Ucraina rimane di totale emergenza, ci\u00f2 nonostante oggi, nella capitale, l&#8217;amministrazione ha preso una decisione che prova a ridare una parvenza di noramlit\u00e0, ripristinando le lezioni scolastiche, naturalmente in modalit\u00e0 online. Una decisione volta a &#8220;distrarre&#8221; ragazzi e ragazze dalla quotidianit\u00e0 della guerra e offrire loro supporto psicologico.<\/p>\n<p><strong>28\/03 &#8211; ore 9.20<br \/>\n<\/strong><strong>Mariupol &#8220;\u00e8 bloccata dall\u2019esercito russo. <\/strong>Tutti gli ingressi e le uscite dalla citt\u00e0 sono bloccati &#8211; cos\u00ec ha affermato il presidente ucraino Zelensky in un&#8217;intervista-\u00a0 Il porto \u00e8 minato. Una catastrofe umanitaria sta inequivocabile accadendo, perch\u00e9 \u00e8 impossibile arrivarci con cibo, medicine e acqua. L\u2019esercito russo sta bombardando i convogli umanitari&#8221;.\u00a0 &#8220;Secondo i nostri dati, sono stati portati fuori pi\u00f9 di <strong>2000 bambini<\/strong> &#8211; ha affermato il presidente &#8211; la loro posizione esatta risulta sconosciuta. Possono essere l\u00ec con o senza genitori&#8230;&#8221;.<\/p>\n<p><strong>27\/03 &#8211; ore 17.10<br \/>\n<\/strong>Nelle ultime ore da pi\u00f9 parti vengono fatte analisi su un possibile cambio della strategia della Russia: dopo aver fallito l&#8217;intento iniziale di arrivare fino a Kiev in pochi giorni e dopo le difficolt\u00e0 di avanzamento riscontrate nel&#8217;ultimo periodo, ora Putin potrebbe decidere di concentrare i suoi sforzi sul Donbass, cercando di assicurarsi il conrtollo almeno di quella parte dell&#8217;Ucraina. Si tratta, per\u00f2, solamente di ipotesi che non hanno, al momento, conferme chiare nei fatti, anche se rimane evidente che \u00e8 proprio nella parte meridionale e orientale dell&#8217;Ucraina che le truppe russe continuano a colpire con maggiore violenza.<\/p>\n<p><strong>27\/03 &#8211; ore 9.50<br \/>\n<\/strong>Sono pi\u00f9 di <strong>100.000 le persone<\/strong> rimaste intrappolate nella citt\u00e0 ucraina di <strong>Mariupol<\/strong> mentre <strong>le scorte di cibo e di acqua scarseggiano.<\/strong> \u201c<em>Ci sono persone<\/em> \u2013 ha detto Sergey Orlov vice sindaco della citt\u00e0, riporta Agenpress &#8211; <em>che stanno morendo per disidratazione e mancanza di cibo. Alcuni muoiono per la mancanza di medicine, di insulina&#8230; Perch\u00e9 le persone non riescono a trovare assistenza medica&#8221;.<br \/>\n&#8220;Ci sono mamme che non hanno latte e che non hanno cibo per i bambini&#8221;.<\/em> \u201c<em>Le persone<\/em> \u2013 dichiara Orlov- <em>cercano solo ogni possibilit\u00e0 per sopravvivere. Condividono cibo, acqua, raccolgono legna per cucinare per strada\u201d.<\/em><\/p>\n<p><strong>26\/03 &#8211; ore 17.00<br \/>\n<\/strong>Dopo poco pi\u00f9 di un mese dall\u2019inizio del conflitto\u00a0<strong>in Ucraina<\/strong>, secondo quanto riportato dall\u2019<strong>Unhcr,<\/strong>\u00a0si stimano essere gi\u00e0\u00a0<strong>10 milioni le persone costrette a fuggire<\/strong>, lasciando la propria casa. Oltre 6,5 milioni di loro sono sfollate all\u2019interno del Paese, mentre sono circa <strong>3,7 milioni<\/strong> i profughi che hanno attraversato il confine. \u201cSi stima \u2013 sottolinea l\u2019Unhcr- che circa 13 milioni di persone siano bloccate nelle aree colpite, o siano impossibilitate ad andarsene a causa del rischio elevato per la loro sicurezza, della distruzione di ponti e strade e della mancanza di risorse o informazioni su dove trovare un alloggio e condizioni di sicurezza&#8221;. Ad oggi sono <strong>70.784<\/strong> i profughi ucraini giunti in Italia, 27.877 <strong>sono minori<\/strong>,\u00a0a riportarlo il Ministero dell\u2019Interno.<\/p>\n<p><strong>26\/03 &#8211; ore 10.00<br \/>\n<\/strong>Nel dramma della guerra in Ucraina, l&#8217;epicentro della violenza e della barbarie \u00e8 la citta di Mariupol, da giorni complita dalla bombe e senza acqua, cibo, elettricit\u00e0, rifornimenti. MIgliaia di persone sono intrappolate e senza aiuti, visto che i russi non fanno arrivare nulla in citt\u00e0. Davanti a questa situazione, il generale e vice capo della polizia nazionale ucraina Vyacheslav Abroskin (foto in apertura da Facebook) si \u00e8 offerto all&#8217;esercito russo come ostaggio in cambio della possibilit\u00e0 di portare fuori dalla citt\u00e0 i bambini rimasti. Il Generale \u00e8 gi\u00e0 ricercato dai russi e la sua proposta &#8220;conta&#8221; proprio su questo per essere accolta. Un atto di eroismo su cui, come riporta la news del sito Rai, i russi &#8220;stanno valutando&#8221;.<\/p>\n<p><strong>25\/03 &#8211; ore 18.10<br \/>\n<\/strong>A giorni di distanza dal bombardamento, arriva qualche informazione in pi\u00f9 sull&#8217;attacco al teatro di Mariupol, in cui erano rifugiate tantissime persone. Secondo fonti locali, da verificare, nell&#8217;attacco sono morte almeno 300 persone, tra cui tre donne incinte e una che aveva appena partorito.<\/p>\n<p><strong>25\/03 &#8211; ore 16.00<br \/>\n<\/strong>Il ponte che collega la citt\u00e0 ucraina di Solotvino a quella romena di Sighetu \u00e8 diventato un ponte di solidariet\u00e0 tra due popoli e di vicinanza e calore per i bambini in fuga dalle bombe. In una foto, pubblicata <a href=\"https:\/\/www.facebook.com\/politiadefrontieramaramures\/posts\/329941015835375\">sui social dalla polizia di frontiera rumena<\/a> di Sighetu Marmatiei, si vedono numerosi giocattoli disposti in bella vista sul checkpoint che unisce le due citt\u00e0. I piccoli di passaggio possono scegliere il proprio gioco e portarlo con s\u00e9. Un modo per alleviare anche se per poco, il loro dolore.<\/p>\n<p><strong>25\/03 &#8211; ore 11.30<br \/>\n<\/strong>Secondo gli ultimi dati pubblicati dal Viminale, sono<strong> 67.885<\/strong> i profughi ucraini giunti in Italia <strong>25.938 di loro sono minori.<\/strong><\/p>\n<p><strong>25\/03 &#8211; ore 9.50<br \/>\n<\/strong>Dopo un mese di guerra, 1 bambino ucraino su 2 \u00e8 stato costretto a fuggire dalla propria casa.\u00a0 A sottolinearlo \u00e8 stato in un&#8217;intervista alla CNN il portavoce dell&#8217;Unicef James Elder:\u00a0 &#8220;\u00c8 una situazione che non abbiamo mai visto prima, non a memoria d&#8217;uomo ed \u00e8 quasi impossibile da affrontare&#8221;.<\/p>\n<p><strong>24\/03 &#8211; 17.50<br \/>\n<\/strong>L&#8217;ONU ha votato una nuova risoluzione per chiedere la fine delle ostilit\u00e0 alla Russia. L&#8217;esito \u00e8 stato grossomodo come quello della votazione precedente, anche se aluni stati africani si sono aggiunti a quelli astenuti (mentre la scorsa volta avevano votato a favore). Tra gli astenuti &#8220;pesa&#8221; sempre il volto della Cina. I contrari, invece, oltre a Russia e Bielorussia, sono Corea del Nord, Siria ed Eritrea.<\/p>\n<p><strong>24\/03 &#8211; 09.45<br \/>\n<\/strong>Come annunciato dai deputati Paolo Siani e Paolo Lattanzio, rispettivamente vice presidente e capogruppo dem della Commissione Infanzia, comincia oggi, in Commissione Infanzia, la discussione sulle iniziative da adottare in favore dei bambini e degli adolescenti che si trovano in Ucraina e dei profughi minori di et\u00e0 provenienti da questa zona di conflitto.\u00a0\u201cL\u2019indagine &#8211; si legge nel comunicato stampa pubblicato sul sito dell&#8217;on. Lattanzio &#8211; ha l&#8217;obiettivo sia di approfondire in maniera duratura la questione della tutela dei bambini rimasti in Ucraina e dell\u2019accoglienza dei minori profughi, sia di elaborare proposte al governo e ai vari attori che stanno gestendo la parte emergenziale portando, come abbiamo fatto durante la pandemia, un focus specifico sul tema infanzia e adolescenza, una delle grandi emergenze all\u2019interno di questa tragedia\u201d.<br \/>\nDurante i lavori verranno ascoltati Ministre e Ministri cos\u00ec come le Associazioni impegnate sul campo.<\/p>\n<p><strong>23\/03 &#8211; 17.10<br \/>\n<\/strong>Jana \u00e8 una donna e una mamma scappata dall&#8217;Ucraina con i suoi due figli di 8 e 10 anni allo scoppio della guerra. <a href=\"http:\/\/aibi.it\/ita\/bambinixlapace-ai-bi-moldova-accoglie-una-nuova-collega-jana\/\">Arrivata in Moldova per cercare rifugio<\/a>, ha trovato, qui, tutto quello che cercava: \u201cUn tetto sopra la testa, un letto caldo per me e per i due bambini e da qualche giorno anche una seconda famiglia!\u201d. Ovvero la famiglia di Ai.Bi., che l&#8217;ha accolta e che ha trovato in Jana una preziosa risorsa, che ha subito messo a disposizione le sue conoscenze e abilit\u00e0 di insegnante e allenatrice di ginnastica e nuoto per portare un sorriso ai tantissimi bambini che si trovano nei campi d\u2019accoglienza in cui Ai.Bi. opera. Eccola, in un video, mentre porta il suo entusiasmo e il suo sorriso ai bambini del centro MoldExpo di Chisinau.<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/ogIhb53Htq8\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><strong>23\/03 &#8211; 10.15<br \/>\n<\/strong>Nella giornata di ieri, il Presidente dell&#8217;Ucraina Zelensky, oltre ad aver parlato in diretta con il parlamento, ha avuto anche un nuovo colloquio telefonico con Papa Francesco (i due si erano gi\u00e0 sentiti a fine febbraio, pochi giorni dopo l&#8217;inizio della guerra). Nel corso della telefonata Zelensky ha ribadito al Papa l&#8217;invito a recarsi a Kiev. In un Tweet il Presidente ha cos\u00ec riassunto il colloquio: &#8220;Ho riferito a Sua Santit\u00e0 la difficile situazione umanitaria e il blocco dei corridoi di soccorso da parte delle forze russe. Sarebbe accolto con favore il ruolo di mediazione della Santa Sede nel porre fine alla sofferenza umana. Ho ringraziato per le preghiere per la pace e per l\u2019Ucraina\u201d.<\/p>\n<p><strong>23\/03 &#8211; 10.00<br \/>\n<\/strong>Notte di bombe, purtroppo, in diverse parti dell&#8217;Ucraina. Le cronache riportano di un attacco a una stazione ferroviaria non lontano da Dnipro e a un edificio divile nella zona del Donbass. Qui si parla di tre vittime, due dei quali bambini. Anche a Kiev continuano gli scontri su alcuni edifici della citt\u00e0.<\/p>\n<p><strong>22\/03 &#8211; 21.20<br \/>\n<\/strong>Se per l&#8217;Italia l&#8217;ultimo dato del Ministero degli Interni parla di oltre 61mila profughi gi\u00e0 arrivati dall&#8217;inizio della guerra, l&#8217;UNHCR ha aggiornato il dato totale dei rifugiati ucraini che hanno lascioato il Paese: 3.557.245. Pi\u00f9 della met\u00e0 di questi sono scappati verso la Polonia. Seguono la Romania e la Moldova con 368mila, molti dei quali, per\u00f2, hanno poi proseguito verso l&#8217;Europa.<\/p>\n<p><strong>22\/03 &#8211; 17.40<br \/>\n<\/strong>Quotidiano aggiornamento da parte del Viminale sui numero dei profughi ucraini che hanno gi\u00e0 raggiunto l&#8217;Italia: sono 61.493, di cui 31.502 donne, 5.400 uomini e 24.591 minori.<\/p>\n<p><strong>22\/03 &#8211; 13.44<br \/>\n<\/strong>&#8220;<em>Oggi non \u00e8 previsto&#8221; un sostegno diretto alle famiglie che ospitano profughi: &#8220;passa tutto attraverso un&#8217;organizzazione centrale che \u00e8 la Protezione civile, il ministro dell&#8217;interno e quello dell&#8217;economia e delle finanze<\/em> <em>e\u00a0questo sembra funzionare <\/em>-Cos\u00ec ha affermato il Presidente Mario Draghi riferendosi agli aiuti da erogare per l&#8217;accoglienza dei profughi ucraini giunti nel nostro Paese, come riportato dall&#8217;Ansa &#8211; <em>In ogni caso quello che \u00e8 cruciale<\/em><em>\u00a0\u00e8 che <strong>gli aiuti<\/strong> che vengano dati direttamente o passino attraverso una procedura, <strong>vengano erogati subito<\/strong>, perch\u00e9 il bisogno \u00e8 ora non fra settimane&#8221;.<br \/>\n<\/em>Sul sito della <strong>protezione civile<\/strong> sono on line tutte le informazioni utili per i profughi ucraini ospiti nel nostro Paese: dagli obblighi sanitari da rispettare per far fronte alla pandemia, a chi rivolgersi per usufruire di un alloggio, a come regolarizzare la propria posizione in Italia. Per maggiori informazioni <a href=\"https:\/\/emergenze.protezionecivile.gov.it\/it\/pagina-base\/le-informazioni-utili-i-cittadini-ucraini\" target=\"_blank\" rel=\"noopener\">QUI<\/a><\/p>\n<p><strong>21\/03 &#8211; 18.30<br \/>\n<\/strong>Giornata ancora tra bombardamenti, accordi che non ci sono, accuse reciproche&#8230; Mosca ha rivendicato il bombardamento di un centro commerciale di Kiev affermando fosse un deposito di munizioni, mentre Kiev denuncia che a Mariupol, la citt\u00e0 assediata da settimane, le vittime civili sono ormai 3mila.<\/p>\n<p><strong>21\/03 &#8211; 13.20<br \/>\n<\/strong>Il Ministero dell&#8217;Interno ha aggiornato i dati sui profughi gi\u00e0 entrati in Italia: alle 12:44 di luned\u00ec 21 marzo si contano 59.589 persone. In maggioranza si tratta di donne (30.499) seguite da 23.877 minori e 5.213 uomini. Le principali destinazioni dichiarate all&#8217;ingresso sono le grandi citt\u00e0: Milano, Roma, Napoli e Bologna.<\/p>\n<p><strong>21\/03 &#8211; 10.00<br \/>\n<\/strong>Aggiornamento dalla Moldova: mentre proseguono i colloqui con il direttore del centro di Carpineni, per capire i bisogni della realt\u00e0 in cui Ai.Bi. sta portando avanti il lavoro di animazione, nella sede locale \u00e8 arrivata una nuova collega (animatrice) ucraina: come prima cosa ha tenuto a portare i suoi ringraziamenti e la grattitudine per l&#8217;accoglienza che ha trovato in Moldova e in Ai.Bi. Moldova in particolare.<\/p>\n<p><strong>20\/03 &#8211; 11.45<br \/>\n<\/strong>Mentre Ai.Bi. continua senza sosta il suo lavoro di accoglienza, preparando, grazie all&#8217;aiuto di tanti volontari, la casa di <strong>Mulazzano<\/strong>, quasi pronta per accogliere i bambvini delle case famiglia scappati dall&#8217;Ucraina, il Viminale aggiorna ancora i dati dei profughi finora arrivati in Italia: sono <strong>55.711<\/strong>, di cui 28.537 donne, 4.776 uomini e <strong>22.398 minori.<\/strong><\/p>\n<p><strong>19\/03 &#8211; 17.20<br \/>\n<\/strong>E intanto, anche lontano da casa, anche dopo essere scappati dalle bombe, anche se il futuro rimane un punto di domanda&#8230; Grazie alla generosit\u00e0 di chi ha aperto le sue braccia e di chi da settimane lavora senza sosta per fare tutto il possibile in favore dei profughi, in particolare i minori, si pu\u00f2 trovare il sorriso per festeggiare il proprio compleanno. \u00c8 successo anche oggi, a MoldExpo, il campo di Chisinau, in Moldova, dove Ai.Bi. quotidianamente organizza momenti ricreativi per i ragazzi e di supporto psicologico. Buon compleanno!<\/p>\n<div id='gallery-6' class='gallery galleryid-197352 gallery-columns-1 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-tutti-gli-aggiornamenti\/whatsapp-image-2022-03-19-at-16-26-11\/'><img loading=\"lazy\" decoding=\"async\" width=\"226\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-19-at-16.26.11-226x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-19-at-16.26.11-226x300.jpeg 226w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-19-at-16.26.11-113x150.jpeg 113w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-19-at-16.26.11.jpeg 630w\" sizes=\"auto, (max-width: 226px) 100vw, 226px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p><strong>19\/03 &#8211; 14.45<br \/>\n<\/strong>Sale a <strong>816<\/strong> il conto delle vittime del conflitto in Ucraina diffuso dall&#8217;ONU. A queste, si aggiungono 1333 feriti. Cifre gi\u00e0 di per s\u00e9 spaventose ma che tutti sanno essere inferiori alla realt\u00e0, potendo contare solo le morti effettivamente verificate fino a questo momento.<\/p>\n<p><strong>19\/03 &#8211; 9.10<br \/>\n<\/strong>Nuovo aggiornamento da parte del Viminale dei dati relativi ai profughi arrivati in Italia dall&#8217;inizio della guerra: a venerd\u00ec 18, ore 16:48, si contavano <strong>53.669<\/strong> profughi, di cui <strong>27.429<\/strong> donne,\u00a0<strong>4.582\u00a0<\/strong>uomini e\u00a0<strong>21.658<\/strong>\u00a0minori.<\/p>\n<p><strong>19\/03 &#8211; 9.00<br \/>\n<\/strong>Notte ancora di bombe, in Ucraina: a Mykolaiv \u00e8 stata colpita una base militare uccidendo, secondo le fonti, almeno 40 soldati. Continua il martirio di Mariupol, nel frattempo, con i russi che non permettono l&#8217;arrivo di aiuti umanitari e fanno uscire dalla citt\u00e0 unicamente qualche veicolo privato.<\/p>\n<p><strong>18\/03 &#8211; 17.50<br \/>\n<\/strong>Non si chiarisce ancora del tutto la situazione del teatro di Mariupol, pesantemente bombardato dai russi e all&#8217;interno del quale, secondo diverse fonti, si trovavano oltre 1000 persone in cerca di rifugio. Al momento pare siano in corso dei tentativi di missione di soccorso, rese per molto complicate dagli attacchi verso la citt\u00e0 che non si fermano. Secondo delle voci circolate in mattinata, almeno 130 persone sono riuscite a uscire dalla macerie del teatro, ma, come detto, il quadro \u00e8 molto incerto.<\/p>\n<p><strong>18\/03 &#8211; 14.50<br \/>\n<\/strong>Alla giornata di gioved\u00ec 17, i numeri comunicati dal Viminale riportano che i profughi finora entrari in Italia dall&#8217;Ucraina sono 50.649. Come gi\u00e0 ampiamente riportato fin dei primi arrivi, la grande maggioranza \u00e8 composta da donne (25.846) e minori (20.478). Gli uomini sono, invece, 4.325.<\/p>\n<p><strong>18\/03 &#8211; 9.50<br \/>\n<\/strong>La situazione sul campo sembra sostanzialmente in stallo: l&#8217;esercito russo non ha compiuto significativi passi avanti nelal conquista del territorio, ma sta continuando a bombardare da lontano diverse citt\u00e0. Nella giornata di oggi c&#8217;\u00e8 molta attesa verso l&#8217;annunciata telefonata tra il Presidente americano Biden quello cinese Xi Jinping: finora la Cina non ha assunto una posizione chiara in merito al conflitto, anche se non ha mai espressamente condannato la Russia e sembra essere sempre pi\u00f9 vicina alle sue posizioni piuttosto che a quelle dell&#8217;Occidente e della NATO.<\/p>\n<p><strong>17\/03 &#8211; 13.45<br \/>\n<\/strong>In Moldova prosegue senza sosta il lavoro dell&#8217;equipe di Ai.Bi. guidata da Stela. Sia ieri sia oggi sono state portati ai campi sul confine con l&#8217;Ucraina di Palancca cibi e bevande calde.<br \/>\nNel pomeriggio avverr\u00e0 un incontro con le animatrici e il direttore della struttura di Carpineni, mentre a Chisinau, nel campo MoldExpo continuano quotidianamente le attivit\u00e0 delle 2 equipe impegnate nell&#8217;accoglienza e l&#8217;animazione per i minori.<\/p>\n<p><strong>17\/03 &#8211; 8.46<br \/>\n<\/strong><strong>James Elder<\/strong>, portavoce dell&#8217;agenzia <strong>Onu<\/strong> per l&#8217;infanzia ha reso noto come <em>&#8220;In media, ogni giorno negli ultimi 20 giorni in Ucraina, pi\u00f9 di 70.000 bambini sono diventati rifugiati,<\/em>\u00a0<em>ci\u00f2 equivale a circa 55 ogni minuto, &#8220;quindi quasi uno al secondo&#8221;<\/em>. A riportarlo \u00e8 l&#8217;ANSA che sottolinea come dall&#8217;inizio del conflitto siano quasi <strong>3 milioni gli ucraini<\/strong> che hanno lasciato il proprio Paese.<\/p>\n<p><strong>16\/03 &#8211; 17.01<br \/>\n<\/strong>La Regione <strong>Lombardia<\/strong> ha pubblicato alcune importanti informazioni riguardanti l<strong>\u2019assistenza sanitaria<\/strong> per i profughi provenienti dall\u2019Ucraina, specificando come l\u2019assistenza sanitaria sul territorio lombardo\u00a0<strong>sia \u201c<em>garantita gratuitamente a tutti i cittadini provenienti dall\u2019Ucraina\u00a0<\/em><\/strong><em>e in fuga dalla guerra, che abbiano necessit\u00e0 sanitarie per patologie acute o croniche<\/em>\u201d. Maggiori informazioni <a href=\"https:\/\/www.regione.lombardia.it\/wps\/portal\/istituzionale\/HP\/DettaglioRedazionale\/servizi-e-informazioni\/cittadini\/salute-e-prevenzione\/Emergenze-e-urgenze\/assistenza-sanitaria-ucraina\/assistenza-sanitaria-ucraina\">QUI<\/a><br \/>\nAnche la Regione <strong>Lazio<\/strong> <a href=\"https:\/\/www.regione.lazio.it\/helpukraine#:~:text=Per%20l'assistenza%20sanitaria%20gratuita,strutture%20sanitarie%20pubbliche%20e%20private\">QUI<\/a> ha pubblicato sul proprio sito, sia in lingua italiana che in l<strong>ingua ucraina<\/strong>, alcune importanti indicazioni riguardanti il permesso di soggiorno temporaneo, l&#8217;assistenza sanitaria o il reperimento di beni di prima necessit\u00e0. Chi si trovasse nella Regione Lazio e avesse <strong>bisogno di un alloggio<\/strong> o di assistenza pu\u00f2 compilare il form <a href=\"https:\/\/protezionecivile.regione.lazio.it\/form\/scheda-anamnestica-\">QUI<\/a><\/p>\n<p><strong>14\/03 &#8211; 18.50<br \/>\n<\/strong>Arriva un nuovo aggiornamento dall&#8217;ONU per quanto riguarda il unmero dei migranti: gi\u00e0 3 milioni pe persone che hanno lasciato l&#8217;Ucraina dallo scoppio del conflitto. Il tweet dello IOM (International Organization for Migration) sottolinea che si tratta di 150 mila persona al giorno; 6250 ogni ora; 104 al minuti; 2 al secondo.<\/p>\n<p><strong>14\/03 &#8211; 10.40<br \/>\n<\/strong>Nella mattina di marted\u00ec 14 marzo il Ministro degli Esteri e della Cooperazione Internazionale <strong>Luigi Di Maio<\/strong> si \u00e8 recato al campo di MoldExpo, a Chisinau, nell&#8217;ambito della sua visita in Romania e Moldova. Qui ha incontrato anche Stela, la Direttrice di Ai.Bi. \/ Moldova che dall&#8217;ainizio del conflitto sta lavorando per portare aiuti e organizzare la messa in salvo dei profughi. Il Ministro si \u00e8 informato delle attivit\u00e0 di Ai.Bi. in Moldova e ha ringraziato per tutto quello che si sta facendo per i bambini ucraini.<\/p>\n<p><strong>13\/03 &#8211; 14.45<br \/>\n<\/strong>Firmata da parte della protezione divicle un&#8217;ordinanza che prevede l agratuit\u00e0 dei trasporti sul territorio italiano entro 5 giorni dall&#8217;ingresso in Italia dei profughi dall&#8217;Ucraina. L&#8217;agevolazione vale per\u00a0i treni della societ\u00e0 Trenitalia (Gruppo FS) che effettuano servizio di Intercity, Eurocity e Regionali, sui servizi marittimi e sulla rete autostradale. \u00abLa fattiva collaborazione con il Ministero delle Infrastrutture e della Mobilit\u00e0 Sostenibili, Trenitalia e Aiscat ha portato a questa importante misura che rappresenta un ulteriore tassello nel piano di accoglienza della popolazione in fuga dalla guerra \u2013 ha detto il Capo Dipartimento, Fabrizio Curcio \u2013. Siamo di fronte a uno scenario delicato e complesso che il nostro Paese deve affrontare in modo sinergico\u00bb.<\/p>\n<p><strong>13\/03 &#8211; 12.15<br \/>\n<\/strong>Quarto giro di negoziati tra Ucraina e Russia. Questa volta i colloqui si svolgeranno online, tra le due delegazioni, ma ancora una volta non ci sono grosse speranza che l&#8217;incontro possa portare a qualche soluzione concreta a breve termine.<\/p>\n<p><strong>13\/03 &#8211; 16.10<br \/>\n<\/strong>L&#8217;UNHCR ha nuovamente aggiornato il numero dei profughi scappati dall&#8217;Ucraina dall&#8217;inizio della guerra: sono gi\u00e0 2,7 milioni, per quello che la Nazioni Unite hanno definito il pi\u00f9 grande esodo di sfollati dalla Seconda Guerra Mondiale.<\/p>\n<p><strong>13\/03 &#8211; 12.15<br \/>\n<\/strong>Papa Francesco, durante il tradizionale Angelus della domenica, ha usate parole molto forti e decise nei confronti della guerra in Ucraina. Il Pontefice ha richiamto il martirio della citt\u00e0 di Mariupol, bombardata senza tregua in questa settimana: &#8220;Uccidere bambini \u00e8 barbarie&#8221; ha tuonato il Papa, che ha unito la sua volce a quella di tutta la &#8220;gente comune&#8221; che implora la fine della guerra. L&#8217;invito del Papa \u00e8 stato all&#8217;apertura di negoziati e corridoi umanitari, per fermare &#8220;in nome di Dio&#8221; questo massacro. Perch\u00e9 &#8220;Dio \u00e8 Dio della pace e non della guerra&#8221;.<\/p>\n<p><strong>13\/03 &#8211; 11.40<br \/>\n<\/strong>Non ci sono sabati e domeniche davanti all&#8217;emergenza. La sa bene Stela, la direttrice di Ai.Bi. \/ Moldova, che da quando \u00e8 scoppiata la guerra lavora senza sosta con il suo staff per organizzare, accogliere, aiutare&#8230; Risolta, ieri, una delicata situazione che coinvolgeva i componenti della casa fmaiglia sfollata da Odessa, oggi \u00e8 di nuovo in viaggio verso la frontiera di Palanca per portare aiuti ai profughi nei campi allestiti sul confine.<\/p>\n<div class=\"wp-playlist wp-video-playlist wp-playlist-light\">\n\t\t<video controls=\"controls\" preload=\"none\" width=\"978\"\n\t\t height=\"538\"\t><\/video>\n\t<div class=\"wp-playlist-next\"><\/div>\n\t<div class=\"wp-playlist-prev\"><\/div>\n\t<noscript>\n\t<ol>\n\t\t<li><a href='https:\/\/www.aibi.it\/ita\/images\/2022\/03\/Stela_placinte_Palanca.mp4'>Stela_placinte_Palanca<\/a><\/li>\t<\/ol>\n\t<\/noscript>\n\t<script type=\"application\/json\" class=\"wp-playlist-script\">{\"type\":\"video\",\"tracklist\":true,\"tracknumbers\":true,\"images\":true,\"artists\":true,\"tracks\":[{\"src\":\"https:\/\/www.aibi.it\/ita\/images\/2022\/03\/Stela_placinte_Palanca.mp4\",\"type\":\"video\/mp4\",\"title\":\"Stela_placinte_Palanca\",\"caption\":\"\",\"description\":\"\",\"meta\":{\"length_formatted\":\"0:15\"},\"dimensions\":{\"original\":{\"width\":640,\"height\":352},\"resized\":{\"width\":978,\"height\":538}},\"image\":{\"src\":\"https:\/\/www.aibi.it\/ita\/wp-includes\/images\/media\/video.svg\",\"width\":48,\"height\":64},\"thumb\":{\"src\":\"https:\/\/www.aibi.it\/ita\/wp-includes\/images\/media\/video.svg\",\"width\":48,\"height\":64}}]}<\/script>\n<\/div>\n\t\n<p><strong>13\/03 &#8211; 11.00<br \/>\n<\/strong>Continuano le operazione militari in Ucraina. E se nei dintorni di Kiev la situazione \u00e8 come sospesa, con le truppe russe che stanno compiendo movimenti di accerchiamento, probabilmente in previsione di un prossimo assedio, il bombardamento pi\u00f9 importante \u00e8 avvenuto nei pressi della base militare di Leopoli. Si \u00e8 trattato dell&#8217;attacco pi\u00f9 a ovest finora avvenuto, a poche decine di chilometri dal confine della Polonia.<\/p>\n<p><strong>13\/03 &#8211; 10.15<br \/>\n<\/strong>Continuano L&#8217;Opera di Odessa ha tenuto un concerto improvvisato sulla piazza della citt\u00e0. Qui, il &#8220;Va Pensiero&#8221; dal Nabucco di Verdi<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"cs\">Nabuchodonosor, Verdi 1\/2 <a href=\"https:\/\/t.co\/F7pbWzawBs\">pic.twitter.com\/F7pbWzawBs<\/a><\/p>\n<p>\u2014 Pierre Alonso (@pierre_alonso) <a href=\"https:\/\/twitter.com\/pierre_alonso\/status\/1502613188336136194?ref_src=twsrc%5Etfw\">March 12, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><strong>12\/03 &#8211; 10.25<br \/>\n<\/strong>Non ci sono grosse novit\u00e0 sul fronte del conflitto: l&#8217;evacuazione da alcune citt\u00e0 prosegue con grandissima fatica, in mancanza di percorsi sicuri e di un &#8220;cessate il fuoco&#8221; che possa reggere. Altre citt\u00e0, invece, continuano a essere bombardate, in particolare la gi\u00e0 martoriata Mariupol, ormai da giorni colpita indiscriminatamente e ormai senza acqua, riscaldamento ed elettricit\u00e0, evidenziando una strategia dal parte dell&#8217;esercito russo gi\u00e0 vista in Cecenia e in Siria.<\/p>\n<p><strong>11\/03 &#8211; 12.20<br \/>\n<\/strong>L&#8217;UNHCR, come fa ormai periodicamente dall&#8217;inizio del conflitto in Ucraina, ha aggiornato il numero dei profughi: l&#8217;ultima stima \u00e8 che siano gi\u00e0 2,5 milioni le persone scappate dal Paese, mentre altri 2 milioni sono gli sfollati interni, ovvero che hanno lasciato le loro case abituali e hanno cercato riparo in altre zone dell&#8217;Ucraina pi\u00f9 sicure e lontane dagli epicentri degli attacchi russi.<\/p>\n<p><strong>10\/03 &#8211; 21.50<br \/>\n<\/strong>I nuovi dati del Viminale sui profughi che hanno gi\u00e0 raggiunto l&#8217;Italia: alla mattina di gioved\u00ec 10 marzo si contano 26.738 rifugiati provenienti dall&#8217;Ucraina, di cui 10.894 minori.<br \/>\nSul fronte ucraino, invece, le Nazioni Unite calcolano che la guerra scatenata dalla Russia abbia provocato finora 549 morti tra i civili e 957 feriti. Ma \u00e8 opinione di quasi tutti che i numeri reali siano ben peggiori.<\/p>\n<p><strong>9\/03 &#8211; 21.55<br \/>\n<\/strong>Dall&#8217;inizio del conflitto in Ucraina, la Moldavia \u00e8 il Paese messo pi\u00f9 sotto pressione dall&#8217;arrivo dei profughi. Non tanto in termini assoluti (la frontiera con la Polonia \u00e8 quella attraversata di gran punga dal pi\u00f9 alto numero di persone), quanto in rapporto alla popolazione e la grandezza del territorio. Gli ultimi dati aggiornati al 9 marzo parlano di <strong>259.564 cittadini<\/strong> ucraini entrati in Moldova. Di questi, 157.736 hanno proseguito il loro esodo in altri Paesi; <strong>101.485<\/strong> sono invece rimasti sul territorio.<br \/>\nPer quanto riguarda l&#8217;Italia, secondo l&#8217;ultimo aggiornamento del Viminale sono gi\u00e0 23.872 i profughi arrivati nel nostro Paese.<\/p>\n<p><strong>9\/03 &#8211; 15.15<br \/>\n<\/strong>Non \u00e8 positivo l&#8217;aggiornamento fornito dall&#8217;agenzia Reuters in merito ai corridoi umanitari che avrebbero dovuto essere garantiti per l&#8217;evacuazione dei civili: anche oggi, come gi\u00e0 successo ieri, l&#8217;unico che semba reggere \u00e8 quello dalla citt\u00e0 di Sumy. A Mariupol, invece, la situazione \u00e8 sempre pi\u00f9 compromessa: la Croce Rossa lancia l&#8217;allarme e Kiev denuncia la presenza di 400mila civili bloccati, senza acqua, cibo n\u00e9 riscldamento. Circolano diversi video del terribile bombardamento dell&#8217;ospedale pediatrico della citt\u00e0.<\/p>\n<p><strong>9\/03 &#8211; 10.20<br \/>\n<\/strong>Si aprono nuovo spiragli, nella giornata odierna, per la tenuta dei &#8220;cessate il fuoco&#8221; che consentano l&#8217;evacuazione dei civili da diverse citt\u00e0 dell&#8217;Ucraina, in particolare Enerhodar. Ma la situazione pi\u00f9 delicata \u00e8 sempre a Mariupol, citt\u00e0 di circa 500 mila abitanti che da giorni \u00e8 sottoposta a pesanti bombardamenti e per la quale i tantativi di tregua dei giorni scorsi sono stati tutti disattesi.<\/p>\n<p><strong>8\/03 &#8211; 17.35<br \/>\n<\/strong>Mentre la tregua sembra aver retto nella citt\u00e0 di Sumy, permettendo l&#8217;evacuazione di migliaia di civili, non altrettanto \u00e8 successo a Maripuol. Intanto, nel pomeriggio, l&#8217;Alto commissariato delle Nazioni Unite per i diritti umani ha fatto una nuova stima dei civili morti finora nella guerra in Ucraina: 474, cui si aggiungono 861 feriti. Ma il conteggio \u00e8 tutto tranne che certo, con le autorit\u00e0 dell&#8217;Ucraina che da giorni parlano di un numero di morti civili ben maggiore.<\/p>\n<p><strong>8\/03 &#8211; 10.30<br \/>\n<\/strong>Sono arrivati a Carpineni i 13 bambini e i 5 adulti sfollati in emergenza da una casa famiglia di Odessa e per i quali era stato chiesto aiuto ad Ai.Bi. Dopo un viaggio difficile, prima in territorio Ucraino fino alla frontiera di Palanca, poi, da qui, fino a Carpineni, il gruppo \u00e8 arrivato a destinazione, sul pulmino con la scritta &#8220;bambini&#8221; dipinta sulla fiancata. Nelle prossime ore altre 8 persone dovrebbero aggiungersi, arrivando in autonomia. Ma il viaggio non \u00e8 ancora finito: Ai.Bi. sta organizzando il trasferimento in Italia e la sistemazione in una struttura dove, finalmente, tutti possano trovare un po&#8217; di serenti\u00e0.<\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-197908 size-full\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/03\/auto_bambini_rid.jpeg\" alt=\"\" width=\"1200\" height=\"630\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/03\/auto_bambini_rid.jpeg 1200w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/auto_bambini_rid-571x300.jpeg 571w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/auto_bambini_rid-150x79.jpeg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/auto_bambini_rid-768x403.jpeg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><br \/>\n<\/strong><\/p>\n<p><strong>7\/03 &#8211; 18.15<br \/>\n<\/strong>Continuano a crescere, in maniera impressionante, i numeri dell&#8217;emergenza. Secondo l&#8217;ultimo rapporto di OCHA, in Ucraina <strong>12 milioni<\/strong> di persone necessitano di assistenza umanitaria. Le vittime civili che si contano dall&#8217;inizio del conflitto sono 1.123, di cui 364 uccise. <strong>500.000 i bambini che sono gi\u00e0 fuggiti<\/strong> dall&#8217;Ucraina.<br \/>\nA seguito della chiusura delle scuole in tutto il Paese, l&#8217;accesso all&#8217;istruzione impatta su 5,7 milioni di bambini e adolescenti.<br \/>\n1,5 milioni di persone sono fuggite dall&#8217;Ucraina verso i vicini paesi negli ultimi 10 giorni, tra cui pi\u00f9 di 885.000 persone nella sola Polonia.<br \/>\nPer quanto riguarda l&#8217;Italia, invece, anche il Viminale ha aggiornato il numero degli sfollati entrati nel nostro Paese: <strong>17.286.<\/strong> Di cui 8.608 donne, 1.682 uomini e 6.996 minori.<\/p>\n<p><strong>7\/03 &#8211; 13.20<br \/>\n<\/strong>Con il grande esodo di profughi dall&#8217;Ucraina, tutti i Paesi confinanti si stanno organizzando, non solo per l&#8217;accoglienza, ma anche per l&#8217;assistenza e la logistica rivolta ai tanti che vogliono proseguire il loro viaggio. In Moldova, l&#8217;aeronautica civile ha previsto dei voli charter proprio per questo. On line \u00e8 stato predisposto un modulo da compilare per organizzare al meglio i voli charter durante questo periodo di emergenza. Il modulo si pu\u00f2 compilare <a href=\"https:\/\/www.caa.md\/en\/form-regarding-organization-of-charter-flights-during-the-state-of-emergency-4-216\" target=\"_blank\" rel=\"noopener\">QUI<\/a><\/p>\n<p><strong>7\/03 &#8211; 10.25<br \/>\n<\/strong>Nella serata di domenica \u00e8 arrivata ad Ai.Bi. una richiesta di emergenza: 13 bambini e 5 adulti, sfollati da una casa famiglia di Odessa, avevano urgente bisogno di accoglienza. Subito, Stela, la direttrice di Ai.Bi. Moldova, si \u00e8 attivata per organizzare una missione di emergenza. Grazie alla disposnibilit\u00e0 del direttore di una struttura a Carpineni che ha messo a disposizione 18 posti letto. Porprio in queste ore \u00e8 in corso l&#8217;operazione, con i profughi che sono partiti da Odessa e si incontrareanno a breve con il pulmino predisposto da Ai.Bi., con il quale <a href=\"https:\/\/www.aibi.it\/ita\/emergenza-in-ucraina-aibi-sfollati-casa-famiglia-odessa\/\">verranno portati a Carpineni<\/a>, in attesa, magari, di una sistenzione diversa pi\u00f9 a lungo termine.<\/p>\n<p><strong>7\/03 &#8211; 09.30<br \/>\n<\/strong>Secondo diverse fonti, questa mattina dovrebbe esserci un &#8220;cessate il fuoco&#8221; per permettere l&#8217;evacuazione dei civili dalle grandi citt\u00e0. Ma visti i fallimenti delle ultime tregue, nulla \u00e8 sicuro. Intanto continua l&#8217;esodo di chi riesce a uscire dal Paese: secondo gli ultimi dati del Ministero dell&#8217;Interno, sono 14.237 i profughi accolti finora in Italia.<\/p>\n<p><strong>6\/03 &#8211; 17.25<br \/>\n<\/strong>Anche il secondo tentativo di stabilire un cessate il fuoco \u00e8 fallito. Questa mattina sembrava che le operazioni di evacuazione potessero proseguire dalla citt\u00e0 di Mariupol, tanto che erano girate le immagini di diversi pullman che si avvicinavano alla citt\u00e0 per portare via i civili. Ma gli scontri non si sono mai interrotti del tutto e nel pomeriggio anche la Croce Rossa ha comunicato il fallimento dell&#8217;operazione.<\/p>\n<p><strong>6\/03 &#8211; 9.00<br \/>\n<\/strong><a href=\"https:\/\/www.aibi.it\/ita\/emergenza-ucraina-la-fondazione-sipec-aderisce-alliniziativa-di-ai-bi-bambinixlapace\/\">Anche la Fondazione Sipec aderisce all\u2019iniziativa di Ai.Bi. #BAMBINIxLAPACE<\/a> e lancia il suo appello: <i>\u201cChiediamo, a chi pu\u00f2 di unirsi a noi nella raccolta fondi per sostenere la campagna di Amici dei Bambini in aiuto alle famiglie colpite dalla guerra in Ucraina #BAMBINIxLAPACE\u201d.<\/i> Da sempre vicina all\u2019Associazione Ai.Bi. e attenta alle iniziative a favore dell\u2019infanzia in difficolt\u00e0, la\u00a0<b>Fondazione Sipec<\/b>\u00a0si \u00e8 subito attivata per portare il proprio contributo alla popolazione ucraina, in particolare donne, bambini e anziani che in fuga dalla guerra cercano protezione nei campi sfollati della vicina Moldova.<\/p>\n<p><strong>5\/03 &#8211; 22.35<br \/>\n<\/strong>La tregua che avrebbe dovuto consentire l&#8217;evacuazione dei civili dalle citt\u00e0 sotto assedio di Mariupol e Volnovakha non \u00e8 stata rispettata. Kiev e Mosca si accusano a vicenda per il mancato cessate il fuoco ma, al di l\u00e0 delle responsabilit\u00e0, l&#8217;unico risultato tangibile \u00e8 che gli attacchi russi sono proseguiti e la situazione non \u00e8 migliorata. Un nuovo spiraglio si apre per luned\u00ec, quando dovrebbe tenersi il terzo round dei negoziati tra le delegazioni di Ucraina e Russia. Intanto, un po&#8217; a sorpresa, anche il premier israeliano Naftali Bennett si \u00e8 recato a Mosca per provare a mediare con Putin.<\/p>\n<p><strong>5\/03 &#8211; 18.45<br \/>\n<\/strong>Continua l&#8217;esodo della popolazione ucraina. Gli ultimi dati rilevano solo sul territorio moldavo la presenza di <strong>7.500 profughi<\/strong>, accolti nei vari centri. Solo a Chisinau ne sono stati contati 3.500. Ma non solo i campi profughi sono attivi, anche le singole famiglie accolgono gli sfollati, come ha fatto Tatiana, dell\u2019equipe di Ai.Bi., che attende proprio per stasera una famiglia in fuga.<br \/>\nAi.Bi. intanto, continua il suo lavoro nel campo di MoldExpo, gi\u00e0 sovraffollato, e porta aiuto nei due campi allestiti alle dogana di Palanca e Ocnita. Sta venendo organizzata anche una presenza pi\u00f9 costante a <strong>Carpineni<\/strong>, dove verr\u00e0 riattivata la ludoteca e Ai.Bi. dovrebbe fornire 2 animatori in presenza fissa.<\/p>\n<p><strong>5\/03 &#8211; 18.15<br \/>\n<\/strong>Nel pomeriggio di sabato 5 marzo a Roma si \u00e8 svolta la manifestazione \u201cEurope for Peace\u201d che ha visto, secondo gli organizzatori, oltre 50 mila partecipanti chiedere l\u2019immediato cessate il fuoco e il ripristino della pace in Europa. Tante le bandiere e le sigle presenti, in prima fila anche AOI (Associazione ONG italiane), che aderisce alla Rete Italiana Pace e Solidariet\u00e0. Tra i presenti anche i rappresentanti di Ai.Bi., guidati dalla referente relazione istituzionali e responsabile delle sedi di Ai.Bi. Marzia Masiello.<\/p>\n<div id='gallery-7' class='gallery galleryid-197352 gallery-columns-2 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/whatsapp-image-2022-03-05-at-14-21-08\/'><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-05-at-14.21.08-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-05-at-14.21.08-400x300.jpeg 400w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-05-at-14.21.08-150x113.jpeg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-05-at-14.21.08-768x576.jpeg 768w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-05-at-14.21.08.jpeg 1024w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/whatsapp-image-2022-03-05-at-14-21-08-1\/'><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-05-at-14.21.08-1-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-05-at-14.21.08-1-400x300.jpeg 400w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-05-at-14.21.08-1-150x113.jpeg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-05-at-14.21.08-1-768x576.jpeg 768w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-05-at-14.21.08-1.jpeg 1200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p><strong>05\/03 &#8211; 14.07<br \/>\n<\/strong>L&#8217;emergenza profughi continua. In Moldova, la nostra cooperante Stela e l&#8217;equipe di Ai.Bi. lavorano senza sosta. Questa mattina sono stati contattati per un intervento di urgenza, per portare beni di prima necessit\u00e0 a 16 adulti e 30 bambini trovati infreddoliti, spaventati ed affamati all&#8217;esterno di un campo, in un prato. Con loro non avevano nulla.<\/p>\n<p><strong>05\/03 &#8211; 11.38<br \/>\n<\/strong>Previsti per oggi, in Ucraina, l&#8217;apertura di apertura di corridoi umanitari per consentire alla popolazione di Mariupol e Volnovakha di lasciare le citt\u00e0.<\/p>\n<p><strong>04\/03 \u2013 Ore 22.50<\/strong><br \/>\nIn serata l&#8217;aggiornamento arriva direttamente dal capo della Protezione Civile Fabrizio Curcio: in Italia i profughi ucraini sono ormai 9 mila. Solo nella giornata di gioved\u00ec 3 marzo ne sono entrati nel nostro Paese 2500. L&#8217;accoglienza diventa sempre di pi\u00f9 l&#8217;emergenza principale.<\/p>\n<p><strong>04\/03 \u2013 Ore 18.05<\/strong><br \/>\nSecondo quanto ci riferisce Stela, la cooperante di Ai.Bi. a Chisinau, impegnata in prima persona nel coordinamento degli aiuti in Moldova, a oggi sono 138mila i profughi entrati nel Paese dall&#8217;Ucraina. Di questi, 63 mila hanno proseguito per altri Paesi d&#8217;Europa, gli altri hanno trovato accoglienza nei campi profughi che continuano a essere allestiti sul territorio.<\/p>\n<p><strong>04\/03 \u2013 Ore 16.50<\/strong><br \/>\nSe 1,2 milioni sono gli sfollati che, in totale, hanno gi\u00e0 lasciato l&#8217;Europa, oltre 6mila di questi hanno gi\u00e0 raggiunto l&#8217;Italia. Un Tweet del Viminale, ormai di ieri, ha dato queste cifre: 6.608 i cittadini ucraini entrati in Italia dall\u2019inizio del conflitto: 3.286 donne, 804 uomini e 2.518 minori. Famiglie e comunit\u00e0 si sono subito mosse con una straordinaria generosit\u00e0, ma \u00e8 doveroso ricordare, anche in momenti come questi, come al di l\u00e0 del generoso slancio di accoglienza, sia essenziale conoscere chi sono le persone che ci si appresta ad accogliere, da dove provengono e che storia si portano sulle spalle. Per questo motivo il FARIS sta organizzando degli\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-possiamo-accogliere-in-italia-un-minore-con-la-sua-famiglia\/\" target=\"_blank\" rel=\"noopener\">incontri informativi online\u00a0<\/a>dove vengono presentate le possibili forme di accoglienza di rifugiati e bambini. Le date sono in continuo aggiornamento, visto che al momento sono gi\u00e0 oltre 450 le richieste di partecipazione arrivate da tutta Italia.<\/p>\n<p><strong>04\/03 \u2013 Ore 15.40<\/strong><br \/>\nSta diventando sempre pi\u00f9 chiaro che l&#8217;energenza primaria, al di fuori dei confini dell&#8217;Ucraina \u00e8, e sar\u00e0, quella riguardante i profughi. I numeri sono impressionanti, cos\u00ec come impressionante \u00e8 la loro crescita nel giro di brevissimo tempo. Secondo l&#8217;ultimo aggiornamento dell&#8217;UNHCR, ma i cui dati sono aggiornati al 2 marzo, gli sfollati dall&#8217;Ucraina hanno gi\u00e0 raggiunto quota 1,2 milioni. Di questi, oltre il 50% sono entrati in Polonia, mentre gi\u00e0 103 mila hanno cercato rifugio in Moldavia.<br \/>\n[sotto, <a href=\"http:\/\/data2.unhcr.org\/en\/situations\/ukraine\" target=\"_blank\" rel=\"noopener\">l&#8217;immagine dell&#8217;UNHCR<\/a> sulla destinazione presa dalle persone in fuga dall&#8217;Ucraina]\n<div id='gallery-8' class='gallery galleryid-197352 gallery-columns-1 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/profughi_ucraina\/'><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/03\/profughi_Ucraina.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/03\/profughi_Ucraina.jpg 1200w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/profughi_Ucraina-571x300.jpg 571w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/profughi_Ucraina-150x79.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/profughi_Ucraina-768x403.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p><strong>04\/03 \u2013 Ore 10.05<\/strong><br \/>\nSi aggiorna di ora in ora la stima dei profughi che si prevede lasceranno l&#8217;Ucraina nei prossimi giorni: secondo le ultime previsioni si parla di 7 &#8211; 8 milioni di persone, ma gi\u00e0 qualcuno si spinge alla cifra di 10 milioni, quasi un quarto della popolazione del Paese. L&#8217;Europa si apre all&#8217;accoglienza, con i primi Paesi confinanti subito mobilitatisi in prima persona, ma con tutte le altre nazione pronte a fare la propria parte, sia inviando aiuti, sia preparandosi ad accogliere i tanti sfollati che arriveranno nelle prossime settimane.<br \/>\nDa questo punto di vista, l&#8217;Unione Europea ha deciso di attivare il meccanismo di protezione temporanea che prevede il rilascio di un permesso di soggiorno valido un anno, rinnovabile, la libert\u00e0 di movimento all\u2019interno dell\u2019Ue, l&#8217; assistenza sanitaria e il diritto all\u2019istruzione per i minori.<br \/>\nPer i tantissimi che stanno dando la propria disponibilit\u00e0 per l&#8217;accoglienza, il Faris &#8211; Family Relationship International School, la scuola di relazioni familiari di Ai.Bi., ha attivato una serie di webinar di formazione per preparare le famiglie ad accogliere i profughi.<br \/>\nTutte le informazioni riguardanti i webinar si possono trovare <a href=\"https:\/\/www.fondazioneaibi.it\/faris\/emergenza-ucraina-in-2-giorni-300-richieste-di-disponibilita-allaccoglienza-giunte-ad-ai-bi-dalle-famiglie-italiane\/\">QUI<\/a><\/p>\n<p><strong>04\/03 \u2013 Ore 09.30<\/strong><br \/>\nLa Duma che approva all&#8217;unanimit\u00e0 una legge per rendere un reato la divulgazione di notizie false (che per un paradosso, significa quella che nel resto del mondo sono le notizie &#8220;vere&#8221;); dichiarazioni che ribadiscono l&#8217;intenzione di non fermare in alcun modo le operazioni militari finch\u00e9 &#8220;l&#8217;unico popolo&#8221; di russi e ucraini sar\u00e0 unito; il video della devastazione di un Paese nei pressi di Kiev, edifici civili compresi&#8230; Se questi sono i segnali della giornata successiva ai colloqui tra Russia e Ucraina, ci vuole davvero un notevole sforzo di volont\u00e0 per guardare al futuro pi\u00f9 immediato con ottimismo.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Drone footage showed destruction of buildings and burnt out Russian military vehicles in Ukraine\u2019s Borodyanka, a town near Kyiv where locals claimed they had repelled a Russian assault <a href=\"https:\/\/t.co\/fxUQvGWe9W\">https:\/\/t.co\/fxUQvGWe9W<\/a> <a href=\"https:\/\/t.co\/VWdon9Pzrf\">pic.twitter.com\/VWdon9Pzrf<\/a><\/p>\n<p>\u2014 Reuters (@Reuters) <a href=\"https:\/\/twitter.com\/Reuters\/status\/1499488533622448134?ref_src=twsrc%5Etfw\">March 3, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>;<\/p>\n<p><strong>03\/03 \u2013 Ore 22.30<\/strong><br \/>\nSecondo quanto riportano tutti i media, i colloqui tenutisi tra Russia e Ucraina hanno portato a una intesa sulla creazione di corridoi umanitari e di un cessate il fuoco temporaneo. A riferirlo &#8211; riporta l&#8217;Ansa &#8211; \u00e8 il consigliere di Zelensky, citato dalla Tass.<\/p>\n<p><strong>03\/03 \u2013 Ore 16.15<\/strong><br \/>\nProsegue quasi senza sosta il flusso degli sfollati verso i campi profughi allestiti nei Paesi confinanti dell&#8217;Ucraina. In Moldova, dove Stala sta coordinando il lavoro dell&#8217;equipe di Ai.Bi., il primo centro di MoldExpo, un ex centro Covid trasformato, ora, in campo per gli sfollati. La capienza massima sarebbe di 460 posti, ma gi\u00e0 ora sono presenti circa 600 persone. Proprio in questi minuti \u00e8 arrivata anche la richiesta di supporto da un altro campo, che ha appena accolto circa 200 persone e si trova in difficolt\u00e0 non avendo generi di prima necessit\u00e0 da fornire loro. Ai.Bi. Moldova si \u00e8 subito attivata per portare aiuti anche l\u00ec.<\/p>\n<p><strong>03\/03 \u2013 Ore 10.00<\/strong><br \/>\nNotte particolarmente difficile al confine tra l&#8217;Ucraina e la Moldova, dove \u00e8 arrivato il maltempo con neve e pioggia a complicare la situazione degli sfollati. Soprattutto nei campi profughi in Dogana il freddo si \u00e8 fatto sentire. L&#8217;equipe di Ai.Bi. sta lavorando senza sosta, sia per portare aiuti direttamente ai campi in dogana, sia per proseguire le attivit\u00e0 di animazione e di supporto psicologico nei centri di Chisinau.<br \/>\nMa \u00e8 pronta a intervenire e portare il propprio supporto anche in altri punti della citt\u00e0 e del Paese, in una situazione che \u00e8 in continua, veloce, evoluzione. Sotto, qualche foto dei bambini arrivati ieri, soprattutto dalla citt\u00e0 di Odessa.<\/p>\n<div id='gallery-9' class='gallery galleryid-197352 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-tutti-gli-aggiornamenti\/image011\/'><img loading=\"lazy\" decoding=\"async\" width=\"520\" height=\"293\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/03\/image011.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/03\/image011.jpg 520w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/image011-150x85.jpg 150w\" sizes=\"auto, (max-width: 520px) 100vw, 520px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-tutti-gli-aggiornamenti\/image013\/'><img loading=\"lazy\" decoding=\"async\" width=\"520\" height=\"293\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/03\/image013.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/03\/image013.jpg 520w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/image013-150x85.jpg 150w\" sizes=\"auto, (max-width: 520px) 100vw, 520px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-tutti-gli-aggiornamenti\/image009\/'><img loading=\"lazy\" decoding=\"async\" width=\"520\" height=\"293\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/03\/image009.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/03\/image009.jpg 520w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/image009-150x85.jpg 150w\" sizes=\"auto, (max-width: 520px) 100vw, 520px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p><strong>02\/03 \u2013 Ore 17.15<\/strong><br \/>\nContinua a crescere il numero degli sfollati. Un nuovo aggiornamento delle Nazioni Unite riportato dall&#8217;Ansa stima che siano gi\u00e0 836mila i profughi che hanno varcato le frontiere dei Paesi vicini. Ovunque si racconta di una straordinaria mobilitazione da parte della popolazione locale per accogliere gli ucraini, diversi dei quali cercano, poi, di proseguire il viaggio verso i parenti nei vari Paesi in Europa. Tanti, per\u00f2, rimangono, trovano accoglienza nei campi come quelli di Chisinau, dove Ai.Bi. \u00e8 presente con le sue attivit\u00e0 ricreative e di supporto psicologico.<\/p>\n<p><strong>02\/03 \u2013 Ore 10.30<\/strong><br \/>\nAltra notte di combattimenti e di bombardamenti sulle citt\u00e0 dell&#8217;Ucraina. Mentre dalla Russia arrivano notizie di alcune citt\u00e0 pi\u00f9 piccole conquistate dall&#8217;esercito, prosegue inarrestabile l&#8217;esodo delle persone che scappano. Secondo l&#8217;UNHCR (l&#8217;Agenzia ONU per i Rifugiati) sono gi\u00e0 660 mila gli sfollati che hanno varcato le frontiere arrivando nei Paesi confinanti.<\/p>\n<p><strong>01\/03 \u2013 Ore 18.30<\/strong><br \/>\nIl noto vaticanista del <em>Corriere della Sera<\/em> Gian Guido Vecchi, ha pubblicato su Twitter un allarme arrivato alla sede romana della chiesa ortodossa ucraina; &#8220;Salvare Santa Sofia&#8221;. Sono giunte informazioni &#8211; si legge &#8211; che le truppe russe stanno preparando un attacco aereo sul santuario pi\u00f9 importante del popolo ucraino dai tempi della Rus&#8217; di Kyiv. Sua beatitudine Sviatoslav, Capo e Padre della Chiesa greco-cattolica ucraina, invita tutti i cristiani a pregare per il santuario spiritualedei popoli slavi ed esorta l&#8217;aggressore ad astenersi da questo orribile atto di vandalismo.<\/p>\n<p><strong>01\/03 \u2013 Ore 16.00<\/strong><br \/>\nL&#8217;ambasciata d&#8217;Italia in Ucraina ha spostato la sua sede da Kiev, sempre pi\u00f9 sotto l&#8217;assedio delle truppe russe, a Leopoli, citt\u00e0 pi\u00f9 vicina al confine con la Polonia. Nel trasferimento, secondo quanto riporta l&#8217;Ansa, l&#8217;ambasciatore italiano a Kiev, Zazo, \u00e8 riuscito a portare con s\u00e9 circa 20 minori, tra cui 6 neonati. Questi minori erano gi\u00e0 stati accolti nei giorni scorsi in ambascita, perch\u00e9 privi di un posto sicuro in cui stare.<\/p>\n<p><strong>01\/03 \u2013 Ore 13.05<\/strong><br \/>\nNel campo profughi di Chisinau, in Moldova, continuano ad arrivare profughi che lasciano l&#8217;Ucraina. Ai.Bi., attraverso il lavoro della sua equipe, coordinata da Stela, cooperante nel Paese, ha iniziato a portare sul posto le prima attivit\u00e0 di supporto. In particolare, sono state organizzate delle attivit\u00e0 ludiche per i bambini, per cercare di fare vivere loro questo momento difficile con un po&#8217; di serenit\u00e0.<\/p>\n<p><iframe loading=\"lazy\" title=\"Ai.Bi. Associazione Amici dei Bambini\" width=\"1000\" height=\"563\" src=\"https:\/\/www.youtube.com\/embed\/o0ukp-ZcTHw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<div id='gallery-10' class='gallery galleryid-197352 gallery-columns-4 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/whatsapp-image-2022-03-01-at-11-24-49\/'><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-01-at-11.24.49-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-01-at-11.24.49-400x300.jpeg 400w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-01-at-11.24.49-1200x900.jpeg 1200w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-01-at-11.24.49-150x113.jpeg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-01-at-11.24.49-768x576.jpeg 768w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-01-at-11.24.49-1536x1152.jpeg 1536w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-01-at-11.24.49.jpeg 1600w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/whatsapp-image-2022-03-01-at-11-24-50-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-01-at-11.24.50-2-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-01-at-11.24.50-2-400x300.jpeg 400w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-01-at-11.24.50-2-1200x900.jpeg 1200w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-01-at-11.24.50-2-150x113.jpeg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-01-at-11.24.50-2-768x576.jpeg 768w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-01-at-11.24.50-2-1536x1152.jpeg 1536w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-01-at-11.24.50-2.jpeg 1600w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/whatsapp-image-2022-03-01-at-11-24-50-1\/'><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-01-at-11.24.50-1-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-01-at-11.24.50-1-400x300.jpeg 400w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-01-at-11.24.50-1-1200x900.jpeg 1200w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-01-at-11.24.50-1-150x113.jpeg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-01-at-11.24.50-1-768x576.jpeg 768w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-01-at-11.24.50-1-1536x1152.jpeg 1536w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-01-at-11.24.50-1.jpeg 1600w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/whatsapp-image-2022-03-01-at-11-24-50\/'><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-01-at-11.24.50-400x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-01-at-11.24.50-400x300.jpeg 400w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-01-at-11.24.50-1200x900.jpeg 1200w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-01-at-11.24.50-150x113.jpeg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-01-at-11.24.50-768x576.jpeg 768w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-01-at-11.24.50-1536x1152.jpeg 1536w, https:\/\/www.aibi.it\/ita\/images\/2022\/03\/WhatsApp-Image-2022-03-01-at-11.24.50.jpeg 1600w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p><strong>01\/03 \u2013 Ore 09.50<\/strong><br \/>\nNotizie sempre pi\u00f9 terribili arrivano dall&#8217;Ucraina, dove i russi hanno intensificato i bombardamenti colpendo anche edifici civili. Un lunghissimo convoglio di mezzi militari \u00e8 stato fotografato dai satelliti in avvicnamento a Kiev, mentre nella giornata di ieri gli attacchi pi\u00f9 pesanti si sono concentrati nella citt\u00e0 di Kharkiv.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"it\">Una bomba colpisce la sede dell\u2019amministrazione provinciale di Kharkov <a href=\"https:\/\/t.co\/dY0BkwNbl2\">pic.twitter.com\/dY0BkwNbl2<\/a><\/p>\n<p>\u2014 GeopoliticalCenter (@GeopoliticalCen) <a href=\"https:\/\/twitter.com\/GeopoliticalCen\/status\/1498549980147167235?ref_src=twsrc%5Etfw\">March 1, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><strong>28\/02 \u2013 Ore 22.10<\/strong><br \/>\nOlte le bombe, i negoziati inconcludenti, la follia degli uomini e gli atti di coraggio, il sole sorge e tramonta come sempre. <strong>Anche sul cielo di Kiev<\/strong>. Oggi, per qualche ora durante il pomeriggio, l&#8217;intensit\u00e0 degli scontri \u00e8 diminuita e le persone sono riuscite a uscire da casa e dai rifugi. Come Mila, un&#8217;altra collaboratrice di Ai.Bi. che \u00e8 rimasta a Kiev e cos\u00ec ci scrive: &#8220;Sono uscita per fare due passi e ho visto tanta gente in giro, bambini che giocavano e avevano voglia di vivere la loro vita quotidiana. Questa situazione <strong>ci ha uniti<\/strong> e adesso, camminando per strada, incontro le persone che <strong>mi augurano buona giornata e sorridono<\/strong>, perch\u00e9 si sono svegliate e hanno davanti un nuovo giorno&#8221;.<\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-197543 size-full\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/Kiev_Ucraina.jpeg\" alt=\"\" width=\"1200\" height=\"629\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/Kiev_Ucraina.jpeg 1200w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/Kiev_Ucraina-572x300.jpeg 572w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/Kiev_Ucraina-150x79.jpeg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/Kiev_Ucraina-768x403.jpeg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/strong><\/p>\n<p><strong>28\/02 \u2013 Ore 18.35<\/strong><br \/>\nIntanto, in Italia, il Consiglio dei Ministri ha approvato un decreto-legge che introduce ulteriori misure urgenti sulla crisi in Ucraina.<br \/>\nOltre ad alcune decisioni in tema di <strong>difesa<\/strong> e di <strong>energia,<\/strong> il provvedimento \u201cprende prime misure per l\u2019eventualit\u00e0 che una parte del flusso dei profughi si indirizzi presso il nostro Paese\u201d, dove c\u2019\u00e8 una presenza di circa <strong>250mila cittadini ucraini<\/strong>. Il decreto prevede \u201cil rafforzamento della rete di accoglienza degli stranieri. Inoltre, si dispone che i cittadini ucraini vengano ospitati nei CAS anche indipendentemente dal fatto che abbiano presentato domanda di protezione internazionale\u201d.<br \/>\nIl Consiglio dei Ministri ha inoltre dichiarato <strong>lo stato di emergenza fino al 31 dicembre 2022<\/strong> \u201cin relazione all\u2019esigenza di assicurare soccorso e assistenza alla popolazione ucraina sul territorio nazionale in conseguenza della grave crisi internazionale in atto. Al fine di organizzare ed attuare gli interventi pi\u00f9 urgenti sono stati stanziati 10 milioni di euro, a carico del Fondo per le emergenze nazionali.\u201d<\/p>\n<p><strong>28\/02 \u2013 Ore 16.45<\/strong><br \/>\nLa cooperante di Ai.Bi., Stela, \u00e8 stata in uno dei centri allestiti a Chisinau, capitale della Moldava, dove viene data assistenza ai profughi dall\u2019Ucraina. Gi\u00e0 centinaia le persone accolte, nel contesto di un esodo che, secondo l\u2019Alto commissario ONU per i rifugiati Filippo Grandi, conta gi\u00e0 <strong>500mila persone<\/strong> scappate dal Paese.<br \/>\nAl momento, nei campi viene fornita la prima assistenza, ma il centro unico per la gestione della crisi, di cui Ai.Bi. fa parte, e che viene coordinato dal Governo moldavo, sta incrementando gli interventi di assistenza. In particolare, l\u2019equipe di Ai.Bi. gi\u00e0 da donami sar\u00e0 attiva nel centro con attivit\u00e0 di <strong>animazione per i bambini<\/strong> e di <strong>supporto psicologico<\/strong>.<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/4lL98QDsEP0\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><strong>28\/02 \u2013 Ore 15.10<br \/>\n<\/strong>Mentre sono in corso i negoziati, \u00e8 stato segnalato un intenso bombardamento delle truppe russe a Kharkiv. Tante, secondo il ministero dell&#8217;Interno ucraino le vittime civili. In rete sono molti i video dei bombardamenti.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">This is what they are doing now to Kharkiv &#8211; a city that they totally believed was part of the &#8220;Russian world&#8221;. What will they do to the OTHERS?? <a href=\"https:\/\/t.co\/PXKVVG5snq\">pic.twitter.com\/PXKVVG5snq<\/a><\/p>\n<p>\u2014 Christo Grozev (@christogrozev) <a href=\"https:\/\/twitter.com\/christogrozev\/status\/1498286881544577024?ref_src=twsrc%5Etfw\">February 28, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><strong>28\/02 \u2013 Ore 10.30<br \/>\n<\/strong>Breve aggiornamento dalla Moldova dalla nostra cooperante Stela, che ieri \u00e8 stata nei campi allestiti sul confine con l&#8217;Ucraina: &#8220;Abbiamo ordinato lenzuola, cuscini e le coperte; stiamo reclutando gli animatori e gli psicologi; abbiamo ordinato i giochi per allestire gli spazi gioco al centro profughi di Chisinau. Aspettiamo dal Ministero la lista dei centri dove c&#8217;\u00e8 pi\u00f9 bsogno di intervenire, dove ci sono p\u00f9 bambini&#8221;.<br \/>\nCome si pu\u00f2 capire l&#8217;attivit\u00e0 procede frenetica, grazie anche a tutti gli aiuti che di ora in ora arrivano sempre pi\u00f9 numerosi.<\/p>\n<p><strong>28\/02 \u2013 Ore 09.40<br \/>\n<\/strong>Durante la notte sono proseguiti i bombardamenti sul territorio ucraino, in particolare gli scontri sono violenti nella citt\u00e0 di\u00a0Kharkiv, oltre che Kiev. In attesa dell&#8217;incontro tra le delegazioni di Russia e Ucraina, dal quale, per\u00f2, \u00e8 parere unanime, non ci si aspettano grossi passi avanti, viste le posizioni distantissime da cui partono gli interlocutori, le sanzioni dell&#8217;Unione Europea si fanno sentire. In mattinata il valore del Rublo (la moneta russa) \u00e8 crollato arrivando a uno dei valori pi\u00f9 bassi mai raggiunti.<\/p>\n<p><strong>27\/02 \u2013 Ore 20.15<br \/>\n<\/strong>\u201cLa situazione di grave precariet\u00e0 dei minori orfani in Ucraina a seguito dell\u2019aggressione russa suscita preoccupazione e richiede di attivare con sollecitudine tutte le misure a loro tutela previste dagli accordi internazionali. Nella cornice dei rapporti gi\u00e0 in essere in materia di adozioni internazionali tra l\u2019Italia e l\u2019Ucraina, siamo impegnati in queste ore nell\u2019attivazione di corridoi speciali per i minori orfani, perch\u00e9 al pi\u00f9 presto ed in sicurezza possano raggiungere il nostro Paese. L\u2019Ambasciata italiana in Ucraina \u00e8 al lavoro per creare le condizioni delle partenze, mentre in Italia la Commissione per le Adozioni Internazionali si sta attivando per predisporre la prima accoglienza, per la quale ha gi\u00e0 offerto collaborazione l\u2019Istituto degli Innocenti di Firenze\u201d.<br \/>\nQuesta la nota congiunta della ministra per le Pari opportunit\u00e0, nonch\u00e9 presidente della Commissione per le adozioni internazionali Elena Bonettie, e del ministro degli Affari esteri e della Cooperazione internazionale Luigi Di Maio, che aprono ufficialmente la strada per l&#8217;arrivo in Italia dei bambini degli orfanotrofi dell&#8217;Ucraina.<\/p>\n<div id='gallery-11' class='gallery galleryid-197352 gallery-columns-1 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-tutti-gli-aggiornamenti\/bambini-guerra-in-ucraina\/'><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/bambini-guerra-in-ucraina.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/bambini-guerra-in-ucraina.jpeg 1200w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/bambini-guerra-in-ucraina-571x300.jpeg 571w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/bambini-guerra-in-ucraina-150x79.jpeg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/bambini-guerra-in-ucraina-768x403.jpeg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p><strong>27\/02 \u2013 Ore 18.50<br \/>\n<\/strong>Alcune immagini della distribuzione di alimenti da parte della cooperante di Ai.Bi. Stela e altre volontarie. Lunghissima la fila gi\u00e0 creatasi al confine tra Ucraina o Moldova dove sono stati allestiti tre campi di emergenza.<\/p>\n<div id='gallery-12' class='gallery galleryid-197352 gallery-columns-2 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/distribuzione-confine-moldova-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/distribuzione-confine-Moldova-2-300x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/distribuzione-confine-Moldova-2-300x300.jpeg 300w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/distribuzione-confine-Moldova-2-1024x1024.jpeg 1024w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/distribuzione-confine-Moldova-2-150x150.jpeg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/distribuzione-confine-Moldova-2-768x768.jpeg 768w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/distribuzione-confine-Moldova-2.jpeg 1496w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/distribuzione-confine-moldova\/'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/distribuzione-confine-Moldova-225x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/distribuzione-confine-Moldova-225x300.jpeg 225w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/distribuzione-confine-Moldova-768x1024.jpeg 768w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/distribuzione-confine-Moldova-113x150.jpeg 113w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/distribuzione-confine-Moldova-1152x1536.jpeg 1152w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/distribuzione-confine-Moldova.jpeg 1200w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p><strong>27\/02 \u2013 Ore 15.30<br \/>\n<\/strong>\u00c8 stata confermata la notizia dell&#8217;organizzazione di una incontro tra una delegazione del governo russo e una del governo ucraino. Dopo qualche trattativa, alla fine l&#8217;incontro dovrebbe avvenire in un luogo al confine tra Ucraina e Bielorussia, anche se ancora non sono chiari i termini su ci\u00f2 che verr\u00e0 discusso e i tempi nei quali l&#8217;incontro potr\u00e0 avvenire.<\/p>\n<p><strong>27\/02 \u2013 Ore 12.25<\/strong><br \/>\nStela, la cooperante di Ai.Bi. in Moldova, insieme a un&#8217;altra volontaria \u00e8 partita per portare cibo e aiuti ai campi profughi allestiti nella Dogane, al confine tra Ucraina e Moldova. Nel bagagliaio della macchina tutte le scatole di &#8220;placinte&#8221; (focacce) che ci stavano e bevande calde.<\/p>\n<div id='gallery-13' class='gallery galleryid-197352 gallery-columns-2 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-tutti-gli-aggiornamenti\/whatsapp-image-2022-02-27-at-12-20-46\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/WhatsApp-Image-2022-02-27-at-12.20.46-300x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/WhatsApp-Image-2022-02-27-at-12.20.46-300x300.jpeg 300w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/WhatsApp-Image-2022-02-27-at-12.20.46-1024x1024.jpeg 1024w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/WhatsApp-Image-2022-02-27-at-12.20.46-150x150.jpeg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/WhatsApp-Image-2022-02-27-at-12.20.46-768x768.jpeg 768w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/WhatsApp-Image-2022-02-27-at-12.20.46-1536x1536.jpeg 1536w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/WhatsApp-Image-2022-02-27-at-12.20.46.jpeg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-tutti-gli-aggiornamenti\/whatsapp-image-2022-02-27-at-12-20-51\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/WhatsApp-Image-2022-02-27-at-12.20.51-300x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/WhatsApp-Image-2022-02-27-at-12.20.51-300x300.jpeg 300w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/WhatsApp-Image-2022-02-27-at-12.20.51-1024x1024.jpeg 1024w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/WhatsApp-Image-2022-02-27-at-12.20.51-150x150.jpeg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/WhatsApp-Image-2022-02-27-at-12.20.51-768x768.jpeg 768w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/WhatsApp-Image-2022-02-27-at-12.20.51-1536x1536.jpeg 1536w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/WhatsApp-Image-2022-02-27-at-12.20.51.jpeg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n<p><strong>27\/02 \u2013 Ore 10.08<\/strong><br \/>\nI combattimenti pi\u00f9 aspri, al momento, si stanno verificando a Kharkiv, la seconda citt\u00e0 del paese. I soldati russi sono in citt\u00e0 e gli scontri avvengono ormai per le strade.<br \/>\nNel frattempo, Masha, la cooperante di Ai.Bi. in Ucraina, che \u00e8 riuscita a lasciare Kiev nei giorni scorsi, racconta di un&#8217;altra notte di &#8220;resistenza&#8221; da parte di sua sorella e dei suoi amici rimasti nella capitale. &#8220;Stanno&#8230;&#8221; &#8211; dice con un sorriso tirato e rassegnato. &#8220;Il problema ora \u00e8 che anche la connessione Internet inizia a essere instabile&#8221;, rendendo ancora pi\u00f9 complicate le comunicazioni.<\/p>\n<p><strong>27\/02 \u2013 Ore 09.34<\/strong><br \/>\nAltra notte di combattimenti. Faticano ad arrivare notizie dal territorio, ma, come sempre capita in situazioni come quella che stanno vivenso in Ucraina, le storia personali di chi prova a resistere, come si pu\u00f2, contro la follia della guerra, sono quelle che colpiscono di pi\u00f9. Anche giornalisti di lungo corso che ne hanno viste tante, come riporta la giornalista della Reuters Anita Komuves su Twitter<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">I have never cried while reporting. Until today. <a href=\"https:\/\/t.co\/B6gb82YXr6\">https:\/\/t.co\/B6gb82YXr6<\/a><\/p>\n<p>\u2014 Anita Komuves (@AnitaKomuves) <a href=\"https:\/\/twitter.com\/AnitaKomuves\/status\/1497561772198445056?ref_src=twsrc%5Etfw\">February 26, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><strong>26\/02 \u2013 Ore 23.44<\/strong><br \/>\nSuonano le sirene nel cielo di Kiev, gli abitanti si recano nei rifugi, mentre le autorit\u00e0 annunciano la possibilit\u00e0 di &#8220;pesanti raid aerei&#8221;. Intanto, l&#8217;Unione Europa fa sapere che verr\u00e0 proposta la possibilit\u00e0 di estromettere alcune banche russe dal sistema internazionale di pagamenti SWIFT.<br \/>\nLa Germania, che da alcuni giorni veniva indicata come il Paese europeo pi\u00f9 cauto sulle sanzioni verso la Russia, annuncia l&#8217;invio di armi in Ucraina per difendersi e la prossima chiusura dello spazio aereo tedesco agli aerei russi, come gi\u00e0 hanno fatto o stanno valutando di fare altri Paesi europei<\/p>\n<p><strong>26\/02 \u2013 Ore 18.40<\/strong><br \/>\nInizia a intensificarsi il flusso dei profughi che cerca rifugio in Moldavia. Il Governo, con le associazioni coinvolte nella task force, tra le quali Ai.Bi., stanno valutando un nuovo intervento di emergenza, alla dogana con l&#8217;Ucraina, almeno per i prossimi giorni. Riporta Stela, la cooperante di Ai.Bi. in MOldova: &#8220;Visto il flusso molto grande, oggi, di persone che vogliono entrare in Moldova, si \u00e8 creata una fila lunghissima di persone&#8230; Soprattutto verso sera non farebbe male poter dare loro almeno un tazza di te&#8217; caldo e una &#8216;placinta&#8217; (un piatto tipico della Moldavia, Romania e del Sud dell&#8217;Ucraina n.d.r.). Quello che finora si riesce a portare non basta. I bambini, in particolare, chiedono sempre da mangiare&#8221;.<\/p>\n<p><strong>26\/02 \u2013 Ore 15.50<\/strong><br \/>\nAnche all&#8217;orfanotrofio Volodarka, dove si trovano i 180 minori che Ai.Bi. segue da anni con il progetto di Adozione a Distanza, si sta allestando un campo per accogliere i porofughi. La struttura si presta per questa operazione, trovandosi a circa 140 chilometri da Kiev, in una posizione di relativa, maggiore sicurezza, e per gli ampi spazi a disposizione. Gli insegnanti della scuola e le aducatrici di Ai.Bi. che si trovano sul posto riferiscono che gi\u00e0 stanno arrivando le prime famiglie, provenienti soprattutto dalle regioni di Kiev e di Donetsk (la zona del Donbass).<\/p>\n<p><strong>26\/02 \u2013 Ore 15.20<\/strong><br \/>\nTra i primi Paesi a muoversi con azioni concrete in favore dell&#8217;Ucraina c&#8217;\u00e8 la Moldavia, che ha un allestito o sta allestendo due campi profughi per la prima emergenza al confine e altri due nella capitale Chisinau. Di questi, uno \u00e8 gi\u00e0 completamente attivo e al momento ospita 426 persone di cui 40 bambini. Proprio verso questi campi profughi, e altri che verranno allestiti in seguito, si concentrar\u00e0 l&#8217;aiuto di Ai.Bi. sostenuto dalla campagna <strong>#BAMBINIxLAPACE<\/strong><br \/>\n<iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fphoto.php%3Ffbid%3D315759333919215%26set%3Da.222820439879772%26type%3D3&amp;show_text=true&amp;width=500\" width=\"500\" height=\"333\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><br \/>\n<strong>\u00a0<\/strong><\/p>\n<p><strong>26\/02 \u2013 Ore 10.40<br \/>\n<\/strong>Notte di guerra a Kiev: gli scontri tra le truppe russe e l&#8217;esercito ucraino si sono intensificati. Tanti civili hanno risposto all&#8217;appello e si sono presentati da volontari per combattere e difendere il loro Paese.<br \/>\nNelle prime ore della mattina un missile ha centrato un palazzo residenziale a Kiev: dal 14\u00b0 al 21\u00b0 piano \u00e8 completamente ditrutto, per fortuna sembra fosse stato evacuato e non ci siano morti, in questo scoppio, tra i civili.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Another video of the shelling <a href=\"https:\/\/t.co\/vt2ZqL8jcP\">pic.twitter.com\/vt2ZqL8jcP<\/a><\/p>\n<p>&mdash; NEXTA (@nexta_tv) <a href=\"https:\/\/twitter.com\/nexta_tv\/status\/1497469371018588167?ref_src=twsrc%5Etfw\">February 26, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><strong>25\/02 \u2013 Ore 18.20<br \/>\n<\/strong>12 ore di auto per fare circa 100 chilometri e spostarsi fuori citt\u00e0, in cerca di una maggiore sicurezza. Chi \u00e8 rimasto a Kiev, ora, \u00e8 impossibilitato a fuggire. Ormai le truppe russe sparano anche sui palazzi. Gli abitanti continuano a fare avanti e indietro dai rifugi, mentre dalle finestre degli appartamenti vedono i carri armati nelle strade. Carri armati che, \u00e8 capitato, schiacciano le auto parcheggiate senza un motivo.<\/p>\n<p><strong>25\/02 \u2013 Ore 16.30<br \/>\n<\/strong>Almeno un&#8217;ora di fila necessaria per fare benzina. &#8220;Ma per fortuna ci consentono di farne fino a 40 litri&#8221;.<br \/>\nLa situazione pi\u00f9 preoccupante \u00e8 all&#8217;interno delle grandi citt\u00e0, dove continuano i bombardamenti.<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/XaotLo2ur3Q\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><strong>25\/02 \u2013 Ore 12.46<br \/>\n<\/strong>Secondo quanto riferisce Masha, la cooperante di Ai.Bi. a Kiev, due pullman che stavano andando nella parte est del Paese per prendere dei profughi sono stato bombardati.<br \/>\nDa Kiev, invece, al momento non ci sono molte possibilit\u00e0 di partire e lasciare la citt\u00e0.<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/0BsMadVMB48\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><strong>25\/02 \u2013 Ore 10.57<br \/>\n<\/strong>Si mobilita la Moldavia per accogliere i profughi ucraini. \u00c8 stato costituito un gruppo di lavoro gestito dal Ministero con la partecipazione di alcune Associazioni, tra le quali Ai.Bi., che in Moldavia \u00e8 presente attraverso la sua cooperante Stela.<br \/>\nAl momento sono stati allestiti <strong>due punti di prima assistenza<\/strong> direttamente alla dogana, dove i profughi possono rimanere per un massimo di 72 ore. \u00c8 stato allestito, inoltre, un campo profughi a Chisinau, la capitale del Paese, con una capacit\u00e0 massima di 450 posti. Al momento, si segnalano gi\u00e0 100 persone presenti nel campo.<\/p>\n<p><strong>25\/02 \u2013 Ore 7.50 <\/strong><br \/>\nQualche foto condivisa da Masha nelle chat di WhatsApp con altri cittadini di Kiev, che mostrano alcuni momenti di questa notte terribile<\/p>\n<div id='gallery-14' class='gallery galleryid-197352 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/images\/2022\/02\/ukr-01.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"274\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/ukr-01-274x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/ukr-01-274x300.jpg 274w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/ukr-01-137x150.jpg 137w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/ukr-01.jpg 740w\" sizes=\"auto, (max-width: 274px) 100vw, 274px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/images\/2022\/02\/ukr-02.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"274\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/ukr-02-274x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/ukr-02-274x300.jpg 274w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/ukr-02-137x150.jpg 137w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/ukr-02.jpg 740w\" sizes=\"auto, (max-width: 274px) 100vw, 274px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/images\/2022\/02\/ukr-03.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"274\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/ukr-03-274x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/ukr-03-274x300.jpg 274w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/ukr-03-137x150.jpg 137w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/ukr-03.jpg 740w\" sizes=\"auto, (max-width: 274px) 100vw, 274px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p><strong>25\/02 &#8211; Ore 06.54<br \/>\n<\/strong>Notte di bombe, a Kiev. In molti hanno preferito passare rifugiarsi nella relativa sicurezza delle banchine della metro, ma al risveglio hanno trovato i soldati che ormai girano per le vie della capitale armati di fucili automatici.<br \/>\nDopo un giorno di combattimenti, la situazione si \u00e8 gi\u00e0 fatta decisamente complicata: lasciare la citt\u00e0 \u00e8 difficilissimo, con diversi ponti distrutti (non si capisce se dagli stessi ucraini per rallentare l\u2019avanzata dei soldati russi, o dalle truppe russe) e posti di blocco con mezzi blindati sulle altre vie d\u2019accesso.<\/p>\n<p>Dai il tuo contributo ora per i <strong>#BAMBINIxLAPACE<\/strong><\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*197331-start*\/\n#btnsx-197331{margin-top:0px;margin-bottom:25px;margin-left:0px;margin-right:0px;padding-top:16px;padding-bottom:15px;padding-left:43px;padding-right:44px;}\n#btnsx-197331 .btnsx-text-primary{text-transform:uppercase;font-size:20px;line-height:20px;font-weight:800;font-family:Raleway;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-197331:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-197331{background-color:#dd3333!important;}\n#btnsx-197331:hover{background-color:#d13030!important;}\n#btnsx-197331{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px;}\n#btnsx-197331:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:solid;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px;}\n#btnsx-197331{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-197331:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*197331-end*\/\n<\/style>\n<a href=\"https:\/\/dona.aibi.it\/emergenza-ucraina\/?act=cplt&amp;origine=web-button-in-post\" id=\"btnsx-197331\" class=\"btnsx-btn btnsx-btn-block\"  data-font-primary=\"Raleway\">\n\t<span class=\"btnsx-text-primary \">EMERGENZA UCRAINA<\/span><\/a>\n\n<!-- Buttons X - End -->\n\n","protected":false},"excerpt":{"rendered":"<p>EMERGENZA UCRAINA. Al termine di un colloquio con il Presidente USA Biden, il presidente ucraino Zelensky si dice soddisfatto che &ldquo;la nostra formula di pace&rdquo; sia stata percepita positivamente. Disponibilit&agrave; della Santa Sede a essere terreno comune per un incontro. Ma sul campo la guerra non si ferma<\/p>\n","protected":false},"author":102,"featured_media":201290,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[909],"tags":[895,840,913,423],"class_list":["post-197352","post","type-post","status-publish","format-standard","has-post-thumbnail","category-bambinixlapace","tag-bambinixlapace","tag-guerra","tag-kiev","tag-ucraina"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Guerra in Ucraina: tutti gli aggiornamenti<\/title>\n<meta name=\"description\" content=\"Guerra in Ucraina. freddo non ferma le attivit\u00e0 del progetto #BAMBINIxLAPACE, a cui saranno devolute le donazioni dell&#039;evento di Natale \u201cIl Bello che Fa Bene\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-tutti-gli-aggiornamenti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EMERGENZA UCRAINA. Zelensky apre alla pace. Vaticano: \u201cDisponibili come spazio in cui le parti possano avviare un dialogo\u201d\" \/>\n<meta property=\"og:description\" content=\"Guerra in Ucraina. freddo non ferma le attivit\u00e0 del progetto #BAMBINIxLAPACE, a cui saranno devolute le donazioni dell&#039;evento di Natale \u201cIl Bello che Fa Bene\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-tutti-gli-aggiornamenti\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-12T10:00:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-25T12:50:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/bombe-Kiev-Ucraina-guerra.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2022\/11\/guerra-ucraina-aggiornamento-kiev-senza-acqua.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"136 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/guerra-in-ucraina-tutti-gli-aggiornamenti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/guerra-in-ucraina-tutti-gli-aggiornamenti\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"EMERGENZA UCRAINA. Zelensky apre alla pace. Vaticano: \u201cDisponibili come spazio in cui le parti possano avviare un dialogo\u201d\",\"datePublished\":\"2022-12-12T10:00:58+00:00\",\"dateModified\":\"2023-10-25T12:50:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/guerra-in-ucraina-tutti-gli-aggiornamenti\\\/\"},\"wordCount\":25320,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/guerra-in-ucraina-tutti-gli-aggiornamenti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/06\\\/bombe-Kiev-Ucraina-guerra.jpg\",\"keywords\":[\"BAMBINIxLAPACE\",\"guerra\",\"Kiev\",\"Ucraina\"],\"articleSection\":[\"BAMBINIXLAPACE\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/guerra-in-ucraina-tutti-gli-aggiornamenti\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/guerra-in-ucraina-tutti-gli-aggiornamenti\\\/\",\"name\":\"Guerra in Ucraina: tutti gli aggiornamenti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/guerra-in-ucraina-tutti-gli-aggiornamenti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/guerra-in-ucraina-tutti-gli-aggiornamenti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/06\\\/bombe-Kiev-Ucraina-guerra.jpg\",\"datePublished\":\"2022-12-12T10:00:58+00:00\",\"dateModified\":\"2023-10-25T12:50:59+00:00\",\"description\":\"Guerra in Ucraina. freddo non ferma le attivit\u00e0 del progetto #BAMBINIxLAPACE, a cui saranno devolute le donazioni dell'evento di Natale \u201cIl Bello che Fa Bene\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/guerra-in-ucraina-tutti-gli-aggiornamenti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/guerra-in-ucraina-tutti-gli-aggiornamenti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/guerra-in-ucraina-tutti-gli-aggiornamenti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/06\\\/bombe-Kiev-Ucraina-guerra.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/06\\\/bombe-Kiev-Ucraina-guerra.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/guerra-in-ucraina-tutti-gli-aggiornamenti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BAMBINIXLAPACE\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/bambinixlapace\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"EMERGENZA UCRAINA. Zelensky apre alla pace. Vaticano: \u201cDisponibili come spazio in cui le parti possano avviare un dialogo\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Guerra in Ucraina: tutti gli aggiornamenti","description":"Guerra in Ucraina. freddo non ferma le attivit\u00e0 del progetto #BAMBINIxLAPACE, a cui saranno devolute le donazioni dell'evento di Natale \u201cIl Bello che Fa Bene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-tutti-gli-aggiornamenti\/","og_locale":"it_IT","og_type":"article","og_title":"EMERGENZA UCRAINA. Zelensky apre alla pace. Vaticano: \u201cDisponibili come spazio in cui le parti possano avviare un dialogo\u201d","og_description":"Guerra in Ucraina. freddo non ferma le attivit\u00e0 del progetto #BAMBINIxLAPACE, a cui saranno devolute le donazioni dell'evento di Natale \u201cIl Bello che Fa Bene","og_url":"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-tutti-gli-aggiornamenti\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2022-12-12T10:00:58+00:00","article_modified_time":"2023-10-25T12:50:59+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/bombe-Kiev-Ucraina-guerra.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.aibi.it\/ita\/images\/2022\/11\/guerra-ucraina-aggiornamento-kiev-senza-acqua.jpg","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"136 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-tutti-gli-aggiornamenti\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-tutti-gli-aggiornamenti\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"EMERGENZA UCRAINA. Zelensky apre alla pace. Vaticano: \u201cDisponibili come spazio in cui le parti possano avviare un dialogo\u201d","datePublished":"2022-12-12T10:00:58+00:00","dateModified":"2023-10-25T12:50:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-tutti-gli-aggiornamenti\/"},"wordCount":25320,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-tutti-gli-aggiornamenti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/bombe-Kiev-Ucraina-guerra.jpg","keywords":["BAMBINIxLAPACE","guerra","Kiev","Ucraina"],"articleSection":["BAMBINIXLAPACE"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-tutti-gli-aggiornamenti\/","url":"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-tutti-gli-aggiornamenti\/","name":"Guerra in Ucraina: tutti gli aggiornamenti","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-tutti-gli-aggiornamenti\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-tutti-gli-aggiornamenti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/bombe-Kiev-Ucraina-guerra.jpg","datePublished":"2022-12-12T10:00:58+00:00","dateModified":"2023-10-25T12:50:59+00:00","description":"Guerra in Ucraina. freddo non ferma le attivit\u00e0 del progetto #BAMBINIxLAPACE, a cui saranno devolute le donazioni dell'evento di Natale \u201cIl Bello che Fa Bene","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-tutti-gli-aggiornamenti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-tutti-gli-aggiornamenti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-tutti-gli-aggiornamenti\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/bombe-Kiev-Ucraina-guerra.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/bombe-Kiev-Ucraina-guerra.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-tutti-gli-aggiornamenti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"BAMBINIXLAPACE","item":"https:\/\/www.aibi.it\/ita\/category\/bambinixlapace\/"},{"@type":"ListItem","position":3,"name":"EMERGENZA UCRAINA. Zelensky apre alla pace. Vaticano: \u201cDisponibili come spazio in cui le parti possano avviare un dialogo\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:55:43","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/197352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=197352"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/197352\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/201290"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=197352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=197352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=197352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}