﻿{"id":19745,"date":"2011-02-11T13:12:28","date_gmt":"2011-02-11T12:12:28","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=19745"},"modified":"2011-02-11T14:36:48","modified_gmt":"2011-02-11T13:36:48","slug":"regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni\/","title":{"rendered":"Regione Basilicata: presentata proposta di legge a sostegno delle adozioni"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.aibi.it\/ita\/images\/mani_adozioni_1003.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-19747\" style=\"margin: 5px;\" title=\"mani_adozioni_100\" src=\"https:\/\/www.aibi.it\/ita\/images\/mani_adozioni_1003.jpg\" alt=\"\" width=\"100\" height=\"100\" \/><\/a><\/strong><\/p>\n<p>\u00a0Presentata ieri in Consiglio Regionale della Basilicata<strong> una proposta di legge per l\u2019istituzione del \u201cServizio regionale per garantire il sostegno per le adozioni e gli affidamenti familiari \u2013 Saaf\u201d. <\/strong><\/p>\n<p><em>\u201cLa proposta di legge<\/em> \u2013 spiega il primo firmatario Gianni Rosa (Pdl) \u2013 <em>che vede quali sottoscrittori gli altri consiglieri del Pdl, Nicola Pagliuca, Mariano Pici, Mario Venezia, Romeo Sarra, Franco Mattia, Paolo Castelluccio, <strong>ha lo scopo di promuovere la diffusione di una cultura favorevole agli interventi rivolti ai minori in situazioni di difficolt\u00e0<\/strong>, alla prevenzione dell\u2019abbandono dei minori, agli interventi di solidariet\u00e0 internazionale, alla creazione di forme di collaborazione fra i vari soggetti dell\u2019adozione\u201d.<\/em><\/p>\n<p><em>\u201cLa legge n. 476 del 1998<\/em> \u2013 continua Rosa &#8211; <strong><em>ha affidato alle Regioni compiti importanti in materia di adozione internazionale,<\/em><\/strong><em> <strong>il Legislatore ha assegnato alle Regioni l\u2019organizzazione di una rete di servizi in grado di svolgere i compiti previsti dalla legge nei rispettivi territori<\/strong>, dando anche la possibilit\u00e0, indicando requisiti e competenze, alle Regioni stesse, di istituire un servizio pubblico per l\u2019adozione internazionale. La proposta di legge presentata dal gruppo Pdl ha la finalit\u00e0 di istituire il \u2018Servizio regionale per garantire il sostegno per le adozioni e gli affidamenti familiari \u2013 Saaf\u2019, presso l\u2019Assessorato alla Sicurezza e Solidariet\u00e0 Sociale Servizio &#8211; Interventi Socio-Sanitari ed Assistenziali, con ricorso al personale gi\u00e0 in servizio in possesso di competenze e specifici profili professionali, con delega alla Giunta regionale che provvede all\u2019adozione di apposita regolamentazione per la sua attuazione\u201d.<\/em><\/p>\n<p><strong><em>\u201cAttualmente<\/em><\/strong> \u2013 sottolinea Rosa &#8211; <strong><em>esiste ancora una variegata differenziazione di procedure nelle diverse realt\u00e0 territoriali, pertanto appare necessario eliminare l&#8217;inconveniente dell&#8217;incertezza dovuta alla pluralit\u00e0 delle competenze attribuite che, spesso, rendono problematica l&#8217;individuazione dell&#8217;ente tenuto ad intervenire con conseguenze assai negative per i cittadini.<\/em><\/strong><em> Con questa proposta legislativa colmiamo un vuoto che esiste in Basilicata dopo l\u2019emanazione della legge di riforma nazionale. Infatti, si sollecita la creazione di reti fra i vari soggetti dell&#8217;adozione; in ordine a tale aspetto, come espressamente previsto dalla legge n. 184 del 1983 (art. 39- bis comma 1 lett. c), appare indifferibile la definizione di rapporti tra il Tribunale per i minori, la Regione, gli Enti locali, gli Enti autorizzati e la Commissione per le adozioni internazionali. Si vuole promuovere l\u2019attivit\u00e0 di informazione sulle procedure amministrative, sulle attivit\u00e0 di servizi e sui requisiti necessari per gli affidamenti e le adozioni internazionali, si vogliono favorire la stipula di protocolli operativi e di convenzioni tra associazione, Enti autorizzati, nonch\u00e9 forme stabili di collegamento tra gli stessi e gli organi giudiziari minorili. Una legge \u2013 conclude Rosa &#8211; che favorisce anche lo scambio di esperienze umane e sociali tra le famiglie adottive e che nasce con l\u2019intenzione di aiutare le famiglie che vogliono intraprendere il percorso dell\u2019adozione, oggi molto spesso non agevole e denso di insidie\u201d.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p><em>\u201cLa proposta ha lo scopo di promuovere la diffusione di una cultura favorevole agli interventi rivolti ai minori in situazioni di difficolt\u00e0, alla prevenzione dell\u2019abbandono dei minori, agli interventi di solidariet\u00e0 internazionale, alla creazione di forme di collaborazione fra i vari soggetti dell\u2019adozione\u201d. <\/em><strong><a href=\"https:\/\/www.aibi.it\/ita\/regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni\/\">LEGGI TUTTO&#8230;<\/a><\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-19745","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Regione Basilicata: presentata proposta di legge a sostegno delle adozioni  - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Regione Basilicata: presentata proposta di legge a sostegno delle adozioni\" \/>\n<meta property=\"og:description\" content=\"\u201cLa proposta ha lo scopo di promuovere la diffusione di una cultura favorevole agli interventi rivolti ai minori in situazioni di difficolt\u00e0, alla prevenzione dell\u2019abbandono dei minori, agli interventi di solidariet\u00e0 internazionale, alla creazione di forme di collaborazione fra i vari soggetti dell\u2019adozione\u201d. LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-02-11T12:12:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-02-11T13:36:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/mani_adozioni_1003.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Regione Basilicata: presentata proposta di legge a sostegno delle adozioni\",\"datePublished\":\"2011-02-11T12:12:28+00:00\",\"dateModified\":\"2011-02-11T13:36:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni\\\/\"},\"wordCount\":472,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/mani_adozioni_1003.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni\\\/\",\"name\":\"Regione Basilicata: presentata proposta di legge a sostegno delle adozioni - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/mani_adozioni_1003.jpg\",\"datePublished\":\"2011-02-11T12:12:28+00:00\",\"dateModified\":\"2011-02-11T13:36:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/mani_adozioni_1003.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/mani_adozioni_1003.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Regione Basilicata: presentata proposta di legge a sostegno delle adozioni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Regione Basilicata: presentata proposta di legge a sostegno delle adozioni  - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni\/","og_locale":"it_IT","og_type":"article","og_title":"Regione Basilicata: presentata proposta di legge a sostegno delle adozioni","og_description":"\u201cLa proposta ha lo scopo di promuovere la diffusione di una cultura favorevole agli interventi rivolti ai minori in situazioni di difficolt\u00e0, alla prevenzione dell\u2019abbandono dei minori, agli interventi di solidariet\u00e0 internazionale, alla creazione di forme di collaborazione fra i vari soggetti dell\u2019adozione\u201d. LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2011-02-11T12:12:28+00:00","article_modified_time":"2011-02-11T13:36:48+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/mani_adozioni_1003.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Regione Basilicata: presentata proposta di legge a sostegno delle adozioni","datePublished":"2011-02-11T12:12:28+00:00","dateModified":"2011-02-11T13:36:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni\/"},"wordCount":472,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/mani_adozioni_1003.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni\/","url":"https:\/\/www.aibi.it\/ita\/regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni\/","name":"Regione Basilicata: presentata proposta di legge a sostegno delle adozioni - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/mani_adozioni_1003.jpg","datePublished":"2011-02-11T12:12:28+00:00","dateModified":"2011-02-11T13:36:48+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/mani_adozioni_1003.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/mani_adozioni_1003.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/regione-basilicata-presentata-proposta-di-legge-a-sostegno-delle-adozioni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Regione Basilicata: presentata proposta di legge a sostegno delle adozioni"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 16:50:23","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/19745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=19745"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/19745\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=19745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=19745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=19745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}