﻿


{"id":197450,"date":"2022-02-27T07:35:46","date_gmt":"2022-02-27T06:35:46","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=197450"},"modified":"2022-03-14T10:33:39","modified_gmt":"2022-03-14T09:33:39","slug":"guerra-in-ucraina-progetti-aibi-ucraina-moldova-bambinixlapace","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-progetti-aibi-ucraina-moldova-bambinixlapace\/","title":{"rendered":"Guerra in Ucraina: i progetti di Ai.Bi. in Ucraina e Moldova della campagna #BAMBINIxLAPACE"},"content":{"rendered":"<h2><strong>Sono gi\u00e0 cominciate le attivit\u00e0 di emergenza che Ai.Bi. e i suoi partner locali stanno portando avanti in Ucraina e Moldova per il reperimento di beni di prima necessit\u00e0, il supporto psico-sociale e l\u2019allestimento di 3 spazi protetti \u201ca misura di bambino\u201d<\/strong><\/h2>\n<p>Gioved\u00ec mattina dopo circa 20 anni, L\u2019Europa si \u00e8 risvegliata in guerra.<br \/>\nE in una guerra, le prime vittime sono sempre le bambine, i bambini e, in generale, i pi\u00f9 indifesi.<br \/>\nIn Ucraina, su una popolazione di 47 milioni di persone, sono oltre <strong>100.000 i bambini abbandonati<\/strong> accolti in 663 orfanotrofi del Paese. La guerra ha aggravato una situazione gi\u00e0 tragica, colpendo duramente bambini e adolescenti dell\u2019Ucraina orientale.<br \/>\nOra, con lo scoppio della guerra sul territorio, l\u2019emergenza si \u00e8 fatta ancora pi\u00f9 pressante: secondo le stime dell\u2019ONU <strong>le persone in fuga dall\u2019Ucraina sarebbero gi\u00e0 50.000<\/strong>, dirette verso Romania, Polonia, Repubblica Ceca, Ungheria, Slovenia, Lituania e Moldova. \u00c8 solo l\u2019inizio di un esodo che, secondo l\u2019UNHCR, potrebbe coinvolgere <strong>5 milioni di persone<\/strong>.<br \/>\nDavanti a questa situazione, Ai.Bi, ha subito attivato una raccolta fondi BambinixLaPace, il cui obiettivo \u00e8 raccogliere risorse per intervenire alle Dogane al Confine Moldova- Ucraina; a Chi\u0219in\u0103u, in Moldova; a Volodarka, regione di Kiev, Ucraina.<\/p>\n<h3>Le azioni in Moldova<\/h3>\n<p>In Moldova, dove Ai.Bi. \u00e8 presente da oltre 16 anni, sono stati allestiti <strong>due punti di prima assistenza<\/strong> direttamente alla dogana, dove i profughi possono rimanere per un massimo di 72 ore, ma visto l\u2019afflusso un terzo punto \u00e8 gi\u00e0 in fase di allestimento. Campi profughi pi\u00f9 strutturati, nei quali le persone possono fermarsi di pi\u00f9, sono stati preparati a <strong>Chisinau<\/strong>, la capitale. Uno, in particolare, ha un capacit\u00e0 di 450 posti, ma gi\u00e0 sabato 26 febbraio le autorit\u00e0 moldave hanno segnalato la presenza nel campo di <strong>426 persone<\/strong>, di cui 40 bambini.<br \/>\nNei campi mancano i <strong>beni di prima necessit\u00e0<\/strong>: cibo, coperte, prodotti igienici, per una popolazione che aumenta di ora in ora. Gli spazi, improvvisati, non sono adeguati all\u2019accoglienza dei bambini e delle bambine, che gi\u00e0 hanno affrontano il trauma della fuga, n\u00e9 sono pensati per loro momenti ricreativi di sollievo o un supporto strutturato, per prevenire disturbi da stress post traumatico.<\/p>\n<h3>Gli interventi in Ucraina<\/h3>\n<p>In Ucraina, come racconta la nostra cooperante in loco, scarseggiano ormai tutti i beni di prima necessit\u00e0: i pochi negozi aperti sono vuoti. Molti uomini sono andati a combattere lasciando le donne sole con i propri bambini. Dall\u2019inizio dei bombardamenti, un <strong>esodo di persone verso le campagne<\/strong> ha iniziato a spopolare le citt\u00e0, in particolare la capitale Kiev, da giorni sotto le bombe.<br \/>\nL\u2019istituto di accoglienza per minori <strong>Volodarka<\/strong>, con cui Amici dei Bambini ha attivo un progetto di Adozione a Distanza da tempo, \u00e8 diventato anche <strong>rifugio per bambini e famiglie<\/strong> in fuga dalle citt\u00e0.<br \/>\nAnche qui, la prima emergenza \u00e8 quella dell\u2019approvvigionamento di beni di prima necessit\u00e0. Ma anche qui serve un programma di sostegno integrato che preveda supporto psicologico, sociale, spazi e momenti di gioco e educativi, affinch\u00e9 i bambini non siano costretti a rinunciare alla loro infanzia.<br \/>\nAl momento, il progetto si rivolge a <strong>100 famiglie<\/strong> con bambini, in fuga dalla guerra che stanno trovando rifugio nei campi profughi a Chi\u0219in\u0103u in Moldova, al confine con l\u2019Ucraina; <strong>40 famiglie<\/strong> con bambini accolti nei centri di accoglienza per profughi allestito presso l\u2019Istituto Volodarka, nella regione di Kiev, in Ucraina; <strong>180 minori<\/strong> in condizione di grave vulnerabilit\u00e0 famigliare accolti presso l\u2019istituto Volodarka, Ucraina.<\/p>\n<h3>Il dettaglio delle attivit\u00e0<\/h3>\n<p>Le principali attivit\u00e0 sono<strong> l\u2019assistenza materiale ai <\/strong>minori e le famiglie dei profughi in Moldova e Ucraina, con distribuzione di beni di prima necessit\u00e0 (prodotti igienici, pannolini, biancheria da letto, cuscini, coperte, kit di alimentazione per i pi\u00f9 piccoli, medicine, mascherine e altri presidi igienico sanitari, cibo) L\u2019attivit\u00e0 in Moldova \u00e8 svolta in coordinamento con il <strong>Ministero della Protezione Sociale<\/strong>, che, a conflitto iniziato, ha mobilitato la rete di ONG locali e internazionali a supporto dell\u2019intervento di emergenza.<br \/>\nIn Ucraina, l\u2019attivit\u00e0 \u00e8 coordinata e supervisionata <strong>dall\u2019equipe dell\u2019istituto Volodarka,<\/strong> con cui Ai.Bi. collabora da molti anni. Ulteriori esigenze potrebbero emergere nei prossimi giorni, la presenza delle nostre equipe sul territorio consente di avere informazioni costanti ed aggiornate e di modificare, quindi, gli aiuti in funzione delle esigenze di volta in volta emergenti.<br \/>\nOltre a questo, il progetto prevede anche interventi di <strong>sostegno psico-sociale per minori e famiglie<\/strong>. Pu\u00f2 sembrare un\u2019attivit\u00e0 meno \u201curgente\u201d, ma da anni ormai \u00e8 stata riconosciuta universalmente l\u2019importanza di interventi di supporto psico-sociale dedicati ai bambini nell\u2019ambito di programmi di assistenza umanitaria e di gestione delle emergenze. L\u2019azione prevede <strong>l\u2019attivazione di un equipe<\/strong> per il supporto dei minori vittime del conflitto, nei centri profughi in Moldova e presso il centro Volodarka in Ucraina: \u00e8 prevista un\u2019attivit\u00e0 di formazione in Moldova, in linea con il protocollo UNICEF e con altri standard internazionali, adattati allo specifico contesto ucraino, e l\u2019attivazione dell\u2019equipe stessa presso i 2 centri profughi in Moldova e il centro Volodarka in Ucraina.<br \/>\nInoltre, \u00e8 previsto l\u2019allestimento di <strong>uno spazio protetto<\/strong> e a \u201cmisura di bambino\u201d in ciascun centro profughi, in cui poter svolgere le attivit\u00e0 di animazione e sostegno psico-sociale.<\/p>\n<p>Sostieni anche tu la campagna #BAMBINIxLAPACE<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*197331-start*\/\n#btnsx-197331{margin-top:0px;margin-bottom:25px;margin-left:0px;margin-right:0px;padding-top:16px;padding-bottom:15px;padding-left:43px;padding-right:44px;}\n#btnsx-197331 .btnsx-text-primary{text-transform:uppercase;font-size:20px;line-height:20px;font-weight:800;font-family:Raleway;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-197331:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-197331{background-color:#dd3333!important;}\n#btnsx-197331:hover{background-color:#d13030!important;}\n#btnsx-197331{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px;}\n#btnsx-197331:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:solid;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px;}\n#btnsx-197331{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-197331:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*197331-end*\/\n<\/style>\n<a href=\"https:\/\/dona.aibi.it\/emergenza-ucraina\/?act=cplt&amp;origine=web-button-in-post\" id=\"btnsx-197331\" class=\"btnsx-btn btnsx-btn-block\"  data-font-primary=\"Raleway\">\n\t<span class=\"btnsx-text-primary \">EMERGENZA UCRAINA<\/span><\/a>\n\n<!-- Buttons X - End -->\n\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-197452 aligncenter\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/bambinixlapace-ukraina-1500x500-1-700x233.jpg\" alt=\"\" width=\"700\" height=\"233\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/bambinixlapace-ukraina-1500x500-1-700x233.jpg 700w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/bambinixlapace-ukraina-1500x500-1-1200x400.jpg 1200w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/bambinixlapace-ukraina-1500x500-1-150x50.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/bambinixlapace-ukraina-1500x500-1-768x256.jpg 768w, https:\/\/www.aibi.it\/ita\/images\/2022\/02\/bambinixlapace-ukraina-1500x500-1.jpg 1500w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sono gi&agrave; cominciate le attivit&agrave; di emergenza che Ai.Bi. e i suoi partner locali stanno portando avanti in Ucraina e Moldova per il reperimento di beni di prima necessit&agrave;, il supporto psico-sociale e l&rsquo;allestimento di 3 spazi protetti &ldquo;a misura di bambino&rdquo; Gioved&igrave; mattina dopo circa 20 anni, L&rsquo;Europa si [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":197453,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[909,5],"tags":[895,840,423],"class_list":["post-197450","post","type-post","status-publish","format-standard","has-post-thumbnail","category-bambinixlapace","category-cooperazione-internazionale","tag-bambinixlapace","tag-guerra","tag-ucraina"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Guerra in Ucraina: i progetti di Ai.Bi. in Ucraina e Moldova<\/title>\n<meta name=\"description\" content=\"Guerra in Ucraina: sono cominciate le attivit\u00e0 di emergenza che Ai.Bi. e i partner portano avanti in Ucraina e Moldova nell&#039;ambito della campagna BambinixLaPace\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-progetti-aibi-ucraina-moldova-bambinixlapace\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guerra in Ucraina: i progetti di Ai.Bi. in Ucraina e Moldova della campagna #BAMBINIxLAPACE\" \/>\n<meta property=\"og:description\" content=\"Guerra in Ucraina: sono cominciate le attivit\u00e0 di emergenza che Ai.Bi. e i partner portano avanti in Ucraina e Moldova nell&#039;ambito della campagna BambinixLaPace\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-progetti-aibi-ucraina-moldova-bambinixlapace\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-27T06:35:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-14T09:33:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/progetti_Ucraina.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"629\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/guerra-in-ucraina-progetti-aibi-ucraina-moldova-bambinixlapace\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/guerra-in-ucraina-progetti-aibi-ucraina-moldova-bambinixlapace\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Guerra in Ucraina: i progetti di Ai.Bi. in Ucraina e Moldova della campagna #BAMBINIxLAPACE\",\"datePublished\":\"2022-02-27T06:35:46+00:00\",\"dateModified\":\"2022-03-14T09:33:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/guerra-in-ucraina-progetti-aibi-ucraina-moldova-bambinixlapace\\\/\"},\"wordCount\":875,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/guerra-in-ucraina-progetti-aibi-ucraina-moldova-bambinixlapace\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/02\\\/progetti_Ucraina.jpg\",\"keywords\":[\"BAMBINIxLAPACE\",\"guerra\",\"Ucraina\"],\"articleSection\":[\"BAMBINIXLAPACE\",\"Cooperazione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/guerra-in-ucraina-progetti-aibi-ucraina-moldova-bambinixlapace\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/guerra-in-ucraina-progetti-aibi-ucraina-moldova-bambinixlapace\\\/\",\"name\":\"Guerra in Ucraina: i progetti di Ai.Bi. in Ucraina e Moldova\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/guerra-in-ucraina-progetti-aibi-ucraina-moldova-bambinixlapace\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/guerra-in-ucraina-progetti-aibi-ucraina-moldova-bambinixlapace\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/02\\\/progetti_Ucraina.jpg\",\"datePublished\":\"2022-02-27T06:35:46+00:00\",\"dateModified\":\"2022-03-14T09:33:39+00:00\",\"description\":\"Guerra in Ucraina: sono cominciate le attivit\u00e0 di emergenza che Ai.Bi. e i partner portano avanti in Ucraina e Moldova nell'ambito della campagna BambinixLaPace\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/guerra-in-ucraina-progetti-aibi-ucraina-moldova-bambinixlapace\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/guerra-in-ucraina-progetti-aibi-ucraina-moldova-bambinixlapace\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/guerra-in-ucraina-progetti-aibi-ucraina-moldova-bambinixlapace\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/02\\\/progetti_Ucraina.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/02\\\/progetti_Ucraina.jpg\",\"width\":1200,\"height\":629},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/guerra-in-ucraina-progetti-aibi-ucraina-moldova-bambinixlapace\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cooperazione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/cooperazione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Guerra in Ucraina: i progetti di Ai.Bi. in Ucraina e Moldova della campagna #BAMBINIxLAPACE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Guerra in Ucraina: i progetti di Ai.Bi. in Ucraina e Moldova","description":"Guerra in Ucraina: sono cominciate le attivit\u00e0 di emergenza che Ai.Bi. e i partner portano avanti in Ucraina e Moldova nell'ambito della campagna BambinixLaPace","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-progetti-aibi-ucraina-moldova-bambinixlapace\/","og_locale":"it_IT","og_type":"article","og_title":"Guerra in Ucraina: i progetti di Ai.Bi. in Ucraina e Moldova della campagna #BAMBINIxLAPACE","og_description":"Guerra in Ucraina: sono cominciate le attivit\u00e0 di emergenza che Ai.Bi. e i partner portano avanti in Ucraina e Moldova nell'ambito della campagna BambinixLaPace","og_url":"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-progetti-aibi-ucraina-moldova-bambinixlapace\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2022-02-27T06:35:46+00:00","article_modified_time":"2022-03-14T09:33:39+00:00","og_image":[{"width":1200,"height":629,"url":"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/progetti_Ucraina.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-progetti-aibi-ucraina-moldova-bambinixlapace\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-progetti-aibi-ucraina-moldova-bambinixlapace\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Guerra in Ucraina: i progetti di Ai.Bi. in Ucraina e Moldova della campagna #BAMBINIxLAPACE","datePublished":"2022-02-27T06:35:46+00:00","dateModified":"2022-03-14T09:33:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-progetti-aibi-ucraina-moldova-bambinixlapace\/"},"wordCount":875,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-progetti-aibi-ucraina-moldova-bambinixlapace\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/progetti_Ucraina.jpg","keywords":["BAMBINIxLAPACE","guerra","Ucraina"],"articleSection":["BAMBINIXLAPACE","Cooperazione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-progetti-aibi-ucraina-moldova-bambinixlapace\/","url":"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-progetti-aibi-ucraina-moldova-bambinixlapace\/","name":"Guerra in Ucraina: i progetti di Ai.Bi. in Ucraina e Moldova","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-progetti-aibi-ucraina-moldova-bambinixlapace\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-progetti-aibi-ucraina-moldova-bambinixlapace\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/progetti_Ucraina.jpg","datePublished":"2022-02-27T06:35:46+00:00","dateModified":"2022-03-14T09:33:39+00:00","description":"Guerra in Ucraina: sono cominciate le attivit\u00e0 di emergenza che Ai.Bi. e i partner portano avanti in Ucraina e Moldova nell'ambito della campagna BambinixLaPace","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-progetti-aibi-ucraina-moldova-bambinixlapace\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-progetti-aibi-ucraina-moldova-bambinixlapace\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-progetti-aibi-ucraina-moldova-bambinixlapace\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/progetti_Ucraina.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/02\/progetti_Ucraina.jpg","width":1200,"height":629},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/guerra-in-ucraina-progetti-aibi-ucraina-moldova-bambinixlapace\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Cooperazione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/cooperazione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Guerra in Ucraina: i progetti di Ai.Bi. in Ucraina e Moldova della campagna #BAMBINIxLAPACE"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:58:38","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/197450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=197450"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/197450\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/197453"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=197450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=197450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=197450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}