﻿{"id":19953,"date":"2011-02-18T16:20:03","date_gmt":"2011-02-18T15:20:03","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=19953"},"modified":"2011-02-18T16:20:58","modified_gmt":"2011-02-18T15:20:58","slug":"bulgaria-risultati-della-collaborazione-pubblico-privato","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/bulgaria-risultati-della-collaborazione-pubblico-privato\/","title":{"rendered":"Bulgaria: risultati della collaborazione pubblico privato"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/bulgaria.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-19954\" style=\"margin: 5px;\" title=\"bulgaria\" src=\"https:\/\/www.aibi.it\/ita\/images\/bulgaria.jpg\" alt=\"\" width=\"100\" height=\"100\" \/><\/a>A Pleven i nostri operatori del Centro di Servizi al Bambino e alla Famiglia, hanno partecipato al Consiglio che si e\u2019 riunito <strong>per valutare un caso di adozione di un bambino ospitato presso l\u2019istituto Mladen Antonov di Totleben.<\/strong><\/p>\n<p>Si e\u2019 infatti aperta per lui la possibilita\u2019di un\u2019adozione nazionale. Il lavoro \u00e8 frutto della collaborazione tra pubblico e privato a livello multidisciplinare. Le attivit\u00e0 infatti degli assistenti sociali municipali vanno di pari passo con gli interventi degli assistenti sociali di Amici dei Bambini.<\/p>\n<p><strong>Secondo i servizi sociali le capacita\u2019 di adattamento e psico-sociali del bambino sono buone e si prevede che possa abbracciare la sua nuova famiglia in tempi brevi.<\/strong> Sebbene questa pratica sia ancora poco diffusa in Bulgaria, questo caso sarebbe il secondo presso lo stesso istituto nel 2011. A breve saranno disponibili i dati ufficiali dell\u2019Agenzia per i Servizi Sociali relativi alle adozioni nazionali nel 2010 nel Paese.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pleven i nostri operatori del Centro di Servizi al Bambino e alla Famiglia, hanno partecipato al Consiglio che si e\u2019 riunito <strong>per valutare un caso di adozione di un bambino ospitato presso l\u2019istituto Mladen Antonov di Totleben. <a href=\"https:\/\/www.aibi.it\/ita\/bulgaria-risultati-della-collaborazione-pubblico-privato\/\">LEGGI TUTTO&#8230;<\/a><\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-19953","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bulgaria: risultati della collaborazione pubblico privato - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/bulgaria-risultati-della-collaborazione-pubblico-privato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bulgaria: risultati della collaborazione pubblico privato\" \/>\n<meta property=\"og:description\" content=\"A Pleven i nostri operatori del Centro di Servizi al Bambino e alla Famiglia, hanno partecipato al Consiglio che si e\u2019 riunito per valutare un caso di adozione di un bambino ospitato presso l\u2019istituto Mladen Antonov di Totleben. LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/bulgaria-risultati-della-collaborazione-pubblico-privato\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-02-18T15:20:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-02-18T15:20:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/bulgaria.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bulgaria-risultati-della-collaborazione-pubblico-privato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bulgaria-risultati-della-collaborazione-pubblico-privato\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Bulgaria: risultati della collaborazione pubblico privato\",\"datePublished\":\"2011-02-18T15:20:03+00:00\",\"dateModified\":\"2011-02-18T15:20:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bulgaria-risultati-della-collaborazione-pubblico-privato\\\/\"},\"wordCount\":156,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bulgaria-risultati-della-collaborazione-pubblico-privato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bulgaria.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bulgaria-risultati-della-collaborazione-pubblico-privato\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bulgaria-risultati-della-collaborazione-pubblico-privato\\\/\",\"name\":\"Bulgaria: risultati della collaborazione pubblico privato - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bulgaria-risultati-della-collaborazione-pubblico-privato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bulgaria-risultati-della-collaborazione-pubblico-privato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bulgaria.jpg\",\"datePublished\":\"2011-02-18T15:20:03+00:00\",\"dateModified\":\"2011-02-18T15:20:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bulgaria-risultati-della-collaborazione-pubblico-privato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bulgaria-risultati-della-collaborazione-pubblico-privato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bulgaria-risultati-della-collaborazione-pubblico-privato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bulgaria.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bulgaria.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bulgaria-risultati-della-collaborazione-pubblico-privato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bulgaria: risultati della collaborazione pubblico privato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bulgaria: risultati della collaborazione pubblico privato - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/bulgaria-risultati-della-collaborazione-pubblico-privato\/","og_locale":"it_IT","og_type":"article","og_title":"Bulgaria: risultati della collaborazione pubblico privato","og_description":"A Pleven i nostri operatori del Centro di Servizi al Bambino e alla Famiglia, hanno partecipato al Consiglio che si e\u2019 riunito per valutare un caso di adozione di un bambino ospitato presso l\u2019istituto Mladen Antonov di Totleben. LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/bulgaria-risultati-della-collaborazione-pubblico-privato\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2011-02-18T15:20:03+00:00","article_modified_time":"2011-02-18T15:20:58+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/bulgaria.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/bulgaria-risultati-della-collaborazione-pubblico-privato\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/bulgaria-risultati-della-collaborazione-pubblico-privato\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Bulgaria: risultati della collaborazione pubblico privato","datePublished":"2011-02-18T15:20:03+00:00","dateModified":"2011-02-18T15:20:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bulgaria-risultati-della-collaborazione-pubblico-privato\/"},"wordCount":156,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bulgaria-risultati-della-collaborazione-pubblico-privato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/bulgaria.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/bulgaria-risultati-della-collaborazione-pubblico-privato\/","url":"https:\/\/www.aibi.it\/ita\/bulgaria-risultati-della-collaborazione-pubblico-privato\/","name":"Bulgaria: risultati della collaborazione pubblico privato - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bulgaria-risultati-della-collaborazione-pubblico-privato\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bulgaria-risultati-della-collaborazione-pubblico-privato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/bulgaria.jpg","datePublished":"2011-02-18T15:20:03+00:00","dateModified":"2011-02-18T15:20:58+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/bulgaria-risultati-della-collaborazione-pubblico-privato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/bulgaria-risultati-della-collaborazione-pubblico-privato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/bulgaria-risultati-della-collaborazione-pubblico-privato\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/bulgaria.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/bulgaria.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/bulgaria-risultati-della-collaborazione-pubblico-privato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Bulgaria: risultati della collaborazione pubblico privato"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 16:37:07","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/19953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=19953"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/19953\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=19953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=19953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=19953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}