﻿


{"id":200002,"date":"2022-05-12T07:30:59","date_gmt":"2022-05-12T05:30:59","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=200002"},"modified":"2022-07-22T15:55:29","modified_gmt":"2022-07-22T13:55:29","slug":"bolivia-la-giornata-dei-bambini-noi-la-festeggiamo-ogni-giorno","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/bolivia-la-giornata-dei-bambini-noi-la-festeggiamo-ogni-giorno\/","title":{"rendered":"Bolivia. La Giornata dei bambini? Noi la festeggiamo ogni giorno!"},"content":{"rendered":"<h2 style=\"font-weight: 400;\"><strong>Tra pagliacci, giochi e risate senza sosta, i piccoli non hanno smesso di mangiare dolci e di giocare! Un successo reso possibile anche grazie\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/\">all\u2019Adozione a Distanza!<\/a><\/strong><\/h2>\n<p style=\"font-weight: 400;\">Il 12\u00a0aprile\u00a0si \u00e8 celebrata in\u00a0<strong>Bolivia<\/strong>\u00a0la\u00a0<strong>Giornata dei bambini<\/strong>. Un momento di festa dedicato ai pi\u00f9 piccoli che non poteva non coinvolgere anche i \u00a0bimbi ospiti degli orfanotrofi\u00a0<strong>Ni\u00f1o Jes\u00fas, Jos\u00e9 Storia e<\/strong><strong>\u00a0Gota de Leche,<\/strong>\u00a0partner di Ai.Bi. nel Paese sudamericano.<\/p>\n<p style=\"font-weight: 400;\">Andiamo a scoprire insieme come hanno vissuto questa gioiosa giornata a loro dedicata!<\/p>\n<h3 style=\"font-weight: 400;\"><strong>Bolivia. La giornata dei bambini all\u2019orfanotrofio Ni\u00f1o Jes\u00fas<\/strong><\/h3>\n<p style=\"font-weight: 400;\">In attesa di celebrare la giornata a loro dedicata, i piccoli ospiti dell\u2019orfanotrofio\u00a0<strong>Ni\u00f1o Jes\u00fas<\/strong>\u00a0non stavano pi\u00f9 nella pelle. Tutto era una sorpresa. Tra i piccolini, girava voce che ci sarebbero state molte torte e cupcakes\u2026 e non sono rimasti delusi!\u00a0Tante istituzioni boliviane sono arrivate in orfanotrofio con donazioni e tanti regali per i bambini.\u00a0<strong>Tra pagliacci, giochi e risate senza sosta,\u00a0<\/strong>i piccoli non hanno smesso di mangiare dolci e di giocare!<\/p>\n<h3 style=\"font-weight: 400;\">\u00a0<strong>Bolivia. Una grande festa per i bambini dell\u2019orfanotrofio\u00a0<\/strong><strong>Jos\u00e9 Soria<\/strong><\/h3>\n<p style=\"font-weight: 400;\">\u00a0Anche all\u2019interno dell\u2019orfanotrofio Jos\u00e9 Soria, la Giornata dei bambini non \u00e8 di certo passata inosservata e per tutti i piccoli ospiti della struttura, gli educatori hanno organizzato una\u00a0<strong>grande festa!\u00a0<\/strong>Prima \u00e8 stata celebrata la messa e dopo, \u00e8 stato organizzato uno spettacolo con clown, con balli, canti, dolci e molti regalini per i bambini.\u00a0\u00c9 stata una festa bella e speciale\u00a0<strong>dopo due anni di pandemia<\/strong>.<\/p>\n<h3 style=\"font-weight: 400;\"><strong>Bolivia. La giornata del bambino all\u2019orfanotrofio Gota del Leche<\/strong><\/h3>\n<p style=\"font-weight: 400;\">Pagliacci e\u00a0<strong>cestini di caramelle personalizzati<\/strong>\u00a0hanno colorato di gioia questa giornata speciale anche per i bimbi dell\u2019orfanotrofio Gota de Leche. Una festa che si \u00e8 prolungata anche il giorno successivo, quando i bimbi dell\u2019orfanotrofio hanno fatto una bella gita\u00a0<strong>al parco dei draghi<\/strong>, nella quale si sono divertiti davvero molto!<\/p>\n<h3 style=\"font-weight: 400;\"><strong>Aderisci anche tu al progetto di Ai.Bi.: \u201c<a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/\">Adotta un orfanotrofio in Bolivia\u201d<\/a><\/strong><\/h3>\n<p style=\"font-weight: 400;\">La giornata boliviana dei bambini, \u00e8 stato un momento molto speciale per i piccoli ospiti degli orfanotrofi sostenuti da Ai.Bi. nel Paese. I nostri piccolini hanno trascorso momenti di\u00a0<strong>gioia e spensieratezza<\/strong>\u00a0sentendosi accolti ed amati, dopo due anni di chiusure a causa della pandemia da coronavirus.<\/p>\n<p style=\"font-weight: 400;\"><strong>Clown, regalini e dolcetti\u2026<\/strong>\u00a0momenti di felicit\u00e0 resi possibili anche grazie al sostegno del progetto di\u00a0<strong>Adozione a Distanza di Ai.Bi.<\/strong><\/p>\n<p style=\"font-weight: 400;\">Aiutaci anche tu a far s\u00ec che\u00a0la Giornata dei bambini non sia solo il 12 aprile, ma sia celebrata ogni giorno dell\u2019anno! Aderisci al progetto di Adozione a Distanza di Ai.Bi. in Bolivia.\u00a0<strong>Con 25 euro al mese puoi farlo!<\/strong><\/p>\n<p style=\"font-weight: 400;\">Tutte le donazioni\u00a0ad Ai.Bi., compresa l\u2019Adozione a Distanza,\u00a0godono delle seguenti\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/images\/AGEVOLAZIONI_FISCALI.pdf\"><strong>agevolazioni fiscali<\/strong><\/a><\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn btnsx-btn-embossed\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Scopri di pi\u00f9<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\">\n","protected":false},"excerpt":{"rendered":"<p>Tra pagliacci, giochi e risate senza sosta, i piccoli non hanno smesso di mangiare dolci e di giocare! Un successo reso possibile anche grazie&nbsp;all&rsquo;Adozione a Distanza! Il 12&nbsp;aprile&nbsp;si &egrave; celebrata in&nbsp;Bolivia&nbsp;la&nbsp;Giornata dei bambini. Un momento di festa dedicato ai pi&ugrave; piccoli che non poteva non coinvolgere anche i &nbsp;bimbi ospiti [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":200003,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209],"tags":[882,647,646],"class_list":["post-200002","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-a-distanza","tag-gota-de-leche","tag-jose-soria","tag-nino-jesus"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bolivia. La Giornata dei bambini? Noi la festeggiamo ogni giorno! - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Bolivia. Tra pagliacci, giochi e risate senza sosta, i piccoli non hanno smesso di mangiare dolci e di giocare! Un successo reso possibile anche grazie\u00a0all\u2019Adozione a Distanza!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/bolivia-la-giornata-dei-bambini-noi-la-festeggiamo-ogni-giorno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bolivia. La Giornata dei bambini? Noi la festeggiamo ogni giorno!\" \/>\n<meta property=\"og:description\" content=\"Bolivia. Tra pagliacci, giochi e risate senza sosta, i piccoli non hanno smesso di mangiare dolci e di giocare! Un successo reso possibile anche grazie\u00a0all\u2019Adozione a Distanza!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/bolivia-la-giornata-dei-bambini-noi-la-festeggiamo-ogni-giorno\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-12T05:30:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-22T13:55:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2022\/05\/Bolivia.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"809\" \/>\n\t<meta property=\"og:image:height\" content=\"429\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-la-giornata-dei-bambini-noi-la-festeggiamo-ogni-giorno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-la-giornata-dei-bambini-noi-la-festeggiamo-ogni-giorno\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"Bolivia. La Giornata dei bambini? Noi la festeggiamo ogni giorno!\",\"datePublished\":\"2022-05-12T05:30:59+00:00\",\"dateModified\":\"2022-07-22T13:55:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-la-giornata-dei-bambini-noi-la-festeggiamo-ogni-giorno\\\/\"},\"wordCount\":480,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-la-giornata-dei-bambini-noi-la-festeggiamo-ogni-giorno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/05\\\/Bolivia.jpeg\",\"keywords\":[\"Gota de Leche\",\"Jos\u00e8 Soria\",\"Nino Jesus\"],\"articleSection\":[\"Adozione a Distanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-la-giornata-dei-bambini-noi-la-festeggiamo-ogni-giorno\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-la-giornata-dei-bambini-noi-la-festeggiamo-ogni-giorno\\\/\",\"name\":\"Bolivia. La Giornata dei bambini? Noi la festeggiamo ogni giorno! - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-la-giornata-dei-bambini-noi-la-festeggiamo-ogni-giorno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-la-giornata-dei-bambini-noi-la-festeggiamo-ogni-giorno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/05\\\/Bolivia.jpeg\",\"datePublished\":\"2022-05-12T05:30:59+00:00\",\"dateModified\":\"2022-07-22T13:55:29+00:00\",\"description\":\"Bolivia. Tra pagliacci, giochi e risate senza sosta, i piccoli non hanno smesso di mangiare dolci e di giocare! Un successo reso possibile anche grazie\u00a0all\u2019Adozione a Distanza!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-la-giornata-dei-bambini-noi-la-festeggiamo-ogni-giorno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-la-giornata-dei-bambini-noi-la-festeggiamo-ogni-giorno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-la-giornata-dei-bambini-noi-la-festeggiamo-ogni-giorno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/05\\\/Bolivia.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/05\\\/Bolivia.jpeg\",\"width\":809,\"height\":429},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bolivia-la-giornata-dei-bambini-noi-la-festeggiamo-ogni-giorno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione a Distanza\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-a-distanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bolivia. La Giornata dei bambini? Noi la festeggiamo ogni giorno!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bolivia. La Giornata dei bambini? Noi la festeggiamo ogni giorno! - Ai.Bi. Amici dei Bambini","description":"Bolivia. Tra pagliacci, giochi e risate senza sosta, i piccoli non hanno smesso di mangiare dolci e di giocare! Un successo reso possibile anche grazie\u00a0all\u2019Adozione a Distanza!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/bolivia-la-giornata-dei-bambini-noi-la-festeggiamo-ogni-giorno\/","og_locale":"it_IT","og_type":"article","og_title":"Bolivia. La Giornata dei bambini? Noi la festeggiamo ogni giorno!","og_description":"Bolivia. Tra pagliacci, giochi e risate senza sosta, i piccoli non hanno smesso di mangiare dolci e di giocare! Un successo reso possibile anche grazie\u00a0all\u2019Adozione a Distanza!","og_url":"https:\/\/www.aibi.it\/ita\/bolivia-la-giornata-dei-bambini-noi-la-festeggiamo-ogni-giorno\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2022-05-12T05:30:59+00:00","article_modified_time":"2022-07-22T13:55:29+00:00","og_image":[{"width":809,"height":429,"url":"https:\/\/www.aibi.it\/ita\/images\/2022\/05\/Bolivia.jpeg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/bolivia-la-giornata-dei-bambini-noi-la-festeggiamo-ogni-giorno\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-la-giornata-dei-bambini-noi-la-festeggiamo-ogni-giorno\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"Bolivia. La Giornata dei bambini? Noi la festeggiamo ogni giorno!","datePublished":"2022-05-12T05:30:59+00:00","dateModified":"2022-07-22T13:55:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-la-giornata-dei-bambini-noi-la-festeggiamo-ogni-giorno\/"},"wordCount":480,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-la-giornata-dei-bambini-noi-la-festeggiamo-ogni-giorno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/05\/Bolivia.jpeg","keywords":["Gota de Leche","Jos\u00e8 Soria","Nino Jesus"],"articleSection":["Adozione a Distanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/bolivia-la-giornata-dei-bambini-noi-la-festeggiamo-ogni-giorno\/","url":"https:\/\/www.aibi.it\/ita\/bolivia-la-giornata-dei-bambini-noi-la-festeggiamo-ogni-giorno\/","name":"Bolivia. La Giornata dei bambini? Noi la festeggiamo ogni giorno! - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-la-giornata-dei-bambini-noi-la-festeggiamo-ogni-giorno\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-la-giornata-dei-bambini-noi-la-festeggiamo-ogni-giorno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/05\/Bolivia.jpeg","datePublished":"2022-05-12T05:30:59+00:00","dateModified":"2022-07-22T13:55:29+00:00","description":"Bolivia. Tra pagliacci, giochi e risate senza sosta, i piccoli non hanno smesso di mangiare dolci e di giocare! Un successo reso possibile anche grazie\u00a0all\u2019Adozione a Distanza!","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/bolivia-la-giornata-dei-bambini-noi-la-festeggiamo-ogni-giorno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/bolivia-la-giornata-dei-bambini-noi-la-festeggiamo-ogni-giorno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/bolivia-la-giornata-dei-bambini-noi-la-festeggiamo-ogni-giorno\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2022\/05\/Bolivia.jpeg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/05\/Bolivia.jpeg","width":809,"height":429},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/bolivia-la-giornata-dei-bambini-noi-la-festeggiamo-ogni-giorno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione a Distanza","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-a-distanza\/"},{"@type":"ListItem","position":3,"name":"Bolivia. La Giornata dei bambini? Noi la festeggiamo ogni giorno!"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:55:57","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/200002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=200002"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/200002\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/200003"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=200002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=200002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=200002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}