﻿


{"id":200024,"date":"2022-05-13T07:50:04","date_gmt":"2022-05-13T05:50:04","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=200024"},"modified":"2022-05-13T11:16:01","modified_gmt":"2022-05-13T09:16:01","slug":"moldova-aibi-linea-telefonica-supporto-psicologico-famiglie-donne","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/moldova-aibi-linea-telefonica-supporto-psicologico-famiglie-donne\/","title":{"rendered":"BAMBINIxLAPACE. In Moldova Ai.Bi. apre una linea telefonica di supporto psicologico per famiglie in fuga dalla guerra in Ucraina e per donne vittime di violenza"},"content":{"rendered":"<h2>Nell\u2019ambito del progetto per l\u2019emergenza ucraina, #BAMBINIxLAPACE, Ai.Bi. \u2013 Amici dei Bambini, con il supporto di Oxfam, attiva un nuovo servizio di supporto psicologico e ascolto per le donne e i bambini scappati dall\u2019Ucraina e per le donne vittime di violenza<\/h2>\n<p>Quando scoppia un conflitto, in qualsiasi parte del mondo, i primi interventi di emergenza sono sempre rivolti, giustamente, a soddisfare le necessit\u00e0 pratiche pi\u00f9 immediate e \u201cbasiche\u201d. Con il passare dei giorni, per\u00f2, emerge ben presto che le esigenze di chi scappa o di chi \u00e8 coinvolto in una guerra sono ben di pi\u00f9 e ben pi\u00f9 profonde. Soprattutto, oltre al livello materiale che riguarda i beni di prima necessit\u00e0, l\u2019accoglienza e la protezione in luoghi sicuri\u2026 diventa via via sempre pi\u00f9 importante occuparsi anche del lato <strong>psicologico e mentale<\/strong>, pi\u00f9 \u201csilenzioso\u201d e invisibile, ma anche quello su cui gli effetti di una guerra possono essere pi\u00f9 lunghi e difficili da guarire.<\/p>\n<h3>Sostegno psicologico alle donne e i bambini in fuga dalla guerra<\/h3>\n<p>Ecco perch\u00e9, all\u2019interno degli interventi che sta portando avanti in Ucraina e in Moldova nell\u2019ambito della <a href=\"https:\/\/www.aibi.it\/ita\/bambinixlapace\/\">campagna #BAMBINIxLAPACE<\/a>, oltre le necessit\u00e0 basiche dei profughi ucraini Ai.Bi. ha cercato immediatamente di guardare anche al loro benessere psicologico e mentale.<\/p>\n<p>Durante le diverse azioni di accoglienza portate avanti in queste settimane, in particolare in Moldova, lo staff di Ai.Bi. ha incontrato tantissime donne spaventate; angosciate tanto per il futuro dei figli che sono riuscite a portare in salvo, quanto per quelli che magari hanno dovuto lasciare a casa insieme ai mariti.<br \/>\nOgnuna di queste donne ha sulle spalle un carico diverso e bisogno di un diverso supporto: a volte basta qualcuno che le ascolti e che conceda loro di \u201cliberarsi\u201d raccontando quanto vissuto; altre hanno bisogno di un sostegno pi\u00f9 strutturato perch\u00e9 non vedono i loro mariti e familiari da pi\u00f9 di due mesi; altre ancora i mariti li hanno gi\u00e0 persi e hanno bisogno di aiuto e motivazioni per tornare a essere una risorsa per i loro figli.<br \/>\nPer tutte loro, Ai.Bi. ha attivato una <strong>linea telefonica dedicata<\/strong>, attiva <strong>9 ore al giorno<\/strong> e gestita da un&#8217;equipe di <strong>4 psicologi<\/strong> che, dopo una formazione specifica, saranno pronti a dare aiuto, sostegno, ascolto e orientamento alle donne e i minori che si trovano in Moldova.<\/p>\n<h3><strong>Una rete di sostegno anche per le donne vittime di violenza<\/strong><\/h3>\n<p>Ma l\u2019obiettivo dell\u2019intervento, che si avvale del sostegno finanziario del Regno Unito e del popolo britannico, si spinge pi\u00f9 in l\u00e0: per i casi che richiederanno un aiuto pi\u00f9 strutturato e costante, si far\u00e0 riferimento ad altri specialisti presenti sul territorio, che potranno seguire pi\u00f9 da vicino e in maniera pi\u00f9 continuativa queste persone. Inoltre, l\u2019intento del progetto \u00e8 anche quello di <strong>raggiungere donne e ragazze vittima di violenza e abusi<\/strong> offrendo loro tutto il supporto di cui possono avere bisogno.<br \/>\nL\u2019intervento, per il momento, ha una durata di <strong>11 mesi<\/strong> e, come detto, si inserisce nel pi\u00f9 ampio contesto del progetto #BAMBINIxLAPACE promosso da Ai.Bi. \u2013 Amici dei Bambini, che prevede interventi in Ucraina, in Moldova e in Italia.<br \/>\nDall\u2019inizio della guerra , Ai.Bi. \u00e8 impegnata in molteplici attivit\u00e0 lanciate all\u2019interno del progetto\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/bambinixlapace\/\">#BAMBINIxLAPACE<\/a>\u00a0, attivo in Ucraina, Moldova e Italia a favore dei bambini ucraini e delle loro famiglie. Chiunque pu\u00f2 sostenere questa campagna con una donazione. E se sei cliente Fineco, la banca\u00a0<a href=\"https:\/\/finecobank.com\/it\/online\/charity\/emergenza-ucraina\/\">raddoppia la tua donazione<\/a>\u00a0fino al 30 giugno.<br \/>\nTutte le donazioni ad Ai.Bi. godono delle seguenti\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/images\/AGEVOLAZIONI_FISCALI.pdf\">agevolazioni fiscali.<\/a><\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*197331-start*\/\n#btnsx-197331{margin-top:0px;margin-bottom:25px;margin-left:0px;margin-right:0px;padding-top:16px;padding-bottom:15px;padding-left:43px;padding-right:44px;}\n#btnsx-197331 .btnsx-text-primary{text-transform:uppercase;font-size:20px;line-height:20px;font-weight:800;font-family:Raleway;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-197331:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-197331{background-color:#dd3333!important;}\n#btnsx-197331:hover{background-color:#d13030!important;}\n#btnsx-197331{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px;}\n#btnsx-197331:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:solid;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px;}\n#btnsx-197331{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-197331:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*197331-end*\/\n<\/style>\n<a href=\"https:\/\/dona.aibi.it\/emergenza-ucraina\/?act=cplt&amp;origine=web-button-in-post\" id=\"btnsx-197331\" class=\"btnsx-btn btnsx-btn-block\"  data-font-primary=\"Raleway\">\n\t<span class=\"btnsx-text-primary \">EMERGENZA UCRAINA<\/span><\/a>\n\n<!-- Buttons X - End -->\n\n","protected":false},"excerpt":{"rendered":"<p>Nell&rsquo;ambito del progetto per l&rsquo;emergenza ucraina, #BAMBINIxLAPACE, Ai.Bi. &ndash; Amici dei Bambini, con il supporto di Oxfam, attiva un nuovo servizio di supporto psicologico e ascolto per le donne e i bambini scappati dall&rsquo;Ucraina e per le donne vittime di violenza Quando scoppia un conflitto, in qualsiasi parte del mondo, [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":200027,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[909],"tags":[895,530],"class_list":["post-200024","post","type-post","status-publish","format-standard","has-post-thumbnail","category-bambinixlapace","tag-bambinixlapace","tag-moldova"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>In Moldova Ai.Bi. apre una linea telefonica di supporto psicologico<\/title>\n<meta name=\"description\" content=\"Nell\u2019ambito del progetto #BAMBINIxLAPACE, Ai.Bi. attiva un servizio di supporto psicologico per le donne e i bambini scappati dalla guerra in Ucraina\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/moldova-aibi-linea-telefonica-supporto-psicologico-famiglie-donne\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BAMBINIxLAPACE. In Moldova Ai.Bi. apre una linea telefonica di supporto psicologico per famiglie in fuga dalla guerra in Ucraina e per donne vittime di violenza\" \/>\n<meta property=\"og:description\" content=\"Nell\u2019ambito del progetto #BAMBINIxLAPACE, Ai.Bi. attiva un servizio di supporto psicologico per le donne e i bambini scappati dalla guerra in Ucraina\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/moldova-aibi-linea-telefonica-supporto-psicologico-famiglie-donne\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-13T05:50:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-13T09:16:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2022\/05\/linea-telefonica-supporto-psicologico-guerra-Ucraina.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-aibi-linea-telefonica-supporto-psicologico-famiglie-donne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-aibi-linea-telefonica-supporto-psicologico-famiglie-donne\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"BAMBINIxLAPACE. In Moldova Ai.Bi. apre una linea telefonica di supporto psicologico per famiglie in fuga dalla guerra in Ucraina e per donne vittime di violenza\",\"datePublished\":\"2022-05-13T05:50:04+00:00\",\"dateModified\":\"2022-05-13T09:16:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-aibi-linea-telefonica-supporto-psicologico-famiglie-donne\\\/\"},\"wordCount\":609,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-aibi-linea-telefonica-supporto-psicologico-famiglie-donne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/05\\\/linea-telefonica-supporto-psicologico-guerra-Ucraina.jpg\",\"keywords\":[\"BAMBINIxLAPACE\",\"Moldova\"],\"articleSection\":[\"BAMBINIXLAPACE\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-aibi-linea-telefonica-supporto-psicologico-famiglie-donne\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-aibi-linea-telefonica-supporto-psicologico-famiglie-donne\\\/\",\"name\":\"In Moldova Ai.Bi. apre una linea telefonica di supporto psicologico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-aibi-linea-telefonica-supporto-psicologico-famiglie-donne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-aibi-linea-telefonica-supporto-psicologico-famiglie-donne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/05\\\/linea-telefonica-supporto-psicologico-guerra-Ucraina.jpg\",\"datePublished\":\"2022-05-13T05:50:04+00:00\",\"dateModified\":\"2022-05-13T09:16:01+00:00\",\"description\":\"Nell\u2019ambito del progetto #BAMBINIxLAPACE, Ai.Bi. attiva un servizio di supporto psicologico per le donne e i bambini scappati dalla guerra in Ucraina\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-aibi-linea-telefonica-supporto-psicologico-famiglie-donne\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-aibi-linea-telefonica-supporto-psicologico-famiglie-donne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-aibi-linea-telefonica-supporto-psicologico-famiglie-donne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/05\\\/linea-telefonica-supporto-psicologico-guerra-Ucraina.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/05\\\/linea-telefonica-supporto-psicologico-guerra-Ucraina.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-aibi-linea-telefonica-supporto-psicologico-famiglie-donne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BAMBINIXLAPACE\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/bambinixlapace\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BAMBINIxLAPACE. In Moldova Ai.Bi. apre una linea telefonica di supporto psicologico per famiglie in fuga dalla guerra in Ucraina e per donne vittime di violenza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"In Moldova Ai.Bi. apre una linea telefonica di supporto psicologico","description":"Nell\u2019ambito del progetto #BAMBINIxLAPACE, Ai.Bi. attiva un servizio di supporto psicologico per le donne e i bambini scappati dalla guerra in Ucraina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/moldova-aibi-linea-telefonica-supporto-psicologico-famiglie-donne\/","og_locale":"it_IT","og_type":"article","og_title":"BAMBINIxLAPACE. In Moldova Ai.Bi. apre una linea telefonica di supporto psicologico per famiglie in fuga dalla guerra in Ucraina e per donne vittime di violenza","og_description":"Nell\u2019ambito del progetto #BAMBINIxLAPACE, Ai.Bi. attiva un servizio di supporto psicologico per le donne e i bambini scappati dalla guerra in Ucraina","og_url":"https:\/\/www.aibi.it\/ita\/moldova-aibi-linea-telefonica-supporto-psicologico-famiglie-donne\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2022-05-13T05:50:04+00:00","article_modified_time":"2022-05-13T09:16:01+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2022\/05\/linea-telefonica-supporto-psicologico-guerra-Ucraina.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/moldova-aibi-linea-telefonica-supporto-psicologico-famiglie-donne\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/moldova-aibi-linea-telefonica-supporto-psicologico-famiglie-donne\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"BAMBINIxLAPACE. In Moldova Ai.Bi. apre una linea telefonica di supporto psicologico per famiglie in fuga dalla guerra in Ucraina e per donne vittime di violenza","datePublished":"2022-05-13T05:50:04+00:00","dateModified":"2022-05-13T09:16:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/moldova-aibi-linea-telefonica-supporto-psicologico-famiglie-donne\/"},"wordCount":609,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/moldova-aibi-linea-telefonica-supporto-psicologico-famiglie-donne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/05\/linea-telefonica-supporto-psicologico-guerra-Ucraina.jpg","keywords":["BAMBINIxLAPACE","Moldova"],"articleSection":["BAMBINIXLAPACE"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/moldova-aibi-linea-telefonica-supporto-psicologico-famiglie-donne\/","url":"https:\/\/www.aibi.it\/ita\/moldova-aibi-linea-telefonica-supporto-psicologico-famiglie-donne\/","name":"In Moldova Ai.Bi. apre una linea telefonica di supporto psicologico","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/moldova-aibi-linea-telefonica-supporto-psicologico-famiglie-donne\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/moldova-aibi-linea-telefonica-supporto-psicologico-famiglie-donne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/05\/linea-telefonica-supporto-psicologico-guerra-Ucraina.jpg","datePublished":"2022-05-13T05:50:04+00:00","dateModified":"2022-05-13T09:16:01+00:00","description":"Nell\u2019ambito del progetto #BAMBINIxLAPACE, Ai.Bi. attiva un servizio di supporto psicologico per le donne e i bambini scappati dalla guerra in Ucraina","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/moldova-aibi-linea-telefonica-supporto-psicologico-famiglie-donne\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/moldova-aibi-linea-telefonica-supporto-psicologico-famiglie-donne\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/moldova-aibi-linea-telefonica-supporto-psicologico-famiglie-donne\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2022\/05\/linea-telefonica-supporto-psicologico-guerra-Ucraina.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/05\/linea-telefonica-supporto-psicologico-guerra-Ucraina.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/moldova-aibi-linea-telefonica-supporto-psicologico-famiglie-donne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"BAMBINIXLAPACE","item":"https:\/\/www.aibi.it\/ita\/category\/bambinixlapace\/"},{"@type":"ListItem","position":3,"name":"BAMBINIxLAPACE. In Moldova Ai.Bi. apre una linea telefonica di supporto psicologico per famiglie in fuga dalla guerra in Ucraina e per donne vittime di violenza"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:33:57","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/200024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=200024"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/200024\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/200027"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=200024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=200024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=200024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}