﻿


{"id":200256,"date":"2022-05-20T07:30:34","date_gmt":"2022-05-20T05:30:34","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=200256"},"modified":"2022-05-20T14:57:43","modified_gmt":"2022-05-20T12:57:43","slug":"bambinixlapace-moldova-storie-di-vita-nel-centro-profughi-di-edinet-la-bimba-che-non-voleva-festeggiare-il-suo-compleanno","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-storie-di-vita-nel-centro-profughi-di-edinet-la-bimba-che-non-voleva-festeggiare-il-suo-compleanno\/","title":{"rendered":"BAMBINIXLAPACE. Moldova. Storie di vita nel Centro Profughi di Edinet: la bimba che non voleva festeggiare il suo compleanno"},"content":{"rendered":"<h2 style=\"font-weight: 400;\"><strong>Un sorriso, un gesto di accoglienza e alcune candeline su cui soffiare, hanno regalato un sorriso e un momento di serenit\u00e0 ad una bimba ucraina che non voleva festeggiare il giorno del suo compleanno\u2026<\/strong><\/h2>\n<p style=\"font-weight: 400;\">A\u00a0Edinet, nella piccola ma accogliente\u00a0<strong>Moldova<\/strong>, sorge un\u00a0<strong>centro\u00a0di\u00a0accoglienza<\/strong>\u00a0per\u00a0profughi\u00a0ucraini gestito dall\u2019Ong DEMOS con il sostegno\u00a0di\u00a0Ai.Bi. e di altri enti, il cui supporto \u00e8 indirizzato all\u2019aiuto delle famiglie ucraine che hanno lasciato il proprio Paese sconvolto dalla guerra.\u00a0Il\u00a0centro\u00a0ha una capacit\u00e0\u00a0di\u00a0circa\u00a0<strong>20 posti letto<\/strong>, ma i servizi\u00a0di\u00a0sostegno realizzati, sono estesi nella comunit\u00e0, dove il numero dei\u00a0profughi\u00a0\u00e8 molto alto.<\/p>\n<p style=\"font-weight: 400;\"><strong>Viorica Orac<\/strong>, una delle persone-chiave del centro, ogni giorno a contatto diretto con gli adulti e i bambini ucraini che giungono nella struttura, ha raccontato all\u2019equipe di Ai.Bi. Moldova la storia di una bambina che ha trovato rifugio, assieme alla sua famiglia, per un periodo nel centro. Racconto denso di significato che oggi, vogliamo condividere con voi\u2026<\/p>\n<h3 style=\"font-weight: 400;\"><strong>Moldova. Un sorriso e una candelina. Piccoli gesti di accoglienza per ricominciare<\/strong><\/h3>\n<p style=\"font-weight: 400;\">\u201dQui \u2013 racconta Viorica Orac- arrivano persone dalle citt\u00e0 ucraine pi\u00f9 colpite dal conflitto: <strong>Mariupol, Donbass, Odessa.<\/strong><\/p>\n<p style=\"font-weight: 400;\">Tra le prime arrivate c\u2019\u00e8 stata una\u00a0<strong>famiglia con 2 figli<\/strong>.\u00a0 Era l\u20191 di notte quando sono giunti nella struttura e completando le schede per l\u2019accoglienza, ci siamo resi conto che uno dei due minori, una bimba, proprio quel giorno, compiva 11 anni.<\/p>\n<p style=\"font-weight: 400;\">Le abbiamo fatto gli auguri ed\u00a0<strong>abbiamo improvvisato un piccolo momento\u00a0di\u00a0festa<\/strong>, con della torta che avevamo\u00a0nel\u00a0frigo e delle candeline che per una strana coincidenza avevamo al\u00a0centro.<\/p>\n<p style=\"font-weight: 400;\">Con quel gesto volevamo che la bimba ricordasse quel giorno <strong>come un nuovo inizio<\/strong>\u00a0non solo per gli anni che compiva, ma anche della\u00a0sua vita\u00a0che\u00a0<strong>stava per aprirsi ad un nuovo orizzonte<\/strong>. Poi, tutta la famiglia \u00e8 andata a dormire.<\/p>\n<p style=\"font-weight: 400;\">Il mattino seguente ci si \u00e8 avvicinata la madre ringraziandoci per aver\u00a0<strong>ridato speranza a sua figlia<\/strong>\u00a0che: \u201c<em>non voleva festeggiare i suoi 11 anni&#8230; stava ancora sentendo nelle orecchie il suono delle sirene e aveva paura di tutto. Dopo 24 ore che non dormiva, questa \u00e8 stata la prima notte che ha riposato tranquilla\u201d.\u00a0\u00a0<\/em><\/p>\n<p style=\"font-weight: 400;\">Ora la famiglia non si trova pi\u00f9 al\u00a0centro. Ha continuato il proprio viaggio verso la libert\u00e0 in un altro Paese europeo, ma siamo sicuri che con il supporto psicologico che abbiamo offerto loro e con i beni\u00a0di\u00a0prima necessit\u00e0 che hanno ricevuto, siamo riusciti a scaldare un po\u2019 i loro cuori e a renderli un po\u2019 pi\u00f9 forti per ricominciare la loro vita da capo\u201d.<\/p>\n<h3><strong>Sostieni l\u2019impegno di Ai.Bi. per i bambini dell\u2019Ucraina<\/strong><\/h3>\n<p style=\"font-weight: 400;\">Dall\u2019inizio della guerra, Ai.Bi. \u00e8 impegnata in molteplici attivit\u00e0 lanciate all\u2019interno del progetto\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/bambinixlapace\/\"><strong>#BAMBINIxLAPACE<\/strong><\/a>, attivo in Ucraina, Moldova e Italia a favore dei bambini ucraini e delle loro famiglie. Chiunque pu\u00f2 sostenerli\u00a0con una donazione\u00a0una tantum o con l\u2019Adozione a Distanza.\u00a0E se sei cliente Fineco, la banca\u00a0<a href=\"https:\/\/finecobank.com\/it\/online\/charity\/emergenza-ucraina\/\"><strong>raddoppia la tua donazione<\/strong><\/a>\u00a0fino al\u00a030 giugno.\u00a0Ricordati che tutte le donazioni ad Ai.Bi. godono delle seguenti\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/images\/AGEVOLAZIONI_FISCALI.pdf\"><strong>agevolazioni fiscali<\/strong><\/a><\/p>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong>\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*197331-start*\/\n#btnsx-197331{margin-top:0px;margin-bottom:25px;margin-left:0px;margin-right:0px;padding-top:16px;padding-bottom:15px;padding-left:43px;padding-right:44px;}\n#btnsx-197331 .btnsx-text-primary{text-transform:uppercase;font-size:20px;line-height:20px;font-weight:800;font-family:Raleway;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-197331:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-197331{background-color:#dd3333!important;}\n#btnsx-197331:hover{background-color:#d13030!important;}\n#btnsx-197331{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px;}\n#btnsx-197331:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:solid;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px;}\n#btnsx-197331{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-197331:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*197331-end*\/\n<\/style>\n<a href=\"https:\/\/dona.aibi.it\/emergenza-ucraina\/?act=cplt&amp;origine=web-button-in-post\" id=\"btnsx-197331\" class=\"btnsx-btn btnsx-btn-block\"  data-font-primary=\"Raleway\">\n\t<span class=\"btnsx-text-primary \">EMERGENZA UCRAINA<\/span><\/a>\n\n<!-- Buttons X - End -->\n\n","protected":false},"excerpt":{"rendered":"<p>Un sorriso, un gesto di accoglienza e alcune candeline su cui soffiare, hanno regalato un sorriso e un momento di serenit&agrave; ad una bimba ucraina che non voleva festeggiare il giorno del suo compleanno&hellip; A&nbsp;Edinet, nella piccola ma accogliente&nbsp;Moldova, sorge un&nbsp;centro&nbsp;di&nbsp;accoglienza&nbsp;per&nbsp;profughi&nbsp;ucraini gestito dall&rsquo;Ong DEMOS con il sostegno&nbsp;di&nbsp;Ai.Bi. e di altri [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":200258,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[909],"tags":[895,530],"class_list":["post-200256","post","type-post","status-publish","format-standard","has-post-thumbnail","category-bambinixlapace","tag-bambinixlapace","tag-moldova"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>BAMBINIXLAPACE. Moldova. Storie di vita nel Centro Profughi di Edinet: la bimba che non voleva festeggiare il suo compleanno - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Moldova. Un sorriso, un gesto di accoglienza e alcune candeline su cui soffiare, hanno regalato un sorriso e un momento di serenit\u00e0 ad una bimba ucraina che non voleva festeggiare il giorno del suo compleanno\u2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-storie-di-vita-nel-centro-profughi-di-edinet-la-bimba-che-non-voleva-festeggiare-il-suo-compleanno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BAMBINIXLAPACE. Moldova. Storie di vita nel Centro Profughi di Edinet: la bimba che non voleva festeggiare il suo compleanno\" \/>\n<meta property=\"og:description\" content=\"Moldova. Un sorriso, un gesto di accoglienza e alcune candeline su cui soffiare, hanno regalato un sorriso e un momento di serenit\u00e0 ad una bimba ucraina che non voleva festeggiare il giorno del suo compleanno\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-storie-di-vita-nel-centro-profughi-di-edinet-la-bimba-che-non-voleva-festeggiare-il-suo-compleanno\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-20T05:30:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-20T12:57:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2022\/05\/moldova-compleanno.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-storie-di-vita-nel-centro-profughi-di-edinet-la-bimba-che-non-voleva-festeggiare-il-suo-compleanno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-storie-di-vita-nel-centro-profughi-di-edinet-la-bimba-che-non-voleva-festeggiare-il-suo-compleanno\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"BAMBINIXLAPACE. Moldova. Storie di vita nel Centro Profughi di Edinet: la bimba che non voleva festeggiare il suo compleanno\",\"datePublished\":\"2022-05-20T05:30:34+00:00\",\"dateModified\":\"2022-05-20T12:57:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-storie-di-vita-nel-centro-profughi-di-edinet-la-bimba-che-non-voleva-festeggiare-il-suo-compleanno\\\/\"},\"wordCount\":530,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-storie-di-vita-nel-centro-profughi-di-edinet-la-bimba-che-non-voleva-festeggiare-il-suo-compleanno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/05\\\/moldova-compleanno.jpg\",\"keywords\":[\"BAMBINIxLAPACE\",\"Moldova\"],\"articleSection\":[\"BAMBINIXLAPACE\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-storie-di-vita-nel-centro-profughi-di-edinet-la-bimba-che-non-voleva-festeggiare-il-suo-compleanno\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-storie-di-vita-nel-centro-profughi-di-edinet-la-bimba-che-non-voleva-festeggiare-il-suo-compleanno\\\/\",\"name\":\"BAMBINIXLAPACE. Moldova. Storie di vita nel Centro Profughi di Edinet: la bimba che non voleva festeggiare il suo compleanno - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-storie-di-vita-nel-centro-profughi-di-edinet-la-bimba-che-non-voleva-festeggiare-il-suo-compleanno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-storie-di-vita-nel-centro-profughi-di-edinet-la-bimba-che-non-voleva-festeggiare-il-suo-compleanno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/05\\\/moldova-compleanno.jpg\",\"datePublished\":\"2022-05-20T05:30:34+00:00\",\"dateModified\":\"2022-05-20T12:57:43+00:00\",\"description\":\"Moldova. Un sorriso, un gesto di accoglienza e alcune candeline su cui soffiare, hanno regalato un sorriso e un momento di serenit\u00e0 ad una bimba ucraina che non voleva festeggiare il giorno del suo compleanno\u2026\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-storie-di-vita-nel-centro-profughi-di-edinet-la-bimba-che-non-voleva-festeggiare-il-suo-compleanno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-storie-di-vita-nel-centro-profughi-di-edinet-la-bimba-che-non-voleva-festeggiare-il-suo-compleanno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-storie-di-vita-nel-centro-profughi-di-edinet-la-bimba-che-non-voleva-festeggiare-il-suo-compleanno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/05\\\/moldova-compleanno.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/05\\\/moldova-compleanno.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-storie-di-vita-nel-centro-profughi-di-edinet-la-bimba-che-non-voleva-festeggiare-il-suo-compleanno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BAMBINIXLAPACE\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/bambinixlapace\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BAMBINIXLAPACE. Moldova. Storie di vita nel Centro Profughi di Edinet: la bimba che non voleva festeggiare il suo compleanno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"BAMBINIXLAPACE. Moldova. Storie di vita nel Centro Profughi di Edinet: la bimba che non voleva festeggiare il suo compleanno - Ai.Bi. Amici dei Bambini","description":"Moldova. Un sorriso, un gesto di accoglienza e alcune candeline su cui soffiare, hanno regalato un sorriso e un momento di serenit\u00e0 ad una bimba ucraina che non voleva festeggiare il giorno del suo compleanno\u2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-storie-di-vita-nel-centro-profughi-di-edinet-la-bimba-che-non-voleva-festeggiare-il-suo-compleanno\/","og_locale":"it_IT","og_type":"article","og_title":"BAMBINIXLAPACE. Moldova. Storie di vita nel Centro Profughi di Edinet: la bimba che non voleva festeggiare il suo compleanno","og_description":"Moldova. Un sorriso, un gesto di accoglienza e alcune candeline su cui soffiare, hanno regalato un sorriso e un momento di serenit\u00e0 ad una bimba ucraina che non voleva festeggiare il giorno del suo compleanno\u2026","og_url":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-storie-di-vita-nel-centro-profughi-di-edinet-la-bimba-che-non-voleva-festeggiare-il-suo-compleanno\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2022-05-20T05:30:34+00:00","article_modified_time":"2022-05-20T12:57:43+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2022\/05\/moldova-compleanno.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-storie-di-vita-nel-centro-profughi-di-edinet-la-bimba-che-non-voleva-festeggiare-il-suo-compleanno\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-storie-di-vita-nel-centro-profughi-di-edinet-la-bimba-che-non-voleva-festeggiare-il-suo-compleanno\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"BAMBINIXLAPACE. Moldova. Storie di vita nel Centro Profughi di Edinet: la bimba che non voleva festeggiare il suo compleanno","datePublished":"2022-05-20T05:30:34+00:00","dateModified":"2022-05-20T12:57:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-storie-di-vita-nel-centro-profughi-di-edinet-la-bimba-che-non-voleva-festeggiare-il-suo-compleanno\/"},"wordCount":530,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-storie-di-vita-nel-centro-profughi-di-edinet-la-bimba-che-non-voleva-festeggiare-il-suo-compleanno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/05\/moldova-compleanno.jpg","keywords":["BAMBINIxLAPACE","Moldova"],"articleSection":["BAMBINIXLAPACE"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-storie-di-vita-nel-centro-profughi-di-edinet-la-bimba-che-non-voleva-festeggiare-il-suo-compleanno\/","url":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-storie-di-vita-nel-centro-profughi-di-edinet-la-bimba-che-non-voleva-festeggiare-il-suo-compleanno\/","name":"BAMBINIXLAPACE. Moldova. Storie di vita nel Centro Profughi di Edinet: la bimba che non voleva festeggiare il suo compleanno - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-storie-di-vita-nel-centro-profughi-di-edinet-la-bimba-che-non-voleva-festeggiare-il-suo-compleanno\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-storie-di-vita-nel-centro-profughi-di-edinet-la-bimba-che-non-voleva-festeggiare-il-suo-compleanno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/05\/moldova-compleanno.jpg","datePublished":"2022-05-20T05:30:34+00:00","dateModified":"2022-05-20T12:57:43+00:00","description":"Moldova. Un sorriso, un gesto di accoglienza e alcune candeline su cui soffiare, hanno regalato un sorriso e un momento di serenit\u00e0 ad una bimba ucraina che non voleva festeggiare il giorno del suo compleanno\u2026","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-storie-di-vita-nel-centro-profughi-di-edinet-la-bimba-che-non-voleva-festeggiare-il-suo-compleanno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-storie-di-vita-nel-centro-profughi-di-edinet-la-bimba-che-non-voleva-festeggiare-il-suo-compleanno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-storie-di-vita-nel-centro-profughi-di-edinet-la-bimba-che-non-voleva-festeggiare-il-suo-compleanno\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2022\/05\/moldova-compleanno.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/05\/moldova-compleanno.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-storie-di-vita-nel-centro-profughi-di-edinet-la-bimba-che-non-voleva-festeggiare-il-suo-compleanno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"BAMBINIXLAPACE","item":"https:\/\/www.aibi.it\/ita\/category\/bambinixlapace\/"},{"@type":"ListItem","position":3,"name":"BAMBINIXLAPACE. Moldova. Storie di vita nel Centro Profughi di Edinet: la bimba che non voleva festeggiare il suo compleanno"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:34:08","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/200256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=200256"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/200256\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/200258"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=200256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=200256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=200256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}