﻿


{"id":200940,"date":"2022-06-14T07:30:14","date_gmt":"2022-06-14T05:30:14","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=200940"},"modified":"2023-10-25T14:52:31","modified_gmt":"2023-10-25T12:52:31","slug":"bambinixlapace-storie-di-bambini-paure-e-speranze-a-edinet-in-moldova","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/bambinixlapace-storie-di-bambini-paure-e-speranze-a-edinet-in-moldova\/","title":{"rendered":"BAMBINIxLAPACE. Storie di bambini, paure e speranze a Edine\u021b, in Moldova"},"content":{"rendered":"<h2>Nei centri profughi della Moldova si incrociano le storie e le vite di tanti bambini e famiglie in fuga dall\u2019Ucraina. Ai.Bi., con il gioco, le attivit\u00e0, il lavoro di tutto il suo staff e il vostro aiuto, accoglie, ascolta e prova a dare una nuova speranza a tutti<\/h2>\n<p><!--more--><\/p>\n<p><strong>\u00a0<\/strong>Irina \u00e8 una bambina ucraina che si trova in Moldova da circa un mese. \u00c8 arrivata con un bagaglio molto pesante, non composto da valigie o oggetti preziosi, che quando si scappa non si possono portare con s\u00e9, ma fatto di emozioni, ricordi, paure, dolore, rumore di missili sulla testa\u2026<br \/>\nIrina e sua mamma hanno trovato alloggio presso il centro di accoglienza per i profughi di <strong>Edine\u021b<\/strong>, nel nord della Moldova. Per loro \u00e8 stato il primo luogo in cui trovare un po\u2019 di conforto da quando hanno lasciato la loro casa. Il primo tetto stabile sotto cui assaggiare un po\u2019 di <strong>pace<\/strong> e nle quale l\u2019accoglienza ricevuta \u00e8 stata \u201coltre le aspettative\u201d. Ma ci vorr\u00e0 ancora del tempo e del lavoro per riuscire a istituire un <strong>vero rapporto di fiducia e condivisione<\/strong> tra chi soffre e chi offre aiuto.<\/p>\n<h3>Aiutare significa prendere su di s\u00e9 un po\u2019 del peso che portano gli altri<\/h3>\n<p>Per questo, al centro di Edinet, l\u2019aiuto umanitario non si limita a fornire vitto e alloggio, ma si estende ad <strong>altri servizi specializzati<\/strong> come consulenze giuridiche, supporto informativo, consulto medico e psicologico, inserimento lavorativo, ecc.<br \/>\nPerch\u00e9 il senso di portare aiuto in una situazione di guerra \u00e8 <strong>riuscire a prendere sulle proprie spalle un po\u2019 del peso<\/strong> che altri sono costretti a portare.<br \/>\nCon i bambini questa operazione \u00e8 pi\u00f9 difficile, specie con quelli che ancora non sanno parlare ma che gi\u00e0 hanno vissuto molti traumi. Per sciogliere il ghiaccio ci sono i giochi e le attivit\u00e0 ludiche: attraverso i disegni e le creazioni realizzate dai bambini, infatti, si possono intuire i loro problemi e le loro emozioni, strutturando, poi, degli <strong>interventi mirati pi\u00f9 efficaci<\/strong>.<br \/>\nIrina, per esempio, fin dal suo arrivo ha parlato per settimane intere in maniera ossessiva della sua casa: \u201cLo sapete che noi non abbiamo pi\u00f9 casa? &#8211; ripeteva. \u00c8 successo per la guerra che siamo rimasti senza casa. Ma io la rifar\u00f2. Prima sulla carta, e poi, da grande, la ricostruir\u00f2. La mia cameretta sar\u00e0 cos\u00ec\u201d &#8211; diceva, disegnandola su un foglio.<\/p>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-200945 size-full\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/Edinet-tre-storie.jpg\" alt=\"\" width=\"1200\" height=\"629\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/Edinet-tre-storie.jpg 1200w, https:\/\/www.aibi.it\/ita\/images\/2022\/06\/Edinet-tre-storie-572x300.jpg 572w, https:\/\/www.aibi.it\/ita\/images\/2022\/06\/Edinet-tre-storie-150x79.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/06\/Edinet-tre-storie-768x403.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>Storie di bambine tra paure e futuro<\/h3>\n<p>Olesea \u00e8 un\u2019altra piccola ospite del centro: ha 4 anni e si presentava sempre come \u201cfiglia di sua madre\u201d, in un segnale di come la guerra l\u2019avesse spinta a riaffermare in ogni occasione l\u2019appartenenza, per scongiurare la <strong>paura di perdere la figura materna<\/strong>. Con il passare dei giorni la situazione \u00e8 un po\u2019 migliorata: Olesa continua a non parlare molto, ma si fa capire quando vuole qualcosa, specie se si tratta di un pezzetto di cioccolato!<br \/>\nAnche Lena, 7 anni, preferisce il silenzio; addirittura sua mamma pensava che potesse avere problemi di comunicazione. Ma durante il gioco riesce a sciogliersi un po\u2019, rimostrando buone capacit\u00e0 creative e una <strong>spiccata sensibilit\u00e0 verso chi \u00e8 in difficolt\u00e0<\/strong>: si rende utile nelle attivit\u00e0 condotte dagli animatori e offre il suo aiuto agli altri bambini che non riescono a disegnare.<\/p>\n<p>Queste sono solo tre delle tante storie che tutti i giorni si intrecciano nei villaggi e nei centri della Moldova dove Ai.Bi. porta i suoi interventi nell\u2019ambito della campagna #BAMBINIxLAPACE, attiva anche in Ucraina e in Italia. Chiunque pu\u00f2 sostenere queste attivit\u00e0, e le storie che si incontrano, con una <a href=\"https:\/\/www.aibi.it\/ita\/emergenza-ucraina\/?scelta=Una%20tantum\">donazione una tantum<\/a> o con <a href=\"https:\/\/www.aibi.it\/ita\/emergenza-ucraina\/?scelta=Adozione%20a%20Distanza\">l\u2019Adozione a Distanza<\/a>.<br \/>\nE se sei cliente Fineco, la banca <a href=\"https:\/\/finecobank.com\/it\/online\/charity\/emergenza-ucraina\/\"><strong>raddoppia la tua donazione<\/strong><\/a> fino al 30 giugno. Ricordati che tutte le donazioni ad Ai.Bi. godono delle seguenti <a href=\"https:\/\/www.aibi.it\/ita\/images\/AGEVOLAZIONI_FISCALI.pdf\"><strong>agevolazioni fiscali<\/strong><\/a>.<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*197331-start*\/\n#btnsx-197331{margin-top:0px;margin-bottom:25px;margin-left:0px;margin-right:0px;padding-top:16px;padding-bottom:15px;padding-left:43px;padding-right:44px;}\n#btnsx-197331 .btnsx-text-primary{text-transform:uppercase;font-size:20px;line-height:20px;font-weight:800;font-family:Raleway;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-197331:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-197331{background-color:#dd3333!important;}\n#btnsx-197331:hover{background-color:#d13030!important;}\n#btnsx-197331{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px;}\n#btnsx-197331:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:solid;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px;}\n#btnsx-197331{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-197331:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*197331-end*\/\n<\/style>\n<a href=\"https:\/\/dona.aibi.it\/emergenza-ucraina\/?act=cplt&amp;origine=web-button-in-post\" id=\"btnsx-197331\" class=\"btnsx-btn btnsx-btn-block\"  data-font-primary=\"Raleway\">\n\t<span class=\"btnsx-text-primary \">EMERGENZA UCRAINA<\/span><\/a>\n\n<!-- Buttons X - End -->\n\n","protected":false},"excerpt":{"rendered":"<p>Nei centri profughi della Moldova si incrociano le storie e le vite di tanti bambini e famiglie in fuga dall&rsquo;Ucraina. Ai.Bi., con il gioco, le attivit&agrave;, il lavoro di tutto il suo staff e il vostro aiuto, accoglie, ascolta e prova a dare una nuova speranza a tutti<\/p>\n","protected":false},"author":102,"featured_media":200946,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[909],"tags":[895,530],"class_list":["post-200940","post","type-post","status-publish","format-standard","has-post-thumbnail","category-bambinixlapace","tag-bambinixlapace","tag-moldova"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Storie di bambini, paure e speranze a Edine\u021b, in Moldova<\/title>\n<meta name=\"description\" content=\"Nel centro profughi di Edinet, in Moldova, si incrociano le storie di tanti bambini e famiglie in fuga dall\u2019Ucraina. Ai.Bi. accoglie, ascolta e prova a dare speranza\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/bambinixlapace-storie-di-bambini-paure-e-speranze-a-edinet-in-moldova\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BAMBINIxLAPACE. Storie di bambini, paure e speranze a Edine\u021b, in Moldova\" \/>\n<meta property=\"og:description\" content=\"Nel centro profughi di Edinet, in Moldova, si incrociano le storie di tanti bambini e famiglie in fuga dall\u2019Ucraina. Ai.Bi. accoglie, ascolta e prova a dare speranza\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/bambinixlapace-storie-di-bambini-paure-e-speranze-a-edinet-in-moldova\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-14T05:30:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-25T12:52:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/Casa-visurilor-Edinet.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-storie-di-bambini-paure-e-speranze-a-edinet-in-moldova\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-storie-di-bambini-paure-e-speranze-a-edinet-in-moldova\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"BAMBINIxLAPACE. Storie di bambini, paure e speranze a Edine\u021b, in Moldova\",\"datePublished\":\"2022-06-14T05:30:14+00:00\",\"dateModified\":\"2023-10-25T12:52:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-storie-di-bambini-paure-e-speranze-a-edinet-in-moldova\\\/\"},\"wordCount\":628,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-storie-di-bambini-paure-e-speranze-a-edinet-in-moldova\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/06\\\/Casa-visurilor-Edinet.jpg\",\"keywords\":[\"BAMBINIxLAPACE\",\"Moldova\"],\"articleSection\":[\"BAMBINIXLAPACE\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-storie-di-bambini-paure-e-speranze-a-edinet-in-moldova\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-storie-di-bambini-paure-e-speranze-a-edinet-in-moldova\\\/\",\"name\":\"Storie di bambini, paure e speranze a Edine\u021b, in Moldova\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-storie-di-bambini-paure-e-speranze-a-edinet-in-moldova\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-storie-di-bambini-paure-e-speranze-a-edinet-in-moldova\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/06\\\/Casa-visurilor-Edinet.jpg\",\"datePublished\":\"2022-06-14T05:30:14+00:00\",\"dateModified\":\"2023-10-25T12:52:31+00:00\",\"description\":\"Nel centro profughi di Edinet, in Moldova, si incrociano le storie di tanti bambini e famiglie in fuga dall\u2019Ucraina. Ai.Bi. accoglie, ascolta e prova a dare speranza\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-storie-di-bambini-paure-e-speranze-a-edinet-in-moldova\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-storie-di-bambini-paure-e-speranze-a-edinet-in-moldova\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-storie-di-bambini-paure-e-speranze-a-edinet-in-moldova\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/06\\\/Casa-visurilor-Edinet.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/06\\\/Casa-visurilor-Edinet.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-storie-di-bambini-paure-e-speranze-a-edinet-in-moldova\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BAMBINIXLAPACE\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/bambinixlapace\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BAMBINIxLAPACE. Storie di bambini, paure e speranze a Edine\u021b, in Moldova\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Storie di bambini, paure e speranze a Edine\u021b, in Moldova","description":"Nel centro profughi di Edinet, in Moldova, si incrociano le storie di tanti bambini e famiglie in fuga dall\u2019Ucraina. Ai.Bi. accoglie, ascolta e prova a dare speranza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/bambinixlapace-storie-di-bambini-paure-e-speranze-a-edinet-in-moldova\/","og_locale":"it_IT","og_type":"article","og_title":"BAMBINIxLAPACE. Storie di bambini, paure e speranze a Edine\u021b, in Moldova","og_description":"Nel centro profughi di Edinet, in Moldova, si incrociano le storie di tanti bambini e famiglie in fuga dall\u2019Ucraina. Ai.Bi. accoglie, ascolta e prova a dare speranza","og_url":"https:\/\/www.aibi.it\/ita\/bambinixlapace-storie-di-bambini-paure-e-speranze-a-edinet-in-moldova\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2022-06-14T05:30:14+00:00","article_modified_time":"2023-10-25T12:52:31+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/Casa-visurilor-Edinet.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-storie-di-bambini-paure-e-speranze-a-edinet-in-moldova\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-storie-di-bambini-paure-e-speranze-a-edinet-in-moldova\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"BAMBINIxLAPACE. Storie di bambini, paure e speranze a Edine\u021b, in Moldova","datePublished":"2022-06-14T05:30:14+00:00","dateModified":"2023-10-25T12:52:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-storie-di-bambini-paure-e-speranze-a-edinet-in-moldova\/"},"wordCount":628,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-storie-di-bambini-paure-e-speranze-a-edinet-in-moldova\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/Casa-visurilor-Edinet.jpg","keywords":["BAMBINIxLAPACE","Moldova"],"articleSection":["BAMBINIXLAPACE"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-storie-di-bambini-paure-e-speranze-a-edinet-in-moldova\/","url":"https:\/\/www.aibi.it\/ita\/bambinixlapace-storie-di-bambini-paure-e-speranze-a-edinet-in-moldova\/","name":"Storie di bambini, paure e speranze a Edine\u021b, in Moldova","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-storie-di-bambini-paure-e-speranze-a-edinet-in-moldova\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-storie-di-bambini-paure-e-speranze-a-edinet-in-moldova\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/Casa-visurilor-Edinet.jpg","datePublished":"2022-06-14T05:30:14+00:00","dateModified":"2023-10-25T12:52:31+00:00","description":"Nel centro profughi di Edinet, in Moldova, si incrociano le storie di tanti bambini e famiglie in fuga dall\u2019Ucraina. Ai.Bi. accoglie, ascolta e prova a dare speranza","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-storie-di-bambini-paure-e-speranze-a-edinet-in-moldova\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/bambinixlapace-storie-di-bambini-paure-e-speranze-a-edinet-in-moldova\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-storie-di-bambini-paure-e-speranze-a-edinet-in-moldova\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/Casa-visurilor-Edinet.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/Casa-visurilor-Edinet.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-storie-di-bambini-paure-e-speranze-a-edinet-in-moldova\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"BAMBINIXLAPACE","item":"https:\/\/www.aibi.it\/ita\/category\/bambinixlapace\/"},{"@type":"ListItem","position":3,"name":"BAMBINIxLAPACE. Storie di bambini, paure e speranze a Edine\u021b, in Moldova"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:55:49","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/200940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=200940"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/200940\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/200946"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=200940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=200940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=200940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}