﻿


{"id":201028,"date":"2022-06-17T07:46:12","date_gmt":"2022-06-17T05:46:12","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=201028"},"modified":"2023-10-25T14:52:29","modified_gmt":"2023-10-25T12:52:29","slug":"bambinixlapace-moldova-il-servizio-ludico-un-trattamento-per-il-benessere-mentale-dei-bambini-ucraini","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-il-servizio-ludico-un-trattamento-per-il-benessere-mentale-dei-bambini-ucraini\/","title":{"rendered":"BAMBINIXLAPACE. Moldova: Il servizio ludico, un trattamento per il benessere mentale dei bambini ucraini"},"content":{"rendered":"<h2 style=\"font-weight: 400;\"><strong>Guidati dai ludotecari e dagli animatori, con i quali hanno sviluppato un rapporto di fiducia, i bambini sono aiutati a potenziare le loro abilit\u00e0, ma anche a superare gli ostacoli nella loro mente<\/strong><\/h2>\n<p style=\"font-weight: 400;\"><strong>Diana e Liliana<\/strong>\u00a0sono\u00a0<strong>due gemelline ucraine di 4 anni<\/strong>\u00a0e insieme alla loro mamma vivono in\u00a0<strong>Moldova<\/strong>, nel Centro d\u2019accoglienza di\u00a0<strong>Carpinen<\/strong>i gi\u00e0 da due mesi.<\/p>\n<p style=\"font-weight: 400;\">Le piccole, che in poco tempo si sono abituate alle circostanze della struttura, la considerano ormai come la loro nuova casa, questo grazie anche al supporto che hanno ricevuto per potersi integrare al meglio nella nuova comunit\u00e0.<\/p>\n<h3 style=\"font-weight: 400;\"><strong>Diana e Liliana: i \u201crazzi della gioia\u201d<\/strong><\/h3>\n<p style=\"font-weight: 400;\">Fin dall\u2019arrivo nel centro, le gemelline si sono conquistate subito la simpatia dei collaboratori e degli altri ospiti che vi hanno trovato accoglienza.<\/p>\n<p style=\"font-weight: 400;\"><em>\u201cQuando appaiono nella sala giochi, la sensazione \u00e8 quella che\u00a0<strong>il sole splende ancora pi\u00f9 forte\u201d<\/strong><\/em><strong>,<\/strong>\u00a0racconta Nina Secrieru, la responsabile delle attivit\u00e0 di animazione svolte nella ludoteca allestita all\u2019interno del Centro.\u00a0<em>\u201c\u00c8 grazie all\u2019energia di queste bambine che viene mantenuta\u00a0<strong>un\u2019atmosfera solare e molto calda<\/strong>\u00a0durante le nostre attivit\u00e0, per cui tutti, a buon diritto, le abbiamo soprannominate \u201c<strong>i razzi della gioia\u201d<\/strong><\/em>, continua la signora Nina.<\/p>\n<p style=\"font-weight: 400;\">La famiglia \u00e8 partita in tempo\u00a0<strong>dall\u2019Ucraina,<\/strong>\u00a0salvandosi dai razzi \u2013 quelli veri per\u00f2 \u2013 che qualche giorno dopo la loro partenza sono precipitati sopra le case dei parenti, causando vere tragedie e perdite irrecuperabili.<\/p>\n<p style=\"font-weight: 400;\">La mamma delle gemelline, a Carpineni, ha ricevuto tutto il supporto psicologico necessario per poter affrontare un momento cos\u00ec terribile e rimanere forte per le sue figlie.<\/p>\n<p style=\"font-weight: 400;\">Anche se con\u00a0<strong>Diana e Liliana<\/strong>\u00a0la mamma non parla mai della guerra, le piccole nel loro Paese non vogliono pi\u00f9 tornare e affermano che se un giorno dovranno uscire\u00a0<strong>dal Centro, che ora \u00e8 la loro casa, lo faranno solo per andare al mercato, ma in nessun caso per tornare in Ucraina.<\/strong><\/p>\n<h3 style=\"font-weight: 400;\"><strong>Superare il trauma attraverso il gioco<\/strong><\/h3>\n<p style=\"font-weight: 400;\">Occorre lavorare sui timori di queste bimbe con servizi di supporto,\u00a0per permettere loro di superarli prima che si trasformino\u00a0<strong>in traumi con effetti gravi per la salute.\u00a0<\/strong>Un primo aiuto, che gi\u00e0 sta dando buoni risultati, \u00e8 proprio quello del gioco.<\/p>\n<p style=\"font-weight: 400;\">Grazie ai libri ed ai giochi interattivi, ottime risorse per l\u2019insegnamento ai bambini della loro et\u00e0,\u00a0<strong>Diana e Liliana<\/strong>\u00a0trascorrono lunghi momenti sereni nella ludoteca, in compagnia di coetanei, venuti sempre dall\u2019Ucraina. Guidati dai ludotecari e dagli animatori, con i quali hanno sviluppato un rapporto di fiducia, i bambini sono aiutati ad imparare e a potenziare le loro abilit\u00e0, ma anche a superare gli ostacoli nella loro mente.<\/p>\n<h3 style=\"font-weight: 400;\"><strong>Storie di bambine tra paure e futuro<\/strong><\/h3>\n<p style=\"font-weight: 400;\">Queste sono solo tre delle tante storie che tutti i giorni si intrecciano nei villaggi e nei centri della Moldova dove Ai.Bi. porta i suoi interventi nell\u2019ambito della campagna #BAMBINIxLAPACE, attiva anche in Ucraina e in Italia. Chiunque pu\u00f2 sostenere queste attivit\u00e0, e le storie che si incontrano, con una\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/emergenza-ucraina\/?scelta=Una%20tantum\">donazione una tantum<\/a>\u00a0o con\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/emergenza-ucraina\/?scelta=Adozione%20a%20Distanza\">l\u2019Adozione a Distanza<\/a>.<br \/>\nE se sei cliente Fineco, la banca\u00a0<a href=\"https:\/\/finecobank.com\/it\/online\/charity\/emergenza-ucraina\/\"><strong>raddoppia la tua donazione<\/strong><\/a>\u00a0fino al 30 giugno. Ricordati che tutte le donazioni ad Ai.Bi. godono delle seguenti\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/images\/AGEVOLAZIONI_FISCALI.pdf\"><strong>agevolazioni fiscali<\/strong><\/a>.<\/p>\n<p style=\"font-weight: 400;\">\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*197331-start*\/\n#btnsx-197331{margin-top:0px;margin-bottom:25px;margin-left:0px;margin-right:0px;padding-top:16px;padding-bottom:15px;padding-left:43px;padding-right:44px;}\n#btnsx-197331 .btnsx-text-primary{text-transform:uppercase;font-size:20px;line-height:20px;font-weight:800;font-family:Raleway;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-197331:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-197331{background-color:#dd3333!important;}\n#btnsx-197331:hover{background-color:#d13030!important;}\n#btnsx-197331{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px;}\n#btnsx-197331:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:solid;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px;}\n#btnsx-197331{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-197331:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*197331-end*\/\n<\/style>\n<a href=\"https:\/\/dona.aibi.it\/emergenza-ucraina\/?act=cplt&amp;origine=web-button-in-post\" id=\"btnsx-197331\" class=\"btnsx-btn btnsx-btn-block\"  data-font-primary=\"Raleway\">\n\t<span class=\"btnsx-text-primary \">EMERGENZA UCRAINA<\/span><\/a>\n\n<!-- Buttons X - End -->\n\n<p style=\"font-weight: 400;\">\n","protected":false},"excerpt":{"rendered":"<p>Guidati dai ludotecari e dagli animatori, con i quali hanno sviluppato un rapporto di fiducia, i bambini sono aiutati a potenziare le loro abilit&agrave;, ma anche a superare gli ostacoli nella loro mente Diana e Liliana&nbsp;sono&nbsp;due gemelline ucraine di 4 anni&nbsp;e insieme alla loro mamma vivono in&nbsp;Moldova, nel Centro d&rsquo;accoglienza [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":201034,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[909],"tags":[895,530],"class_list":["post-201028","post","type-post","status-publish","format-standard","has-post-thumbnail","category-bambinixlapace","tag-bambinixlapace","tag-moldova"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>BAMBINIXLAPACE. Moldova: Il servizio ludico, un trattamento per il benessere mentale dei bambini ucraini - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Moldova. Guidati dai ludotecari e dagli animatori, con i quali hanno sviluppato un rapporto di fiducia, i bambini sono aiutati a potenziare le loro abilit\u00e0, ma anche a superare gli ostacoli nella loro mente\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-il-servizio-ludico-un-trattamento-per-il-benessere-mentale-dei-bambini-ucraini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BAMBINIXLAPACE. Moldova: Il servizio ludico, un trattamento per il benessere mentale dei bambini ucraini\" \/>\n<meta property=\"og:description\" content=\"Moldova. Guidati dai ludotecari e dagli animatori, con i quali hanno sviluppato un rapporto di fiducia, i bambini sono aiutati a potenziare le loro abilit\u00e0, ma anche a superare gli ostacoli nella loro mente\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-il-servizio-ludico-un-trattamento-per-il-benessere-mentale-dei-bambini-ucraini\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-17T05:46:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-25T12:52:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/moldova.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-il-servizio-ludico-un-trattamento-per-il-benessere-mentale-dei-bambini-ucraini\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-il-servizio-ludico-un-trattamento-per-il-benessere-mentale-dei-bambini-ucraini\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"BAMBINIXLAPACE. Moldova: Il servizio ludico, un trattamento per il benessere mentale dei bambini ucraini\",\"datePublished\":\"2022-06-17T05:46:12+00:00\",\"dateModified\":\"2023-10-25T12:52:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-il-servizio-ludico-un-trattamento-per-il-benessere-mentale-dei-bambini-ucraini\\\/\"},\"wordCount\":536,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-il-servizio-ludico-un-trattamento-per-il-benessere-mentale-dei-bambini-ucraini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/06\\\/moldova.png\",\"keywords\":[\"BAMBINIxLAPACE\",\"Moldova\"],\"articleSection\":[\"BAMBINIXLAPACE\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-il-servizio-ludico-un-trattamento-per-il-benessere-mentale-dei-bambini-ucraini\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-il-servizio-ludico-un-trattamento-per-il-benessere-mentale-dei-bambini-ucraini\\\/\",\"name\":\"BAMBINIXLAPACE. Moldova: Il servizio ludico, un trattamento per il benessere mentale dei bambini ucraini - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-il-servizio-ludico-un-trattamento-per-il-benessere-mentale-dei-bambini-ucraini\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-il-servizio-ludico-un-trattamento-per-il-benessere-mentale-dei-bambini-ucraini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/06\\\/moldova.png\",\"datePublished\":\"2022-06-17T05:46:12+00:00\",\"dateModified\":\"2023-10-25T12:52:29+00:00\",\"description\":\"Moldova. Guidati dai ludotecari e dagli animatori, con i quali hanno sviluppato un rapporto di fiducia, i bambini sono aiutati a potenziare le loro abilit\u00e0, ma anche a superare gli ostacoli nella loro mente\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-il-servizio-ludico-un-trattamento-per-il-benessere-mentale-dei-bambini-ucraini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-il-servizio-ludico-un-trattamento-per-il-benessere-mentale-dei-bambini-ucraini\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-il-servizio-ludico-un-trattamento-per-il-benessere-mentale-dei-bambini-ucraini\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/06\\\/moldova.png\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/06\\\/moldova.png\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-il-servizio-ludico-un-trattamento-per-il-benessere-mentale-dei-bambini-ucraini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BAMBINIXLAPACE\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/bambinixlapace\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BAMBINIXLAPACE. Moldova: Il servizio ludico, un trattamento per il benessere mentale dei bambini ucraini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"BAMBINIXLAPACE. Moldova: Il servizio ludico, un trattamento per il benessere mentale dei bambini ucraini - Ai.Bi. Amici dei Bambini","description":"Moldova. Guidati dai ludotecari e dagli animatori, con i quali hanno sviluppato un rapporto di fiducia, i bambini sono aiutati a potenziare le loro abilit\u00e0, ma anche a superare gli ostacoli nella loro mente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-il-servizio-ludico-un-trattamento-per-il-benessere-mentale-dei-bambini-ucraini\/","og_locale":"it_IT","og_type":"article","og_title":"BAMBINIXLAPACE. Moldova: Il servizio ludico, un trattamento per il benessere mentale dei bambini ucraini","og_description":"Moldova. Guidati dai ludotecari e dagli animatori, con i quali hanno sviluppato un rapporto di fiducia, i bambini sono aiutati a potenziare le loro abilit\u00e0, ma anche a superare gli ostacoli nella loro mente","og_url":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-il-servizio-ludico-un-trattamento-per-il-benessere-mentale-dei-bambini-ucraini\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2022-06-17T05:46:12+00:00","article_modified_time":"2023-10-25T12:52:29+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/moldova.png","type":"image\/png"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-il-servizio-ludico-un-trattamento-per-il-benessere-mentale-dei-bambini-ucraini\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-il-servizio-ludico-un-trattamento-per-il-benessere-mentale-dei-bambini-ucraini\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"BAMBINIXLAPACE. Moldova: Il servizio ludico, un trattamento per il benessere mentale dei bambini ucraini","datePublished":"2022-06-17T05:46:12+00:00","dateModified":"2023-10-25T12:52:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-il-servizio-ludico-un-trattamento-per-il-benessere-mentale-dei-bambini-ucraini\/"},"wordCount":536,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-il-servizio-ludico-un-trattamento-per-il-benessere-mentale-dei-bambini-ucraini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/moldova.png","keywords":["BAMBINIxLAPACE","Moldova"],"articleSection":["BAMBINIXLAPACE"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-il-servizio-ludico-un-trattamento-per-il-benessere-mentale-dei-bambini-ucraini\/","url":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-il-servizio-ludico-un-trattamento-per-il-benessere-mentale-dei-bambini-ucraini\/","name":"BAMBINIXLAPACE. Moldova: Il servizio ludico, un trattamento per il benessere mentale dei bambini ucraini - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-il-servizio-ludico-un-trattamento-per-il-benessere-mentale-dei-bambini-ucraini\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-il-servizio-ludico-un-trattamento-per-il-benessere-mentale-dei-bambini-ucraini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/moldova.png","datePublished":"2022-06-17T05:46:12+00:00","dateModified":"2023-10-25T12:52:29+00:00","description":"Moldova. Guidati dai ludotecari e dagli animatori, con i quali hanno sviluppato un rapporto di fiducia, i bambini sono aiutati a potenziare le loro abilit\u00e0, ma anche a superare gli ostacoli nella loro mente","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-il-servizio-ludico-un-trattamento-per-il-benessere-mentale-dei-bambini-ucraini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-il-servizio-ludico-un-trattamento-per-il-benessere-mentale-dei-bambini-ucraini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-il-servizio-ludico-un-trattamento-per-il-benessere-mentale-dei-bambini-ucraini\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/moldova.png","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/moldova.png","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-il-servizio-ludico-un-trattamento-per-il-benessere-mentale-dei-bambini-ucraini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"BAMBINIXLAPACE","item":"https:\/\/www.aibi.it\/ita\/category\/bambinixlapace\/"},{"@type":"ListItem","position":3,"name":"BAMBINIXLAPACE. Moldova: Il servizio ludico, un trattamento per il benessere mentale dei bambini ucraini"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:57:03","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/201028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=201028"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/201028\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/201034"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=201028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=201028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=201028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}