﻿


{"id":201299,"date":"2022-06-27T07:39:42","date_gmt":"2022-06-27T05:39:42","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=201299"},"modified":"2022-06-27T20:29:56","modified_gmt":"2022-06-27T18:29:56","slug":"muovi-i-primi-passi-verso-ladozione-di-un-bambino-il-5-giugno-il-webinar","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/muovi-i-primi-passi-verso-ladozione-di-un-bambino-il-5-giugno-il-webinar\/","title":{"rendered":"Muovi i primi passi verso l\u2019adozione di un bambino: il 5 luglio il webinar"},"content":{"rendered":"<h2 style=\"font-weight: 400;\"><strong>Il webinar risponde all\u2019esigenza di dare alle coppie che intendono avvicinarsi per la prima volta al mondo dell\u2019adozione, le nozioni base sulla normativa di riferimento e le procedure da espletare, nonch\u00e9 sul significato stesso dell\u2019adozione\u00a0internazionale\u00a0<\/strong><\/h2>\n<p style=\"font-weight: 400;\">Nei dati pubblicati dal Ministero della Giustizia riguardanti le adozioni 2001 \u2013 2021, si legge un desiderio di adottare che permane nelle coppie italiane.<\/p>\n<p style=\"font-weight: 400;\">Dopo un periodo difficile per le adozioni, che le ha viste precipitare dalle 8.274 richieste del 2004 alle 1920 domande del 2020, nel 2021, finalmente, si torna a vedere un incremento rispetto all\u2019anno precedente con 120 domande in pi\u00f9.\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/sorpresa-tornano-a-salire-le-richieste-di-adozione-internazionale\/\" target=\"_blank\" rel=\"noopener\">QUI<\/a><\/p>\n<p style=\"font-weight: 400;\">Ci\u00f2 che \u00e8 davvero importante \u00e8 arrivare all\u2019incontro con il proprio figlio\u00a0<strong>informati e formati<\/strong>. Proprio per questo\u00a0<strong>FARIS \u2013 Family Relationship International School,\u00a0<\/strong>la scuola di formazione della Fondazione Ai.Bi. organizza webinar dedicati all\u2019Adozione Internazionale che accompagnano gli \u201caspiranti genitori adottivi\u201d sin dai loro \u201cprimi passi\u201d nel mondo dell\u2019adozione.<\/p>\n<h2 style=\"font-weight: 400;\"><strong>Il prossimo webinar \u201cPrimi passi nel mondo dell\u2019Adozione Internazionale\u201d si terr\u00e0 marted\u00ec 5 luglio, ore 15.00, al costo di 10 euro.<\/strong><\/h2>\n<p style=\"font-weight: 400;\">Il webinar risponde all\u2019esigenza di dare alle coppie che intendono avvicinarsi per la prima volta al mondo dell\u2019adozione,\u00a0<strong>le nozioni base sulla normativa di riferimento e le procedure da espletare<\/strong>, nonch\u00e9 sul significato stesso dell\u2019adozione.<\/p>\n<p style=\"font-weight: 400;\">Caterina Calamo, psicologa, operatrice Ai.Bi. ed esperta di Adozione Internazionale, fornir\u00e0 ai partecipanti gli strumenti necessari per\u00a0<strong>presentare domanda di idoneit\u00e0<\/strong>\u00a0per diventare genitori adottivi sia a livello nazionale che a livello internazionale.<\/p>\n<p style=\"font-weight: 400;\">Il webinar \u00e8 rivolto a tutte le\u00a0<strong>coppie di coniugi mai entrate in contatto con il mondo dell\u2019adozione<\/strong>\u00a0e che non hanno ancora presentato domanda per l\u2019ottenimento di idoneit\u00e0.<\/p>\n<p style=\"font-weight: 400;\">Maggiori informazioni e iscrizioni\u00a0<a href=\"https:\/\/www.fondazioneaibi.it\/faris\/prodotto\/webinar-primi-passi-nel-mondo-delladozione-internazionale-5-luglio\/\" target=\"_blank\" rel=\"noopener\">QUI<\/a><\/p>\n<p style=\"font-weight: 400;\">\n","protected":false},"excerpt":{"rendered":"<p>Il webinar risponde all&rsquo;esigenza di dare alle coppie che intendono avvicinarsi per la prima volta al mondo dell&rsquo;adozione, le nozioni base sulla normativa di riferimento e le procedure da espletare, nonch&eacute; sul significato stesso dell&rsquo;adozione&nbsp;internazionale&nbsp; Nei dati pubblicati dal Ministero della Giustizia riguardanti le adozioni 2001 &ndash; 2021, si legge [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":201320,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[777],"tags":[279,776,718],"class_list":["post-201299","post","type-post","status-publish","format-standard","has-post-thumbnail","category-faris","tag-adozione","tag-faris","tag-webinar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Muovi i primi passi verso l\u2019adozione di un bambino: il 5 luglio il webinar - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Adozione. Il webinar risponde all\u2019esigenza di dare alle coppie che intendono avvicinarsi per la prima volta al mondo dell\u2019adozione, le nozioni base sulla normativa di riferimento e le procedure da espletare, nonch\u00e9 sul significato stesso dell\u2019adozione\u00a0internazionale\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/muovi-i-primi-passi-verso-ladozione-di-un-bambino-il-5-giugno-il-webinar\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Muovi i primi passi verso l\u2019adozione di un bambino: il 5 luglio il webinar\" \/>\n<meta property=\"og:description\" content=\"Adozione. Il webinar risponde all\u2019esigenza di dare alle coppie che intendono avvicinarsi per la prima volta al mondo dell\u2019adozione, le nozioni base sulla normativa di riferimento e le procedure da espletare, nonch\u00e9 sul significato stesso dell\u2019adozione\u00a0internazionale\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/muovi-i-primi-passi-verso-ladozione-di-un-bambino-il-5-giugno-il-webinar\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-27T05:39:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-27T18:29:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/Adozione-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/muovi-i-primi-passi-verso-ladozione-di-un-bambino-il-5-giugno-il-webinar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/muovi-i-primi-passi-verso-ladozione-di-un-bambino-il-5-giugno-il-webinar\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"Muovi i primi passi verso l\u2019adozione di un bambino: il 5 luglio il webinar\",\"datePublished\":\"2022-06-27T05:39:42+00:00\",\"dateModified\":\"2022-06-27T18:29:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/muovi-i-primi-passi-verso-ladozione-di-un-bambino-il-5-giugno-il-webinar\\\/\"},\"wordCount\":286,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/muovi-i-primi-passi-verso-ladozione-di-un-bambino-il-5-giugno-il-webinar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/06\\\/Adozione-6.jpg\",\"keywords\":[\"adozione\",\"FARIS\",\"Webinar\"],\"articleSection\":[\"Faris\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/muovi-i-primi-passi-verso-ladozione-di-un-bambino-il-5-giugno-il-webinar\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/muovi-i-primi-passi-verso-ladozione-di-un-bambino-il-5-giugno-il-webinar\\\/\",\"name\":\"Muovi i primi passi verso l\u2019adozione di un bambino: il 5 luglio il webinar - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/muovi-i-primi-passi-verso-ladozione-di-un-bambino-il-5-giugno-il-webinar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/muovi-i-primi-passi-verso-ladozione-di-un-bambino-il-5-giugno-il-webinar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/06\\\/Adozione-6.jpg\",\"datePublished\":\"2022-06-27T05:39:42+00:00\",\"dateModified\":\"2022-06-27T18:29:56+00:00\",\"description\":\"Adozione. Il webinar risponde all\u2019esigenza di dare alle coppie che intendono avvicinarsi per la prima volta al mondo dell\u2019adozione, le nozioni base sulla normativa di riferimento e le procedure da espletare, nonch\u00e9 sul significato stesso dell\u2019adozione\u00a0internazionale\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/muovi-i-primi-passi-verso-ladozione-di-un-bambino-il-5-giugno-il-webinar\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/muovi-i-primi-passi-verso-ladozione-di-un-bambino-il-5-giugno-il-webinar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/muovi-i-primi-passi-verso-ladozione-di-un-bambino-il-5-giugno-il-webinar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/06\\\/Adozione-6.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/06\\\/Adozione-6.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/muovi-i-primi-passi-verso-ladozione-di-un-bambino-il-5-giugno-il-webinar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Faris\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/faris\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Muovi i primi passi verso l\u2019adozione di un bambino: il 5 luglio il webinar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Muovi i primi passi verso l\u2019adozione di un bambino: il 5 luglio il webinar - Ai.Bi. Amici dei Bambini","description":"Adozione. Il webinar risponde all\u2019esigenza di dare alle coppie che intendono avvicinarsi per la prima volta al mondo dell\u2019adozione, le nozioni base sulla normativa di riferimento e le procedure da espletare, nonch\u00e9 sul significato stesso dell\u2019adozione\u00a0internazionale\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/muovi-i-primi-passi-verso-ladozione-di-un-bambino-il-5-giugno-il-webinar\/","og_locale":"it_IT","og_type":"article","og_title":"Muovi i primi passi verso l\u2019adozione di un bambino: il 5 luglio il webinar","og_description":"Adozione. Il webinar risponde all\u2019esigenza di dare alle coppie che intendono avvicinarsi per la prima volta al mondo dell\u2019adozione, le nozioni base sulla normativa di riferimento e le procedure da espletare, nonch\u00e9 sul significato stesso dell\u2019adozione\u00a0internazionale\u00a0","og_url":"https:\/\/www.aibi.it\/ita\/muovi-i-primi-passi-verso-ladozione-di-un-bambino-il-5-giugno-il-webinar\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2022-06-27T05:39:42+00:00","article_modified_time":"2022-06-27T18:29:56+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/Adozione-6.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/muovi-i-primi-passi-verso-ladozione-di-un-bambino-il-5-giugno-il-webinar\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/muovi-i-primi-passi-verso-ladozione-di-un-bambino-il-5-giugno-il-webinar\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"Muovi i primi passi verso l\u2019adozione di un bambino: il 5 luglio il webinar","datePublished":"2022-06-27T05:39:42+00:00","dateModified":"2022-06-27T18:29:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/muovi-i-primi-passi-verso-ladozione-di-un-bambino-il-5-giugno-il-webinar\/"},"wordCount":286,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/muovi-i-primi-passi-verso-ladozione-di-un-bambino-il-5-giugno-il-webinar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/Adozione-6.jpg","keywords":["adozione","FARIS","Webinar"],"articleSection":["Faris"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/muovi-i-primi-passi-verso-ladozione-di-un-bambino-il-5-giugno-il-webinar\/","url":"https:\/\/www.aibi.it\/ita\/muovi-i-primi-passi-verso-ladozione-di-un-bambino-il-5-giugno-il-webinar\/","name":"Muovi i primi passi verso l\u2019adozione di un bambino: il 5 luglio il webinar - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/muovi-i-primi-passi-verso-ladozione-di-un-bambino-il-5-giugno-il-webinar\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/muovi-i-primi-passi-verso-ladozione-di-un-bambino-il-5-giugno-il-webinar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/Adozione-6.jpg","datePublished":"2022-06-27T05:39:42+00:00","dateModified":"2022-06-27T18:29:56+00:00","description":"Adozione. Il webinar risponde all\u2019esigenza di dare alle coppie che intendono avvicinarsi per la prima volta al mondo dell\u2019adozione, le nozioni base sulla normativa di riferimento e le procedure da espletare, nonch\u00e9 sul significato stesso dell\u2019adozione\u00a0internazionale\u00a0","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/muovi-i-primi-passi-verso-ladozione-di-un-bambino-il-5-giugno-il-webinar\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/muovi-i-primi-passi-verso-ladozione-di-un-bambino-il-5-giugno-il-webinar\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/muovi-i-primi-passi-verso-ladozione-di-un-bambino-il-5-giugno-il-webinar\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/Adozione-6.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/Adozione-6.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/muovi-i-primi-passi-verso-ladozione-di-un-bambino-il-5-giugno-il-webinar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Faris","item":"https:\/\/www.aibi.it\/ita\/category\/faris\/"},{"@type":"ListItem","position":3,"name":"Muovi i primi passi verso l\u2019adozione di un bambino: il 5 luglio il webinar"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:55:44","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/201299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=201299"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/201299\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/201320"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=201299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=201299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=201299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}