﻿{"id":20164,"date":"2011-02-25T16:30:04","date_gmt":"2011-02-25T15:30:04","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=20164"},"modified":"2011-02-25T16:32:44","modified_gmt":"2011-02-25T15:32:44","slug":"adozioni-ai-single-prevale-l%e2%80%99interesse-del-bambino","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozioni-ai-single-prevale-l%e2%80%99interesse-del-bambino\/","title":{"rendered":"Adozioni ai single: prevale l\u2019interesse del bambino"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/Adozione-genitore-single.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-20167\" style=\"margin: 5px;\" title=\"Adozione-genitore-single\" src=\"https:\/\/www.aibi.it\/ita\/images\/Adozione-genitore-single.jpg\" alt=\"\" width=\"100\" height=\"100\" \/><\/a>Riportiamo oggi il commento di Adriano Sansa, presidente del Tribunale per i Minori di Genova, pubblicato sull\u2019ultimo numero di Famiglia Cristiana.<\/p>\n<p><em>\u201cL\u2019adozione \u00e8 nell\u2019interesse del bambino, che trova una sua famiglia. Si appagano cos\u00ec anche un\u2019aspirazione profonda e un impulso di affetti degli adottanti. Conta che non si perda di vista la premessa e che chi adotta abbia le qualit\u00e0 necessarie, anche di fronte a difficolt\u00e0 e a frustrazioni che verranno rispetto all\u2019immagine ideale del figlio.<br \/>\n<strong>Quando vi sia una coppia valida, la rete familiare \u00e8 pi\u00f9 vasta, sono presenti entrambe le figure, maschile e femminile, anche ai fini della formazione della personalit\u00e0 e dell\u2019identit\u00e0<\/strong>: si \u00e8 il pi\u00f9 possibile vicini al modello ideale, come \u00e8 giusto che sia per il bene del bambino. Ci\u00f2 non significa naturalmente un giudizio di preferenza della persona del coniugato come tale rispetto al \u201csingolo\u201d; e non garantisce la felice riuscita del rapporto adottivo. Ma sembra corrispondere alle migliori delle opportunit\u00e0. Nelle adozioni nazionali, il numero delle coppie richiedenti eccede quello dei bambini. Pi\u00f9 complessa la situazione in quelle internazionali, sul cui andamento pesa la crisi che espone bambini di molti Paesi a rischi estremi e riduce la disponibilit\u00e0 di adottanti. Pu\u00f2 venire il momento in cui non vi siano abbastanza coppie idonee? L\u2019adozione del singolo potrebbe avere uno spazio, che peraltro gi\u00e0 oggi ha nei \u201ccasi particolari\u201d previsti dalla nostra legislazione (quando vi sia, per esempio, un rapporto di affetto o di convivenza che va garantito senza che si spezzi la relazione con la famiglia biologica, magari inadeguata ma presente).<br \/>\n<strong>Per bambini con gravi ferite fisiche o psichiche spesso non si fanno avanti n\u00e9 coniugi n\u00e9 single. <\/strong>Non dimentichiamo per\u00f2 che il primo obiettivo, anche secondo le convenzioni internazionali, \u00e8 quello di promuovere la capacit\u00e0 della famiglia ad assolvere ai propri compiti. L\u2019estensione della possibilit\u00e0 di adottare a single e coppie gay, in molti Paesi, potrebbe derivare anche da un appannamento di questo traguardo e del principio della prevalenza dell\u2019interesse del minore sulle aspettative degli adulti.\u201d<\/em><\/p>\n<p><em>(Fonte: Famiglia Cristiana N.9-2011)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Riportiamo oggi il commento di <strong>Adriano Sansa<\/strong>,<strong> presidente del Tribunale per i Minori di Genova,<\/strong> pubblicato sull\u2019ultimo numero di Famiglia Cristiana. <em>\u201cL\u2019adozione \u00e8 nell\u2019interesse del bambino, che trova una sua famiglia. Si appagano cos\u00ec anche un\u2019aspirazione profonda e un impulso di affetti degli adottanti&#8221;<\/em>. <strong><a href=\"https:\/\/www.aibi.it\/ita\/adozioni-ai-single-prevale-l\u2019interesse-del-bambino\/\">LEGGI TUTTO&#8230;<\/a><\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-20164","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozioni ai single: prevale l\u2019interesse del bambino - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozioni-ai-single-prevale-l\u2019interesse-del-bambino\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozioni ai single: prevale l\u2019interesse del bambino\" \/>\n<meta property=\"og:description\" content=\"Riportiamo oggi il commento di Adriano Sansa, presidente del Tribunale per i Minori di Genova, pubblicato sull\u2019ultimo numero di Famiglia Cristiana. \u201cL\u2019adozione \u00e8 nell\u2019interesse del bambino, che trova una sua famiglia. Si appagano cos\u00ec anche un\u2019aspirazione profonda e un impulso di affetti degli adottanti&quot;. LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozioni-ai-single-prevale-l\u2019interesse-del-bambino\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-02-25T15:30:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-02-25T15:32:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/Adozione-genitore-single.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-ai-single-prevale-l%e2%80%99interesse-del-bambino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-ai-single-prevale-l%e2%80%99interesse-del-bambino\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Adozioni ai single: prevale l\u2019interesse del bambino\",\"datePublished\":\"2011-02-25T15:30:04+00:00\",\"dateModified\":\"2011-02-25T15:32:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-ai-single-prevale-l%e2%80%99interesse-del-bambino\\\/\"},\"wordCount\":350,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-ai-single-prevale-l%e2%80%99interesse-del-bambino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Adozione-genitore-single.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-ai-single-prevale-l%e2%80%99interesse-del-bambino\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-ai-single-prevale-l%e2%80%99interesse-del-bambino\\\/\",\"name\":\"Adozioni ai single: prevale l\u2019interesse del bambino - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-ai-single-prevale-l%e2%80%99interesse-del-bambino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-ai-single-prevale-l%e2%80%99interesse-del-bambino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Adozione-genitore-single.jpg\",\"datePublished\":\"2011-02-25T15:30:04+00:00\",\"dateModified\":\"2011-02-25T15:32:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-ai-single-prevale-l%e2%80%99interesse-del-bambino\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-ai-single-prevale-l%e2%80%99interesse-del-bambino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-ai-single-prevale-l%e2%80%99interesse-del-bambino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Adozione-genitore-single.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Adozione-genitore-single.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-ai-single-prevale-l%e2%80%99interesse-del-bambino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozioni ai single: prevale l\u2019interesse del bambino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozioni ai single: prevale l\u2019interesse del bambino - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozioni-ai-single-prevale-l\u2019interesse-del-bambino\/","og_locale":"it_IT","og_type":"article","og_title":"Adozioni ai single: prevale l\u2019interesse del bambino","og_description":"Riportiamo oggi il commento di Adriano Sansa, presidente del Tribunale per i Minori di Genova, pubblicato sull\u2019ultimo numero di Famiglia Cristiana. \u201cL\u2019adozione \u00e8 nell\u2019interesse del bambino, che trova una sua famiglia. Si appagano cos\u00ec anche un\u2019aspirazione profonda e un impulso di affetti degli adottanti\". LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/adozioni-ai-single-prevale-l\u2019interesse-del-bambino\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2011-02-25T15:30:04+00:00","article_modified_time":"2011-02-25T15:32:44+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/Adozione-genitore-single.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozioni-ai-single-prevale-l%e2%80%99interesse-del-bambino\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-ai-single-prevale-l%e2%80%99interesse-del-bambino\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Adozioni ai single: prevale l\u2019interesse del bambino","datePublished":"2011-02-25T15:30:04+00:00","dateModified":"2011-02-25T15:32:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-ai-single-prevale-l%e2%80%99interesse-del-bambino\/"},"wordCount":350,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-ai-single-prevale-l%e2%80%99interesse-del-bambino\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Adozione-genitore-single.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozioni-ai-single-prevale-l%e2%80%99interesse-del-bambino\/","url":"https:\/\/www.aibi.it\/ita\/adozioni-ai-single-prevale-l%e2%80%99interesse-del-bambino\/","name":"Adozioni ai single: prevale l\u2019interesse del bambino - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-ai-single-prevale-l%e2%80%99interesse-del-bambino\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-ai-single-prevale-l%e2%80%99interesse-del-bambino\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Adozione-genitore-single.jpg","datePublished":"2011-02-25T15:30:04+00:00","dateModified":"2011-02-25T15:32:44+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-ai-single-prevale-l%e2%80%99interesse-del-bambino\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozioni-ai-single-prevale-l%e2%80%99interesse-del-bambino\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozioni-ai-single-prevale-l%e2%80%99interesse-del-bambino\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/Adozione-genitore-single.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/Adozione-genitore-single.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozioni-ai-single-prevale-l%e2%80%99interesse-del-bambino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Adozioni ai single: prevale l\u2019interesse del bambino"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 16:37:08","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/20164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=20164"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/20164\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=20164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=20164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=20164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}