﻿{"id":20175,"date":"2011-02-25T16:43:04","date_gmt":"2011-02-25T15:43:04","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=20175"},"modified":"2011-02-25T16:44:26","modified_gmt":"2011-02-25T15:44:26","slug":"adozioni-nazionali-francia-l%e2%80%99accademia-di-medicina-chiede-nuove-regole","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozioni-nazionali-francia-l%e2%80%99accademia-di-medicina-chiede-nuove-regole\/","title":{"rendered":"Adozioni nazionali, Francia: l\u2019Accademia di Medicina chiede nuove regole"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/child-joy.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-20176\" style=\"margin: 5px;\" title=\"child-joy\" src=\"https:\/\/www.aibi.it\/ita\/images\/child-joy.jpg\" alt=\"\" width=\"100\" height=\"100\" \/><\/a>L&#8217;Accademia di Medicina francese, in una relazione dai toni severi presentata marted\u00ec 22 febbraio, ha votato in seduta plenaria <strong>chiedendo una riforma delle adozioni nazionali in Francia.<\/strong><\/p>\n<p>L\u2019organizzazione ha denunciato le mancanze delle istituzioni francesi che lasciano bambini in difficolt\u00e0 o abbandonati dai genitori, senza essere adottabili.<\/p>\n<p><strong>Ad oggi sono circa 800 i minori che ogni anno vengono adottati tramite adozione nazionale, un rapporto di 1 a 5 con le adozioni internazionali.<\/strong><\/p>\n<p>La complessit\u00e0 delle procedure, la dispersione delle responsabilit\u00e0 e la lentezza nei procedimenti, secondo il professor Jean-Marie Mantovani, che ha presentato i risultati della relazione, provocano gravi conseguenze.<\/p>\n<p><strong>Anche quando \u00e8 nota la negligenza dei genitori o vengono segnalati degli abusi, i bambini non sono disponibili per l\u2019adozione.<\/strong> Molti, secondo il prof. Mantovani, passano da un affidamento a un altro senza poter stabilire una relazione emozionale stabile e costruirsi un futuro.<\/p>\n<p>Nella sua presentazione, il prof. Mantovani, in particolare, ha messo in evidenza due dati: <strong>mentre ogni anno sono segnalati abusi su circa 20.000 bambini, sono pochi i minori \u201ca rischio\u201d che poi vengono adottati.<\/strong><\/p>\n<p>Il relatore ha proposto anche di introdurre l\u2019obbligo, da parte dei medici, di segnalare eventuali abusi sui minori.<\/p>\n<p>Si suggerisce inoltre la creazione di una catena di famiglie ospitanti volontarie, scelte tra i candidati per l&#8217;adozione, in collaborazione con le famiglie ospitanti retribuite, al fine di semplificare i processi amministrativi e di assistenza giudiziaria per i bambini in pericolo.<\/p>\n<p><strong>Quanto alla negligenza dei genitori, l\u2019organizzazione dei medici ha proposto di introdurre delle valutazioni semestrali anzich\u00e9 annuali alle coppie, come \u00e8 previsto oggi dal Codice Civile.<\/strong><\/p>\n<p>La questione della negligenza dei genitori non \u00e8 nuova e non \u00e8 facile da valutare. Tre anni fa, Jean-Marie Colombani, ex direttore del quotidiano Le Monde, in un rapporto ha deplorato lo scarso utilizzo dello dell&#8217;articolo 350 del codice civile, che permette di avviare una <strong>&#8220;richiesta di dichiarazione giudiziaria di abbandono&#8221;<\/strong> quando i genitori si sono dimostrati essere <em>&#8220;manifestamente disinteressati&#8221;<\/em> al bambino nel corso dell&#8217;anno precedente.<\/p>\n<p>Alcune associazioni, tuttavia, richiedono cautela. Questo \u00e8 il caso di ATD Quarto Mondo, la quale ricorda come possa essere difficile valutare la negligenza dei genitori.<\/p>\n<p><em>&#8220;Seguiamo le famiglie in situazione di disagio tale che a volte \u00e8 difficile mantenere il contatto con il loro figlio adottivo&#8221;, ha detto Maryvonne Caillaux, una delle responsabili dell&#8217;associazione. So che alcune mamme che amano i loro figli, non si sa come, si sentono svalutate; alcune hanno disturbi psichiatrici, nei quali si dibattono. Pochi giorni fa, una di loro, ha detto che non voleva pi\u00f9 vedere i suoi ragazzi, perch\u00e9 i rapporti erano molto difficili, poi mi ha detto: &#8220;Non che io non voglio vederli, ma soffro troppo&#8221;,<\/em> ha detto la Caillaux, senza negare la necessit\u00e0, in casi estremi, di interrompere il rapporto.<\/p>\n<p>Secondo Genevieve Miral, presidente dell&#8217;Associazione dei Familiari e dei Bambini adottati, chi supporta una tale posizione<em>, &#8220;deve stare molto attento a come si muove in questa vicenda dolorosa e complessa&#8221;.<\/em> Per fare questo, raccomanda cambiamenti concreti <em>&#8220;in particolare, i servizi sociali hanno pochissimi strumenti per valutare la negligenza dei genitori&#8221;.<\/em><\/p>\n<p>(Fonte: La Croix, Le Figaro 22.02.2011).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Accademia di Medicina francese, in una relazione dai toni severi presentata marted\u00ec 22 febbraio, ha votato in seduta plenaria <strong>chiedendo una riforma delle adozioni nazionali in Francia.<\/strong>\u00a0<strong><a href=\"https:\/\/www.aibi.it\/ita\/adozioni-nazionali-francia-l\u2019accademia-di-medicina-chiede-nuove-regole\/\">LEGGI TUTTO&#8230;<\/a><\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-20175","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozioni nazionali, Francia: l\u2019Accademia di Medicina chiede nuove regole - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozioni-nazionali-francia-l\u2019accademia-di-medicina-chiede-nuove-regole\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozioni nazionali, Francia: l\u2019Accademia di Medicina chiede nuove regole\" \/>\n<meta property=\"og:description\" content=\"L&#039;Accademia di Medicina francese, in una relazione dai toni severi presentata marted\u00ec 22 febbraio, ha votato in seduta plenaria chiedendo una riforma delle adozioni nazionali in Francia.\u00a0LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozioni-nazionali-francia-l\u2019accademia-di-medicina-chiede-nuove-regole\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-02-25T15:43:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-02-25T15:44:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/child-joy.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-nazionali-francia-l%e2%80%99accademia-di-medicina-chiede-nuove-regole\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-nazionali-francia-l%e2%80%99accademia-di-medicina-chiede-nuove-regole\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Adozioni nazionali, Francia: l\u2019Accademia di Medicina chiede nuove regole\",\"datePublished\":\"2011-02-25T15:43:04+00:00\",\"dateModified\":\"2011-02-25T15:44:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-nazionali-francia-l%e2%80%99accademia-di-medicina-chiede-nuove-regole\\\/\"},\"wordCount\":519,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-nazionali-francia-l%e2%80%99accademia-di-medicina-chiede-nuove-regole\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/child-joy.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-nazionali-francia-l%e2%80%99accademia-di-medicina-chiede-nuove-regole\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-nazionali-francia-l%e2%80%99accademia-di-medicina-chiede-nuove-regole\\\/\",\"name\":\"Adozioni nazionali, Francia: l\u2019Accademia di Medicina chiede nuove regole - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-nazionali-francia-l%e2%80%99accademia-di-medicina-chiede-nuove-regole\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-nazionali-francia-l%e2%80%99accademia-di-medicina-chiede-nuove-regole\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/child-joy.jpg\",\"datePublished\":\"2011-02-25T15:43:04+00:00\",\"dateModified\":\"2011-02-25T15:44:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-nazionali-francia-l%e2%80%99accademia-di-medicina-chiede-nuove-regole\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-nazionali-francia-l%e2%80%99accademia-di-medicina-chiede-nuove-regole\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-nazionali-francia-l%e2%80%99accademia-di-medicina-chiede-nuove-regole\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/child-joy.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/child-joy.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-nazionali-francia-l%e2%80%99accademia-di-medicina-chiede-nuove-regole\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozioni nazionali, Francia: l\u2019Accademia di Medicina chiede nuove regole\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozioni nazionali, Francia: l\u2019Accademia di Medicina chiede nuove regole - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozioni-nazionali-francia-l\u2019accademia-di-medicina-chiede-nuove-regole\/","og_locale":"it_IT","og_type":"article","og_title":"Adozioni nazionali, Francia: l\u2019Accademia di Medicina chiede nuove regole","og_description":"L'Accademia di Medicina francese, in una relazione dai toni severi presentata marted\u00ec 22 febbraio, ha votato in seduta plenaria chiedendo una riforma delle adozioni nazionali in Francia.\u00a0LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/adozioni-nazionali-francia-l\u2019accademia-di-medicina-chiede-nuove-regole\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2011-02-25T15:43:04+00:00","article_modified_time":"2011-02-25T15:44:26+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/child-joy.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozioni-nazionali-francia-l%e2%80%99accademia-di-medicina-chiede-nuove-regole\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-nazionali-francia-l%e2%80%99accademia-di-medicina-chiede-nuove-regole\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Adozioni nazionali, Francia: l\u2019Accademia di Medicina chiede nuove regole","datePublished":"2011-02-25T15:43:04+00:00","dateModified":"2011-02-25T15:44:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-nazionali-francia-l%e2%80%99accademia-di-medicina-chiede-nuove-regole\/"},"wordCount":519,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-nazionali-francia-l%e2%80%99accademia-di-medicina-chiede-nuove-regole\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/child-joy.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozioni-nazionali-francia-l%e2%80%99accademia-di-medicina-chiede-nuove-regole\/","url":"https:\/\/www.aibi.it\/ita\/adozioni-nazionali-francia-l%e2%80%99accademia-di-medicina-chiede-nuove-regole\/","name":"Adozioni nazionali, Francia: l\u2019Accademia di Medicina chiede nuove regole - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-nazionali-francia-l%e2%80%99accademia-di-medicina-chiede-nuove-regole\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-nazionali-francia-l%e2%80%99accademia-di-medicina-chiede-nuove-regole\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/child-joy.jpg","datePublished":"2011-02-25T15:43:04+00:00","dateModified":"2011-02-25T15:44:26+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-nazionali-francia-l%e2%80%99accademia-di-medicina-chiede-nuove-regole\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozioni-nazionali-francia-l%e2%80%99accademia-di-medicina-chiede-nuove-regole\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozioni-nazionali-francia-l%e2%80%99accademia-di-medicina-chiede-nuove-regole\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/child-joy.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/child-joy.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozioni-nazionali-francia-l%e2%80%99accademia-di-medicina-chiede-nuove-regole\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Adozioni nazionali, Francia: l\u2019Accademia di Medicina chiede nuove regole"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 16:49:24","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/20175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=20175"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/20175\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=20175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=20175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=20175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}