﻿{"id":20289,"date":"2011-03-01T17:26:32","date_gmt":"2011-03-01T16:26:32","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=20289"},"modified":"2011-03-03T16:28:49","modified_gmt":"2011-03-03T15:28:49","slug":"ride-bene-chi-ride-ultimo-a-teatro-per-ai-bi","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/ride-bene-chi-ride-ultimo-a-teatro-per-ai-bi\/","title":{"rendered":"&#8220;Ride bene chi ride ultimo&#8221; a teatro per Ai.Bi."},"content":{"rendered":"<p><strong>A\u00a0Bergamo va in scena,\u00a0gioved\u00ec 3 marzo, al Teatro Colognola\u2013 \u00a0lo spettacolo \u201cRide bene chi ride ultimo<\/strong>\u201d organizzato da\u00a0Saxofone Tuttospettacolo\u00a0Srl.<\/p>\n<p><strong>Andare a teatro \u00e8 anche un modo per sostenere le attivit\u00e0 di Ai.Bi. a favore dell\u2019infanzia abbandonata <\/strong>e in difficolt\u00e0 in Italia e in 26 Paesi del mondo; parte del ricavato della serata sar\u00e0 destinato, infatti, ai progetti dell\u2019associazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A&nbsp;Bergamo va in scena,&nbsp;gioved&igrave; 3 marzo, al Teatro Colognola&ndash; &nbsp;lo spettacolo &ldquo;Ride bene chi ride ultimo&rdquo; organizzato da&nbsp;Saxofone Tuttospettacolo&nbsp;Srl. Andare a teatro &egrave; anche un modo per sostenere le attivit&agrave; di Ai.Bi. a favore dell&rsquo;infanzia abbandonata e in difficolt&agrave; in Italia e in 26 Paesi del mondo; parte del ricavato [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-20289","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>&quot;Ride bene chi ride ultimo&quot; a teatro per Ai.Bi. - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/ride-bene-chi-ride-ultimo-a-teatro-per-ai-bi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Ride bene chi ride ultimo&quot; a teatro per Ai.Bi.\" \/>\n<meta property=\"og:description\" content=\"A&nbsp;Bergamo va in scena,&nbsp;gioved&igrave; 3 marzo, al Teatro Colognola&ndash; &nbsp;lo spettacolo &ldquo;Ride bene chi ride ultimo&rdquo; organizzato da&nbsp;Saxofone Tuttospettacolo&nbsp;Srl. Andare a teatro &egrave; anche un modo per sostenere le attivit&agrave; di Ai.Bi. a favore dell&rsquo;infanzia abbandonata e in difficolt&agrave; in Italia e in 26 Paesi del mondo; parte del ricavato [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/ride-bene-chi-ride-ultimo-a-teatro-per-ai-bi\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-03-01T16:26:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-03-03T15:28:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ride-bene-chi-ride-ultimo-a-teatro-per-ai-bi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ride-bene-chi-ride-ultimo-a-teatro-per-ai-bi\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"&#8220;Ride bene chi ride ultimo&#8221; a teatro per Ai.Bi.\",\"datePublished\":\"2011-03-01T16:26:32+00:00\",\"dateModified\":\"2011-03-03T15:28:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ride-bene-chi-ride-ultimo-a-teatro-per-ai-bi\\\/\"},\"wordCount\":72,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ride-bene-chi-ride-ultimo-a-teatro-per-ai-bi\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ride-bene-chi-ride-ultimo-a-teatro-per-ai-bi\\\/\",\"name\":\"\\\"Ride bene chi ride ultimo\\\" a teatro per Ai.Bi. - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"datePublished\":\"2011-03-01T16:26:32+00:00\",\"dateModified\":\"2011-03-03T15:28:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ride-bene-chi-ride-ultimo-a-teatro-per-ai-bi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ride-bene-chi-ride-ultimo-a-teatro-per-ai-bi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ride-bene-chi-ride-ultimo-a-teatro-per-ai-bi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"&#8220;Ride bene chi ride ultimo&#8221; a teatro per Ai.Bi.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\"Ride bene chi ride ultimo\" a teatro per Ai.Bi. - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/ride-bene-chi-ride-ultimo-a-teatro-per-ai-bi\/","og_locale":"it_IT","og_type":"article","og_title":"\"Ride bene chi ride ultimo\" a teatro per Ai.Bi.","og_description":"A&nbsp;Bergamo va in scena,&nbsp;gioved&igrave; 3 marzo, al Teatro Colognola&ndash; &nbsp;lo spettacolo &ldquo;Ride bene chi ride ultimo&rdquo; organizzato da&nbsp;Saxofone Tuttospettacolo&nbsp;Srl. Andare a teatro &egrave; anche un modo per sostenere le attivit&agrave; di Ai.Bi. a favore dell&rsquo;infanzia abbandonata e in difficolt&agrave; in Italia e in 26 Paesi del mondo; parte del ricavato [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/ride-bene-chi-ride-ultimo-a-teatro-per-ai-bi\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2011-03-01T16:26:32+00:00","article_modified_time":"2011-03-03T15:28:49+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg","type":"image\/jpeg"}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi."},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/ride-bene-chi-ride-ultimo-a-teatro-per-ai-bi\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/ride-bene-chi-ride-ultimo-a-teatro-per-ai-bi\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"&#8220;Ride bene chi ride ultimo&#8221; a teatro per Ai.Bi.","datePublished":"2011-03-01T16:26:32+00:00","dateModified":"2011-03-03T15:28:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/ride-bene-chi-ride-ultimo-a-teatro-per-ai-bi\/"},"wordCount":72,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/ride-bene-chi-ride-ultimo-a-teatro-per-ai-bi\/","url":"https:\/\/www.aibi.it\/ita\/ride-bene-chi-ride-ultimo-a-teatro-per-ai-bi\/","name":"\"Ride bene chi ride ultimo\" a teatro per Ai.Bi. - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"datePublished":"2011-03-01T16:26:32+00:00","dateModified":"2011-03-03T15:28:49+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/ride-bene-chi-ride-ultimo-a-teatro-per-ai-bi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/ride-bene-chi-ride-ultimo-a-teatro-per-ai-bi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/ride-bene-chi-ride-ultimo-a-teatro-per-ai-bi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"&#8220;Ride bene chi ride ultimo&#8221; a teatro per Ai.Bi."}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 16:38:01","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/20289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=20289"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/20289\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=20289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=20289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=20289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}