﻿


{"id":203490,"date":"2022-08-01T18:44:22","date_gmt":"2022-08-01T16:44:22","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=203490"},"modified":"2022-08-01T18:44:35","modified_gmt":"2022-08-01T16:44:35","slug":"adozione-internazionale-come-posso-incontrare-i-miei-nuovi-genitori-il-corso-di-faris-per-preparare-le-coppie-allottenimento-dellidoneita","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-come-posso-incontrare-i-miei-nuovi-genitori-il-corso-di-faris-per-preparare-le-coppie-allottenimento-dellidoneita\/","title":{"rendered":"Adozione Internazionale: \u201cCome posso incontrare i miei nuovi genitori?\u201d Il corso di FARIS per preparare le coppie all\u2019ottenimento dell&#8217;idoneit\u00e0"},"content":{"rendered":"<h2 style=\"font-weight: 400;\"><strong>Il corso permetter\u00e0 alle coppie di approfondire i motivi per cui, quelli che saranno i loro figli, sono stati abbandonati una prima volta, dove vivono, quanti anni hanno, quali sono le loro patologie e come avviene un abbinamento.\u00a0Il webinar sara\u0300 attivato al raggiungimento di almeno 5 coppie partecipanti<\/strong><\/h2>\n<p style=\"font-weight: 400;\"><em>\u201cIn quali Paesi si pu\u00f2 realizzare l\u2019Adozione Internazionale\u00a0<\/em><em>oggi<\/em><em>? Quando sar\u00e0 possibile conoscere il Paese per il quale partire? E quando potremo conoscere l\u2019et\u00e0 e il genere del minore, invece?\u201d<\/em><\/p>\n<p style=\"font-weight: 400;\">Pu\u00f2 risultare difficile immaginare come il proprio desiderio di genitorialit\u00e0 adottiva possa prendere forma a seguito, o appena prima della preparazione delle iniziali pratiche all\u2019Adozione Internazionale.<\/p>\n<p style=\"font-weight: 400;\">Queste legittime domande sono spesso poste ad Ai.Bi. da chi sta per presentare, o lo ha gi\u00e0 fatto, la\u00a0<strong>domanda di idoneit\u00e0<\/strong>\u00a0all\u2019Adozione di un minore straniero presso il proprio Tribunale per i Minorenni di riferimento.<\/p>\n<p style=\"font-weight: 400;\">Ai.Bi., in collaborazione con FARIS \u2013 Family Relationship International School, la scuola di formazione della Fondazione Ai.Bi. dedicata all\u2019accoglienza e alla famiglia, ha deciso di rispondere a questi dubbi promovendo il corso di formazione online\u00a0<strong>\u201cCome posso incontrare i miei nuovi genitori? \u2013 Invito di un bambino abbandonato alle famiglie che desiderano adottarlo\u201d.<\/strong><\/p>\n<h3 style=\"font-weight: 400;\"><strong>\u00a0<\/strong><strong>Di cosa si tratta?<\/strong><\/h3>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong>Il webinar \u00e8 progettato specificatamente per permettere agli aspiranti genitori adottivi, in attesa di idoneit\u00e0, di\u00a0<strong>prepararsi nel migliore dei modi all\u2019incontro con i propri figli.<\/strong><\/p>\n<p style=\"font-weight: 400;\">Il corso permetter\u00e0 alle coppie di approfondire i motivi per cui, quelli che saranno i loro figli, sono stati abbandonati una prima volta, dove vivono, quanti anni hanno, quali sono le loro patologie e come avviene un abbinamento.<\/p>\n<p style=\"font-weight: 400;\">I nostri operatori, inoltre, ascolteranno le storie e il sogno che gli aspiranti genitori hanno sul \u201cloro\u201d bambino, accompagnandoli verso l\u2019incontro con lui attraverso la realt\u00e0 dell\u2019Adozione Internazionale.<\/p>\n<p style=\"font-weight: 400;\"><strong>Il corso si articola in 5 moduli<\/strong>, che saranno affrontati in modalit\u00e0\u00a0<strong>webinar,<\/strong>\u00a0avr\u00e0 una durata di complessiva di 23 ore.<\/p>\n<h3 style=\"font-weight: 400;\"><strong>Il corso sara\u0300 attivato al raggiungimento di almeno 5 coppie partecipanti.<\/strong><\/h3>\n<p style=\"font-weight: 400;\">Per maggiori informazioni \u00e8 possibile visitare la pagina dedicata\u00a0<a href=\"https:\/\/www.fondazioneaibi.it\/faris\/prodotto\/webinar-corso-pre-idoneita-adozione-internazionale\/\">QUI\u00a0<\/a><\/p>\n<p style=\"font-weight: 400;\">Per dubbi o necessit\u00e0 \u00e8 possibile scrivere a:\u00a0faris@fondazioneaibi.it<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\">\n","protected":false},"excerpt":{"rendered":"<p>Il corso permetter&agrave; alle coppie di approfondire i motivi per cui, quelli che saranno i loro figli, sono stati abbandonati una prima volta, dove vivono, quanti anni hanno, quali sono le loro patologie e come avviene un abbinamento.&nbsp;Il webinar sara&#768; attivato al raggiungimento di almeno 5 coppie partecipanti &ldquo;In quali [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":203491,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[777],"tags":[279,776,718],"class_list":["post-203490","post","type-post","status-publish","format-standard","has-post-thumbnail","category-faris","tag-adozione","tag-faris","tag-webinar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione Internazionale: \u201cCome posso incontrare i miei nuovi genitori?\u201d Il corso di FARIS per preparare le coppie all\u2019ottenimento dell&#039;idoneit\u00e0 - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Adozione. Il corso permetter\u00e0 alle coppie di approfondire i motivi per cui, quelli che saranno i loro figli, sono stati abbandonati una prima volta, dove vivono, quanti anni hanno, quali sono le loro patologie e come avviene un abbinamento.\u00a0Il webinar sara\u0300 attivato al raggiungimento di almeno 5 coppie partecipanti\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-come-posso-incontrare-i-miei-nuovi-genitori-il-corso-di-faris-per-preparare-le-coppie-allottenimento-dellidoneita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione Internazionale: \u201cCome posso incontrare i miei nuovi genitori?\u201d Il corso di FARIS per preparare le coppie all\u2019ottenimento dell&#039;idoneit\u00e0\" \/>\n<meta property=\"og:description\" content=\"Adozione. Il corso permetter\u00e0 alle coppie di approfondire i motivi per cui, quelli che saranno i loro figli, sono stati abbandonati una prima volta, dove vivono, quanti anni hanno, quali sono le loro patologie e come avviene un abbinamento.\u00a0Il webinar sara\u0300 attivato al raggiungimento di almeno 5 coppie partecipanti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-come-posso-incontrare-i-miei-nuovi-genitori-il-corso-di-faris-per-preparare-le-coppie-allottenimento-dellidoneita\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-01T16:44:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-01T16:44:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2022\/08\/adozione.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-come-posso-incontrare-i-miei-nuovi-genitori-il-corso-di-faris-per-preparare-le-coppie-allottenimento-dellidoneita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-come-posso-incontrare-i-miei-nuovi-genitori-il-corso-di-faris-per-preparare-le-coppie-allottenimento-dellidoneita\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"Adozione Internazionale: \u201cCome posso incontrare i miei nuovi genitori?\u201d Il corso di FARIS per preparare le coppie all\u2019ottenimento dell&#8217;idoneit\u00e0\",\"datePublished\":\"2022-08-01T16:44:22+00:00\",\"dateModified\":\"2022-08-01T16:44:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-come-posso-incontrare-i-miei-nuovi-genitori-il-corso-di-faris-per-preparare-le-coppie-allottenimento-dellidoneita\\\/\"},\"wordCount\":367,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-come-posso-incontrare-i-miei-nuovi-genitori-il-corso-di-faris-per-preparare-le-coppie-allottenimento-dellidoneita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/08\\\/adozione.jpg\",\"keywords\":[\"adozione\",\"FARIS\",\"Webinar\"],\"articleSection\":[\"Faris\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-come-posso-incontrare-i-miei-nuovi-genitori-il-corso-di-faris-per-preparare-le-coppie-allottenimento-dellidoneita\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-come-posso-incontrare-i-miei-nuovi-genitori-il-corso-di-faris-per-preparare-le-coppie-allottenimento-dellidoneita\\\/\",\"name\":\"Adozione Internazionale: \u201cCome posso incontrare i miei nuovi genitori?\u201d Il corso di FARIS per preparare le coppie all\u2019ottenimento dell'idoneit\u00e0 - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-come-posso-incontrare-i-miei-nuovi-genitori-il-corso-di-faris-per-preparare-le-coppie-allottenimento-dellidoneita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-come-posso-incontrare-i-miei-nuovi-genitori-il-corso-di-faris-per-preparare-le-coppie-allottenimento-dellidoneita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/08\\\/adozione.jpg\",\"datePublished\":\"2022-08-01T16:44:22+00:00\",\"dateModified\":\"2022-08-01T16:44:35+00:00\",\"description\":\"Adozione. Il corso permetter\u00e0 alle coppie di approfondire i motivi per cui, quelli che saranno i loro figli, sono stati abbandonati una prima volta, dove vivono, quanti anni hanno, quali sono le loro patologie e come avviene un abbinamento.\u00a0Il webinar sara\u0300 attivato al raggiungimento di almeno 5 coppie partecipanti\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-come-posso-incontrare-i-miei-nuovi-genitori-il-corso-di-faris-per-preparare-le-coppie-allottenimento-dellidoneita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-come-posso-incontrare-i-miei-nuovi-genitori-il-corso-di-faris-per-preparare-le-coppie-allottenimento-dellidoneita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-come-posso-incontrare-i-miei-nuovi-genitori-il-corso-di-faris-per-preparare-le-coppie-allottenimento-dellidoneita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/08\\\/adozione.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/08\\\/adozione.jpg\",\"width\":1200,\"height\":650},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-come-posso-incontrare-i-miei-nuovi-genitori-il-corso-di-faris-per-preparare-le-coppie-allottenimento-dellidoneita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Faris\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/faris\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione Internazionale: \u201cCome posso incontrare i miei nuovi genitori?\u201d Il corso di FARIS per preparare le coppie all\u2019ottenimento dell&#8217;idoneit\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione Internazionale: \u201cCome posso incontrare i miei nuovi genitori?\u201d Il corso di FARIS per preparare le coppie all\u2019ottenimento dell'idoneit\u00e0 - Ai.Bi. Amici dei Bambini","description":"Adozione. Il corso permetter\u00e0 alle coppie di approfondire i motivi per cui, quelli che saranno i loro figli, sono stati abbandonati una prima volta, dove vivono, quanti anni hanno, quali sono le loro patologie e come avviene un abbinamento.\u00a0Il webinar sara\u0300 attivato al raggiungimento di almeno 5 coppie partecipanti","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-come-posso-incontrare-i-miei-nuovi-genitori-il-corso-di-faris-per-preparare-le-coppie-allottenimento-dellidoneita\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione Internazionale: \u201cCome posso incontrare i miei nuovi genitori?\u201d Il corso di FARIS per preparare le coppie all\u2019ottenimento dell'idoneit\u00e0","og_description":"Adozione. Il corso permetter\u00e0 alle coppie di approfondire i motivi per cui, quelli che saranno i loro figli, sono stati abbandonati una prima volta, dove vivono, quanti anni hanno, quali sono le loro patologie e come avviene un abbinamento.\u00a0Il webinar sara\u0300 attivato al raggiungimento di almeno 5 coppie partecipanti","og_url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-come-posso-incontrare-i-miei-nuovi-genitori-il-corso-di-faris-per-preparare-le-coppie-allottenimento-dellidoneita\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2022-08-01T16:44:22+00:00","article_modified_time":"2022-08-01T16:44:35+00:00","og_image":[{"width":1200,"height":650,"url":"https:\/\/www.aibi.it\/ita\/images\/2022\/08\/adozione.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-come-posso-incontrare-i-miei-nuovi-genitori-il-corso-di-faris-per-preparare-le-coppie-allottenimento-dellidoneita\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-come-posso-incontrare-i-miei-nuovi-genitori-il-corso-di-faris-per-preparare-le-coppie-allottenimento-dellidoneita\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"Adozione Internazionale: \u201cCome posso incontrare i miei nuovi genitori?\u201d Il corso di FARIS per preparare le coppie all\u2019ottenimento dell&#8217;idoneit\u00e0","datePublished":"2022-08-01T16:44:22+00:00","dateModified":"2022-08-01T16:44:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-come-posso-incontrare-i-miei-nuovi-genitori-il-corso-di-faris-per-preparare-le-coppie-allottenimento-dellidoneita\/"},"wordCount":367,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-come-posso-incontrare-i-miei-nuovi-genitori-il-corso-di-faris-per-preparare-le-coppie-allottenimento-dellidoneita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/08\/adozione.jpg","keywords":["adozione","FARIS","Webinar"],"articleSection":["Faris"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-come-posso-incontrare-i-miei-nuovi-genitori-il-corso-di-faris-per-preparare-le-coppie-allottenimento-dellidoneita\/","url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-come-posso-incontrare-i-miei-nuovi-genitori-il-corso-di-faris-per-preparare-le-coppie-allottenimento-dellidoneita\/","name":"Adozione Internazionale: \u201cCome posso incontrare i miei nuovi genitori?\u201d Il corso di FARIS per preparare le coppie all\u2019ottenimento dell'idoneit\u00e0 - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-come-posso-incontrare-i-miei-nuovi-genitori-il-corso-di-faris-per-preparare-le-coppie-allottenimento-dellidoneita\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-come-posso-incontrare-i-miei-nuovi-genitori-il-corso-di-faris-per-preparare-le-coppie-allottenimento-dellidoneita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/08\/adozione.jpg","datePublished":"2022-08-01T16:44:22+00:00","dateModified":"2022-08-01T16:44:35+00:00","description":"Adozione. Il corso permetter\u00e0 alle coppie di approfondire i motivi per cui, quelli che saranno i loro figli, sono stati abbandonati una prima volta, dove vivono, quanti anni hanno, quali sono le loro patologie e come avviene un abbinamento.\u00a0Il webinar sara\u0300 attivato al raggiungimento di almeno 5 coppie partecipanti","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-come-posso-incontrare-i-miei-nuovi-genitori-il-corso-di-faris-per-preparare-le-coppie-allottenimento-dellidoneita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-internazionale-come-posso-incontrare-i-miei-nuovi-genitori-il-corso-di-faris-per-preparare-le-coppie-allottenimento-dellidoneita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-come-posso-incontrare-i-miei-nuovi-genitori-il-corso-di-faris-per-preparare-le-coppie-allottenimento-dellidoneita\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2022\/08\/adozione.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/08\/adozione.jpg","width":1200,"height":650},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-come-posso-incontrare-i-miei-nuovi-genitori-il-corso-di-faris-per-preparare-le-coppie-allottenimento-dellidoneita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Faris","item":"https:\/\/www.aibi.it\/ita\/category\/faris\/"},{"@type":"ListItem","position":3,"name":"Adozione Internazionale: \u201cCome posso incontrare i miei nuovi genitori?\u201d Il corso di FARIS per preparare le coppie all\u2019ottenimento dell&#8217;idoneit\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:57:33","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/203490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=203490"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/203490\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/203491"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=203490"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=203490"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=203490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}