﻿


{"id":203943,"date":"2022-08-22T07:30:39","date_gmt":"2022-08-22T05:30:39","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=203943"},"modified":"2023-10-25T14:51:53","modified_gmt":"2023-10-25T12:51:53","slug":"moldova-la-decisione-piu-difficile-della-nostra-vita-fuggire-da-mykolayiv","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/moldova-la-decisione-piu-difficile-della-nostra-vita-fuggire-da-mykolayiv\/","title":{"rendered":"Moldova. &#8220;La decisione pi\u00f9 difficile della nostra vita: fuggire da Mykolayiv&#8221;"},"content":{"rendered":"<h2>Mamma, pap\u00e0 e tre bambini di 2, 4 e 12 anni. Sono scappati dall\u2019Ucraina per la guerra, ma hanno trovato accoglienza e la possibilit\u00e0 di un nuova vita in Moldova. Anche con l\u2019aiuto del progetto #BAMBINIxLAPACE<\/h2>\n<p>Lena e Andrei sono arrivati da poco a Hirtop, nel distretto di Taraclia, in Moldova, insieme ai loro tre bambini di 2, 4 e 12 anni. La famiglia \u00e8 ucraina, ma ha radici moldave ed \u00e8 stata costretta a tornare nel Paese e nella casa dei genitori paterni a causa dello scoppio della guerra. <strong>Lasciare Mykolayiv<\/strong>, la citt\u00e0 in cui vivevano e avevano costruito casa, \u00e8 stata la decisione pi\u00f9 difficile che hanno preso, ma lo hanno fatto per i figli.<br \/>\nNonostante siano ancora giovani, nessuno dei due coniugi ha pi\u00f9 i genitori in vita: ora, il loro unico tesoro sono i tre figli e la casa di Hirtop che, per\u00f2, \u00e8 praticamente priva di ogni comodit\u00e0: \u201cAlmeno si vive in pace e circondati dai migliori vicini\u201d \u2013 confessa Lena, ricordando il modo in cui sono stati ricevuti dagli abitanti del villaggio.<br \/>\n\u201cSiamo arrivati a marzo. Faceva un freddo tremendo, eravamo spaventati, confusi, affamati e molto stanchi. Qui ci aspettava una casa disabitata da anni, in cui mancava tutto ed era utilizzata solo come deposito di vecchie cose della sorella di Andrei, che ora vive in Germania\u201d.<\/p>\n<h3>L\u2019accoglienza in Moldova<\/h3>\n<p>Ma i vicini non hanno dimenticato Andrei e, appena hanno saputo del suo ritorno nel villaggio, si sono organizzati a turno per portare alla nuova famiglia alimenti, vestiti, e offrendosi anche di accudire i piccoli per dare ai genitori la possibilit\u00e0 di riposare. <strong>Lo fanno tuttora<\/strong>, a quattro mesi da quando la famiglia si \u00e8 stabilita nel villaggio.<br \/>\nSempre con l\u2019aiuto dei vicini, che lo raccomandano per i vari lavori stagionali nella comunit\u00e0, Andrei riesce a guadagnare qualcosa per poter mantenere la famiglia: d\u2019estate le possibilit\u00e0 di lavoro sono tante, sia nel campo delle costruzioni, sia nei campi agricoli.<br \/>\nIntanto, i bambini pi\u00f9 grandi frequentano le attivit\u00e0 ricreative organizzate nella biblioteca pubblica, grazie al <strong><a href=\"https:\/\/www.aibi.it\/ita\/bambinixlapace\/\">progetto #BAMBINIxLAPACE<\/a> promosso da Ai.Bi.<\/strong> Qui si trovano molto bene, possono giocare e imparare cose nuove, insieme ai loro nuovi amici moldavi e ucraini (sempre arrivati da Mykolayiv).<br \/>\nLa sera per\u00f2, quando tutta la famiglia si riunisce, la domanda che i bambini fanno \u00e8 sempre quella: \u201cQuando torneremo nella nostra vera casa, quella in Ucraina?\u201d.<em><br \/>\n<\/em>\u201cSappiamo che nella nostra citt\u00e0 la situazione \u00e8 critica \u2013 spiega Lena. Nonostante all\u2019inizio pensavamo di rimanere in Moldova solo per qualche mese, per ora non possiamo fare dei piani per tornare. <strong>Siamo forti davanti ai bambini<\/strong>, che dobbiamo incoraggiare per il loro benessere psichico e fisico, ma quando sono tutti a letto\u2026 allora scoppia anche \u2018la nostra guerra\u2019. E le lacrime. Ancora non possiamo fare pace con quello che abbiamo perso e forse non potremo mai riavere. Per lo meno in Ucraina.\u201d<\/p>\n<h3>D\u2019estate slitta e d\u2019inverno carro<\/h3>\n<p>Ma il tempo passa velocemente e, come ci insegna un vecchio provverbio rumeno: <em>D\u2019estate slitta e d\u2019inverno carro<\/em> (che ha un corrispettivo italiano che recita: i<em>l prudente compra d\u2019estate il suo cappotto per l\u2019inverno<\/em>), anche Lena e Andrei stanno pensando ai tempi che verranno, coscienti che <strong>per qualche tempo ancora si fermeranno in Moldova<\/strong>. Perci\u00f2 hanno iniziato a preparare la casa per la stagione fredda e, con il denaro che Andrei guadagna, sono riusciti a procurare un po\u2019 di legna per poter riscaldare la casa d\u2019inverno.<br \/>\nAnche i bambini stanno seguendo un <strong>percorso d\u2019integrazione<\/strong> nelle strutture moldave di educazione, prevedendo gi\u00e0 l\u2019apprendimento della lingua rumena, visto che l\u2019unica scuola con insegnamento in russo si trova in un villaggio difficile da raggiungere, soprattutto d\u2019inverno.<br \/>\n\u201cCi dispiace molto per il modo in cui siamo stati costretti a conoscere la Moldova, che tra l\u2019altro \u00e8 bellissima, anche per la cultura (che assomiglia molto a quella ucraina) e per l\u2019umanit\u00e0 delle persone, che non smette mai di meravigliarci. Ma siamo anche contenti di aver trovato qui una seconda casa, dove rimanere insieme, poter dare la buona notte ai bambini e vederli addormentarsi sereni e tranquilli.<\/p>\n<h3>Sostieni anche tu la campagna di Ai.Bi. BAMBINIxLAPACE<\/h3>\n<p>Ai.Bi. \u2013 Amici dei bambini ha messo in campo una\u00a0campagna dedicata alla crisi ucraina:<a href=\"https:\/\/www.aibi.it\/ita\/bambinixlapace\/?utm_source=site-ita&amp;utm_medium=button&amp;utm_campaign=bambinixlapace&amp;utm_id=bambinixlapace-menu-new\">\u00a0BAMBINIxLAPACE<\/a>, alla quale chiunque pu\u00f2 partecipare scegliendo una delle varie modalit\u00e0 di aiuto e vicinanza alle famiglie e i bambini ucraini.<br \/>\nOggi\u00a0aiutare un bambino ucraino in fuga dalla guerra,\u00a0significa tenere viva la sua speranza che la guerra non \u00e8 l\u2019ultima parola della sua vita e che anche per lui ci sar\u00e0 un futuro sereno nella sua terra.<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*197331-start*\/\n#btnsx-197331{margin-top:0px;margin-bottom:25px;margin-left:0px;margin-right:0px;padding-top:16px;padding-bottom:15px;padding-left:43px;padding-right:44px;}\n#btnsx-197331 .btnsx-text-primary{text-transform:uppercase;font-size:20px;line-height:20px;font-weight:800;font-family:Raleway;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-197331:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-197331{background-color:#dd3333!important;}\n#btnsx-197331:hover{background-color:#d13030!important;}\n#btnsx-197331{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px;}\n#btnsx-197331:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:solid;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px;}\n#btnsx-197331{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-197331:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*197331-end*\/\n<\/style>\n<a href=\"https:\/\/dona.aibi.it\/emergenza-ucraina\/?act=cplt&amp;origine=web-button-in-post\" id=\"btnsx-197331\" class=\"btnsx-btn btnsx-btn-block\"  data-font-primary=\"Raleway\">\n\t<span class=\"btnsx-text-primary \">EMERGENZA UCRAINA<\/span><\/a>\n\n<!-- Buttons X - End -->\n\n","protected":false},"excerpt":{"rendered":"<p>Mamma, pap&agrave; e tre bambini di 2, 4 e 12 anni. Sono scappati dall&rsquo;Ucraina per la guerra, ma hanno trovato accoglienza e la possibilit&agrave; di un nuova vita in Moldova. Anche con l&rsquo;aiuto del progetto #BAMBINIxLAPACE Lena e Andrei sono arrivati da poco a Hirtop, nel distretto di Taraclia, in [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":203945,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[909],"tags":[895,530],"class_list":["post-203943","post","type-post","status-publish","format-standard","has-post-thumbnail","category-bambinixlapace","tag-bambinixlapace","tag-moldova"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Casa dolce Casa. Il villaggio di Hirtop si arricchisce di una famiglia<\/title>\n<meta name=\"description\" content=\"Mamma, pap\u00e0 e 3 bambini scappati dall\u2019Ucraina hanno trovato accoglienza in Moldova, a Hirtop. Per ricominciare, anche con l\u2019aiuto del progetto #BAMBINIxLAPACE\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/moldova-la-decisione-piu-difficile-della-nostra-vita-fuggire-da-mykolayiv\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Moldova. &quot;La decisione pi\u00f9 difficile della nostra vita: fuggire da Mykolayiv&quot;\" \/>\n<meta property=\"og:description\" content=\"Mamma, pap\u00e0 e 3 bambini scappati dall\u2019Ucraina hanno trovato accoglienza in Moldova, a Hirtop. Per ricominciare, anche con l\u2019aiuto del progetto #BAMBINIxLAPACE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/moldova-la-decisione-piu-difficile-della-nostra-vita-fuggire-da-mykolayiv\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-22T05:30:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-25T12:51:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2022\/08\/hirtop-casa-dolce-casa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"629\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-la-decisione-piu-difficile-della-nostra-vita-fuggire-da-mykolayiv\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-la-decisione-piu-difficile-della-nostra-vita-fuggire-da-mykolayiv\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Moldova. &#8220;La decisione pi\u00f9 difficile della nostra vita: fuggire da Mykolayiv&#8221;\",\"datePublished\":\"2022-08-22T05:30:39+00:00\",\"dateModified\":\"2023-10-25T12:51:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-la-decisione-piu-difficile-della-nostra-vita-fuggire-da-mykolayiv\\\/\"},\"wordCount\":774,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-la-decisione-piu-difficile-della-nostra-vita-fuggire-da-mykolayiv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/08\\\/hirtop-casa-dolce-casa.jpg\",\"keywords\":[\"BAMBINIxLAPACE\",\"Moldova\"],\"articleSection\":[\"BAMBINIXLAPACE\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-la-decisione-piu-difficile-della-nostra-vita-fuggire-da-mykolayiv\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-la-decisione-piu-difficile-della-nostra-vita-fuggire-da-mykolayiv\\\/\",\"name\":\"Casa dolce Casa. Il villaggio di Hirtop si arricchisce di una famiglia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-la-decisione-piu-difficile-della-nostra-vita-fuggire-da-mykolayiv\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-la-decisione-piu-difficile-della-nostra-vita-fuggire-da-mykolayiv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/08\\\/hirtop-casa-dolce-casa.jpg\",\"datePublished\":\"2022-08-22T05:30:39+00:00\",\"dateModified\":\"2023-10-25T12:51:53+00:00\",\"description\":\"Mamma, pap\u00e0 e 3 bambini scappati dall\u2019Ucraina hanno trovato accoglienza in Moldova, a Hirtop. Per ricominciare, anche con l\u2019aiuto del progetto #BAMBINIxLAPACE\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-la-decisione-piu-difficile-della-nostra-vita-fuggire-da-mykolayiv\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-la-decisione-piu-difficile-della-nostra-vita-fuggire-da-mykolayiv\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-la-decisione-piu-difficile-della-nostra-vita-fuggire-da-mykolayiv\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/08\\\/hirtop-casa-dolce-casa.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/08\\\/hirtop-casa-dolce-casa.jpg\",\"width\":1200,\"height\":629},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-la-decisione-piu-difficile-della-nostra-vita-fuggire-da-mykolayiv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BAMBINIXLAPACE\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/bambinixlapace\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Moldova. &#8220;La decisione pi\u00f9 difficile della nostra vita: fuggire da Mykolayiv&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Casa dolce Casa. Il villaggio di Hirtop si arricchisce di una famiglia","description":"Mamma, pap\u00e0 e 3 bambini scappati dall\u2019Ucraina hanno trovato accoglienza in Moldova, a Hirtop. Per ricominciare, anche con l\u2019aiuto del progetto #BAMBINIxLAPACE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/moldova-la-decisione-piu-difficile-della-nostra-vita-fuggire-da-mykolayiv\/","og_locale":"it_IT","og_type":"article","og_title":"Moldova. \"La decisione pi\u00f9 difficile della nostra vita: fuggire da Mykolayiv\"","og_description":"Mamma, pap\u00e0 e 3 bambini scappati dall\u2019Ucraina hanno trovato accoglienza in Moldova, a Hirtop. Per ricominciare, anche con l\u2019aiuto del progetto #BAMBINIxLAPACE","og_url":"https:\/\/www.aibi.it\/ita\/moldova-la-decisione-piu-difficile-della-nostra-vita-fuggire-da-mykolayiv\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2022-08-22T05:30:39+00:00","article_modified_time":"2023-10-25T12:51:53+00:00","og_image":[{"width":1200,"height":629,"url":"https:\/\/www.aibi.it\/ita\/images\/2022\/08\/hirtop-casa-dolce-casa.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/moldova-la-decisione-piu-difficile-della-nostra-vita-fuggire-da-mykolayiv\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/moldova-la-decisione-piu-difficile-della-nostra-vita-fuggire-da-mykolayiv\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Moldova. &#8220;La decisione pi\u00f9 difficile della nostra vita: fuggire da Mykolayiv&#8221;","datePublished":"2022-08-22T05:30:39+00:00","dateModified":"2023-10-25T12:51:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/moldova-la-decisione-piu-difficile-della-nostra-vita-fuggire-da-mykolayiv\/"},"wordCount":774,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/moldova-la-decisione-piu-difficile-della-nostra-vita-fuggire-da-mykolayiv\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/08\/hirtop-casa-dolce-casa.jpg","keywords":["BAMBINIxLAPACE","Moldova"],"articleSection":["BAMBINIXLAPACE"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/moldova-la-decisione-piu-difficile-della-nostra-vita-fuggire-da-mykolayiv\/","url":"https:\/\/www.aibi.it\/ita\/moldova-la-decisione-piu-difficile-della-nostra-vita-fuggire-da-mykolayiv\/","name":"Casa dolce Casa. Il villaggio di Hirtop si arricchisce di una famiglia","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/moldova-la-decisione-piu-difficile-della-nostra-vita-fuggire-da-mykolayiv\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/moldova-la-decisione-piu-difficile-della-nostra-vita-fuggire-da-mykolayiv\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/08\/hirtop-casa-dolce-casa.jpg","datePublished":"2022-08-22T05:30:39+00:00","dateModified":"2023-10-25T12:51:53+00:00","description":"Mamma, pap\u00e0 e 3 bambini scappati dall\u2019Ucraina hanno trovato accoglienza in Moldova, a Hirtop. Per ricominciare, anche con l\u2019aiuto del progetto #BAMBINIxLAPACE","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/moldova-la-decisione-piu-difficile-della-nostra-vita-fuggire-da-mykolayiv\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/moldova-la-decisione-piu-difficile-della-nostra-vita-fuggire-da-mykolayiv\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/moldova-la-decisione-piu-difficile-della-nostra-vita-fuggire-da-mykolayiv\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2022\/08\/hirtop-casa-dolce-casa.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/08\/hirtop-casa-dolce-casa.jpg","width":1200,"height":629},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/moldova-la-decisione-piu-difficile-della-nostra-vita-fuggire-da-mykolayiv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"BAMBINIXLAPACE","item":"https:\/\/www.aibi.it\/ita\/category\/bambinixlapace\/"},{"@type":"ListItem","position":3,"name":"Moldova. &#8220;La decisione pi\u00f9 difficile della nostra vita: fuggire da Mykolayiv&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:58:09","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/203943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=203943"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/203943\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/203945"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=203943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=203943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=203943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}