﻿


{"id":204233,"date":"2022-08-31T07:13:42","date_gmt":"2022-08-31T05:13:42","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=204233"},"modified":"2022-08-31T13:27:41","modified_gmt":"2022-08-31T11:27:41","slug":"ghana-se-non-paghi-laffitto-ti-ritrovi-in-mezzo-alla-strada","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/ghana-se-non-paghi-laffitto-ti-ritrovi-in-mezzo-alla-strada\/","title":{"rendered":"Ghana. Se non paghi l\u2019affitto, ti ritrovi in mezzo alla strada\u2026"},"content":{"rendered":"<h2 style=\"font-weight: 400;\"><strong>Ecco cosa pu\u00f2 fare Ai.Bi., grazie all\u2019Adozione a Distanza, per i minori e le famiglie vulnerabili del Ghana. Solo cos\u00ec \u00e8 possibile sconfiggere il dramma dell\u2019abbandono!<\/strong><\/h2>\n<p style=\"font-weight: 400;\">Con l\u2019ultima settimana\u00a0di agosto,\u00a0<strong>in Ghana,<\/strong>\u00a0si \u00e8 concluso un ciclo di visite, durato ben 4 mesi, con l\u2019obiettivo di \u00a0distribuire beni di primaria necessit\u00e0 e sconfiggere lo spettro dell\u2019abbandono in quelle famiglie vulnerabili dove un bimbo sia stato reintegrato.<\/p>\n<h3 style=\"font-weight: 400;\"><strong>Ai.Bi. non lascia sole le sue famiglie e i suoi \u201caltri figli\u201d.<\/strong><\/h3>\n<p style=\"font-weight: 400;\">Proseguiranno infatti, anche nei mesi successivi,\u00a0<strong>continui follow up telefonici e visite in casa,<\/strong>\u00a0per continuare a monitorare la situazione.<\/p>\n<p style=\"font-weight: 400;\">\u00a0Sono davvero molte le famiglie che ci hanno ringraziato, dimostrando un sincero coinvolgimento.<\/p>\n<p style=\"font-weight: 400;\">\u201c<em>Il\u00a024\u00a0<\/em><em>agosto<\/em>\u00a0\u2013\u00a0scrive un operatore di Ai.Bi. in Ghana, coinvolto nel progetto-\u00a0<em>mi sono recato presso l\u2019abitazione di Jane (nome di fantasia). La ragazza, ci ha confidato quanto per lei fosse difficile trovare soldi a sufficienza per pagare l\u2019affitto e che il\u00a0proprietario\u00a0era sul punto di sfrattare lei e la sua famiglia, chiedendoci se fosse possibile darle una mano.<\/em><\/p>\n<p style=\"font-weight: 400;\"><em>Grazie al progetto di\u00a0<strong>Adozione a Distanza<\/strong>, abbiamo potuto incontrare il proprietario e contribuire alle spese. Lo stesso proprietario ha preparato e firmato un accordo dove ha registrato l\u2019avvenuto pagamento. Jane \u00e8 stata riconoscente e piena di gioia per quello che Ai.Bi. ha fatto per lei e la sua famiglia.\u201d<\/em><\/p>\n<p style=\"font-weight: 400;\">Durante le visite\u00a0di agosto, data l\u2019imminenza della ripresa scolastica, ai bambini e alle bambine che vanno a scuola, sono stati consegnati cartelle e<strong>\u00a0zaini\u00a0<\/strong>mentre \u00e8 in programma l\u2019acquisto delle\u00a0<strong>uniformi scolastiche<\/strong>: insieme alle famiglie verranno individuati i sarti che si occupano della realizzazione delle uniformi.<\/p>\n<p style=\"font-weight: 400;\">Ecco cos&#8217;\u00e8 possibile realizzare per i minori e le famiglie vulnerabili del Ghana grazie al tuo aiuto!<\/p>\n<h3 style=\"font-weight: 400;\"><strong>Un\u2019<a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/?paese=Ghana\">Adozione a Distanza<\/a> per i minori del Ghana<\/strong><\/h3>\n<p style=\"font-weight: 400;\">Supporta anche tu le attivit\u00e0 che Ai.Bi. porta avanti in Ghana, per i minori soli, abbandonati o in difficolt\u00e0 familiare.<\/p>\n<p style=\"font-weight: 400;\">Ricordati che tutte le donazioni ad Ai.Bi. godono delle seguenti\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/images\/AGEVOLAZIONI_FISCALI.pdf\"><strong>agevolazioni fiscali<\/strong><\/a><\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/?paese=Ghana\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn btnsx-btn-embossed\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Adotta a distanza<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n","protected":false},"excerpt":{"rendered":"<p>Ecco cosa pu&ograve; fare Ai.Bi., grazie all&rsquo;Adozione a Distanza, per i minori e le famiglie vulnerabili del Ghana. Solo cos&igrave; &egrave; possibile sconfiggere il dramma dell&rsquo;abbandono! Con l&rsquo;ultima settimana&nbsp;di agosto,&nbsp;in Ghana,&nbsp;si &egrave; concluso un ciclo di visite, durato ben 4 mesi, con l&rsquo;obiettivo di &nbsp;distribuire beni di primaria necessit&agrave; e [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":204235,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209],"tags":[511],"class_list":["post-204233","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-a-distanza","tag-ghana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ghana. Se non paghi l\u2019affitto, ti ritrovi in mezzo alla strada\u2026 - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Ecco cosa pu\u00f2 fare Ai.Bi., grazie all\u2019Adozione a Distanza, per i minori e le famiglie vulnerabili del Ghana. Solo cos\u00ec \u00e8 possibile sconfiggere il dramma dell\u2019abbandono!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/ghana-se-non-paghi-laffitto-ti-ritrovi-in-mezzo-alla-strada\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ghana. Se non paghi l\u2019affitto, ti ritrovi in mezzo alla strada\u2026\" \/>\n<meta property=\"og:description\" content=\"Ecco cosa pu\u00f2 fare Ai.Bi., grazie all\u2019Adozione a Distanza, per i minori e le famiglie vulnerabili del Ghana. Solo cos\u00ec \u00e8 possibile sconfiggere il dramma dell\u2019abbandono!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/ghana-se-non-paghi-laffitto-ti-ritrovi-in-mezzo-alla-strada\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-31T05:13:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-31T11:27:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2022\/08\/Ghana.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-se-non-paghi-laffitto-ti-ritrovi-in-mezzo-alla-strada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-se-non-paghi-laffitto-ti-ritrovi-in-mezzo-alla-strada\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"Ghana. Se non paghi l\u2019affitto, ti ritrovi in mezzo alla strada\u2026\",\"datePublished\":\"2022-08-31T05:13:42+00:00\",\"dateModified\":\"2022-08-31T11:27:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-se-non-paghi-laffitto-ti-ritrovi-in-mezzo-alla-strada\\\/\"},\"wordCount\":368,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-se-non-paghi-laffitto-ti-ritrovi-in-mezzo-alla-strada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/08\\\/Ghana.jpg\",\"keywords\":[\"Ghana\"],\"articleSection\":[\"Adozione a Distanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-se-non-paghi-laffitto-ti-ritrovi-in-mezzo-alla-strada\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-se-non-paghi-laffitto-ti-ritrovi-in-mezzo-alla-strada\\\/\",\"name\":\"Ghana. Se non paghi l\u2019affitto, ti ritrovi in mezzo alla strada\u2026 - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-se-non-paghi-laffitto-ti-ritrovi-in-mezzo-alla-strada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-se-non-paghi-laffitto-ti-ritrovi-in-mezzo-alla-strada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/08\\\/Ghana.jpg\",\"datePublished\":\"2022-08-31T05:13:42+00:00\",\"dateModified\":\"2022-08-31T11:27:41+00:00\",\"description\":\"Ecco cosa pu\u00f2 fare Ai.Bi., grazie all\u2019Adozione a Distanza, per i minori e le famiglie vulnerabili del Ghana. Solo cos\u00ec \u00e8 possibile sconfiggere il dramma dell\u2019abbandono!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-se-non-paghi-laffitto-ti-ritrovi-in-mezzo-alla-strada\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-se-non-paghi-laffitto-ti-ritrovi-in-mezzo-alla-strada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-se-non-paghi-laffitto-ti-ritrovi-in-mezzo-alla-strada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/08\\\/Ghana.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/08\\\/Ghana.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-se-non-paghi-laffitto-ti-ritrovi-in-mezzo-alla-strada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione a Distanza\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-a-distanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ghana. Se non paghi l\u2019affitto, ti ritrovi in mezzo alla strada\u2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ghana. Se non paghi l\u2019affitto, ti ritrovi in mezzo alla strada\u2026 - Ai.Bi. Amici dei Bambini","description":"Ecco cosa pu\u00f2 fare Ai.Bi., grazie all\u2019Adozione a Distanza, per i minori e le famiglie vulnerabili del Ghana. Solo cos\u00ec \u00e8 possibile sconfiggere il dramma dell\u2019abbandono!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/ghana-se-non-paghi-laffitto-ti-ritrovi-in-mezzo-alla-strada\/","og_locale":"it_IT","og_type":"article","og_title":"Ghana. Se non paghi l\u2019affitto, ti ritrovi in mezzo alla strada\u2026","og_description":"Ecco cosa pu\u00f2 fare Ai.Bi., grazie all\u2019Adozione a Distanza, per i minori e le famiglie vulnerabili del Ghana. Solo cos\u00ec \u00e8 possibile sconfiggere il dramma dell\u2019abbandono!","og_url":"https:\/\/www.aibi.it\/ita\/ghana-se-non-paghi-laffitto-ti-ritrovi-in-mezzo-alla-strada\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2022-08-31T05:13:42+00:00","article_modified_time":"2022-08-31T11:27:41+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2022\/08\/Ghana.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/ghana-se-non-paghi-laffitto-ti-ritrovi-in-mezzo-alla-strada\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-se-non-paghi-laffitto-ti-ritrovi-in-mezzo-alla-strada\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"Ghana. Se non paghi l\u2019affitto, ti ritrovi in mezzo alla strada\u2026","datePublished":"2022-08-31T05:13:42+00:00","dateModified":"2022-08-31T11:27:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-se-non-paghi-laffitto-ti-ritrovi-in-mezzo-alla-strada\/"},"wordCount":368,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-se-non-paghi-laffitto-ti-ritrovi-in-mezzo-alla-strada\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/08\/Ghana.jpg","keywords":["Ghana"],"articleSection":["Adozione a Distanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/ghana-se-non-paghi-laffitto-ti-ritrovi-in-mezzo-alla-strada\/","url":"https:\/\/www.aibi.it\/ita\/ghana-se-non-paghi-laffitto-ti-ritrovi-in-mezzo-alla-strada\/","name":"Ghana. Se non paghi l\u2019affitto, ti ritrovi in mezzo alla strada\u2026 - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-se-non-paghi-laffitto-ti-ritrovi-in-mezzo-alla-strada\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-se-non-paghi-laffitto-ti-ritrovi-in-mezzo-alla-strada\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/08\/Ghana.jpg","datePublished":"2022-08-31T05:13:42+00:00","dateModified":"2022-08-31T11:27:41+00:00","description":"Ecco cosa pu\u00f2 fare Ai.Bi., grazie all\u2019Adozione a Distanza, per i minori e le famiglie vulnerabili del Ghana. Solo cos\u00ec \u00e8 possibile sconfiggere il dramma dell\u2019abbandono!","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-se-non-paghi-laffitto-ti-ritrovi-in-mezzo-alla-strada\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/ghana-se-non-paghi-laffitto-ti-ritrovi-in-mezzo-alla-strada\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/ghana-se-non-paghi-laffitto-ti-ritrovi-in-mezzo-alla-strada\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2022\/08\/Ghana.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/08\/Ghana.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/ghana-se-non-paghi-laffitto-ti-ritrovi-in-mezzo-alla-strada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione a Distanza","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-a-distanza\/"},{"@type":"ListItem","position":3,"name":"Ghana. Se non paghi l\u2019affitto, ti ritrovi in mezzo alla strada\u2026"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 07:20:06","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/204233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=204233"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/204233\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/204235"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=204233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=204233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=204233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}