﻿


{"id":204297,"date":"2022-09-03T07:30:42","date_gmt":"2022-09-03T05:30:42","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=204297"},"modified":"2022-09-02T11:28:57","modified_gmt":"2022-09-02T09:28:57","slug":"italia-fame-di-mamma-i-nostri-ragazzi-di-casa-pinocchio-axel-dalla-comunita-ad-un-lavoro-a-tempo-indeterminato","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/italia-fame-di-mamma-i-nostri-ragazzi-di-casa-pinocchio-axel-dalla-comunita-ad-un-lavoro-a-tempo-indeterminato\/","title":{"rendered":"Italia. Fame di Mamma. I nostri ragazzi di Casa Pinocchio. Axel: dalla comunit\u00e0 ad un lavoro a tempo indeterminato!"},"content":{"rendered":"<h2><strong>Axel e tutti i nostri ospiti accolti in questi anni, ringraziano chi, sostenendo economicamente i nostri progetti, grazie all\u2019Adozione a Distanza, ha garantito loro un futuro migliore!<\/strong><\/h2>\n<p>Dopo un po\u2019 di tempo che ci eravamo promessi di incontrarci per bere un caff\u00e8 e poter ricordare i \u201cvecchi tempi\u201d, finalmente io e Axel riusciamo a concordare il giorno. Axel, albanese, era arrivato in Italia a 15 anni ed era stato accolto presso la nostra comunit\u00e0 educativa\u00a0<strong>\u201cCasa di Pinocchio\u201d.<\/strong>\u00a0Gli chiedo se \u00e8 disposto a rispondere ad alcune domande perch\u00e9 una tirocinante di Scienze dell\u2019Educazione, nel suo progetto di tesi sui minori stranieri non accompagnati, aveva desiderio di intervistare direttamente uno dei nostri ex ospiti.<\/p>\n<p><strong>Da dove provieni?<\/strong><\/p>\n<p>Sono albanese, vengo dall\u2019Albania.<\/p>\n<p><strong>Quanti anni hai?<\/strong><\/p>\n<p>Ho 22 anni.<\/p>\n<p><strong>Qual era la tua destinazione iniziale?<\/strong><\/p>\n<p>In linea generale, l\u2019Italia. Da subito, sapevo per\u00f2 che dovevo raggiungere il nord, dove ci sono pi\u00f9 possibilit\u00e0.<\/p>\n<p><strong>Che percorso hai fatto per arrivare qui?<\/strong><\/p>\n<p>Sono partito in aereo con mio zio che mi ha accompagnato in Italia, in Puglia. Qui mi ha comprato un biglietto del treno, per Milano. Lui \u00e8 tornato in Albania.<\/p>\n<p><strong>Come e quando sei arrivato in Italia?<\/strong><\/p>\n<p>Avevo 15 anni, quindi circa 7 anni fa.<\/p>\n<p><strong>Quali sono le cause che ti hanno spinto a lasciare il tuo paese d\u2019origine?<\/strong><\/p>\n<p>Nel mio paese siamo un po\u2019 tutti poveri. Vediamo in TV come l\u2019Italia sia un bel Paese e mia mamma un giorno mi ha abbracciato dicendomi che voleva un futuro migliore per me. Altri ragazzi del mio paese vivevano gi\u00e0 in Italia e ci raccontavano che potevano studiare. Volevo imparare l\u2019italiano perch\u00e9 in Albania si pu\u00f2 trovare lavoro in diverse aziende italiane.<\/p>\n<p><strong>Come hai vissuto il primo approccio in Italia?<\/strong><\/p>\n<p>Mi sono sentito molto solo. Conoscevo poche parole e non riuscivo a parlare con nessuno. Quando per\u00f2 sono stato accolto in comunit\u00e0, mi sono sentito subito ben accolto e, pian piano, sono tornato sereno.<\/p>\n<p><strong>Cosa pensi dell\u2019Italia?<\/strong><\/p>\n<p>\u00c8 un bel paese e i ragazzi sono fortunati a poter studiare quello che vogliono.<\/p>\n<p><strong>Quali percorsi ti sono stati proposti?<\/strong><\/p>\n<p>Sono arrivato d\u2019estate e sono stato inserito subito in un corso di italiano. Ho dovuto aspettare\u00a0settembre\u00a0per iniziare la scuola di italiano. Ho iniziato anche a giocare subito a calcio in una societ\u00e0 sportiva.<\/p>\n<p><strong>Hai avuto difficolt\u00e0 a dichiarare l\u2019et\u00e0 anagrafica?<\/strong><\/p>\n<p>No, perch\u00e9 avevo con me i documenti albanesi che attestavano la mia data di nascita.<\/p>\n<p><strong>Quando sei entrato a Casa Pinocchio, qual \u00e8 stato il tuo approccio con i tuoi coetanei e con le figure educative di riferimento?<\/strong><\/p>\n<p>Erano presenti altri due ragazzi albanesi che mi hanno spiegato come funzionava. Con gli altri ragazzi italiani giocavo molto volentieri e anche loro mi insegnavano la lingua italiana. Gli educatori sono sempre stati gentili e mi invitavano a non abbattermi se non capivo qualcosa. Cos\u00ec in poche settimane ho iniziato a capire bene quello che mi dicevano e anche io potevo parlare con loro.<\/p>\n<p><strong>Ti sei sentito accolto?<\/strong><\/p>\n<p>Si, soprattutto nei momenti difficili dove pensavo di tornare a casa in Albania. Gli educatori mi davano coraggio e mi sottolineavano i successi ottenuti durante il mio percorso.<\/p>\n<p><strong>Come trascorri le tue giornate?<\/strong><\/p>\n<p>In comunit\u00e0 vivevo la quotidianit\u00e0 di un adolescente che si alza, va a scuola, gioca con gli amici. Poi sono stato spostato in un appartamento per l\u2019autonomia quando ho compiuto i 18 anni e l\u00ec ho dovuto imparare a gestirmi da solo i miei spazi; gli educatori mi hanno insegnato l\u2019utilizzo del denaro e pian piano ho trovato un lavoro. Ora che sono assunto a tempo indeterminato, ho un piccolo appartamento in affitto, lavoro e ogni tanto vado a ritrovare gli educatori della comunit\u00e0.<\/p>\n<p><strong>Ti manca il tuo Paese?<\/strong><\/p>\n<p>Si, mi \u00e8 mancato parecchio ma ora che ho un lavoro, sono gi\u00e0 tornato due volte in Albania per trovare la mamma.<\/p>\n<p><strong>Sei in contatto con la tua famiglia? In quali rapporti sei?<\/strong><\/p>\n<p>Ho sempre sentito la mia mamma che \u00e8 molto contenta di me. Quando la vado a trovare \u00e8 la cosa pi\u00f9 bella del mondo!<\/p>\n<p><strong>Quali sono i tuoi sogni?<\/strong><\/p>\n<p>Forse lo sto gi\u00e0 vivendo. Il lavoro a volte \u00e8 faticoso ma i miei colleghi mi vogliono bene. Mi sento soddisfatto. Probabilmente, vorrei tornare definitivamente in Albania\u2026<\/p>\n<p><strong>Cosa pensi di te?<\/strong><\/p>\n<p>Che domanda difficile! Penso bene\u2026<\/p>\n<p><strong>Hai paura ora che non sei pi\u00f9 in comunit\u00e0\/alloggio?<\/strong><\/p>\n<p>No, perch\u00e9 \u00e8 rimasta l\u2019amicizia e so che se ho bisogno posso sempre contare su un aiuto.<\/p>\n<p><strong>Conosci il sistema di protezione dei minori?<\/strong><\/p>\n<p>La mia assistente sociale ha sempre cercato di farmi capire il contesto in cui mi trovavo. Cos\u00ec anche gli educatori mi hanno sempre accompagnato passo dopo passo. Non posso dire per\u00f2 di conoscere le leggi\u2026 (<em>ride<\/em>)<\/p>\n<p><strong>Hai avuto altre esperienze oltre alla \u201cCasa di Pinocchio\u201d (comunit\u00e0 educativa)?<\/strong><\/p>\n<p>No, dopo essere stato in comunit\u00e0, sono passato in un alloggio per l\u2019autonomia, mantenendo i miei educatori di riferimento.<\/p>\n<p><strong>Quali sono i tuoi obiettivi?<\/strong><\/p>\n<p>Vivere la mia vita il meglio possibile!<\/p>\n<p>Axel e tutti i nostri ospiti accolti in questi anni, ringraziano chi, sostenendo economicamente i nostri progetti, ha garantito loro un futuro migliore!<\/p>\n<p style=\"font-weight: 400;\"><em>Diego Moretti \u2013 responsabile dell\u2019area minori di AIBC<\/em><\/p>\n<h3><strong>Attiva anche tu un\u2019Adozione a Distanza in Italia.<\/strong><\/h3>\n<p>Bastano 10 euro al mese.<strong>\u00a0Scopri\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-10\/\">QUI<\/a>\u00a0come fare!<\/strong><strong><br \/>\n<\/strong>E ricorda:\u00a0<strong>le Adozioni a Distanza di Ai.Bi.\u00a0<\/strong>godono delle seguenti\u00a0<strong><a href=\"https:\/\/www.aibi.it\/ita\/images\/AGEVOLAZIONI_FISCALI.pdf\">agevolazioni fiscali<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Axel e tutti i nostri ospiti accolti in questi anni, ringraziano chi, sostenendo economicamente i nostri progetti, grazie all&rsquo;Adozione a Distanza, ha garantito loro un futuro migliore! Dopo un po&rsquo; di tempo che ci eravamo promessi di incontrarci per bere un caff&egrave; e poter ricordare i &ldquo;vecchi tempi&rdquo;, finalmente io [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":204298,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209],"tags":[801,608],"class_list":["post-204297","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-a-distanza","tag-casa-pinocchio","tag-fame-di-mamma"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Italia. Fame di Mamma. I nostri ragazzi di Casa Pinocchio. Axel: dalla comunit\u00e0 ad un lavoro a tempo indeterminato! - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Italia. Fame di mamma. Axel e tutti i nostri ospiti accolti in questi anni, ringraziano chi, sostenendo economicamente i nostri progetti, grazie all\u2019Adozione a Distanza, ha garantito loro un futuro migliore!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/italia-fame-di-mamma-i-nostri-ragazzi-di-casa-pinocchio-axel-dalla-comunita-ad-un-lavoro-a-tempo-indeterminato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Italia. Fame di Mamma. I nostri ragazzi di Casa Pinocchio. Axel: dalla comunit\u00e0 ad un lavoro a tempo indeterminato!\" \/>\n<meta property=\"og:description\" content=\"Italia. Fame di mamma. Axel e tutti i nostri ospiti accolti in questi anni, ringraziano chi, sostenendo economicamente i nostri progetti, grazie all\u2019Adozione a Distanza, ha garantito loro un futuro migliore!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/italia-fame-di-mamma-i-nostri-ragazzi-di-casa-pinocchio-axel-dalla-comunita-ad-un-lavoro-a-tempo-indeterminato\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-03T05:30:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2022\/09\/casa-pinocchio-Itlaia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/italia-fame-di-mamma-i-nostri-ragazzi-di-casa-pinocchio-axel-dalla-comunita-ad-un-lavoro-a-tempo-indeterminato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/italia-fame-di-mamma-i-nostri-ragazzi-di-casa-pinocchio-axel-dalla-comunita-ad-un-lavoro-a-tempo-indeterminato\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"Italia. Fame di Mamma. I nostri ragazzi di Casa Pinocchio. Axel: dalla comunit\u00e0 ad un lavoro a tempo indeterminato!\",\"datePublished\":\"2022-09-03T05:30:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/italia-fame-di-mamma-i-nostri-ragazzi-di-casa-pinocchio-axel-dalla-comunita-ad-un-lavoro-a-tempo-indeterminato\\\/\"},\"wordCount\":911,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/italia-fame-di-mamma-i-nostri-ragazzi-di-casa-pinocchio-axel-dalla-comunita-ad-un-lavoro-a-tempo-indeterminato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/09\\\/casa-pinocchio-Itlaia.jpg\",\"keywords\":[\"Casa Pinocchio\",\"Fame di mamma\"],\"articleSection\":[\"Adozione a Distanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/italia-fame-di-mamma-i-nostri-ragazzi-di-casa-pinocchio-axel-dalla-comunita-ad-un-lavoro-a-tempo-indeterminato\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/italia-fame-di-mamma-i-nostri-ragazzi-di-casa-pinocchio-axel-dalla-comunita-ad-un-lavoro-a-tempo-indeterminato\\\/\",\"name\":\"Italia. Fame di Mamma. I nostri ragazzi di Casa Pinocchio. Axel: dalla comunit\u00e0 ad un lavoro a tempo indeterminato! - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/italia-fame-di-mamma-i-nostri-ragazzi-di-casa-pinocchio-axel-dalla-comunita-ad-un-lavoro-a-tempo-indeterminato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/italia-fame-di-mamma-i-nostri-ragazzi-di-casa-pinocchio-axel-dalla-comunita-ad-un-lavoro-a-tempo-indeterminato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/09\\\/casa-pinocchio-Itlaia.jpg\",\"datePublished\":\"2022-09-03T05:30:42+00:00\",\"description\":\"Italia. Fame di mamma. Axel e tutti i nostri ospiti accolti in questi anni, ringraziano chi, sostenendo economicamente i nostri progetti, grazie all\u2019Adozione a Distanza, ha garantito loro un futuro migliore!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/italia-fame-di-mamma-i-nostri-ragazzi-di-casa-pinocchio-axel-dalla-comunita-ad-un-lavoro-a-tempo-indeterminato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/italia-fame-di-mamma-i-nostri-ragazzi-di-casa-pinocchio-axel-dalla-comunita-ad-un-lavoro-a-tempo-indeterminato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/italia-fame-di-mamma-i-nostri-ragazzi-di-casa-pinocchio-axel-dalla-comunita-ad-un-lavoro-a-tempo-indeterminato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/09\\\/casa-pinocchio-Itlaia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/09\\\/casa-pinocchio-Itlaia.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/italia-fame-di-mamma-i-nostri-ragazzi-di-casa-pinocchio-axel-dalla-comunita-ad-un-lavoro-a-tempo-indeterminato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione a Distanza\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-a-distanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Italia. Fame di Mamma. I nostri ragazzi di Casa Pinocchio. Axel: dalla comunit\u00e0 ad un lavoro a tempo indeterminato!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Italia. Fame di Mamma. I nostri ragazzi di Casa Pinocchio. Axel: dalla comunit\u00e0 ad un lavoro a tempo indeterminato! - Ai.Bi. Amici dei Bambini","description":"Italia. Fame di mamma. Axel e tutti i nostri ospiti accolti in questi anni, ringraziano chi, sostenendo economicamente i nostri progetti, grazie all\u2019Adozione a Distanza, ha garantito loro un futuro migliore!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/italia-fame-di-mamma-i-nostri-ragazzi-di-casa-pinocchio-axel-dalla-comunita-ad-un-lavoro-a-tempo-indeterminato\/","og_locale":"it_IT","og_type":"article","og_title":"Italia. Fame di Mamma. I nostri ragazzi di Casa Pinocchio. Axel: dalla comunit\u00e0 ad un lavoro a tempo indeterminato!","og_description":"Italia. Fame di mamma. Axel e tutti i nostri ospiti accolti in questi anni, ringraziano chi, sostenendo economicamente i nostri progetti, grazie all\u2019Adozione a Distanza, ha garantito loro un futuro migliore!","og_url":"https:\/\/www.aibi.it\/ita\/italia-fame-di-mamma-i-nostri-ragazzi-di-casa-pinocchio-axel-dalla-comunita-ad-un-lavoro-a-tempo-indeterminato\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2022-09-03T05:30:42+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2022\/09\/casa-pinocchio-Itlaia.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/italia-fame-di-mamma-i-nostri-ragazzi-di-casa-pinocchio-axel-dalla-comunita-ad-un-lavoro-a-tempo-indeterminato\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/italia-fame-di-mamma-i-nostri-ragazzi-di-casa-pinocchio-axel-dalla-comunita-ad-un-lavoro-a-tempo-indeterminato\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"Italia. Fame di Mamma. I nostri ragazzi di Casa Pinocchio. Axel: dalla comunit\u00e0 ad un lavoro a tempo indeterminato!","datePublished":"2022-09-03T05:30:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/italia-fame-di-mamma-i-nostri-ragazzi-di-casa-pinocchio-axel-dalla-comunita-ad-un-lavoro-a-tempo-indeterminato\/"},"wordCount":911,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/italia-fame-di-mamma-i-nostri-ragazzi-di-casa-pinocchio-axel-dalla-comunita-ad-un-lavoro-a-tempo-indeterminato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/09\/casa-pinocchio-Itlaia.jpg","keywords":["Casa Pinocchio","Fame di mamma"],"articleSection":["Adozione a Distanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/italia-fame-di-mamma-i-nostri-ragazzi-di-casa-pinocchio-axel-dalla-comunita-ad-un-lavoro-a-tempo-indeterminato\/","url":"https:\/\/www.aibi.it\/ita\/italia-fame-di-mamma-i-nostri-ragazzi-di-casa-pinocchio-axel-dalla-comunita-ad-un-lavoro-a-tempo-indeterminato\/","name":"Italia. Fame di Mamma. I nostri ragazzi di Casa Pinocchio. Axel: dalla comunit\u00e0 ad un lavoro a tempo indeterminato! - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/italia-fame-di-mamma-i-nostri-ragazzi-di-casa-pinocchio-axel-dalla-comunita-ad-un-lavoro-a-tempo-indeterminato\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/italia-fame-di-mamma-i-nostri-ragazzi-di-casa-pinocchio-axel-dalla-comunita-ad-un-lavoro-a-tempo-indeterminato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/09\/casa-pinocchio-Itlaia.jpg","datePublished":"2022-09-03T05:30:42+00:00","description":"Italia. Fame di mamma. Axel e tutti i nostri ospiti accolti in questi anni, ringraziano chi, sostenendo economicamente i nostri progetti, grazie all\u2019Adozione a Distanza, ha garantito loro un futuro migliore!","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/italia-fame-di-mamma-i-nostri-ragazzi-di-casa-pinocchio-axel-dalla-comunita-ad-un-lavoro-a-tempo-indeterminato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/italia-fame-di-mamma-i-nostri-ragazzi-di-casa-pinocchio-axel-dalla-comunita-ad-un-lavoro-a-tempo-indeterminato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/italia-fame-di-mamma-i-nostri-ragazzi-di-casa-pinocchio-axel-dalla-comunita-ad-un-lavoro-a-tempo-indeterminato\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2022\/09\/casa-pinocchio-Itlaia.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/09\/casa-pinocchio-Itlaia.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/italia-fame-di-mamma-i-nostri-ragazzi-di-casa-pinocchio-axel-dalla-comunita-ad-un-lavoro-a-tempo-indeterminato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione a Distanza","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-a-distanza\/"},{"@type":"ListItem","position":3,"name":"Italia. Fame di Mamma. I nostri ragazzi di Casa Pinocchio. Axel: dalla comunit\u00e0 ad un lavoro a tempo indeterminato!"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 06:50:20","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/204297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=204297"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/204297\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/204298"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=204297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=204297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=204297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}