﻿


{"id":205655,"date":"2022-10-12T07:30:57","date_gmt":"2022-10-12T05:30:57","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=205655"},"modified":"2023-10-25T14:51:29","modified_gmt":"2023-10-25T12:51:29","slug":"bambinixlapace-ucraina-le-lettere-dei-bambini-e-ragazzi-ucraini-ai-loro-sostenitori-a-distanza","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/bambinixlapace-ucraina-le-lettere-dei-bambini-e-ragazzi-ucraini-ai-loro-sostenitori-a-distanza\/","title":{"rendered":"#BAMBINIXLAPACE: Ucraina. Le lettere dei bambini e ragazzi ucraini ai loro sostenitori a distanza"},"content":{"rendered":"<h2 style=\"font-weight: 400;\"><em><strong>\u201cCiao mia cara amica italiana.\u00a0<\/strong><\/em><strong><em>Voglio dirti che sono molto felice che non ti dimentichi di me e della mia famiglia\u2026\u201d<\/em><\/strong><\/h2>\n<p style=\"font-weight: 400;\">Ancora \u00a0bombe, morte e devastazione. La terribile pazzia della guerra, in\u00a0<strong>Ucraina<\/strong>\u00a0non accenna a vedere fine, anzi, purtroppo in questi giorni, ha nuovamente spinto l\u2019acceleratore, senza riguardo per le vite di uomini, donne e bambini.<\/p>\n<p style=\"font-weight: 400;\">Oggi, pi\u00f9 che mai, gli operatori di Ai.Bi. in Ucraina, attraverso il progetto\u00a0<strong>#BAMBINIXLAPACE<\/strong>, continuano a portare, all\u2019interno dei\u00a0<strong><a href=\"https:\/\/www.aibi.it\/ita\/perche-costruiamo-punti-aibi-minori-ucraina\/\">Punti Ai.Bi.<\/a>\u00a0<\/strong>allestiti nel Paese, sostegno psicologico agli adulti e momenti di svago e di rilassamento dallo stress a tanti bambini che purtroppo non possono fare altro che\u00a0<strong>crescere sotto i bombardamenti<\/strong>.<\/p>\n<p style=\"font-weight: 400;\">Ma non si sono fermati neanche i progetti di Adozione a Distanza di Ai.Bi. in Ucraina, che hanno continuato a sostenere tanti minori tornati a vivere in famiglia.<\/p>\n<p style=\"font-weight: 400;\">I ragazzi, in occasione della visita dell\u2019assistente sociale che, grazie alla\u00a0<strong>generosit\u00e0<\/strong>\u00a0dei nostri sostenitori, ha potuto portare alle famiglie alcuni beni di prima necessit\u00e0, hanno deciso di scrivere alcune\u00a0<strong>brevi lettere ai loro \u201cangeli dal cuore grande\u201d<\/strong>.<\/p>\n<h3 style=\"font-weight: 400;\"><strong>Per questioni di privacy ometteremo il loro nomi, ma vogliamo condividere con voi il loro ringraziamento.<\/strong><\/h3>\n<p style=\"font-weight: 400;\"><em>Ciao mia cara amica italiana.<\/em><\/p>\n<p style=\"font-weight: 400;\"><em>Voglio dirti che sono molto felice che non ti dimentichi di me e della mia famiglia. Grazie a voi italiani per ogni persona che avete ospitato durante la guerra. Ringrazio Dio, che dove vivo non ci sono azioni militari. Credo che la guerra finir\u00e0 tra poco e niente mi impedir\u00e0 di studiare, come prima. Grazie per il tuo aiuto e grazie per aver scelto per me un regalo stupendo. \u00c8 proprio quello che mi serve per la scuola, lo zaino.<\/em><\/p>\n<p style=\"font-weight: 400;\"><em>Ti auguro pace, bont\u00e0, felicit\u00e0 e prosperit\u00e0 per il tuo paese.<\/em><\/p>\n<p style=\"font-weight: 400;\">&#8230;.<\/p>\n<p style=\"font-weight: 400;\"><em>Ciao,<\/em><\/p>\n<p style=\"font-weight: 400;\"><em>come stai? Scusa se non ti ho scritto per cos\u00ec tanto tempo. In Ucraina \u00e8 iniziata la guerra, ho avuto molta paura al suono delle sirene, poi siamo partite per la Spagna e ci siamo stati per 5 mesi.<\/em><\/p>\n<p style=\"font-weight: 400;\"><em>Mamma \u00e8 rimasta senza lavoro, dovrebbe operarsi alla schiena, voleva farlo in Spagna ma io ho insistito per tornare a casa. Mia mamma \u00e8 molto buona e la amo tanto. Adesso ho ricominciato la scuola e vado bene, perch\u00e9 siamo all\u2019inizio ed \u00e8 tutto facile. Quest\u2019anno ho iniziato a studiare anche fisica, chimica, geometria e algebra; invece, nella 6 classe avevo solo matematica. Mi piace molto algebra, ma non vado molto bene negli esercizi di matematica, ma ho deciso di andare dall\u2019insegnante di sostegno per fare pi\u00f9 pratica.<\/em><\/p>\n<p style=\"font-weight: 400;\"><em>Il 9 settembre \u00e8 il mio compleanno!\u00a0 Ora ti saluto, le scarpe da ginnastica che mi hai regalato sono molto belle, le uso sempre, grazie mille. Se mi scrivi mi fa tanto piacere.<\/em><\/p>\n<p style=\"font-weight: 400;\"><em>Un abbraccio.<\/em><\/p>\n<p style=\"font-weight: 400;\">&#8230;.<\/p>\n<p style=\"font-weight: 400;\"><em>Ciao!<\/em><\/p>\n<p style=\"font-weight: 400;\"><em>Ho 13 anni. Vivo con la mia famiglia: i miei amati mamma, pap\u00e0 e mio fratello Artem che ha 5 anni. Che carattere ho? Penso che non sia un brutto carattere. Mi dicono che sono molto carina, gioiosa e sincera. Mi piace molto disegnare. Ho 2 gatti e un cane. Il gatto si chiama Marchese, invece la gatta Masca e il cane Barsik. La mia lezione preferita \u00e8 l\u2019educazione fisica.<\/em><\/p>\n<p style=\"font-weight: 400;\"><em>Tu come stai? Ha qualche animale? Ti voglio ringraziare per il tuo aiuto.<\/em><\/p>\n<p style=\"font-weight: 400;\">&#8230;<\/p>\n<p style=\"font-weight: 400;\"><em>Ciao cari amici. Vi saluto con affetto. Io e la mia famiglia vi ringraziamo per l\u2019aiuto.<\/em>\u00a0<em>Il vostro aiuto in questo periodo ci serve molto, grazie mille.<\/em><\/p>\n<p style=\"font-weight: 400;\"><em>\u00a0Vorrei comunicare con voi, come state, com\u2019\u00e8 la salute e come sta vostra figlia?<\/em><\/p>\n<p style=\"font-weight: 400;\"><em>Un grande saluto.<\/em><\/p>\n<p style=\"font-weight: 400;\"><em>\u00a0\u00a0<\/em><\/p>\n<h3 style=\"font-weight: 400;\"><strong>Sostieni anche tu la campagna di Ai.Bi. BAMBINIXLAPACE<\/strong><\/h3>\n<p style=\"font-weight: 400;\">Ai.Bi. \u2013 Amici dei bambini ha messo in campo una\u00a0campagna dedicata alla crisi ucraina:<a href=\"https:\/\/www.aibi.it\/ita\/bambinixlapace\">\u00a0BAMBINIxLAPACE<\/a>, alla quale chiunque pu\u00f2 partecipare scegliendo una delle varie modalit\u00e0 di aiuto e vicinanza alle famiglie e i bambini ucraini.\u00a0Oggi\u00a0aiutare un bambino ucraino in fuga dalla guerra,\u00a0significa tenere viva la sua speranza che la guerra non \u00e8 l\u2019ultima parola della sua vita e che anche per lui ci sar\u00e0 un futuro sereno nella sua terra.<\/p>\n<p style=\"font-weight: 400;\">\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*197331-start*\/\n#btnsx-197331{margin-top:0px;margin-bottom:25px;margin-left:0px;margin-right:0px;padding-top:16px;padding-bottom:15px;padding-left:43px;padding-right:44px;}\n#btnsx-197331 .btnsx-text-primary{text-transform:uppercase;font-size:20px;line-height:20px;font-weight:800;font-family:Raleway;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-197331:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-197331{background-color:#dd3333!important;}\n#btnsx-197331:hover{background-color:#d13030!important;}\n#btnsx-197331{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px;}\n#btnsx-197331:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:solid;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px;}\n#btnsx-197331{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-197331:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*197331-end*\/\n<\/style>\n<a href=\"https:\/\/dona.aibi.it\/emergenza-ucraina\/?act=cplt&amp;origine=web-button-in-post\" id=\"btnsx-197331\" class=\"btnsx-btn btnsx-btn-block\"  data-font-primary=\"Raleway\">\n\t<span class=\"btnsx-text-primary \">EMERGENZA UCRAINA<\/span><\/a>\n\n<!-- Buttons X - End -->\n\n<p style=\"font-weight: 400;\">\n","protected":false},"excerpt":{"rendered":"<p>&ldquo;Ciao mia cara amica italiana.&nbsp;Voglio dirti che sono molto felice che non ti dimentichi di me e della mia famiglia&hellip;&rdquo; Ancora &nbsp;bombe, morte e devastazione. La terribile pazzia della guerra, in&nbsp;Ucraina&nbsp;non accenna a vedere fine, anzi, purtroppo in questi giorni, ha nuovamente spinto l&rsquo;acceleratore, senza riguardo per le vite di [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":205656,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[909],"tags":[895,423],"class_list":["post-205655","post","type-post","status-publish","format-standard","has-post-thumbnail","category-bambinixlapace","tag-bambinixlapace","tag-ucraina"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>#BAMBINIXLAPACE: Ucraina. Le lettere dei bambini e ragazzi ucraini ai loro sostenitori a distanza - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Ucraina. \u201cCiao mia cara amica italiana.\u00a0Voglio dirti che sono molto felice che non ti dimentichi di me e della mia famiglia\u2026\u201d\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/bambinixlapace-ucraina-le-lettere-dei-bambini-e-ragazzi-ucraini-ai-loro-sostenitori-a-distanza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#BAMBINIXLAPACE: Ucraina. Le lettere dei bambini e ragazzi ucraini ai loro sostenitori a distanza\" \/>\n<meta property=\"og:description\" content=\"Ucraina. \u201cCiao mia cara amica italiana.\u00a0Voglio dirti che sono molto felice che non ti dimentichi di me e della mia famiglia\u2026\u201d\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/bambinixlapace-ucraina-le-lettere-dei-bambini-e-ragazzi-ucraini-ai-loro-sostenitori-a-distanza\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-12T05:30:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-25T12:51:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ucraina.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-ucraina-le-lettere-dei-bambini-e-ragazzi-ucraini-ai-loro-sostenitori-a-distanza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-ucraina-le-lettere-dei-bambini-e-ragazzi-ucraini-ai-loro-sostenitori-a-distanza\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"#BAMBINIXLAPACE: Ucraina. Le lettere dei bambini e ragazzi ucraini ai loro sostenitori a distanza\",\"datePublished\":\"2022-10-12T05:30:57+00:00\",\"dateModified\":\"2023-10-25T12:51:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-ucraina-le-lettere-dei-bambini-e-ragazzi-ucraini-ai-loro-sostenitori-a-distanza\\\/\"},\"wordCount\":674,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-ucraina-le-lettere-dei-bambini-e-ragazzi-ucraini-ai-loro-sostenitori-a-distanza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/10\\\/Ucraina.jpg\",\"keywords\":[\"BAMBINIxLAPACE\",\"Ucraina\"],\"articleSection\":[\"BAMBINIXLAPACE\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-ucraina-le-lettere-dei-bambini-e-ragazzi-ucraini-ai-loro-sostenitori-a-distanza\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-ucraina-le-lettere-dei-bambini-e-ragazzi-ucraini-ai-loro-sostenitori-a-distanza\\\/\",\"name\":\"#BAMBINIXLAPACE: Ucraina. Le lettere dei bambini e ragazzi ucraini ai loro sostenitori a distanza - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-ucraina-le-lettere-dei-bambini-e-ragazzi-ucraini-ai-loro-sostenitori-a-distanza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-ucraina-le-lettere-dei-bambini-e-ragazzi-ucraini-ai-loro-sostenitori-a-distanza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/10\\\/Ucraina.jpg\",\"datePublished\":\"2022-10-12T05:30:57+00:00\",\"dateModified\":\"2023-10-25T12:51:29+00:00\",\"description\":\"Ucraina. \u201cCiao mia cara amica italiana.\u00a0Voglio dirti che sono molto felice che non ti dimentichi di me e della mia famiglia\u2026\u201d\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-ucraina-le-lettere-dei-bambini-e-ragazzi-ucraini-ai-loro-sostenitori-a-distanza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-ucraina-le-lettere-dei-bambini-e-ragazzi-ucraini-ai-loro-sostenitori-a-distanza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-ucraina-le-lettere-dei-bambini-e-ragazzi-ucraini-ai-loro-sostenitori-a-distanza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/10\\\/Ucraina.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/10\\\/Ucraina.jpg\",\"width\":1200,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-ucraina-le-lettere-dei-bambini-e-ragazzi-ucraini-ai-loro-sostenitori-a-distanza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BAMBINIXLAPACE\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/bambinixlapace\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"#BAMBINIXLAPACE: Ucraina. Le lettere dei bambini e ragazzi ucraini ai loro sostenitori a distanza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"#BAMBINIXLAPACE: Ucraina. Le lettere dei bambini e ragazzi ucraini ai loro sostenitori a distanza - Ai.Bi. Amici dei Bambini","description":"Ucraina. \u201cCiao mia cara amica italiana.\u00a0Voglio dirti che sono molto felice che non ti dimentichi di me e della mia famiglia\u2026\u201d","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/bambinixlapace-ucraina-le-lettere-dei-bambini-e-ragazzi-ucraini-ai-loro-sostenitori-a-distanza\/","og_locale":"it_IT","og_type":"article","og_title":"#BAMBINIXLAPACE: Ucraina. Le lettere dei bambini e ragazzi ucraini ai loro sostenitori a distanza","og_description":"Ucraina. \u201cCiao mia cara amica italiana.\u00a0Voglio dirti che sono molto felice che non ti dimentichi di me e della mia famiglia\u2026\u201d","og_url":"https:\/\/www.aibi.it\/ita\/bambinixlapace-ucraina-le-lettere-dei-bambini-e-ragazzi-ucraini-ai-loro-sostenitori-a-distanza\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2022-10-12T05:30:57+00:00","article_modified_time":"2023-10-25T12:51:29+00:00","og_image":[{"width":1200,"height":420,"url":"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ucraina.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-ucraina-le-lettere-dei-bambini-e-ragazzi-ucraini-ai-loro-sostenitori-a-distanza\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-ucraina-le-lettere-dei-bambini-e-ragazzi-ucraini-ai-loro-sostenitori-a-distanza\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"#BAMBINIXLAPACE: Ucraina. Le lettere dei bambini e ragazzi ucraini ai loro sostenitori a distanza","datePublished":"2022-10-12T05:30:57+00:00","dateModified":"2023-10-25T12:51:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-ucraina-le-lettere-dei-bambini-e-ragazzi-ucraini-ai-loro-sostenitori-a-distanza\/"},"wordCount":674,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-ucraina-le-lettere-dei-bambini-e-ragazzi-ucraini-ai-loro-sostenitori-a-distanza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ucraina.jpg","keywords":["BAMBINIxLAPACE","Ucraina"],"articleSection":["BAMBINIXLAPACE"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-ucraina-le-lettere-dei-bambini-e-ragazzi-ucraini-ai-loro-sostenitori-a-distanza\/","url":"https:\/\/www.aibi.it\/ita\/bambinixlapace-ucraina-le-lettere-dei-bambini-e-ragazzi-ucraini-ai-loro-sostenitori-a-distanza\/","name":"#BAMBINIXLAPACE: Ucraina. Le lettere dei bambini e ragazzi ucraini ai loro sostenitori a distanza - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-ucraina-le-lettere-dei-bambini-e-ragazzi-ucraini-ai-loro-sostenitori-a-distanza\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-ucraina-le-lettere-dei-bambini-e-ragazzi-ucraini-ai-loro-sostenitori-a-distanza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ucraina.jpg","datePublished":"2022-10-12T05:30:57+00:00","dateModified":"2023-10-25T12:51:29+00:00","description":"Ucraina. \u201cCiao mia cara amica italiana.\u00a0Voglio dirti che sono molto felice che non ti dimentichi di me e della mia famiglia\u2026\u201d","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-ucraina-le-lettere-dei-bambini-e-ragazzi-ucraini-ai-loro-sostenitori-a-distanza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/bambinixlapace-ucraina-le-lettere-dei-bambini-e-ragazzi-ucraini-ai-loro-sostenitori-a-distanza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-ucraina-le-lettere-dei-bambini-e-ragazzi-ucraini-ai-loro-sostenitori-a-distanza\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ucraina.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ucraina.jpg","width":1200,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-ucraina-le-lettere-dei-bambini-e-ragazzi-ucraini-ai-loro-sostenitori-a-distanza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"BAMBINIXLAPACE","item":"https:\/\/www.aibi.it\/ita\/category\/bambinixlapace\/"},{"@type":"ListItem","position":3,"name":"#BAMBINIXLAPACE: Ucraina. Le lettere dei bambini e ragazzi ucraini ai loro sostenitori a distanza"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:58:11","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/205655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=205655"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/205655\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/205656"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=205655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=205655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=205655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}