﻿


{"id":205757,"date":"2022-10-14T07:30:10","date_gmt":"2022-10-14T05:30:10","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=205757"},"modified":"2023-10-25T14:51:28","modified_gmt":"2023-10-25T12:51:28","slug":"bambinixlapace-perche-un-adozione-a-distanza-per-i-bambini-dellucraina","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/bambinixlapace-perche-un-adozione-a-distanza-per-i-bambini-dellucraina\/","title":{"rendered":"BAMBINIXLAPACE. Perch\u00e9 un&#8217; Adozione a Distanza per i bambini dell\u2019Ucraina?"},"content":{"rendered":"<h2 style=\"font-weight: 400;\"><strong>Nei Punti Ai.Bi. a fare la differenza sono le persone. Il rapporto che si instaura tra operatori e famiglie. E&#8217; davvero importante il lavoro svolto quotidianamente dagli psicologi presenti nelle strutture sia con i bambini, sia con gli altri membri della famiglia<\/strong><\/h2>\n<p style=\"font-weight: 400;\">Mentre le bombe continuano a cadere sulla povera\u00a0<strong>Ucraina<\/strong>\u00a0gettando nell\u2019angoscia e nel dolore uomini, donne e bambini che chiedono a gran voce la pace, continuano senza sosta, nel Paese, le attivit\u00e0 del\u00a0progetto di Ai.Bi.\u00a0<strong>BAMBINIXLAPACE<\/strong>, a sostegno dei minori vittime della guerra e delle loro famiglie.<\/p>\n<p style=\"font-weight: 400;\">Ai.Bi., infatti, come ormai abbiamo imparato a conoscere, ha allestito in Ucraina i\u00a0<strong>Punti Ai.Bi.<\/strong>\u00a0luoghi sicuri e colorati, dove i bambini possono trascorrere momenti di\u00a0<strong>serenit\u00e0<\/strong>, in compagnia di altri bambini e di educatori, animatori e personale specializzato, per cercare di alleviare i traumi della guerra.\u00a0In questi luoghi, i minori, ma anche le loro famiglie, possono trovare uno spazio di accoglienza dove essere supportati psicologicamente e momenti di serenit\u00e0, dove poter continuare &#8220;ad essere bambini&#8221; seppure attorno impazza la guerra degli adulti.<\/p>\n<p>Il progetto attualmente\u00a0\u00e8 operativo<strong>\u00a0<\/strong>nel distretto di\u00a0<strong>Obolon, a nord di Kiev\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/aperto-primo-punto-aibi-obolon-ucraina\/\">QUI<\/a>\u00a0<\/strong><strong>e a Stepashky<\/strong>, nel distretto di\u00a0<strong>Vinnytsia<\/strong>, a circa 300 km a sud \u2013 ovest della capitale.\u00a0<strong><a href=\"https:\/\/www.aibi.it\/ita\/punto-aibi-stepashky-ucraina-bambinixlapace\/\">QUI<\/a><\/strong><\/p>\n<h3><\/h3>\n<h3 style=\"font-weight: 400;\"><strong>Nei Punti Ai.Bi. i bambini tornano ad essere bambini, almeno per un momento\u2026<\/strong><\/h3>\n<p style=\"font-weight: 400;\">All\u2019interno del Punto Ai.Bi. di Obolon, ci sono due stanze,\u00a0<strong>una ludoteca,\u00a0<\/strong><strong>che permette ai bambini, di giocare, disegnare ed esprimere la propria creativit\u00e0 e<\/strong><strong>\u00a0una palestra,\u00a0<\/strong><strong>per dare sfogo a tutta la loro energia.<\/strong><\/p>\n<p style=\"font-weight: 400;\">Nel\u00a0<strong>villaggio di Stepashky,\u00a0<\/strong><strong>invece<\/strong>, il Punto Ai.Bi. sorge in una scuola mezzo al verde. Ci\u00f2 offre ai ragazzi la possibilit\u00e0 di stare all\u2019aperto, quando il tempo \u00e8 bello, e di potersi rifugiare in ludoteca, quando fuori fa freddo o piove.<\/p>\n<p style=\"font-weight: 400;\">Ai minori piace molto poter godere di uno spazio accogliente, dove giocare liberamente, ridere, parlare a voce alta, correre, a volte gridare e anche piangere. Dove poter\u00a0<strong>non nascondere le proprie emozioni.<\/strong><\/p>\n<h3><\/h3>\n<h3 style=\"font-weight: 400;\"><strong><b>L\u2019esperienza dei Punti Ai.Bi. non nasce dall&#8217;Ucraina, ma arriva da lontano.<\/b><\/strong><\/h3>\n<p style=\"font-weight: 400;\"><strong><span style=\"font-weight: 400;\">Arriva dalle guerre nei Balcani, che ferirono al cuore la popolazione durante gli anni 90. L\u00ec. in quei luoghi, appesantiti dalle macerie dell&#8217;odio e della guerra,\u00a0 Ai.Bi.\u00a0<\/span><br style=\"font-weight: 400;\" \/><span style=\"font-weight: 400;\">inizi\u00f2 un paziente\u00a0<\/span><b>processo di\u00a0 tessitura di legami tra comunit\u00e0 diverse<\/b><span style=\"font-weight: 400;\">\u00a0coinvolgendo i bambini e gli adolescenti che con maggiori probabilit\u00e0 di successo potevano imparare a convivere nelle diversit\u00e0, negli opposti.\u00a0<\/span><span style=\"font-weight: 400;\">Kosovo, Albania, Bosnia Erzegovina furono i Paesi costellati dai Punti Ai.Bi.\u00a0<\/span><\/strong><\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"font-weight: 400;\"><strong>Sono davvero tante le attivit\u00e0 che gli operatori di Ai.Bi. riescono ad organizzare per i bambini<\/strong><\/h3>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Nei Punti Ai.Bi. a fare la differenza sono le persone. Il rapporto che si instaura tra operatori e famiglie. E&#8217; davvero importante\u00a0il lavoro svolto quotidianamente in Ucraina dagli operatori e<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><strong>dagli psicologi<\/strong><span style=\"font-weight: 400;\">\u00a0<\/span><span style=\"font-weight: 400;\">presenti nelle strutture sia con i bambini,\u00a0che devono vivere la propria infanzia, tra le atrocit\u00e0 della guerra<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><a style=\"font-weight: 400;\" href=\"https:\/\/www.aibi.it\/ita\/bambinixlapace-ucraina-aiutare-i-bambini-a-vedere-cosa-ce-al-di-la-della-guerra\/\">QUI<\/a><span style=\"font-weight: 400;\">,\u00a0sia con gli altri membri della famiglia. Il loro compito \u00e8 quello di permettere agli adulti di scaricare lo stress, di trovare una voce amica e di andare avanti, anche con il peso sul cuore<\/span><span style=\"font-weight: 400;\">\u00a0della perdita di una persona cara<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><a style=\"font-weight: 400;\" href=\"https:\/\/www.aibi.it\/ita\/bambinixlapace-ucraina-come-sopportare-il-dolore-per-la-perdita-di-una-persona-cara\/\">QUI<\/a><\/p>\n<p style=\"font-weight: 400;\">Ora che l&#8217;inverno velocemente si avvicina, Ai.Bi. non lascer\u00e0 soli bambini e famiglie, ma, grazie al progetto BAMBINIXLAPACE, garantir\u00e0 assistenza, cura e protezione alla popolazione ucraina, sfollata e residente, con particolare riferimento ai gruppi pi\u00f9 vulnerabili di donne e minori, attraverso la distribuzione di cibo\u00a0e di beni di prima necessit\u00e0 come\u00a0\u00a0<span style=\"font-weight: 400;\">kit food, kit igienico-sanitario, kit scuola e kit winter, senza tralasciare il sostegno psicologico e sociale per i pi\u00f9 vulnerabili.<\/span><\/p>\n<p style=\"font-weight: 400;\">Ma i bambini, anche sotto le bombe, devono, per quanto \u00e8 possibile, <strong>continuare ad avere il diritto di vivere la propria infanzia e scaricare il trauma della guerra anche attraverso il gioco<\/strong>. Ecco allora che nei Punti Ai.Bi. i nostri operatori accompagnano quotidianamente i bambini in uno spazio di gioia e serenit\u00e0, attraverso l&#8217;organizzazione di attivit\u00e0 ludiche, artistiche, musicali, fino a sessioni di carattere\u00a0meditativo per cercare di alleviare lo stress, come il QI GONG\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/ucraina-punto-ai-bi-di-obolon-kiev-meditazione-e-qui-gong-per-dimenticare-la-guerra\/\">QUI<\/a><\/p>\n<p style=\"font-weight: 400;\">Tutte queste attivit\u00e0 Ai.Bi. riesce a portarle avanti grazie al prezioso sostegno del progetto\u00a0<strong>BAMBINIXLAPACE<\/strong>.<\/p>\n<h3><\/h3>\n<h3 style=\"font-weight: 400;\"><strong>Sostieni anche tu la campagna di Ai.Bi. BAMBINIXLAPACE<\/strong><\/h3>\n<p style=\"font-weight: 400;\">Ai.Bi. \u2013 Amici dei bambini ha messo in campo una\u00a0campagna dedicata alla crisi ucraina:<a href=\"https:\/\/www.aibi.it\/ita\/bambinixlapace\">\u00a0BAMBINIxLAPACE<\/a>, alla quale anche tu puoi aderire attivando\u00a0<strong>un\u2019Adozione a Distanza per i minori dell\u2019Ucraina.<\/strong>\u00a0Bastano 0,83 centesimi al giorno.<\/p>\n<p style=\"font-weight: 400;\">Oggi\u00a0aiutare un bambino ucraino in fuga dalla guerra,\u00a0significa tenere viva la sua speranza che la guerra non \u00e8 l\u2019ultima parola della sua vita e che anche per lui ci sar\u00e0 un futuro sereno nella sua terra.<\/p>\n<p style=\"font-weight: 400;\">\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*197331-start*\/\n#btnsx-197331{margin-top:0px;margin-bottom:25px;margin-left:0px;margin-right:0px;padding-top:16px;padding-bottom:15px;padding-left:43px;padding-right:44px;}\n#btnsx-197331 .btnsx-text-primary{text-transform:uppercase;font-size:20px;line-height:20px;font-weight:800;font-family:Raleway;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-197331:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-197331{background-color:#dd3333!important;}\n#btnsx-197331:hover{background-color:#d13030!important;}\n#btnsx-197331{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px;}\n#btnsx-197331:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:solid;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px;}\n#btnsx-197331{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-197331:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*197331-end*\/\n<\/style>\n<a href=\"https:\/\/dona.aibi.it\/emergenza-ucraina\/?act=cplt&amp;origine=web-button-in-post\" id=\"btnsx-197331\" class=\"btnsx-btn btnsx-btn-block\"  data-font-primary=\"Raleway\">\n\t<span class=\"btnsx-text-primary \">EMERGENZA UCRAINA<\/span><\/a>\n\n<!-- Buttons X - End -->\n\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">\n","protected":false},"excerpt":{"rendered":"<p>Nei Punti Ai.Bi. a fare la differenza sono le persone. Il rapporto che si instaura tra operatori e famiglie. E&rsquo; davvero importante il lavoro svolto quotidianamente dagli psicologi presenti nelle strutture sia con i bambini, sia con gli altri membri della famiglia Mentre le bombe continuano a cadere sulla povera&nbsp;Ucraina&nbsp;gettando [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":201089,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[909],"tags":[895,423],"class_list":["post-205757","post","type-post","status-publish","format-standard","has-post-thumbnail","category-bambinixlapace","tag-bambinixlapace","tag-ucraina"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>BAMBINIXLAPACE. Perch\u00e9 un&#039; Adozione a Distanza per i bambini dell\u2019Ucraina? - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Ucraina. Nei Punti Ai.Bi. a fare la differenza sono le persone. Il rapporto che si instaura tra operatori e famiglie. E&#039; davvero importante il lavoro svolto quotidianamente dagli psicologi presenti nelle strutture sia con i bambini, sia con gli altri membri della famiglia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/bambinixlapace-perche-un-adozione-a-distanza-per-i-bambini-dellucraina\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BAMBINIXLAPACE. Perch\u00e9 un&#039; Adozione a Distanza per i bambini dell\u2019Ucraina?\" \/>\n<meta property=\"og:description\" content=\"Ucraina. Nei Punti Ai.Bi. a fare la differenza sono le persone. Il rapporto che si instaura tra operatori e famiglie. E&#039; davvero importante il lavoro svolto quotidianamente dagli psicologi presenti nelle strutture sia con i bambini, sia con gli altri membri della famiglia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/bambinixlapace-perche-un-adozione-a-distanza-per-i-bambini-dellucraina\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-14T05:30:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-25T12:51:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/punto-AiBi-Obolon-Ucraina.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-perche-un-adozione-a-distanza-per-i-bambini-dellucraina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-perche-un-adozione-a-distanza-per-i-bambini-dellucraina\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"BAMBINIXLAPACE. Perch\u00e9 un&#8217; Adozione a Distanza per i bambini dell\u2019Ucraina?\",\"datePublished\":\"2022-10-14T05:30:10+00:00\",\"dateModified\":\"2023-10-25T12:51:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-perche-un-adozione-a-distanza-per-i-bambini-dellucraina\\\/\"},\"wordCount\":793,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-perche-un-adozione-a-distanza-per-i-bambini-dellucraina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/06\\\/punto-AiBi-Obolon-Ucraina.jpg\",\"keywords\":[\"BAMBINIxLAPACE\",\"Ucraina\"],\"articleSection\":[\"BAMBINIXLAPACE\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-perche-un-adozione-a-distanza-per-i-bambini-dellucraina\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-perche-un-adozione-a-distanza-per-i-bambini-dellucraina\\\/\",\"name\":\"BAMBINIXLAPACE. Perch\u00e9 un' Adozione a Distanza per i bambini dell\u2019Ucraina? - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-perche-un-adozione-a-distanza-per-i-bambini-dellucraina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-perche-un-adozione-a-distanza-per-i-bambini-dellucraina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/06\\\/punto-AiBi-Obolon-Ucraina.jpg\",\"datePublished\":\"2022-10-14T05:30:10+00:00\",\"dateModified\":\"2023-10-25T12:51:28+00:00\",\"description\":\"Ucraina. Nei Punti Ai.Bi. a fare la differenza sono le persone. Il rapporto che si instaura tra operatori e famiglie. E' davvero importante il lavoro svolto quotidianamente dagli psicologi presenti nelle strutture sia con i bambini, sia con gli altri membri della famiglia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-perche-un-adozione-a-distanza-per-i-bambini-dellucraina\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-perche-un-adozione-a-distanza-per-i-bambini-dellucraina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-perche-un-adozione-a-distanza-per-i-bambini-dellucraina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/06\\\/punto-AiBi-Obolon-Ucraina.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/06\\\/punto-AiBi-Obolon-Ucraina.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-perche-un-adozione-a-distanza-per-i-bambini-dellucraina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BAMBINIXLAPACE\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/bambinixlapace\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BAMBINIXLAPACE. Perch\u00e9 un&#8217; Adozione a Distanza per i bambini dell\u2019Ucraina?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"BAMBINIXLAPACE. Perch\u00e9 un' Adozione a Distanza per i bambini dell\u2019Ucraina? - Ai.Bi. Amici dei Bambini","description":"Ucraina. Nei Punti Ai.Bi. a fare la differenza sono le persone. Il rapporto che si instaura tra operatori e famiglie. E' davvero importante il lavoro svolto quotidianamente dagli psicologi presenti nelle strutture sia con i bambini, sia con gli altri membri della famiglia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/bambinixlapace-perche-un-adozione-a-distanza-per-i-bambini-dellucraina\/","og_locale":"it_IT","og_type":"article","og_title":"BAMBINIXLAPACE. Perch\u00e9 un' Adozione a Distanza per i bambini dell\u2019Ucraina?","og_description":"Ucraina. Nei Punti Ai.Bi. a fare la differenza sono le persone. Il rapporto che si instaura tra operatori e famiglie. E' davvero importante il lavoro svolto quotidianamente dagli psicologi presenti nelle strutture sia con i bambini, sia con gli altri membri della famiglia","og_url":"https:\/\/www.aibi.it\/ita\/bambinixlapace-perche-un-adozione-a-distanza-per-i-bambini-dellucraina\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2022-10-14T05:30:10+00:00","article_modified_time":"2023-10-25T12:51:28+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/punto-AiBi-Obolon-Ucraina.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-perche-un-adozione-a-distanza-per-i-bambini-dellucraina\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-perche-un-adozione-a-distanza-per-i-bambini-dellucraina\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"BAMBINIXLAPACE. Perch\u00e9 un&#8217; Adozione a Distanza per i bambini dell\u2019Ucraina?","datePublished":"2022-10-14T05:30:10+00:00","dateModified":"2023-10-25T12:51:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-perche-un-adozione-a-distanza-per-i-bambini-dellucraina\/"},"wordCount":793,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-perche-un-adozione-a-distanza-per-i-bambini-dellucraina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/punto-AiBi-Obolon-Ucraina.jpg","keywords":["BAMBINIxLAPACE","Ucraina"],"articleSection":["BAMBINIXLAPACE"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-perche-un-adozione-a-distanza-per-i-bambini-dellucraina\/","url":"https:\/\/www.aibi.it\/ita\/bambinixlapace-perche-un-adozione-a-distanza-per-i-bambini-dellucraina\/","name":"BAMBINIXLAPACE. Perch\u00e9 un' Adozione a Distanza per i bambini dell\u2019Ucraina? - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-perche-un-adozione-a-distanza-per-i-bambini-dellucraina\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-perche-un-adozione-a-distanza-per-i-bambini-dellucraina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/punto-AiBi-Obolon-Ucraina.jpg","datePublished":"2022-10-14T05:30:10+00:00","dateModified":"2023-10-25T12:51:28+00:00","description":"Ucraina. Nei Punti Ai.Bi. a fare la differenza sono le persone. Il rapporto che si instaura tra operatori e famiglie. E' davvero importante il lavoro svolto quotidianamente dagli psicologi presenti nelle strutture sia con i bambini, sia con gli altri membri della famiglia","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-perche-un-adozione-a-distanza-per-i-bambini-dellucraina\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/bambinixlapace-perche-un-adozione-a-distanza-per-i-bambini-dellucraina\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-perche-un-adozione-a-distanza-per-i-bambini-dellucraina\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/punto-AiBi-Obolon-Ucraina.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/06\/punto-AiBi-Obolon-Ucraina.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-perche-un-adozione-a-distanza-per-i-bambini-dellucraina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"BAMBINIXLAPACE","item":"https:\/\/www.aibi.it\/ita\/category\/bambinixlapace\/"},{"@type":"ListItem","position":3,"name":"BAMBINIXLAPACE. Perch\u00e9 un&#8217; Adozione a Distanza per i bambini dell\u2019Ucraina?"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:56:39","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/205757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=205757"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/205757\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/201089"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=205757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=205757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=205757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}