﻿


{"id":206080,"date":"2022-10-25T07:30:18","date_gmt":"2022-10-25T05:30:18","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=206080"},"modified":"2022-10-25T16:20:49","modified_gmt":"2022-10-25T14:20:49","slug":"ghana-lotta-dispersione-scolastica","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/ghana-lotta-dispersione-scolastica\/","title":{"rendered":"Ghana. La fondamentale lotta alla dispersione scolastica in un Paese con quasi 8 milioni di analfabeti"},"content":{"rendered":"<h2>Tra le attivit\u00e0 portate avanti da Ai.Bi. in Ghana, nell\u2019ambito del progetto Home finanziato dalla CAI, c\u2019\u00e8 la lotta alla dispersione scolastica, fondata su un grande lavoro di sostegno psicologico e di consulenza per i minori<\/h2>\n<p><!--more--><\/p>\n<p>In Ghana, contrariamente a quanto accade da noi, la popolazione \u00e8 in costante e velocissima crescita, tanto da essere raddoppiata nel corso degli ultimi 30 anni, arrivando a superare, oggi, quota <strong>31 milioni di persone<\/strong>. Purtroppo, secondo l\u2019ultimo studio sull\u2019analfabetismo condotto dal Servizio Statistico del Ghana, <strong>7,9 milioni di questi sono analfabeti<\/strong>. Un numero enorme, che si fa ancora pi\u00f9 drammatico se si considera che si riferisce, chiaramente, solo alle persone maggiori di sei anni e, dunque, da rapportare a un totale di circa 28 milioni di abitanti, ovvero quelli che contava il Paese nel 2016 (sei anni fa). Il rapporto aggiunge la considerazione di come il fenomeno dell\u2019analfabetismo sia <strong>in aumento<\/strong>, con 1,2 milioni di adulti analfabeti maggiori di 15 anni in pi\u00f9 rispetto a quanti erano nel 2010.<br \/>\nAnche nei confronti degli altri Paesi sub-sahariani di reddito medio-basso il Ghana appare particolarmente in difficolt\u00e0, nonostante le disposizioni sull\u2019analfabetismo emanate ormai dal 2018 nel Piano Strategico per l\u2019Istruzione.<\/p>\n<div id='gallery-1' class='gallery galleryid-206080 gallery-columns-2 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/ghana_sostegno_psicologico_abbandono_scolastico4\/'><img loading=\"lazy\" decoding=\"async\" width=\"572\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ghana_sostegno_psicologico_abbandono_scolastico4-572x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ghana_sostegno_psicologico_abbandono_scolastico4-572x300.jpg 572w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ghana_sostegno_psicologico_abbandono_scolastico4-150x79.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ghana_sostegno_psicologico_abbandono_scolastico4-768x403.jpg 768w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ghana_sostegno_psicologico_abbandono_scolastico4.jpg 1200w\" sizes=\"auto, (max-width: 572px) 100vw, 572px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/ghana_sostegno_psicologico_abbandono_scolastico5\/'><img loading=\"lazy\" decoding=\"async\" width=\"572\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ghana_sostegno_psicologico_abbandono_scolastico5-572x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ghana_sostegno_psicologico_abbandono_scolastico5-572x300.jpg 572w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ghana_sostegno_psicologico_abbandono_scolastico5-150x79.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ghana_sostegno_psicologico_abbandono_scolastico5-768x403.jpg 768w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ghana_sostegno_psicologico_abbandono_scolastico5.jpg 1200w\" sizes=\"auto, (max-width: 572px) 100vw, 572px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/ghana_sostegno_psicologico_abbandono_scolastico3\/'><img loading=\"lazy\" decoding=\"async\" width=\"571\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ghana_sostegno_psicologico_abbandono_scolastico3-571x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ghana_sostegno_psicologico_abbandono_scolastico3-571x300.jpg 571w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ghana_sostegno_psicologico_abbandono_scolastico3-150x79.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ghana_sostegno_psicologico_abbandono_scolastico3-768x403.jpg 768w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ghana_sostegno_psicologico_abbandono_scolastico3.jpg 1200w\" sizes=\"auto, (max-width: 571px) 100vw, 571px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.aibi.it\/ita\/ghana_sostegno_psicologico_abbandono_scolastico2\/'><img loading=\"lazy\" decoding=\"async\" width=\"571\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ghana_sostegno_psicologico_abbandono_scolastico2-571x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ghana_sostegno_psicologico_abbandono_scolastico2-571x300.jpg 571w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ghana_sostegno_psicologico_abbandono_scolastico2-150x79.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ghana_sostegno_psicologico_abbandono_scolastico2-768x403.jpg 768w, https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ghana_sostegno_psicologico_abbandono_scolastico2.jpg 1200w\" sizes=\"auto, (max-width: 571px) 100vw, 571px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<h3>Le attivit\u00e0 di Ai.Bi. per la lotta all\u2019abbandono scolastico<\/h3>\n<p>Sull\u2019importanza dell\u2019alfabetismo non c\u2019\u00e8 molto da aggiungere rispetto a quello che universalmente \u00e8 gi\u00e0 noto, ovvero di come la possibilit\u00e0 di avere un futuro migliore, in qualsiasi Paese e societ\u00e0 del mondo ma a maggior ragione in Paesi particolarmente poveri, passi inevitabilmente dall\u2019<strong>accesso all\u2019istruzione<\/strong>. Per questo, all\u2019interno del progetto <a href=\"https:\/\/www.aibi.it\/ita\/parte-il-progetto-home-ghana-costa-davorio-sierra-leone-un-network-per-laccoglienza-e-leducazione-di-minori-vulnerabili-ai-bi-referente-delle-operazioni-in-g\/\">HOME<\/a> finanziato dalla CAI (Commissione Adozioni Internazionali) e coordinato da Ai.Bi. in Ghana, uno dei principali obiettivi \u00e8 la <strong>lotta all\u2019abbandono scolastico<\/strong>. Tra le attivit\u00e0 attraverso le quali il discorso viene portato avanti c\u2019\u00e8 anche quella del <strong>sostegno psicologico<\/strong> e della <strong>consulenza<\/strong> nei confronti dei bambini al fine di incoraggiare la frequenza scolastica.<br \/>\nIn particolare, la psicologa del progetto sta lavorando in questo senso con i minori del Don Bosco &#8211; Child Protection Center (CPC), facendosi promotrice in prima persona di <strong>buone relazioni<\/strong> tra e con i minori. Attraverso sedute individuali, la psicologa esplora le\u201csimpatie\u201d e le \u201cantipatie\u201d dei bambini e li aiuta ad adattarsi mettendo in atto meccanismi di coping (semplificando enormemente, tutte le strategia che gli individui possono mettere in atto per fronteggiare problemi e circostanza spiacevoli o situazioni di forte stress), accompagnandoli nello studio e, pi\u00f9 in generale, cercando di conoscerli meglio e di instaurare con loro un dialogo proficuo per capire quali siano le loro aspirazioni per il futuro.<br \/>\nI bambini seguiti dalla psicologa nei mesi passati si sono dimostrati <strong>collaborativi e disponibili<\/strong> al dialogo. Il buon clima comunicativo creatosi ha coinvolto anche lo staff del centro, gli insegnanti, gli assistenti sociali e la direzione, con benefici per tutti.<br \/>\nUn risultato ulteriore da segnalare \u00e8 che dei 13 ragazzi seguiti nel mese di agosto dalla psicologa, uno \u00e8 stato reintegrato in famiglia e ha lasciato l\u2019orfanotrofio.<\/p>\n<h3>Aiuta anche tu le attivit\u00e0 di Ai.Bi. in Ghana<\/h3>\n<p>Tutti possono sostenere le diverse attivit\u00e0 portate avanti da Ai.Bi. in Ghana attraverso una <a href=\"https:\/\/www.aibi.it\/ita\/sostieni-aibi\/donazione-libera\/\"><strong>donazione libera<\/strong><\/a> una tantum oppure aderendo al progetto &#8220;<a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/?paese=Ghana\">Adotta a distanza i bambini degli orfanotrofi in Ghana<\/a>&#8220;, che permette di dare un sostegno continuativo nel corso del tempo a partire da soli 0,83 centesimi al giorno. Come tutte le donazioni ad Ai.Bi. anche quelle per il Ghana godono delle agevolazioni fiscali previste.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tra le attivit&agrave; portate avanti da Ai.Bi. in Ghana, nell&rsquo;ambito del progetto Home finanziato dalla CAI, c&rsquo;&egrave; la lotta alla dispersione scolastica, fondata su un grande lavoro di sostegno psicologico e di consulenza per i minori<\/p>\n","protected":false},"author":102,"featured_media":206082,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[551,511,545],"class_list":["post-206080","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cooperazione-internazionale","tag-cooperazione-internazionale","tag-ghana","tag-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ghana: lotta alla dispersione scolastica<\/title>\n<meta name=\"description\" content=\"Tra le attivit\u00e0 di Ai.Bi. nel progetto Home finanziato dalla CAI in Ghana c\u2019\u00e8 la lotta alla dispersione scolastica, fondata su sostegno psicologico e consulenza\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/ghana-lotta-dispersione-scolastica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ghana. La fondamentale lotta alla dispersione scolastica in un Paese con quasi 8 milioni di analfabeti\" \/>\n<meta property=\"og:description\" content=\"Tra le attivit\u00e0 di Ai.Bi. nel progetto Home finanziato dalla CAI in Ghana c\u2019\u00e8 la lotta alla dispersione scolastica, fondata su sostegno psicologico e consulenza\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/ghana-lotta-dispersione-scolastica\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-25T05:30:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-25T14:20:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ghana_sostegno_psicologico_abbandono_scolastico.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lotta-dispersione-scolastica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lotta-dispersione-scolastica\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Ghana. La fondamentale lotta alla dispersione scolastica in un Paese con quasi 8 milioni di analfabeti\",\"datePublished\":\"2022-10-25T05:30:18+00:00\",\"dateModified\":\"2022-10-25T14:20:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lotta-dispersione-scolastica\\\/\"},\"wordCount\":583,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lotta-dispersione-scolastica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/10\\\/Ghana_sostegno_psicologico_abbandono_scolastico.jpeg\",\"keywords\":[\"cooperazione internazionale\",\"Ghana\",\"scuola\"],\"articleSection\":[\"Cooperazione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lotta-dispersione-scolastica\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lotta-dispersione-scolastica\\\/\",\"name\":\"Ghana: lotta alla dispersione scolastica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lotta-dispersione-scolastica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lotta-dispersione-scolastica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/10\\\/Ghana_sostegno_psicologico_abbandono_scolastico.jpeg\",\"datePublished\":\"2022-10-25T05:30:18+00:00\",\"dateModified\":\"2022-10-25T14:20:49+00:00\",\"description\":\"Tra le attivit\u00e0 di Ai.Bi. nel progetto Home finanziato dalla CAI in Ghana c\u2019\u00e8 la lotta alla dispersione scolastica, fondata su sostegno psicologico e consulenza\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lotta-dispersione-scolastica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lotta-dispersione-scolastica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lotta-dispersione-scolastica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/10\\\/Ghana_sostegno_psicologico_abbandono_scolastico.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/10\\\/Ghana_sostegno_psicologico_abbandono_scolastico.jpeg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lotta-dispersione-scolastica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cooperazione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/cooperazione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ghana. La fondamentale lotta alla dispersione scolastica in un Paese con quasi 8 milioni di analfabeti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ghana: lotta alla dispersione scolastica","description":"Tra le attivit\u00e0 di Ai.Bi. nel progetto Home finanziato dalla CAI in Ghana c\u2019\u00e8 la lotta alla dispersione scolastica, fondata su sostegno psicologico e consulenza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/ghana-lotta-dispersione-scolastica\/","og_locale":"it_IT","og_type":"article","og_title":"Ghana. La fondamentale lotta alla dispersione scolastica in un Paese con quasi 8 milioni di analfabeti","og_description":"Tra le attivit\u00e0 di Ai.Bi. nel progetto Home finanziato dalla CAI in Ghana c\u2019\u00e8 la lotta alla dispersione scolastica, fondata su sostegno psicologico e consulenza","og_url":"https:\/\/www.aibi.it\/ita\/ghana-lotta-dispersione-scolastica\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2022-10-25T05:30:18+00:00","article_modified_time":"2022-10-25T14:20:49+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ghana_sostegno_psicologico_abbandono_scolastico.jpeg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/ghana-lotta-dispersione-scolastica\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-lotta-dispersione-scolastica\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Ghana. La fondamentale lotta alla dispersione scolastica in un Paese con quasi 8 milioni di analfabeti","datePublished":"2022-10-25T05:30:18+00:00","dateModified":"2022-10-25T14:20:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-lotta-dispersione-scolastica\/"},"wordCount":583,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-lotta-dispersione-scolastica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ghana_sostegno_psicologico_abbandono_scolastico.jpeg","keywords":["cooperazione internazionale","Ghana","scuola"],"articleSection":["Cooperazione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/ghana-lotta-dispersione-scolastica\/","url":"https:\/\/www.aibi.it\/ita\/ghana-lotta-dispersione-scolastica\/","name":"Ghana: lotta alla dispersione scolastica","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-lotta-dispersione-scolastica\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-lotta-dispersione-scolastica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ghana_sostegno_psicologico_abbandono_scolastico.jpeg","datePublished":"2022-10-25T05:30:18+00:00","dateModified":"2022-10-25T14:20:49+00:00","description":"Tra le attivit\u00e0 di Ai.Bi. nel progetto Home finanziato dalla CAI in Ghana c\u2019\u00e8 la lotta alla dispersione scolastica, fondata su sostegno psicologico e consulenza","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-lotta-dispersione-scolastica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/ghana-lotta-dispersione-scolastica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/ghana-lotta-dispersione-scolastica\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ghana_sostegno_psicologico_abbandono_scolastico.jpeg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/Ghana_sostegno_psicologico_abbandono_scolastico.jpeg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/ghana-lotta-dispersione-scolastica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Cooperazione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/cooperazione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Ghana. La fondamentale lotta alla dispersione scolastica in un Paese con quasi 8 milioni di analfabeti"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 07:21:12","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/206080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=206080"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/206080\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/206082"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=206080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=206080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=206080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}