﻿{"id":206204,"date":"2022-11-01T07:30:36","date_gmt":"2022-11-01T06:30:36","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=206204"},"modified":"2022-10-28T12:49:37","modified_gmt":"2022-10-28T10:49:37","slug":"affido-piemonte-allontanamento-zero-approvato-il-disegno-di-legge-che-ha-spaccato-in-due-lopinione-pubblica","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/affido-piemonte-allontanamento-zero-approvato-il-disegno-di-legge-che-ha-spaccato-in-due-lopinione-pubblica\/","title":{"rendered":"Affido. Piemonte: \u201cAllontanamento zero\u201d approvato il disegno di legge che ha spaccato in due l\u2019opinione pubblica"},"content":{"rendered":"<h2><strong>Jo\u00eblle Long<\/strong>, <strong>esperta di diritto minorile e docente all\u2019Universit\u00e0 di Torino: \u201cSi passa dalla proclamazione del diritto del bambino a crescere in una famiglia al diritto dei genitori a crescere i propri figli\u201d<\/strong><\/h2>\n<p>Nei giorni scorsi \u00e8 stato approvato dal <strong>Consiglio regionale del Piemonte<\/strong>, il disegno di legge \u201c<strong><em>Allontanamento zero<\/em><\/strong>\u201d proposto dall\u2019assessore all\u2019infanzia <strong>Chiara Caucino<\/strong> e riguardante \u00ab<em>interventi a sostegno della genitorialit\u00e0 e norme per la prevenzione degli allontanamenti<\/em><em> dal nucleo famigliare d\u2019origine<\/em><em>\u00bb.<\/em> La nuova legge, si apprende da <strong><em>Avvenire<\/em><\/strong>: \u201c<em>si propone di sostenere con <strong>aiuti mirati<\/strong>, di tipo economico ed educativo, i minori pi\u00f9 fragili, che hanno alla spalle famiglie disgregate\u201d.<\/em><\/p>\n<p>Una proposta di legge, approvata con 29 s\u00ec e 14 no, ricorda <strong><em>Vita<\/em><\/strong>, che era stata presentata: \u201ca dicembre 2019 sulla scia della vicenda Bibbiano\u201d e per la quale, l\u2019assessore Caucino ha sostenuto <strong>l\u2019urgenza<\/strong> poich\u00e9, come riporta il <strong><em>Corriere della Sera di Torino<\/em><\/strong>: \u201cspesso i bambini affidati alle comunit\u00e0 dei minori vivono in condizioni di precariet\u00e0 e sostanziale trascuratezza\u201d.<\/p>\n<h3><strong>Una legge che ha spaccato in due l\u2019opinione pubblica, tra favorevoli e contrari.<\/strong><\/h3>\n<p>Da una parte l\u2019assessore Caucino (Lega) che sottolinea come \u201c<strong><em>Allontanamento Zero<\/em><\/strong>\u201d non sia un provvedimento di un determinato \u201c<em>colore politico<\/em>&#8221; ma, riporta il noto quotidiano, vada invece: \u201c<em>nell\u2019interesse dei minori introducendo finalmente un preciso dettato legislativo di supporto alle famiglie di origine, rispettando il \u2018diritto naturale\u2019 dei minori di poter vivere nel nucleo originario\u201d.<\/em><\/p>\n<p>Dall\u2019altra chi invece ritenga, come <strong>Domenico Rossi<\/strong>, (Pd) vice presidente della commissione Sanit\u00e0, politiche e sociali e politiche per gli anziani come queste dichiarazioni abbiano: \u201c<em>fatto cadere tutte le maschere: attacchi sguaiati ai servizi sociali e alla magistratura che, secondo le parole dei consiglieri di maggioranza e dell\u2019assessora strappano i bambini alle famiglie con violenza e per futili motivi<\/em>. <em>Tutto questo sulla pelle dei bambini, delle famiglie, degli operatori e dell\u2019intero sistema di sostegno a minori e famiglie costruito in Piemonte in tanti anni<\/em> [\u2026]\u201d.<\/p>\n<p>La professoressa <strong>Jo\u00eblle Long<\/strong>, esperta di diritto minorile e docente all\u2019Universit\u00e0 di Torino interpellata dal <em>web magazine Vita<\/em> in un\u2019intervista ha commentato con una nota negativa il provvedimento:<\/p>\n<p>\u201c<em>Il punto di partenza<\/em> \u2013 spiega la Long- <em>\u00e8 condivisibile, ridurre gli allontanamenti in modo da attuare pienamente <strong>il dritto del bambino a crescere nella propria famiglia e ad esserne allontanato solo nei casi strettamente necessari per la sua protezione<\/strong>. Questo principio \u00e8 peraltro pacifico e gi\u00e0 scritto nel diritto internazionale e nazionale. Ci\u00f2 che <strong>non \u00e8 condivisibile \u00e8 la strada indicata dal disegno<\/strong> di legge per attuare questo diritto del minore. L\u2019analisi del disegno di legge ne mostra l\u2019impronta adultocentrica: si va incontro pi\u00f9 alle istanze dei genitori che lamentano gli allontanamenti che all\u2019interesse del minore, disconoscendo che in alcuni casi l\u2019allontanamento \u00e8 una necessit\u00e0 per garantire adeguata protezione al minore. <strong>Si passa dunque dalla tutela prioritaria dell\u2019interesse del minore a quella degli interessi della famiglia d\u2019origine,<\/strong> dalla proclamazione del diritto del bambino a crescere in una famiglia al diritto dei genitori a crescere i propri figli<\/em>\u201d.<\/p>\n<p><em>\u00a0<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jo&euml;lle Long, esperta di diritto minorile e docente all&rsquo;Universit&agrave; di Torino: &ldquo;Si passa dalla proclamazione del diritto del bambino a crescere in una famiglia al diritto dei genitori a crescere i propri figli&rdquo; Nei giorni scorsi &egrave; stato approvato dal Consiglio regionale del Piemonte, il disegno di legge &ldquo;Allontanamento zero&rdquo; [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":206206,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[652],"tags":[320],"class_list":["post-206204","post","type-post","status-publish","format-standard","has-post-thumbnail","category-affido","tag-affido"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Affido. Piemonte: \u201cAllontanamento zero\u201d approvato il disegno di legge che ha spaccato in due l\u2019opinione pubblica - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Affido. Jo\u00eblle Long, esperta di diritto minorile e docente all\u2019Universit\u00e0 di Torino: \u201cSi passa dalla proclamazione del diritto del bambino a crescere in una famiglia al diritto dei genitori a crescere i propri figli\u201d\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/affido-piemonte-allontanamento-zero-approvato-il-disegno-di-legge-che-ha-spaccato-in-due-lopinione-pubblica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Affido. Piemonte: \u201cAllontanamento zero\u201d approvato il disegno di legge che ha spaccato in due l\u2019opinione pubblica\" \/>\n<meta property=\"og:description\" content=\"Affido. Jo\u00eblle Long, esperta di diritto minorile e docente all\u2019Universit\u00e0 di Torino: \u201cSi passa dalla proclamazione del diritto del bambino a crescere in una famiglia al diritto dei genitori a crescere i propri figli\u201d\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/affido-piemonte-allontanamento-zero-approvato-il-disegno-di-legge-che-ha-spaccato-in-due-lopinione-pubblica\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-01T06:30:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/affido-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-piemonte-allontanamento-zero-approvato-il-disegno-di-legge-che-ha-spaccato-in-due-lopinione-pubblica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-piemonte-allontanamento-zero-approvato-il-disegno-di-legge-che-ha-spaccato-in-due-lopinione-pubblica\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"Affido. Piemonte: \u201cAllontanamento zero\u201d approvato il disegno di legge che ha spaccato in due l\u2019opinione pubblica\",\"datePublished\":\"2022-11-01T06:30:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-piemonte-allontanamento-zero-approvato-il-disegno-di-legge-che-ha-spaccato-in-due-lopinione-pubblica\\\/\"},\"wordCount\":517,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-piemonte-allontanamento-zero-approvato-il-disegno-di-legge-che-ha-spaccato-in-due-lopinione-pubblica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/10\\\/affido-4.jpg\",\"keywords\":[\"affido\"],\"articleSection\":[\"Affido &amp; Accoglienza Familiare\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-piemonte-allontanamento-zero-approvato-il-disegno-di-legge-che-ha-spaccato-in-due-lopinione-pubblica\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-piemonte-allontanamento-zero-approvato-il-disegno-di-legge-che-ha-spaccato-in-due-lopinione-pubblica\\\/\",\"name\":\"Affido. Piemonte: \u201cAllontanamento zero\u201d approvato il disegno di legge che ha spaccato in due l\u2019opinione pubblica - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-piemonte-allontanamento-zero-approvato-il-disegno-di-legge-che-ha-spaccato-in-due-lopinione-pubblica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-piemonte-allontanamento-zero-approvato-il-disegno-di-legge-che-ha-spaccato-in-due-lopinione-pubblica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/10\\\/affido-4.jpg\",\"datePublished\":\"2022-11-01T06:30:36+00:00\",\"description\":\"Affido. Jo\u00eblle Long, esperta di diritto minorile e docente all\u2019Universit\u00e0 di Torino: \u201cSi passa dalla proclamazione del diritto del bambino a crescere in una famiglia al diritto dei genitori a crescere i propri figli\u201d\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-piemonte-allontanamento-zero-approvato-il-disegno-di-legge-che-ha-spaccato-in-due-lopinione-pubblica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-piemonte-allontanamento-zero-approvato-il-disegno-di-legge-che-ha-spaccato-in-due-lopinione-pubblica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-piemonte-allontanamento-zero-approvato-il-disegno-di-legge-che-ha-spaccato-in-due-lopinione-pubblica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/10\\\/affido-4.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/10\\\/affido-4.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-piemonte-allontanamento-zero-approvato-il-disegno-di-legge-che-ha-spaccato-in-due-lopinione-pubblica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Affido &amp; Accoglienza Familiare\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/affido\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Affido. Piemonte: \u201cAllontanamento zero\u201d approvato il disegno di legge che ha spaccato in due l\u2019opinione pubblica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Affido. Piemonte: \u201cAllontanamento zero\u201d approvato il disegno di legge che ha spaccato in due l\u2019opinione pubblica - Ai.Bi. Amici dei Bambini","description":"Affido. Jo\u00eblle Long, esperta di diritto minorile e docente all\u2019Universit\u00e0 di Torino: \u201cSi passa dalla proclamazione del diritto del bambino a crescere in una famiglia al diritto dei genitori a crescere i propri figli\u201d","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/affido-piemonte-allontanamento-zero-approvato-il-disegno-di-legge-che-ha-spaccato-in-due-lopinione-pubblica\/","og_locale":"it_IT","og_type":"article","og_title":"Affido. Piemonte: \u201cAllontanamento zero\u201d approvato il disegno di legge che ha spaccato in due l\u2019opinione pubblica","og_description":"Affido. Jo\u00eblle Long, esperta di diritto minorile e docente all\u2019Universit\u00e0 di Torino: \u201cSi passa dalla proclamazione del diritto del bambino a crescere in una famiglia al diritto dei genitori a crescere i propri figli\u201d","og_url":"https:\/\/www.aibi.it\/ita\/affido-piemonte-allontanamento-zero-approvato-il-disegno-di-legge-che-ha-spaccato-in-due-lopinione-pubblica\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2022-11-01T06:30:36+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/affido-4.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/affido-piemonte-allontanamento-zero-approvato-il-disegno-di-legge-che-ha-spaccato-in-due-lopinione-pubblica\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/affido-piemonte-allontanamento-zero-approvato-il-disegno-di-legge-che-ha-spaccato-in-due-lopinione-pubblica\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"Affido. Piemonte: \u201cAllontanamento zero\u201d approvato il disegno di legge che ha spaccato in due l\u2019opinione pubblica","datePublished":"2022-11-01T06:30:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/affido-piemonte-allontanamento-zero-approvato-il-disegno-di-legge-che-ha-spaccato-in-due-lopinione-pubblica\/"},"wordCount":517,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/affido-piemonte-allontanamento-zero-approvato-il-disegno-di-legge-che-ha-spaccato-in-due-lopinione-pubblica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/affido-4.jpg","keywords":["affido"],"articleSection":["Affido &amp; Accoglienza Familiare"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/affido-piemonte-allontanamento-zero-approvato-il-disegno-di-legge-che-ha-spaccato-in-due-lopinione-pubblica\/","url":"https:\/\/www.aibi.it\/ita\/affido-piemonte-allontanamento-zero-approvato-il-disegno-di-legge-che-ha-spaccato-in-due-lopinione-pubblica\/","name":"Affido. Piemonte: \u201cAllontanamento zero\u201d approvato il disegno di legge che ha spaccato in due l\u2019opinione pubblica - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/affido-piemonte-allontanamento-zero-approvato-il-disegno-di-legge-che-ha-spaccato-in-due-lopinione-pubblica\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/affido-piemonte-allontanamento-zero-approvato-il-disegno-di-legge-che-ha-spaccato-in-due-lopinione-pubblica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/affido-4.jpg","datePublished":"2022-11-01T06:30:36+00:00","description":"Affido. Jo\u00eblle Long, esperta di diritto minorile e docente all\u2019Universit\u00e0 di Torino: \u201cSi passa dalla proclamazione del diritto del bambino a crescere in una famiglia al diritto dei genitori a crescere i propri figli\u201d","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/affido-piemonte-allontanamento-zero-approvato-il-disegno-di-legge-che-ha-spaccato-in-due-lopinione-pubblica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/affido-piemonte-allontanamento-zero-approvato-il-disegno-di-legge-che-ha-spaccato-in-due-lopinione-pubblica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/affido-piemonte-allontanamento-zero-approvato-il-disegno-di-legge-che-ha-spaccato-in-due-lopinione-pubblica\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/affido-4.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/affido-4.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/affido-piemonte-allontanamento-zero-approvato-il-disegno-di-legge-che-ha-spaccato-in-due-lopinione-pubblica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Affido &amp; Accoglienza Familiare","item":"https:\/\/www.aibi.it\/ita\/category\/affido\/"},{"@type":"ListItem","position":3,"name":"Affido. Piemonte: \u201cAllontanamento zero\u201d approvato il disegno di legge che ha spaccato in due l\u2019opinione pubblica"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 03:18:36","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/206204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=206204"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/206204\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/206206"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=206204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=206204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=206204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}