﻿


{"id":206595,"date":"2022-11-09T07:40:19","date_gmt":"2022-11-09T06:40:19","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=206595"},"modified":"2022-11-09T12:30:58","modified_gmt":"2022-11-09T11:30:58","slug":"muovere-i-primi-passi-nel-mondo-delladozione-internazionale-e-piu-semplice-con-i-webinar-faris","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/muovere-i-primi-passi-nel-mondo-delladozione-internazionale-e-piu-semplice-con-i-webinar-faris\/","title":{"rendered":"Muovere i primi passi nel mondo dell\u2019Adozione Internazionale \u00e8 pi\u00f9 semplice con i webinar FARIS"},"content":{"rendered":"<h2><strong> Il 16 novembre, alle ore 18.00, FARIS \u2013 Family Relationship International School organizza il webinar: \u201cPrimi passi nel mondo dell\u2019Adozione Internazionale\u201d<\/strong><\/h2>\n<p>La scelta di donare ad un bambino la gioia di \u201c<em>rinascere figlio<\/em>\u201d \u00e8 una decisione che in primo luogo fiorisce all\u2019interno del proprio cuore. Prima di giungere per\u00f2, all\u2019incontro con il proprio figlio, vi \u00e8 un <strong>percorso da intraprendere<\/strong>, costellato da nozioni normative da conoscere e procedure passo, passo da espletare, ma prima di tutto, occorre essere certi di aver ben compreso il significato stesso dell\u2019adozione.<\/p>\n<p>Proprio con l\u2019intento di fornire alle coppie che <strong>muovono i loro primi passi<\/strong> nel mondo dell\u2019adozione, gli <strong>strumenti<\/strong> necessari per presentare <strong>domanda di idoneit\u00e0<\/strong> per divenire genitori adottivi sia a livello nazionale che internazionale, il <strong>16 novembre, alle ore 18.00,<\/strong> FARIS \u2013 Family Relationship International School organizza il webinar: <strong>\u201cPrimi passi nel mondo dell\u2019Adozione Internazionale<\/strong>\u201d. Costo dell\u2019incontro euro <strong>10,00.<\/strong><\/p>\n<p>Ad accompagnare i presenti sar\u00e0 <strong>Alice Paolin<\/strong>, desk adozioni internazionali di Ai.Bi. \u2013 Amici dei Bambini.<\/p>\n<p>Il webinar, partendo da un\u2019analisi della normativa di riferimento per l\u2019adozione, approfondir\u00e0 quali siano\u00a0 le procedure da espletare, affrontando anche il ruolo degli enti autorizzati all\u2019adozione internazionale.<\/p>\n<p>Per informazioni e iscrizioni <a href=\"https:\/\/www.fondazioneaibi.it\/faris\/prodotto\/webinar-primi-passi-nel-mondo-delladozione-internazionale-appuntamento-del-15-nov\/\" target=\"_blank\" rel=\"noopener\">QUI<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il 16 novembre, alle ore 18.00, FARIS &ndash; Family Relationship International School organizza il webinar: &ldquo;Primi passi nel mondo dell&rsquo;Adozione Internazionale&rdquo; La scelta di donare ad un bambino la gioia di &ldquo;rinascere figlio&rdquo; &egrave; una decisione che in primo luogo fiorisce all&rsquo;interno del proprio cuore. Prima di giungere per&ograve;, all&rsquo;incontro [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":206596,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[777],"tags":[279,718],"class_list":["post-206595","post","type-post","status-publish","format-standard","has-post-thumbnail","category-faris","tag-adozione","tag-webinar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Muovere i primi passi nel mondo dell\u2019Adozione Internazionale \u00e8 pi\u00f9 semplice con i webinar FARIS - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Adozione. Il 16 novembre, alle ore 18.00, FARIS \u2013 Family Relationship International School organizza il webinar: \u201cPrimi passi nel mondo dell\u2019Adozione Internazionale\u201d\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/muovere-i-primi-passi-nel-mondo-delladozione-internazionale-e-piu-semplice-con-i-webinar-faris\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Muovere i primi passi nel mondo dell\u2019Adozione Internazionale \u00e8 pi\u00f9 semplice con i webinar FARIS\" \/>\n<meta property=\"og:description\" content=\"Adozione. Il 16 novembre, alle ore 18.00, FARIS \u2013 Family Relationship International School organizza il webinar: \u201cPrimi passi nel mondo dell\u2019Adozione Internazionale\u201d\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/muovere-i-primi-passi-nel-mondo-delladozione-internazionale-e-piu-semplice-con-i-webinar-faris\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-09T06:40:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-09T11:30:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2022\/11\/adozione-faris.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/muovere-i-primi-passi-nel-mondo-delladozione-internazionale-e-piu-semplice-con-i-webinar-faris\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/muovere-i-primi-passi-nel-mondo-delladozione-internazionale-e-piu-semplice-con-i-webinar-faris\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"Muovere i primi passi nel mondo dell\u2019Adozione Internazionale \u00e8 pi\u00f9 semplice con i webinar FARIS\",\"datePublished\":\"2022-11-09T06:40:19+00:00\",\"dateModified\":\"2022-11-09T11:30:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/muovere-i-primi-passi-nel-mondo-delladozione-internazionale-e-piu-semplice-con-i-webinar-faris\\\/\"},\"wordCount\":212,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/muovere-i-primi-passi-nel-mondo-delladozione-internazionale-e-piu-semplice-con-i-webinar-faris\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/11\\\/adozione-faris.jpg\",\"keywords\":[\"adozione\",\"Webinar\"],\"articleSection\":[\"Faris\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/muovere-i-primi-passi-nel-mondo-delladozione-internazionale-e-piu-semplice-con-i-webinar-faris\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/muovere-i-primi-passi-nel-mondo-delladozione-internazionale-e-piu-semplice-con-i-webinar-faris\\\/\",\"name\":\"Muovere i primi passi nel mondo dell\u2019Adozione Internazionale \u00e8 pi\u00f9 semplice con i webinar FARIS - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/muovere-i-primi-passi-nel-mondo-delladozione-internazionale-e-piu-semplice-con-i-webinar-faris\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/muovere-i-primi-passi-nel-mondo-delladozione-internazionale-e-piu-semplice-con-i-webinar-faris\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/11\\\/adozione-faris.jpg\",\"datePublished\":\"2022-11-09T06:40:19+00:00\",\"dateModified\":\"2022-11-09T11:30:58+00:00\",\"description\":\"Adozione. Il 16 novembre, alle ore 18.00, FARIS \u2013 Family Relationship International School organizza il webinar: \u201cPrimi passi nel mondo dell\u2019Adozione Internazionale\u201d\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/muovere-i-primi-passi-nel-mondo-delladozione-internazionale-e-piu-semplice-con-i-webinar-faris\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/muovere-i-primi-passi-nel-mondo-delladozione-internazionale-e-piu-semplice-con-i-webinar-faris\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/muovere-i-primi-passi-nel-mondo-delladozione-internazionale-e-piu-semplice-con-i-webinar-faris\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/11\\\/adozione-faris.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/11\\\/adozione-faris.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/muovere-i-primi-passi-nel-mondo-delladozione-internazionale-e-piu-semplice-con-i-webinar-faris\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Faris\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/faris\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Muovere i primi passi nel mondo dell\u2019Adozione Internazionale \u00e8 pi\u00f9 semplice con i webinar FARIS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Muovere i primi passi nel mondo dell\u2019Adozione Internazionale \u00e8 pi\u00f9 semplice con i webinar FARIS - Ai.Bi. Amici dei Bambini","description":"Adozione. Il 16 novembre, alle ore 18.00, FARIS \u2013 Family Relationship International School organizza il webinar: \u201cPrimi passi nel mondo dell\u2019Adozione Internazionale\u201d","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/muovere-i-primi-passi-nel-mondo-delladozione-internazionale-e-piu-semplice-con-i-webinar-faris\/","og_locale":"it_IT","og_type":"article","og_title":"Muovere i primi passi nel mondo dell\u2019Adozione Internazionale \u00e8 pi\u00f9 semplice con i webinar FARIS","og_description":"Adozione. Il 16 novembre, alle ore 18.00, FARIS \u2013 Family Relationship International School organizza il webinar: \u201cPrimi passi nel mondo dell\u2019Adozione Internazionale\u201d","og_url":"https:\/\/www.aibi.it\/ita\/muovere-i-primi-passi-nel-mondo-delladozione-internazionale-e-piu-semplice-con-i-webinar-faris\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2022-11-09T06:40:19+00:00","article_modified_time":"2022-11-09T11:30:58+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2022\/11\/adozione-faris.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/muovere-i-primi-passi-nel-mondo-delladozione-internazionale-e-piu-semplice-con-i-webinar-faris\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/muovere-i-primi-passi-nel-mondo-delladozione-internazionale-e-piu-semplice-con-i-webinar-faris\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"Muovere i primi passi nel mondo dell\u2019Adozione Internazionale \u00e8 pi\u00f9 semplice con i webinar FARIS","datePublished":"2022-11-09T06:40:19+00:00","dateModified":"2022-11-09T11:30:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/muovere-i-primi-passi-nel-mondo-delladozione-internazionale-e-piu-semplice-con-i-webinar-faris\/"},"wordCount":212,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/muovere-i-primi-passi-nel-mondo-delladozione-internazionale-e-piu-semplice-con-i-webinar-faris\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/11\/adozione-faris.jpg","keywords":["adozione","Webinar"],"articleSection":["Faris"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/muovere-i-primi-passi-nel-mondo-delladozione-internazionale-e-piu-semplice-con-i-webinar-faris\/","url":"https:\/\/www.aibi.it\/ita\/muovere-i-primi-passi-nel-mondo-delladozione-internazionale-e-piu-semplice-con-i-webinar-faris\/","name":"Muovere i primi passi nel mondo dell\u2019Adozione Internazionale \u00e8 pi\u00f9 semplice con i webinar FARIS - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/muovere-i-primi-passi-nel-mondo-delladozione-internazionale-e-piu-semplice-con-i-webinar-faris\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/muovere-i-primi-passi-nel-mondo-delladozione-internazionale-e-piu-semplice-con-i-webinar-faris\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/11\/adozione-faris.jpg","datePublished":"2022-11-09T06:40:19+00:00","dateModified":"2022-11-09T11:30:58+00:00","description":"Adozione. Il 16 novembre, alle ore 18.00, FARIS \u2013 Family Relationship International School organizza il webinar: \u201cPrimi passi nel mondo dell\u2019Adozione Internazionale\u201d","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/muovere-i-primi-passi-nel-mondo-delladozione-internazionale-e-piu-semplice-con-i-webinar-faris\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/muovere-i-primi-passi-nel-mondo-delladozione-internazionale-e-piu-semplice-con-i-webinar-faris\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/muovere-i-primi-passi-nel-mondo-delladozione-internazionale-e-piu-semplice-con-i-webinar-faris\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2022\/11\/adozione-faris.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/11\/adozione-faris.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/muovere-i-primi-passi-nel-mondo-delladozione-internazionale-e-piu-semplice-con-i-webinar-faris\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Faris","item":"https:\/\/www.aibi.it\/ita\/category\/faris\/"},{"@type":"ListItem","position":3,"name":"Muovere i primi passi nel mondo dell\u2019Adozione Internazionale \u00e8 pi\u00f9 semplice con i webinar FARIS"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:56:37","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/206595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=206595"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/206595\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/206596"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=206595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=206595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=206595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}