﻿


{"id":209269,"date":"2023-02-01T07:30:15","date_gmt":"2023-02-01T06:30:15","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=209269"},"modified":"2023-10-25T14:50:34","modified_gmt":"2023-10-25T12:50:34","slug":"bambinixlapace-moldova-lontani-dalla-propria-terra-ma-felici-di-essere-stati-accolti","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-lontani-dalla-propria-terra-ma-felici-di-essere-stati-accolti\/","title":{"rendered":"BAMBINIXLAPACE Moldova. Lontani dalla propria terra ma \u201cfelici di essere stati accolti\u201d"},"content":{"rendered":"<h2>L\u2019indagine sull\u2019integrazione scolastica dei bambini ucraini fuggiti dalla guerra in Ucraina a quasi un anno di permanenza in Moldova<\/h2>\n<p>Un percorso valutativo sulle <strong>esigenze degli alunni ucraini<\/strong>, integrati nelle scuole moldave, \u00e8 stato intrapreso dagli operatori di <strong>Ai.Bi. Moldova<\/strong>.<\/p>\n<p>L\u2019equipe ha organizzato 7 incontri del tipo <em>Focus Group<\/em>, con la partecipazione di insegnanti, genitori e, non per ultimo, degli stessi studenti.<\/p>\n<p>Scopo dell\u2019indagine \u00e8 stato quello di valutare, quali siano i <strong>bisogni<\/strong>, il grado di soddisfazione circa l\u2019insegnamento, le criticit\u00e0 e le aspettative riguardanti l\u2019 inserimento scolastico dei minori ucraini, a circa un anno di permanenza delle famiglie ucraine sul territorio moldavo.<\/p>\n<p>Generalmente soddisfatti e riconoscenti per le opportunit\u00e0 di studio che hanno trovato in Moldova e per le nuove amicizie fatte, i bambini (23 in totale) partecipanti ai colloqui <strong>si sono mostrati sereni durante le discussioni e si sono dichiarati contenti, perch\u00e9 non sono stati del tutto \u201csradicati\u201d dalla loro terra<\/strong>. Anche se non conoscono la lingua romena, infatti, possono parlare e studiare in russo, il che da loro la possibilit\u00e0 di farsi capire, di apprendere le materie scolastiche e dunque, di \u201c<em>continuare serenamente il loro percorso di sviluppo personale e di crescita\u201d.<\/em><\/p>\n<h3><strong>Entusiasti delle nuove amicizie fatte in Moldova<\/strong><\/h3>\n<p>Si dicono <strong>entusiasti delle nuove amicizie,<\/strong> che hanno potuto stringere con i coetanei moldavi, <strong>piacevolmente sorpresi dalla calda accoglienza<\/strong> che non <em>si aspettavano all\u2019ingresso nel Paese <\/em>e&#8230; <strong>sconvolti per la mancanza degli amici ucraini<\/strong> che sentono tutti i gioni, via internet, o che non sentono pi\u00f9, da un anno.<\/p>\n<h3><strong>La scuola: tra aspetti positivi e criticit\u00e0<\/strong><\/h3>\n<p>Si mostrano <strong>preoccupati per l\u2019attivit\u00e0 fisica,<\/strong> che praticano poco in Moldova e per le altre attivit\u00e0 extracurricolari che vorrebbero svolgere pi\u00f9 frequentemente. Tra le loro preferenze vi \u00e8 la pittura, la scuola d\u2019arte, i corsi IT, le ore di ucraino e di romeno. Per quest\u2019ultimo, dicono scherzando che, nonostante <em>\u201cil rumeno non sia come il tedesco\u201d<\/em> (nel senso che non si capisce nulla)<em>, \u00e8 una lingua che vale la pena imparare<\/em>, <em>per rispetto del Paese che li ha accolti <\/em>e anche perch\u00e9, stando alle loro parole:<em> \u201cpi\u00f9 lingue si conosce, pi\u00f9 si diventa umani\u201d.<\/em><\/p>\n<p>I bambini hanno parlato anche delle differenze osservate tra le materie di studio nella scuola moldava e quella ucraina; <strong>concordano sul fatto che l\u2019insegnamento on-line, che viene spesso interrotto a causa dei bombardamenti nel loro Paese, non \u00e8 di qualit\u00e0, ma \u00e8 importante<\/strong> perch\u00e9 si parla in ucraino e si resta in contatto con i compagni e gli insegnanti di lingua-madre.<\/p>\n<p>Parlano anche degli episodi di tensione avvenuti fra i compagni, sia in classe, che fuori scuola, ma con una maturit\u00e0, atipica per la loro et\u00e0, <strong>riconoscono che \u201c<em>i discorsi politici sono per i grandi e piuttosto che lanciarsi in polemiche, preferiscono dare precedenza allo sviluppo<\/em><\/strong><em> delle nuove amicizie ed alla scoperta della cultura moldava, che per loro \u00e8 una terra incognita, che suscita il loro interesse\u201d. \u00a0<\/em><\/p>\n<p>In fine, si dicono <strong>felici di essere stati accolti<\/strong> nelle scuole moldave, considerati ed ascoltati. Ringraziano per avere l\u2019opportunit\u00e0 di interagire con persone \u201c<em>straniere, ma disposte ad ascoltarli e tenere conto dei loro vissuti e sentimenti, nonch\u00e9 delle loro emozioni e dei consigli rispetto al loro percorso scolastico\u201d. <\/em><\/p>\n<h3><strong>Sostieni anche tu la campagna #BAMBINIXLAPACE<\/strong><\/h3>\n<p>In questo contesto difficile, i bisogni delle famiglie sono davvero tanti e l\u2019aiuto che ognuno pu\u00f2 dare \u00e8 quanto mai prezioso! Attraverso una\u00a0<strong>donazione \u201cuna tantum<\/strong>\u201d o sostenendo il progetto di\u00a0<strong>adozione a distanza dei bambini e le famiglie ucraine,<\/strong>\u00a0potrai aiutare Ai.Bi. a dare continuit\u00e0 agli interventi che l\u2019associazione compie ogni giorno nel contesto dell\u2019iniziativa #BAMBINIXLAPACE. Clicca\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/emergenza-ucraina\/?scelta=Adozione%20a%20Distanza\"><strong>QUI<\/strong><\/a>\u00a0per dare il tuo contributo.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;indagine sull&rsquo;integrazione scolastica dei bambini ucraini fuggiti dalla guerra in Ucraina a quasi un anno di permanenza in Moldova Un percorso valutativo sulle esigenze degli alunni ucraini, integrati nelle scuole moldave, &egrave; stato intrapreso dagli operatori di Ai.Bi. Moldova. L&rsquo;equipe ha organizzato 7 incontri del tipo Focus Group, con la [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":209270,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[909],"tags":[895,530],"class_list":["post-209269","post","type-post","status-publish","format-standard","has-post-thumbnail","category-bambinixlapace","tag-bambinixlapace","tag-moldova"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>BAMBINIXLAPACE Moldova. Lontani dalla propria terra ma \u201cfelici di essere stati accolti\u201d - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Moldova. L\u2019indagine sull\u2019integrazione scolastica dei bambini ucraini fuggiti dalla guerra in Ucraina a quasi un anno di permanenza in Moldova\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-lontani-dalla-propria-terra-ma-felici-di-essere-stati-accolti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BAMBINIXLAPACE Moldova. Lontani dalla propria terra ma \u201cfelici di essere stati accolti\u201d\" \/>\n<meta property=\"og:description\" content=\"Moldova. L\u2019indagine sull\u2019integrazione scolastica dei bambini ucraini fuggiti dalla guerra in Ucraina a quasi un anno di permanenza in Moldova\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-lontani-dalla-propria-terra-ma-felici-di-essere-stati-accolti\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-01T06:30:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-25T12:50:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2023\/02\/Moldova.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mc.sabatini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mc.sabatini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-lontani-dalla-propria-terra-ma-felici-di-essere-stati-accolti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-lontani-dalla-propria-terra-ma-felici-di-essere-stati-accolti\\\/\"},\"author\":{\"name\":\"mc.sabatini\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\"},\"headline\":\"BAMBINIXLAPACE Moldova. Lontani dalla propria terra ma \u201cfelici di essere stati accolti\u201d\",\"datePublished\":\"2023-02-01T06:30:15+00:00\",\"dateModified\":\"2023-10-25T12:50:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-lontani-dalla-propria-terra-ma-felici-di-essere-stati-accolti\\\/\"},\"wordCount\":615,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-lontani-dalla-propria-terra-ma-felici-di-essere-stati-accolti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/02\\\/Moldova.jpg\",\"keywords\":[\"BAMBINIxLAPACE\",\"Moldova\"],\"articleSection\":[\"BAMBINIXLAPACE\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-lontani-dalla-propria-terra-ma-felici-di-essere-stati-accolti\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-lontani-dalla-propria-terra-ma-felici-di-essere-stati-accolti\\\/\",\"name\":\"BAMBINIXLAPACE Moldova. Lontani dalla propria terra ma \u201cfelici di essere stati accolti\u201d - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-lontani-dalla-propria-terra-ma-felici-di-essere-stati-accolti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-lontani-dalla-propria-terra-ma-felici-di-essere-stati-accolti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/02\\\/Moldova.jpg\",\"datePublished\":\"2023-02-01T06:30:15+00:00\",\"dateModified\":\"2023-10-25T12:50:34+00:00\",\"description\":\"Moldova. L\u2019indagine sull\u2019integrazione scolastica dei bambini ucraini fuggiti dalla guerra in Ucraina a quasi un anno di permanenza in Moldova\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-lontani-dalla-propria-terra-ma-felici-di-essere-stati-accolti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-lontani-dalla-propria-terra-ma-felici-di-essere-stati-accolti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-lontani-dalla-propria-terra-ma-felici-di-essere-stati-accolti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/02\\\/Moldova.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/02\\\/Moldova.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambinixlapace-moldova-lontani-dalla-propria-terra-ma-felici-di-essere-stati-accolti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BAMBINIXLAPACE\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/bambinixlapace\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BAMBINIXLAPACE Moldova. Lontani dalla propria terra ma \u201cfelici di essere stati accolti\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/87286c023dadcd887f1157d35a485938\",\"name\":\"mc.sabatini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/marias\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"BAMBINIXLAPACE Moldova. Lontani dalla propria terra ma \u201cfelici di essere stati accolti\u201d - Ai.Bi. Amici dei Bambini","description":"Moldova. L\u2019indagine sull\u2019integrazione scolastica dei bambini ucraini fuggiti dalla guerra in Ucraina a quasi un anno di permanenza in Moldova","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-lontani-dalla-propria-terra-ma-felici-di-essere-stati-accolti\/","og_locale":"it_IT","og_type":"article","og_title":"BAMBINIXLAPACE Moldova. Lontani dalla propria terra ma \u201cfelici di essere stati accolti\u201d","og_description":"Moldova. L\u2019indagine sull\u2019integrazione scolastica dei bambini ucraini fuggiti dalla guerra in Ucraina a quasi un anno di permanenza in Moldova","og_url":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-lontani-dalla-propria-terra-ma-felici-di-essere-stati-accolti\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2023-02-01T06:30:15+00:00","article_modified_time":"2023-10-25T12:50:34+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2023\/02\/Moldova.jpg","type":"image\/jpeg"}],"author":"mc.sabatini","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"mc.sabatini","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-lontani-dalla-propria-terra-ma-felici-di-essere-stati-accolti\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-lontani-dalla-propria-terra-ma-felici-di-essere-stati-accolti\/"},"author":{"name":"mc.sabatini","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938"},"headline":"BAMBINIXLAPACE Moldova. Lontani dalla propria terra ma \u201cfelici di essere stati accolti\u201d","datePublished":"2023-02-01T06:30:15+00:00","dateModified":"2023-10-25T12:50:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-lontani-dalla-propria-terra-ma-felici-di-essere-stati-accolti\/"},"wordCount":615,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-lontani-dalla-propria-terra-ma-felici-di-essere-stati-accolti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/02\/Moldova.jpg","keywords":["BAMBINIxLAPACE","Moldova"],"articleSection":["BAMBINIXLAPACE"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-lontani-dalla-propria-terra-ma-felici-di-essere-stati-accolti\/","url":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-lontani-dalla-propria-terra-ma-felici-di-essere-stati-accolti\/","name":"BAMBINIXLAPACE Moldova. Lontani dalla propria terra ma \u201cfelici di essere stati accolti\u201d - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-lontani-dalla-propria-terra-ma-felici-di-essere-stati-accolti\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-lontani-dalla-propria-terra-ma-felici-di-essere-stati-accolti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/02\/Moldova.jpg","datePublished":"2023-02-01T06:30:15+00:00","dateModified":"2023-10-25T12:50:34+00:00","description":"Moldova. L\u2019indagine sull\u2019integrazione scolastica dei bambini ucraini fuggiti dalla guerra in Ucraina a quasi un anno di permanenza in Moldova","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-lontani-dalla-propria-terra-ma-felici-di-essere-stati-accolti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-lontani-dalla-propria-terra-ma-felici-di-essere-stati-accolti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-lontani-dalla-propria-terra-ma-felici-di-essere-stati-accolti\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2023\/02\/Moldova.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/02\/Moldova.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/bambinixlapace-moldova-lontani-dalla-propria-terra-ma-felici-di-essere-stati-accolti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"BAMBINIXLAPACE","item":"https:\/\/www.aibi.it\/ita\/category\/bambinixlapace\/"},{"@type":"ListItem","position":3,"name":"BAMBINIXLAPACE Moldova. Lontani dalla propria terra ma \u201cfelici di essere stati accolti\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/87286c023dadcd887f1157d35a485938","name":"mc.sabatini","url":"https:\/\/www.aibi.it\/ita\/author\/marias\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:57:04","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/209269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=209269"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/209269\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/209270"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=209269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=209269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=209269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}