﻿


{"id":209684,"date":"2023-02-16T08:00:40","date_gmt":"2023-02-16T07:00:40","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=209684"},"modified":"2023-02-17T12:15:58","modified_gmt":"2023-02-17T11:15:58","slug":"dichiarazione-dei-redditi-2023-ce-la-data-di-scadenza-per-la-presentazione-il-2-ottobre","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/dichiarazione-dei-redditi-2023-ce-la-data-di-scadenza-per-la-presentazione-il-2-ottobre\/","title":{"rendered":"Dichiarazione dei redditi 2023. C\u2019\u00e8 la data di scadenza per la presentazione: il 2 ottobre"},"content":{"rendered":"<h2>L\u2019Agenzia delle Entrate ha pubblicato un provvedimento che fissa le novit\u00e0 e i termini di presentazione del modello 730\/2023, caratterizzato in particolare dai nuovi scaglioni irpef. Confermato, naturalmente, il modulo per la scelta di destinazione del 5&#215;1000<\/h2>\n<p><!--more--><\/p>\n<p>Di tempo ce n\u2019\u00e8 ancora, specie visto che l\u2019argomento non \u00e8 dei pi\u00f9 graditi\u2026 Come si dice, per\u00f2, meglio portarsi avanti e sapere che, secondo quanto da poco pubblicato dall\u2019Agenzia delle Entrate, la scadenza della presentazione delle dichiarazioni dei redditi relative all\u2019anno 2022 \u00e8 il <strong>2 ottobre<\/strong>, visto che il 30 settembre, termine che \u00e8 stato confermato, cade di sabato.<\/p>\n<h3>Tutte le novit\u00e0 della dichiarazione dei redditi 2023<\/h3>\n<p>\u00c8 questa la principale notizia contenuta all\u2019interno del Provvedimento numero 34545 del 6 febbraio con il quale l\u2019Agenzia delle Entrate ha <strong>approvato il modello 730\/2023<\/strong> e le relative istruzioni per la sua compilazione.<br \/>\nL\u2019impianto generale non cambia, ma sono state inserite alcune significative modifiche per fare spazio alle varie misure, incentivi, bonus e detrazioni che sono state introdotti dal governo l\u2019anno scorso.<br \/>\nIn particolare, nel nuovo modello 730\/2023 trovano spazio le <strong>nuove regole relative all\u2019IRPEF<\/strong>, con la prima aliquota confermata al <strong>23%<\/strong>, ma la seconda (per redditi da 15 a 28mila euro<strong>) scesa dal 27% al 25%<\/strong>; la terza (per redditi da 28\u00a0 a 50mila) passata dal 38% al <strong>35%<\/strong>; mentre al di sopra dei 50mila euro l\u2019aliquota \u00e8 unica per tutti al <strong>43%<\/strong>.<br \/>\nCi sono novit\u00e0 anche nel quadro dedicato alle detrazioni per il lavoro e i figli a carico, mentre risulter\u00e0 un po\u2019 pi\u00f9 complesso orientarsi nei vari bonus e superbonus edilizi che sono stati pi\u00f9 volte modificati nel corso dell\u2019anno.<\/p>\n<h3>\u00c8 gi\u00e0 tempo di pensare alla destinazione del 5 x 1000<\/h3>\n<p>Naturalmente, rimane, nella dichiarazione, il modulo per la <strong>destinazione del 5&#215;1000<\/strong> a agli enti non profit, una misura importantissima per le realt\u00e0 del terzo settore. Ai.Bi. sta gi\u00e0 pensando alla \u201ccampagna\u201d per sensibilizzare verso l\u2019importanza di questa firma che, per la dichiarazione del 2023, rinnover\u00e0 il particolare impegno verso il progetto <strong><a href=\"https:\/\/www.aibi.it\/ita\/bambinixlapace\">#BAMBINIxLAPACE<\/a><\/strong>, destinato a tutte le famiglie e i minori in difficolt\u00e0 a causa di un conflitto in Ucraina che, purtroppo, non accenna a dirigersi verso nuovi scenari di pace.<br \/>\nDunque\u2026 non \u00e8 mai troppo presto per segnarsi il codice fiscale di Ai.Bi. da inserire nella dichiarazione, unitamente alla propria firma: <strong>92504680155<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;Agenzia delle Entrate ha pubblicato un provvedimento che fissa le novit&agrave; e i termini di presentazione del modello 730\/2023, caratterizzato in particolare dai nuovi scaglioni irpef. Confermato, naturalmente, il modulo per la scelta di destinazione del 5&times;1000<\/p>\n","protected":false},"author":102,"featured_media":209685,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[665,922,829],"class_list":["post-209684","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-5xmille","tag-dichiarazione-redditi","tag-tasse"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Dichiarazione dei redditi 2023. Consegna entro il 2 ottobre<\/title>\n<meta name=\"description\" content=\"L\u2019Agenzia delle Entrate ha pubblicato un provvedimento che fissa le novit\u00e0 e i termini di presentazione della Dichiarazione dei Redditi 2023 con il 5x1000\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/dichiarazione-dei-redditi-2023-ce-la-data-di-scadenza-per-la-presentazione-il-2-ottobre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dichiarazione dei redditi 2023. C\u2019\u00e8 la data di scadenza per la presentazione: il 2 ottobre\" \/>\n<meta property=\"og:description\" content=\"L\u2019Agenzia delle Entrate ha pubblicato un provvedimento che fissa le novit\u00e0 e i termini di presentazione della Dichiarazione dei Redditi 2023 con il 5x1000\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/dichiarazione-dei-redditi-2023-ce-la-data-di-scadenza-per-la-presentazione-il-2-ottobre\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-16T07:00:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-17T11:15:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2023\/02\/Dichiarazione-dei-redditi-2023.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/dichiarazione-dei-redditi-2023-ce-la-data-di-scadenza-per-la-presentazione-il-2-ottobre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/dichiarazione-dei-redditi-2023-ce-la-data-di-scadenza-per-la-presentazione-il-2-ottobre\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Dichiarazione dei redditi 2023. C\u2019\u00e8 la data di scadenza per la presentazione: il 2 ottobre\",\"datePublished\":\"2023-02-16T07:00:40+00:00\",\"dateModified\":\"2023-02-17T11:15:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/dichiarazione-dei-redditi-2023-ce-la-data-di-scadenza-per-la-presentazione-il-2-ottobre\\\/\"},\"wordCount\":380,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/dichiarazione-dei-redditi-2023-ce-la-data-di-scadenza-per-la-presentazione-il-2-ottobre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/02\\\/Dichiarazione-dei-redditi-2023.jpg\",\"keywords\":[\"5xmille\",\"dichiarazione redditi\",\"tasse\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/dichiarazione-dei-redditi-2023-ce-la-data-di-scadenza-per-la-presentazione-il-2-ottobre\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/dichiarazione-dei-redditi-2023-ce-la-data-di-scadenza-per-la-presentazione-il-2-ottobre\\\/\",\"name\":\"Dichiarazione dei redditi 2023. Consegna entro il 2 ottobre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/dichiarazione-dei-redditi-2023-ce-la-data-di-scadenza-per-la-presentazione-il-2-ottobre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/dichiarazione-dei-redditi-2023-ce-la-data-di-scadenza-per-la-presentazione-il-2-ottobre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/02\\\/Dichiarazione-dei-redditi-2023.jpg\",\"datePublished\":\"2023-02-16T07:00:40+00:00\",\"dateModified\":\"2023-02-17T11:15:58+00:00\",\"description\":\"L\u2019Agenzia delle Entrate ha pubblicato un provvedimento che fissa le novit\u00e0 e i termini di presentazione della Dichiarazione dei Redditi 2023 con il 5x1000\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/dichiarazione-dei-redditi-2023-ce-la-data-di-scadenza-per-la-presentazione-il-2-ottobre\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/dichiarazione-dei-redditi-2023-ce-la-data-di-scadenza-per-la-presentazione-il-2-ottobre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/dichiarazione-dei-redditi-2023-ce-la-data-di-scadenza-per-la-presentazione-il-2-ottobre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/02\\\/Dichiarazione-dei-redditi-2023.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/02\\\/Dichiarazione-dei-redditi-2023.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/dichiarazione-dei-redditi-2023-ce-la-data-di-scadenza-per-la-presentazione-il-2-ottobre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dichiarazione dei redditi 2023. C\u2019\u00e8 la data di scadenza per la presentazione: il 2 ottobre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dichiarazione dei redditi 2023. Consegna entro il 2 ottobre","description":"L\u2019Agenzia delle Entrate ha pubblicato un provvedimento che fissa le novit\u00e0 e i termini di presentazione della Dichiarazione dei Redditi 2023 con il 5x1000","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/dichiarazione-dei-redditi-2023-ce-la-data-di-scadenza-per-la-presentazione-il-2-ottobre\/","og_locale":"it_IT","og_type":"article","og_title":"Dichiarazione dei redditi 2023. C\u2019\u00e8 la data di scadenza per la presentazione: il 2 ottobre","og_description":"L\u2019Agenzia delle Entrate ha pubblicato un provvedimento che fissa le novit\u00e0 e i termini di presentazione della Dichiarazione dei Redditi 2023 con il 5x1000","og_url":"https:\/\/www.aibi.it\/ita\/dichiarazione-dei-redditi-2023-ce-la-data-di-scadenza-per-la-presentazione-il-2-ottobre\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2023-02-16T07:00:40+00:00","article_modified_time":"2023-02-17T11:15:58+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2023\/02\/Dichiarazione-dei-redditi-2023.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/dichiarazione-dei-redditi-2023-ce-la-data-di-scadenza-per-la-presentazione-il-2-ottobre\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/dichiarazione-dei-redditi-2023-ce-la-data-di-scadenza-per-la-presentazione-il-2-ottobre\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Dichiarazione dei redditi 2023. C\u2019\u00e8 la data di scadenza per la presentazione: il 2 ottobre","datePublished":"2023-02-16T07:00:40+00:00","dateModified":"2023-02-17T11:15:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/dichiarazione-dei-redditi-2023-ce-la-data-di-scadenza-per-la-presentazione-il-2-ottobre\/"},"wordCount":380,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/dichiarazione-dei-redditi-2023-ce-la-data-di-scadenza-per-la-presentazione-il-2-ottobre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/02\/Dichiarazione-dei-redditi-2023.jpg","keywords":["5xmille","dichiarazione redditi","tasse"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/dichiarazione-dei-redditi-2023-ce-la-data-di-scadenza-per-la-presentazione-il-2-ottobre\/","url":"https:\/\/www.aibi.it\/ita\/dichiarazione-dei-redditi-2023-ce-la-data-di-scadenza-per-la-presentazione-il-2-ottobre\/","name":"Dichiarazione dei redditi 2023. Consegna entro il 2 ottobre","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/dichiarazione-dei-redditi-2023-ce-la-data-di-scadenza-per-la-presentazione-il-2-ottobre\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/dichiarazione-dei-redditi-2023-ce-la-data-di-scadenza-per-la-presentazione-il-2-ottobre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/02\/Dichiarazione-dei-redditi-2023.jpg","datePublished":"2023-02-16T07:00:40+00:00","dateModified":"2023-02-17T11:15:58+00:00","description":"L\u2019Agenzia delle Entrate ha pubblicato un provvedimento che fissa le novit\u00e0 e i termini di presentazione della Dichiarazione dei Redditi 2023 con il 5x1000","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/dichiarazione-dei-redditi-2023-ce-la-data-di-scadenza-per-la-presentazione-il-2-ottobre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/dichiarazione-dei-redditi-2023-ce-la-data-di-scadenza-per-la-presentazione-il-2-ottobre\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/dichiarazione-dei-redditi-2023-ce-la-data-di-scadenza-per-la-presentazione-il-2-ottobre\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2023\/02\/Dichiarazione-dei-redditi-2023.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/02\/Dichiarazione-dei-redditi-2023.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/dichiarazione-dei-redditi-2023-ce-la-data-di-scadenza-per-la-presentazione-il-2-ottobre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Dichiarazione dei redditi 2023. C\u2019\u00e8 la data di scadenza per la presentazione: il 2 ottobre"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:33:55","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/209684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=209684"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/209684\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/209685"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=209684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=209684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=209684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}