﻿


{"id":210123,"date":"2023-02-27T07:30:24","date_gmt":"2023-02-27T06:30:24","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=210123"},"modified":"2023-02-27T15:25:26","modified_gmt":"2023-02-27T14:25:26","slug":"testamento-internazionale-ente-benefico","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/testamento-internazionale-ente-benefico\/","title":{"rendered":"Con il testamento internazionale anche chi vive all\u2019estero pu\u00f2 fare un lascito a un ente benefico italiano"},"content":{"rendered":"<h2>I cittadini italiani residenti all\u2019estero hanno la possibilit\u00e0 di redigere il testamento internazionale, introdotto con la ratifica della convenzione di Washington, e di lasciare parte dei propri beni a un ente benefico con sede legale di Italia<\/h2>\n<p><!--more--><\/p>\n<blockquote><p><em>Buongiorno, sono un cittadino italiano residente all\u2019estero, per la precisione in Francia, e vorrei sapere se posso validamente scrivere un testamento a favore di un ente benefico con sede legale in Italia.<br \/>\n<\/em><em>\u00a0Grazie.<\/em><\/p><\/blockquote>\n<p>Buongiorno,<br \/>\ngrazie della domanda alla quale possiamo rispondere, prima di tutto, che il tipo di testamento di cui chiede informazioni \u00e8 il cosiddetto <strong>testamento internazionale<\/strong>, come gi\u00e0 avevamo sottolineato in occasione di <a href=\"https:\/\/www.aibi.it\/ita\/lasciti-solidali-il-testamento-degli-italiani-residenti-allestero-quale-legge-si-applica-e-quali-sono-i-vincoli-da-rispettare\/\">un altro articolo<\/a> presente in queste rubrica. Quindi, la risposta al suo quesito \u00e8 positiva, ma le questioni che questo argomento coinvolge sono diverse e, qui, possiamo sottolinearne alcune delle principali.<br \/>\nIl \u201ctestamento internazionale\u201d \u00e8 stato introdotto nel nostro ordinamento con la L. 387\/1990 (in vigore dal 16\/11\/1991) che ha ratificato la <strong>Convenzione di Washington<\/strong> del 26\/11\/1973.<br \/>\nFondamentale \u00e8 la deroga all\u2019art. 48 della L. 218\/95 con la quale la Convenzione attesta la validit\u00e0 formale del testamento dello straniero in Italia o del cittadino italiano all\u2019estero purch\u00e9 rispetti i requisiti di forma stabiliti dalla Convenzione, anche in contrasto con quanto disposto dalla legge di Riforma del sistema di diritto internazionale privato.<br \/>\nMentre le questioni sostanziali, come la capacit\u00e0 di testare, il contenuto delle disposizioni, la legge regolatrici delle successioni, continuano ad essere disciplinati dalla L. 218\/1995.<br \/>\nSi pu\u00f2 pacificamente inserire il testamento internazionale tra le <strong>forme testamentarie ulteriori<\/strong> rispetto a quelle disciplinate dal codice civile, in quanto pu\u00f2 essere redatto anche in assenza di un qualsivoglia criterio di collegamento con l\u2019estero.<br \/>\nPossiamo concludere che il suo caso rientra perfettamente nelle forme del testamento internazionale, ma anche il cittadino italiano residente in Italia, i cui beni si trovino in Italia, pu\u00f2 valersi validamente di tale forma di testamento.<\/p>\n<h3>La ratifica della Convenzione di Washington<\/h3>\n<p>Fondamentale nella legge di ratifica della Convenzione di Washington non \u00e8 tanto l\u2019articolato, che \u00e8 costituito da sole 4 norme, ma <strong>l\u2019Annesso<\/strong>.<br \/>\nL\u2019elemento essenziale per la validit\u00e0 del testamento internazionale \u00e8 costituito dalla <strong>consegna della scheda testamentaria<\/strong>, di cui si redige apposito verbale, al Notaio, alla presenza dei testimoni.<br \/>\nIl testamento internazionale si compone della scheda testamentaria vera e propria, che ha natura di scrittura privata e per la quale la Convenzione stabilisce alcuni requisiti di forma <em>ad validatem<\/em>, e di un <strong>attestato<\/strong>, dal contenuto sostanzialmente predeterminato, che deve essere ricevuto da un soggetto abilitato e, dunque, <strong>costituisce un atto pubblico<\/strong>: in Italia tale soggetto e\u0300 il <strong>notaio<\/strong>.<br \/>\nEntriamo nello specifico, pur in maniera sintetica, dicendo che l\u2019atto di stesura della carta testamentaria segue le disposizioni generali e pu\u00f2 avvenire in qualsiasi momento e con ampia libert\u00e0 di modalit\u00e0 (Art. 3 Annesso).<br \/>\nSuccessivamente, e qui interviene la particolarit\u00e0: il testatore deve dichiarare in \u201c<em>presenza di due testimoni e di una persona abilitata a stipulare atti a tal fine <\/em>(notaio)<em> che il documento \u00e8 il suo testamento e che egli \u00e8 a conoscenza del suo contenuto.<br \/>\n<\/em><em>2. Il testatore non \u00e8 tenuto a far conoscere il contenuto del testamento ai testimoni oppure alla persona abilitata\u201d <\/em>(art. 4 Annesso).<br \/>\nInfine, il notaio deve redigere l\u2019attestato che costituisce una certificazione del fatto che sono state osservate le formalit\u00e0 previste dalla legge.<br \/>\nL\u2019art. 10 dell\u2019Annesso fornisce un modello testuale di attestato, a cui la prassi consiglia di attenersi pedissequamente.<\/p>\n<p>Nel ringraziarla nuovamente per essersi rivolto al nostro servizio, le ribadiamo che pu\u00f2, seguendo le modalit\u00e0 indicate dalla normativa sopra riportata, <strong>decidere di lasciare parte dei suoi beni a un ente benefico<\/strong> italiano.<br \/>\nConcludiamo con una nota di colore: il fondamento del testamento internazionale \u00e8 la Convenzione di Washington, capitale degli USA, ma tra i Paesi che non l\u2019hanno ancora ratificata ci sono gli proprio Stati Uniti d\u2019America.<br \/>\nPer ulteriori chiarimenti sui lasciti solidali \u00e8 possibile consultare la <a href=\"https:\/\/www.aibi.it\/lasciti-testamentari\/\">pagina dedicata<\/a> del sito di Ai.Bi., scrivere alla mail <strong>lasciti@aibi.it<\/strong> o chiamare il numero <strong>02.98822332<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>I cittadini italiani residenti all&rsquo;estero hanno la possibilit&agrave; di redigere il testamento internazionale, introdotto con la ratifica della convenzione di Washington, e di lasciare parte dei propri beni a un ente benefico con sede legale di Italia<\/p>\n","protected":false},"author":102,"featured_media":210125,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[731],"tags":[999,596],"class_list":["post-210123","post","type-post","status-publish","format-standard","has-post-thumbnail","category-lasciti-testamentari","tag-eredita","tag-lasciti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fare lasciti a enti benefici italiani con il testamento internazionale<\/title>\n<meta name=\"description\" content=\"I cittadini italiani residenti all\u2019estero possono redigere un testamento internazionale e lasciare parte dei propri beni a un ente benefico con sede in Italia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/testamento-internazionale-ente-benefico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Con il testamento internazionale anche chi vive all\u2019estero pu\u00f2 fare un lascito a un ente benefico italiano\" \/>\n<meta property=\"og:description\" content=\"I cittadini italiani residenti all\u2019estero possono redigere un testamento internazionale e lasciare parte dei propri beni a un ente benefico con sede in Italia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/testamento-internazionale-ente-benefico\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-27T06:30:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-27T14:25:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2023\/02\/testamento_internazionale.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/testamento-internazionale-ente-benefico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/testamento-internazionale-ente-benefico\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Con il testamento internazionale anche chi vive all\u2019estero pu\u00f2 fare un lascito a un ente benefico italiano\",\"datePublished\":\"2023-02-27T06:30:24+00:00\",\"dateModified\":\"2023-02-27T14:25:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/testamento-internazionale-ente-benefico\\\/\"},\"wordCount\":664,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/testamento-internazionale-ente-benefico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/02\\\/testamento_internazionale.jpg\",\"keywords\":[\"eredit\u00e0\",\"lasciti\"],\"articleSection\":[\"Lasciti Testamentari\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/testamento-internazionale-ente-benefico\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/testamento-internazionale-ente-benefico\\\/\",\"name\":\"Fare lasciti a enti benefici italiani con il testamento internazionale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/testamento-internazionale-ente-benefico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/testamento-internazionale-ente-benefico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/02\\\/testamento_internazionale.jpg\",\"datePublished\":\"2023-02-27T06:30:24+00:00\",\"dateModified\":\"2023-02-27T14:25:26+00:00\",\"description\":\"I cittadini italiani residenti all\u2019estero possono redigere un testamento internazionale e lasciare parte dei propri beni a un ente benefico con sede in Italia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/testamento-internazionale-ente-benefico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/testamento-internazionale-ente-benefico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/testamento-internazionale-ente-benefico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/02\\\/testamento_internazionale.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/02\\\/testamento_internazionale.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/testamento-internazionale-ente-benefico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lasciti Testamentari\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/lasciti-testamentari\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Con il testamento internazionale anche chi vive all\u2019estero pu\u00f2 fare un lascito a un ente benefico italiano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fare lasciti a enti benefici italiani con il testamento internazionale","description":"I cittadini italiani residenti all\u2019estero possono redigere un testamento internazionale e lasciare parte dei propri beni a un ente benefico con sede in Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/testamento-internazionale-ente-benefico\/","og_locale":"it_IT","og_type":"article","og_title":"Con il testamento internazionale anche chi vive all\u2019estero pu\u00f2 fare un lascito a un ente benefico italiano","og_description":"I cittadini italiani residenti all\u2019estero possono redigere un testamento internazionale e lasciare parte dei propri beni a un ente benefico con sede in Italia","og_url":"https:\/\/www.aibi.it\/ita\/testamento-internazionale-ente-benefico\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2023-02-27T06:30:24+00:00","article_modified_time":"2023-02-27T14:25:26+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2023\/02\/testamento_internazionale.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/testamento-internazionale-ente-benefico\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/testamento-internazionale-ente-benefico\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Con il testamento internazionale anche chi vive all\u2019estero pu\u00f2 fare un lascito a un ente benefico italiano","datePublished":"2023-02-27T06:30:24+00:00","dateModified":"2023-02-27T14:25:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/testamento-internazionale-ente-benefico\/"},"wordCount":664,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/testamento-internazionale-ente-benefico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/02\/testamento_internazionale.jpg","keywords":["eredit\u00e0","lasciti"],"articleSection":["Lasciti Testamentari"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/testamento-internazionale-ente-benefico\/","url":"https:\/\/www.aibi.it\/ita\/testamento-internazionale-ente-benefico\/","name":"Fare lasciti a enti benefici italiani con il testamento internazionale","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/testamento-internazionale-ente-benefico\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/testamento-internazionale-ente-benefico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/02\/testamento_internazionale.jpg","datePublished":"2023-02-27T06:30:24+00:00","dateModified":"2023-02-27T14:25:26+00:00","description":"I cittadini italiani residenti all\u2019estero possono redigere un testamento internazionale e lasciare parte dei propri beni a un ente benefico con sede in Italia","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/testamento-internazionale-ente-benefico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/testamento-internazionale-ente-benefico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/testamento-internazionale-ente-benefico\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2023\/02\/testamento_internazionale.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/02\/testamento_internazionale.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/testamento-internazionale-ente-benefico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Lasciti Testamentari","item":"https:\/\/www.aibi.it\/ita\/category\/lasciti-testamentari\/"},{"@type":"ListItem","position":3,"name":"Con il testamento internazionale anche chi vive all\u2019estero pu\u00f2 fare un lascito a un ente benefico italiano"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 03:26:18","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/210123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=210123"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/210123\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/210125"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=210123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=210123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=210123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}