﻿


{"id":210347,"date":"2023-03-06T07:29:37","date_gmt":"2023-03-06T06:29:37","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=210347"},"modified":"2023-03-06T16:26:00","modified_gmt":"2023-03-06T15:26:00","slug":"tasse-pagare-sui-lasciti-solidali","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/tasse-pagare-sui-lasciti-solidali\/","title":{"rendered":"Ci sono tasse da pagare sui lasciti solidali?"},"content":{"rendered":"<h2>Quando si decide di devolvere una parte della propria eredit\u00e0 a un ente benefico, questi, una volta ricevuto il lascito, deve a sua volta pagare delle tasse?<\/h2>\n<p><!--more--><\/p>\n<p>Qualsiasi sostenitore che decide di <strong>fare un lascito a un Ente del terzo settore<\/strong> sosterr\u00e0 o meno costi, a parte la donazione in s\u00e9, a seconda che decida di <strong>rivolgersi a un notaio<\/strong> e fare un testamento con la sua assistenza o meno. Una modalit\u00e0 per redigere un testamento \u201cfai da te\u201d senza costi esiste (testamento olografo), ma certamente espone al rischio di scrivere volont\u00e0 irrealizzabili o di rendere difficile l&#8217;esecuzione del testamento nel caso di violazione delle leggi che prevedono quote da lasciare necessariamente ad alcuni parenti e che siano ignorate. \u00c8 quindi sempre consigliabile rivolgersi a un notaio per una consulenza o un\u2019assistenza notarile, con i relativi costi che questo comporta.<\/p>\n<h3>Differenza tra erede e legatario<\/h3>\n<p>Per chi riceve il lascito solidale, invece, va distinta la posizione dell&#8217;<em>erede<\/em> da quella del semplice <em>legatario<\/em>. L&#8217;erede avr\u00e0 la &#8220;massa&#8221; del patrimonio dopo che da questa siano stati detratti gli eventuali costi (spese notarili legate alla pubblicazione del testamento, spese funerarie, eventuali debiti della persona deceduta) e dopo che siano stati anche sottratti i &#8220;lasciti&#8221; per i legatari (c.d. legati), che possono essere oggetti ma anche <strong>quote di eredit\u00e0 in denaro<\/strong>. Il legatario, invece, a meno che il testamento sia impugnato o che per qualche ragione le quote siano ridotte proporzionalmente per incapienza, <strong>ricever\u00e0 il proprio lascito solidale testamentario senza detrarre nulla<\/strong> dall&#8217;ammontare previsto.<br \/>\nPi\u00f9 in generale, salve eventuali prossime nuove disposizioni per il profilo fiscale in materia di Enti del Terzo Settore, il trattamento attuale della tassazione o meno dei lasciti agli Enti, si basa sul &#8220;<strong>Testo unico delle disposizioni concernenti l&#8217;imposta sulle successioni e donazioni<\/strong>&#8221; del 31 ottobre 1990 n. 346, in particolare l&#8217;articolo 3 sui &#8220;Trasferimenti non soggetti a imposta&#8221;, che prevede le esenzioni per gli Enti del terzo settore dividendoli in tre diversi gruppi.<\/p>\n<h3>Onlus, fondazioni ed enti che non perseguono scopi di pubblica utilit\u00e0<\/h3>\n<p>Nel primo gruppo rientrano le donazioni, che siano in vita oppure anche per causa di morte, e dunque tramite testamento, fatte in favore di <strong>Enti senza scopo di lucro <\/strong>(ONLUS) oppure di <strong>Fondazioni bancarie<\/strong>, che sono totalmente esenti da imposta di successione e di donazione. Questa esenzione riguarda sia la donazione in s\u00e9 che la tassa di registrazione dell&#8217;atto presso l&#8217;Agenzia delle Entrate. Se per\u00f2 l&#8217;atto ha tra i beneficiari sia Enti onlus che altre persone non sar\u00e0 esente dalla tassa di registrazione.<\/p>\n<p>Se, per\u00f2, la donazione ha a oggetto beni immobili, per l&#8217;Ente che la riceve in regime di esenzione da imposta di donazione e successione, \u00e8 prevista anche l&#8217;esenzione dal pagamento delle imposte ipotecarie e catastali necessarie previste per trascrizione e voltura. Ci saranno per\u00f2 in questo caso da pagare alcune imposte legate agli atti notarili di donazione (tassa d&#8217;Archivio, tassa per l&#8217;adempimento telematico Unico) che sono dovute essendo una specie di corrispettivo per l&#8217;attivit\u00e0 svolta dalla pubblica amministrazione (per queste tasse in genere non si superano le 250 euro).<br \/>\nNon \u00e8 per\u00f2 mai dovuta dalle <strong>ONLUS<\/strong> l&#8217;imposta di bollo (mentre le Fondazioni bancarie la pagano).<\/p>\n<p>Nel secondo gruppo di enti rientrano le <strong>fondazioni e associazioni riconosciute che perseguano scopi di pubblica utilit\u00e0, <\/strong>che avranno o meno l&#8217;esenzione per le donazioni e i lasciti ricevuti a seconda se abbiano ottenuto o meno la qualifica di onlus. Nel caso in cui l&#8217;abbiano ottenuta avranno le stesse agevolazioni sopra indicate, e cio\u00e8 la totale esenzione da imposte di successione, donazione, ipotecarie e catastali ed esenzione dal bollo. Se invece non dovessero avere ottenuto la qualifica di onlus, il bollo sar\u00e0 dovuto come per le fondazioni bancarie.<\/p>\n<p>Nel terzo gruppo di enti rientrano l<strong>e fondazioni in genere e le associazioni riconosciute, che <u>non<\/u> perseguono scopi di pubblica utilit\u00e0<\/strong>. Anche in questo caso sono previste esenzioni dalle imposte di successione, donazione, ipotecarie e catastali ma solo se il <em>de cuius<\/em> o il donante hanno effettuato la donazione con il fine specifico di condizionarla alla realizzazione di un fine di pubblica utilit\u00e0 che, pur non facendo parte degli scopi statutari dell&#8217;ente, dovr\u00e0 diventare, per volont\u00e0 del donatore, uno scopo da raggiungere. Quindi l&#8217;esenzione \u00e8 in questi casi concessa ma <em>\u201cil beneficiario deve dimostrare, entro <u>cinque<\/u> <u>ann<\/u>i dall&#8217;accettazione dell&#8217;eredit\u00e0 o della donazione o dall&#8217;acquisto del legato, di avere impiegato i beni o diritti ricevuti o la somma ricavata dalla loro alienazione per il conseguimento delle finalit\u00e0 indicate dal testatore o dal donante. In mancanza di tale dimostrazione esso \u00e8 tenuto al pagamento dell&#8217;imposta con gli interessi legali dalla data in cui avrebbe dovuto essere<\/em> <em>pagata\u201d.<\/em> La stessa agevolazione \u00e8 prevista anche per le imposte ipotecarie e catastali con la possibilit\u00e0 di recuperare gli interessi legali per le somme nel frattempo pagate che si rivelassero non dovute all&#8217;Agenzia delle Entrate.<\/p>\n<p><strong>Ai.Bi. \u00e8 una associazione riconosciuta che persegue fini sociali ed \u00e8 anche un Ente senza scopo di lucro<\/strong> iscritto alla Anagrafe delle ONLUS. Le donazioni sia in vita che in un testamento in favore di Ai.Bi. sono dunque totalmente esenti per l&#8217;Associazione, come pure gli eventuali atti nel caso si trattasse di ricevere la propriet\u00e0 di un immobile. Chi decidesse di fare un lascito solidale ad Ai.Bi., insomma, potrebbe essere sicuro che l\u2019intero valore del lascito (fatta eccezione per le singole, eventuali, voci, riportato sopre) andrebbe a favore dell\u2019ente senza che su di esso vadano pagate ulteriori tasse.<br \/>\nPer ulteriori informazioni sui lasciti \u00e8 possibile consultare la <a href=\"https:\/\/www.aibi.it\/lasciti-testamentari\/\"><strong>pagina dedicata<\/strong><\/a> del sito di Ai.Bi., scrivere alla mail <strong>lasciti@aibi.it<\/strong>o chiamare il numero <strong>02.98822332<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando si decide di devolvere una parte della propria eredit&agrave; a un ente benefico, questi, una volta ricevuto il lascito, deve a sua volta pagare delle tasse?<\/p>\n","protected":false},"author":102,"featured_media":210350,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[731],"tags":[999,596],"class_list":["post-210347","post","type-post","status-publish","format-standard","has-post-thumbnail","category-lasciti-testamentari","tag-eredita","tag-lasciti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bisogna pagare delle tasse sui lasciti solidali?<\/title>\n<meta name=\"description\" content=\"Quando si decide di devolvere una parte della propria eredit\u00e0 a un ente benefico, questi una volta ricevuti i beni deve pagare delle tasse sui lasciti solidali?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/tasse-pagare-sui-lasciti-solidali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ci sono tasse da pagare sui lasciti solidali?\" \/>\n<meta property=\"og:description\" content=\"Quando si decide di devolvere una parte della propria eredit\u00e0 a un ente benefico, questi una volta ricevuti i beni deve pagare delle tasse sui lasciti solidali?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/tasse-pagare-sui-lasciti-solidali\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-06T06:29:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-06T15:26:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2023\/03\/tasse-sui-lasciti-solidali.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tasse-pagare-sui-lasciti-solidali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tasse-pagare-sui-lasciti-solidali\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Ci sono tasse da pagare sui lasciti solidali?\",\"datePublished\":\"2023-03-06T06:29:37+00:00\",\"dateModified\":\"2023-03-06T15:26:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tasse-pagare-sui-lasciti-solidali\\\/\"},\"wordCount\":949,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tasse-pagare-sui-lasciti-solidali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/03\\\/tasse-sui-lasciti-solidali.jpg\",\"keywords\":[\"eredit\u00e0\",\"lasciti\"],\"articleSection\":[\"Lasciti Testamentari\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tasse-pagare-sui-lasciti-solidali\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tasse-pagare-sui-lasciti-solidali\\\/\",\"name\":\"Bisogna pagare delle tasse sui lasciti solidali?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tasse-pagare-sui-lasciti-solidali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tasse-pagare-sui-lasciti-solidali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/03\\\/tasse-sui-lasciti-solidali.jpg\",\"datePublished\":\"2023-03-06T06:29:37+00:00\",\"dateModified\":\"2023-03-06T15:26:00+00:00\",\"description\":\"Quando si decide di devolvere una parte della propria eredit\u00e0 a un ente benefico, questi una volta ricevuti i beni deve pagare delle tasse sui lasciti solidali?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tasse-pagare-sui-lasciti-solidali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tasse-pagare-sui-lasciti-solidali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tasse-pagare-sui-lasciti-solidali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/03\\\/tasse-sui-lasciti-solidali.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/03\\\/tasse-sui-lasciti-solidali.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tasse-pagare-sui-lasciti-solidali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lasciti Testamentari\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/lasciti-testamentari\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ci sono tasse da pagare sui lasciti solidali?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bisogna pagare delle tasse sui lasciti solidali?","description":"Quando si decide di devolvere una parte della propria eredit\u00e0 a un ente benefico, questi una volta ricevuti i beni deve pagare delle tasse sui lasciti solidali?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/tasse-pagare-sui-lasciti-solidali\/","og_locale":"it_IT","og_type":"article","og_title":"Ci sono tasse da pagare sui lasciti solidali?","og_description":"Quando si decide di devolvere una parte della propria eredit\u00e0 a un ente benefico, questi una volta ricevuti i beni deve pagare delle tasse sui lasciti solidali?","og_url":"https:\/\/www.aibi.it\/ita\/tasse-pagare-sui-lasciti-solidali\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2023-03-06T06:29:37+00:00","article_modified_time":"2023-03-06T15:26:00+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2023\/03\/tasse-sui-lasciti-solidali.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/tasse-pagare-sui-lasciti-solidali\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/tasse-pagare-sui-lasciti-solidali\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Ci sono tasse da pagare sui lasciti solidali?","datePublished":"2023-03-06T06:29:37+00:00","dateModified":"2023-03-06T15:26:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/tasse-pagare-sui-lasciti-solidali\/"},"wordCount":949,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/tasse-pagare-sui-lasciti-solidali\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/03\/tasse-sui-lasciti-solidali.jpg","keywords":["eredit\u00e0","lasciti"],"articleSection":["Lasciti Testamentari"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/tasse-pagare-sui-lasciti-solidali\/","url":"https:\/\/www.aibi.it\/ita\/tasse-pagare-sui-lasciti-solidali\/","name":"Bisogna pagare delle tasse sui lasciti solidali?","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/tasse-pagare-sui-lasciti-solidali\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/tasse-pagare-sui-lasciti-solidali\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/03\/tasse-sui-lasciti-solidali.jpg","datePublished":"2023-03-06T06:29:37+00:00","dateModified":"2023-03-06T15:26:00+00:00","description":"Quando si decide di devolvere una parte della propria eredit\u00e0 a un ente benefico, questi una volta ricevuti i beni deve pagare delle tasse sui lasciti solidali?","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/tasse-pagare-sui-lasciti-solidali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/tasse-pagare-sui-lasciti-solidali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/tasse-pagare-sui-lasciti-solidali\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2023\/03\/tasse-sui-lasciti-solidali.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/03\/tasse-sui-lasciti-solidali.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/tasse-pagare-sui-lasciti-solidali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Lasciti Testamentari","item":"https:\/\/www.aibi.it\/ita\/category\/lasciti-testamentari\/"},{"@type":"ListItem","position":3,"name":"Ci sono tasse da pagare sui lasciti solidali?"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 03:24:30","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/210347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=210347"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/210347\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/210350"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=210347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=210347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=210347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}