﻿{"id":210621,"date":"2023-03-16T08:00:32","date_gmt":"2023-03-16T07:00:32","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=210621"},"modified":"2023-03-20T16:04:58","modified_gmt":"2023-03-20T15:04:58","slug":"cina-riapre-confini-speranza-coppie-adottive","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/cina-riapre-confini-speranza-coppie-adottive\/","title":{"rendered":"La Cina riapre i confini. Torna la speranza per tutte le coppie adottive"},"content":{"rendered":"<h2>Dopo tre anni di ferrea chiusura dei confini, la Cina riapre ai turisti e torna a rilasciare visti per l\u2019ingresso nel Paese. \u00c8 finalmente giunta alla fine l\u2019odissea delle coppie adottive che potranno riabbracciare i loro figli?<\/h2>\n<p><!--more--><\/p>\n<p>Fa quasi strano, oggi, tornare a parlare di <strong>Covid<\/strong>, perch\u00e9 davvero, nelle ultime settimane, il virus \u00e8 sostanzialmente sparito non solo da giornali e telegiornali, ma anche dalle conversazioni di tutti tra amici e parenti. Il Covid, sia chiaro, c\u2019\u00e8 ancora: ancora ci si ammala e ancora, purtroppo, ogni giorno si contano dei decessi, ma la situazione non \u00e8 nemmeno lontanamente paragonabile a quella del passato. E, infatti, se oggi si torna a parlare di Covid non \u00e8 per una nuova variante o per lo scoppio di un focolaio, ma per <strong>la fine di una delle ultimissime restrizioni<\/strong> che ancora erano in vigore nel mondo: ovvero quella della chiusura dei confini della Cina ai turisti.<\/p>\n<h3>La Cina riapre i confini ai turisti<\/h3>\n<p>Dopo oltre due anni di durissima politica \u201czero-Covid\u201d, che ha puntato su severi lockdown e totale chiusura del territorio per provare ad arginare il virus, la Cina da qualche tempo ha cambiato strategia e <strong>progressivamente ammorbidito le restrizioni<\/strong>. Ora finalmente arriva uno dei provvedimenti pi\u00f9 attesi: la <strong>riaperture dell\u2019accesso ai turisti su tutto il territorio<\/strong>, con il rilascio di nuovi visti <strong>a partire dal 15 di marzo<\/strong>. Il Governo ha fatto sapere che sar\u00e0 possibile tornare a viaggiare anche in quelle aree per le quali non \u00e8 necessario un visto, come alcune note mete turistiche. Inoltre, potranno essere utilizzati per l\u2019ingresso nel Paese i visti concessi prima della chiusura dei confini ancora in corso di validit\u00e0.<\/p>\n<h3>Un\u2019attesa lunga tre anni<\/h3>\n<p>Se si considera che la chiusura dei confini \u00e8 stata stabilita il <strong>28 marzo del 2020<\/strong>, \u00e8 da tre anni quasi esatti che il <strong>territorio cinese \u00e8 rimasto irraggiungibile<\/strong> per la stragrande maggioranza degli stranieri, comprese le <strong>coppie italiane<\/strong> che hanno un percorso di adozione in essere e che a quella data erano gi\u00e0 state abbinate a dei minori cinesi.<br \/>\nPer tre anni queste coppie, gli enti che li supportano e le autorit\u00e0 competenti italiane <a href=\"https:\/\/www.aibi.it\/ita\/roma-manifestazione-famiglie-adottive-cina\/\">hanno lavorato<\/a> in cerca di una soluzione, ma ogni tentativo finora si era scontrato con problemi, burocrazia e la ferrea politica di chiusura. Ora, con la riapertura dei confini ai turisti, davvero, nonostante sia giustamente da aspettare una <strong>comunicazione ufficiale della CAI<\/strong>, non si vedono ulteriori impedimenti che possano fermare questi genitori, che cos\u00ec a lungo hanno pazientato, dal poter correre ad abbracciare una volta per tutte i loro figli ritrovati!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo tre anni di ferrea chiusura dei confini, la Cina riapre ai turisti e torna a rilasciare visti per l&rsquo;ingresso nel Paese. &Egrave; finalmente giunta alla fine l&rsquo;odissea delle coppie adottive che potranno riabbracciare i loro figli?<\/p>\n","protected":false},"author":102,"featured_media":210624,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[347,434],"class_list":["post-210621","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale","tag-adozione-internazionale","tag-cina"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La Cina riapre i confini. Torna la speranza per le coppie adottive<\/title>\n<meta name=\"description\" content=\"Dopo tre anni di chiusura, la Cina riapre ai turisti e torna a rilasciare visti per l\u2019ingresso nel Paese. Giunge alla fine l\u2019odissea delle coppie adottive?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/cina-riapre-confini-speranza-coppie-adottive\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Cina riapre i confini. Torna la speranza per tutte le coppie adottive\" \/>\n<meta property=\"og:description\" content=\"Dopo tre anni di chiusura, la Cina riapre ai turisti e torna a rilasciare visti per l\u2019ingresso nel Paese. Giunge alla fine l\u2019odissea delle coppie adottive?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/cina-riapre-confini-speranza-coppie-adottive\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-16T07:00:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-20T15:04:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2023\/03\/cina-riapre-confini-coppie-adottive.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-riapre-confini-speranza-coppie-adottive\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-riapre-confini-speranza-coppie-adottive\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"La Cina riapre i confini. Torna la speranza per tutte le coppie adottive\",\"datePublished\":\"2023-03-16T07:00:32+00:00\",\"dateModified\":\"2023-03-20T15:04:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-riapre-confini-speranza-coppie-adottive\\\/\"},\"wordCount\":432,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-riapre-confini-speranza-coppie-adottive\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/03\\\/cina-riapre-confini-coppie-adottive.jpg\",\"keywords\":[\"Adozione Internazionale\",\"Cina\"],\"articleSection\":[\"Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-riapre-confini-speranza-coppie-adottive\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-riapre-confini-speranza-coppie-adottive\\\/\",\"name\":\"La Cina riapre i confini. Torna la speranza per le coppie adottive\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-riapre-confini-speranza-coppie-adottive\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-riapre-confini-speranza-coppie-adottive\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/03\\\/cina-riapre-confini-coppie-adottive.jpg\",\"datePublished\":\"2023-03-16T07:00:32+00:00\",\"dateModified\":\"2023-03-20T15:04:58+00:00\",\"description\":\"Dopo tre anni di chiusura, la Cina riapre ai turisti e torna a rilasciare visti per l\u2019ingresso nel Paese. Giunge alla fine l\u2019odissea delle coppie adottive?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-riapre-confini-speranza-coppie-adottive\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-riapre-confini-speranza-coppie-adottive\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-riapre-confini-speranza-coppie-adottive\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/03\\\/cina-riapre-confini-coppie-adottive.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/03\\\/cina-riapre-confini-coppie-adottive.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-riapre-confini-speranza-coppie-adottive\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La Cina riapre i confini. Torna la speranza per tutte le coppie adottive\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La Cina riapre i confini. Torna la speranza per le coppie adottive","description":"Dopo tre anni di chiusura, la Cina riapre ai turisti e torna a rilasciare visti per l\u2019ingresso nel Paese. Giunge alla fine l\u2019odissea delle coppie adottive?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/cina-riapre-confini-speranza-coppie-adottive\/","og_locale":"it_IT","og_type":"article","og_title":"La Cina riapre i confini. Torna la speranza per tutte le coppie adottive","og_description":"Dopo tre anni di chiusura, la Cina riapre ai turisti e torna a rilasciare visti per l\u2019ingresso nel Paese. Giunge alla fine l\u2019odissea delle coppie adottive?","og_url":"https:\/\/www.aibi.it\/ita\/cina-riapre-confini-speranza-coppie-adottive\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2023-03-16T07:00:32+00:00","article_modified_time":"2023-03-20T15:04:58+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2023\/03\/cina-riapre-confini-coppie-adottive.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/cina-riapre-confini-speranza-coppie-adottive\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/cina-riapre-confini-speranza-coppie-adottive\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"La Cina riapre i confini. Torna la speranza per tutte le coppie adottive","datePublished":"2023-03-16T07:00:32+00:00","dateModified":"2023-03-20T15:04:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/cina-riapre-confini-speranza-coppie-adottive\/"},"wordCount":432,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/cina-riapre-confini-speranza-coppie-adottive\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/03\/cina-riapre-confini-coppie-adottive.jpg","keywords":["Adozione Internazionale","Cina"],"articleSection":["Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/cina-riapre-confini-speranza-coppie-adottive\/","url":"https:\/\/www.aibi.it\/ita\/cina-riapre-confini-speranza-coppie-adottive\/","name":"La Cina riapre i confini. Torna la speranza per le coppie adottive","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/cina-riapre-confini-speranza-coppie-adottive\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/cina-riapre-confini-speranza-coppie-adottive\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/03\/cina-riapre-confini-coppie-adottive.jpg","datePublished":"2023-03-16T07:00:32+00:00","dateModified":"2023-03-20T15:04:58+00:00","description":"Dopo tre anni di chiusura, la Cina riapre ai turisti e torna a rilasciare visti per l\u2019ingresso nel Paese. Giunge alla fine l\u2019odissea delle coppie adottive?","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/cina-riapre-confini-speranza-coppie-adottive\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/cina-riapre-confini-speranza-coppie-adottive\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/cina-riapre-confini-speranza-coppie-adottive\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2023\/03\/cina-riapre-confini-coppie-adottive.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/03\/cina-riapre-confini-coppie-adottive.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/cina-riapre-confini-speranza-coppie-adottive\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"La Cina riapre i confini. Torna la speranza per tutte le coppie adottive"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 09:34:16","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/210621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=210621"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/210621\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/210624"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=210621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=210621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=210621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}