﻿


{"id":210630,"date":"2023-03-19T08:00:06","date_gmt":"2023-03-19T07:00:06","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=210630"},"modified":"2023-03-16T17:52:34","modified_gmt":"2023-03-16T16:52:34","slug":"denatalita-giappone-intelligenza-artificiale","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/denatalita-giappone-intelligenza-artificiale\/","title":{"rendered":"Denatalit\u00e0 record: il Giappone mette in campo l\u2019intelligenza artificiale"},"content":{"rendered":"<h2>Il Giappone \u00e8 uno dei Paesi con i pi\u00f9 grossi problemi di danatalit\u00e0 e di invecchiamento della popolazione. Governo e grandi aziende si affidano anche ad App e intelligenza artificiale per favorire la formazione di nuove famiglie. Ma l\u2019impressione \u00e8 che ci vorr\u00e0 ben altro\u2026<\/h2>\n<p><!--more--><\/p>\n<p>La denatalit\u00e0 \u00e8 un problema che riguarda una gran parte del mondo, non solo in Occidente, visto che anche la Cina, per la prima volta nella sua storia, sta assistendo a una <a href=\"https:\/\/www.aibi.it\/ita\/denatalita-cina-cala-popolazione-tornano-stati-generali-natalita\/\">diminuzione della popolazione<\/a> (problema acuito anche da decenni di \u201cpolitica del figlio unico\u201d che ha portato ad avere uno squilibrio incredibile nella societ\u00e0, con gli uomini che sono, oggi, circa <strong>30 milioni pi\u00f9 delle donne<\/strong>). Uno dei Paesi in cui il fenomeno \u00e8 pi\u00f9 accentuato e preoccupante in assoluto, per\u00f2, \u00e8 il <strong>Giappone<\/strong>, Paese che ha registrato l\u2019ennesimo record negativo di nascite nel 2022, per la prima volta scese <strong>sotto le 800 mila<\/strong> e, soprattutto, che sono state circa la met\u00e0 rispetto alle morti. Il trend in atto ormai da anni ha portato la popolazione a scendere a <strong>124,6 milioni di persone,<\/strong> dal picco di 128 milioni del 2008, e con ormai il 29% dei giapponesi che ha pi\u00f9 di 65 anni, l\u2019esiguo numero di nuovi nati fa aumentare i timori per la tenuta economica e sociale futura del Paese.<\/p>\n<h3>Denatalit\u00e0 Giappone: App e intelligenza artificiale per far nascere nuove famiglie<\/h3>\n<p>L\u2019ha detto chiaramente Masako Mori, consigliera del primo ministro Fumio Kishida: \u201cSe continuiamo in questo modo, il Paese scomparir\u00e0\u201d (da <em>Repubblica<\/em>). Inevitabile, dunque, che il problema della natalit\u00e0 sia tra le priorit\u00e0 del governo, che infatti lo scorso dicembre ha stanziato un <strong>fondo da 35 milioni di euro<\/strong> \u201cper una nuova agenzia governativa che si occupi della questione\u201d.<br \/>\nMa gli analisti sono scettici che questa iniziativa, da sola, possa funzionare: il Giappone, infatti, da tempo attraverso una <strong>fase economica di stallo<\/strong>, mentre nelle citt\u00e0 scarseggiano i servizi di assistenza per l\u2019infanzia e il costo della vita rimane molto alto.<br \/>\nOltre a questi fondi, una delle direzioni intraprese dal Giappone \u00e8 quella di favorire la formazione di nuova famiglie anche <strong>attraverso applicazioni e intelligenza artificiale<\/strong>. Come raccontato sempre da <em>Repubblica<\/em>, in alcune prefetture del Paese i residenti hanno a disposizione un servizio di \u201cmatchmaking\u201d sponsorizzato dal governo e basato sull\u2019intelligenza artificiale, mentre moltissime aziende anche di primo piano (Mizuho, All Nippon Airways, Mitsubishi, giusto per fare tre nomi) offrono ai loro dipendenti una app che <strong>favorisce la conoscenza e \u201cl\u2019incontro\u201d tra colleghi<\/strong>. Una sorta di Tinder su base aziendale, pagata dal datore di lavoro, che, pur con tutta la buona volont\u00e0 e nella consapevolezza che in una situazione del genere ogni incentivo \u00e8 benvenuto, non appare propriamente una strada sicura per invertire un <strong>trend di denatalit\u00e0 che ha radici ben pi\u00f9 profonde e preoccupanti<\/strong> che non la difficolt\u00e0 di incontrare \u201cla persona giusta\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Giappone &egrave; uno dei Paesi con i pi&ugrave; grossi problemi di danatalit&agrave; e di invecchiamento della popolazione. Governo e grandi aziende si affidano anche ad App e intelligenza artificiale per favorire la formazione di nuove famiglie. Ma l&rsquo;impressione &egrave; che ci vorr&agrave; ben altro&hellip;<\/p>\n","protected":false},"author":102,"featured_media":210632,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[299,681],"class_list":["post-210630","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-denatalita","tag-giappone"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Denatalit\u00e0 record: il Giappone prova con l\u2019intelligenza artificiale<\/title>\n<meta name=\"description\" content=\"Denatalit\u00e0 Giappone. Popolazione sempre pi\u00f9 vecchia: governo e aziende si affidano anche ad App e intelligenza artificiale per cercare di formare nuove famiglie\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/denatalita-giappone-intelligenza-artificiale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Denatalit\u00e0 record: il Giappone mette in campo l\u2019intelligenza artificiale\" \/>\n<meta property=\"og:description\" content=\"Denatalit\u00e0 Giappone. Popolazione sempre pi\u00f9 vecchia: governo e aziende si affidano anche ad App e intelligenza artificiale per cercare di formare nuove famiglie\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/denatalita-giappone-intelligenza-artificiale\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-19T07:00:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2023\/03\/denatalita-Giappone.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/denatalita-giappone-intelligenza-artificiale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/denatalita-giappone-intelligenza-artificiale\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Denatalit\u00e0 record: il Giappone mette in campo l\u2019intelligenza artificiale\",\"datePublished\":\"2023-03-19T07:00:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/denatalita-giappone-intelligenza-artificiale\\\/\"},\"wordCount\":471,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/denatalita-giappone-intelligenza-artificiale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/03\\\/denatalita-Giappone.jpg\",\"keywords\":[\"denatalit\u00e0\",\"Giappone\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/denatalita-giappone-intelligenza-artificiale\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/denatalita-giappone-intelligenza-artificiale\\\/\",\"name\":\"Denatalit\u00e0 record: il Giappone prova con l\u2019intelligenza artificiale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/denatalita-giappone-intelligenza-artificiale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/denatalita-giappone-intelligenza-artificiale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/03\\\/denatalita-Giappone.jpg\",\"datePublished\":\"2023-03-19T07:00:06+00:00\",\"description\":\"Denatalit\u00e0 Giappone. Popolazione sempre pi\u00f9 vecchia: governo e aziende si affidano anche ad App e intelligenza artificiale per cercare di formare nuove famiglie\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/denatalita-giappone-intelligenza-artificiale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/denatalita-giappone-intelligenza-artificiale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/denatalita-giappone-intelligenza-artificiale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/03\\\/denatalita-Giappone.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/03\\\/denatalita-Giappone.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/denatalita-giappone-intelligenza-artificiale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Denatalit\u00e0 record: il Giappone mette in campo l\u2019intelligenza artificiale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Denatalit\u00e0 record: il Giappone prova con l\u2019intelligenza artificiale","description":"Denatalit\u00e0 Giappone. Popolazione sempre pi\u00f9 vecchia: governo e aziende si affidano anche ad App e intelligenza artificiale per cercare di formare nuove famiglie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/denatalita-giappone-intelligenza-artificiale\/","og_locale":"it_IT","og_type":"article","og_title":"Denatalit\u00e0 record: il Giappone mette in campo l\u2019intelligenza artificiale","og_description":"Denatalit\u00e0 Giappone. Popolazione sempre pi\u00f9 vecchia: governo e aziende si affidano anche ad App e intelligenza artificiale per cercare di formare nuove famiglie","og_url":"https:\/\/www.aibi.it\/ita\/denatalita-giappone-intelligenza-artificiale\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2023-03-19T07:00:06+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2023\/03\/denatalita-Giappone.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/denatalita-giappone-intelligenza-artificiale\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/denatalita-giappone-intelligenza-artificiale\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Denatalit\u00e0 record: il Giappone mette in campo l\u2019intelligenza artificiale","datePublished":"2023-03-19T07:00:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/denatalita-giappone-intelligenza-artificiale\/"},"wordCount":471,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/denatalita-giappone-intelligenza-artificiale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/03\/denatalita-Giappone.jpg","keywords":["denatalit\u00e0","Giappone"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/denatalita-giappone-intelligenza-artificiale\/","url":"https:\/\/www.aibi.it\/ita\/denatalita-giappone-intelligenza-artificiale\/","name":"Denatalit\u00e0 record: il Giappone prova con l\u2019intelligenza artificiale","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/denatalita-giappone-intelligenza-artificiale\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/denatalita-giappone-intelligenza-artificiale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/03\/denatalita-Giappone.jpg","datePublished":"2023-03-19T07:00:06+00:00","description":"Denatalit\u00e0 Giappone. Popolazione sempre pi\u00f9 vecchia: governo e aziende si affidano anche ad App e intelligenza artificiale per cercare di formare nuove famiglie","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/denatalita-giappone-intelligenza-artificiale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/denatalita-giappone-intelligenza-artificiale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/denatalita-giappone-intelligenza-artificiale\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2023\/03\/denatalita-Giappone.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/03\/denatalita-Giappone.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/denatalita-giappone-intelligenza-artificiale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Denatalit\u00e0 record: il Giappone mette in campo l\u2019intelligenza artificiale"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 10:00:51","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/210630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=210630"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/210630\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/210632"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=210630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=210630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=210630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}