﻿


{"id":211161,"date":"2023-03-31T12:28:51","date_gmt":"2023-03-31T10:28:51","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=211161"},"modified":"2023-03-31T12:28:51","modified_gmt":"2023-03-31T10:28:51","slug":"calo-bollette-luce-secondo-trimestre-2023","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/calo-bollette-luce-secondo-trimestre-2023\/","title":{"rendered":"Crollo delle bollette della luce: per il secondo trimestre 2023 prezzi gi\u00f9 del 55,3%"},"content":{"rendered":"<h2>Comunicate le nuove tariffe per l\u2019energie elettrica del mercato tutelato: meno 55,3% rispetto al primo trimestre. Per una famiglia tipo il risparmio \u00e8 di circa 800 euro in un anno<\/h2>\n<p><!--more--><\/p>\n<p>Sul fatto che le nuove tariffe dell\u2019energia elettrica sarebbero diminuiti ancora c\u2019erano pochi dubbi, ma in pochi si aspettavano <strong>un calo cos\u00ec significativo<\/strong>. L\u2019Arera (Autorit\u00e0 di Regolazione per Energia Reti e Ambeinte), infatti, ha comunicato che i prezzi di riferimento per la bolletta della luce validi per il secondo trimestre 2023 vedono una <strong>riduzione del 55,3%.<\/strong> Un abbassamento notevole figlio in gran parte della riduzione della domanda di gas in Europa, grazie anche al clima mite che ha caratterizzato l\u2019inverno e ha fatto s\u00ec che a marzo gli stoccaggi siano ancora pieni a oltre il 50%. (Come abbiamo <a href=\"https:\/\/www.aibi.it\/ita\/rincari-bollette-luce-record\/\">gi\u00e0 avuto modo di ricordare<\/a>, infatti, il prezzo dell&#8217;energie dipende strettamente da quello del gas)<\/p>\n<h3>Decisivi per il calo bollette la diminuzione della domanda e il clima mite<\/h3>\n<p>Complessivamente, la domanda eruopea di gas \u00e8 stata del <strong>13% in meno<\/strong> rispetto all\u2019anno scorso. Se a questo si aggiungono la ripresa della domanda asiatica di Gas naturale liquefatto e la ripresa o la messa in funzione di <strong>nuovi impianti di rigassificazione<\/strong>, ecco perch\u00e9 l&#8217;energia elettrica e le prossime bollette della luce, nonostante il ripristino del pagamento degli oneri di sistema, costeranno di meno, portando un <strong>risparmio per le famiglie italiane<\/strong> che Assoutenti ha stimato <strong>intorno agli 800 euro<\/strong> su base annuale.<br \/>\nVa ricordato, comunque, che i cali di oggi ancora non riportano la situazione a com\u2019era prima della crisi energetica: considerando \u201cl\u2019anno scorrevole\u201d (ovvero comparando due identici periodi di 12 mesi a un anno di distanza) la spesa tra l\u20191 luglio 2022 e il 30 giugno 2023 risulta ancora <strong>superiore del 33,7%<\/strong> rispetto al periodo 1 luglio 2021 \u2013 30 giugno 2022. Da qui la conferma che c\u2019\u00e8 stata solo pochi giorni fa, nel <a href=\"https:\/\/www.aibi.it\/ita\/nuovo-decreto-bollette-scongiurati-aumenti\/\">decreto bollette<\/a>, di diversi incentivi per le famiglie, come il <strong>bonus sociale<\/strong> rinnovato per tutti i nuclei al di sotto dei 15mila euro di ISEE (o al di sotto del 30mila euro se con 4 o pi\u00f9 figli) e <strong>l\u2019azzeramento degli oneri di sistema<\/strong> per quanto riguarda il gas.<br \/>\nNella speranza che, comunque, la situazione anche a livello internazionale possa migliorare e, con essa, <strong>i prezzi possano continuare a scendere<\/strong>, con ulteriori risparmi per tutte le famiglie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comunicate le nuove tariffe per l&rsquo;energie elettrica del mercato tutelato: meno 55,3% rispetto al primo trimestre. Per una famiglia tipo il risparmio &egrave; di circa 800 euro in un anno<\/p>\n","protected":false},"author":102,"featured_media":211181,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[889,957,951],"class_list":["post-211161","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-bollette","tag-energia","tag-prezzi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Calo bollette luce: per il secondo trimestre prezzi gi\u00f9 del 55,3%<\/title>\n<meta name=\"description\" content=\"Comunicate le nuove tariffe per l\u2019energia elettrica del mercato tutelato: il calo bollette della luce segna un meno 55,3% rispetto al primo trimestre\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/calo-bollette-luce-secondo-trimestre-2023\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crollo delle bollette della luce: per il secondo trimestre 2023 prezzi gi\u00f9 del 55,3%\" \/>\n<meta property=\"og:description\" content=\"Comunicate le nuove tariffe per l\u2019energia elettrica del mercato tutelato: il calo bollette della luce segna un meno 55,3% rispetto al primo trimestre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/calo-bollette-luce-secondo-trimestre-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-31T10:28:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2023\/03\/calo-bollette-energia-elettrica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/calo-bollette-luce-secondo-trimestre-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/calo-bollette-luce-secondo-trimestre-2023\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Crollo delle bollette della luce: per il secondo trimestre 2023 prezzi gi\u00f9 del 55,3%\",\"datePublished\":\"2023-03-31T10:28:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/calo-bollette-luce-secondo-trimestre-2023\\\/\"},\"wordCount\":391,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/calo-bollette-luce-secondo-trimestre-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/03\\\/calo-bollette-energia-elettrica.jpg\",\"keywords\":[\"bollette\",\"energia\",\"prezzi\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/calo-bollette-luce-secondo-trimestre-2023\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/calo-bollette-luce-secondo-trimestre-2023\\\/\",\"name\":\"Calo bollette luce: per il secondo trimestre prezzi gi\u00f9 del 55,3%\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/calo-bollette-luce-secondo-trimestre-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/calo-bollette-luce-secondo-trimestre-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/03\\\/calo-bollette-energia-elettrica.jpg\",\"datePublished\":\"2023-03-31T10:28:51+00:00\",\"description\":\"Comunicate le nuove tariffe per l\u2019energia elettrica del mercato tutelato: il calo bollette della luce segna un meno 55,3% rispetto al primo trimestre\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/calo-bollette-luce-secondo-trimestre-2023\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/calo-bollette-luce-secondo-trimestre-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/calo-bollette-luce-secondo-trimestre-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/03\\\/calo-bollette-energia-elettrica.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/03\\\/calo-bollette-energia-elettrica.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/calo-bollette-luce-secondo-trimestre-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Crollo delle bollette della luce: per il secondo trimestre 2023 prezzi gi\u00f9 del 55,3%\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Calo bollette luce: per il secondo trimestre prezzi gi\u00f9 del 55,3%","description":"Comunicate le nuove tariffe per l\u2019energia elettrica del mercato tutelato: il calo bollette della luce segna un meno 55,3% rispetto al primo trimestre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/calo-bollette-luce-secondo-trimestre-2023\/","og_locale":"it_IT","og_type":"article","og_title":"Crollo delle bollette della luce: per il secondo trimestre 2023 prezzi gi\u00f9 del 55,3%","og_description":"Comunicate le nuove tariffe per l\u2019energia elettrica del mercato tutelato: il calo bollette della luce segna un meno 55,3% rispetto al primo trimestre","og_url":"https:\/\/www.aibi.it\/ita\/calo-bollette-luce-secondo-trimestre-2023\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2023-03-31T10:28:51+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2023\/03\/calo-bollette-energia-elettrica.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/calo-bollette-luce-secondo-trimestre-2023\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/calo-bollette-luce-secondo-trimestre-2023\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Crollo delle bollette della luce: per il secondo trimestre 2023 prezzi gi\u00f9 del 55,3%","datePublished":"2023-03-31T10:28:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/calo-bollette-luce-secondo-trimestre-2023\/"},"wordCount":391,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/calo-bollette-luce-secondo-trimestre-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/03\/calo-bollette-energia-elettrica.jpg","keywords":["bollette","energia","prezzi"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/calo-bollette-luce-secondo-trimestre-2023\/","url":"https:\/\/www.aibi.it\/ita\/calo-bollette-luce-secondo-trimestre-2023\/","name":"Calo bollette luce: per il secondo trimestre prezzi gi\u00f9 del 55,3%","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/calo-bollette-luce-secondo-trimestre-2023\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/calo-bollette-luce-secondo-trimestre-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/03\/calo-bollette-energia-elettrica.jpg","datePublished":"2023-03-31T10:28:51+00:00","description":"Comunicate le nuove tariffe per l\u2019energia elettrica del mercato tutelato: il calo bollette della luce segna un meno 55,3% rispetto al primo trimestre","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/calo-bollette-luce-secondo-trimestre-2023\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/calo-bollette-luce-secondo-trimestre-2023\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/calo-bollette-luce-secondo-trimestre-2023\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2023\/03\/calo-bollette-energia-elettrica.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/03\/calo-bollette-energia-elettrica.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/calo-bollette-luce-secondo-trimestre-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Crollo delle bollette della luce: per il secondo trimestre 2023 prezzi gi\u00f9 del 55,3%"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:27:03","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/211161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=211161"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/211161\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/211181"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=211161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=211161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=211161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}