﻿


{"id":211316,"date":"2023-04-05T08:00:21","date_gmt":"2023-04-05T06:00:21","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=211316"},"modified":"2023-04-05T09:17:00","modified_gmt":"2023-04-05T07:17:00","slug":"calcolatore-assegno-unico","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/calcolatore-assegno-unico\/","title":{"rendered":"Come calcolare i nuovi importi dell\u2019Assegno Unico? Ecco il nuovo calcolatore dell\u2019INPS"},"content":{"rendered":"<h2>L\u2019INPS ha predisposto sul suo sito Internet un nuovo calcolatore che permette di stimare l\u2019importo dell\u2019Assegno Unico dopo le modifiche e gli aumenti introdotti a partire dal 2023<\/h2>\n<p><!--more--><\/p>\n<p>Come noto, nel 2023 l\u2019Assegno Unico ha subito qualche modifica: non solo gli importi, tanto delle quote \u201cbase\u201d quanto delle maggiorazioni, sono stati indicizzati all\u2019inflazione (particolarmente significativa in termini percentuali), ma il Governo ha anche introdotto <a href=\"https:\/\/www.aibi.it\/ita\/le-novita-per-l-assegno-unico-gli-aumenti-scattano-da-febbraio\/\">alcuni cambiamenti<\/a> che hanno fatto salire la cifra destinata a molte famiglie.<br \/>\nI nuovi importi sono gi\u00e0 stati percepiti a partire dal mese di febbraio, cos\u00ec come \u00e8 stato pagato, a parte, <a href=\"https:\/\/www.aibi.it\/ita\/assegno-unico-conguaglio-gennaio\/\">il conguaglio<\/a> relativo alla differenza sul mese di gennaio (inizialmente pagato ancora secondo i calcoli del 2022). Naturale ci possa essere un po\u2019 di confusione visto che le modifiche non sono cos\u00ec poche: per esempio sono stati <strong>aumentati gli importi per i figli<\/strong> al di sotto di un anno o al di sotto dei tre anni per le famiglie con almeno tre figli e ISEE inferiore a 40mila euro; sono stati confermati e definiti gli aumenti gi\u00e0 partiti nel 2022 <strong>per i figli disabili<\/strong> che hanno gi\u00e0 compiuto la maggiore et\u00e0, cos\u00ec come gli incrementi della maggiorazione transitoria per le famiglie con figli disabili.<\/p>\n<h3>Il nuovo calcolatore dell\u2019INPS per l\u2019Assegno Unico<\/h3>\n<p>Ecco che allora, a fronte di tutti questo, pu\u00f2 diventare molto utile il <strong><a href=\"https:\/\/servizi2.inps.it\/servizi\/AssegnoUnicoFigli\/Simulatore\">nuovo calcolatore<\/a><\/strong> che l\u2019INPS ha messo online sul proprio sito e che permette di avere un\u2019indicazione dell\u2019importo dell\u2019Assegno Unico spettante a ciascuna famiglia a seconda della propria situazione.<br \/>\nLa consultazione \u00e8 facilitata dal fatto che il sistema pone alcune domande all\u2019utente le cui risposte modificano le successive richieste, cos\u00ec che <strong>non vengano posti quesiti inutili<\/strong>. Inoltre, in caso di errore, il sistema stesso segnala se una risposta data sia inconciliabile con una di quelle date in precedenza, permettendo cos\u00ec di rifare velocemente i calcoli corretti.<br \/>\nLa procedura, alla quale si pu\u00f2 accedere <strong>senza dover autenticarsi<\/strong>, d\u00e0 solo un\u2019indicazione dell\u2019importo e non \u00e8 in alcun modo una modalit\u00e0 per richiedere l\u2019assegno, la cui domanda continua a seguire le modalit\u00e0 comunicate sinora e pu\u00f2 essere presentata in autonomia sempre attraverso il sito dell\u2019INPS (ma loggandosi con SPID o CIE) o avvalendosi del supporto di un patronato.<\/p>\n<h3>Subentro del \u201cGenitore affidatario\u201d in caso di decesso di un genitore<\/h3>\n<p>In occasione della presentazione del nuovo calcolatore, L\u2019INPS ha comunicato di aver anche introdotto alcune nuove funzionalit\u00e0. In particolare, \u00e8 ora possibile <strong>presentare la domanda di \u201csebentro\u201d come genitore affidatario<\/strong>, tutore o figlio maggiorenne in caso di decesso del genitore che ha richiesto l\u2019assegno unico o di entrambi i genitori. Inoltre, \u00e8 stato specificato che nel caso di decesso dell\u2019 \u201caltro\u201d genitore (ovvero del genitore che non ha presentato la richiesta dell\u2019assegno unico) il nuovo importo dell\u2019Assegno verr\u00e0 calcolato in maniera automatica senza bisogno di inoltrare una nuova domanda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;INPS ha predisposto sul suo sito Internet un nuovo calcolatore che permette di stimare l&rsquo;importo dell&rsquo;Assegno Unico dopo le modifiche e gli aumenti introdotti a partire dal 2023<\/p>\n","protected":false},"author":102,"featured_media":211318,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[750,931],"class_list":["post-211316","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-assegno-unico","tag-inps"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Il nuovo calcolatore Assegno Unico dell&#039;INPS<\/title>\n<meta name=\"description\" content=\"L\u2019INPS ha predisposto sul suo sito Internet un nuovo calcolatore Assegno Unico che permette di stimare gli importi dopo le modifiche introdotte nel 2023\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/calcolatore-assegno-unico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come calcolare i nuovi importi dell\u2019Assegno Unico? Ecco il nuovo calcolatore dell\u2019INPS\" \/>\n<meta property=\"og:description\" content=\"L\u2019INPS ha predisposto sul suo sito Internet un nuovo calcolatore Assegno Unico che permette di stimare gli importi dopo le modifiche introdotte nel 2023\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/calcolatore-assegno-unico\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-05T06:00:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-05T07:17:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2023\/04\/Calcolatore-Assegno-Unico.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/calcolatore-assegno-unico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/calcolatore-assegno-unico\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Come calcolare i nuovi importi dell\u2019Assegno Unico? Ecco il nuovo calcolatore dell\u2019INPS\",\"datePublished\":\"2023-04-05T06:00:21+00:00\",\"dateModified\":\"2023-04-05T07:17:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/calcolatore-assegno-unico\\\/\"},\"wordCount\":489,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/calcolatore-assegno-unico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/04\\\/Calcolatore-Assegno-Unico.jpg\",\"keywords\":[\"assegno unico\",\"INPS\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/calcolatore-assegno-unico\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/calcolatore-assegno-unico\\\/\",\"name\":\"Il nuovo calcolatore Assegno Unico dell'INPS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/calcolatore-assegno-unico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/calcolatore-assegno-unico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/04\\\/Calcolatore-Assegno-Unico.jpg\",\"datePublished\":\"2023-04-05T06:00:21+00:00\",\"dateModified\":\"2023-04-05T07:17:00+00:00\",\"description\":\"L\u2019INPS ha predisposto sul suo sito Internet un nuovo calcolatore Assegno Unico che permette di stimare gli importi dopo le modifiche introdotte nel 2023\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/calcolatore-assegno-unico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/calcolatore-assegno-unico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/calcolatore-assegno-unico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/04\\\/Calcolatore-Assegno-Unico.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/04\\\/Calcolatore-Assegno-Unico.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/calcolatore-assegno-unico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Come calcolare i nuovi importi dell\u2019Assegno Unico? Ecco il nuovo calcolatore dell\u2019INPS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Il nuovo calcolatore Assegno Unico dell'INPS","description":"L\u2019INPS ha predisposto sul suo sito Internet un nuovo calcolatore Assegno Unico che permette di stimare gli importi dopo le modifiche introdotte nel 2023","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/calcolatore-assegno-unico\/","og_locale":"it_IT","og_type":"article","og_title":"Come calcolare i nuovi importi dell\u2019Assegno Unico? Ecco il nuovo calcolatore dell\u2019INPS","og_description":"L\u2019INPS ha predisposto sul suo sito Internet un nuovo calcolatore Assegno Unico che permette di stimare gli importi dopo le modifiche introdotte nel 2023","og_url":"https:\/\/www.aibi.it\/ita\/calcolatore-assegno-unico\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2023-04-05T06:00:21+00:00","article_modified_time":"2023-04-05T07:17:00+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2023\/04\/Calcolatore-Assegno-Unico.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/calcolatore-assegno-unico\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/calcolatore-assegno-unico\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Come calcolare i nuovi importi dell\u2019Assegno Unico? Ecco il nuovo calcolatore dell\u2019INPS","datePublished":"2023-04-05T06:00:21+00:00","dateModified":"2023-04-05T07:17:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/calcolatore-assegno-unico\/"},"wordCount":489,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/calcolatore-assegno-unico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/04\/Calcolatore-Assegno-Unico.jpg","keywords":["assegno unico","INPS"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/calcolatore-assegno-unico\/","url":"https:\/\/www.aibi.it\/ita\/calcolatore-assegno-unico\/","name":"Il nuovo calcolatore Assegno Unico dell'INPS","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/calcolatore-assegno-unico\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/calcolatore-assegno-unico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/04\/Calcolatore-Assegno-Unico.jpg","datePublished":"2023-04-05T06:00:21+00:00","dateModified":"2023-04-05T07:17:00+00:00","description":"L\u2019INPS ha predisposto sul suo sito Internet un nuovo calcolatore Assegno Unico che permette di stimare gli importi dopo le modifiche introdotte nel 2023","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/calcolatore-assegno-unico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/calcolatore-assegno-unico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/calcolatore-assegno-unico\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2023\/04\/Calcolatore-Assegno-Unico.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/04\/Calcolatore-Assegno-Unico.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/calcolatore-assegno-unico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Come calcolare i nuovi importi dell\u2019Assegno Unico? Ecco il nuovo calcolatore dell\u2019INPS"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:34:09","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/211316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=211316"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/211316\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/211318"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=211316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=211316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=211316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}