﻿


{"id":211374,"date":"2023-04-11T08:00:50","date_gmt":"2023-04-11T06:00:50","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=211374"},"modified":"2023-04-19T14:43:56","modified_gmt":"2023-04-19T12:43:56","slug":"barletta-benedizione-adozioni","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/barletta-benedizione-adozioni\/","title":{"rendered":"Barletta.&#8221;Un\u2019adozione benedetta&#8221;: torna in Puglia il rito della &#8220;Benedizione delle Adozioni&#8221;"},"content":{"rendered":"<h2>La cerimonia sar\u00e0 celebrata Domenica 16 aprile, presso il Santuario Maria S.S. dello Sterpeto di Barletta,da S.E. Mons. Leonardo D\u2019Ascenzo, Arcivescovo della Diocesi di Trani-Barletta-Bisceglie. Seguir\u00e0, nel pomeriggio, un incontro del Presidente di Ai.Bi. con le famiglie adottive per celebrare i 10 anni di attivit\u00e0 di AiBi Barletta<\/h2>\n<p><!--more--><\/p>\n<p><strong>Domenica 16 aprile, <\/strong>alle ore <strong>11.30<\/strong>, presso il Santuario Maria S.S. dello Sterpeto di Barletta, (viale del Santuario n.13), <strong>S.E. Mons. Leonardo D\u2019Ascenzo<\/strong>, Arcivescovo della Diocesi di Trani-Barletta-Bisceglie, celebrer\u00e0 il <strong>Rito per la Benedizione delle Adozioni<\/strong>.<br \/>\nIl rito, promosso da tempo dall\u2019associazione \u201cLa Pietra Scartata\u201d e dalle famiglie di Ai.Bi., ha lo scopo di <strong>esprimere il senso autentico delle relazioni che nell\u2019adozione si istituiscono per reciproco atto di accoglienza e di fede: <\/strong>c\u2019\u00e8 una famiglia adottiva e c\u2019\u00e8 un bambino che non era pi\u00f9 figlio e che <strong>torna a esserlo<\/strong>, facendosi accogliere <strong>nel nome del Signore<\/strong>.<br \/>\nSar\u00e0, dunque, un\u2019occasione per tutte le famiglie della diocesi di testimoniare il miracolo dell\u2019accoglienza adottiva, compiuta nel nome di Ges\u00f9 dinanzi alla locale comunit\u00e0 cristiana.<br \/>\nIl Rito per la Benedizione delle Adozioni che viene proposto in questa occasione per le famiglie di tutta la Puglia \u00e8 gi\u00e0 stato celebrato in altre diocesi (Milano, Salerno, Torino, Bari, Venezia, Bologna, Fiesole\u2026) e, in diversi casi, inserito quale periodico appuntamento del cammino proposto dalla pastorale familiare.<\/p>\n<h3>I 10 anni di attivit\u00e0 della sede Ai.Bi. di Barletta<\/h3>\n<p>La Benedizione delle Adozioni sar\u00e0 anche un modo per ricordare i 10 anni di attivit\u00e0 della sede Ai.Bi.<br \/>\nBarletta, operativa dal 2012\/2013.<br \/>\nPer celebrare nel migliore dei modi la ricorrenza, nel pomeriggio della stessa giornata di domenica 16, a<br \/>\npartire dalle ore 15.00, le famiglie adottive si confronteranno sul tema \u201cAdozione: un cammino di grazia?\u201d<\/p>\n<p>Questo il programma:<br \/>\n<strong>ore 15.15<\/strong>: introduzione e apertura lavori \u201c10 anni di Ai.Bi. in Puglia\u201d- Dott.ssa <strong>Floriana Canfora<\/strong> referente sede Ai.Bi. Barletta<br \/>\n<strong>ore 15.30<\/strong>: testimonianza di una famiglia adottiva<br \/>\n<strong>ore 15.50<\/strong>: testimonianza di Greta\u2026 una figlia accogliente<br \/>\n<strong>ore 16.15<\/strong>: intervento del Presidente Ai.Bi. <strong>Marco Griffini<br \/>\n<\/strong><strong>ore 16.45<\/strong>: conclusioni e saluti<br \/>\nModera l\u2019incontro <strong>Antonio Gorgoglione<\/strong>, coordinatore Movimento Famiglie Ai.Bi. Puglia<\/p>\n<p>L\u2019invito alla partecipazione \u00e8 rivolto e aperto a tutti e all\u2019intera comunit\u00e0 cristiana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La cerimonia sar&agrave; celebrata Domenica 16 aprile, presso il Santuario Maria S.S. dello Sterpeto di Barletta,da S.E. Mons. Leonardo D&rsquo;Ascenzo, Arcivescovo della Diocesi di Trani-Barletta-Bisceglie. Seguir&agrave;, nel pomeriggio, un incontro del Presidente di Ai.Bi. con le famiglie adottive per celebrare i 10 anni di attivit&agrave; di AiBi Barletta<\/p>\n","protected":false},"author":102,"featured_media":211376,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[279,370,348],"class_list":["post-211374","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale","tag-adozione","tag-barletta","tag-italia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Barletta. Benedizione delle adozioni e incontro su Adozione<\/title>\n<meta name=\"description\" content=\"Domenica 16 aprile. S.E. Mons. Leonardo D\u2019Ascenzo, Arcivescovo della Diocesi di Trani-Barletta-Bisceglie, celebrer\u00e0 il Rito per la Benedizione delle Adozioni\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/barletta-benedizione-adozioni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Barletta.&quot;Un\u2019adozione benedetta&quot;: torna in Puglia il rito della &quot;Benedizione delle Adozioni&quot;\" \/>\n<meta property=\"og:description\" content=\"Domenica 16 aprile. S.E. Mons. Leonardo D\u2019Ascenzo, Arcivescovo della Diocesi di Trani-Barletta-Bisceglie, celebrer\u00e0 il Rito per la Benedizione delle Adozioni\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/barletta-benedizione-adozioni\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-11T06:00:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-19T12:43:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2023\/04\/Benedizione-Adozioni-Barletta.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"629\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/barletta-benedizione-adozioni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/barletta-benedizione-adozioni\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Barletta.&#8221;Un\u2019adozione benedetta&#8221;: torna in Puglia il rito della &#8220;Benedizione delle Adozioni&#8221;\",\"datePublished\":\"2023-04-11T06:00:50+00:00\",\"dateModified\":\"2023-04-19T12:43:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/barletta-benedizione-adozioni\\\/\"},\"wordCount\":374,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/barletta-benedizione-adozioni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/04\\\/Benedizione-Adozioni-Barletta.jpg\",\"keywords\":[\"adozione\",\"Barletta\",\"Italia\"],\"articleSection\":[\"Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/barletta-benedizione-adozioni\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/barletta-benedizione-adozioni\\\/\",\"name\":\"Barletta. Benedizione delle adozioni e incontro su Adozione\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/barletta-benedizione-adozioni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/barletta-benedizione-adozioni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/04\\\/Benedizione-Adozioni-Barletta.jpg\",\"datePublished\":\"2023-04-11T06:00:50+00:00\",\"dateModified\":\"2023-04-19T12:43:56+00:00\",\"description\":\"Domenica 16 aprile. S.E. Mons. Leonardo D\u2019Ascenzo, Arcivescovo della Diocesi di Trani-Barletta-Bisceglie, celebrer\u00e0 il Rito per la Benedizione delle Adozioni\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/barletta-benedizione-adozioni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/barletta-benedizione-adozioni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/barletta-benedizione-adozioni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/04\\\/Benedizione-Adozioni-Barletta.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/04\\\/Benedizione-Adozioni-Barletta.jpg\",\"width\":1200,\"height\":629},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/barletta-benedizione-adozioni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Barletta.&#8221;Un\u2019adozione benedetta&#8221;: torna in Puglia il rito della &#8220;Benedizione delle Adozioni&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Barletta. Benedizione delle adozioni e incontro su Adozione","description":"Domenica 16 aprile. S.E. Mons. Leonardo D\u2019Ascenzo, Arcivescovo della Diocesi di Trani-Barletta-Bisceglie, celebrer\u00e0 il Rito per la Benedizione delle Adozioni","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/barletta-benedizione-adozioni\/","og_locale":"it_IT","og_type":"article","og_title":"Barletta.\"Un\u2019adozione benedetta\": torna in Puglia il rito della \"Benedizione delle Adozioni\"","og_description":"Domenica 16 aprile. S.E. Mons. Leonardo D\u2019Ascenzo, Arcivescovo della Diocesi di Trani-Barletta-Bisceglie, celebrer\u00e0 il Rito per la Benedizione delle Adozioni","og_url":"https:\/\/www.aibi.it\/ita\/barletta-benedizione-adozioni\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2023-04-11T06:00:50+00:00","article_modified_time":"2023-04-19T12:43:56+00:00","og_image":[{"width":1200,"height":629,"url":"https:\/\/www.aibi.it\/ita\/images\/2023\/04\/Benedizione-Adozioni-Barletta.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/barletta-benedizione-adozioni\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/barletta-benedizione-adozioni\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Barletta.&#8221;Un\u2019adozione benedetta&#8221;: torna in Puglia il rito della &#8220;Benedizione delle Adozioni&#8221;","datePublished":"2023-04-11T06:00:50+00:00","dateModified":"2023-04-19T12:43:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/barletta-benedizione-adozioni\/"},"wordCount":374,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/barletta-benedizione-adozioni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/04\/Benedizione-Adozioni-Barletta.jpg","keywords":["adozione","Barletta","Italia"],"articleSection":["Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/barletta-benedizione-adozioni\/","url":"https:\/\/www.aibi.it\/ita\/barletta-benedizione-adozioni\/","name":"Barletta. Benedizione delle adozioni e incontro su Adozione","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/barletta-benedizione-adozioni\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/barletta-benedizione-adozioni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/04\/Benedizione-Adozioni-Barletta.jpg","datePublished":"2023-04-11T06:00:50+00:00","dateModified":"2023-04-19T12:43:56+00:00","description":"Domenica 16 aprile. S.E. Mons. Leonardo D\u2019Ascenzo, Arcivescovo della Diocesi di Trani-Barletta-Bisceglie, celebrer\u00e0 il Rito per la Benedizione delle Adozioni","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/barletta-benedizione-adozioni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/barletta-benedizione-adozioni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/barletta-benedizione-adozioni\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2023\/04\/Benedizione-Adozioni-Barletta.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/04\/Benedizione-Adozioni-Barletta.jpg","width":1200,"height":629},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/barletta-benedizione-adozioni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Barletta.&#8221;Un\u2019adozione benedetta&#8221;: torna in Puglia il rito della &#8220;Benedizione delle Adozioni&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:34:07","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/211374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=211374"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/211374\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/211376"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=211374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=211374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=211374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}