﻿{"id":21229,"date":"2011-03-31T15:04:33","date_gmt":"2011-03-31T14:04:33","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=21229"},"modified":"2011-04-05T14:33:54","modified_gmt":"2011-04-05T13:33:54","slug":"ferrara-1%c2%b0-convegno-nazionale-sui-care-leavers","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/ferrara-1%c2%b0-convegno-nazionale-sui-care-leavers\/","title":{"rendered":"Ferrara: 1\u00b0 Convegno nazionale sui care-leavers"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/care11.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-21230\" style=\"margin: 5px;\" title=\"care1\" src=\"https:\/\/www.aibi.it\/ita\/images\/care11.jpg\" alt=\"\" width=\"100\" height=\"100\" \/><\/a>Venerd\u00ec 1 aprile si terr\u00e0 a Ferrara alla \u201cCitt\u00e0 del Ragazzo\u201d il primo convegno nazionale dedicato ai care-leavers, dal titolo <strong>\u201cNeomaggiorenni e autonomia\u201d.<\/strong><\/p>\n<p>L\u2019obiettivo di questa giornata congressuale, \u00e8 quello di approfondire la riflessione in merito agli interventi di sostegno e accompagnamento all\u2019autonomia<strong> nei confronti di neomaggiorenni e giovani-adulti<\/strong> <strong>che concludono il percorso di accoglienza residenziale in comunit\u00e0 per minori e\/o affidamento familiare.<\/strong><\/p>\n<p>Amici dei Bambini promuove ormai da anni progetti di ricerca europei e interventi di cooperazione internazionale per quei ragazzi che escono dai servizi di protezione all\u2019infanzia di tipo residenziale (quali istituti, comunit\u00e0 educative\/alloggio, case famiglia, etc.) e che spesso si trovano a dover affrontare, ad un\u2019et\u00e0 prefissata per legge, <strong>il dover essere improvvisamente adulti<\/strong>, sprovvisti di una rete familiare e di un sostegno nel medio periodo che possa aiutarli in questa transizione.<\/p>\n<p>Partendo dalle <strong><em>Linee guida per l\u2019inclusione sociale dei giovani careleavers<\/em><\/strong><em> <\/em>(vedi www.childout.org) elaborate in un precedente progetto di ricerca, Ai.Bi. ha dato vita in Italia (Bologna) in Bulgaria (Sofia) ed in Romania (Bucarest) <strong>al progetto europeo di sperimentazione sociale \u201c<em>Supporting life after institutional care<\/em>\u201d<\/strong>&#8211; co-finanziato dal <em>Programma EU Progress <\/em>\u2013 che si propone di accompagnare i giovani fuori famiglia nella fase delicata del post-uscita dal sistema di protezione all\u2019infanzia, affiancando loro una apposita figura professionale denominata <strong>\u201cintermediario sociale\u201d.<\/strong><\/p>\n<p><strong>L\u2019intermediario sociale affianca il\/la giovane care-leaver<\/strong> (indicativamente 18-24 anni) nel <strong>momento di crescita verso \u201cle autonomie\u201d<\/strong> (esplicitandone meglio quelle a lui\/lei pi\u00f9 adeguate); \u00e8 un \u201ctraduttore\u201d per il giovane della realt\u00e0 quotidiana, un consulente di orientamento e si caratterizza per una nuova relazione educativa basata su un rapporto adulto (e quindi rischioso) e quanto \u201cmeno asimmetrico\u201d possibile con il giovane stesso, favorendone l\u2019autonomia in ambito abitativo, lavorativo, legale, sociale e delle relazioni con la famiglia di origine, ove presente. <em>\u00abE\u2019 quindi un educatore strictu sensu, consulente di giovani adulti che hanno bisogno di completare i percorsi di crescita desiderati; sostiene e <\/em><em>propone arricchimenti ai progetti di vita dei care-leavers, attraverso opportuni strumenti che hanno finalit\u00e0 condivise e obiettivi misurabili\u00bb.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Venerd\u00ec 1 aprile si terr\u00e0 a Ferrara alla \u201cCitt\u00e0 del Ragazzo\u201d il primo convegno nazionale dedicato ai care-leavers, dal titolo <strong>\u201cNeomaggiorenni e autostima\u201d.<\/strong> L\u2019obiettivo di questa giornata \u00e8 quello di approfondire la riflessione in merito agli interventi di sostegno <strong>nei confronti di neomaggiorenni e giovani-adulti. <a href=\"https:\/\/www.aibi.it\/ita\/ferrara-1\u00b0-convegno-nazionale-sui-care-leavers\/\">LEGGI TUTTO&#8230;<\/a><\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-21229","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ferrara: 1\u00b0 Convegno nazionale sui care-leavers - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/ferrara-1\u00b0-convegno-nazionale-sui-care-leavers\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ferrara: 1\u00b0 Convegno nazionale sui care-leavers\" \/>\n<meta property=\"og:description\" content=\"Venerd\u00ec 1 aprile si terr\u00e0 a Ferrara alla \u201cCitt\u00e0 del Ragazzo\u201d il primo convegno nazionale dedicato ai care-leavers, dal titolo \u201cNeomaggiorenni e autostima\u201d. L\u2019obiettivo di questa giornata \u00e8 quello di approfondire la riflessione in merito agli interventi di sostegno nei confronti di neomaggiorenni e giovani-adulti. LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/ferrara-1\u00b0-convegno-nazionale-sui-care-leavers\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-03-31T14:04:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-04-05T13:33:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/care11.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ferrara-1%c2%b0-convegno-nazionale-sui-care-leavers\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ferrara-1%c2%b0-convegno-nazionale-sui-care-leavers\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Ferrara: 1\u00b0 Convegno nazionale sui care-leavers\",\"datePublished\":\"2011-03-31T14:04:33+00:00\",\"dateModified\":\"2011-04-05T13:33:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ferrara-1%c2%b0-convegno-nazionale-sui-care-leavers\\\/\"},\"wordCount\":349,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ferrara-1%c2%b0-convegno-nazionale-sui-care-leavers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/care11.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ferrara-1%c2%b0-convegno-nazionale-sui-care-leavers\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ferrara-1%c2%b0-convegno-nazionale-sui-care-leavers\\\/\",\"name\":\"Ferrara: 1\u00b0 Convegno nazionale sui care-leavers - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ferrara-1%c2%b0-convegno-nazionale-sui-care-leavers\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ferrara-1%c2%b0-convegno-nazionale-sui-care-leavers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/care11.jpg\",\"datePublished\":\"2011-03-31T14:04:33+00:00\",\"dateModified\":\"2011-04-05T13:33:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ferrara-1%c2%b0-convegno-nazionale-sui-care-leavers\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ferrara-1%c2%b0-convegno-nazionale-sui-care-leavers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ferrara-1%c2%b0-convegno-nazionale-sui-care-leavers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/care11.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/care11.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ferrara-1%c2%b0-convegno-nazionale-sui-care-leavers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ferrara: 1\u00b0 Convegno nazionale sui care-leavers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ferrara: 1\u00b0 Convegno nazionale sui care-leavers - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/ferrara-1\u00b0-convegno-nazionale-sui-care-leavers\/","og_locale":"it_IT","og_type":"article","og_title":"Ferrara: 1\u00b0 Convegno nazionale sui care-leavers","og_description":"Venerd\u00ec 1 aprile si terr\u00e0 a Ferrara alla \u201cCitt\u00e0 del Ragazzo\u201d il primo convegno nazionale dedicato ai care-leavers, dal titolo \u201cNeomaggiorenni e autostima\u201d. L\u2019obiettivo di questa giornata \u00e8 quello di approfondire la riflessione in merito agli interventi di sostegno nei confronti di neomaggiorenni e giovani-adulti. LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/ferrara-1\u00b0-convegno-nazionale-sui-care-leavers\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2011-03-31T14:04:33+00:00","article_modified_time":"2011-04-05T13:33:54+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/care11.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/ferrara-1%c2%b0-convegno-nazionale-sui-care-leavers\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/ferrara-1%c2%b0-convegno-nazionale-sui-care-leavers\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Ferrara: 1\u00b0 Convegno nazionale sui care-leavers","datePublished":"2011-03-31T14:04:33+00:00","dateModified":"2011-04-05T13:33:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/ferrara-1%c2%b0-convegno-nazionale-sui-care-leavers\/"},"wordCount":349,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/ferrara-1%c2%b0-convegno-nazionale-sui-care-leavers\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/care11.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/ferrara-1%c2%b0-convegno-nazionale-sui-care-leavers\/","url":"https:\/\/www.aibi.it\/ita\/ferrara-1%c2%b0-convegno-nazionale-sui-care-leavers\/","name":"Ferrara: 1\u00b0 Convegno nazionale sui care-leavers - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/ferrara-1%c2%b0-convegno-nazionale-sui-care-leavers\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/ferrara-1%c2%b0-convegno-nazionale-sui-care-leavers\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/care11.jpg","datePublished":"2011-03-31T14:04:33+00:00","dateModified":"2011-04-05T13:33:54+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/ferrara-1%c2%b0-convegno-nazionale-sui-care-leavers\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/ferrara-1%c2%b0-convegno-nazionale-sui-care-leavers\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/ferrara-1%c2%b0-convegno-nazionale-sui-care-leavers\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/care11.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/care11.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/ferrara-1%c2%b0-convegno-nazionale-sui-care-leavers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Ferrara: 1\u00b0 Convegno nazionale sui care-leavers"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 18:09:40","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/21229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=21229"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/21229\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=21229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=21229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=21229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}