﻿


{"id":212319,"date":"2023-05-05T07:30:20","date_gmt":"2023-05-05T05:30:20","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=212319"},"modified":"2023-05-29T17:25:01","modified_gmt":"2023-05-29T15:25:01","slug":"ghana-lotta-contro-abbandono-prevenzione","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/ghana-lotta-contro-abbandono-prevenzione\/","title":{"rendered":"Ghana. La lotta contro\u00a0l\u2019abbandono:\u00a0la prevenzione"},"content":{"rendered":"<h2><b>La prevenzione dell\u2019abbandono \u00e8 stato l\u2019obiettivo principale del progetto \u201cHOME\u201d attuato da Amici dei Bambini in GHANA che ha coinvolto pi\u00f9 di 260 \u00a0minori degli orfanotrofi e di decine di famiglie vulnerabili<\/b><\/h2>\n<p><!--more--><\/p>\n<p>\u201cHOME &#8211; GHana, COsta d\u2019Avorio, Sierra Leone: un Network per l\u2019accoglienza e l\u2019educazione di Minori vulnErabili\u201d <b>\u00e8 il progetto multi-country finanziato dalla\u00a0CAI\u00a0e portato avanti da Ai.Bi. in Ghana\u00a0in partnership con AVSI .\u00a0<\/b><\/p>\n<h3><b>Le attivit\u00e0 di Ai.Bi. in Ghana<\/b><\/h3>\n<p><b>Amici dei Bambini, insieme a VIS<\/b> &#8211; Volontari per lo Sviluppo e Child Protection Centre (Salesians of Don Bosco) ha sviluppato diverse attivit\u00e0 in Ghana per contribuire al potenziamento di una rete di attori pubblici e privati (famiglie e comunit\u00e0) <b>impegnati ad\u00a0assicurare il benessere di bambine e bambini e prevenirne l\u2019abbandono<\/b>, migliorando la qualit\u00e0 del sistema di accoglienza dei minori in stato di vulnerabilit\u00e0 e <b>favorendo lo sviluppo di percorsi educativi <\/b>adatti a sostenere il loro sviluppo integrale.<\/p>\n<h3><b>L\u2019evento<\/b><\/h3>\n<p>Durante l\u2019evento conclusivo del progetto lo staff locale e i Project Manager dei Paesi coinvolti hanno <b>presentato le attivit\u00e0 svolte<\/b> con i beneficiari, insieme ai risultati ottenuti, le difficolt\u00e0 incontrate, sfide e <b>prospettive per il prossimo progetto<\/b> che sar\u00e0 finanziato dalla Commissione Italiana per le Adozioni Internazionali e che inizier\u00e0 a\u00a0luglio\u00a02023\u00a0garantendo la continuit\u00e0 del <b>sostegno di bambini e famiglie vulnerabili in Ghana, Costa d\u2019Avorio e Sierra Leone.<\/b><\/p>\n<p>Nel corso della presentazione delle <b>attivit\u00e0 di Ai.Bi in Ghana<\/b> sono intervenute la desk cooperazione della <b>sede di Ai.Bi Italia e la psicologa clinica Diana Abena Ade<\/b>, che ha potuto delineare i dettagli degli interventi psicologici di gruppo ed individuali a favore dei 140 minori ospitati nell\u2019orfanotrofio \u201cOsu Children\u2019s\u00a0Home\u201d\u00a0nella Regione Greater Accra e dei bambini reinseriti nelle 50 famiglie sostenute con kit alimentari, pagamento tasse scolastiche e servizi pubblici nella Volta Region.<\/p>\n<h3><b>Il progetto<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/h3>\n<p>Grazie al progetto, <b>pi\u00f9 di 260 bambini negli orfanotrofi e nelle famiglie vulnerabili sono stati supportati insieme a pi\u00f9 di 70 persone adulte<\/b>, tra cui componenti di famiglia di origine beneficiarie dei processi di reinserimento e riunificazione e quelle affidatarie: hanno potuto ricevere i sostegni alimentari, educativi e formativi <b>grazie ad Amici dei Bambini che, in collaborazione stretta con le autorit\u00e0 centrali locali (DSW), <\/b>ha potuto organizzare eventi formativi a funzionari distrettuali, operatori sociali negli istituti sensibilizzandoli al tema dell\u2019 adozione, a un approccio integrale nel sistema di protezione infantile, generando sinergie e partnerships a livello regionale e dipartimentale.<\/p>\n<h3><b>\u00a0<\/b><b>Le necessit\u00e0<\/b><\/h3>\n<p>Molti bambini e bambine beneficiari delle <b>attivit\u00e0 di Amici dei Bambini in Ghana<\/b> presentano quadri clinici complessi a livello di sanit\u00e0 fisica, mentale e psicologica che richiederebbero interventi mirati e specializzati.<\/p>\n<p>Nell\u2019 ultima parte del progetto\u00a0HOME,\u00a0<b>Ai.Bi, attraverso la sua fondazione Friends of Children Foundation, <\/b>ha potuto estendere le attivit\u00e0 di cooperazione anche all\u2019orfanotrofio \u201cRoyal Seed\u00a0Home\u201d\u00a0nella Central Region che ospita circa 60 minori: ha garantito loro il diritto a una alimentazione sana ed adeguata fornendo generi alimentari, il diritto all\u2019 educazione e all\u2019 accesso effettivo ai servizi educativi attraverso il pagamento delle tasse scolastiche per la scuola primaria e secondaria.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<h3><b>\u00a0<\/b><b>Le attivit\u00e0 negli orfanotrofi e nelle famiglie<\/b><\/h3>\n<p>Le attivit\u00e0 svolte negli orfanotrofi e le visite domiciliari, nelle diverse regioni del Ghana, hanno incluso <b>anche momenti dedicati alle famiglie dei minori<\/b>, con monitoraggi costanti a seguito del reinserimento in famiglia, supporto al nucleo familiare ricostituito con la consegna di generi alimentari, l\u2019acquisto di materiale per lo studio e l\u2019organizzazione di gite scolastiche volte a <b>promuovere l\u2019educazione.<\/b><\/p>\n<h3><b>Sostieni le attivit\u00e0 di Ai.Bi. in Ghana<\/b><\/h3>\n<p>Anche tu puoi sostenere le attivit\u00e0 dell\u2019Associazione in Ghana con\u00a0 una donazione libera o aderendo al progetto\u00a0<b>\u201c<\/b><a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/?paese=Ghana\"><b>Adotta a distanza i bambini degli orfanotrofi in Ghana<\/b><\/a><b>\u201d<\/b>, che permette di dare un contributo continuativo a partire da soli 83 centesimi al giorno.<br \/>\nLe donazioni per il Ghana godono delle agevolazioni fiscali previste.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La prevenzione dell&rsquo;abbandono &egrave; stato l&rsquo;obiettivo principale del progetto &ldquo;HOME&rdquo; attuato da Amici dei Bambini in GHANA che ha coinvolto pi&ugrave; di 260 &nbsp;minori degli orfanotrofi e di decine di famiglie vulnerabili<\/p>\n","protected":false},"author":125,"featured_media":212320,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[989],"class_list":["post-212319","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cooperazione-internazionale","tag-ghana-home"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ghana. La lotta contro\u00a0l\u2019abbandono:\u00a0la prevenzione<\/title>\n<meta name=\"description\" content=\"Con il progetto \u201cHOME\u201d attuato da Amici dei Bambini in GHANA che ha coinvolto minori degli orfanotrofi e decine di famiglie vulnerabili.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/ghana-lotta-contro-abbandono-prevenzione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ghana. La lotta contro\u00a0l\u2019abbandono:\u00a0la prevenzione\" \/>\n<meta property=\"og:description\" content=\"Con il progetto \u201cHOME\u201d attuato da Amici dei Bambini in GHANA che ha coinvolto minori degli orfanotrofi e decine di famiglie vulnerabili.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/ghana-lotta-contro-abbandono-prevenzione\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-05T05:30:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-29T15:25:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2023\/05\/Progetto-senza-titolo-5.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"daniela.bilanzuoli@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"daniela.bilanzuoli@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lotta-contro-abbandono-prevenzione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lotta-contro-abbandono-prevenzione\\\/\"},\"author\":{\"name\":\"daniela.bilanzuoli@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/875a59753f5fd2a8db23e6bddc57456b\"},\"headline\":\"Ghana. La lotta contro\u00a0l\u2019abbandono:\u00a0la prevenzione\",\"datePublished\":\"2023-05-05T05:30:20+00:00\",\"dateModified\":\"2023-05-29T15:25:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lotta-contro-abbandono-prevenzione\\\/\"},\"wordCount\":646,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lotta-contro-abbandono-prevenzione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/05\\\/Progetto-senza-titolo-5.png\",\"keywords\":[\"Ghana - HOME\"],\"articleSection\":[\"Cooperazione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lotta-contro-abbandono-prevenzione\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lotta-contro-abbandono-prevenzione\\\/\",\"name\":\"Ghana. La lotta contro\u00a0l\u2019abbandono:\u00a0la prevenzione\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lotta-contro-abbandono-prevenzione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lotta-contro-abbandono-prevenzione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/05\\\/Progetto-senza-titolo-5.png\",\"datePublished\":\"2023-05-05T05:30:20+00:00\",\"dateModified\":\"2023-05-29T15:25:01+00:00\",\"description\":\"Con il progetto \u201cHOME\u201d attuato da Amici dei Bambini in GHANA che ha coinvolto minori degli orfanotrofi e decine di famiglie vulnerabili.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lotta-contro-abbandono-prevenzione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lotta-contro-abbandono-prevenzione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lotta-contro-abbandono-prevenzione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/05\\\/Progetto-senza-titolo-5.png\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/05\\\/Progetto-senza-titolo-5.png\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lotta-contro-abbandono-prevenzione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cooperazione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/cooperazione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ghana. La lotta contro\u00a0l\u2019abbandono:\u00a0la prevenzione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/875a59753f5fd2a8db23e6bddc57456b\",\"name\":\"daniela.bilanzuoli@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/daniela-bilanzuoliaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ghana. La lotta contro\u00a0l\u2019abbandono:\u00a0la prevenzione","description":"Con il progetto \u201cHOME\u201d attuato da Amici dei Bambini in GHANA che ha coinvolto minori degli orfanotrofi e decine di famiglie vulnerabili.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/ghana-lotta-contro-abbandono-prevenzione\/","og_locale":"it_IT","og_type":"article","og_title":"Ghana. La lotta contro\u00a0l\u2019abbandono:\u00a0la prevenzione","og_description":"Con il progetto \u201cHOME\u201d attuato da Amici dei Bambini in GHANA che ha coinvolto minori degli orfanotrofi e decine di famiglie vulnerabili.","og_url":"https:\/\/www.aibi.it\/ita\/ghana-lotta-contro-abbandono-prevenzione\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2023-05-05T05:30:20+00:00","article_modified_time":"2023-05-29T15:25:01+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2023\/05\/Progetto-senza-titolo-5.png","type":"image\/png"}],"author":"daniela.bilanzuoli@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"daniela.bilanzuoli@aibi.it","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/ghana-lotta-contro-abbandono-prevenzione\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-lotta-contro-abbandono-prevenzione\/"},"author":{"name":"daniela.bilanzuoli@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/875a59753f5fd2a8db23e6bddc57456b"},"headline":"Ghana. La lotta contro\u00a0l\u2019abbandono:\u00a0la prevenzione","datePublished":"2023-05-05T05:30:20+00:00","dateModified":"2023-05-29T15:25:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-lotta-contro-abbandono-prevenzione\/"},"wordCount":646,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-lotta-contro-abbandono-prevenzione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/05\/Progetto-senza-titolo-5.png","keywords":["Ghana - HOME"],"articleSection":["Cooperazione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/ghana-lotta-contro-abbandono-prevenzione\/","url":"https:\/\/www.aibi.it\/ita\/ghana-lotta-contro-abbandono-prevenzione\/","name":"Ghana. La lotta contro\u00a0l\u2019abbandono:\u00a0la prevenzione","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-lotta-contro-abbandono-prevenzione\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-lotta-contro-abbandono-prevenzione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/05\/Progetto-senza-titolo-5.png","datePublished":"2023-05-05T05:30:20+00:00","dateModified":"2023-05-29T15:25:01+00:00","description":"Con il progetto \u201cHOME\u201d attuato da Amici dei Bambini in GHANA che ha coinvolto minori degli orfanotrofi e decine di famiglie vulnerabili.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-lotta-contro-abbandono-prevenzione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/ghana-lotta-contro-abbandono-prevenzione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/ghana-lotta-contro-abbandono-prevenzione\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2023\/05\/Progetto-senza-titolo-5.png","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/05\/Progetto-senza-titolo-5.png","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/ghana-lotta-contro-abbandono-prevenzione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Cooperazione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/cooperazione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Ghana. La lotta contro\u00a0l\u2019abbandono:\u00a0la prevenzione"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/875a59753f5fd2a8db23e6bddc57456b","name":"daniela.bilanzuoli@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/daniela-bilanzuoliaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:56:33","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/212319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/125"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=212319"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/212319\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/212320"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=212319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=212319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=212319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}