﻿


{"id":213093,"date":"2023-06-04T07:30:10","date_gmt":"2023-06-04T05:30:10","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=213093"},"modified":"2023-06-04T10:08:23","modified_gmt":"2023-06-04T08:08:23","slug":"kenya-john-problemi-di-salute-finalmente-posso-studiare","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/kenya-john-problemi-di-salute-finalmente-posso-studiare\/","title":{"rendered":"Kenya. John: orfano dell\u2019AIDS, dopo 5 anni di orfanotrofio, ha bisogno di credere nel suo futuro\u00a0"},"content":{"rendered":"<h2><strong>Entrambi i suoi genitori sono morti di malattie legate all&#8217;AIDS e lui, insieme ai suoi fratelli, tutti sieropositivi, sono stati abbandonati da tutti loro parenti che non volevano avere niente a che fare con loro.\u00a0Grazie al progetto di Ai.Bi. \u201cAdotta a Distanza i minori di un orfanotrofio in Kenya\u201d\u00a0potrai accompagnarli nella loro crescita.<\/strong><\/h2>\n<p><!--more--><\/p>\n<p>John Samuria ha avuto\u00a0un&#8217;infanzia molto difficile<strong>: \u00e8 rimasto orfano in tenera et\u00e0, entrambi i suoi genitori sono morti di malattie legate all&#8217;AIDS<\/strong> e lui, insieme ai suoi fratelli, tutti sieropositivi, sono stati abbandonati da tutti loro parenti che non volevano avere niente a che fare con loro. <strong>Secondo i parenti, la famiglia era una maledizione<\/strong> e farsi coinvolgere nella loro storia avrebbe portato una maledizione alla famiglia allargata.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<h3><b>L\u2019arrivo in orfanotrofio<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/h3>\n<p>John\u00a0\u00e8 stato salvato dall&#8217;amministrazione locale del suo villaggio e indirizzato <strong>all\u2019orfanotrofio Shelter, partner di Ai.Bi. in Kenya.<\/strong> Anche gli altri suoi fratelli sono stati portati in diversi orfanotrofi per cure e protezione.<\/p>\n<p>Quando \u00e8 arrivato allo Shelter, John aveva 8 anni, <strong>era molto fragile e debole: portato in ospedale, \u00e8 stato sottoposto a farmaci, integratori e antiretrovirali; cos\u00ec la sua salute \u00e8 migliorata.<\/strong> Oggi John \u00e8 ancora sotto cure costanti e un&#8217;infermiera dell\u2019orfanotrofio \u00e8 sempre attenta ai suoi progressi di salute. Vivere allo Shelter gli ha permesso di affrontare la vita e la sua salute \u00e8 migliorata notevolmente.<\/p>\n<h3><b>La possibilit\u00e0 di studiare<\/b><\/h3>\n<p><strong>Grazie ad Ai.Bi.,\u00a0John,\u00a0che adesso ha 13 anni, frequenta\u00a0la scuola, le sue tasse scolastiche sono pagate e tutti gli altri bisogni\u00a0educativi sono soddisfatti.<\/strong> Gli insegnanti continuano a incoraggiarlo e lui ama i suoi coetanei. Adora creare giocattoli e giocarci.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Grazie ad Amici dei Bambini <strong>la vita di\u00a0John\u00a0si sta trasformando, sta ricevendo un&#8217;istruzione e anche la sua salute viene monitorata.<\/strong> Ci sono piani per continuare a incontrare i suoi parenti, in modo che lo accettino pienamente nonostante le sue condizioni.<\/p>\n<h3><b>Kenya.\u00a0<\/b><a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/?paese=Kenya\"><b>Un\u2019Adozione a Distanza<\/b><\/a><b>\u00a0per i minori in grave difficolt\u00e0 familiare\u00a0<\/b><\/h3>\n<p>Tutti possono aderire al progetto \u201cAdotta a Distanza i minori di un orfanotrofio in Kenya\u201d, con un contributo\u00a0<b>che parte da 0,83 centesimi al giorno<\/b>. Un aiuto prezioso per offrire un futuro a chi, spesso, fa fatica anche solo a sognarlo. Aiutaci anche tu!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entrambi i suoi genitori sono morti di malattie legate all&rsquo;AIDS e lui, insieme ai suoi fratelli, tutti sieropositivi, sono stati abbandonati da tutti loro parenti che non volevano avere niente a che fare con loro.&nbsp;Grazie al progetto di Ai.Bi. &ldquo;Adotta a Distanza i minori di un orfanotrofio in Kenya&rdquo;&nbsp;potrai accompagnarli [&hellip;]<\/p>\n","protected":false},"author":125,"featured_media":213094,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209],"tags":[300],"class_list":["post-213093","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-a-distanza","tag-sostegno-a-distanza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kenya. John: orfano dell\u2019AIDS, dopo 5 anni di orfanotrofio, ha bisogno di credere nel suo futuro\u00a0<\/title>\n<meta name=\"description\" content=\"John ha avuto la possibilit\u00e0 di migliorare il suo precario stato di salute, studiare, avere una casa e amici con i quali crescere insieme!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/kenya-john-problemi-di-salute-finalmente-posso-studiare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kenya. John: orfano dell\u2019AIDS, dopo 5 anni di orfanotrofio, ha bisogno di credere nel suo futuro\u00a0\" \/>\n<meta property=\"og:description\" content=\"John ha avuto la possibilit\u00e0 di migliorare il suo precario stato di salute, studiare, avere una casa e amici con i quali crescere insieme!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/kenya-john-problemi-di-salute-finalmente-posso-studiare\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-04T05:30:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-04T08:08:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2023\/05\/Progetto-senza-titolo-51-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"daniela.bilanzuoli@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"daniela.bilanzuoli@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-john-problemi-di-salute-finalmente-posso-studiare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-john-problemi-di-salute-finalmente-posso-studiare\\\/\"},\"author\":{\"name\":\"daniela.bilanzuoli@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/875a59753f5fd2a8db23e6bddc57456b\"},\"headline\":\"Kenya. John: orfano dell\u2019AIDS, dopo 5 anni di orfanotrofio, ha bisogno di credere nel suo futuro\u00a0\",\"datePublished\":\"2023-06-04T05:30:10+00:00\",\"dateModified\":\"2023-06-04T08:08:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-john-problemi-di-salute-finalmente-posso-studiare\\\/\"},\"wordCount\":387,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-john-problemi-di-salute-finalmente-posso-studiare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/05\\\/Progetto-senza-titolo-51-1.jpg\",\"keywords\":[\"sostegno a distanza\"],\"articleSection\":[\"Adozione a Distanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-john-problemi-di-salute-finalmente-posso-studiare\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-john-problemi-di-salute-finalmente-posso-studiare\\\/\",\"name\":\"Kenya. John: orfano dell\u2019AIDS, dopo 5 anni di orfanotrofio, ha bisogno di credere nel suo futuro\u00a0\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-john-problemi-di-salute-finalmente-posso-studiare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-john-problemi-di-salute-finalmente-posso-studiare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/05\\\/Progetto-senza-titolo-51-1.jpg\",\"datePublished\":\"2023-06-04T05:30:10+00:00\",\"dateModified\":\"2023-06-04T08:08:23+00:00\",\"description\":\"John ha avuto la possibilit\u00e0 di migliorare il suo precario stato di salute, studiare, avere una casa e amici con i quali crescere insieme!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-john-problemi-di-salute-finalmente-posso-studiare\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-john-problemi-di-salute-finalmente-posso-studiare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-john-problemi-di-salute-finalmente-posso-studiare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/05\\\/Progetto-senza-titolo-51-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/05\\\/Progetto-senza-titolo-51-1.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-john-problemi-di-salute-finalmente-posso-studiare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione a Distanza\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-a-distanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kenya. John: orfano dell\u2019AIDS, dopo 5 anni di orfanotrofio, ha bisogno di credere nel suo futuro\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/875a59753f5fd2a8db23e6bddc57456b\",\"name\":\"daniela.bilanzuoli@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/daniela-bilanzuoliaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kenya. John: orfano dell\u2019AIDS, dopo 5 anni di orfanotrofio, ha bisogno di credere nel suo futuro\u00a0","description":"John ha avuto la possibilit\u00e0 di migliorare il suo precario stato di salute, studiare, avere una casa e amici con i quali crescere insieme!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/kenya-john-problemi-di-salute-finalmente-posso-studiare\/","og_locale":"it_IT","og_type":"article","og_title":"Kenya. John: orfano dell\u2019AIDS, dopo 5 anni di orfanotrofio, ha bisogno di credere nel suo futuro\u00a0","og_description":"John ha avuto la possibilit\u00e0 di migliorare il suo precario stato di salute, studiare, avere una casa e amici con i quali crescere insieme!","og_url":"https:\/\/www.aibi.it\/ita\/kenya-john-problemi-di-salute-finalmente-posso-studiare\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2023-06-04T05:30:10+00:00","article_modified_time":"2023-06-04T08:08:23+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2023\/05\/Progetto-senza-titolo-51-1.jpg","type":"image\/jpeg"}],"author":"daniela.bilanzuoli@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"daniela.bilanzuoli@aibi.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/kenya-john-problemi-di-salute-finalmente-posso-studiare\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-john-problemi-di-salute-finalmente-posso-studiare\/"},"author":{"name":"daniela.bilanzuoli@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/875a59753f5fd2a8db23e6bddc57456b"},"headline":"Kenya. John: orfano dell\u2019AIDS, dopo 5 anni di orfanotrofio, ha bisogno di credere nel suo futuro\u00a0","datePublished":"2023-06-04T05:30:10+00:00","dateModified":"2023-06-04T08:08:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-john-problemi-di-salute-finalmente-posso-studiare\/"},"wordCount":387,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-john-problemi-di-salute-finalmente-posso-studiare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/05\/Progetto-senza-titolo-51-1.jpg","keywords":["sostegno a distanza"],"articleSection":["Adozione a Distanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/kenya-john-problemi-di-salute-finalmente-posso-studiare\/","url":"https:\/\/www.aibi.it\/ita\/kenya-john-problemi-di-salute-finalmente-posso-studiare\/","name":"Kenya. John: orfano dell\u2019AIDS, dopo 5 anni di orfanotrofio, ha bisogno di credere nel suo futuro\u00a0","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-john-problemi-di-salute-finalmente-posso-studiare\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-john-problemi-di-salute-finalmente-posso-studiare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/05\/Progetto-senza-titolo-51-1.jpg","datePublished":"2023-06-04T05:30:10+00:00","dateModified":"2023-06-04T08:08:23+00:00","description":"John ha avuto la possibilit\u00e0 di migliorare il suo precario stato di salute, studiare, avere una casa e amici con i quali crescere insieme!","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-john-problemi-di-salute-finalmente-posso-studiare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/kenya-john-problemi-di-salute-finalmente-posso-studiare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/kenya-john-problemi-di-salute-finalmente-posso-studiare\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2023\/05\/Progetto-senza-titolo-51-1.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/05\/Progetto-senza-titolo-51-1.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/kenya-john-problemi-di-salute-finalmente-posso-studiare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione a Distanza","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-a-distanza\/"},{"@type":"ListItem","position":3,"name":"Kenya. John: orfano dell\u2019AIDS, dopo 5 anni di orfanotrofio, ha bisogno di credere nel suo futuro\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/875a59753f5fd2a8db23e6bddc57456b","name":"daniela.bilanzuoli@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/daniela-bilanzuoliaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 07:51:35","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/213093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/125"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=213093"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/213093\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/213094"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=213093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=213093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=213093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}