﻿


{"id":214103,"date":"2023-06-22T07:45:23","date_gmt":"2023-06-22T05:45:23","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=214103"},"modified":"2023-06-22T17:25:02","modified_gmt":"2023-06-22T15:25:02","slug":"adozione-internazionale-crisi-attesa-decreto","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-crisi-attesa-decreto\/","title":{"rendered":"Adozione Internazionale in crisi. Un anno di attesa dal colloquio con il giudice all\u2019emissione del decreto"},"content":{"rendered":"<h2>Prosegue l\u2019inchiesta di AiBiNews sulla crisi delle Adozioni Internazionali. Tre testimonianze, da tre differenti regioni (e Tribunali di riferimento) di Italia, che denunciano i tempi lunghissimi che intercorrono prima della notifica del decreto di idoneit\u00e0<\/h2>\n<p><!--more--><\/p>\n<p>Denatalit\u00e0, maternit\u00e0 surrogata, polemiche su trascrizioni di figli all\u2019anagrafe, revoche e riconoscimenti\u2026 Poi, spostando lo sguardo poco pi\u00f9 in l\u00e0, si scopre con allarmante facilit\u00e0 quanti <strong>problemi ed enormi difficolt\u00e0<\/strong> circondino le adozioni internazionali. E quasi nessuno dice nulla!<br \/>\nGenitori in attesa da anni, da una parte, e <strong>figli che aspettano<\/strong> da ancora pi\u00f9 anni dall\u2019altra, sospesi in un limbo che tutti, nessuno escluso, trovano scandaloso a parole, e che nessuno, o quasi, fa nulla per modificare. Da ormai tantissimi anni.<br \/>\nAiBiNews sta provando a raccontare tutto questo, tramite un\u2019<strong>inchiesta <\/strong>che ha suscitato molto interesse e sta raccogliendo numerosissime testimonianze di coppie alle prese con percorsi adottivi lunghi, difficili, molto spesso <strong>incomprensibili e frustranti nelle loro dinamiche<\/strong>. Di seguito, raccontiamo altri tre casi accomunati dagli enormi ritardi nel completamento di un percorso che normalmente, per legge, <strong>dovrebbe durare al massimo sei mesi<\/strong> dalla presentazione della domanda all\u2019arrivo del decreto di idoneit\u00e0.<\/p>\n<h3>Quasi tre anni, e il decreto ancora non c\u2019\u00e8<\/h3>\n<p>Una coppia che risiede in Emilia Romagna, per esempio, ci scrive raccontando di aver presentato la propria domanda nell\u2019<strong>agosto del 2020<\/strong>. Solo per il percorso con i servizi sociali hanno impiegato quasi due anni, concludendo l\u2019iter nel marzo del 2022. Cinque mesi dopo, nell\u2019agosto del 2022, \u00e8 arrivato il tanto sospirato colloquio con il giudice. Peccato che, <strong>dopo quasi un anno, la notifica del decreto non sia ancora arrivata<\/strong>. La coppia ha avuto rassicurazioni sul fatto che il decreto sia stato emesso, e per questo si \u00e8 \u201cportata avanti\u201d incontrando gi\u00e0 alcuni enti autorizzati, ma la notifica ufficiale (dovuta, \u00e8 stato loro riferito, dai ritardi del <strong>Tribunale di Bologna<\/strong>) non \u00e8 ancora giunta. I due hanno superato gi\u00e0 i 50 anni e, tenendo conto che anche il percorso con l\u2019ente che sceglieranno per l\u2019adozione internazionale ha i suoi inevitabili tempi lunghi, \u00e8 chiaro che la frustrazione cresce ogni giorno che passa.<\/p>\n<p>Un po\u2019 pi\u00f9 giovani (45 anni lui, 42 lei) sono i componenti di un\u2019altra coppia delle <strong>Marche<\/strong> che sta sperimentando un analogo \u201ccalvario\u201d. I due hanno depositato la domanda presso il <strong>Tribunale di Ancona<\/strong> nel <strong>2020<\/strong>, poco prima delle chiusure dettate dalla pandemia. Certo, per\u00f2, non basta il Covid per giustificare il fatto che ad aprile 2023 i coniugi fossero <strong>ancora in attesa del colloquio con il giudice<\/strong>. Il percorso con i servizi sociali, per quanto lunghissimo, \u00e8 andato bene, come gli stessi servizi hanno loro assicurato, ma l\u2019ultimo passo con il giudice (cui dovr\u00e0 seguire la notifica del decreto), dopo tre anni, ancora non era stato fatto.<\/p>\n<h3>La frustrazione di chi \u00e8 in attesa dal 2019<\/h3>\n<p>Una terza, amaramente analoga storia arriva da una coppia di <strong>Roma<\/strong>, il cui iter \u00e8 cominciato addirittura nel <strong>2019<\/strong>. Dopo un percorso lunghissimo, tra il colloquio con il giudice e l\u2019arrivo effettivo del decreto \u00e8 passato un ulteriore anno! Inevitabile che, oggi, i due (53 anni lui, 41 lei) si sentano <strong>demoralizzati<\/strong>. Ma nonostante questo non hanno smesso di sperare e lottare per arrivare a costruire la loro nuova famiglia attraverso l\u2019Adozione Internazionale.<\/p>\n<p>Chiunque pu\u00f2 mandare la sua testimonianza (firmata. Non verranno presi in considerazione messaggi anonimi, anche se per rispetto della privacy Ai.Bi. non pubblicher\u00e0 i nominativi dei protagonisti, cos\u00ec come i Tribunali e i servizi sociali coinvolti) scrivendo all\u2019indirizzo mail\u00a0<a href=\"mailto:ufficiostampa@aibi.it\"><strong>ufficiostampa@aibi.it<\/strong><\/a>.<\/p>\n<p>Le altre puntate dell\u2019inchiesta si trovano qui;<br \/>\n<a href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-quanto-tempo-impiega-una-coppia-del-lazio-per-ottenere-lidoneita\/\"><strong>prima puntata<\/strong><\/a><br \/>\n<a href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-in-crisi-meglio-prendersi-del-tempo-per-riflettere-su-alcune-questioni-o-la-relazione-sarebbe-stata-negativa-2\/\"><strong>seconda puntata<\/strong><\/a><br \/>\n<a href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-crisi-via-crucis-non-finita\/\"><strong>terza puntata<\/strong><\/a><br \/>\n<a href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-crisi-attesa-incontro-giudice\/\"><strong>quarta puntata<\/strong><\/a><br \/>\n<a href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-crisi-ottenere-idoneita\/\"><strong>quinta puntata<\/strong><\/a><br \/>\n<a href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-crisi-attesa-infinita\/\"><strong>sesta puntata<\/strong><\/a><br \/>\n<a href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-in-crisi-un-percorso-non-a-lieto-fine-verso-ladozione-internazionale-7\/\"><strong>settima puntata<\/strong><\/a><br \/>\n<a href=\"https:\/\/www.aibi.it\/ita\/adozione-crisi-anni-attesa-senza-risposta\/\"><strong>ottava puntata<\/strong><\/a><strong><br \/>\n<\/strong><a href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-crisi-ostacoli-burocrazia\/\"><strong>nona puntata<\/strong><\/a><strong><br \/>\n<\/strong><a href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-crisi-tempo-perso\/\"><strong>decima puntata<\/strong><\/a><strong><br \/>\n<\/strong><a href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-crisi-idoneita-cuore\/\"><strong>undicesima puntata<\/strong><\/a><br \/>\n<a href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-crisi-cambi-regione-devi-rifare-tutto\/\"><strong>dodicesima puntata<\/strong><\/a><br \/>\n<a href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-crisi-ritardi-burocratici-servizi-sociali-13\/\"><strong>tredicesima puntata<\/strong><\/a><br \/>\n<strong><a href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-crisi-molteplici-difficolta\/\">quattordicesima puntata<\/a><\/strong><\/p>\n<p><strong>Informazioni e domande sull\u2019adozione internazionale<\/strong><\/p>\n<p>Chi sta considerando un\u2019adozione internazionale o semplicemente desidera avere maggiori informazioni a su questi temi, pu\u00f2 contattare l\u2019ufficio adozioni di Ai.Bi. scrivendo un\u2019e-mail a <a href=\"mailto:adozioni@aibi.it\"><strong>adozioni@aibi.it<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prosegue l&rsquo;inchiesta di AiBiNews sulla crisi delle Adozioni Internazionali. Tre testimonianze, da tre differenti regioni (e Tribunali di riferimento) di Italia, che denunciano i tempi lunghissimi che intercorrono prima della notifica del decreto di idoneit&agrave;<\/p>\n","protected":false},"author":102,"featured_media":214104,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[347,997,344],"class_list":["post-214103","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale","tag-adozione-internazionale","tag-decreto","tag-tribunale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione Internazionale in crisi. Anni di attesa per il decreto<\/title>\n<meta name=\"description\" content=\"Prosegue l\u2019inchiesta di AiBiNews sull&#039;Adozione Internazionale in crisi. Tre storie, da tre differenti regioni (e Tribunali), che denunciano i tempi lunghissimi\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-crisi-attesa-decreto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione Internazionale in crisi. Un anno di attesa dal colloquio con il giudice all\u2019emissione del decreto\" \/>\n<meta property=\"og:description\" content=\"Prosegue l\u2019inchiesta di AiBiNews sull&#039;Adozione Internazionale in crisi. Tre storie, da tre differenti regioni (e Tribunali), che denunciano i tempi lunghissimi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-crisi-attesa-decreto\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-22T05:45:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-22T15:25:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2023\/06\/adozione-internazionale-in-crisi-tempi-lunghi-decreto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-crisi-attesa-decreto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-crisi-attesa-decreto\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Adozione Internazionale in crisi. Un anno di attesa dal colloquio con il giudice all\u2019emissione del decreto\",\"datePublished\":\"2023-06-22T05:45:23+00:00\",\"dateModified\":\"2023-06-22T15:25:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-crisi-attesa-decreto\\\/\"},\"wordCount\":663,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-crisi-attesa-decreto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/06\\\/adozione-internazionale-in-crisi-tempi-lunghi-decreto.jpg\",\"keywords\":[\"Adozione Internazionale\",\"decreto\",\"tribunale\"],\"articleSection\":[\"Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-crisi-attesa-decreto\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-crisi-attesa-decreto\\\/\",\"name\":\"Adozione Internazionale in crisi. Anni di attesa per il decreto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-crisi-attesa-decreto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-crisi-attesa-decreto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/06\\\/adozione-internazionale-in-crisi-tempi-lunghi-decreto.jpg\",\"datePublished\":\"2023-06-22T05:45:23+00:00\",\"dateModified\":\"2023-06-22T15:25:02+00:00\",\"description\":\"Prosegue l\u2019inchiesta di AiBiNews sull'Adozione Internazionale in crisi. Tre storie, da tre differenti regioni (e Tribunali), che denunciano i tempi lunghissimi\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-crisi-attesa-decreto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-crisi-attesa-decreto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-crisi-attesa-decreto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/06\\\/adozione-internazionale-in-crisi-tempi-lunghi-decreto.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/06\\\/adozione-internazionale-in-crisi-tempi-lunghi-decreto.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-crisi-attesa-decreto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione Internazionale in crisi. Un anno di attesa dal colloquio con il giudice all\u2019emissione del decreto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione Internazionale in crisi. Anni di attesa per il decreto","description":"Prosegue l\u2019inchiesta di AiBiNews sull'Adozione Internazionale in crisi. Tre storie, da tre differenti regioni (e Tribunali), che denunciano i tempi lunghissimi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-crisi-attesa-decreto\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione Internazionale in crisi. Un anno di attesa dal colloquio con il giudice all\u2019emissione del decreto","og_description":"Prosegue l\u2019inchiesta di AiBiNews sull'Adozione Internazionale in crisi. Tre storie, da tre differenti regioni (e Tribunali), che denunciano i tempi lunghissimi","og_url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-crisi-attesa-decreto\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2023-06-22T05:45:23+00:00","article_modified_time":"2023-06-22T15:25:02+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2023\/06\/adozione-internazionale-in-crisi-tempi-lunghi-decreto.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-crisi-attesa-decreto\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-crisi-attesa-decreto\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Adozione Internazionale in crisi. Un anno di attesa dal colloquio con il giudice all\u2019emissione del decreto","datePublished":"2023-06-22T05:45:23+00:00","dateModified":"2023-06-22T15:25:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-crisi-attesa-decreto\/"},"wordCount":663,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-crisi-attesa-decreto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/06\/adozione-internazionale-in-crisi-tempi-lunghi-decreto.jpg","keywords":["Adozione Internazionale","decreto","tribunale"],"articleSection":["Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-crisi-attesa-decreto\/","url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-crisi-attesa-decreto\/","name":"Adozione Internazionale in crisi. Anni di attesa per il decreto","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-crisi-attesa-decreto\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-crisi-attesa-decreto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/06\/adozione-internazionale-in-crisi-tempi-lunghi-decreto.jpg","datePublished":"2023-06-22T05:45:23+00:00","dateModified":"2023-06-22T15:25:02+00:00","description":"Prosegue l\u2019inchiesta di AiBiNews sull'Adozione Internazionale in crisi. Tre storie, da tre differenti regioni (e Tribunali), che denunciano i tempi lunghissimi","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-crisi-attesa-decreto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-internazionale-crisi-attesa-decreto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-crisi-attesa-decreto\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2023\/06\/adozione-internazionale-in-crisi-tempi-lunghi-decreto.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/06\/adozione-internazionale-in-crisi-tempi-lunghi-decreto.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-crisi-attesa-decreto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Adozione Internazionale in crisi. Un anno di attesa dal colloquio con il giudice all\u2019emissione del decreto"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 23:00:46","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/214103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=214103"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/214103\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/214104"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=214103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=214103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=214103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}