﻿{"id":21436,"date":"2011-04-07T15:09:41","date_gmt":"2011-04-07T14:09:41","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=21436"},"modified":"2011-09-27T14:45:13","modified_gmt":"2011-09-27T13:45:13","slug":"adozioni-centinaia-di-torte-per-sostenere-un%e2%80%99adozione-speciale","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozioni-centinaia-di-torte-per-sostenere-un%e2%80%99adozione-speciale\/","title":{"rendered":"Adozioni: centinaia di torte per sostenere un\u2019adozione speciale"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/torta.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-21438\" style=\"margin: 5px;\" title=\"torta\" src=\"https:\/\/www.aibi.it\/ita\/images\/torta.jpg\" alt=\"\" width=\"100\" height=\"100\" \/><\/a>Kateri Lambrose era sicura di poter fare qualcosa di speciale per cercare di coprire le spese per l\u2019adozione di una bambina cinese. <strong>La risposta \u00e8 arrivata\u00a0in una torta. O meglio: in centinaia di torte. <\/strong><\/p>\n<p><em>&#8220;Mio marito, Dave, ed io abbiamo due figli biologici, Troy e Kyrsten. Un giorno, dopo aver visto un programma televisivo, entrambi ci chiesero: &#8220;Perch\u00e9 non adottiamo un bambino?&#8221;<\/em>. <em>&#8220;Al momento non siamo stati in grado di dare una risposta, poi abbiamo iniziato a cercare di capire come iniziare le procedure per un\u2019adozione internazionale.&#8221;<br \/>\n<\/em><br \/>\nLa coppia, ha pregato molto per orientarsi. Essi inizialmente pensavano ad un&#8217;adozione dall\u2019Africa, <strong>poi hanno scelto la Cina.<\/strong><\/p>\n<p>I Lambroses hanno imparato presto che vi erano due distinte categorie di bambini disponibili per l&#8217;adozione: quelli con esigenze speciali e quelli senza. Nel marzo del 2005, hanno firmato per un bambino senza esigenze speciali, che avesse al massimo un anno di et\u00e0.<br \/>\n<strong>Presa la decisione, hanno iniziato la raccolta di fondi.<\/strong><\/p>\n<p>Kateri lavorava a tempo pieno presso la scuola elementare di Salisbury, mentre il marito lavorava come costruttore nel settore edile. <em>\u201cSapevamo di avere fondi provenienti dal suo lavoro, ma la crisi del mercato immobiliare ci ha messo in difficolt\u00e0\u201d <\/em>ha detto Kateri<em>.<\/em><\/p>\n<p><strong>Un passatempo che ho sempre avuto era quello di cucinare torte per gli amici e la famiglia<\/strong>; alcune persone allora mi hanno suggerito di iniziare a venderle, come raccolta fondi per poter portare a termine l\u2019adozione. E&#8217; stato un bel passaparola: torta di carote, torta al cioccolato con caramello, torta al cocco e la mia versione di torta al mandarino. \u201c<em>Sono torte semplici, ma le ho migliorate per farle mie&#8221;<\/em>, ha detto. <em>&#8220;E sono tutte fatte in casa&#8221;<br \/>\n<\/em><strong>Ogni torta \u00e8 stata venduta per 30 dollari, e ci sono stati molti ordini<\/strong>. Non ha un conteggio esatto delle torte, ma <strong>sa di aver utilizzato pi\u00f9 di 300 scatole di cartone per mettere i dolci finiti.<\/strong><\/p>\n<p>Il costo di un&#8217;adozione internazionale, varia dai 20.000 ai 30.000 dollari. <em>&#8220;Tu non &#8216;paghi&#8217; per un bambino, questo \u00e8 solo il costo del processo legale&#8221;<\/em>, ha detto.<br \/>\nI Lambroses hanno avviato le pratiche per l\u2019adozione nel 2006, ricevendo assicurazioni che il loro processo non sarebbe durato pi\u00f9 di un anno. <em>\u201cEppure abbiamo dovuto attendere molto di pi\u00f9.\u201d<\/em><\/p>\n<p><strong><em>&#8220;E &#8216;stato allora che abbiamo preso in considerazione i bambini con esigenze speciali&#8221;<\/em><\/strong>.<br \/>\nAll&#8217;inizio di dicembre del 2007, i due hanno avuto un altro elenco, con i bambini con esigenze speciali idonei all\u2019adozione e hanno depositato le pratiche per incominciare l\u2019iter.<\/p>\n<p><strong><em>&#8220;Quando ho visto il volto di questa bambina, \u00e8 stato uno di quei momenti nei quali ho saputo che questa era la bambina per noi.<\/em><\/strong><em> <strong>Se hai fede, lo capisci.<\/strong> Mi era stato detto che c&#8217;era qualcosa di speciale in quella bambina<\/em>&#8220;. <em>&#8220;Lei non era diversa da tutti gli altri bambini, era carina, ma c&#8217;era qualcosa in quella foto che mi ha attirato a s\u00e9. <strong>Ha subito toccato il mio cuore<\/strong>&#8220;. <\/em>La bambina di 14 mesi \u00e8 nata con un labbro leporino e palatoschisi.<br \/>\nL&#8217;8 aprile 2008, i Lambroses, erano in viaggio verso la Cina per portare la bambina nella sua nuova casa.<br \/>\nIl suo nome cinese era <strong>Ning Fu Chang<\/strong> (&#8220;Colei che cresce fino a diventare una persona bella e beata che vive una vita migliore&#8221;, ha detto Lambrose). Ora lei si chiama Alayna Fu Chang Lambrose ed \u00e8 diventata cittadina americana nell\u2019istante in cui l\u2019aereo ha toccato il terreno del Dulles International Airport, vicino a Washington.<br \/>\n\u201c<em>Lei ha benedetto cos\u00ec tanto la nostra famiglia che non posso immaginare la nostra vita senza di lei. E&#8217; impensabile&#8221;.<\/em><\/p>\n<p>(Fonte: http:\/\/www.delmarvanow)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kateri Lambrose era sicura di poter fare qualcosa di speciale per cercare di coprire le spese per l\u2019adozione di una bambina cinese. <strong>La risposta \u00e8 arrivata in una torta. O meglio: in centinaia di torte. <a href=\"https:\/\/www.aibi.it\/ita\/adozioni-centinaia-di-torte-per-sostenere-un\u2019adozione-speciale\/\">LEGGI TUTTO&#8230;<\/a><\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-21436","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozioni: centinaia di torte per sostenere un\u2019adozione speciale - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozioni-centinaia-di-torte-per-sostenere-un\u2019adozione-speciale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozioni: centinaia di torte per sostenere un\u2019adozione speciale\" \/>\n<meta property=\"og:description\" content=\"Kateri Lambrose era sicura di poter fare qualcosa di speciale per cercare di coprire le spese per l\u2019adozione di una bambina cinese. La risposta \u00e8 arrivata in una torta. O meglio: in centinaia di torte. LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozioni-centinaia-di-torte-per-sostenere-un\u2019adozione-speciale\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-04-07T14:09:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-09-27T13:45:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/torta.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-centinaia-di-torte-per-sostenere-un%e2%80%99adozione-speciale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-centinaia-di-torte-per-sostenere-un%e2%80%99adozione-speciale\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Adozioni: centinaia di torte per sostenere un\u2019adozione speciale\",\"datePublished\":\"2011-04-07T14:09:41+00:00\",\"dateModified\":\"2011-09-27T13:45:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-centinaia-di-torte-per-sostenere-un%e2%80%99adozione-speciale\\\/\"},\"wordCount\":604,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-centinaia-di-torte-per-sostenere-un%e2%80%99adozione-speciale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/torta.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-centinaia-di-torte-per-sostenere-un%e2%80%99adozione-speciale\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-centinaia-di-torte-per-sostenere-un%e2%80%99adozione-speciale\\\/\",\"name\":\"Adozioni: centinaia di torte per sostenere un\u2019adozione speciale - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-centinaia-di-torte-per-sostenere-un%e2%80%99adozione-speciale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-centinaia-di-torte-per-sostenere-un%e2%80%99adozione-speciale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/torta.jpg\",\"datePublished\":\"2011-04-07T14:09:41+00:00\",\"dateModified\":\"2011-09-27T13:45:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-centinaia-di-torte-per-sostenere-un%e2%80%99adozione-speciale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-centinaia-di-torte-per-sostenere-un%e2%80%99adozione-speciale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-centinaia-di-torte-per-sostenere-un%e2%80%99adozione-speciale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/torta.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/torta.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-centinaia-di-torte-per-sostenere-un%e2%80%99adozione-speciale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozioni: centinaia di torte per sostenere un\u2019adozione speciale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozioni: centinaia di torte per sostenere un\u2019adozione speciale - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozioni-centinaia-di-torte-per-sostenere-un\u2019adozione-speciale\/","og_locale":"it_IT","og_type":"article","og_title":"Adozioni: centinaia di torte per sostenere un\u2019adozione speciale","og_description":"Kateri Lambrose era sicura di poter fare qualcosa di speciale per cercare di coprire le spese per l\u2019adozione di una bambina cinese. La risposta \u00e8 arrivata in una torta. O meglio: in centinaia di torte. LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/adozioni-centinaia-di-torte-per-sostenere-un\u2019adozione-speciale\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2011-04-07T14:09:41+00:00","article_modified_time":"2011-09-27T13:45:13+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/torta.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozioni-centinaia-di-torte-per-sostenere-un%e2%80%99adozione-speciale\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-centinaia-di-torte-per-sostenere-un%e2%80%99adozione-speciale\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Adozioni: centinaia di torte per sostenere un\u2019adozione speciale","datePublished":"2011-04-07T14:09:41+00:00","dateModified":"2011-09-27T13:45:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-centinaia-di-torte-per-sostenere-un%e2%80%99adozione-speciale\/"},"wordCount":604,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-centinaia-di-torte-per-sostenere-un%e2%80%99adozione-speciale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/torta.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozioni-centinaia-di-torte-per-sostenere-un%e2%80%99adozione-speciale\/","url":"https:\/\/www.aibi.it\/ita\/adozioni-centinaia-di-torte-per-sostenere-un%e2%80%99adozione-speciale\/","name":"Adozioni: centinaia di torte per sostenere un\u2019adozione speciale - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-centinaia-di-torte-per-sostenere-un%e2%80%99adozione-speciale\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-centinaia-di-torte-per-sostenere-un%e2%80%99adozione-speciale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/torta.jpg","datePublished":"2011-04-07T14:09:41+00:00","dateModified":"2011-09-27T13:45:13+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-centinaia-di-torte-per-sostenere-un%e2%80%99adozione-speciale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozioni-centinaia-di-torte-per-sostenere-un%e2%80%99adozione-speciale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozioni-centinaia-di-torte-per-sostenere-un%e2%80%99adozione-speciale\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/torta.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/torta.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozioni-centinaia-di-torte-per-sostenere-un%e2%80%99adozione-speciale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Adozioni: centinaia di torte per sostenere un\u2019adozione speciale"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 18:10:30","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/21436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=21436"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/21436\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=21436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=21436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=21436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}