﻿


{"id":214473,"date":"2023-07-05T13:36:16","date_gmt":"2023-07-05T11:36:16","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=214473"},"modified":"2023-07-05T15:20:16","modified_gmt":"2023-07-05T13:20:16","slug":"ghana-mangiare-crescere-meglio-grazie-progetto-care-for-ghana","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/ghana-mangiare-crescere-meglio-grazie-progetto-care-for-ghana\/","title":{"rendered":"La lotta all\u2019abbandono in\u00a0Ghana. Mangiare e crescere meglio, anche in orfanotrofio,\u00a0grazie al progetto &#8220;Care for Ghana&#8221;\u00a0"},"content":{"rendered":"<h2><b>Ai.Bi. Ghana, attraverso il progetto \u201cCare for Ghana\u201d\u00a0finanziato dalla provincia di Bolzano, supporta l&#8217;orfanotrofio Royal Seed Home nell&#8217;offrire pasti equilibrati e materiali educativi ai bambini abbandonati. Un passo verso un futuro migliore e pieno di opportunit\u00e0<\/b><\/h2>\n<p><!--more--><\/p>\n<p>Il progetto \u201cCare for Ghana\u201d ha tra i suoi primi obiettivi garantire un&#8217;alimentazione sana ed equilibrata ai bambini ospitati nell\u2019orfanotrofio Royal Seed Home, partner di Ai.Bi. in Ghana. Grazie a queste donazioni, <strong>i bambini possono godere di tre pasti sostanziosi al giorno, assicurando loro le giuste energie per crescere e svilupparsi.<\/strong> Inoltre, la donazione dei libri scolastici mira a tutelare il diritto di ogni bambino a un&#8217;educazione di qualit\u00e0 presso il Royal Seed.<\/p>\n<h3><b>Lotta all&#8217;abbandono in Ghana<\/b><\/h3>\n<p>Continuano le attivit\u00e0 del progetto \u201cCare for Ghana\u201d, finanziato dalla Provincia di Bolzano, <strong>a sostegno dei 68 bambini ospitati presso l\u2019orfanotrofio Royal Seed Home, partner di Ai.Bi. in Ghana.<\/strong> In particolare, grazie agli operatori di Ai.Bi. nel Paese, \u00e8 stato possibile acquistare alcuni generi alimentari e libri presso il mercato di Kasoa, che successivamente sono stati consegnati al centro beneficiario.<\/p>\n<h3><b>Le donazioni all\u2019orfanotrofio<\/b><\/h3>\n<p>Riso, zucchero, pepe, olio, farina, pesce, uova, concentrato di pomodoro e latte in polvere, insieme a 96 libri scolastici, sono stati accuratamente selezionati e donati all\u2019orfanotrofio. La direttrice Naomi, la vice direttrice omonima e un altro membro del personale <strong>hanno accolto i pacchi con profonda gratitudine, esprimendo il loro ringraziamento per il prezioso sostegno ricevuto<br \/>\n<\/strong>Come riconoscimento formale della generosit\u00e0 di Ai.Bi., <strong>la direttrice Naomi ha consegnato a Gideon un Certificato di Apprezzamento, testimoniando il profondo riconoscimento del centro per l&#8217;importante contributo offerto.<\/strong><\/p>\n<h3><b>Aiuta anche tu le attivit\u00e0 di Ai.Bi. in Ghana<\/b><\/h3>\n<p><b>Chiunque pu\u00f2 contribuire al sostegno delle attivit\u00e0 che Ai.Bi. porta avanti in Ghana attraverso una\u00a0\u00a0<\/b><a href=\"https:\/\/www.aibi.it\/ita\/sostieni-aibi\/donazione-libera\/\"><b>donazione libera<\/b><\/a><b>, oppure aderendo al progetto \u201c<\/b><a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/?paese=Ghana\"><b>Adotta a distanza i bambini degli orfanotrofi in Ghana<\/b><\/a><b>\u201c, che permette di dare un sostegno continuativo nel corso del tempo a partire da soli 83 centesimi al giorno.<br \/>\nCome tutte le donazioni ad Ai.Bi. anche quelle per il Ghana godono delle agevolazioni fiscali previste.<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ai.Bi. Ghana, attraverso il progetto &ldquo;Care for Ghana&rdquo;&nbsp;finanziato dalla provincia di Bolzano, supporta l&rsquo;orfanotrofio Royal Seed Home nell&rsquo;offrire pasti equilibrati e materiali educativi ai bambini abbandonati. Un passo verso un futuro migliore e pieno di opportunit&agrave;<\/p>\n","protected":false},"author":125,"featured_media":214474,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[551,511],"class_list":["post-214473","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cooperazione-internazionale","tag-cooperazione-internazionale","tag-ghana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lotta all\u2019abbandono in Ghana, all&#039;interno degli orfanotrofi<\/title>\n<meta name=\"description\" content=\"Lotta all\u2019abbandono in Ghana attraverso il progetto di Ai.Bi.\u00a0finanziato dalla provincia di Bolzano a supporto dell&#039;orfanotrofio Royal Seed Home\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/ghana-mangiare-crescere-meglio-grazie-progetto-care-for-ghana\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La lotta all\u2019abbandono in\u00a0Ghana. Mangiare e crescere meglio, anche in orfanotrofio,\u00a0grazie al progetto &quot;Care for Ghana&quot;\u00a0\" \/>\n<meta property=\"og:description\" content=\"Lotta all\u2019abbandono in Ghana attraverso il progetto di Ai.Bi.\u00a0finanziato dalla provincia di Bolzano a supporto dell&#039;orfanotrofio Royal Seed Home\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/ghana-mangiare-crescere-meglio-grazie-progetto-care-for-ghana\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-05T11:36:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-05T13:20:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2023\/07\/Progetto-senza-titolo-91.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"daniela.bilanzuoli@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"daniela.bilanzuoli@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-mangiare-crescere-meglio-grazie-progetto-care-for-ghana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-mangiare-crescere-meglio-grazie-progetto-care-for-ghana\\\/\"},\"author\":{\"name\":\"daniela.bilanzuoli@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/875a59753f5fd2a8db23e6bddc57456b\"},\"headline\":\"La lotta all\u2019abbandono in\u00a0Ghana. Mangiare e crescere meglio, anche in orfanotrofio,\u00a0grazie al progetto &#8220;Care for Ghana&#8221;\u00a0\",\"datePublished\":\"2023-07-05T11:36:16+00:00\",\"dateModified\":\"2023-07-05T13:20:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-mangiare-crescere-meglio-grazie-progetto-care-for-ghana\\\/\"},\"wordCount\":367,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-mangiare-crescere-meglio-grazie-progetto-care-for-ghana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/07\\\/Progetto-senza-titolo-91.jpg\",\"keywords\":[\"cooperazione internazionale\",\"Ghana\"],\"articleSection\":[\"Cooperazione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-mangiare-crescere-meglio-grazie-progetto-care-for-ghana\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-mangiare-crescere-meglio-grazie-progetto-care-for-ghana\\\/\",\"name\":\"Lotta all\u2019abbandono in Ghana, all'interno degli orfanotrofi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-mangiare-crescere-meglio-grazie-progetto-care-for-ghana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-mangiare-crescere-meglio-grazie-progetto-care-for-ghana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/07\\\/Progetto-senza-titolo-91.jpg\",\"datePublished\":\"2023-07-05T11:36:16+00:00\",\"dateModified\":\"2023-07-05T13:20:16+00:00\",\"description\":\"Lotta all\u2019abbandono in Ghana attraverso il progetto di Ai.Bi.\u00a0finanziato dalla provincia di Bolzano a supporto dell'orfanotrofio Royal Seed Home\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-mangiare-crescere-meglio-grazie-progetto-care-for-ghana\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-mangiare-crescere-meglio-grazie-progetto-care-for-ghana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-mangiare-crescere-meglio-grazie-progetto-care-for-ghana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/07\\\/Progetto-senza-titolo-91.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/07\\\/Progetto-senza-titolo-91.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-mangiare-crescere-meglio-grazie-progetto-care-for-ghana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cooperazione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/cooperazione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La lotta all\u2019abbandono in\u00a0Ghana. Mangiare e crescere meglio, anche in orfanotrofio,\u00a0grazie al progetto &#8220;Care for Ghana&#8221;\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/875a59753f5fd2a8db23e6bddc57456b\",\"name\":\"daniela.bilanzuoli@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/daniela-bilanzuoliaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lotta all\u2019abbandono in Ghana, all'interno degli orfanotrofi","description":"Lotta all\u2019abbandono in Ghana attraverso il progetto di Ai.Bi.\u00a0finanziato dalla provincia di Bolzano a supporto dell'orfanotrofio Royal Seed Home","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/ghana-mangiare-crescere-meglio-grazie-progetto-care-for-ghana\/","og_locale":"it_IT","og_type":"article","og_title":"La lotta all\u2019abbandono in\u00a0Ghana. Mangiare e crescere meglio, anche in orfanotrofio,\u00a0grazie al progetto \"Care for Ghana\"\u00a0","og_description":"Lotta all\u2019abbandono in Ghana attraverso il progetto di Ai.Bi.\u00a0finanziato dalla provincia di Bolzano a supporto dell'orfanotrofio Royal Seed Home","og_url":"https:\/\/www.aibi.it\/ita\/ghana-mangiare-crescere-meglio-grazie-progetto-care-for-ghana\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2023-07-05T11:36:16+00:00","article_modified_time":"2023-07-05T13:20:16+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2023\/07\/Progetto-senza-titolo-91.jpg","type":"image\/jpeg"}],"author":"daniela.bilanzuoli@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"daniela.bilanzuoli@aibi.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/ghana-mangiare-crescere-meglio-grazie-progetto-care-for-ghana\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-mangiare-crescere-meglio-grazie-progetto-care-for-ghana\/"},"author":{"name":"daniela.bilanzuoli@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/875a59753f5fd2a8db23e6bddc57456b"},"headline":"La lotta all\u2019abbandono in\u00a0Ghana. Mangiare e crescere meglio, anche in orfanotrofio,\u00a0grazie al progetto &#8220;Care for Ghana&#8221;\u00a0","datePublished":"2023-07-05T11:36:16+00:00","dateModified":"2023-07-05T13:20:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-mangiare-crescere-meglio-grazie-progetto-care-for-ghana\/"},"wordCount":367,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-mangiare-crescere-meglio-grazie-progetto-care-for-ghana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/07\/Progetto-senza-titolo-91.jpg","keywords":["cooperazione internazionale","Ghana"],"articleSection":["Cooperazione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/ghana-mangiare-crescere-meglio-grazie-progetto-care-for-ghana\/","url":"https:\/\/www.aibi.it\/ita\/ghana-mangiare-crescere-meglio-grazie-progetto-care-for-ghana\/","name":"Lotta all\u2019abbandono in Ghana, all'interno degli orfanotrofi","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-mangiare-crescere-meglio-grazie-progetto-care-for-ghana\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-mangiare-crescere-meglio-grazie-progetto-care-for-ghana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/07\/Progetto-senza-titolo-91.jpg","datePublished":"2023-07-05T11:36:16+00:00","dateModified":"2023-07-05T13:20:16+00:00","description":"Lotta all\u2019abbandono in Ghana attraverso il progetto di Ai.Bi.\u00a0finanziato dalla provincia di Bolzano a supporto dell'orfanotrofio Royal Seed Home","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-mangiare-crescere-meglio-grazie-progetto-care-for-ghana\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/ghana-mangiare-crescere-meglio-grazie-progetto-care-for-ghana\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/ghana-mangiare-crescere-meglio-grazie-progetto-care-for-ghana\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2023\/07\/Progetto-senza-titolo-91.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/07\/Progetto-senza-titolo-91.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/ghana-mangiare-crescere-meglio-grazie-progetto-care-for-ghana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Cooperazione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/cooperazione-internazionale\/"},{"@type":"ListItem","position":3,"name":"La lotta all\u2019abbandono in\u00a0Ghana. Mangiare e crescere meglio, anche in orfanotrofio,\u00a0grazie al progetto &#8220;Care for Ghana&#8221;\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/875a59753f5fd2a8db23e6bddc57456b","name":"daniela.bilanzuoli@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/daniela-bilanzuoliaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 09:28:02","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/214473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/125"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=214473"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/214473\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/214474"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=214473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=214473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=214473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}