﻿


{"id":214754,"date":"2023-07-13T07:30:42","date_gmt":"2023-07-13T05:30:42","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=214754"},"modified":"2023-07-13T15:57:45","modified_gmt":"2023-07-13T13:57:45","slug":"rosa-di-jericho-bomboniera-solidale","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/rosa-di-jericho-bomboniera-solidale\/","title":{"rendered":"La &#8220;Rosa di Jericho&#8221;: un&#8217;esclusiva bomboniera solidale piena di significato"},"content":{"rendered":"<h2>Tra le esclusive bomboniere solidali di Ai.Bi. la Rosa di Jericho \u00e8 particolarmente significativa, perch\u00e9 simboleggia la rinascita: quella di un bambino abbandonato all\u2019interno di una famiglia<strong><br \/>\n<\/strong><\/h2>\n<p><!--more--><\/p>\n<blockquote><p>Buongiorno,<br \/>\nsto cercando una bomboniera solidale per la Cresima di mia figlia che si terr\u00e0 a ottobre e ho visto sul vostro sito la rosa di Jericho. Mi ha colpito molto, soprattutto per il suo significato, e mi piacerebbe utilizzarla come bomboniera da regalare ai nostri invitati.<br \/>\nPosso sapere come viene consegnata e quanto tempo prima devo fare l\u2019ordine?<br \/>\nGrazie<br \/>\nStella<\/p><\/blockquote>\n<p>Gentile Stella,<br \/>\nci fa piacere sapere che sempre pi\u00f9 persone scelgono le bomboniere solidali per festeggiare i loro eventi importanti, dando un sostegno a una buona causa e creando cos\u00ec un circolo virtuoso della solidariet\u00e0.<br \/>\nCome avrai sicuramente visto sul nostro sito, tante sono le nostre proposte solidali e, tra queste, c\u2019\u00e8 anche la <strong>Rosa di Jericho<\/strong>, che \u00e8 il simbolo della nostra Associazione perch\u00e9 rappresenta \u201cla vita\u201d che non muore mai e \u201cl\u2019amore\u201d che pu\u00f2 farla rifiorire.<br \/>\nPer Ai.Bi. questa pianta del deserto <strong>simboleggia <\/strong><strong>la rinascita di un bambino abbandonato all\u2019interno di una famiglia<\/strong>.<strong><br \/>\n<\/strong>La rosa di Jericho, infatti, si presenta chiusa e secca, ma le bastano pochissime gocce d\u2019acqua per aprirsi completamente, <strong>fiorire e tornare a splendere<\/strong>, proprio come un bambino che torna a sentirsi figlio grazie alle amorevoli attenzioni e cure di una mamma e di un pap\u00e0.<br \/>\n<strong>La Rosa di Jericho <\/strong>viene fornita all\u2019interno di una confezione di cartone color avana, riposta su un piattino di terracotta e protetta da un sacchetto di cellophane. Ogni scatola contiene inoltre una pergamena che spiega il suo significato simbolico e le istruzioni per la fioritura. \u00c8 disponibile in due formati, grande o piccola.<br \/>\nIl costo della rosa include anche un\u2019elegante pergamena o un cartoncino personalizzato con i dati dell\u2019evento e il logo dell\u2019associazione a testimonianza del vostro gesto di solidariet\u00e0.<br \/>\nPotete inoltre decidere di ordinare solo la rosa di Jericho e pensare poi voi al confezionamento oppure scegliere la bomboniera confezionata e quindi completa di sacchettino con 5 confetti e nastro del colore a vostra scelta tra quelli proposti sul sito.<br \/>\nI tempi di consegna per la rosa di Jericho non confezionata sono di circa 15\/20 gg mentre per le bomboniere confezionate i tempi di lavorazione sono di circa 30 gg.<br \/>\nPuoi trovare tutte le informazioni necessarie per completare il tuo ordine direttamente sul sito della nostra <a href=\"https:\/\/www.fondazioneaibi.it\/bomboniere-solidali\/\"><strong>Fondazione Ai.Bi.<\/strong><\/a><br \/>\nPer qualsiasi ulteriore richiesta di informazioni o chiarimento non esitare a contattarci al n.\u00a0<a href=\"callto:0298822359\">0298822359<\/a>\u00a0o via mail all\u2019indirizzo\u00a0<strong>bomboniere@aibi.it<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tra le esclusive bomboniere solidali di Ai.Bi. la Rosa di Jericho &egrave; particolarmente significativa, perch&eacute; simboleggia la rinascita: quella di un bambino abbandonato all&rsquo;interno di una famiglia<\/p>\n","protected":false},"author":102,"featured_media":157116,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[764],"tags":[944,520],"class_list":["post-214754","post","type-post","status-publish","format-standard","has-post-thumbnail","category-progetti-in-italia","tag-battesimo","tag-bomboniere-solidali"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Rosa di Jericho: una bomboniera solidale piena di significato<\/title>\n<meta name=\"description\" content=\"L&#039;esclusiva bomboniera solidale &quot;Rosa di Jericho&quot; di Ai.Bi. simboleggia la rinascita: quella di un bambino abbandonato all\u2019interno di una famiglia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/rosa-di-jericho-bomboniera-solidale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La &quot;Rosa di Jericho&quot;: un&#039;esclusiva bomboniera solidale piena di significato\" \/>\n<meta property=\"og:description\" content=\"L&#039;esclusiva bomboniera solidale &quot;Rosa di Jericho&quot; di Ai.Bi. simboleggia la rinascita: quella di un bambino abbandonato all\u2019interno di una famiglia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/rosa-di-jericho-bomboniera-solidale\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-13T05:30:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-13T13:57:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/rosa-di-jericho_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rosa-di-jericho-bomboniera-solidale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rosa-di-jericho-bomboniera-solidale\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"La &#8220;Rosa di Jericho&#8221;: un&#8217;esclusiva bomboniera solidale piena di significato\",\"datePublished\":\"2023-07-13T05:30:42+00:00\",\"dateModified\":\"2023-07-13T13:57:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rosa-di-jericho-bomboniera-solidale\\\/\"},\"wordCount\":437,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rosa-di-jericho-bomboniera-solidale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/rosa-di-jericho_fb.jpg\",\"keywords\":[\"battesimo;\",\"bomboniere solidali\"],\"articleSection\":[\"Progetti in Italia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rosa-di-jericho-bomboniera-solidale\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rosa-di-jericho-bomboniera-solidale\\\/\",\"name\":\"Rosa di Jericho: una bomboniera solidale piena di significato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rosa-di-jericho-bomboniera-solidale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rosa-di-jericho-bomboniera-solidale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/rosa-di-jericho_fb.jpg\",\"datePublished\":\"2023-07-13T05:30:42+00:00\",\"dateModified\":\"2023-07-13T13:57:45+00:00\",\"description\":\"L'esclusiva bomboniera solidale \\\"Rosa di Jericho\\\" di Ai.Bi. simboleggia la rinascita: quella di un bambino abbandonato all\u2019interno di una famiglia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rosa-di-jericho-bomboniera-solidale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rosa-di-jericho-bomboniera-solidale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rosa-di-jericho-bomboniera-solidale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/rosa-di-jericho_fb.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/rosa-di-jericho_fb.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rosa-di-jericho-bomboniera-solidale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti in Italia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/progetti-in-italia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La &#8220;Rosa di Jericho&#8221;: un&#8217;esclusiva bomboniera solidale piena di significato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rosa di Jericho: una bomboniera solidale piena di significato","description":"L'esclusiva bomboniera solidale \"Rosa di Jericho\" di Ai.Bi. simboleggia la rinascita: quella di un bambino abbandonato all\u2019interno di una famiglia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/rosa-di-jericho-bomboniera-solidale\/","og_locale":"it_IT","og_type":"article","og_title":"La \"Rosa di Jericho\": un'esclusiva bomboniera solidale piena di significato","og_description":"L'esclusiva bomboniera solidale \"Rosa di Jericho\" di Ai.Bi. simboleggia la rinascita: quella di un bambino abbandonato all\u2019interno di una famiglia","og_url":"https:\/\/www.aibi.it\/ita\/rosa-di-jericho-bomboniera-solidale\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2023-07-13T05:30:42+00:00","article_modified_time":"2023-07-13T13:57:45+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/rosa-di-jericho_fb.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/rosa-di-jericho-bomboniera-solidale\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/rosa-di-jericho-bomboniera-solidale\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"La &#8220;Rosa di Jericho&#8221;: un&#8217;esclusiva bomboniera solidale piena di significato","datePublished":"2023-07-13T05:30:42+00:00","dateModified":"2023-07-13T13:57:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/rosa-di-jericho-bomboniera-solidale\/"},"wordCount":437,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/rosa-di-jericho-bomboniera-solidale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/rosa-di-jericho_fb.jpg","keywords":["battesimo;","bomboniere solidali"],"articleSection":["Progetti in Italia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/rosa-di-jericho-bomboniera-solidale\/","url":"https:\/\/www.aibi.it\/ita\/rosa-di-jericho-bomboniera-solidale\/","name":"Rosa di Jericho: una bomboniera solidale piena di significato","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/rosa-di-jericho-bomboniera-solidale\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/rosa-di-jericho-bomboniera-solidale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/rosa-di-jericho_fb.jpg","datePublished":"2023-07-13T05:30:42+00:00","dateModified":"2023-07-13T13:57:45+00:00","description":"L'esclusiva bomboniera solidale \"Rosa di Jericho\" di Ai.Bi. simboleggia la rinascita: quella di un bambino abbandonato all\u2019interno di una famiglia","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/rosa-di-jericho-bomboniera-solidale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/rosa-di-jericho-bomboniera-solidale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/rosa-di-jericho-bomboniera-solidale\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/rosa-di-jericho_fb.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/rosa-di-jericho_fb.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/rosa-di-jericho-bomboniera-solidale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Progetti in Italia","item":"https:\/\/www.aibi.it\/ita\/category\/progetti-in-italia\/"},{"@type":"ListItem","position":3,"name":"La &#8220;Rosa di Jericho&#8221;: un&#8217;esclusiva bomboniera solidale piena di significato"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 06:22:45","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/214754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=214754"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/214754\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/157116"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=214754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=214754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=214754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}