﻿


{"id":215174,"date":"2023-08-02T08:00:31","date_gmt":"2023-08-02T06:00:31","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=215174"},"modified":"2023-08-01T14:35:33","modified_gmt":"2023-08-01T12:35:33","slug":"torino-stanza-ascolto-donne-abortire","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/torino-stanza-ascolto-donne-abortire\/","title":{"rendered":"Torino. Una stanza di ascolto per le donne che hanno intenzione di abortire"},"content":{"rendered":"<h2>Presso l\u2019Ospedale Sant&#8217;Anna di Torino nasce una stanza di ascolto per le donne in gravidanza. Un servizio di sostegno per le donne che si trovano in situazioni di fragilit\u00e0 o vulnerabilit\u00e0 durante la gravidanza<!--more--><\/h2>\n<p>Per offrire supporto e vicinanza alle <strong>donne in gravidanza<\/strong> che stanno pensando all\u2019aborto, nasce presso l&#8217;<strong>Ospedale Sant&#8217;Anna di Torino<\/strong> una <strong>stanza di ascolto<\/strong>.<br \/>\nSi tratta di una convenzione tra la <strong>Citt\u00e0 della Salute<\/strong> e la <strong>Federazione Movimento per la vita<\/strong>, uno spazio dove le donne e le coppie che vivono il momento con difficolt\u00e0 possono trovare aiuto nei progetti a sostegno della vita nascente.<\/p>\n<h3>La stanza di ascolto: come funziona<\/h3>\n<p>La stanza di ascolto \u00e8 un servizio gratuito e volontario che si rivolge alle donne gestanti che ne abbiano necessit\u00e0, nell&#8217;ambito di un pi\u00f9 generale percorso di sostegno durante e dopo la gravidanza. Le donne possono accedere alla stanza di ascolto tramite un appuntamento telefonico o tramite il personale sanitario dell&#8217;ospedale.<br \/>\nLa stanza di ascolto \u00e8 gestita da operatori qualificati del Movimento per la vita, che offrono un&#8217;ascolto attento e rispettoso delle esigenze delle donne, contribuendo a far superare le cause che potrebbero indurre alla interruzione della gravidanza. Gli operatori possono anche fornire informazioni sui servizi e le opportunit\u00e0 presenti sul territorio, come ad esempio i centri di aiuto alla vita, le case famiglia, i consultori familiari, i servizi sociali.<br \/>\nLa stanza di ascolto non ha alcuna finalit\u00e0 medica o giuridica, ma solo umana e solidale. Non si tratta quindi di un luogo dove si effettuano diagnosi o prescrizioni, ma dove si cerca di accompagnare le donne nella loro scelta, nel rispetto della loro libert\u00e0 e dignit\u00e0.<\/p>\n<h3>L&#8217;Ospedale Sant&#8217;Anna<\/h3>\n<p>L&#8217;ospedale piemontese \u00e8 il presidio sanitario primo in Italia per numero di parti con 6.590 nuovi nati nel 2020 e dove si effettua il maggior numero di interruzioni di gravidanza, con circa 2.500 casi nel 2021 (il 90% delle ivg effettuate a Torino e circa il 50% di quelle a livello regionale).<br \/>\n&#8220;Ogni volta che una donna abortisce perch\u00e9 si \u00e8 sentita abbandonata di fronte alla sfida della maternit\u00e0 siamo di fronte a una drammatica sconfitta delle istituzioni. Per questa ragione aprire nel principale ospedale ostetrico ginecologico del Piemonte uno spazio dove donne e coppie in difficolt\u00e0 possano trovare aiuto nei progetti a sostegno della vita nascente \u00e8 una conquista sociale per tutta la comunit\u00e0&#8221; spiega l&#8217;assessore alle Politiche Sociali della Regione Piemonte <strong>Maurizio Marrone.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Presso l&rsquo;Ospedale Sant&rsquo;Anna di Torino nasce una stanza di ascolto per le donne in gravidanza. Un servizio di sostegno per le donne che si trovano in situazioni di fragilit&agrave; o vulnerabilit&agrave; durante la gravidanza<\/p>\n","protected":false},"author":133,"featured_media":215175,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[515],"class_list":["post-215174","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","tag-aborto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Torino. Una stanza di ascolto per le donne che hanno intenzione di abortire<\/title>\n<meta name=\"description\" content=\"Presso l\u2019Ospedale Sant&#039;Anna di Torino nasce una stanza di ascolto per le donne in gravidanza. Un servizio di sostegno per le donne che si trovano in situazioni di fragilit\u00e0 o vulnerabilit\u00e0 durante la gravidanza\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/torino-stanza-ascolto-donne-abortire\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Torino. Una stanza di ascolto per le donne che hanno intenzione di abortire\" \/>\n<meta property=\"og:description\" content=\"Presso l\u2019Ospedale Sant&#039;Anna di Torino nasce una stanza di ascolto per le donne in gravidanza. Un servizio di sostegno per le donne che si trovano in situazioni di fragilit\u00e0 o vulnerabilit\u00e0 durante la gravidanza\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/torino-stanza-ascolto-donne-abortire\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-02T06:00:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2023\/08\/Torino-Stanza-di-ascolto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/torino-stanza-ascolto-donne-abortire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/torino-stanza-ascolto-donne-abortire\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Torino. Una stanza di ascolto per le donne che hanno intenzione di abortire\",\"datePublished\":\"2023-08-02T06:00:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/torino-stanza-ascolto-donne-abortire\\\/\"},\"wordCount\":412,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/torino-stanza-ascolto-donne-abortire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/08\\\/Torino-Stanza-di-ascolto.jpg\",\"keywords\":[\"aborto\"],\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/torino-stanza-ascolto-donne-abortire\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/torino-stanza-ascolto-donne-abortire\\\/\",\"name\":\"Torino. Una stanza di ascolto per le donne che hanno intenzione di abortire\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/torino-stanza-ascolto-donne-abortire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/torino-stanza-ascolto-donne-abortire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/08\\\/Torino-Stanza-di-ascolto.jpg\",\"datePublished\":\"2023-08-02T06:00:31+00:00\",\"description\":\"Presso l\u2019Ospedale Sant'Anna di Torino nasce una stanza di ascolto per le donne in gravidanza. Un servizio di sostegno per le donne che si trovano in situazioni di fragilit\u00e0 o vulnerabilit\u00e0 durante la gravidanza\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/torino-stanza-ascolto-donne-abortire\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/torino-stanza-ascolto-donne-abortire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/torino-stanza-ascolto-donne-abortire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/08\\\/Torino-Stanza-di-ascolto.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/08\\\/Torino-Stanza-di-ascolto.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/torino-stanza-ascolto-donne-abortire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Torino. Una stanza di ascolto per le donne che hanno intenzione di abortire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Torino. Una stanza di ascolto per le donne che hanno intenzione di abortire","description":"Presso l\u2019Ospedale Sant'Anna di Torino nasce una stanza di ascolto per le donne in gravidanza. Un servizio di sostegno per le donne che si trovano in situazioni di fragilit\u00e0 o vulnerabilit\u00e0 durante la gravidanza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/torino-stanza-ascolto-donne-abortire\/","og_locale":"it_IT","og_type":"article","og_title":"Torino. Una stanza di ascolto per le donne che hanno intenzione di abortire","og_description":"Presso l\u2019Ospedale Sant'Anna di Torino nasce una stanza di ascolto per le donne in gravidanza. Un servizio di sostegno per le donne che si trovano in situazioni di fragilit\u00e0 o vulnerabilit\u00e0 durante la gravidanza","og_url":"https:\/\/www.aibi.it\/ita\/torino-stanza-ascolto-donne-abortire\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2023-08-02T06:00:31+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2023\/08\/Torino-Stanza-di-ascolto.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/torino-stanza-ascolto-donne-abortire\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/torino-stanza-ascolto-donne-abortire\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Torino. Una stanza di ascolto per le donne che hanno intenzione di abortire","datePublished":"2023-08-02T06:00:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/torino-stanza-ascolto-donne-abortire\/"},"wordCount":412,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/torino-stanza-ascolto-donne-abortire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/08\/Torino-Stanza-di-ascolto.jpg","keywords":["aborto"],"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/torino-stanza-ascolto-donne-abortire\/","url":"https:\/\/www.aibi.it\/ita\/torino-stanza-ascolto-donne-abortire\/","name":"Torino. Una stanza di ascolto per le donne che hanno intenzione di abortire","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/torino-stanza-ascolto-donne-abortire\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/torino-stanza-ascolto-donne-abortire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/08\/Torino-Stanza-di-ascolto.jpg","datePublished":"2023-08-02T06:00:31+00:00","description":"Presso l\u2019Ospedale Sant'Anna di Torino nasce una stanza di ascolto per le donne in gravidanza. Un servizio di sostegno per le donne che si trovano in situazioni di fragilit\u00e0 o vulnerabilit\u00e0 durante la gravidanza","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/torino-stanza-ascolto-donne-abortire\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/torino-stanza-ascolto-donne-abortire\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/torino-stanza-ascolto-donne-abortire\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2023\/08\/Torino-Stanza-di-ascolto.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/08\/Torino-Stanza-di-ascolto.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/torino-stanza-ascolto-donne-abortire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Torino. Una stanza di ascolto per le donne che hanno intenzione di abortire"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 09:27:32","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/215174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=215174"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/215174\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/215175"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=215174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=215174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=215174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}