﻿


{"id":215222,"date":"2023-08-06T08:55:33","date_gmt":"2023-08-06T06:55:33","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=215222"},"modified":"2023-08-06T09:53:00","modified_gmt":"2023-08-06T07:53:00","slug":"adozione-internazionale-david-antony-fratello-sorella","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-david-antony-fratello-sorella\/","title":{"rendered":"Adozione internazionale. David e Antony: &#8220;Io vorr\u00f2 sempre un fratello o una sorella, per tutta la vita, non smetter\u00f2 mai di aspettare!\u201d"},"content":{"rendered":"<h2 class=\"gmail-p1\">Se oggi\u00a0Antony, un ragazzino colombiano di 12 anni, \u00e8 diventato\u00a0nuovamente figlio, ha\u00a0due genitori\u00a0e una\u00a0prospettiva di vita serena, lo deve alla caparbiet\u00e0 di suo\u00a0fratello David, arrivato in Italia dal Per\u00f9 dieci anni fa<\/h2>\n<p><!--more--><\/p>\n<p>\u00c8 stato proprio <strong>David<\/strong> che in pi\u00f9 occasioni nel corso degli anni ha sostenuto e incoraggiato i genitori <strong>Teresa e Marco<\/strong> a non mollare, in attesa della loro <strong>seconda adozione<\/strong>.<br \/>\nE ha tenuto testa perfino davanti a un <strong>giudice di un Tribunale per i minorenni<\/strong> quando, convocata tutta la famiglia per un possibile caso di adozione nazionale, in realt\u00e0 il tutto si tradusse in una verifica e aggiornamento di documenti. E cos\u00ec, davanti al giudice che non era nelle condizioni di proporre un abbinamento, David ha detto: \u201c<strong>Io vorr\u00f2 sempre un fratello o una sorella<\/strong>, per tutta la vita, <strong>non smetter\u00f2 mai di aspettare!<\/strong>\u201d.<br \/>\nLa dimostrazione pi\u00f9 evidente che David <strong>si sentiva gi\u00e0 fratello maggiore di un\u00a0un bambino o una bambina in attesa<\/strong> in qualche parte del mondo.<br \/>\n\u201cDavid quel giorno ci ha sorpreso e commosso \u2013 dicono Marco e Teresa, che con Ai.Bi. adottarono David, allora 3 anni e mezzo, in Per\u00f9 \u2013 e davvero ci ha dato molta carica. Certo che desideravamo ancora adottare , ma chi ci \u00e8 passato sa che i tempi lunghi di attesa possono far allontanare il pensiero oppure pu\u00f2 spingere le famiglie a ripensare alle loro scelte. In pi\u00f9 \u2013 aggiunge la mamma \u2013 avremmo dovuto attendere ancora molto per incontrare Antony: anni spesi da nostro figlio, comunque, fuori dalla famiglia\u201d.<br \/>\nIl tempo che passa infatti \u00e8 spesso visto solo dall\u2019ottica degli adulti, da chi deve lottare contro la burocrazia; meno si tende a riflettere sulla diversa percezione del tempo, e sui suoi effetti, dalla prospettiva dei bambini in istituto per i quali la famiglia \u00e8 un bisogno speciale e urgente.<br \/>\nCos\u00ec dopo tentativi andati a vuoto con l\u2019adozione internazionale, Teresa e Marco sono tornati dalle \u201ccicogne di Salerno, ovvero la sede Ai.Bi. che ci conosce molto bene\u201d e sono ripartiti, ricominciando da capo, con l\u2019iter per l\u2019adozione internazionale. David allora aveva dieci anni e ne avrebbe attesi altri tre prima di incontrare suo fratello.<\/p>\n<h3>L\u2019arrivo di Antony<\/h3>\n<p><strong>Antony \u00e8 arrivato in Italia a fine aprile<\/strong> di quest\u2019anno dopo essere stato abbinato alla famiglia l\u2019ottobre precedente. A <strong>Natale<\/strong>, sotto l\u2019albero <strong>David ha confezionato in tanti pacchi regalo la foto del fratello<\/strong>, per tutti i parenti della famiglia. Si possono immaginare i volti sorpresi e commossi di tutti quanti.<br \/>\nEra ormai partito il conto alla rovescia.<br \/>\n\u201cAltri mesi di attesa che diventavano sempre pi\u00f9 difficili da sopportare &#8211; racconta Teresa &#8211; : erano certamente tempi tecnici e burocratici tra Italia e Colombia, tempi che abbiamo cercato di rendere produttivi al massimo. E cos\u00ec abbiamo iniziato a incontrare Antony in video chiamata una volta alla settimana con la referente Ai.Bi. nel paese e la psicologa del bambino, una giovane colombiana che ha studiato italiano quindi efficacissima nel facilitare la comunicazione. In Colombia sono davvero bravissimi a preparare i bambini\u201d.<br \/>\nMarzo \u00e8 arrivato e con questo l\u2019incontro a Bogot\u00e0 con quel figlio in carne ed ossa, i capelli rossicci e le lentiggini, felicissimo di stritolare la mamma, finalmente.<br \/>\n\u201cOggi <strong>Antony \u00e8 ancora un sulla difensiva<\/strong>, del resto ci conosce solo da quattro mesi, ma <strong>gi\u00e0 esprime un fortissimo attaccamento alla mamma<\/strong>, mentre David fin da subito aveva interagito maggiormente con me \u2013 racconta Marco \u2013 Questo per\u00f2 \u00e8 normale, dipende dalle storie singole dei bambini, dal loro passato, da quali figure di riferimento adulte hanno contato di pi\u00f9 o di meno nella loro vita\u201d.<br \/>\nDavid era arrivato nella sua casa in Molise relativamente piccolo, con un <strong>bisogno sanitario<\/strong> che pareva impegnativo e che poi si \u00e8 rivelato gestibile (un caso di idrocefalia ben compensata). Una adozione che Marco e Teresa definiscono <strong>perfetta nel senso che tutto si \u00e8 svolto nel pi\u00f9 naturale dei mondi<\/strong>, dal percorso all\u2019ambientamento del figlio, sorridente e, come abbiamo compreso, di una tenacia incrollabile che gli ha permesso di partire, oggi, felice per andare a conoscere il fratello.<br \/>\nNei giorni colombiani, Antony ha compiuto 12 anni, la mamma ha fatto in tempo a ammalarsi a causa di un virus \u2013 \u201cEra capitata la stessa cosa in Per\u00f9 con David: probabilmente ho scaricato la tensione!\u201d, dice Teresa \u2013 e tutta la famiglia, con il supporto dei referenti locali, \u00e8 stata sostenuta e aiutata nella gestione delle prime settimane di convivenza della famiglia. Anche nella dimensione del tempo libero.<br \/>\n\u201cIn entrambe le adozioni siamo stati seguiti molto bene dallo staff locale e da quello in sede &#8211; raccontano i genitori che si sono appassionati alla lingua spagnola e alla cultura sudamericana &#8211; e questo ha aiutato moltissimo nei primi giorni, subito dopo l\u2019incontro con i figli\u201d.<br \/>\nAntony a settembre andr\u00e0 in seconda media, \u201cin una scuola che lo ha accolto molto bene e ha gi\u00e0 valutato nostro figlio inserendolo nella classe pi\u00f9 adatta a lui e con il dovuto sostegno. \u2013 dice Teresa \u2013 Gli insegnanti ci hanno consigliato un percorso di studio estivo ma gi\u00e0 vediamo che <strong>Antony sta recuperando<\/strong>, \u00e8 un ragazzino maturo\u201d. Nel frattempo va a nuoto e partecipa a campi estivi.<br \/>\nIntanto cresce e <strong>si rafforza il legame di fratellanza con David<\/strong>: i due stanno imparando a stare insieme e Antony sta gi\u00e0 confidando al fratello ricordi e pezzi di storia personale che non erano presenti nella scheda di abbinamento.<\/p>\n<p>Undici anni di vita, certamente sotto protezione, ma in stato di abbandono dai legami fondamentali; undici anni vissuti in istituto e in diverse famiglie affidatarie, senza mai perdere la speranza di poter finalmente\u00a0 trovare casa e famiglia.<\/p>\n<h3>Informazioni e domande sull\u2019adozione internazionale<\/h3>\n<p>Chi sta considerando un\u2019adozione internazionale o semplicemente desidera avere maggiori informazioni a su questi temi, pu\u00f2 contattare l\u2019ufficio adozioni di Ai.Bi. scrivendo un\u2019e-mail a\u00a0<a href=\"mailto:adozioni@aibi.it\"><strong>adozioni@aibi.it<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se oggi&nbsp;Antony, un ragazzino colombiano di 12 anni, &egrave; diventato&nbsp;nuovamente figlio, ha&nbsp;due genitori&nbsp;e una&nbsp;prospettiva di vita serena, lo deve alla caparbiet&agrave; di suo&nbsp;fratello David, arrivato in Italia dal Per&ugrave; dieci anni fa<\/p>\n","protected":false},"author":133,"featured_media":215223,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[279,347],"class_list":["post-215222","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale","tag-adozione","tag-adozione-internazionale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione internazionale. David e Antony: &quot;Io vorr\u00f2 sempre un fratello o una sorella&quot;<\/title>\n<meta name=\"description\" content=\"Se oggi\u00a0Antony, un ragazzino colombiano di 12 anni, \u00e8 diventato\u00a0nuovamente figlio, ha\u00a0due genitori\u00a0e una\u00a0prospettiva di vita serena, lo deve alla caparbiet\u00e0 di suo\u00a0fratello David, arrivato in Italia dal Per\u00f9 dieci anni fa\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-david-antony-fratello-sorella\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione internazionale. David e Antony: &quot;Io vorr\u00f2 sempre un fratello o una sorella, per tutta la vita, non smetter\u00f2 mai di aspettare!\u201d\" \/>\n<meta property=\"og:description\" content=\"Se oggi\u00a0Antony, un ragazzino colombiano di 12 anni, \u00e8 diventato\u00a0nuovamente figlio, ha\u00a0due genitori\u00a0e una\u00a0prospettiva di vita serena, lo deve alla caparbiet\u00e0 di suo\u00a0fratello David, arrivato in Italia dal Per\u00f9 dieci anni fa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-david-antony-fratello-sorella\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-06T06:55:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-06T07:53:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2023\/08\/Adozione-internazionale-fratelli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-david-antony-fratello-sorella\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-david-antony-fratello-sorella\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Adozione internazionale. David e Antony: &#8220;Io vorr\u00f2 sempre un fratello o una sorella, per tutta la vita, non smetter\u00f2 mai di aspettare!\u201d\",\"datePublished\":\"2023-08-06T06:55:33+00:00\",\"dateModified\":\"2023-08-06T07:53:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-david-antony-fratello-sorella\\\/\"},\"wordCount\":981,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-david-antony-fratello-sorella\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/08\\\/Adozione-internazionale-fratelli.jpg\",\"keywords\":[\"adozione\",\"Adozione Internazionale\"],\"articleSection\":[\"Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-david-antony-fratello-sorella\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-david-antony-fratello-sorella\\\/\",\"name\":\"Adozione internazionale. David e Antony: \\\"Io vorr\u00f2 sempre un fratello o una sorella\\\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-david-antony-fratello-sorella\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-david-antony-fratello-sorella\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/08\\\/Adozione-internazionale-fratelli.jpg\",\"datePublished\":\"2023-08-06T06:55:33+00:00\",\"dateModified\":\"2023-08-06T07:53:00+00:00\",\"description\":\"Se oggi\u00a0Antony, un ragazzino colombiano di 12 anni, \u00e8 diventato\u00a0nuovamente figlio, ha\u00a0due genitori\u00a0e una\u00a0prospettiva di vita serena, lo deve alla caparbiet\u00e0 di suo\u00a0fratello David, arrivato in Italia dal Per\u00f9 dieci anni fa\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-david-antony-fratello-sorella\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-david-antony-fratello-sorella\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-david-antony-fratello-sorella\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/08\\\/Adozione-internazionale-fratelli.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/08\\\/Adozione-internazionale-fratelli.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-david-antony-fratello-sorella\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione internazionale. David e Antony: &#8220;Io vorr\u00f2 sempre un fratello o una sorella, per tutta la vita, non smetter\u00f2 mai di aspettare!\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione internazionale. David e Antony: \"Io vorr\u00f2 sempre un fratello o una sorella\"","description":"Se oggi\u00a0Antony, un ragazzino colombiano di 12 anni, \u00e8 diventato\u00a0nuovamente figlio, ha\u00a0due genitori\u00a0e una\u00a0prospettiva di vita serena, lo deve alla caparbiet\u00e0 di suo\u00a0fratello David, arrivato in Italia dal Per\u00f9 dieci anni fa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-david-antony-fratello-sorella\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione internazionale. David e Antony: \"Io vorr\u00f2 sempre un fratello o una sorella, per tutta la vita, non smetter\u00f2 mai di aspettare!\u201d","og_description":"Se oggi\u00a0Antony, un ragazzino colombiano di 12 anni, \u00e8 diventato\u00a0nuovamente figlio, ha\u00a0due genitori\u00a0e una\u00a0prospettiva di vita serena, lo deve alla caparbiet\u00e0 di suo\u00a0fratello David, arrivato in Italia dal Per\u00f9 dieci anni fa","og_url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-david-antony-fratello-sorella\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2023-08-06T06:55:33+00:00","article_modified_time":"2023-08-06T07:53:00+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2023\/08\/Adozione-internazionale-fratelli.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-david-antony-fratello-sorella\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-david-antony-fratello-sorella\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Adozione internazionale. David e Antony: &#8220;Io vorr\u00f2 sempre un fratello o una sorella, per tutta la vita, non smetter\u00f2 mai di aspettare!\u201d","datePublished":"2023-08-06T06:55:33+00:00","dateModified":"2023-08-06T07:53:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-david-antony-fratello-sorella\/"},"wordCount":981,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-david-antony-fratello-sorella\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/08\/Adozione-internazionale-fratelli.jpg","keywords":["adozione","Adozione Internazionale"],"articleSection":["Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-david-antony-fratello-sorella\/","url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-david-antony-fratello-sorella\/","name":"Adozione internazionale. David e Antony: \"Io vorr\u00f2 sempre un fratello o una sorella\"","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-david-antony-fratello-sorella\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-david-antony-fratello-sorella\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/08\/Adozione-internazionale-fratelli.jpg","datePublished":"2023-08-06T06:55:33+00:00","dateModified":"2023-08-06T07:53:00+00:00","description":"Se oggi\u00a0Antony, un ragazzino colombiano di 12 anni, \u00e8 diventato\u00a0nuovamente figlio, ha\u00a0due genitori\u00a0e una\u00a0prospettiva di vita serena, lo deve alla caparbiet\u00e0 di suo\u00a0fratello David, arrivato in Italia dal Per\u00f9 dieci anni fa","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-david-antony-fratello-sorella\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-internazionale-david-antony-fratello-sorella\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-david-antony-fratello-sorella\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2023\/08\/Adozione-internazionale-fratelli.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/08\/Adozione-internazionale-fratelli.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-david-antony-fratello-sorella\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Adozione internazionale. David e Antony: &#8220;Io vorr\u00f2 sempre un fratello o una sorella, per tutta la vita, non smetter\u00f2 mai di aspettare!\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 09:59:52","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/215222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=215222"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/215222\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/215223"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=215222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=215222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=215222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}