﻿{"id":21525,"date":"2011-04-08T15:02:38","date_gmt":"2011-04-08T14:02:38","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=21525"},"modified":"2011-04-08T15:04:16","modified_gmt":"2011-04-08T14:04:16","slug":"cina-il-nome-meraviglioso-di-nostro-figlio","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/cina-il-nome-meraviglioso-di-nostro-figlio\/","title":{"rendered":"Cina: il nome meraviglioso di nostro figlio"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/MONDO11.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-21526\" style=\"margin: 5px;\" title=\"MONDO[1]\" src=\"https:\/\/www.aibi.it\/ita\/images\/MONDO11.jpg\" alt=\"\" width=\"100\" height=\"100\" \/><\/a>Il piccolo Zhijian \u00e8 tornato pochi giorni fa dalla Cina con mamma Arianna e pap\u00e0 Igor. La sua storia di adozione \u00e8 unica e speciale.<br \/>\n<em>\u201cQuando l\u2019abbiamo incontrato aveva un sacchettino rosso pieno di caramelle in mano e si guardava intorno&#8230;ha incrociato i nostri occhi strasognanti e da quel momento <strong>e\u2019 iniziata la nostra vera vita.\u201d<\/strong><\/em><\/p>\n<p>Ne abbiamo parlato con la neo mamma:<\/p>\n<p><strong>Come \u00e8 andato il momento dell\u2019incontro?<\/strong><\/p>\n<p>Salendo le scale, siamo entrati in una grande stanza, illuminata dal sole delle 15.05 di fine inverno, arredata con grandi panchine di legno stile anni 70; l\u00ec abbiamo trovato\u00a0 le \u201ctate\u201d, ciascuna con un bimbo, sedute qua e l\u00e0 per la stanza; in tutto, abbiamo contato\u00a0 5 bimbi.<br \/>\nMa il primo che abbiamo visto, era lui. Era diverso dalla foto, ancora pi\u00f9 bello ancora pi\u00f9 dolce, ancora e ancora di pi\u00f9 \u2026.Aveva un sacchettino rosso pieno di caramelle in mano e si guardava intorno&#8230;ha incrociato i nostri occhi strasognanti e da quel momento e\u2019 iniziata la nostra vera vita.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>C\u2019 \u00e8 stato un episodio significativo che ricorda?<\/strong><\/p>\n<p>Prima di partire eravamo indecisi riguardo al nome: che fare?<br \/>\nAggiungere un nome italiano, lasciare prima il suo, alcuni lo hanno fatto, sembra che in Cina sia cosa gradita\u2026.ma prima quello cinese e poi quello italiano\u2026, lasciare solo quello cinese, ma poi che difficolt\u00e0 a scuola,\u00a0 i documenti\u2026<br \/>\nAll\u2019aeroporto di Malpensa, chiedendo informazioni sul nostro volo, ci \u201csfugge\u201d che torneremo con nostro figlio dalla Cina.<br \/>\nAlla hostess si illuminano gli occhi e ci confida che lei e\u2019 stata adottata e tra le poche e discrete domande, ci chiede quale nome daremo al nostro piccolo.<br \/>\nNoi rispondiamo che probabilmente lasceremo il suo, quello Cinese, e lei, con molta nostalgia, dice: \u201ca\u00a0 me lo hanno tolto, mi chiamavo Maddalena&#8230;\u201d<br \/>\nSeduti in aereo, abbiamo avuto la certezza: nostro figlio avrebbe avuto solo il suo nome che gi\u00e0 dalla nascita portava con s\u00e9\u2026meravigliosamente Zhijian.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Come \u00e8 andato il rientro?<\/strong><\/p>\n<p>Finalmente a casa, tutti e tre stravolti dal viaggio e soprattutto dalle mille e mille emozioni, \u00e8 stata una festa con le persone che hanno atteso e condiviso il suo arrivo. Ed ancora, a distanza di quasi un mese del rientro, squilla il telefono, suona il campanello, con tanti inviti e auguri di benvenuto per nostro figlio. C\u2019\u00e8 stata una accoglienza ricca di amore, con qualche lacrimuccia di felicit\u00e0 ed emozione, nel vedere\u00a0 il piccolo principe dagli occhi a mandorla..<br \/>\nA casa ogni giorno per noi e\u2019 festa\u2026essere finalmente una famiglia e\u2019 meraviglioso.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Se volesse lasciare un messaggio ai genitori che iniziano il cammino adottivo cosa direbbe?<\/strong><\/p>\n<p>Dicono che ogni momento di dolore, rabbia, paura, o solitudine vissuto durante l\u2019attesa scompaia non appena si incontrano gli occhi di proprio figlio. Dicono che, indipendentemente dall\u2019et\u00e0 del bimbo, sembra di conoscersi da sempre. Dicono poi che sono i bimbi ad adottare i genitori.<br \/>\nE dicono anche che l\u2019amore che si prova \u00e8 unico al mondo.<br \/>\nE\u2019 tutto vero. Parola di mamma e pap\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il piccolo Zhijian \u00e8 tornato pochi giorni fa dalla Cina con mamma Arianna e pap\u00e0 Igor. La sua storia di adozione \u00e8 unica e speciale. <em>\u201cQuando l\u2019abbiamo incontrato aveva un sacchettino rosso pieno di caramelle in mano e si guardava intorno&#8230;ha incrociato i nostri occhi strasognanti e da quel momento <\/em><strong><em>e\u2019 iniziata la nostra vera vita.\u201d<\/em> <a href=\"https:\/\/www.aibi.it\/ita\/cina-il-nome-meraviglioso-di-nostro-figlio\/\">LEGGI TUTTO&#8230;<\/a><\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-21525","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cina: il nome meraviglioso di nostro figlio - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/cina-il-nome-meraviglioso-di-nostro-figlio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cina: il nome meraviglioso di nostro figlio\" \/>\n<meta property=\"og:description\" content=\"Il piccolo Zhijian \u00e8 tornato pochi giorni fa dalla Cina con mamma Arianna e pap\u00e0 Igor. La sua storia di adozione \u00e8 unica e speciale. \u201cQuando l\u2019abbiamo incontrato aveva un sacchettino rosso pieno di caramelle in mano e si guardava intorno...ha incrociato i nostri occhi strasognanti e da quel momento e\u2019 iniziata la nostra vera vita.\u201d LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/cina-il-nome-meraviglioso-di-nostro-figlio\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-04-08T14:02:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-04-08T14:04:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/MONDO11.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-il-nome-meraviglioso-di-nostro-figlio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-il-nome-meraviglioso-di-nostro-figlio\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Cina: il nome meraviglioso di nostro figlio\",\"datePublished\":\"2011-04-08T14:02:38+00:00\",\"dateModified\":\"2011-04-08T14:04:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-il-nome-meraviglioso-di-nostro-figlio\\\/\"},\"wordCount\":500,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-il-nome-meraviglioso-di-nostro-figlio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/MONDO11.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-il-nome-meraviglioso-di-nostro-figlio\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-il-nome-meraviglioso-di-nostro-figlio\\\/\",\"name\":\"Cina: il nome meraviglioso di nostro figlio - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-il-nome-meraviglioso-di-nostro-figlio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-il-nome-meraviglioso-di-nostro-figlio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/MONDO11.jpg\",\"datePublished\":\"2011-04-08T14:02:38+00:00\",\"dateModified\":\"2011-04-08T14:04:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-il-nome-meraviglioso-di-nostro-figlio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-il-nome-meraviglioso-di-nostro-figlio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-il-nome-meraviglioso-di-nostro-figlio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/MONDO11.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/MONDO11.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-il-nome-meraviglioso-di-nostro-figlio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cina: il nome meraviglioso di nostro figlio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cina: il nome meraviglioso di nostro figlio - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/cina-il-nome-meraviglioso-di-nostro-figlio\/","og_locale":"it_IT","og_type":"article","og_title":"Cina: il nome meraviglioso di nostro figlio","og_description":"Il piccolo Zhijian \u00e8 tornato pochi giorni fa dalla Cina con mamma Arianna e pap\u00e0 Igor. La sua storia di adozione \u00e8 unica e speciale. \u201cQuando l\u2019abbiamo incontrato aveva un sacchettino rosso pieno di caramelle in mano e si guardava intorno...ha incrociato i nostri occhi strasognanti e da quel momento e\u2019 iniziata la nostra vera vita.\u201d LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/cina-il-nome-meraviglioso-di-nostro-figlio\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2011-04-08T14:02:38+00:00","article_modified_time":"2011-04-08T14:04:16+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/MONDO11.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/cina-il-nome-meraviglioso-di-nostro-figlio\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/cina-il-nome-meraviglioso-di-nostro-figlio\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Cina: il nome meraviglioso di nostro figlio","datePublished":"2011-04-08T14:02:38+00:00","dateModified":"2011-04-08T14:04:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/cina-il-nome-meraviglioso-di-nostro-figlio\/"},"wordCount":500,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/cina-il-nome-meraviglioso-di-nostro-figlio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/MONDO11.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/cina-il-nome-meraviglioso-di-nostro-figlio\/","url":"https:\/\/www.aibi.it\/ita\/cina-il-nome-meraviglioso-di-nostro-figlio\/","name":"Cina: il nome meraviglioso di nostro figlio - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/cina-il-nome-meraviglioso-di-nostro-figlio\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/cina-il-nome-meraviglioso-di-nostro-figlio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/MONDO11.jpg","datePublished":"2011-04-08T14:02:38+00:00","dateModified":"2011-04-08T14:04:16+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/cina-il-nome-meraviglioso-di-nostro-figlio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/cina-il-nome-meraviglioso-di-nostro-figlio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/cina-il-nome-meraviglioso-di-nostro-figlio\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/MONDO11.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/MONDO11.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/cina-il-nome-meraviglioso-di-nostro-figlio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Cina: il nome meraviglioso di nostro figlio"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 19:37:49","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/21525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=21525"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/21525\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=21525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=21525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=21525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}