﻿


{"id":216267,"date":"2023-09-24T07:55:16","date_gmt":"2023-09-24T05:55:16","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=216267"},"modified":"2023-09-20T20:28:20","modified_gmt":"2023-09-20T18:28:20","slug":"adozione-fillus-de-anima-tradizione-sarda-figli-anima-significato","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-fillus-de-anima-tradizione-sarda-figli-anima-significato\/","title":{"rendered":"Adozione. Fillus de anima: la tradizione sarda dei figli d&#8217;anima e il suo significato per l&#8217;adozione"},"content":{"rendered":"<h2>La pratica antica e moderna di affidare i bambini a una famiglia diversa da quella biologica ci insegna il valore dei legami al di l\u00e0 del sangue e dell&#8217;ascolto dei minori <!--more--><\/h2>\n<p>Parlando di adozione si utilizza spesso il termine <strong>rinascita<\/strong>: i bambini e le bambine, generati biologicamente da altre donne e altri uomini, nascono in una nuova famiglia; le madri e i padri, che diventano tali con l\u2019adozione, si ritrovano fecondi di una genitorialit\u00e0 che non immaginavano o non speravano pi\u00f9 di avere.<br \/>\nSi rinasce perch\u00e9 si nasce di nuovo, insieme, ricominciando da capo.<\/p>\n<h3>Il romanzo di Michela Murgia<\/h3>\n<p>Un tema, quello dei leg\u00e0mi al di l\u00e0 della linea di sangue, che \u00e8 riemerso sui media nelle ultime settimane di vita e dopo la morte della scrittrice sarda\u00a0<strong>Michela Murgia<\/strong>. Gi\u00e0 nei suoi romanzi si parlava dei figli d\u2019anima, fillus de anima, tradizione antica in Sardegna che ancora\u00a0oggi, saltuariamente, \u00e8 praticata a favore dei minori soli o a rischio di abbandono e di trascuratezza in una comunit\u00e0.<br \/>\nI figli d\u2019anima sono \u201ci bambini generati due volte, dalla povert\u00e0 di una donna e dalla sterilit\u00e0 di un\u2019altra.\u201d \u00c8 l\u2019incipit del romanzo\u00a0<strong><em>Accabadora<\/em><\/strong>\u00a0quando inizia la storia di \u201cMaria Listru, frutto tardivo dell\u2019anima di Bonaria Urrai\u201d.<br \/>\nE a questo punto, per chi si occupa di adozione o la vive in prima persona &#8211; che sia figlio, figlia o genitore &#8211; suona un campanello.<br \/>\nPer prima cosa i leg\u00e0mi di sangue: esistono, sono legittimi e importanti, ma non sono tutto, non sono fondamentali o imprescindibili di fronte all\u2019amore tra genitori e figli, di fronte alla scelta di volersi come madre padre figlio o figlia.<br \/>\nPensate a quando una coppia comunica in famiglia la volont\u00e0 di adottare: spesso i primi ad avere un sussulto sono i futuri nonni perch\u00e9 inconsciamente gi\u00e0 sanno che la linea familiare di sangue sar\u00e0 interrotta. \u00c8 qualcosa di ancestrale, il sangue, quasi l\u2019appartenenza al clan che\u00a0<strong>riemerge dopo millenni e generazioni<\/strong>.<br \/>\nPoi, tutto passa, svanisce: l\u2019amore per quei bambini, che prima dell\u2019incontro si conoscono nei\u00a0<strong>lunghi tempi vuoti dell\u2019attesa<\/strong>, ristabilisce un\u2019altra linea, un\u2019altra appartenenza. Altre viscere che anche madri e padri imparano a sentire, nel processo formativo di accompagnamento all\u2019adozione.<\/p>\n<h3>I nuovi legami<\/h3>\n<p>E quindi i nuovi leg\u00e0mi, quelli non regolati dal vincolo di sangue, hanno pari dignit\u00e0 rispetto a quelli biologici: come ha ricordato e ribadito in pi\u00f9 occasioni Murgia, la tradizione antica dei figli d\u2018anima appare moderna proprio nella nostra epoca in cui, per proteggere minori in difficolt\u00e0 familiare, si ricorre spesso alla soluzione della comunit\u00e0 o degli istituti &#8211; con alti costi sociali e impiego di risorse professionali &#8211; mentre le relazioni, le reti familiari, la comunit\u00e0 operano velocemente e con maggiore efficacia nell\u2019interesse dei minori. E ristabiliscono linee di appartenenza familiare che sembravano lacerate o interrotte.<\/p>\n<h3>Stiamo quindi parlando di un affido o di un\u2019adozione, con i fill\u2019e anima?<\/h3>\n<p>Essere figlio d\u2019 anima non necessita di una regolamentazione giuridica perch\u00e9 si basa e si regge sul consenso di tutti: genitori, figli, comunit\u00e0 in nome dell\u2019amore e della cura reciproca. Anche ai bambini viene chiesto di volerlo, se sono ragazzi spesso lo scelgono. Ci si affida reciprocamente: \u00e8 qualcosa che assomiglia all\u2019ascolto del minore nei casi di adozione, ma applicato per volont\u00e0 delle parti, non a discrezione del giudice o in casi particolari.<br \/>\nMurgia \u00e8 stata una di loro, una di quelle adolescenti affidata dai genitori biologici ad altri adulti della comunit\u00e0 con i quali esistevano gi\u00e0 dei rapporti. Poteva essere per un periodo limitato nel tempo a causa di una difficolt\u00e0 grave familiare o di una malattia.<br \/>\nMa i legami\u00a0 tra le persone &#8211; famiglia di origine e famiglia accogliente &#8211; restavano e restano per sempre, con la comunit\u00e0 intorno a sostenere questo intreccio di volont\u00e0 e di scelte per il benessere dei minori in difficolt\u00e0.<br \/>\nE laddove la disciplina giuridica non regolamenta, \u00e8 il concetto di co-genitorialit\u00e0 e di responsabilit\u00e0 reciproca su tutti i figli, tipico di molte societ\u00e0-villaggio, a vincere.<\/p>\n<h3>Superare i legami di sangue<\/h3>\n<p>I fillus de anima portano a\u00a0<strong>una riflessione utile nell\u2019adozione e nelle molte forme di accoglienza e protezione dei minori<\/strong>: mettiamoci dalla parte dei bambini, ascoltiamo il loro desiderio di essere accolti e di crescere in famiglia, anche in famiglie molto larghe, capaci di accompagnarli nella vita.<br \/>\nRispetto all\u2019adozione, tutto questo conferma come\u00a0<strong>l\u2019accoglienza pi\u00f9 piena, reciproca, tra genitori e figli \u00e8 capace di creare legami nuovi, eterni<\/strong>, superando non solo il legame di sangue ma anche quell\u2019abbandono che, per ragioni diverse, entrambe le parti hanno conosciuto e vissuto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pratica antica e moderna di affidare i bambini a una famiglia diversa da quella biologica ci insegna il valore dei legami al di l&agrave; del sangue e dell&rsquo;ascolto dei minori<\/p>\n","protected":false},"author":133,"featured_media":216268,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[279],"class_list":["post-216267","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale","tag-adozione"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fillus de anima: la tradizione sarda e il significato per l&#039;adozione<\/title>\n<meta name=\"description\" content=\"La pratica antica e moderna di affidare i bambini a una famiglia diversa da quella biologica ci insegna il valore dei legami al di l\u00e0 del sangue e dell&#039;ascolto dei minori\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-fillus-de-anima-tradizione-sarda-figli-anima-significato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione. Fillus de anima: la tradizione sarda dei figli d&#039;anima e il suo significato per l&#039;adozione\" \/>\n<meta property=\"og:description\" content=\"La pratica antica e moderna di affidare i bambini a una famiglia diversa da quella biologica ci insegna il valore dei legami al di l\u00e0 del sangue e dell&#039;ascolto dei minori\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-fillus-de-anima-tradizione-sarda-figli-anima-significato\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-24T05:55:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2023\/09\/Fillus-de-anima.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-fillus-de-anima-tradizione-sarda-figli-anima-significato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-fillus-de-anima-tradizione-sarda-figli-anima-significato\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Adozione. Fillus de anima: la tradizione sarda dei figli d&#8217;anima e il suo significato per l&#8217;adozione\",\"datePublished\":\"2023-09-24T05:55:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-fillus-de-anima-tradizione-sarda-figli-anima-significato\\\/\"},\"wordCount\":791,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-fillus-de-anima-tradizione-sarda-figli-anima-significato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/09\\\/Fillus-de-anima.jpg\",\"keywords\":[\"adozione\"],\"articleSection\":[\"Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-fillus-de-anima-tradizione-sarda-figli-anima-significato\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-fillus-de-anima-tradizione-sarda-figli-anima-significato\\\/\",\"name\":\"Fillus de anima: la tradizione sarda e il significato per l'adozione\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-fillus-de-anima-tradizione-sarda-figli-anima-significato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-fillus-de-anima-tradizione-sarda-figli-anima-significato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/09\\\/Fillus-de-anima.jpg\",\"datePublished\":\"2023-09-24T05:55:16+00:00\",\"description\":\"La pratica antica e moderna di affidare i bambini a una famiglia diversa da quella biologica ci insegna il valore dei legami al di l\u00e0 del sangue e dell'ascolto dei minori\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-fillus-de-anima-tradizione-sarda-figli-anima-significato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-fillus-de-anima-tradizione-sarda-figli-anima-significato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-fillus-de-anima-tradizione-sarda-figli-anima-significato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/09\\\/Fillus-de-anima.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/09\\\/Fillus-de-anima.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-fillus-de-anima-tradizione-sarda-figli-anima-significato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione. Fillus de anima: la tradizione sarda dei figli d&#8217;anima e il suo significato per l&#8217;adozione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fillus de anima: la tradizione sarda e il significato per l'adozione","description":"La pratica antica e moderna di affidare i bambini a una famiglia diversa da quella biologica ci insegna il valore dei legami al di l\u00e0 del sangue e dell'ascolto dei minori","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-fillus-de-anima-tradizione-sarda-figli-anima-significato\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione. Fillus de anima: la tradizione sarda dei figli d'anima e il suo significato per l'adozione","og_description":"La pratica antica e moderna di affidare i bambini a una famiglia diversa da quella biologica ci insegna il valore dei legami al di l\u00e0 del sangue e dell'ascolto dei minori","og_url":"https:\/\/www.aibi.it\/ita\/adozione-fillus-de-anima-tradizione-sarda-figli-anima-significato\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2023-09-24T05:55:16+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2023\/09\/Fillus-de-anima.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-fillus-de-anima-tradizione-sarda-figli-anima-significato\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-fillus-de-anima-tradizione-sarda-figli-anima-significato\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Adozione. Fillus de anima: la tradizione sarda dei figli d&#8217;anima e il suo significato per l&#8217;adozione","datePublished":"2023-09-24T05:55:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-fillus-de-anima-tradizione-sarda-figli-anima-significato\/"},"wordCount":791,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-fillus-de-anima-tradizione-sarda-figli-anima-significato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/09\/Fillus-de-anima.jpg","keywords":["adozione"],"articleSection":["Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-fillus-de-anima-tradizione-sarda-figli-anima-significato\/","url":"https:\/\/www.aibi.it\/ita\/adozione-fillus-de-anima-tradizione-sarda-figli-anima-significato\/","name":"Fillus de anima: la tradizione sarda e il significato per l'adozione","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-fillus-de-anima-tradizione-sarda-figli-anima-significato\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-fillus-de-anima-tradizione-sarda-figli-anima-significato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/09\/Fillus-de-anima.jpg","datePublished":"2023-09-24T05:55:16+00:00","description":"La pratica antica e moderna di affidare i bambini a una famiglia diversa da quella biologica ci insegna il valore dei legami al di l\u00e0 del sangue e dell'ascolto dei minori","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-fillus-de-anima-tradizione-sarda-figli-anima-significato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-fillus-de-anima-tradizione-sarda-figli-anima-significato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-fillus-de-anima-tradizione-sarda-figli-anima-significato\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2023\/09\/Fillus-de-anima.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/09\/Fillus-de-anima.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-fillus-de-anima-tradizione-sarda-figli-anima-significato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Adozione. Fillus de anima: la tradizione sarda dei figli d&#8217;anima e il suo significato per l&#8217;adozione"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:27:30","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/216267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=216267"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/216267\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/216268"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=216267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=216267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=216267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}