﻿


{"id":216309,"date":"2023-09-22T12:54:40","date_gmt":"2023-09-22T10:54:40","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=216309"},"modified":"2026-01-14T16:50:22","modified_gmt":"2026-01-14T15:50:22","slug":"adozione-internazionale-sudamerica-anisa","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anisa\/","title":{"rendered":"Adozione Internazionale in Sudamerica. Anisa, 14 anni, cerca due genitori la cui generosit\u00e0 vada oltre la sua et\u00e0"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row el_class=&#8221;wpz-sc-box normal&#8221;][vc_column][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;216311&#8243; img_size=&#8221;large&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_message icon_fontawesome=&#8221;fas fa-calendar&#8221;]Scheda inserita il: 22\/09\/2023[\/vc_message][vc_message icon_fontawesome=&#8221;fas fa-birthday-cake&#8221;]Anno di nascita: 2009[\/vc_message][vc_message icon_fontawesome=&#8221;fas fa-globe-americas&#8221;]Provenienza: Sud America[\/vc_message][vc_message icon_fontawesome=&#8221;fas fa-heart&#8221;]nessuna patologia evidente[\/vc_message][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][\/vc_row][vc_column][\/vc_column][vc_column_text]<strong>Anisa <\/strong>\u00e8 una ragazzina sudamericana di 14 anni che si trova in affido familiare, dopo che il processo di protezione e recupero della famiglia nucleare ed estesa, negligente e disfunzionale, non ha avuto gli esiti sperati.<br \/>\nAnisa \u00e8 <strong>una bella ragazza, con un dolce sorriso<\/strong>, collaborativa in casa, tranquilla e rispettosa. Da quando \u00e8 stata collocata in affido ha fatto un percorso di crescita, con progressi in tutte le aree di sviluppo e oggi si mostra emotivamente stabile.<br \/>\nAttualmente frequenta la settima classe (2\u00b0 media) ed \u00e8 quindi leggermente in ritardo rispetto al corso di studi classico. Il suo impegno scolastico \u00e8 molto buono, cos\u00ec come il suo comportamento; ha una <strong>spiccata vena artistica<\/strong>, tant\u2019\u00e8 che un suo disegno \u00e8 stato selezionato per un concorso (di cui ancora non si conosce il risultato).<br \/>\nNel futuro vorrebbe continuare a studiare e da grande si figura come psicologa specializzata nell\u2019infanzia.<br \/>\n\u00c8 perfettamente cosciente che la famiglia in cui si trova \u00e8 temporanea e per lei adozione si<strong>gnifica entrare in una famiglia unita, allegra, amorevole<\/strong> e che possa offrirle orientamento nella crescita. Preferirebbe essere l\u2019unica figlia.<br \/>\nSperiamo che due genitori, leggendo la storia di Anisa, decidano di aprirle le braccia e il cuore, accogliendola come figlia, andando oltre l\u2019et\u00e0 anagrafica e rendendosi disponibili ad accompagnarla con amore nella crescita e nel raggiungimento dei suoi obiettivi.<\/p>\n<p>In associazione sono disponibili foto e video della bambina.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p><strong>Anisa<\/strong><\/p>\n<ul>\n<li><strong>Anno di Nascita: <\/strong>2009<\/li>\n<li><strong>Provenienza: <\/strong>Sud America<\/li>\n<li><strong>Nessuna patologia evidente<\/strong><\/li>\n<\/ul>\n","protected":false},"author":102,"featured_media":216311,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[89],"tags":[],"class_list":["post-216309","post","type-post","status-publish","format-standard","has-post-thumbnail","category-appelli-adozioni-internazionali-concluse"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione Internazionale in Sudamerica. Anisa, 14 anni<\/title>\n<meta name=\"description\" content=\"Adozione Internazionale Sudamerica. Anisa, 14 anni, cerca due genitori che la accolgano come figlia e la cui generosit\u00e0 sappia guardare oltre la sua et\u00e0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anisa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione Internazionale in Sudamerica. Anisa, 14 anni, cerca due genitori la cui generosit\u00e0 vada oltre la sua et\u00e0\" \/>\n<meta property=\"og:description\" content=\"Adozione Internazionale. Dylan, 10 anni, dal sud America non vede l&#039;ora ti abbracciare la sua mamma e il suo pap\u00e0!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anisa\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-22T10:54:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-14T15:50:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2023\/09\/appello-adozione-internazionale-Anisa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sudamerica-anisa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sudamerica-anisa\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Adozione Internazionale in Sudamerica. Anisa, 14 anni, cerca due genitori la cui generosit\u00e0 vada oltre la sua et\u00e0\",\"datePublished\":\"2023-09-22T10:54:40+00:00\",\"dateModified\":\"2026-01-14T15:50:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sudamerica-anisa\\\/\"},\"wordCount\":335,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sudamerica-anisa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/09\\\/appello-adozione-internazionale-Anisa.jpg\",\"articleSection\":[\"Adozioni Realizzate\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sudamerica-anisa\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sudamerica-anisa\\\/\",\"name\":\"Adozione Internazionale in Sudamerica. Anisa, 14 anni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sudamerica-anisa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sudamerica-anisa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/09\\\/appello-adozione-internazionale-Anisa.jpg\",\"datePublished\":\"2023-09-22T10:54:40+00:00\",\"dateModified\":\"2026-01-14T15:50:22+00:00\",\"description\":\"Adozione Internazionale Sudamerica. Anisa, 14 anni, cerca due genitori che la accolgano come figlia e la cui generosit\u00e0 sappia guardare oltre la sua et\u00e0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sudamerica-anisa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sudamerica-anisa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sudamerica-anisa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/09\\\/appello-adozione-internazionale-Anisa.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/09\\\/appello-adozione-internazionale-Anisa.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sudamerica-anisa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozioni Realizzate\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/appelli-adozioni-internazionali-concluse\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione Internazionale in Sudamerica. Anisa, 14 anni, cerca due genitori la cui generosit\u00e0 vada oltre la sua et\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione Internazionale in Sudamerica. Anisa, 14 anni","description":"Adozione Internazionale Sudamerica. Anisa, 14 anni, cerca due genitori che la accolgano come figlia e la cui generosit\u00e0 sappia guardare oltre la sua et\u00e0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anisa\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione Internazionale in Sudamerica. Anisa, 14 anni, cerca due genitori la cui generosit\u00e0 vada oltre la sua et\u00e0","og_description":"Adozione Internazionale. Dylan, 10 anni, dal sud America non vede l'ora ti abbracciare la sua mamma e il suo pap\u00e0!","og_url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anisa\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2023-09-22T10:54:40+00:00","article_modified_time":"2026-01-14T15:50:22+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2023\/09\/appello-adozione-internazionale-Anisa.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anisa\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anisa\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Adozione Internazionale in Sudamerica. Anisa, 14 anni, cerca due genitori la cui generosit\u00e0 vada oltre la sua et\u00e0","datePublished":"2023-09-22T10:54:40+00:00","dateModified":"2026-01-14T15:50:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anisa\/"},"wordCount":335,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anisa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/09\/appello-adozione-internazionale-Anisa.jpg","articleSection":["Adozioni Realizzate"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anisa\/","url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anisa\/","name":"Adozione Internazionale in Sudamerica. Anisa, 14 anni","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anisa\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anisa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/09\/appello-adozione-internazionale-Anisa.jpg","datePublished":"2023-09-22T10:54:40+00:00","dateModified":"2026-01-14T15:50:22+00:00","description":"Adozione Internazionale Sudamerica. Anisa, 14 anni, cerca due genitori che la accolgano come figlia e la cui generosit\u00e0 sappia guardare oltre la sua et\u00e0","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anisa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anisa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anisa\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2023\/09\/appello-adozione-internazionale-Anisa.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/09\/appello-adozione-internazionale-Anisa.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anisa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozioni Realizzate","item":"https:\/\/www.aibi.it\/ita\/category\/appelli-adozioni-internazionali-concluse\/"},{"@type":"ListItem","position":3,"name":"Adozione Internazionale in Sudamerica. Anisa, 14 anni, cerca due genitori la cui generosit\u00e0 vada oltre la sua et\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 06:50:20","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/216309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=216309"}],"version-history":[{"count":2,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/216309\/revisions"}],"predecessor-version":[{"id":235289,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/216309\/revisions\/235289"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/216311"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=216309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=216309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=216309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}