﻿


{"id":216809,"date":"2023-10-11T07:40:21","date_gmt":"2023-10-11T05:40:21","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=216809"},"modified":"2023-10-11T14:22:32","modified_gmt":"2023-10-11T12:22:32","slug":"ghana-festa-partenariato-ai-bi-royal-seed-home","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/ghana-festa-partenariato-ai-bi-royal-seed-home\/","title":{"rendered":"Ghana. Una grande festa per celebrare il partenariato tra\u00a0Ai.Bi.\u00a0e il centro Royal\u00a0Seed Home"},"content":{"rendered":"<h2>Una giornata di gioia e condivisione per i bambini accolti nell\u2019orfanotrofio del Royal Seed Home che \u00e8 stata anche l&#8217;occasione per mostrare le attivit\u00e0 organizzate dal centro grazie al sostegno dell\u2019Adozione a Distanza<!--more--><\/h2>\n<p><strong>Gioved\u00ec 7 settembre<\/strong> lo staff di\u00a0<strong>Ai.Bi.<\/strong>\u00a0e quello dell\u2019orfanotrofio <strong>Royal Seed Home<\/strong> in Ghana hanno organizzato una giornata per celebrare il <strong>partenariato tra\u00a0le due realt\u00e0.<\/strong><\/p>\n<h3>Il video per il concerto di raccolta fondi<\/h3>\n<p>Nell\u2019occasione \u00e8 stato girato un video che sar\u00e0 proiettato durante l\u2019evento di raccolta fondi <a href=\"https:\/\/www.aibi.it\/ita\/salerno-concerto-solidarieta-bambini-ghana\/\">Concerto di solidariet\u00e0<\/a>, che si terr\u00e0 sabato 14 ottobre presso la chiesa di San Giorgio di Salerno, il cui ricavato sar\u00e0 destinato proprio ai bambini del centro, in particolare a quelli con esigenze mediche.<\/p>\n<h3>La partecipazione alla celebrazione<\/h3>\n<p>Oltre allo staff di\u00a0Ai.Bi.\u00a0e del Royal Seed Home, ha partecipato anche il <strong>Direttore distrettuale del Dipartimento del Social Welfare<\/strong>, che si \u00e8 congratulato con\u00a0Ai.Bi.\u00a0per il supporto fornito al centro e al suo ufficio.<\/p>\n<h3>Le attivit\u00e0 del centro<\/h3>\n<p>Durante la festa, lo staff del centro\u00a0ha potuto mostrare tutte le attivit\u00e0 svolte:\u00a0 la\u00a0banda musicale, il gruppo dei cadetti, il gruppo di danza tradizionale, il calcio e il pugilato.<br \/>\nIl centro, infatti, offre a tutti i bambini\u00a0la possibilit\u00e0 di praticare un\u2019attivit\u00e0 che possa\u00a0contribuire alla loro crescita e che possano sfruttare in futuro.<\/p>\n<h3>La visita alla scuola<\/h3>\n<p>Durante l\u2019iniziativa si \u00e8 tenuta <strong>una visita alle scuole<\/strong> e i partecipanti hanno assistito <strong>a una lezione della lingua dei segni<\/strong> che l\u2019insegnante specializzata stava tenendo per i bambini con bisogni speciali.<\/p>\n<h3>Un momento conviviale per i bambini del centro<\/h3>\n<p>Grazie al sostegno garantito dall\u2019Adozione a Distanza ad Ai.Bi., \u00e8\u00a0stato quindi organizzato un momento conviviale con tutti i bambini del centro e quelli della scuola gestita dal centro, frequentata da molti minori vulnerabili che\u00a0spesso\u00a0beneficiano di un pasto al Royal Seed Home.<br \/>\nNella giornata si \u00e8 respirato un <strong>clima di collaborazione<\/strong> e gratitudine per il supporto che\u00a0Ai.Bi.\u00a0sta fornendo all\u2019orfanotrofio attraverso il progetto <strong>Care for Ghana<\/strong>, finanziato dalla <strong>Provincia di Bolzano<\/strong>.<br \/>\nAllo stesso tempo, lo staff del <strong>Royal Seed Home<\/strong> ha espresso molta fiducia nel risultato della raccolta fondi che sar\u00e0 realizzata ad ottobre, ringraziando\u00a0Ai.Bi. e l\u2019associazione\u00a0<strong>Agape Fraterna<\/strong>, per aver organizzato il <strong>Concerto<\/strong> <strong>di solidariet\u00e0<\/strong>.<\/p>\n<h3>L&#8217;Adozione a Distanza in Ghana<\/h3>\n<p>Anche tu puoi aiutare tanti minori abbandonati, decidendo di aderire al progetto di Ai.Bi. \u201c<a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/?paese=Ghana\"><strong>Adotta a Distanza i bambini di un orfanotrofio in Ghana<\/strong><\/a>\u201d, bastano 82 centesimi al giorno.<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/?paese=Ghana\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn btnsx-btn-embossed\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Adotta a Distanza ORA<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n<p>Per richiedere informazioni sull\u2019Adozione a Distanza <a href=\"#infosad\">clicca qui<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una giornata di gioia e condivisione per i bambini accolti nell&rsquo;orfanotrofio del Royal Seed Home che &egrave; stata anche l&rsquo;occasione per mostrare le attivit&agrave; organizzate dal centro grazie al sostegno dell&rsquo;Adozione a Distanza<\/p>\n","protected":false},"author":133,"featured_media":216810,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209],"tags":[1012],"class_list":["post-216809","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-a-distanza","tag-royal-seed-home"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ghana. Una festa per celebrare il partenariato tra\u00a0Ai.Bi.\u00a0e il Royal\u00a0Seed Home<\/title>\n<meta name=\"description\" content=\"Una giornata di gioia e condivisione per i bambini accolti nell\u2019orfanotrofio del Royal Seed Home che \u00e8 stata anche l&#039;occasione per mostrare le attivit\u00e0 organizzate dal centro grazie al sostegno dell\u2019Adozione a Distanza\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/ghana-festa-partenariato-ai-bi-royal-seed-home\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ghana. Una grande festa per celebrare il partenariato tra\u00a0Ai.Bi.\u00a0e il centro Royal\u00a0Seed Home\" \/>\n<meta property=\"og:description\" content=\"Una giornata di gioia e condivisione per i bambini accolti nell\u2019orfanotrofio del Royal Seed Home che \u00e8 stata anche l&#039;occasione per mostrare le attivit\u00e0 organizzate dal centro grazie al sostegno dell\u2019Adozione a Distanza\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/ghana-festa-partenariato-ai-bi-royal-seed-home\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-11T05:40:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-11T12:22:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2023\/10\/Ghana-Royal-Seed-Home-festa.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-festa-partenariato-ai-bi-royal-seed-home\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-festa-partenariato-ai-bi-royal-seed-home\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Ghana. Una grande festa per celebrare il partenariato tra\u00a0Ai.Bi.\u00a0e il centro Royal\u00a0Seed Home\",\"datePublished\":\"2023-10-11T05:40:21+00:00\",\"dateModified\":\"2023-10-11T12:22:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-festa-partenariato-ai-bi-royal-seed-home\\\/\"},\"wordCount\":456,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-festa-partenariato-ai-bi-royal-seed-home\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/10\\\/Ghana-Royal-Seed-Home-festa.jpeg\",\"keywords\":[\"Royal Seed Home\"],\"articleSection\":[\"Adozione a Distanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-festa-partenariato-ai-bi-royal-seed-home\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-festa-partenariato-ai-bi-royal-seed-home\\\/\",\"name\":\"Ghana. Una festa per celebrare il partenariato tra\u00a0Ai.Bi.\u00a0e il Royal\u00a0Seed Home\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-festa-partenariato-ai-bi-royal-seed-home\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-festa-partenariato-ai-bi-royal-seed-home\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/10\\\/Ghana-Royal-Seed-Home-festa.jpeg\",\"datePublished\":\"2023-10-11T05:40:21+00:00\",\"dateModified\":\"2023-10-11T12:22:32+00:00\",\"description\":\"Una giornata di gioia e condivisione per i bambini accolti nell\u2019orfanotrofio del Royal Seed Home che \u00e8 stata anche l'occasione per mostrare le attivit\u00e0 organizzate dal centro grazie al sostegno dell\u2019Adozione a Distanza\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-festa-partenariato-ai-bi-royal-seed-home\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-festa-partenariato-ai-bi-royal-seed-home\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-festa-partenariato-ai-bi-royal-seed-home\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/10\\\/Ghana-Royal-Seed-Home-festa.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/10\\\/Ghana-Royal-Seed-Home-festa.jpeg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-festa-partenariato-ai-bi-royal-seed-home\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione a Distanza\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-a-distanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ghana. Una grande festa per celebrare il partenariato tra\u00a0Ai.Bi.\u00a0e il centro Royal\u00a0Seed Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ghana. Una festa per celebrare il partenariato tra\u00a0Ai.Bi.\u00a0e il Royal\u00a0Seed Home","description":"Una giornata di gioia e condivisione per i bambini accolti nell\u2019orfanotrofio del Royal Seed Home che \u00e8 stata anche l'occasione per mostrare le attivit\u00e0 organizzate dal centro grazie al sostegno dell\u2019Adozione a Distanza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/ghana-festa-partenariato-ai-bi-royal-seed-home\/","og_locale":"it_IT","og_type":"article","og_title":"Ghana. Una grande festa per celebrare il partenariato tra\u00a0Ai.Bi.\u00a0e il centro Royal\u00a0Seed Home","og_description":"Una giornata di gioia e condivisione per i bambini accolti nell\u2019orfanotrofio del Royal Seed Home che \u00e8 stata anche l'occasione per mostrare le attivit\u00e0 organizzate dal centro grazie al sostegno dell\u2019Adozione a Distanza","og_url":"https:\/\/www.aibi.it\/ita\/ghana-festa-partenariato-ai-bi-royal-seed-home\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2023-10-11T05:40:21+00:00","article_modified_time":"2023-10-11T12:22:32+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/www.aibi.it\/ita\/images\/2023\/10\/Ghana-Royal-Seed-Home-festa.jpeg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/ghana-festa-partenariato-ai-bi-royal-seed-home\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-festa-partenariato-ai-bi-royal-seed-home\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Ghana. Una grande festa per celebrare il partenariato tra\u00a0Ai.Bi.\u00a0e il centro Royal\u00a0Seed Home","datePublished":"2023-10-11T05:40:21+00:00","dateModified":"2023-10-11T12:22:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-festa-partenariato-ai-bi-royal-seed-home\/"},"wordCount":456,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-festa-partenariato-ai-bi-royal-seed-home\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/10\/Ghana-Royal-Seed-Home-festa.jpeg","keywords":["Royal Seed Home"],"articleSection":["Adozione a Distanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/ghana-festa-partenariato-ai-bi-royal-seed-home\/","url":"https:\/\/www.aibi.it\/ita\/ghana-festa-partenariato-ai-bi-royal-seed-home\/","name":"Ghana. Una festa per celebrare il partenariato tra\u00a0Ai.Bi.\u00a0e il Royal\u00a0Seed Home","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-festa-partenariato-ai-bi-royal-seed-home\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-festa-partenariato-ai-bi-royal-seed-home\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/10\/Ghana-Royal-Seed-Home-festa.jpeg","datePublished":"2023-10-11T05:40:21+00:00","dateModified":"2023-10-11T12:22:32+00:00","description":"Una giornata di gioia e condivisione per i bambini accolti nell\u2019orfanotrofio del Royal Seed Home che \u00e8 stata anche l'occasione per mostrare le attivit\u00e0 organizzate dal centro grazie al sostegno dell\u2019Adozione a Distanza","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-festa-partenariato-ai-bi-royal-seed-home\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/ghana-festa-partenariato-ai-bi-royal-seed-home\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/ghana-festa-partenariato-ai-bi-royal-seed-home\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2023\/10\/Ghana-Royal-Seed-Home-festa.jpeg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/10\/Ghana-Royal-Seed-Home-festa.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/ghana-festa-partenariato-ai-bi-royal-seed-home\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione a Distanza","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-a-distanza\/"},{"@type":"ListItem","position":3,"name":"Ghana. Una grande festa per celebrare il partenariato tra\u00a0Ai.Bi.\u00a0e il centro Royal\u00a0Seed Home"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 09:25:41","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/216809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=216809"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/216809\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/216810"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=216809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=216809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=216809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}