﻿{"id":21697,"date":"2011-04-15T14:08:54","date_gmt":"2011-04-15T13:08:54","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=21697"},"modified":"2011-04-15T14:10:05","modified_gmt":"2011-04-15T13:10:05","slug":"moldova-storia-a-lieto-fine","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/moldova-storia-a-lieto-fine\/","title":{"rendered":"Moldova: storia a lieto fine"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/bambini-in-cerchio3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-21700\" style=\"margin: 5px;\" title=\"bambini in cerchio\" src=\"https:\/\/www.aibi.it\/ita\/images\/bambini-in-cerchio3.jpg\" alt=\"\" width=\"100\" height=\"100\" \/><\/a>Riceviamo e volentieri pubblichiamo la testimonianza di una nostra collaboratrice in Moldova.\u00a0<\/p>\n<p><strong>L\u2019arrivo di un bambino in famiglia \u00e8 un dono di Dio<\/strong>, un motivo di gioia che dovrebbe durare\u00a0nel tempo, nonostante le difficolt\u00e0 che, con gli anni, appaiono nella famiglia.<\/p>\n<p>Purtroppo, <strong>la povert\u00e0 e la trascuratezza da parte degli adulti sono i principali motivi per i quali i piccoli finiscono in istituto<\/strong>, essendo affidati alla cura dello Stato.<\/p>\n<p>\u00c8 quasi un anno da quando siamo entrati in una delle istituzioni statali a regime residenziale, che \u00e8 l\u2019Istituto no.3. In questo periodo abbiamo sentito e conosciuto tantissime storie anche se non sempre a lieto fine, sicuramente impressionanti e toccanti talmente da voler coinvolgerci e dare il meglio di noi per far s\u00ec che un giorno si possa dire di aver \u201ccreato\u201d per loro, <strong>un lieto fine.<\/strong><\/p>\n<p><strong>Lo vogliamo fare anche nel caso di Vlad, Andrei e Olga<\/strong>. Sono tre fratelli che ci hanno impressionati da subito per il loro modo di essere e per la forza che hanno dentro di se.<\/p>\n<p>I bambini sono stati portati in istituto dalla nonna, troppo malata per poter prendersi cura dei nipoti che sono stati abbandonati dal padre e trascurati dalla madre, che aveva trovato rifugio nell\u2019alcool.<\/p>\n<p><strong>Le uniche persone di riferimento per loro sono la nonna, che li accoglie ogni fine settimana, quando i piccoli tornano a casa e la bisnonna<\/strong> che, nonostante i problemi di salute ha deciso di lavorare in istituto come bidella, per rimanere accanto ai bambini ed assicurarsi che non gli mancasse niente.<\/p>\n<p>Per questo, i nipoti le sono molto grati, cercano di essere bravi a scuola e uniti tra di loro. <strong>Il pi\u00f9 piccolo \u00e8 un leader nella sua classe.<\/strong> Si impegna volentieri in tutte le attivit\u00e0 e gi\u00e0 da piccolo dimostra un interesse particolare per il calcio. Gli altri fratelli, insieme alla bisnonna, fanno i tifosi quando nella scuola si organizzano partite di calcio ed anche se non vince sempre la squadra di Vlad, non mancano mai quei brevi momenti di gloria, perch\u00e9 si sta insieme. Ci fa piacere vederli tutti e tre intorno alla bisnonna che \u00e8 diventata come una madre per questi bambini. Li prepara per i momenti festivi, gli sta accanto quando hanno bisogno di sostegno e da loro il bacio di buonanotte.<\/p>\n<p><strong>Recentemente Vlad ha festeggiato il suo undicesimo compleanno. Neanche quest\u2019anno ha avuto accanto tutta la sua famiglia, ma grazie alla bisnonna \u00e8 stato veramente un giorno speciale.<\/strong> La signora gli ha organizzato una bella festa in istituto che \u00e8 culminata con la consegna dei regali, tra i quali un pallone di calcio vero e proprio.<\/p>\n<p>\u00c8 ancora presto parlare di una reintegrazione familiare nel caso di questi fratelli, per\u00f2 sapendo che possiamo contare almeno su una persona che vuole molto bene ai bambini, <strong>gi\u00e0 si pu\u00f2 pensare ad una preparazione scolastica e professionale, per quando i ragazzi dovranno lasciare l\u2019istituto.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>L\u2019arrivo di un bambino in famiglia \u00e8 un dono di Dio<\/strong>, un motivo di gioia che dovrebbe durare\u00a0nel tempo, nonostante le difficolt\u00e0 che, con gli anni, appaiono nella famiglia. Riceviamo e volentieri pubblichiamo la testimonianza di una nostra collaboratrice in Moldova. <strong><a href=\"https:\/\/www.aibi.it\/ita\/moldova-storia-a-lieto-fine\/\">LEGGI TUTTO&#8230;<\/a><\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-21697","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Moldova: storia a lieto fine - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/moldova-storia-a-lieto-fine\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Moldova: storia a lieto fine\" \/>\n<meta property=\"og:description\" content=\"L\u2019arrivo di un bambino in famiglia \u00e8 un dono di Dio, un motivo di gioia che dovrebbe durare\u00a0nel tempo, nonostante le difficolt\u00e0 che, con gli anni, appaiono nella famiglia. Riceviamo e volentieri pubblichiamo la testimonianza di una nostra collaboratrice in Moldova. LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/moldova-storia-a-lieto-fine\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-04-15T13:08:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-04-15T13:10:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/bambini-in-cerchio3.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-storia-a-lieto-fine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-storia-a-lieto-fine\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Moldova: storia a lieto fine\",\"datePublished\":\"2011-04-15T13:08:54+00:00\",\"dateModified\":\"2011-04-15T13:10:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-storia-a-lieto-fine\\\/\"},\"wordCount\":482,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-storia-a-lieto-fine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bambini-in-cerchio3.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-storia-a-lieto-fine\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-storia-a-lieto-fine\\\/\",\"name\":\"Moldova: storia a lieto fine - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-storia-a-lieto-fine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-storia-a-lieto-fine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bambini-in-cerchio3.jpg\",\"datePublished\":\"2011-04-15T13:08:54+00:00\",\"dateModified\":\"2011-04-15T13:10:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-storia-a-lieto-fine\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-storia-a-lieto-fine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-storia-a-lieto-fine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bambini-in-cerchio3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bambini-in-cerchio3.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-storia-a-lieto-fine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Moldova: storia a lieto fine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Moldova: storia a lieto fine - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/moldova-storia-a-lieto-fine\/","og_locale":"it_IT","og_type":"article","og_title":"Moldova: storia a lieto fine","og_description":"L\u2019arrivo di un bambino in famiglia \u00e8 un dono di Dio, un motivo di gioia che dovrebbe durare\u00a0nel tempo, nonostante le difficolt\u00e0 che, con gli anni, appaiono nella famiglia. Riceviamo e volentieri pubblichiamo la testimonianza di una nostra collaboratrice in Moldova. LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/moldova-storia-a-lieto-fine\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2011-04-15T13:08:54+00:00","article_modified_time":"2011-04-15T13:10:05+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/bambini-in-cerchio3.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/moldova-storia-a-lieto-fine\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/moldova-storia-a-lieto-fine\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Moldova: storia a lieto fine","datePublished":"2011-04-15T13:08:54+00:00","dateModified":"2011-04-15T13:10:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/moldova-storia-a-lieto-fine\/"},"wordCount":482,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/moldova-storia-a-lieto-fine\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/bambini-in-cerchio3.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/moldova-storia-a-lieto-fine\/","url":"https:\/\/www.aibi.it\/ita\/moldova-storia-a-lieto-fine\/","name":"Moldova: storia a lieto fine - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/moldova-storia-a-lieto-fine\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/moldova-storia-a-lieto-fine\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/bambini-in-cerchio3.jpg","datePublished":"2011-04-15T13:08:54+00:00","dateModified":"2011-04-15T13:10:05+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/moldova-storia-a-lieto-fine\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/moldova-storia-a-lieto-fine\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/moldova-storia-a-lieto-fine\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/bambini-in-cerchio3.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/bambini-in-cerchio3.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/moldova-storia-a-lieto-fine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Moldova: storia a lieto fine"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 18:08:48","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/21697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=21697"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/21697\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=21697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=21697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=21697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}