﻿


{"id":217228,"date":"2023-10-30T07:40:58","date_gmt":"2023-10-30T06:40:58","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=217228"},"modified":"2023-10-30T10:47:56","modified_gmt":"2023-10-30T09:47:56","slug":"adozione-voce-bambini-abbandonati-aspettano-famiglia-incontro-online","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-voce-bambini-abbandonati-aspettano-famiglia-incontro-online\/","title":{"rendered":"Adozione. La voce dei bambini abbandonati che aspettano una famiglia. L\u2019incontro online"},"content":{"rendered":"<h2>Mercoled\u00ec 8 novembre alle ore 21, Faris, il centro di formazione di Ai.Bi., ha organizzato un webinar che ha l\u2019obiettivo di dare voce a quei bambini che attendono di diventare figli. Ecco i dettagli<!--more--><\/h2>\n<p>Al fine di <strong>dare voce a tanti bambini abbandonati<\/strong>,\u00a0nel rispetto della loro privacy,\u00a0e allo stesso tempo di\u00a0<strong>accompagnare gli aspiranti genitori adottivi a scoprire se possono diventare la loro famiglia<\/strong>, <strong>FARIS \u2013 Family Relationship International School<\/strong> ha organizzato il webinar <strong>Vieni a conoscere i bambini abbandonati in attesa di famiglia<\/strong>. L\u2019appuntamento \u00e8 per <strong>mercoled\u00ec 8 novembre alle ore 21<\/strong><strong>.<\/strong><\/p>\n<h3>L\u2019attesa di diventare figli<\/h3>\n<p>In tutto il mondo ci sono\u00a0<strong>bambini che attendono di diventare figli,<\/strong>\u00a0cos\u00ec come ci sono persone che attendono di diventare genitori. Per alcuni di quei bambini l\u2019attesa \u00e8 molto pi\u00f9 lunga.<br \/>\nIl loro desiderio di famiglia non viene esaudito, il loro percorso \u00e8 accidentato, perch\u00e9 hanno qualche anno in pi\u00f9 dei bambini solitamente immaginati e desiderati, perch\u00e9 fanno parte di un gruppo numeroso di fratelli con i quali vogliono essere adottati, oppure perch\u00e9 soffrono di qualche patologia che, oltre ad essere la causa del loro abbandono, spaventa i futuri genitori.<\/p>\n<h3>Programma del webinar<\/h3>\n<ol>\n<li>La rubrica Figli in Attesa di Ai.Bi. Amici dei Bambini: cos\u2019\u00e8? Perch\u00e9 \u00e8 nata?<\/li>\n<li>I minori\u00a0<em>special needs<\/em>, come la categoria \u00e8 definita dall\u2019Aja e l\u2019evoluzione del termine<\/li>\n<li>Il lavoro dei paesi accoglienti e di origine per l\u2019accoglienza di minori\u00a0<em>special needs<\/em><\/li>\n<li>Testimonianza della giornalista e mamma adottiva Francesca Mineo con la presentazione del suo libro \u201c<a href=\"https:\/\/www.edizionisanpaolo.it\/varie_1\/famiglia_1\/progetto-famiglia\/libro\/nessuno-e-perfetto-ma-l-amore-si.aspx\">Nessuno \u00e8 perfetto, ma l\u2019amore s\u00ec. Adozione e bisogni speciali<\/a>\u201d.<\/li>\n<\/ol>\n<h3>I relatori<\/h3>\n<p>Il webinar sar\u00e0 condotto da\u00a0<strong>Monica\u00a0<em>Colombo<\/em><\/strong>,\u00a0operatore Adozione Internazionale di\u00a0Ai.Bi. Amici dei Bambini,\u00a0e vedr\u00e0 la\u00a0<strong>testimonianza di Francesca Mineo<\/strong>,\u00a0scrittrice e consulente per il non profit.<\/p>\n<h3>Informazioni<\/h3>\n<p><strong>Webinar. Vieni a conoscere i bambini abbandonati in attesa di famiglia<\/strong><\/p>\n<p><strong>Mercoled\u00ec 8 novembre alle ore 21<\/strong><\/p>\n<p>Per maggiori informazioni \u00e8 possibile contattare la segreteria di FARIS a\u00a0<a href=\"mailto:faris@fondazioneaibi.it\">faris@fondazioneaibi.it<\/a> o cliccando <a href=\"https:\/\/www.fondazioneaibi.it\/faris\/prodotto\/webinar-vieni-a-conoscere-i-bambini-abbandonati-in-attesa-di-famiglia\/\">qui<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mercoled&igrave; 8 novembre alle ore 21, Faris, il centro di formazione di Ai.Bi., ha organizzato un webinar che ha l&rsquo;obiettivo di dare voce a quei bambini che attendono di diventare figli. Ecco i dettagli<\/p>\n","protected":false},"author":133,"featured_media":217229,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[776,718],"class_list":["post-217228","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale","tag-faris","tag-webinar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione. La voce dei bambini abbandonati che aspettano una famiglia. L\u2019incontro online - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-voce-bambini-abbandonati-aspettano-famiglia-incontro-online\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione. La voce dei bambini abbandonati che aspettano una famiglia. L\u2019incontro online\" \/>\n<meta property=\"og:description\" content=\"Mercoled&igrave; 8 novembre alle ore 21, Faris, il centro di formazione di Ai.Bi., ha organizzato un webinar che ha l&rsquo;obiettivo di dare voce a quei bambini che attendono di diventare figli. Ecco i dettagli\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-voce-bambini-abbandonati-aspettano-famiglia-incontro-online\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-30T06:40:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-30T09:47:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2023\/10\/Faris-webinar.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-voce-bambini-abbandonati-aspettano-famiglia-incontro-online\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-voce-bambini-abbandonati-aspettano-famiglia-incontro-online\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Adozione. La voce dei bambini abbandonati che aspettano una famiglia. L\u2019incontro online\",\"datePublished\":\"2023-10-30T06:40:58+00:00\",\"dateModified\":\"2023-10-30T09:47:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-voce-bambini-abbandonati-aspettano-famiglia-incontro-online\\\/\"},\"wordCount\":335,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-voce-bambini-abbandonati-aspettano-famiglia-incontro-online\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/10\\\/Faris-webinar.jpg\",\"keywords\":[\"FARIS\",\"Webinar\"],\"articleSection\":[\"Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-voce-bambini-abbandonati-aspettano-famiglia-incontro-online\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-voce-bambini-abbandonati-aspettano-famiglia-incontro-online\\\/\",\"name\":\"Adozione. La voce dei bambini abbandonati che aspettano una famiglia. L\u2019incontro online - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-voce-bambini-abbandonati-aspettano-famiglia-incontro-online\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-voce-bambini-abbandonati-aspettano-famiglia-incontro-online\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/10\\\/Faris-webinar.jpg\",\"datePublished\":\"2023-10-30T06:40:58+00:00\",\"dateModified\":\"2023-10-30T09:47:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-voce-bambini-abbandonati-aspettano-famiglia-incontro-online\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-voce-bambini-abbandonati-aspettano-famiglia-incontro-online\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-voce-bambini-abbandonati-aspettano-famiglia-incontro-online\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/10\\\/Faris-webinar.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/10\\\/Faris-webinar.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-voce-bambini-abbandonati-aspettano-famiglia-incontro-online\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione. La voce dei bambini abbandonati che aspettano una famiglia. L\u2019incontro online\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione. La voce dei bambini abbandonati che aspettano una famiglia. L\u2019incontro online - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-voce-bambini-abbandonati-aspettano-famiglia-incontro-online\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione. La voce dei bambini abbandonati che aspettano una famiglia. L\u2019incontro online","og_description":"Mercoled&igrave; 8 novembre alle ore 21, Faris, il centro di formazione di Ai.Bi., ha organizzato un webinar che ha l&rsquo;obiettivo di dare voce a quei bambini che attendono di diventare figli. Ecco i dettagli","og_url":"https:\/\/www.aibi.it\/ita\/adozione-voce-bambini-abbandonati-aspettano-famiglia-incontro-online\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2023-10-30T06:40:58+00:00","article_modified_time":"2023-10-30T09:47:56+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2023\/10\/Faris-webinar.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-voce-bambini-abbandonati-aspettano-famiglia-incontro-online\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-voce-bambini-abbandonati-aspettano-famiglia-incontro-online\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Adozione. La voce dei bambini abbandonati che aspettano una famiglia. L\u2019incontro online","datePublished":"2023-10-30T06:40:58+00:00","dateModified":"2023-10-30T09:47:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-voce-bambini-abbandonati-aspettano-famiglia-incontro-online\/"},"wordCount":335,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-voce-bambini-abbandonati-aspettano-famiglia-incontro-online\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/10\/Faris-webinar.jpg","keywords":["FARIS","Webinar"],"articleSection":["Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-voce-bambini-abbandonati-aspettano-famiglia-incontro-online\/","url":"https:\/\/www.aibi.it\/ita\/adozione-voce-bambini-abbandonati-aspettano-famiglia-incontro-online\/","name":"Adozione. La voce dei bambini abbandonati che aspettano una famiglia. L\u2019incontro online - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-voce-bambini-abbandonati-aspettano-famiglia-incontro-online\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-voce-bambini-abbandonati-aspettano-famiglia-incontro-online\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/10\/Faris-webinar.jpg","datePublished":"2023-10-30T06:40:58+00:00","dateModified":"2023-10-30T09:47:56+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-voce-bambini-abbandonati-aspettano-famiglia-incontro-online\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-voce-bambini-abbandonati-aspettano-famiglia-incontro-online\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-voce-bambini-abbandonati-aspettano-famiglia-incontro-online\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2023\/10\/Faris-webinar.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/10\/Faris-webinar.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-voce-bambini-abbandonati-aspettano-famiglia-incontro-online\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Adozione. La voce dei bambini abbandonati che aspettano una famiglia. L\u2019incontro online"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 07:40:34","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/217228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=217228"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/217228\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/217229"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=217228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=217228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=217228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}