﻿


{"id":217562,"date":"2023-11-18T07:55:38","date_gmt":"2023-11-18T06:55:38","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=217562"},"modified":"2023-11-14T12:51:56","modified_gmt":"2023-11-14T11:51:56","slug":"fame-di-mamma-aiuola-tavola-condivisione","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-aiuola-tavola-condivisione\/","title":{"rendered":"Fame di Mamma. Dalla aiuola alla tavola, ma sempre in condivisione  \u00a0"},"content":{"rendered":"<h2>Il personale delle comunit\u00e0 mamma-bambino ha coinvolto gli ospiti, grandi e piccini, di seguire tutte le fasi della coltivazione e della trasformazione del basilico, un&#8217;attivit\u00e0 che ha richiesto cura, pazienza e condivisione<\/h2>\n<p><!--more--><\/p>\n<p>Tra le molte attivit\u00e0 proposte all\u2019interno delle <strong>comunit\u00e0 mamma-bambino<\/strong>, sostenute dal progetto <strong>Fame di Mamma<\/strong>, il personale Ai.Bi. ha pensato di coinvolgere gli ospiti nella coltivazione di alcune <strong>piante di basilico<\/strong> in una delle aiole della struttura.<br \/>\n\u00c8 stato insegnato ai bambini e alle mamma quali sono le fasi fondamentali e quello che dovevano fare per prendersene cura.<br \/>\nLe piante sono cresciute e hanno prodotto delle <strong>bellissime foglie<\/strong>.<\/p>\n<h3>La raccolta e la preparazione<\/h3>\n<p>A causa del clima caldo, la raccolta \u00e8 stata spostata a ottobre.<br \/>\nIl basilico \u00e8 stato lavato, asciugato e sminuzzato. Seguendo la ricetta, sono stati aggiunti gli ingredienti: olio, pinoli, formaggio.<br \/>\nCos\u00ec gli ospiti della comunit\u00e0 hanno preparato il pesto nella versione senza aglio.<\/p>\n<h3>Il senso della condivisione<\/h3>\n<p>Queste attivit\u00e0 oltre che essere molto apprezzate dai bambini, hanno una grande importanza per il loro grande <strong>valore educativo<\/strong>. Esattamente come il momento della <strong>preparazione delle pietanze insieme<\/strong>, un\u2019attivit\u00e0 di <strong>grande condivisione<\/strong> e che <strong>diverte molto<\/strong> sia i grandi sia i bambini.<br \/>\nInfine, il sapore e la soddisfazione di una pasta,<strong> condita con il pesto fatto in casa con la collaborazione di tutti<\/strong>, non hanno prezzo.<br \/>\nLa cena \u00e8 trascorsa felicemente fra risate e forchettate di pasta verde, lo stesso colore di <strong>Shrek<\/strong>, il film che \u00e8 stato visto dopo la cena, mantenendo cos\u00ec una <strong>certa coerenza cromatica per tutta la serata<\/strong>.<\/p>\n<h3>Un\u2019Adozione a Distanza in Italia<\/h3>\n<p>Sostieni anche tu le attivit\u00e0 del progetto Fame di Mamma, che Ai.Bi. porta avanti in Italia, a sostegno delle strutture che ospitano: i minori in comunit\u00e0 familiari, i bambini con le loro madri nelle comunit\u00e0 mamma- bambino e negli alloggi per l\u2019autonomia e gli adolescenti in necessit\u00e0. Puoi farlo con un contributo di appena\u00a0<strong>10 euro al mese,<\/strong>\u00a0aderendo al progetto\u00a0<strong>\u201cAdotta a distanza una famiglia in Italia\u201d<\/strong>. Scopri come fare\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/sostegno-a-distanza-in-italia\/#fame-di-mamma\"><strong>QUI<\/strong><\/a>.<strong><br \/>\n<\/strong>E ricorda:\u00a0<strong>le Adozioni a Distanza di Ai.Bi.\u00a0<\/strong>godono delle seguenti\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/images\/AGEVOLAZIONI_FISCALI.pdf\"><strong>agevolazioni fiscali<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il personale delle comunit&agrave; mamma-bambino ha coinvolto gli ospiti, grandi e piccini, di seguire tutte le fasi della coltivazione e della trasformazione del basilico, un&rsquo;attivit&agrave; che ha richiesto cura, pazienza e condivisione<\/p>\n","protected":false},"author":133,"featured_media":217564,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209],"tags":[608],"class_list":["post-217562","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-a-distanza","tag-fame-di-mamma"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fame di Mamma. Dalla aiuola alla tavola, in condivisione \u00a0<\/title>\n<meta name=\"description\" content=\"Il personale delle comunit\u00e0 mamma-bambino ha coinvolto gli ospiti, grandi e piccini, di seguire tutte le fasi della coltivazione e della trasformazione del basilico, un&#039;attivit\u00e0 che ha richiesto cura, pazienza e condivisione\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/fame-di-mamma-aiuola-tavola-condivisione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fame di Mamma. Dalla aiuola alla tavola, ma sempre in condivisione \u00a0\" \/>\n<meta property=\"og:description\" content=\"Il personale delle comunit\u00e0 mamma-bambino ha coinvolto gli ospiti, grandi e piccini, di seguire tutte le fasi della coltivazione e della trasformazione del basilico, un&#039;attivit\u00e0 che ha richiesto cura, pazienza e condivisione\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/fame-di-mamma-aiuola-tavola-condivisione\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-18T06:55:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Fame-di-Mamma-basilico.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-aiuola-tavola-condivisione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-aiuola-tavola-condivisione\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Fame di Mamma. Dalla aiuola alla tavola, ma sempre in condivisione \u00a0\",\"datePublished\":\"2023-11-18T06:55:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-aiuola-tavola-condivisione\\\/\"},\"wordCount\":358,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-aiuola-tavola-condivisione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/11\\\/Fame-di-Mamma-basilico.jpg\",\"keywords\":[\"Fame di mamma\"],\"articleSection\":[\"Adozione a Distanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-aiuola-tavola-condivisione\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-aiuola-tavola-condivisione\\\/\",\"name\":\"Fame di Mamma. Dalla aiuola alla tavola, in condivisione \u00a0\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-aiuola-tavola-condivisione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-aiuola-tavola-condivisione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/11\\\/Fame-di-Mamma-basilico.jpg\",\"datePublished\":\"2023-11-18T06:55:38+00:00\",\"description\":\"Il personale delle comunit\u00e0 mamma-bambino ha coinvolto gli ospiti, grandi e piccini, di seguire tutte le fasi della coltivazione e della trasformazione del basilico, un'attivit\u00e0 che ha richiesto cura, pazienza e condivisione\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-aiuola-tavola-condivisione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-aiuola-tavola-condivisione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-aiuola-tavola-condivisione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/11\\\/Fame-di-Mamma-basilico.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2023\\\/11\\\/Fame-di-Mamma-basilico.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/fame-di-mamma-aiuola-tavola-condivisione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione a Distanza\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-a-distanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fame di Mamma. Dalla aiuola alla tavola, ma sempre in condivisione \u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fame di Mamma. Dalla aiuola alla tavola, in condivisione \u00a0","description":"Il personale delle comunit\u00e0 mamma-bambino ha coinvolto gli ospiti, grandi e piccini, di seguire tutte le fasi della coltivazione e della trasformazione del basilico, un'attivit\u00e0 che ha richiesto cura, pazienza e condivisione","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-aiuola-tavola-condivisione\/","og_locale":"it_IT","og_type":"article","og_title":"Fame di Mamma. Dalla aiuola alla tavola, ma sempre in condivisione \u00a0","og_description":"Il personale delle comunit\u00e0 mamma-bambino ha coinvolto gli ospiti, grandi e piccini, di seguire tutte le fasi della coltivazione e della trasformazione del basilico, un'attivit\u00e0 che ha richiesto cura, pazienza e condivisione","og_url":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-aiuola-tavola-condivisione\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2023-11-18T06:55:38+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Fame-di-Mamma-basilico.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-aiuola-tavola-condivisione\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-aiuola-tavola-condivisione\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Fame di Mamma. Dalla aiuola alla tavola, ma sempre in condivisione \u00a0","datePublished":"2023-11-18T06:55:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-aiuola-tavola-condivisione\/"},"wordCount":358,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-aiuola-tavola-condivisione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Fame-di-Mamma-basilico.jpg","keywords":["Fame di mamma"],"articleSection":["Adozione a Distanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-aiuola-tavola-condivisione\/","url":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-aiuola-tavola-condivisione\/","name":"Fame di Mamma. Dalla aiuola alla tavola, in condivisione \u00a0","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-aiuola-tavola-condivisione\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-aiuola-tavola-condivisione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Fame-di-Mamma-basilico.jpg","datePublished":"2023-11-18T06:55:38+00:00","description":"Il personale delle comunit\u00e0 mamma-bambino ha coinvolto gli ospiti, grandi e piccini, di seguire tutte le fasi della coltivazione e della trasformazione del basilico, un'attivit\u00e0 che ha richiesto cura, pazienza e condivisione","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-aiuola-tavola-condivisione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/fame-di-mamma-aiuola-tavola-condivisione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-aiuola-tavola-condivisione\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Fame-di-Mamma-basilico.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/Fame-di-Mamma-basilico.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/fame-di-mamma-aiuola-tavola-condivisione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione a Distanza","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-a-distanza\/"},{"@type":"ListItem","position":3,"name":"Fame di Mamma. Dalla aiuola alla tavola, ma sempre in condivisione \u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 17:09:31","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/217562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=217562"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/217562\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/217564"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=217562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=217562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=217562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}